{"id":15828,"date":"2020-03-20T12:35:00","date_gmt":"2023-06-06T12:35:42","guid":{"rendered":"https:\/\/www.salesforce.com\/?p=15828"},"modified":"2023-07-04T23:37:51","modified_gmt":"2023-07-04T23:37:51","slug":"pardot-como-segmentar-o-marketing-b2b","status":"publish","type":"post","link":"https:\/\/www.salesforce.com\/br\/blog\/pardot-como-segmentar-o-marketing-b2b\/","title":{"rendered":"Pardot: saiba como segmentar o marketing B2B"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Est\u00e1 claro que o futuro do <b>marketing digital<\/b> n\u00e3o se restringe mais \u00e0 <b>automa\u00e7\u00e3o<\/b> apenas, incluindo tamb\u00e9m a <b>personaliza\u00e7\u00e3o<\/b>. Quanto mais segmentada for uma mensagem, melhor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No entanto, os profissionais de marketing empresarial enfrentam um desafio cont\u00ednuo: como equilibrar a <b>necessidade de uma marca e uma mensagem centralizadas<\/b> e, ao mesmo tempo, <b>oferecer flexibilidade<\/b> suficiente \u00e0s equipes regionais ou submarcas para <b>veicular campanhas localizadas<\/b>, que tenham uma melhor repercuss\u00e3o entre seus clientes?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para integrar essas demandas e contempl\u00e1-las em nosso portf\u00f3lio, o <a href=\"https:\/\/www.salesforce.com\/br\/products\/pardot\/overview\/\" target=\"_blank\" adhocenable=\"false\" rel=\"noopener\"><b>Pardot<\/b><\/a> \u2013 sistema completo de <b>automa\u00e7\u00e3o de marketing B2B<\/b> \u2013 tornou-se parte da <b>Salesforce<\/b> em 2013. Desde ent\u00e3o, <b>ajudamos os profissionais de marketing a dimensionar e interagir com as equipes de vendas<\/b> na mesma plataforma, capacitando-os a obterem um melhor alinhamento e agir com maior rapidez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em 2019, lan\u00e7amos <b>recursos inteligentes de<\/b><a adhocenable=\"false\" href=\"https:\/\/www.pardot.com\/blog\/introducing-einstein-account-based-marketing-intelligent-b2b-marketing-built-worlds-1-crm-platform\/\" target=\"_blank\" rel=\"noopener\"><b> marketing baseados em conta<\/b><\/a><b> (<i>Account-Based Marketing<\/i>, ABM)<\/b>, que disponibilizaram \u00e0s equipes de marketing empresarial <i>insights<\/i> necess\u00e1rios \u00e0 personaliza\u00e7\u00e3o de campanhas de contas priorit\u00e1rias. No entanto, as necessidades das equipes de marketing B2B n\u00e3o param de evoluir. Por isso, apresentamos hoje as <b>Unidades de Neg\u00f3cios Pardot<\/b>, novos recursos destinados a ampliar ainda mais nossa solu\u00e7\u00e3o de automa\u00e7\u00e3o e personaliza\u00e7\u00e3o de marketing a n\u00edvel empresarial. Confira!<\/p>\n\n\n\n<div class=\"layout-six wp-block-salesforce-blog-offer\">\n\t<div class=\"wp-block-offer__wrapper\">\n\n\t\t<div class=\"wp-block-offer__content\">\n\t\t\t<h2 class=\"wp-block-offer__title\">Marketing no WhatsApp<\/h2>\n\t\t\t\t\t\t\t<p class=\"wp-block-offer__description\">Neste guia, voc\u00ea descobre os fundamentos do marketing conversacional e como o WhatsApp tornou-se a plataforma mais popular dessa estrat\u00e9gia para empresas e clientes.<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t<a class=\"wp-block-button__link\" target=\"_blank\" href=\"https:\/\/www.salesforce.com\/br\/form\/marketing\/boost-your-whatsapp-strategy\/\">Baixar e-book<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"wp-block-offer__media\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2016\/02\/whatsapp-ebook-form-page-v2.png\" class=\"attachment-full size-full\" alt=\"marketing no whatsapp\" srcset=\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2016\/02\/whatsapp-ebook-form-page-v2.png 768w, https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2016\/02\/whatsapp-ebook-form-page-v2.png?w=300&amp;h=169 300w, https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2016\/02\/whatsapp-ebook-form-page-v2.png?w=150&amp;h=84 150w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t<\/div>\n\t<\/div>\n\n\t\n\t<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-unidades-de-negocios-pardot-o-que-sao\"><b>Unidades de Neg\u00f3cios Pardot: o que s\u00e3o?<\/b><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">As <b>Unidades de Neg\u00f3cios Pardot<\/b> foram desenvolvidas pela Salesforce para que as equipes regionais e submarcas disponham das ferramentas necess\u00e1rias para <b>atingir e gerenciar p\u00fablicos segmentados<\/b>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em sua rotina de trabalho, as submarcas ou equipes regionais t\u00eam de lidar com a <b>falta de compreens\u00e3o sobre a experi\u00eancia geral de marketing<\/b> que os clientes em potencial vivenciam com uma empresa multimarca. Muitas vezes, ao planejar campanhas, as equipes de marketing precisam escolher entre <b>dimensionamento<\/b> (alcance em massa com menos personaliza\u00e7\u00e3o) e <b>agilidade<\/b> (intera\u00e7\u00f5es personalizadas com menos coordena\u00e7\u00e3o). O resultado? Clientes percebendo v\u00e1rios <b>pontos de contato entre marcas que s\u00e3o inconsistentes ou repetitivos<\/b>, ao inv\u00e9s da coer\u00eancia e da experi\u00eancia perfeita que esperam de uma empresa unificada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agora, em uma \u00fanica implementa\u00e7\u00e3o do Salesforce Pardot, as empresas podem facilmente designar p\u00fablicos para marcas, regi\u00f5es geogr\u00e1ficas ou linhas de neg\u00f3cios, a fim de <b>personalizar melhor as campanhas<\/b> destinadas a grupos espec\u00edficos e <b>obter uma vis\u00e3o completa da experi\u00eancia do cliente<\/b>. Assim, as equipes de marketing t\u00eam melhor visibilidade dos esfor\u00e7os de divulga\u00e7\u00e3o j\u00e1 realizados \u2013 o que garante que est\u00e3o cumprindo suas metas e conforma as a\u00e7\u00f5es do time a exig\u00eancias regulamentares, eliminando a necessidade de duplicar perfis de clientes potenciais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por exemplo, digamos que uma empresa de fabrica\u00e7\u00e3o multimarcas pode segmentar seus clientes por setores \u2013 incluindo sa\u00fade, energia e transporte \u2013 e por regi\u00f5es, para garantir que estejam recebendo campanhas localizadas e relevantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para esta empresa, as Unidades de Neg\u00f3cios Pardot <b>fornecem an\u00e1lises agregadas<\/b> com as quais os profissionais de marketing poder\u00e3o compreender como o alcance regional da marca se compara a outros subconjuntos, ou afeta o engajamento global em termos gerais. O <b>compartilhamento simplificado de modelos entre equipes<\/b> tamb\u00e9m garante a consist\u00eancia da mensagem geral da marca e o alinhamento com as boas pr\u00e1ticas da empresa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As Unidades de Neg\u00f3cios Pardot seguem em desenvolvimento e devem ganhar vers\u00f5es em ingl\u00eas, franc\u00eas, alem\u00e3o, espanhol e japon\u00eas.<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a97c40436ca7&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a97c40436ca7\" class=\"wp-block-image size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"432\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/06\/image-28.png?strip=all&#038;quality=95\" alt=\"aplica\u00e7\u00e3o de pardot\" class=\"wp-image-17780\" srcset=\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/06\/image-28.png 768w, https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/06\/image-28.png?w=300&amp;h=169 300w, https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/06\/image-28.png?w=150&amp;h=84 150w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-ampliando-os-recursos-do-salesforce-pardot-com-o-appexchange\"><b>Ampliando os recursos do Salesforce Pardot com o AppExchange<\/b><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Em nosso esfor\u00e7o cont\u00ednuo de <b>promover a inova\u00e7\u00e3o<\/b>, visando atender \u00e0s necessidades cada vez mais abrangentes da empresa moderna, atra\u00edmos tamb\u00e9m <b>novos parceiros<\/b> a fim de ajudar as organiza\u00e7\u00f5es a personalizarem e ampliarem a forma como utilizam o Salesforce Pardot.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No <a href=\"https:\/\/appexchange.salesforce.com\/\" target=\"_blank\" adhocenable=\"false\" rel=\"noopener\"><b>Salesforce AppExchange<\/b><\/a>, maior mercado de nuvem empresarial do mundo, \u00e9 poss\u00edvel encontrar integra\u00e7\u00f5es como o<a href=\"https:\/\/www.demandbase.com\/solutions\/salesforce-pardot\/\" target=\"_blank\" adhocenable=\"false\" rel=\"noopener\"> <b>Demandbase<\/b><\/a>, que <b>amplia os dados em n\u00edvel de conta habilitados para intelig\u00eancia artificial (IA)<\/b> no Salesforce Pardot e no <a href=\"https:\/\/www.salesforce.com\/br\/products\/sales-cloud\/overview\/\" target=\"_blank\" adhocenable=\"false\" rel=\"noopener\">Sales Cloud<\/a>, proporcionando uma vis\u00e3o completa das contas segmentadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recentemente, a <a href=\"https:\/\/appexchange.salesforce.com\/appxListingDetail?listingId=a0N3A00000DqipkUAB\" target=\"_blank\" adhocenable=\"false\" rel=\"noopener\"><b>6sense<\/b><\/a> anunciou que os usu\u00e1rios podem <b>obter previs\u00f5es baseadas no tempo sobre o engajamento de clientes em potencial<\/b>, combinadas com o poder de marketing do Salesforce Pardot.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A <a href=\"https:\/\/appexchange.salesforce.com\/appxListingDetail?listingId=a0N3000000B5B3uEAF\" target=\"_blank\" adhocenable=\"false\" rel=\"noopener\"><b>Terminus<\/b><\/a> tamb\u00e9m <b>capacita os profissionais de marketing a desenvolver, operar e avaliar programas ABM<\/b> em canais digitais de publicidade direcionados a contas espec\u00edficas do Salesforce Pardot, com base em dados de <a adhocenable=\"false\" href=\"https:\/\/www.salesforce.com\/br\/crm\/\" target=\"_blank\" rel=\"noopener\">CRM<\/a>. Com essas e outras fun\u00e7\u00f5es integradas, as equipes regionais de marketing B2B podem compor com o Pardot uma vis\u00e3o ainda mais complexa da marca, desenvolvendo a\u00e7\u00f5es locais cada vez mais assertivas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-trailblazers-o-caso-de-sucesso-da-vmware\"><b><i>Trailblazers<\/i>: o caso de sucesso da VMWare<\/b><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Um de nossos clientes empresariais, a<a href=\"https:\/\/www.youtube.com\/watch?v=iRW9yVHERIM\" target=\"_blank\" adhocenable=\"false\" rel=\"noopener\"> <b>VMWare<\/b><\/a>, trilha h\u00e1 mais de tr\u00eas anos conosco sua trajet\u00f3ria de marketing. A empresa alcan\u00e7ou um <a href=\"https:\/\/www.pardot.com\/blog\/vmware-sees-641-roi-with-salesforce-pardot\/\" target=\"_blank\" adhocenable=\"false\" rel=\"noopener\"><b>aumento de 641% no retorno sobre o investimento (ROI)<\/b><\/a> com o Salesforce Pardot, que disponibilizou uma <b>fonte \u00fanica de informa\u00e7\u00f5es para as equipes de vendas e marketing<\/b>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cO uso da pilha de marketing da Salesforce, incluindo o Pardot, viabilizou a <b>implanta\u00e7\u00e3o de todo um <i>back-office<\/i> de marketing em menos de 90 dias<\/b>, e permitiu que o departamento aumentasse sua contribui\u00e7\u00e3o com os neg\u00f3cios\u201d, afirma Michael King, diretor-s\u00eanior de marketing na nuvem da VMWare.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Pardot une vendas e marketing para ajudar voc\u00ea a gerar leads mais qualificados, fomentar <i>prospects<\/i> durante o ciclo de vendas e vender com mais efici\u00eancia. Junte-se a n\u00f3s no webinar gravado <a adhocenable=\"false\" href=\"https:\/\/www.salesforce.com\/br\/form\/events\/webinars\/form-rss\/2159695\" target=\"_blank\" rel=\"noopener\">Demonstra\u00e7\u00e3o de Salesforce Pardot<\/a> e descubra novas maneiras de impulsionar seus <i>leads<\/i> e gerar receita com a ferramenta de automa\u00e7\u00e3o de marketing B2B da Salesforce<\/p>\n\n\n\n<div class=\"layout-four wp-block-salesforce-blog-offer\">\n\t<div class=\"wp-block-offer__wrapper\">\n\n\t\t<div class=\"wp-block-offer__content\">\n\t\t\t<h2 class=\"wp-block-offer__title\">9\u00aa Edi\u00e7\u00e3o do relat\u00f3rio State of Marketing<\/h2>\n\t\t\t\t\t\t\t<p class=\"wp-block-offer__description\">Descubra as tend\u00eancias de IA, dados e personaliza\u00e7\u00e3o, com informa\u00e7\u00f5es coletadas de quase 5 mil profissionais de marketing em todo o mundo.<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t<a class=\"wp-block-button__link\" target=\"_blank\" href=\"https:\/\/www.salesforce.com\/br\/resources\/research-reports\/state-of-marketing\/\">Baixar relat\u00f3rio<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"wp-block-offer__media\">\n\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\n\t\t\t<!-- Standard Illustration -->\n\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__illustration\" src=\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-illustration-layout-four.png\" alt=\"\">\n\n\t\t<!-- Small Accent Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__accent\" src=\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-accent-layout-four.png\" alt=\"\">\n\t\t\n\t\t<!-- Left Side Illustration -->\n\t\t\n\t\t<!-- Cloud Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__cloud\" src=\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-cloud-layout-four.png\" alt=\"\">\n\t\t\n\t<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"> <span id=\"authorRoot\" path=\"\/content\/blogs\/br\/pt\/authors\/\"><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>As Unidades de Neg\u00f3cios Pardot est\u00e3o transformando a gest\u00e3o de p\u00fablicos segmentados. Veja as vantagens da plataforma para a\u00e7\u00f5es de marketing empresarial!<\/p>\n","protected":false},"author":1,"featured_media":15826,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sf_justforyou_enable_alt":true,"optimizely_content_id":"","post_meta_title":"","ai_synopsis":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"sf_topic":[837],"sf_content_type":[],"blog":[1163,1200,1164],"coauthors":[838],"class_list":["post-15828","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","sf_topic-marketing","blog-pardot","blog-marketing","blog-appexchange"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pardot: saiba como segmentar o marketing B2B | Salesforce<\/title>\n<meta name=\"description\" content=\"As Unidades de Neg\u00f3cios Pardot est\u00e3o transformando a gest\u00e3o de p\u00fablicos segmentados. Veja as vantagens da plataforma para a\u00e7\u00f5es de marketing empresarial!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salesforce.com\/br\/blog\/pardot-como-segmentar-o-marketing-b2b\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pardot: saiba como segmentar o marketing B2B\" \/>\n<meta property=\"og:description\" content=\"As Unidades de Neg\u00f3cios Pardot est\u00e3o transformando a gest\u00e3o de p\u00fablicos segmentados. Veja as vantagens da plataforma para a\u00e7\u00f5es de marketing empresarial!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salesforce.com\/br\/blog\/pardot-como-segmentar-o-marketing-b2b\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-06T12:35:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-04T23:37:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/06\/smb-resources-demo-pardot-guided-tour.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Salesforce Brasil\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Salesforce Brasil\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/pardot-como-segmentar-o-marketing-b2b\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/pardot-como-segmentar-o-marketing-b2b\\\/\"},\"author\":[{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/#\\\/schema\\\/person\\\/image\\\/721817ecd0471fdcdbe63bb84fea85dc\"}],\"headline\":\"Pardot: saiba como segmentar o marketing B2B\",\"datePublished\":\"2023-06-06T12:35:42+00:00\",\"dateModified\":\"2023-07-04T23:37:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/pardot-como-segmentar-o-marketing-b2b\\\/\"},\"wordCount\":960,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/pardot-como-segmentar-o-marketing-b2b\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/06\\\/smb-resources-demo-pardot-guided-tour.jpg\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/pardot-como-segmentar-o-marketing-b2b\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/pardot-como-segmentar-o-marketing-b2b\\\/\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/pardot-como-segmentar-o-marketing-b2b\\\/\",\"name\":\"Pardot: saiba como segmentar o marketing B2B | Salesforce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/pardot-como-segmentar-o-marketing-b2b\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/pardot-como-segmentar-o-marketing-b2b\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/06\\\/smb-resources-demo-pardot-guided-tour.jpg\",\"datePublished\":\"2023-06-06T12:35:42+00:00\",\"dateModified\":\"2023-07-04T23:37:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/#\\\/schema\\\/person\\\/601f410a2801f4ddcf6f00cb182e69d3\"},\"description\":\"As Unidades de Neg\u00f3cios Pardot est\u00e3o transformando a gest\u00e3o de p\u00fablicos segmentados. Veja as vantagens da plataforma para a\u00e7\u00f5es de marketing empresarial!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/pardot-como-segmentar-o-marketing-b2b\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/pardot-como-segmentar-o-marketing-b2b\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/pardot-como-segmentar-o-marketing-b2b\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/06\\\/smb-resources-demo-pardot-guided-tour.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/06\\\/smb-resources-demo-pardot-guided-tour.jpg\",\"width\":768,\"height\":432,\"caption\":\"Pardot: saiba como segmentar o marketing B2B\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/pardot-como-segmentar-o-marketing-b2b\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pardot: saiba como segmentar o marketing B2B\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/\",\"name\":\"Salesforce\",\"description\":\"Novidades sobre ia ag\u00eantica, dados e crm\",\"alternateName\":\"Salesforce Brasil\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/#\\\/schema\\\/person\\\/image\\\/721817ecd0471fdcdbe63bb84fea85dc\",\"name\":\"Salesforce Brasil\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/#\\\/schema\\\/person\\\/image\\\/1d313068b0a89247f1ca07d456b4f5e0\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/07\\\/Salesforce-logo.webp?w=150&h=150&crop=1\",\"contentUrl\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/07\\\/Salesforce-logo.webp?w=150&h=150&crop=1\",\"width\":150,\"height\":150,\"caption\":\"Salesforce Brasil\"},\"description\":\"Somos uma plataforma de gerenciamento de relacionamento com o cliente (CRM) baseada na nuvem, que permite com que empresas possam gerenciar e integrar todas as suas opera\u00e7\u00f5es, como vendas, marketing, atendimento, ecommerce e TI em um lugar s\u00f3.\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/author\\\/salesforce-brasil\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pardot: saiba como segmentar o marketing B2B | Salesforce","description":"As Unidades de Neg\u00f3cios Pardot est\u00e3o transformando a gest\u00e3o de p\u00fablicos segmentados. Veja as vantagens da plataforma para a\u00e7\u00f5es de marketing empresarial!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salesforce.com\/br\/blog\/pardot-como-segmentar-o-marketing-b2b\/","og_locale":"pt_BR","og_type":"article","og_title":"Pardot: saiba como segmentar o marketing B2B","og_description":"As Unidades de Neg\u00f3cios Pardot est\u00e3o transformando a gest\u00e3o de p\u00fablicos segmentados. Veja as vantagens da plataforma para a\u00e7\u00f5es de marketing empresarial!","og_url":"https:\/\/www.salesforce.com\/br\/blog\/pardot-como-segmentar-o-marketing-b2b\/","og_site_name":"Salesforce","article_published_time":"2023-06-06T12:35:42+00:00","article_modified_time":"2023-07-04T23:37:51+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/06\/smb-resources-demo-pardot-guided-tour.jpg","type":"image\/jpeg"}],"author":"Salesforce Brasil","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"","Est. tempo de leitura":"4 minutos","Written by":"Salesforce Brasil"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salesforce.com\/br\/blog\/pardot-como-segmentar-o-marketing-b2b\/#article","isPartOf":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/pardot-como-segmentar-o-marketing-b2b\/"},"author":[{"@id":"https:\/\/www.salesforce.com\/br\/blog\/#\/schema\/person\/image\/721817ecd0471fdcdbe63bb84fea85dc"}],"headline":"Pardot: saiba como segmentar o marketing B2B","datePublished":"2023-06-06T12:35:42+00:00","dateModified":"2023-07-04T23:37:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/pardot-como-segmentar-o-marketing-b2b\/"},"wordCount":960,"commentCount":0,"image":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/pardot-como-segmentar-o-marketing-b2b\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/06\/smb-resources-demo-pardot-guided-tour.jpg","inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.salesforce.com\/br\/blog\/pardot-como-segmentar-o-marketing-b2b\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.salesforce.com\/br\/blog\/pardot-como-segmentar-o-marketing-b2b\/","url":"https:\/\/www.salesforce.com\/br\/blog\/pardot-como-segmentar-o-marketing-b2b\/","name":"Pardot: saiba como segmentar o marketing B2B | Salesforce","isPartOf":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/pardot-como-segmentar-o-marketing-b2b\/#primaryimage"},"image":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/pardot-como-segmentar-o-marketing-b2b\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/06\/smb-resources-demo-pardot-guided-tour.jpg","datePublished":"2023-06-06T12:35:42+00:00","dateModified":"2023-07-04T23:37:51+00:00","author":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/#\/schema\/person\/601f410a2801f4ddcf6f00cb182e69d3"},"description":"As Unidades de Neg\u00f3cios Pardot est\u00e3o transformando a gest\u00e3o de p\u00fablicos segmentados. Veja as vantagens da plataforma para a\u00e7\u00f5es de marketing empresarial!","breadcrumb":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/pardot-como-segmentar-o-marketing-b2b\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salesforce.com\/br\/blog\/pardot-como-segmentar-o-marketing-b2b\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.salesforce.com\/br\/blog\/pardot-como-segmentar-o-marketing-b2b\/#primaryimage","url":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/06\/smb-resources-demo-pardot-guided-tour.jpg","contentUrl":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/06\/smb-resources-demo-pardot-guided-tour.jpg","width":768,"height":432,"caption":"Pardot: saiba como segmentar o marketing B2B"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salesforce.com\/br\/blog\/pardot-como-segmentar-o-marketing-b2b\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salesforce.com\/br\/blog\/"},{"@type":"ListItem","position":2,"name":"Pardot: saiba como segmentar o marketing B2B"}]},{"@type":"WebSite","@id":"https:\/\/www.salesforce.com\/br\/blog\/#website","url":"https:\/\/www.salesforce.com\/br\/blog\/","name":"Salesforce","description":"Novidades sobre ia ag\u00eantica, dados e crm","alternateName":"Salesforce Brasil","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salesforce.com\/br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.salesforce.com\/br\/blog\/#\/schema\/person\/image\/721817ecd0471fdcdbe63bb84fea85dc","name":"Salesforce Brasil","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.salesforce.com\/br\/blog\/#\/schema\/person\/image\/1d313068b0a89247f1ca07d456b4f5e0","url":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/07\/Salesforce-logo.webp?w=150&h=150&crop=1","contentUrl":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/07\/Salesforce-logo.webp?w=150&h=150&crop=1","width":150,"height":150,"caption":"Salesforce Brasil"},"description":"Somos uma plataforma de gerenciamento de relacionamento com o cliente (CRM) baseada na nuvem, que permite com que empresas possam gerenciar e integrar todas as suas opera\u00e7\u00f5es, como vendas, marketing, atendimento, ecommerce e TI em um lugar s\u00f3.","url":"https:\/\/www.salesforce.com\/br\/blog\/author\/salesforce-brasil\/"}]}},"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Salesforce","distributor_original_site_url":"https:\/\/www.salesforce.com\/br\/blog","push-errors":false,"jetpack_featured_media_url":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/06\/smb-resources-demo-pardot-guided-tour.jpg","_links":{"self":[{"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/posts\/15828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/comments?post=15828"}],"version-history":[{"count":4,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/posts\/15828\/revisions"}],"predecessor-version":[{"id":17782,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/posts\/15828\/revisions\/17782"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/media\/15826"}],"wp:attachment":[{"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/media?parent=15828"}],"wp:term":[{"taxonomy":"sf_topic","embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/sf_topic?post=15828"},{"taxonomy":"sf_content_type","embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/sf_content_type?post=15828"},{"taxonomy":"blog","embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/blog?post=15828"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/coauthors?post=15828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}