{"id":15952,"date":"2020-09-14T12:41:00","date_gmt":"2023-06-06T12:41:05","guid":{"rendered":"https:\/\/www.salesforce.com\/?p=15952"},"modified":"2023-07-04T23:46:13","modified_gmt":"2023-07-04T23:46:13","slug":"ebanx-da-dicas-para-ter-sucesso-no-relacionamento-com-clientes-b2b","status":"publish","type":"post","link":"https:\/\/www.salesforce.com\/br\/blog\/ebanx-da-dicas-para-ter-sucesso-no-relacionamento-com-clientes-b2b\/","title":{"rendered":"EBANX d\u00e1 dicas para ter sucesso no relacionamento com clientes B2B"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Durante a pandemia da Covid-19, a Salesforce est\u00e1 realizando uma s\u00e9rie de conte\u00fados para trazer insights para as empresas se manterem na trilha do sucesso em meio ao per\u00edodo dif\u00edcil que atravessamos. Desta vez, a Salesforce convida o<a href=\"https:\/\/www.salesforce.com\/br\/customer-success-stories\/ebanx\/\" target=\"_blank\" adhocenable=\"false\" rel=\"noopener\">EBANX<\/a>, fintech brasileira conhecida por oferecer solu\u00e7\u00f5es de pagamento da Am\u00e9rica Latina a sites nacionais e internacionais, para dar dicas sobre como manter um bom relacionamento com clientes B2B.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pandemia da Covid-19 impactou todas as \u00e1reas de nossa sociedade, inclusive os neg\u00f3cios. Com medidas de distanciamento social adotadas para conter o avan\u00e7o do v\u00edrus, as pessoas tiveram que ficar em casa, modificando a din\u00e2mica do relacionamento entre empresas e clientes. Entre empresas e clientes corporativos ou B2B, n\u00e3o foi diferente: a pandemia for\u00e7ou adapta\u00e7\u00f5es para que elas pudessem continuar auxiliando seus clientes da melhor maneira.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para Luciana Makinodan, gerente de B2B Customer Delivery do EBANX, a din\u00e2mica de atendimento mudou para todas as empresas. \u201cO foco em reten\u00e7\u00e3o ganhou ainda mais espa\u00e7o, passou a ser t\u00e3o importante quanto trazer novos clientes\u201d, comenta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A executiva explica que mais do que nunca o relacionamento deve ser mais pr\u00f3ximo e com muita empatia em todos os contatos com os clientes. Segundo ela, nesse ponto saem na frente as empresas que j\u00e1 possu\u00edam um bom conhecimento e proximidade com seus clientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTodo o trabalho de conhecimento dos clientes, seu neg\u00f3cio e posicionamento de parceria est\u00e1 sendo colocado em xeque neste momento. Quem n\u00e3o fez esta li\u00e7\u00e3o de casa antes, hoje tem mais dificuldade, porque precisa construir esta rela\u00e7\u00e3o em vez de estar junto dos merchants neste momento\u201d, alerta Luciana. \u201c\u00c9 muito importante estar atento ao que os clientes nos falam em cada touchpoint e usar estas informa\u00e7\u00f5es para direcionar os esfor\u00e7os. Atender suas necessidades e demandas n\u00e3o se restringe apenas ao atendimento em si: pode significar tamb\u00e9m uma oportunidade de neg\u00f3cio\u201d, completa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para dar suporte a esse atendimento mais pr\u00f3ximo e prover experi\u00eancias que encantem, \u00e9 preciso considerar tecnologia, estrat\u00e9gia e cultura, tudo voltado para o sucesso do cliente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada empresa tem suas especifica\u00e7\u00f5es, necessidades e demandas, muitas vezes o que funciona para uma n\u00e3o funciona para outra. \u00c9 preciso entender os neg\u00f3cios dos clientes e conhecer onde e como atuam, assim \u00e9 mais f\u00e1cil oferecer servi\u00e7os e solu\u00e7\u00f5es que sejam realmente relevantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para ampliar esse conhecimento, a tecnologia \u00e9 uma importante aliada.<a href=\"https:\/\/www.salesforce.com\/br\/crm\/\" target=\"_blank\" adhocenable=\"false\" rel=\"noopener\">Solu\u00e7\u00f5es como o CRM<\/a> prov\u00eam dados relevantes que ajudam a aprofundar informa\u00e7\u00f5es, tra\u00e7ar uma jornada de compra, saber as pr\u00f3ximas melhores a\u00e7\u00f5es, o que d\u00e1 certo ou errado, como e quando abordar determinado cliente, entre outros. Dessa maneira sua empresa fica habilitada para oferecer ao cliente aquilo que ele espera de maneira proativa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAqui no EBANX, temos implementado em nossas rotinas monitoramentos diversos de nossas contas. Assim, podemos agir proativamente. Estamos tamb\u00e9m fazendo testes em formatos diferentes para colocar conte\u00fados \u00e0 disposi\u00e7\u00e3o dos nossos merchants. Por atuarmos em pa\u00edses diferentes, vemos que alguns canais funcionam melhor em determinadas regi\u00f5es. Por isso, o aspecto cultural e regional do seu merchant (de onde ele \u00e9 e onde est\u00e1 o mercado dele) devem ser levados em considera\u00e7\u00e3o tamb\u00e9m\u201d, explica Luciana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uma estrat\u00e9gia voltada para o cliente consiste em colocar o sucesso e as necessidades dele no centro, ou seja, todas as a\u00e7\u00f5es da empresa devem refletir positivamente para o cliente, mesmo em \u00e1reas que n\u00e3o tenham contato direto. Por exemplo, seu cliente solicitou uma altera\u00e7\u00e3o em uma cobran\u00e7a, que foi encaminhada para o financeiro de sua empresa. Essa pode ser uma demanda priorizada, para acelerar o retorno e garantir o sentimento de que sua marca est\u00e1 empenhada em solucionar as solicita\u00e7\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A cultura tem um papel cr\u00edtico nesse processo. \u00c9 uma cultura tamb\u00e9m focada no cliente que vai fazer com que seus colaboradores entendam que o sucesso e a satisfa\u00e7\u00e3o dele s\u00e3o determinantes para o \u00eaxito da pr\u00f3pria empresa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conhe\u00e7a o Service Cloud, nosso<a href=\"https:\/\/www.salesforce.com\/br\/products\/service-cloud\/overview\/\">software de atendimento ao cliente<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><b>Separamos algumas dicas da Luciana Makinodan, gerente de B2B Customer Delivery do EBANX, para atender seu cliente nesse momento:<\/b><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>\n<p>Mostrar empatia;<\/p>\n<\/li>\n\n\n\n<li>\n<p>Ter expertise no seu campo de atua\u00e7\u00e3o, e se comunicar com clareza;<\/p>\n<\/li>\n\n\n\n<li>\n<p>Adotar t\u00e1ticas que permitam posicionar-se \u00e0 frente dos poss\u00edveis problemas de seus clientes, problemas esses que eles podem n\u00e3o ter percebido. E levantar a quest\u00e3o.<\/p>\n<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><b>Regra de ouro: <\/b><u>entenda o neg\u00f3cio do seu cliente, e as dicas acima v\u00eam como uma consequ\u00eancia.<\/u><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> <span id=\"authorRoot\" path=\"\/content\/blogs\/br\/pt\/authors\/\"><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luciana Makinodan, gerente de B2B Customer Delivery do EBANX: &#8220;Todo trabalho de conhecimento dos clientes, seu neg\u00f3cio e posicionamento de parceria est\u00e1 sendo colocado em xeque neste momento.&#8221;<\/p>\n","protected":false},"author":1,"featured_media":15951,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sf_justforyou_enable_alt":true,"optimizely_content_id":"","post_meta_title":"","ai_synopsis":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"sf_topic":[835,861],"sf_content_type":[],"blog":[1167,1201,1206,1290],"coauthors":[947],"class_list":["post-15952","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","sf_topic-sales","sf_topic-service","blog-experience-cloud","blog-sales","blog-service","blog-trailblazer-story"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>EBANX d\u00e1 dicas para ter sucesso no relacionamento com clientes B2B | Salesforce<\/title>\n<meta name=\"description\" content=\"Luciana Makinodan, gerente de B2B Customer Delivery do EBANX: &quot;Todo trabalho de conhecimento dos clientes, seu neg\u00f3cio e posicionamento de parceria est\u00e1 sendo colocado em xeque neste momento.&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salesforce.com\/br\/blog\/ebanx-da-dicas-para-ter-sucesso-no-relacionamento-com-clientes-b2b\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EBANX d\u00e1 dicas para ter sucesso no relacionamento com clientes B2B\" \/>\n<meta property=\"og:description\" content=\"Luciana Makinodan, gerente de B2B Customer Delivery do EBANX: &quot;Todo trabalho de conhecimento dos clientes, seu neg\u00f3cio e posicionamento de parceria est\u00e1 sendo colocado em xeque neste momento.&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salesforce.com\/br\/blog\/ebanx-da-dicas-para-ter-sucesso-no-relacionamento-com-clientes-b2b\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-06T12:41:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-04T23:46:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/06\/final-ebanx.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"digital-delivery-operations7076\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/ebanx-da-dicas-para-ter-sucesso-no-relacionamento-com-clientes-b2b\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/ebanx-da-dicas-para-ter-sucesso-no-relacionamento-com-clientes-b2b\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/#\\\/schema\\\/person\\\/601f410a2801f4ddcf6f00cb182e69d3\"},\"headline\":\"EBANX d\u00e1 dicas para ter sucesso no relacionamento com clientes B2B\",\"datePublished\":\"2023-06-06T12:41:05+00:00\",\"dateModified\":\"2023-07-04T23:46:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/ebanx-da-dicas-para-ter-sucesso-no-relacionamento-com-clientes-b2b\\\/\"},\"wordCount\":794,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/ebanx-da-dicas-para-ter-sucesso-no-relacionamento-com-clientes-b2b\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/06\\\/final-ebanx.jpg\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/ebanx-da-dicas-para-ter-sucesso-no-relacionamento-com-clientes-b2b\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/ebanx-da-dicas-para-ter-sucesso-no-relacionamento-com-clientes-b2b\\\/\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/ebanx-da-dicas-para-ter-sucesso-no-relacionamento-com-clientes-b2b\\\/\",\"name\":\"EBANX d\u00e1 dicas para ter sucesso no relacionamento com clientes B2B | Salesforce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/ebanx-da-dicas-para-ter-sucesso-no-relacionamento-com-clientes-b2b\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/ebanx-da-dicas-para-ter-sucesso-no-relacionamento-com-clientes-b2b\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/06\\\/final-ebanx.jpg\",\"datePublished\":\"2023-06-06T12:41:05+00:00\",\"dateModified\":\"2023-07-04T23:46:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/#\\\/schema\\\/person\\\/601f410a2801f4ddcf6f00cb182e69d3\"},\"description\":\"Luciana Makinodan, gerente de B2B Customer Delivery do EBANX: \\\"Todo trabalho de conhecimento dos clientes, seu neg\u00f3cio e posicionamento de parceria est\u00e1 sendo colocado em xeque neste momento.\\\"\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/ebanx-da-dicas-para-ter-sucesso-no-relacionamento-com-clientes-b2b\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/ebanx-da-dicas-para-ter-sucesso-no-relacionamento-com-clientes-b2b\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/ebanx-da-dicas-para-ter-sucesso-no-relacionamento-com-clientes-b2b\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/06\\\/final-ebanx.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/06\\\/final-ebanx.jpg\",\"width\":600,\"height\":400,\"caption\":\"EBANX d\u00e1 dicas para ter sucesso no relacionamento com clientes B2B\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/ebanx-da-dicas-para-ter-sucesso-no-relacionamento-com-clientes-b2b\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EBANX d\u00e1 dicas para ter sucesso no relacionamento com clientes B2B\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/\",\"name\":\"Salesforce\",\"description\":\"Novidades sobre ia ag\u00eantica, dados e crm\",\"alternateName\":\"Salesforce Brasil\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/#\\\/schema\\\/person\\\/601f410a2801f4ddcf6f00cb182e69d3\",\"name\":\"\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39c5d4fc7f8f59985f697ce500d830013b61c45f5398d002b410a83eb6a0c33f?s=96&d=mm&r=g8566f0194350bbd26f1616f3ceb627b8\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39c5d4fc7f8f59985f697ce500d830013b61c45f5398d002b410a83eb6a0c33f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39c5d4fc7f8f59985f697ce500d830013b61c45f5398d002b410a83eb6a0c33f?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/www.salesforce.com\"],\"url\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/author\\\/digital-delivery-operations7076\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"EBANX d\u00e1 dicas para ter sucesso no relacionamento com clientes B2B | Salesforce","description":"Luciana Makinodan, gerente de B2B Customer Delivery do EBANX: \"Todo trabalho de conhecimento dos clientes, seu neg\u00f3cio e posicionamento de parceria est\u00e1 sendo colocado em xeque neste momento.\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salesforce.com\/br\/blog\/ebanx-da-dicas-para-ter-sucesso-no-relacionamento-com-clientes-b2b\/","og_locale":"pt_BR","og_type":"article","og_title":"EBANX d\u00e1 dicas para ter sucesso no relacionamento com clientes B2B","og_description":"Luciana Makinodan, gerente de B2B Customer Delivery do EBANX: \"Todo trabalho de conhecimento dos clientes, seu neg\u00f3cio e posicionamento de parceria est\u00e1 sendo colocado em xeque neste momento.\"","og_url":"https:\/\/www.salesforce.com\/br\/blog\/ebanx-da-dicas-para-ter-sucesso-no-relacionamento-com-clientes-b2b\/","og_site_name":"Salesforce","article_published_time":"2023-06-06T12:41:05+00:00","article_modified_time":"2023-07-04T23:46:13+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/06\/final-ebanx.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"","Est. tempo de leitura":"4 minutos","Written by":"digital-delivery-operations7076"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salesforce.com\/br\/blog\/ebanx-da-dicas-para-ter-sucesso-no-relacionamento-com-clientes-b2b\/#article","isPartOf":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/ebanx-da-dicas-para-ter-sucesso-no-relacionamento-com-clientes-b2b\/"},"author":{"name":"","@id":"https:\/\/www.salesforce.com\/br\/blog\/#\/schema\/person\/601f410a2801f4ddcf6f00cb182e69d3"},"headline":"EBANX d\u00e1 dicas para ter sucesso no relacionamento com clientes B2B","datePublished":"2023-06-06T12:41:05+00:00","dateModified":"2023-07-04T23:46:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/ebanx-da-dicas-para-ter-sucesso-no-relacionamento-com-clientes-b2b\/"},"wordCount":794,"commentCount":0,"image":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/ebanx-da-dicas-para-ter-sucesso-no-relacionamento-com-clientes-b2b\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/06\/final-ebanx.jpg","inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.salesforce.com\/br\/blog\/ebanx-da-dicas-para-ter-sucesso-no-relacionamento-com-clientes-b2b\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.salesforce.com\/br\/blog\/ebanx-da-dicas-para-ter-sucesso-no-relacionamento-com-clientes-b2b\/","url":"https:\/\/www.salesforce.com\/br\/blog\/ebanx-da-dicas-para-ter-sucesso-no-relacionamento-com-clientes-b2b\/","name":"EBANX d\u00e1 dicas para ter sucesso no relacionamento com clientes B2B | Salesforce","isPartOf":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/ebanx-da-dicas-para-ter-sucesso-no-relacionamento-com-clientes-b2b\/#primaryimage"},"image":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/ebanx-da-dicas-para-ter-sucesso-no-relacionamento-com-clientes-b2b\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/06\/final-ebanx.jpg","datePublished":"2023-06-06T12:41:05+00:00","dateModified":"2023-07-04T23:46:13+00:00","author":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/#\/schema\/person\/601f410a2801f4ddcf6f00cb182e69d3"},"description":"Luciana Makinodan, gerente de B2B Customer Delivery do EBANX: \"Todo trabalho de conhecimento dos clientes, seu neg\u00f3cio e posicionamento de parceria est\u00e1 sendo colocado em xeque neste momento.\"","breadcrumb":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/ebanx-da-dicas-para-ter-sucesso-no-relacionamento-com-clientes-b2b\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salesforce.com\/br\/blog\/ebanx-da-dicas-para-ter-sucesso-no-relacionamento-com-clientes-b2b\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.salesforce.com\/br\/blog\/ebanx-da-dicas-para-ter-sucesso-no-relacionamento-com-clientes-b2b\/#primaryimage","url":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/06\/final-ebanx.jpg","contentUrl":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/06\/final-ebanx.jpg","width":600,"height":400,"caption":"EBANX d\u00e1 dicas para ter sucesso no relacionamento com clientes B2B"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salesforce.com\/br\/blog\/ebanx-da-dicas-para-ter-sucesso-no-relacionamento-com-clientes-b2b\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salesforce.com\/br\/blog\/"},{"@type":"ListItem","position":2,"name":"EBANX d\u00e1 dicas para ter sucesso no relacionamento com clientes B2B"}]},{"@type":"WebSite","@id":"https:\/\/www.salesforce.com\/br\/blog\/#website","url":"https:\/\/www.salesforce.com\/br\/blog\/","name":"Salesforce","description":"Novidades sobre ia ag\u00eantica, dados e crm","alternateName":"Salesforce Brasil","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salesforce.com\/br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.salesforce.com\/br\/blog\/#\/schema\/person\/601f410a2801f4ddcf6f00cb182e69d3","name":"","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/39c5d4fc7f8f59985f697ce500d830013b61c45f5398d002b410a83eb6a0c33f?s=96&d=mm&r=g8566f0194350bbd26f1616f3ceb627b8","url":"https:\/\/secure.gravatar.com\/avatar\/39c5d4fc7f8f59985f697ce500d830013b61c45f5398d002b410a83eb6a0c33f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/39c5d4fc7f8f59985f697ce500d830013b61c45f5398d002b410a83eb6a0c33f?s=96&d=mm&r=g"},"sameAs":["http:\/\/www.salesforce.com"],"url":"https:\/\/www.salesforce.com\/br\/blog\/author\/digital-delivery-operations7076\/"}]}},"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Salesforce","distributor_original_site_url":"https:\/\/www.salesforce.com\/br\/blog","push-errors":false,"jetpack_featured_media_url":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/06\/final-ebanx.jpg","_links":{"self":[{"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/posts\/15952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/comments?post=15952"}],"version-history":[{"count":3,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/posts\/15952\/revisions"}],"predecessor-version":[{"id":17893,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/posts\/15952\/revisions\/17893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/media\/15951"}],"wp:attachment":[{"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/media?parent=15952"}],"wp:term":[{"taxonomy":"sf_topic","embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/sf_topic?post=15952"},{"taxonomy":"sf_content_type","embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/sf_content_type?post=15952"},{"taxonomy":"blog","embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/blog?post=15952"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/coauthors?post=15952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}