{"id":16386,"date":"2022-05-04T12:54:00","date_gmt":"2023-06-06T12:54:05","guid":{"rendered":"https:\/\/www.salesforce.com\/?p=16386"},"modified":"2024-06-26T21:16:09","modified_gmt":"2024-06-26T21:16:09","slug":"follow-up-de-vendas","status":"publish","type":"post","link":"https:\/\/www.salesforce.com\/br\/blog\/follow-up-de-vendas\/","title":{"rendered":"Follow-up de Vendas: Como realizar?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O <b><i>follow-up<\/i> de <a href=\"https:\/\/www.salesforce.com\/br\/products\/sales-cloud\/overview\/\">vendas<\/a><\/b> \u00e9 uma etapa fundamental para transformar <a href=\"https:\/\/www.salesforce.com\/br\/blog\/leads\/\"><i>leads<\/i> <\/a>em clientes. No entanto, mais do que uma liga\u00e7\u00e3o ou mensagem para retomar contato, ele pode ser <b>decisivo para encurtar o tempo de decis\u00e3o do prospect e, consequentemente, encaminhar o fechamento do neg\u00f3cio.<\/b><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O <i>follow-up<\/i> \u00e9 uma <b>oportunidade para voc\u00ea desenvolver um relacionamento \u00fanico e personalizado<\/b> com seu futuro cliente, mostrando que entende e se importa com os problemas dele. Para ser bem-sucedido, \u00e9 preciso atentar aos detalhes, colocar-se no lugar do <i>prospect<\/i> e focar em a\u00e7\u00f5es e <a href=\"https:\/\/www.salesforce.com\/br\/blog\/customer-360-recursos\/\">abordagens <i>customer-centric<\/i>.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A seguir, voc\u00ea confere como o <i>follow-up<\/i> \u00e9 parte primordial de uma boa <b>gest\u00e3o de<i> leads<\/i> <\/b>e o que voc\u00ea precisa fazer para driblar os erros mais comuns e qualificar a negocia\u00e7\u00e3o. Continue lendo e confira!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><b>LEIA MAIS: <a href=\"https:\/\/www.salesforce.com\/br\/blog\/captacao-de-clientes\/\">Capta\u00e7\u00e3o de Clientes<\/a>: O que \u00e9 e como fazer?<\/b><\/p>\n\n\n\n<div class=\"layout-nine wp-block-salesforce-blog-offer\">\n\t<div class=\"wp-block-offer__wrapper\">\n\n\t\t<div class=\"wp-block-offer__content\">\n\t\t\t<h2 class=\"wp-block-offer__title\">O manual de proje\u00e7\u00e3o de vendas da Salesforce<\/h2>\n\t\t\t\t\t\t\t<p class=\"wp-block-offer__description\">Entenda como fazemos nosso forecast de vendas de maneira assertiva.<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t<a class=\"wp-block-button__link\" target=\"_blank\" href=\"https:\/\/www.salesforce.com\/br\/form\/pdf\/manage-pipeline-and-forecasts\/\">Baixar manual<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"wp-block-offer__media\">\n\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wp-block-offer__graphics wp-block-offer__contour\"><\/div>\n\t\n\t\t\t<!-- Standard Illustration -->\n\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__illustration\" src=\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-illustration-layout-nine.png\" alt=\"\">\n\n\t\t<!-- Small Accent Illustration -->\n\t\t\n\t\t<!-- Left Side Illustration -->\n\t\t\n\t\t<!-- Cloud Illustration -->\n\t\t\n\t<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"sinais-de-que-seu-follow-up-de-vendas-precisa-melhorar\"> <span> Sinais de que seu follow-up de vendas precisa melhorar <\/span> <\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"> Se o <i>follow-up<\/i> n\u00e3o est\u00e1 colhendo os resultados esperados pela sua <a href=\"https:\/\/www.salesforce.com\/br\/blog\/2021\/04\/sales-ops-como-montar-sua-equipe.html\">equipe de vendas<\/a>, pode ser que alguma coisa esteja errada com o seu processo de re-contato. Veja o que pode estar acontecendo. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"voce-so-faz-o-follow-up-antes-da-venda-ser-fechada\"> <span> Voc\u00ea s\u00f3 faz o follow-up antes da venda ser fechada <\/span> <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Depois disso, \u00e9 com o cliente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se essa \u00e9 a sua filosofia de follow-up, este \u00e9 um ponto a melhorar. Afinal, <b>a comunica\u00e7\u00e3o com o potencial cliente n\u00e3o deve ser interrompida assim que ele se torna um cliente de verdade.<\/b> Assim fica na cara que o seu \u00fanico interesse era fechar a venda e n\u00e3o construir um relacionamento embasado em confian\u00e7a, focado em <a href=\"https:\/\/www.salesforce.com\/br\/blog\/2017\/Outubro\/Como-atendimento-ao-cliente-se-tornou-sucesso-do-cliente.html\">ajudar o consumidor a ter sucesso no seu neg\u00f3cio<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> Al\u00e9m disso, estender o processo de follow-up para o <a href=\"https:\/\/www.salesforce.com\/br\/blog\/pos-venda\/\">p\u00f3s-venda <\/a>\u00e9 obrigat\u00f3rio para trabalhar a <a href=\"https:\/\/www.salesforce.com\/br\/blog\/2020\/04\/retencao-de-clientes.html\">reten\u00e7\u00e3o de clientes<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"suas-mensagens-de-follow-up-sao-longas-demais\"> <span> Suas mensagens de follow-up s\u00e3o longas demais <\/span> <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"> Na hora de escrever um e-mail de follow-up, quantos caracteres voc\u00ea utiliza? O ideal \u00e9 que seja o m\u00ednimo poss\u00edvel, a<b>penas o necess\u00e1rio para se comunicar de forma objetiva e amig\u00e1vel.<\/b> De outro modo, voc\u00ea corre o risco de entediar o<i> lead,<\/i> faz\u00ea-lo perder tempo ou ainda induzi-lo a marcar a mensagem para ler depois, desacelerando a prospec\u00e7\u00e3o e eliminando o imediatismo da jogada. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"voce-esta-perdendo-o-timing-do-contato\"> <span> Voc\u00ea est\u00e1 perdendo o timing do contato <\/span> <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Definitivamente <b>um dos erros mais comuns ao realizar o <i>follow-up<\/i> de vendas \u00e9 faz\u00ea-lo quando \u00e9 conveniente para voc\u00ea e n\u00e3o para o cliente. <\/b>Se voc\u00ea costuma enviar mensagens para o <i>prospect <\/i>apenas quando \u201csobra um tempinho\u201d na sua agenda, saiba que voc\u00ea corre o risco de <a href=\"https:\/\/www.salesforce.com\/br\/blog\/2021\/07\/cinco-formas-de-aquecer-leads.html\">transformar um lead quente em lead frio<\/a> rapidinho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> Por isso, tenha em mente que <b>o tempo ideal para retomar contato \u00e9 o tempo do cliente<\/b>. O mais indicado \u00e9 estudar o <a href=\"https:\/\/www.salesforce.com\/br\/crm\/funil-de-vendas\/\">funil de vendas<\/a> e montar um cronograma baseado nele e em todas as etapas que o <i>lead <\/i>ir\u00e1 seguir, sugerindo uma abordagem diferente para cada uma delas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"voce-nao-sabe-quais-sao-os-proximos-passos-da-prospeccao\"> <span> Voc\u00ea n\u00e3o sabe quais s\u00e3o os pr\u00f3ximos passos da prospec\u00e7\u00e3o <\/span> <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Mais um problema que pode acontecer pela falta de um cronograma de <i>follow-up<\/i>. E isso pode impactar diretamente no fechamento das vendas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entenda que <b>a falta de um <a href=\"https:\/\/www.salesforce.com\/br\/blog\/2018\/Fevereiro\/Como-Elaborar-Um-Plano-De-Vendas.html\">plano de a\u00e7\u00e3o<\/a> consistente pode minar suas oportunidades de fechar neg\u00f3cio<\/b> justamente porque, sem um planejamento, voc\u00ea fica \u00e0 merc\u00ea do achismo e das intera\u00e7\u00f5es gen\u00e9ricas \u2013 mesmo quando, at\u00e9 ent\u00e3o, o interesse do <i>lead <\/i>pelo seu produto ou servi\u00e7o era s\u00f3lido e genu\u00edno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para n\u00e3o se perder, na pr\u00f3xima vez em que voc\u00ea estiver conversando com um <i>lead<\/i>, <b>crie uma meta a ser atingida at\u00e9 o pr\u00f3ximo contato<\/b>. Pontue tamb\u00e9m qual ser\u00e1 o prop\u00f3sito do contato e do pr\u00f3ximo passo a ser seguido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uma boa t\u00e9cnica de <i>follow-up<\/i> consiste em <b>enviar (para voc\u00ea mesmo, para o seu gestor e para o cliente) um resumo de sua intera\u00e7\u00e3o <\/b>com os pontos conversados, preocupa\u00e7\u00f5es mencionadas, data e hora da pr\u00f3xima reuni\u00e3o ou uma proposta de venda.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"a-sua-estrategia-nao-conta-com-o-apoio-de-um-crm\"> <span> A sua estrat\u00e9gia n\u00e3o conta com o apoio de um CRM <\/span> <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Vamos supor que voc\u00ea j\u00e1 tenha solucionado os problemas apontados acima. Ser\u00e1 que agora seu <i>follow-up <\/i>vai decolar de vez?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Depende. Se voc\u00ea n\u00e3o contar com o apoio de um <a href=\"https:\/\/www.salesforce.com\/br\/crm\/melhor-crm\/\">software de CRM<\/a> adequado para a sua estrat\u00e9gia, provavelmente n\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Isso porque a demanda para organizar todos os dados e informa\u00e7\u00f5es coletados antes, durante e depois do <i>follow-up<\/i> pode quebrar a <a href=\"https:\/\/www.salesforce.com\/br\/blog\/2021\/12\/7-medidas-para-aumentar-a-produtividade-em-vendas.html\">produtividade do time de vendas<\/a> e comprometer o<i> timing<\/i> para pensar <a href=\"https:\/\/www.salesforce.com\/br\/blog\/taxa-de-conversao\/\">estrat\u00e9gias de convers\u00e3o<\/a>. Um <b>sistema de CRM<\/b> como o da <b>Salesforce<\/b> ajuda voc\u00ea a <b>centralizar todas as informa\u00e7\u00f5es necess\u00e1rias em um s\u00f3 lugar<\/b>, facilitando seu rastreamento e acesso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, a ferramenta pode <b>apoiar o seu time de vendas emitindo lembretes de tarefas <\/b>(como entrar em contato com o consumidor em determinado dia ou hor\u00e1rio) e construindo relat\u00f3rios detalhados sobre o desempenho de vendas, incluindo <a href=\"https:\/\/www.salesforce.com\/br\/blog\/2021\/03\/principais-metricas-e-indicadores-de-atendimento.html\">indicadores e m\u00e9tricas do atendimento<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 claro que agendar e disparar e-mails \u00e9 importante para o fechamento das vendas, mas um <a href=\"https:\/\/www.salesforce.com\/br\/crm\/\">CRM<\/a> vai al\u00e9m de um simples disparador de e-mails. Com ele, <b>voc\u00ea pode manter uma agenda de follow-up automatizada<\/b>, reunindo todos os detalhes sobre o contato com os leads e configurando uma linha do tempo para visualizar de forma macro quem precisa ser contatado e quando isso deve ser feito.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"o-que-um-follow-up-de-vendas-eficiente-precisa-ter\"> <span> O que um follow-up de vendas eficiente precisa ter? <\/span> <\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"> Voc\u00ea j\u00e1 deve ter conseguido identificar alguns problemas que podem estar acontecendo com o seu <i>follow-up <\/i>de vendas, n\u00e3o \u00e9? Ent\u00e3o chegou a hora de entender o que um <i>follow-up <\/i>eficiente precisa ter para funcionar de verdade. Confira: <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"1-historico-do-contato-com-os-possiveis-clientes\"> <span> 1. Hist\u00f3rico do contato com os poss\u00edveis clientes <\/span> <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00e3o importa se o seu contato foi realizado por meio de uma reuni\u00e3o, e-mail ou telefonema. \u00c9 essencial <b>registrar e manter o hist\u00f3rico do <i>lead <\/i>atualizado<\/b>. Informa\u00e7\u00f5es sinalizando o que foi acordado, quais propostas foram feitas ao cliente e o que voc\u00ea ficou de fazer ou enviar s\u00e3o informa\u00e7\u00f5es fundamentais para dar seguimento \u00e0 venda consultiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, se o <i>lead<\/i> eventualmente esfriar, voc\u00ea pode utilizar seu hist\u00f3rico de informa\u00e7\u00f5es para retomar contato, utilizando uma abordagem diferente e <b>criando uma estrat\u00e9gia baseada no que deu ou n\u00e3o deu certo da \u00faltima vez.<\/b><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"2-prazos-para-as-tarefas-criadas\"> <span> 2. Prazos para as tarefas criadas <\/span> <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea prometeu que enviaria uma apresenta\u00e7\u00e3o completa para o cliente 1, mas tamb\u00e9m prometeu que faria uma reuni\u00e3o com o cliente 2 e que acompanharia um<i> trial <\/i>da ferramenta com o cliente 3. \u00c9 bastante coisa \u2013 e se nenhuma delas tiver uma data para ser feita ou entregue, voc\u00ea pode facilmente acabar esquecendo, <b>colocando a venda e a reputa\u00e7\u00e3o da empresa em risco.<\/b><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por isso, <b>trabalhe sempre com datas e prazos reais<\/b>, que comportem a necessidade do cliente mas tamb\u00e9m a sua realidade de entrega dentro do fluxo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"3-imediatismo-nas-respostas\"> <span> 3. Imediatismo nas respostas <\/span> <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Responder o <i>lead <\/i>com <b>rapidez e objetividade <\/b>\u00e9 crucial para uma boa estrat\u00e9gia de <i>follow-up<\/i>. Fa\u00e7a o poss\u00edvel para <b>sanar todas as d\u00favidas do consumidor<\/b> antes de terminar o seu expediente. Se voc\u00ea n\u00e3o tiver uma resposta adequada no momento, deixe um lembrete no CRM para enviar a sua mensagem no outro dia, no m\u00e1ximo. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mesmo assim, se voc\u00ea precisar de mais tempo para oferecer uma resposta completa, mande um e-mail informando o cliente do que est\u00e1 acontecendo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"4-acompanhamento-do-cliente-tambem-no-pos-venda\"> <span> 4. Acompanhamento do cliente tamb\u00e9m no p\u00f3s-venda <\/span> <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A venda foi fechada! Hora de comemorar e disparar uma comunica\u00e7\u00e3o de agradecimento para o novo cliente. Mas e depois? Sua intera\u00e7\u00e3o com o consumidor acaba por a\u00ed?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entenda que <b>o papel da equipe de vendas \u00e9 garantir que o cliente esteja satisfeito com o que comprou<\/b>, pois as expectativas de quem compra s\u00e3o criadas por quem vende \u2013 ou seja, isso \u00e9 sua responsabilidade. Sendo assim, esteja sempre atento para garantir que o trabalho seja executado conforme o prometido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dessa forma, busque estar ao lado do cliente, <b>mostre que voc\u00ea se preocupa mesmo depois que a venda foi fechada e mantenha uma rotina de <i>follow-up<\/i><\/b>. Use o CRM para agendar reuni\u00f5es e acompanhar tudo o que acontece no p\u00f3s-venda. Assim, voc\u00ea contribui tamb\u00e9m para as <a href=\"https:\/\/www.salesforce.com\/br\/blog\/lifetime-value-ltv\/\">m\u00e9tricas de fideliza\u00e7\u00e3o<\/a> da companhia.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"5-uso-estrategico-de-um-software-de-crm\"> <span> 5. Uso estrat\u00e9gico de um software de CRM <\/span> <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Todas as dicas que demos podem ser potencializadas pelo uso de um software de CRM. Isso significa que, com o uso da plataforma, <b>ser\u00e1 muito mais f\u00e1cil aproveitar todas as oportunidades de neg\u00f3cio e incrementar a performance de vendas.<\/b><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Atrav\u00e9s do CRM, <b>\u00e9 poss\u00edvel manter todos os dados e as a\u00e7\u00f5es do <i>follow-up<\/i> de vendas concentradas em um s\u00f3 local:<\/b> informa\u00e7\u00f5es do contato, prefer\u00eancias, pontos positivos e negativos, e-mails enviados e os motivos pelos quais voc\u00ea interrompeu o <i>follow-up<\/i> com o <i>lead.<\/i><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais ainda, voc\u00ea pode utilizar o sistema para criar e <a href=\"https:\/\/www.salesforce.com\/br\/blog\/como-criar-multiplos-funis-de-venda\/\">coordenar funis de vendas <\/a><a href=\"https:\/\/www.salesforce.com\/br\/blog\/2021\/11\/como-criar-multiplos-funis-de-venda.html\">personalizados<\/a>. Tamb\u00e9m \u00e9 poss\u00edvel definir os per\u00edodos de tempo em que voc\u00ea pode entrar em contato com os clientes para novas vendas. Dessa maneira,<b> temos o CRM como uma central de controle de todo o <a href=\"https:\/\/www.salesforce.com\/br\/blog\/2020\/01\/processo-de-vendas-como-definir-e-melhorar.html\">processo de vendas<\/a><\/b>, incluindo o acompanhamento dos clientes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"que-tal-melhorar-o-seu-follow-up-e-conquistar-mais-clientes-confira-nossas-dicas\"> <span> Que tal melhorar o seu follow-up e conquistar mais clientes? Confira nossas dicas! <\/span> <\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"> A seguir, voc\u00ea confere as dicas que separamos para tornar o seu follow-up ainda melhor e mais cadenciado, perfeito para conquistar de vez o prospect. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"dica-1-faca-o-prospect-se-comprometer-com-o-follow-up\"> <span> Dica 1: Fa\u00e7a o prospect se comprometer com o follow-up <\/span> <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"> Se voc\u00ea j\u00e1 sabe de antem\u00e3o que o <i>follow-up<\/i> faz parte da estrat\u00e9gia de vendas da empresa, deixe claro para o <i>prospect <\/i>que essa a\u00e7\u00e3o far\u00e1 parte da comunica\u00e7\u00e3o entre voc\u00eas. Assim, de cara, voc\u00ea j\u00e1 <b>estabelece um relacionamento pautado em transpar\u00eancia e confian\u00e7a.<\/b> Independentemente do canal de contato, j\u00e1 confirme com o seu cliente como o <i>follow-up<\/i> vai acontecer. Aproveite e informe-se sobre quais s\u00e3o os melhores dias e hor\u00e1rios para essa comunica\u00e7\u00e3o. Evite informa\u00e7\u00f5es vagas: avisar o cliente que voc\u00ea \u201cvai ligar daqui alguns dias\u201d n\u00e3o o prepara para nada. <b>Seja espec\u00edfico e objetivo<\/b>, deixando clara a sua inten\u00e7\u00e3o. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"dica-2-estabeleca-um-canal-de-comunicacao\"> <span> Dica 2: Estabele\u00e7a um canal de comunica\u00e7\u00e3o <\/span> <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"> Uma hora voc\u00ea fala por e-mail, outra por telefone e na seguinte j\u00e1 est\u00e1 tentando <a href=\"https:\/\/www.salesforce.com\/br\/blog\/2021\/09\/vender-pelo-whatsapp.html\">vender por WhatsApp<\/a>? Saiba que <b>estar presente em tantos canais pode deixar o<i> lead<\/i> confuso<\/b> e um pouco perdido durante a negocia\u00e7\u00e3o. Para evitar que isso aconte\u00e7a, o melhor \u00e9 <b>escolher uma plataforma para, pelo menos, iniciar o contato<\/b>. Para fazer a melhor escolha, leve em considera\u00e7\u00e3o que <b>ser\u00e1 por meio do canal escolhido que voc\u00ea vai despertar no cliente a confian\u00e7a de que ele precisa para fechar mais neg\u00f3cios.<\/b> Aproveite a oportunidade para tamb\u00e9m perguntar sobre como est\u00e1 sendo a experi\u00eancia dele no canal em quest\u00e3o. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"dica-3-personalize-sua-interacao\"> <span> Dica 3: Personalize sua intera\u00e7\u00e3o <\/span> <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"> Sempre que poss\u00edvel, <b>mostre ao cliente que ele \u00e9 \u00fanico e que a comunica\u00e7\u00e3o entre voc\u00eas n\u00e3o \u00e9 simplesmente algo automatizado.<\/b> Dessa forma, voc\u00ea personaliza o seu contato para cada <a href=\"https:\/\/www.salesforce.com\/br\/blog\/2021\/08\/mql-sql.html\">tipo de <\/a><i><a href=\"https:\/\/www.salesforce.com\/br\/blog\/2021\/08\/mql-sql.html\">lead<\/a> <\/i>e explora estrat\u00e9gias que melhor se adequam aos diferentes <a href=\"https:\/\/www.salesforce.com\/br\/blog\/2021\/06\/icp-perfil-de-cliente-ideal.html\">perfis de p\u00fablico<\/a> que voc\u00ea atinge. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"dica-4-fale-sobre-cases-de-sucesso\"> <span> Dica 4: Fale sobre cases de sucesso <\/span> <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea j\u00e1 atendeu um cliente do mesmo segmento que seu <i>lead <\/i>e o neg\u00f3cio virou um case de sucesso? Ent\u00e3o divulgue essas informa\u00e7\u00f5es! Elas podem ser cruciais para fechar o neg\u00f3cio ou mesmo <a href=\"https:\/\/www.salesforce.com\/br\/blog\/2021\/07\/marketing-boca-a-boca-como-implementar.html\">gerar boas refer\u00eancias para a sua marca<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, essa a\u00e7\u00e3o \u00e9 uma <b>forma de construir confian\u00e7a atrav\u00e9s da prova social do seu produto ou servi\u00e7o.<\/b> Ou seja, voc\u00ea est\u00e1 mostrando ao <i>prospect<\/i> como outras pessoas ou empresas puderam resolver seus problemas com o que voc\u00ea vende.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"dica-5-contrate-um-software-de-crm\"> <span> Dica 5: Contrate um software de CRM <\/span> <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"> Um software que foca em otimizar o relacionamento com o cliente \u00e9 exatamente o que voc\u00ea precisa para melhorar o seu <i>follow-up<\/i>. Um CRM ainda <b>vai ajudar sua empresa a utilizar as chances que aparecem ao seu favor<\/b>, facilitando na hora entrar em contato com os <i>leads<\/i>. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"dica-6-saiba-quando-encerrar-um-follow-up\"> <span> Dica 6: Saiba quando encerrar um follow-up <\/span> <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Se voc\u00ea recebeu um objetivo \u201cn\u00e3o\u201d ou simplesmente est\u00e1 sendo ignorado, \u00e9 hora de <b>repensar se vale a pena insistir no <i>follow-up<\/i> com o<i> lead<\/i><\/b>. Afinal, esses s\u00e3o alguns sinais de que \u00e9 hora de desapegar e riscar esses contatos do seu fluxo de cad\u00eancia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Evite insistir para n\u00e3o ser invasivo, prejudicando a sua reputa\u00e7\u00e3o e a da empresa. Tamb\u00e9m pense que n\u00e3o vale a pena desperdi\u00e7ar seu tempo e nem o do <i>lead<\/i> abordado por voc\u00ea.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"o-que-voce-achou-de-saber-mais-sobre-o-follow-up-de-vendas\"> <span> O que voc\u00ea achou de saber mais sobre o follow-up de vendas? <\/span> <\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para dominar conceitos como esse, fique atento ao nosso <a href=\"https:\/\/www.salesforce.com\/br\/blog\">blog<\/a> e <a href=\"https:\/\/www.salesforce.com\/br\/resources\/\">Centro de Recursos<\/a>, que s\u00e3o atualizados constantemente com novidades sobre o tema e muitos outros assuntos relevantes no mundo das <b>vendas<\/b>, do <b>CRM<\/b> e da <b>experi\u00eancia do cliente<\/b>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Confira outros conte\u00fados que podem interessar a voc\u00ea:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><p><a href=\"https:\/\/www.salesforce.com\/br\/blog\/personalizar-experiencia-b2b\/\">Como personalizar a experi\u00eancia B2B<\/a><\/p><\/li>\n\n\n\n<li>\n<p><a href=\"https:\/\/www.salesforce.com\/br\/blog\/2021\/02\/como-lidar-com-clientes-dificeis.html\">Como atender clientes dif\u00edceis? Saiba como lidar com os perfis mais comuns<\/a><\/p>\n<\/li>\n\n\n\n<li><p><a href=\"https:\/\/www.salesforce.com\/br\/blog\/atendimento-redes-sociais\/\">Dicas de Atendimento em Redes Sociais<\/a><\/p><\/li>\n\n\n\n<li>\n<p><a href=\"https:\/\/www.salesforce.com\/br\/blog\/2022\/2\/onboarding-de-clientes.html\">Onboarding de Clientes: Como e por que fazer<\/a><\/p>\n<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Explore tamb\u00e9m nosso <a href=\"https:\/\/www.salesforce.com\/br\/products\/\">portf\u00f3lio de produtos<\/a> e saiba como nosso CRM pode ajudar sua empresa a prosperar. Boas vendas e at\u00e9 a pr\u00f3xima!<\/p>\n\n\n\n<div class=\"layout-four wp-block-salesforce-blog-offer\">\n\t<div class=\"wp-block-offer__wrapper\">\n\n\t\t<div class=\"wp-block-offer__content\">\n\t\t\t<h2 class=\"wp-block-offer__title\">State of Sales, 4\u00aa Edi\u00e7\u00e3o<\/h2>\n\t\t\t\t\t\t\t<p class=\"wp-block-offer__description\">Entenda o que mais de 7.700 profissionais de vendas em todo mundo est\u00e3o fazendo para impulsionar sua produtividade e vender mais.<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t<a class=\"wp-block-button__link\" target=\"_blank\" href=\"https:\/\/www.salesforce.com\/br\/resources\/research-reports\/state-of-sales\/\">Baixar o relat\u00f3rio<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"wp-block-offer__media\">\n\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\n\t\t\t<!-- Standard Illustration -->\n\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__illustration\" src=\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-illustration-layout-four.png\" alt=\"\">\n\n\t\t<!-- Small Accent Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__accent\" src=\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-accent-layout-four.png\" alt=\"\">\n\t\t\n\t\t<!-- Left Side Illustration -->\n\t\t\n\t\t<!-- Cloud Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__cloud\" src=\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-cloud-layout-four.png\" alt=\"\">\n\t\t\n\t<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O follow-up \u00e9 uma oportunidade para acelerar o fechamento da venda e fortalecer o relacionamento com o cliente. Saiba como aprimorar esse contato aqui!<\/p>\n","protected":false},"author":1,"featured_media":16384,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sf_justforyou_enable_alt":true,"optimizely_content_id":"","post_meta_title":"","ai_synopsis":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"sf_topic":[835,841],"sf_content_type":[],"blog":[1178,1201,1222],"coauthors":[1109],"class_list":["post-16386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","sf_topic-sales","sf_topic-crm","blog-sales-cloud","blog-sales","blog-crm"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Follow-up de Vendas: Como realizar? | Salesforce<\/title>\n<meta name=\"description\" content=\"O follow-up \u00e9 uma oportunidade para acelerar o fechamento da venda e fortalecer o relacionamento com o cliente. Saiba como aprimorar esse contato aqui!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salesforce.com\/br\/blog\/follow-up-de-vendas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Follow-up de Vendas: Como realizar?\" \/>\n<meta property=\"og:description\" content=\"O follow-up \u00e9 uma oportunidade para acelerar o fechamento da venda e fortalecer o relacionamento com o cliente. Saiba como aprimorar esse contato aqui!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salesforce.com\/br\/blog\/follow-up-de-vendas\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-06T12:54:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-26T21:16:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/06\/blog-followup-vendas.png\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"320\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Manuela Andrade\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Manuela Andrade\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/follow-up-de-vendas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/follow-up-de-vendas\\\/\"},\"author\":[{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/#\\\/schema\\\/person\\\/image\\\/4a5c5eb3c92c9cf671ff945a16acdcc7\"}],\"headline\":\"Follow-up de Vendas: Como realizar?\",\"datePublished\":\"2023-06-06T12:54:05+00:00\",\"dateModified\":\"2024-06-26T21:16:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/follow-up-de-vendas\\\/\"},\"wordCount\":2228,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/follow-up-de-vendas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/06\\\/blog-followup-vendas.png\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/follow-up-de-vendas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/follow-up-de-vendas\\\/\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/follow-up-de-vendas\\\/\",\"name\":\"Follow-up de Vendas: Como realizar? | Salesforce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/follow-up-de-vendas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/follow-up-de-vendas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/06\\\/blog-followup-vendas.png\",\"datePublished\":\"2023-06-06T12:54:05+00:00\",\"dateModified\":\"2024-06-26T21:16:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/#\\\/schema\\\/person\\\/601f410a2801f4ddcf6f00cb182e69d3\"},\"description\":\"O follow-up \u00e9 uma oportunidade para acelerar o fechamento da venda e fortalecer o relacionamento com o cliente. Saiba como aprimorar esse contato aqui!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/follow-up-de-vendas\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/follow-up-de-vendas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/follow-up-de-vendas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/06\\\/blog-followup-vendas.png\",\"contentUrl\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/06\\\/blog-followup-vendas.png\",\"width\":480,\"height\":320,\"caption\":\"Vendedor em liga\u00e7\u00e3o de follow-up com o cliente, segurando pap\u00e9is com script de vendas.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/follow-up-de-vendas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Follow-up de Vendas: Como realizar?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/\",\"name\":\"Salesforce\",\"description\":\"Novidades sobre ia ag\u00eantica, dados e crm\",\"alternateName\":\"Salesforce Brasil\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/#\\\/schema\\\/person\\\/image\\\/4a5c5eb3c92c9cf671ff945a16acdcc7\",\"name\":\"Manuela Andrade\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/#\\\/schema\\\/person\\\/image\\\/712176dfdb7549947e9065543bdabfdc\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/05\\\/Honorary-Trailhead-Ranger.png?w=150&h=150&crop=1\",\"contentUrl\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/05\\\/Honorary-Trailhead-Ranger.png?w=150&h=150&crop=1\",\"width\":150,\"height\":150,\"caption\":\"Manuela Andrade\"},\"description\":\"L\u00edder com uma trajet\u00f3ria em diversas ind\u00fastrias e culturas. Possui quinze anos de experi\u00eancia em big techs, sendo os \u00faltimos dez anos dedicados \u00e0 \u00e1rea comercial.\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/br\\\/blog\\\/author\\\/manuela-andrade\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Follow-up de Vendas: Como realizar? | Salesforce","description":"O follow-up \u00e9 uma oportunidade para acelerar o fechamento da venda e fortalecer o relacionamento com o cliente. Saiba como aprimorar esse contato aqui!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salesforce.com\/br\/blog\/follow-up-de-vendas\/","og_locale":"pt_BR","og_type":"article","og_title":"Follow-up de Vendas: Como realizar?","og_description":"O follow-up \u00e9 uma oportunidade para acelerar o fechamento da venda e fortalecer o relacionamento com o cliente. Saiba como aprimorar esse contato aqui!","og_url":"https:\/\/www.salesforce.com\/br\/blog\/follow-up-de-vendas\/","og_site_name":"Salesforce","article_published_time":"2023-06-06T12:54:05+00:00","article_modified_time":"2024-06-26T21:16:09+00:00","og_image":[{"width":480,"height":320,"url":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/06\/blog-followup-vendas.png","type":"image\/png"}],"author":"Manuela Andrade","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"","Est. tempo de leitura":"12 minutos","Written by":"Manuela Andrade"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salesforce.com\/br\/blog\/follow-up-de-vendas\/#article","isPartOf":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/follow-up-de-vendas\/"},"author":[{"@id":"https:\/\/www.salesforce.com\/br\/blog\/#\/schema\/person\/image\/4a5c5eb3c92c9cf671ff945a16acdcc7"}],"headline":"Follow-up de Vendas: Como realizar?","datePublished":"2023-06-06T12:54:05+00:00","dateModified":"2024-06-26T21:16:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/follow-up-de-vendas\/"},"wordCount":2228,"commentCount":0,"image":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/follow-up-de-vendas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/06\/blog-followup-vendas.png","inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.salesforce.com\/br\/blog\/follow-up-de-vendas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.salesforce.com\/br\/blog\/follow-up-de-vendas\/","url":"https:\/\/www.salesforce.com\/br\/blog\/follow-up-de-vendas\/","name":"Follow-up de Vendas: Como realizar? | Salesforce","isPartOf":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/follow-up-de-vendas\/#primaryimage"},"image":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/follow-up-de-vendas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/06\/blog-followup-vendas.png","datePublished":"2023-06-06T12:54:05+00:00","dateModified":"2024-06-26T21:16:09+00:00","author":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/#\/schema\/person\/601f410a2801f4ddcf6f00cb182e69d3"},"description":"O follow-up \u00e9 uma oportunidade para acelerar o fechamento da venda e fortalecer o relacionamento com o cliente. Saiba como aprimorar esse contato aqui!","breadcrumb":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/follow-up-de-vendas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salesforce.com\/br\/blog\/follow-up-de-vendas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.salesforce.com\/br\/blog\/follow-up-de-vendas\/#primaryimage","url":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/06\/blog-followup-vendas.png","contentUrl":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/06\/blog-followup-vendas.png","width":480,"height":320,"caption":"Vendedor em liga\u00e7\u00e3o de follow-up com o cliente, segurando pap\u00e9is com script de vendas."},{"@type":"BreadcrumbList","@id":"https:\/\/www.salesforce.com\/br\/blog\/follow-up-de-vendas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salesforce.com\/br\/blog\/"},{"@type":"ListItem","position":2,"name":"Follow-up de Vendas: Como realizar?"}]},{"@type":"WebSite","@id":"https:\/\/www.salesforce.com\/br\/blog\/#website","url":"https:\/\/www.salesforce.com\/br\/blog\/","name":"Salesforce","description":"Novidades sobre ia ag\u00eantica, dados e crm","alternateName":"Salesforce Brasil","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salesforce.com\/br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.salesforce.com\/br\/blog\/#\/schema\/person\/image\/4a5c5eb3c92c9cf671ff945a16acdcc7","name":"Manuela Andrade","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.salesforce.com\/br\/blog\/#\/schema\/person\/image\/712176dfdb7549947e9065543bdabfdc","url":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2024\/05\/Honorary-Trailhead-Ranger.png?w=150&h=150&crop=1","contentUrl":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2024\/05\/Honorary-Trailhead-Ranger.png?w=150&h=150&crop=1","width":150,"height":150,"caption":"Manuela Andrade"},"description":"L\u00edder com uma trajet\u00f3ria em diversas ind\u00fastrias e culturas. Possui quinze anos de experi\u00eancia em big techs, sendo os \u00faltimos dez anos dedicados \u00e0 \u00e1rea comercial.","url":"https:\/\/www.salesforce.com\/br\/blog\/author\/manuela-andrade\/"}]}},"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Salesforce","distributor_original_site_url":"https:\/\/www.salesforce.com\/br\/blog","push-errors":false,"jetpack_featured_media_url":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/06\/blog-followup-vendas.png","_links":{"self":[{"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/posts\/16386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/comments?post=16386"}],"version-history":[{"count":14,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/posts\/16386\/revisions"}],"predecessor-version":[{"id":21682,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/posts\/16386\/revisions\/21682"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/media\/16384"}],"wp:attachment":[{"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/media?parent=16386"}],"wp:term":[{"taxonomy":"sf_topic","embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/sf_topic?post=16386"},{"taxonomy":"sf_content_type","embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/sf_content_type?post=16386"},{"taxonomy":"blog","embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/blog?post=16386"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/coauthors?post=16386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}