{"id":18568,"date":"2023-05-31T00:23:00","date_gmt":"2023-05-31T00:23:00","guid":{"rendered":"https:\/\/www.salesforce.com\/?p=18568"},"modified":"2023-08-23T18:01:43","modified_gmt":"2023-08-23T18:01:43","slug":"desbravar-horizontes-para-sonhar-novas-realidades","status":"publish","type":"post","link":"https:\/\/www.salesforce.com\/br\/blog\/desbravar-horizontes-para-sonhar-novas-realidades\/","title":{"rendered":"Desbravar horizontes para sonhar novas realidades"},"content":{"rendered":"\n<p>Transformar medo em coragem, preconceito em orgulho, sonho em realidade. A comunidade LGBTQIAPN+ tem sua hist\u00f3ria marcada pela discrimina\u00e7\u00e3o e viol\u00eancias, e, dado este cen\u00e1rio, sempre foi incansavelmente corajosa para que, com a\u00e7\u00f5es di\u00e1rias, trilhasse seu caminho na constru\u00e7\u00e3o de respeito, seguran\u00e7a, acesso a oportunidades e dignidade.&nbsp;<\/p>\n\n\n\n<p>O Dia do Orgulho LGBTQIAPN+ \u00e9 uma celebra\u00e7\u00e3o anual que ocorre no dia 28 de junho e representa um marco importante na hist\u00f3ria dos direitos e da visibilidade da comunidade no mundo inteiro. Essa data foi criada para lembrar e honrar os eventos ocorridos na noite de 27 para 28 de junho de 1969, no bar Stonewall Inn, em Nova York.<\/p>\n\n\n\n<p>Naquela \u00e9poca, a homossexualidade, e qualquer forma de express\u00e3o de g\u00eanero fora do padr\u00e3o, eram amplamente reprimidas e consideradas ilegais nos Estados Unidos. A pol\u00edcia frequentemente realizava batidas em bares frequentados por pessoas LGBTQIAPN+, a fim de prender e intimidar aqueles que n\u00e3o se encaixavam nas normas sociais. No entanto, naquela fat\u00eddica noite, a hist\u00f3ria se fez diferente.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"stonewall-inn-o-marco-da-resistencia\">Stonewall Inn: o marco da resist\u00eancia<\/h2>\n\n\n\n<p>O Stonewall Inn era um dos poucos locais em Nova York onde pessoas da comunidade podiam se encontrar, dan\u00e7ar e se expressar livremente, apesar das constantes amea\u00e7as e agress\u00f5es policiais. Naquela noite, quando a pol\u00edcia invadiu o bar, as pessoas presentes, em vez de recuar, decidiu se unir e lutar contra a opress\u00e3o.<\/p>\n\n\n\n<p>Enfrentar a pol\u00edcia naquela ocasi\u00e3o simbolizou n\u00e3o s\u00f3 o descontentamento com o epis\u00f3dio de maneira isolada, mas um ac\u00famulo de todas as marcas f\u00edsicas e psicol\u00f3gicas deixadas por anos de exclus\u00e3o, discrimina\u00e7\u00e3o e julgamento de suas exist\u00eancias. At\u00e9 aquela data, o direito de vida e de livre express\u00e3o para essa popula\u00e7\u00e3o n\u00e3o era assegurado. Portanto, naquele momento, a discuss\u00e3o era ainda basal: a possibilidade de seguir com vida sendo quem \u00e9.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"marsha-p-johnson-a-figura-central-da-resistencia\">Marsha P. Johnson: a figura central da resist\u00eancia<\/h2>\n\n\n\n<p>Marsha P. Johnson, uma mulher negra transg\u00eanero e ativista pelos direitos LGBTQIAPN+, foi uma das figuras centrais nesse movimento de resist\u00eancia. Ela foi uma das primeiras a se levantar contra a pol\u00edcia naquela noite, batendo de frente com as for\u00e7as de autoridade com coragem e determina\u00e7\u00e3o. Marsha se tornou um s\u00edmbolo de resist\u00eancia e empoderamento para a comunidade, lutando incansavelmente por seus direitos e pela justi\u00e7a ao longo de sua vida.<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a5708aa54d0c&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a5708aa54d0c\" class=\"wp-block-image wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/www.salesforce.com\/content\/dam\/blogs\/br\/2023\/06\/blog-pride-2023.jpg\" alt=\"\"\/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p>Os protestos em resposta \u00e0 invas\u00e3o policial no Stonewall Inn se estenderam por v\u00e1rios dias, envolvendo uma ampla gama de pessoas LGBTQIAPN+ e pessoal aliadas. Este levante foi um catalisador para o movimento de liberta\u00e7\u00e3o da comunidade, gerando um despertar coletivo para a luta pelos direitos civis e pela igualdade.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"o-dia-internacional-do-orgulho-lgbtqiapn-celebrando-a-coragem-e-os-direitos-civis\">O Dia Internacional do Orgulho LGBTQIAPN+: celebrando a coragem e os direitos civis<\/h3>\n\n\n\n<p>Em anos subsequentes, o anivers\u00e1rio desses eventos passou a ser celebrado como o Dia Internacional do Orgulho LGBTQIAPN+. A data serve como um lembrete dos desafios enfrentados pela comunidade e como uma homenagem \u00e0 coragem daqueles que se levantaram contra a opress\u00e3o. Lembrar as pessoas que estiveram \u00e0 frente do movimento \u00e9 de extrema import\u00e2ncia para reiterar que os direitos que temos hoje n\u00e3o vieram por acaso, foram conquistados com muito esfor\u00e7o e luta.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"avancos-e-desafios-o-caminho-para-a-igualdade-lgbtqiapn\">Avan\u00e7os e desafios: o caminho para a igualdade LGBTQIAPN+<\/h3>\n\n\n\n<p>Vale destacar que, embora tenhamos alcan\u00e7ado avan\u00e7os significativos nos direitos LGBTQIAPN+ desde os acontecimentos de Stonewall, ainda h\u00e1 muito trabalho a ser feito. O Dia do Orgulho continua sendo uma oportunidade para reafirmar o compromisso com a igualdade, combater a discrimina\u00e7\u00e3o e buscar uma sociedade mais inclusiva e justa para todas as pessoas,&nbsp;<strong>independentemente de sua orienta\u00e7\u00e3o sexual, identidade de g\u00eanero ou express\u00e3o de g\u00eanero.&nbsp;<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"stonewall-no-brasil-inspiracao-e-luta-por-direitos\">Stonewall no Brasil: inspira\u00e7\u00e3o e luta por direitos<\/h3>\n\n\n\n<p>No Brasil, o reflexo de Stonewall foi sentido de maneira diferente, mas igualmente importante. Apesar de o evento em si n\u00e3o ter tido impacto direto no pa\u00eds, ele serviu de inspira\u00e7\u00e3o e fortaleceu a luta local por direitos LGBTQIAPN+. A partir da d\u00e9cada de 1970, movimentos e organiza\u00e7\u00f5es come\u00e7aram a surgir no Brasil, reivindicando o fim da discrimina\u00e7\u00e3o e da criminaliza\u00e7\u00e3o da homossexualidade.<\/p>\n\n\n\n<p>A luta pelos direitos civis da comunidade LGBTQIAPN+ no Brasil tem avan\u00e7ado, mas ainda h\u00e1 muito a ser conquistado. O Brasil \u00e9 hoje, dentre os pa\u00edses onde h\u00e1 mapeamento dos dados, o pa\u00eds que mais mata pessoas LGBTQIAPN+ no mundo. A garantia da igualdade de direitos, o combate \u00e0 viol\u00eancia e a promo\u00e7\u00e3o do respeito s\u00e3o batalhas cont\u00ednuas. A luta pelos direitos LGBTQIAPN+ \u00e9 uma luta por direitos humanos fundamentais e pela dignidade de todas as pessoas, independentemente de sua orienta\u00e7\u00e3o sexual ou identidade de g\u00eanero.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"a-violencia-contra-a-comunidade-lgbtqiapn-um-chamado-a-acao\">A viol\u00eancia contra a comunidade LGBTQIAPN+: um chamado \u00e0 a\u00e7\u00e3o<\/h3>\n\n\n\n<p>Pessoas aliadas desempenham um papel crucial nessa causa. S\u00e3o pessoas que apoiam e defendem a comunidade, mesmo n\u00e3o sendo parte direta dela. Podem ajudar a ampliar o alcance das vozes, combater preconceitos e estere\u00f3tipos, e promover a inclus\u00e3o em suas pr\u00f3prias comunidades. As pessoas aliadas podem educar-se sobre as quest\u00f5es LGBTQIAPN+, questionar comportamentos discriminat\u00f3rios e apoiar iniciativas e organiza\u00e7\u00f5es que lutam pelos direitos da comunidade.<\/p>\n\n\n\n<p>Portanto, a constru\u00e7\u00e3o de um mundo mais inclusivo, igualit\u00e1rio e seguro para todas as pessoas \u00e9 uma tarefa coletiva, que precisa ser pensada e colocada na pr\u00e1tica cotidiana. Por isso, mais do que apenas apresentar, n\u00f3s sugerimos algumas reflex\u00f5es para essa data:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Quantas pessoas trans e travestis voc\u00ea, pessoa leitora, t\u00eam no seu ciclo social? Se a resposta for nenhuma, qual fator imagina ser o causador desse cen\u00e1rio?&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Quantas pessoas LGBTQIAPN+ voc\u00ea viu em cargos de lideran\u00e7a no seu trabalho?&nbsp;&nbsp;<\/li>\n\n\n\n<li>Como voc\u00ea hoje poderia ajudar na constru\u00e7\u00e3o de um mundo melhor para estas pessoas?&nbsp;<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"o-grupo-outforce-promovendo-diversidade-e-inclusao-na-salesforce\">O Grupo Outforce: promovendo diversidade e inclus\u00e3o na Salesforce<\/h3>\n\n\n\n<p>Na Salesforce temos uma comunidade inclusiva, o Grupo Outforce, composto por pessoas aliadas na luta pela igualdade na orienta\u00e7\u00e3o sexual e identidade de g\u00eanero. Consideramos uma grande oportunidade de destacar as vozes e experi\u00eancias do vibrante coletivo LGBTQIAPN+ tanto dentro quanto fora da empresa.<\/p>\n\n\n\n<p>Com o objetivo de promover o respeito, a liberdade e a igualdade, o Outforce desempenha um papel fundamental ao educar o ecossistema Salesforce sobre como a diversidade e a inclus\u00e3o s\u00e3o elementos essenciais para o sucesso &#8211; nos neg\u00f3cios e na vida! Valorizando cada letra da sigla LGBTQIAPN+, o grupo re\u00fane hist\u00f3rias, nomes, lugares, profissionais e, acima de tudo, pessoas. &nbsp;<\/p>\n\n\n\n<p>Atrav\u00e9s dessa comunidade, a Salesforce reafirma seu compromisso em criar uma cultura aberta, instrutiva e acolhedora, onde todas as pessoas&nbsp;se sintam empoderadas para serem aut\u00eanticas em seu ambiente de trabalho. O Outforce \u00e9 um s\u00edmbolo de orgulho e celebra\u00e7\u00e3o da diversidade e inclus\u00e3o!<\/p>\n\n\n\n<p>Vamos mudar o mundo? Para come\u00e7ar essa mudan\u00e7a precisamos do primeiro passo.\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No M\u00eas Pride, convidamos voc\u00ea a ler o artigo do Victor, que faz parte do Grupo Outforce, em nosso blog. Ele traz uma profunda reflex\u00e3o sobre o surgimento do M\u00eas do Orgulho, os avan\u00e7os e o que ainda precisa ser feito!<\/p>\n","protected":false},"author":1,"featured_media":18570,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sf_justforyou_enable_alt":true,"optimizely_content_id":"","post_meta_title":"","ai_synopsis":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"sf_topic":[],"sf_content_type":[],"blog":[1165],"coauthors":[838],"class_list":["post-18568","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","blog-trailblazer-community"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Desbravar horizontes para sonhar novas realidades | Salesforce<\/title>\n<meta name=\"description\" content=\"No M\u00eas Pride, convidamos voc\u00ea a ler o artigo do Victor, que faz parte do Grupo Outforce, em nosso blog. Ele traz uma profunda reflex\u00e3o sobre o surgimento do M\u00eas do Orgulho, os avan\u00e7os e o que ainda precisa ser feito!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salesforce.com\/br\/blog\/desbravar-horizontes-para-sonhar-novas-realidades\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desbravar horizontes para sonhar novas realidades\" \/>\n<meta property=\"og:description\" content=\"No M\u00eas Pride, convidamos voc\u00ea a ler o artigo do Victor, que faz parte do Grupo Outforce, em nosso blog. Ele traz uma profunda reflex\u00e3o sobre o surgimento do M\u00eas do Orgulho, os avan\u00e7os e o que ainda precisa ser feito!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salesforce.com\/br\/blog\/desbravar-horizontes-para-sonhar-novas-realidades\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-31T00:23:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-23T18:01:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/08\/blog-pride-br-victor-pessoa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"587\" \/>\n\t<meta property=\"og:image:height\" content=\"578\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Salesforce Brasil\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"digital-delivery-operations7076\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Salesforce Brasil\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.salesforce.com\/br\/blog\/desbravar-horizontes-para-sonhar-novas-realidades\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.salesforce.com\/br\/blog\/desbravar-horizontes-para-sonhar-novas-realidades\/\"},\"author\":[{\"@id\":\"https:\/\/www.salesforce.com\/br\/blog\/#\/schema\/person\/image\/721817ecd0471fdcdbe63bb84fea85dc\"}],\"headline\":\"Desbravar horizontes para sonhar novas realidades\",\"datePublished\":\"2023-05-31T00:23:00+00:00\",\"dateModified\":\"2023-08-23T18:01:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.salesforce.com\/br\/blog\/desbravar-horizontes-para-sonhar-novas-realidades\/\"},\"wordCount\":1197,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/br\/blog\/desbravar-horizontes-para-sonhar-novas-realidades\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/08\/blog-pride-br-victor-pessoa.jpg\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.salesforce.com\/br\/blog\/desbravar-horizontes-para-sonhar-novas-realidades\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.salesforce.com\/br\/blog\/desbravar-horizontes-para-sonhar-novas-realidades\/\",\"url\":\"https:\/\/www.salesforce.com\/br\/blog\/desbravar-horizontes-para-sonhar-novas-realidades\/\",\"name\":\"Desbravar horizontes para sonhar novas realidades | Salesforce\",\"isPartOf\":{\"@id\":\"https:\/\/www.salesforce.com\/br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.salesforce.com\/br\/blog\/desbravar-horizontes-para-sonhar-novas-realidades\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/br\/blog\/desbravar-horizontes-para-sonhar-novas-realidades\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/08\/blog-pride-br-victor-pessoa.jpg\",\"datePublished\":\"2023-05-31T00:23:00+00:00\",\"dateModified\":\"2023-08-23T18:01:43+00:00\",\"author\":{\"@id\":\"https:\/\/www.salesforce.com\/br\/blog\/#\/schema\/person\/601f410a2801f4ddcf6f00cb182e69d3\"},\"description\":\"No M\u00eas Pride, convidamos voc\u00ea a ler o artigo do Victor, que faz parte do Grupo Outforce, em nosso blog. Ele traz uma profunda reflex\u00e3o sobre o surgimento do M\u00eas do Orgulho, os avan\u00e7os e o que ainda precisa ser feito!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.salesforce.com\/br\/blog\/desbravar-horizontes-para-sonhar-novas-realidades\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.salesforce.com\/br\/blog\/desbravar-horizontes-para-sonhar-novas-realidades\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.salesforce.com\/br\/blog\/desbravar-horizontes-para-sonhar-novas-realidades\/#primaryimage\",\"url\":\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/08\/blog-pride-br-victor-pessoa.jpg\",\"contentUrl\":\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/08\/blog-pride-br-victor-pessoa.jpg\",\"width\":587,\"height\":578},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.salesforce.com\/br\/blog\/desbravar-horizontes-para-sonhar-novas-realidades\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.salesforce.com\/br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Desbravar horizontes para sonhar novas realidades\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.salesforce.com\/br\/blog\/#website\",\"url\":\"https:\/\/www.salesforce.com\/br\/blog\/\",\"name\":\"Salesforce\",\"description\":\"Novidades sobre ia ag\u00eantica, dados e crm\",\"alternateName\":\"Salesforce Brasil\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.salesforce.com\/br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.salesforce.com\/br\/blog\/#\/schema\/person\/image\/721817ecd0471fdcdbe63bb84fea85dc\",\"name\":\"Salesforce Brasil\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.salesforce.com\/br\/blog\/#\/schema\/person\/image\/1d313068b0a89247f1ca07d456b4f5e0\",\"url\":\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/07\/Salesforce-logo.webp?w=150&h=150&crop=1\",\"contentUrl\":\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/07\/Salesforce-logo.webp?w=150&h=150&crop=1\",\"width\":\"150\",\"height\":\"150\",\"caption\":\"Salesforce Brasil\"},\"description\":\"Somos uma plataforma de gerenciamento de relacionamento com o cliente (CRM) baseada na nuvem, que permite com que empresas possam gerenciar e integrar todas as suas opera\u00e7\u00f5es, como vendas, marketing, atendimento, ecommerce e TI em um lugar s\u00f3.\",\"url\":\"https:\/\/www.salesforce.com\/br\/blog\/author\/salesforce-brasil\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Desbravar horizontes para sonhar novas realidades | Salesforce","description":"No M\u00eas Pride, convidamos voc\u00ea a ler o artigo do Victor, que faz parte do Grupo Outforce, em nosso blog. Ele traz uma profunda reflex\u00e3o sobre o surgimento do M\u00eas do Orgulho, os avan\u00e7os e o que ainda precisa ser feito!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salesforce.com\/br\/blog\/desbravar-horizontes-para-sonhar-novas-realidades\/","og_locale":"pt_BR","og_type":"article","og_title":"Desbravar horizontes para sonhar novas realidades","og_description":"No M\u00eas Pride, convidamos voc\u00ea a ler o artigo do Victor, que faz parte do Grupo Outforce, em nosso blog. Ele traz uma profunda reflex\u00e3o sobre o surgimento do M\u00eas do Orgulho, os avan\u00e7os e o que ainda precisa ser feito!","og_url":"https:\/\/www.salesforce.com\/br\/blog\/desbravar-horizontes-para-sonhar-novas-realidades\/","og_site_name":"Salesforce","article_published_time":"2023-05-31T00:23:00+00:00","article_modified_time":"2023-08-23T18:01:43+00:00","og_image":[{"width":587,"height":578,"url":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/08\/blog-pride-br-victor-pessoa.jpg","type":"image\/jpeg"}],"author":"Salesforce Brasil","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"digital-delivery-operations7076","Est. tempo de leitura":"7 minutos","Written by":"Salesforce Brasil"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salesforce.com\/br\/blog\/desbravar-horizontes-para-sonhar-novas-realidades\/#article","isPartOf":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/desbravar-horizontes-para-sonhar-novas-realidades\/"},"author":[{"@id":"https:\/\/www.salesforce.com\/br\/blog\/#\/schema\/person\/image\/721817ecd0471fdcdbe63bb84fea85dc"}],"headline":"Desbravar horizontes para sonhar novas realidades","datePublished":"2023-05-31T00:23:00+00:00","dateModified":"2023-08-23T18:01:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/desbravar-horizontes-para-sonhar-novas-realidades\/"},"wordCount":1197,"commentCount":0,"image":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/desbravar-horizontes-para-sonhar-novas-realidades\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/08\/blog-pride-br-victor-pessoa.jpg","inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.salesforce.com\/br\/blog\/desbravar-horizontes-para-sonhar-novas-realidades\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.salesforce.com\/br\/blog\/desbravar-horizontes-para-sonhar-novas-realidades\/","url":"https:\/\/www.salesforce.com\/br\/blog\/desbravar-horizontes-para-sonhar-novas-realidades\/","name":"Desbravar horizontes para sonhar novas realidades | Salesforce","isPartOf":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/desbravar-horizontes-para-sonhar-novas-realidades\/#primaryimage"},"image":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/desbravar-horizontes-para-sonhar-novas-realidades\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/08\/blog-pride-br-victor-pessoa.jpg","datePublished":"2023-05-31T00:23:00+00:00","dateModified":"2023-08-23T18:01:43+00:00","author":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/#\/schema\/person\/601f410a2801f4ddcf6f00cb182e69d3"},"description":"No M\u00eas Pride, convidamos voc\u00ea a ler o artigo do Victor, que faz parte do Grupo Outforce, em nosso blog. Ele traz uma profunda reflex\u00e3o sobre o surgimento do M\u00eas do Orgulho, os avan\u00e7os e o que ainda precisa ser feito!","breadcrumb":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/desbravar-horizontes-para-sonhar-novas-realidades\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salesforce.com\/br\/blog\/desbravar-horizontes-para-sonhar-novas-realidades\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.salesforce.com\/br\/blog\/desbravar-horizontes-para-sonhar-novas-realidades\/#primaryimage","url":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/08\/blog-pride-br-victor-pessoa.jpg","contentUrl":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/08\/blog-pride-br-victor-pessoa.jpg","width":587,"height":578},{"@type":"BreadcrumbList","@id":"https:\/\/www.salesforce.com\/br\/blog\/desbravar-horizontes-para-sonhar-novas-realidades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salesforce.com\/br\/blog\/"},{"@type":"ListItem","position":2,"name":"Desbravar horizontes para sonhar novas realidades"}]},{"@type":"WebSite","@id":"https:\/\/www.salesforce.com\/br\/blog\/#website","url":"https:\/\/www.salesforce.com\/br\/blog\/","name":"Salesforce","description":"Novidades sobre ia ag\u00eantica, dados e crm","alternateName":"Salesforce Brasil","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salesforce.com\/br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.salesforce.com\/br\/blog\/#\/schema\/person\/image\/721817ecd0471fdcdbe63bb84fea85dc","name":"Salesforce Brasil","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.salesforce.com\/br\/blog\/#\/schema\/person\/image\/1d313068b0a89247f1ca07d456b4f5e0","url":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/07\/Salesforce-logo.webp?w=150&h=150&crop=1","contentUrl":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/07\/Salesforce-logo.webp?w=150&h=150&crop=1","width":"150","height":"150","caption":"Salesforce Brasil"},"description":"Somos uma plataforma de gerenciamento de relacionamento com o cliente (CRM) baseada na nuvem, que permite com que empresas possam gerenciar e integrar todas as suas opera\u00e7\u00f5es, como vendas, marketing, atendimento, ecommerce e TI em um lugar s\u00f3.","url":"https:\/\/www.salesforce.com\/br\/blog\/author\/salesforce-brasil\/"}]}},"jetpack_featured_media_url":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2023\/08\/blog-pride-br-victor-pessoa.jpg","jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Salesforce","distributor_original_site_url":"https:\/\/www.salesforce.com\/br\/blog","push-errors":false,"_links":{"self":[{"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/posts\/18568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/comments?post=18568"}],"version-history":[{"count":3,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/posts\/18568\/revisions"}],"predecessor-version":[{"id":18631,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/posts\/18568\/revisions\/18631"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/media\/18570"}],"wp:attachment":[{"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/media?parent=18568"}],"wp:term":[{"taxonomy":"sf_topic","embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/sf_topic?post=18568"},{"taxonomy":"sf_content_type","embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/sf_content_type?post=18568"},{"taxonomy":"blog","embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/blog?post=18568"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/coauthors?post=18568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}