{"id":22702,"date":"2025-07-31T13:51:18","date_gmt":"2025-07-31T13:51:18","guid":{"rendered":"https:\/\/www.salesforce.com\/?p=22702"},"modified":"2026-04-08T17:27:48","modified_gmt":"2026-04-08T17:27:48","slug":"grafico-de-gantt","status":"publish","type":"post","link":"https:\/\/www.salesforce.com\/br\/blog\/grafico-de-gantt\/","title":{"rendered":"Gr\u00e1fico de Gantt: o que \u00e9 e como criar um"},"content":{"rendered":"\n<p>Se voc\u00ea atua como gestor ou gerente de projetos &#8211; principalmente de grandes projetos -, o <strong>gr\u00e1fico de Gantt<\/strong> pode ser ideal para facilitar o seu dia a dia. Afinal, a ferramenta foi pensada justamente para desconstruir as v\u00e1rias partes operacionais que comp\u00f5em um grande objetivo.&nbsp;<\/p>\n\n\n\n<p>Atrav\u00e9s da <strong>visualiza\u00e7\u00e3o proporcionada pelo gr\u00e1fico de Gantt,<\/strong> os gestores podem acompanhar o que est\u00e1 sendo feito, em que velocidade e o que ainda est\u00e1 precisando de uma certa aten\u00e7\u00e3o para se desenvolver mais r\u00e1pido.&nbsp;<br>Se voc\u00ea deseja saber mais sobre o <strong>gr\u00e1fico de Gantt<\/strong>, continue a leitura conosco. Abaixo, voc\u00ea pode conferir quais s\u00e3o os principais t\u00f3picos abordados neste conte\u00fado. Boa leitura e bons projetos!<\/p>\n\n\n\n<p><strong>LEIA MAIS: <\/strong><a href=\"https:\/\/www.salesforce.com\/br\/blog\/analise-swot\/\"><strong>An\u00e1lise SWOT: o guia para faz\u00ea-la corretamente<\/strong><\/a><\/p>\n\n\n\n<div class=\"layout-one wp-block-salesforce-blog-offer\">\n\t<div class=\"wp-block-offer__wrapper\">\n\n\t\t<div class=\"wp-block-offer__content\">\n\t\t\t<h2 class=\"wp-block-offer__title\">Guia de CRM para iniciantes<\/h2>\n\t\t\t\t\t\t\t<p class=\"wp-block-offer__description\">Neste e-book te ajudaremos a determinar se vale a pena investir em um CRM. Confira!<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t<a class=\"wp-block-button__link\" target=\"_blank\" href=\"https:\/\/www.salesforce.com\/br\/form\/sales-cloud\/guia-de-crm-para-iniciantes\/\">Baixar e-book<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"wp-block-offer__media\">\n\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wp-block-offer__graphics wp-block-offer__contour\"><\/div>\n\t\n\t\t\t<!-- Standard Illustration -->\n\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__illustration\" src=\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-illustration-layout-one.png\" alt=\"\">\n\n\t\t<!-- Small Accent Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__accent\" src=\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-accent-layout-one.png\" alt=\"\">\n\t\t\n\t\t<!-- Left Side Illustration -->\n\t\t\n\t\t<!-- Cloud Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__cloud\" src=\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-cloud-layout-one.png\" alt=\"\">\n\t\t\n\t<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-o-que-e-o-grafico-de-gantt\">O que \u00e9 o Gr\u00e1fico de Gantt?<\/h2>\n\n\n\n<p>Basicamente, <strong>o gr\u00e1fico de Gantt \u00e9 uma ferramenta visual bastante utilizada para planejar e controlar projetos.<\/strong> Ele consiste em <strong>um gr\u00e1fico de barras horizontais que apresenta as atividades de um projeto distribu\u00eddas ao longo de uma linha do tempo, <\/strong>facilitando a <strong>organiza\u00e7\u00e3o das etapas<\/strong> e o <strong>acompanhamento do progresso.<\/strong><\/p>\n\n\n\n<p>Al\u00e9m disso, o nome Gantt veio do pr\u00f3prio criador do gr\u00e1fico, Henry Gantt. Ele criou a forma de visualiza\u00e7\u00e3o no s\u00e9culo XX com o <strong>objetivo de representar cronogramas de maneira clara. <\/strong>Inicialmente, era usado para <strong>monitorar tarefas repetitivas <\/strong>e <strong>mensurar a produtividade de equipes.<\/strong><\/p>\n\n\n\n<p>Atualmente, <strong>o gr\u00e1fico de Gantt \u00e9 amplamente adotado no gerenciamento de projetos devido \u00e0 sua efici\u00eancia.<\/strong> Eles ajudam as equipes a coordenar melhor suas atividades, otimizar o uso dos recursos dispon\u00edveis e identificar poss\u00edveis obst\u00e1culos relacionados \u00e0 ordem ou \u00e0 depend\u00eancia entre as tarefas.<\/p>\n\n\n\n<p>Quer saber mais sobre como inspirar o seu time operacional a produzir mais? Ent\u00e3o assista ao v\u00eddeo que separamos abaixo, com uma fala do psic\u00f3logo de neg\u00f3cios Andrew Sillitoe para o TED Talks:&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"How to create a high performance culture | Andrew Sillitoe | TEDxRoyalTunbridgeWells\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/BAdeFHlhKi4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Ademais, vale salientar que <strong>a estrutura b\u00e1sica de um gr\u00e1fico de Gantt \u00e9 dividida em duas partes:&nbsp;<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>no <strong>eixo horizontal<\/strong> ficam as datas ou per\u00edodos do projeto;&nbsp;<\/li>\n\n\n\n<li>no <strong>eixo vertical<\/strong>, as tarefas listadas.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>Assim, <strong>cada atividade \u00e9 representada por uma barra que mostra seu in\u00edcio, dura\u00e7\u00e3o e t\u00e9rmino.<\/strong> Por fim, vale dizer que \u00e9 poss\u00edvel enriquecer esses gr\u00e1ficos com informa\u00e7\u00f5es adicionais, como marcos importantes, respons\u00e1veis por cada tarefa e rela\u00e7\u00f5es de depend\u00eancia entre as etapas do projeto.&nbsp;<\/p>\n\n\n\n<p><strong>LEIA MAIS: <\/strong><a href=\"https:\/\/www.salesforce.com\/br\/blog\/plano-de-acao\/\"><strong>Plano de a\u00e7\u00e3o 5w2h: Afinal, o que \u00e9?<\/strong><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Quais s\u00e3o os principais componentes de um Gr\u00e1fico de Gantt?<\/h2>\n\n\n\n<p>O gr\u00e1fico de Gantt \u00e9 composto por diversos elementos, cada um representando uma parte essencial do <strong>planejamento de um projeto.<\/strong> A estrutura exata pode variar conforme a complexidade e o n\u00edvel de detalhamento desejado, mas geralmente inclui os seguintes componentes:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Gr\u00e1fico de barras com linha do tempo:<\/strong> a base do gr\u00e1fico de Gantt. Ele utiliza barras e outros s\u00edmbolos visuais para <strong>representar tarefas, prazos e interdepend\u00eancias<\/strong>, permitindo uma visualiza\u00e7\u00e3o clara da programa\u00e7\u00e3o do projeto.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Barra de tarefas (barra de Gantt):<\/strong> cada tarefa \u00e9 representada por uma barra horizontal que indica sua <strong>dura\u00e7\u00e3o no tempo.<\/strong> Al\u00e9m disso, ela pode revelar se a tarefa \u00e9 um marco, uma atividade cr\u00edtica, seu percentual de progresso, folgas entre tarefas e a compara\u00e7\u00e3o entre datas previstas e reais de in\u00edcio e fim.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Identifica\u00e7\u00e3o das tarefas:<\/strong> s\u00e3o os <strong>nomes ou descri\u00e7\u00f5es<\/strong> que explicam o que cada tarefa representa dentro do projeto.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Linha do tempo (escala temporal):<\/strong> essa parte define os<strong> intervalos utilizados no gr\u00e1fico <\/strong>\u2013 pode ser em horas, dias, semanas ou outro per\u00edodo, dependendo das necessidades do projeto.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Marcos do projeto:<\/strong> pontos-chave no cronograma que <strong>marcam eventos ou entregas significativas, <\/strong>geralmente associados \u00e0 finaliza\u00e7\u00e3o de etapas importantes.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Rela\u00e7\u00f5es de depend\u00eancia:<\/strong> indicam como as tarefas est\u00e3o conectadas entre si, ou seja, quando uma deve come\u00e7ar ou terminar em rela\u00e7\u00e3o a outra, criando uma <strong>sequ\u00eancia l\u00f3gica de execu\u00e7\u00e3o.<\/strong><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Datas espec\u00edficas:<\/strong> normalmente exibidas na parte superior do gr\u00e1fico, essas datas mostram <strong>quando cada atividade deve come\u00e7ar e terminar,<\/strong> al\u00e9m de definir o prazo total estimado do projeto.<\/li>\n<\/ul>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57538dccb5b&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57538dccb5b\" class=\"wp-block-image size-large is-resized wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" height=\"683\" width=\"1024\" src=\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2025\/07\/Consumer-Goods-Consumer-Goods-Cloud-for-Trade-Promotion-Management-Marque-Image-Version-2.webp?w=1024\" alt=\"\" class=\"wp-image-22711\" style=\"width:490px;height:auto\" srcset=\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2025\/07\/Consumer-Goods-Consumer-Goods-Cloud-for-Trade-Promotion-Management-Marque-Image-Version-2.webp 1536w, https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2025\/07\/Consumer-Goods-Consumer-Goods-Cloud-for-Trade-Promotion-Management-Marque-Image-Version-2.webp?w=300&amp;h=200 300w, https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2025\/07\/Consumer-Goods-Consumer-Goods-Cloud-for-Trade-Promotion-Management-Marque-Image-Version-2.webp?w=768&amp;h=512 768w, https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2025\/07\/Consumer-Goods-Consumer-Goods-Cloud-for-Trade-Promotion-Management-Marque-Image-Version-2.webp?w=1024&amp;h=683 1024w, https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2025\/07\/Consumer-Goods-Consumer-Goods-Cloud-for-Trade-Promotion-Management-Marque-Image-Version-2.webp?w=150&amp;h=100 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\"><em>Neste exemplo, podemos conferir os elementos b\u00e1sicos do gr\u00e1fico de Gantt, com as barras horizontais, linha do tempo e barra de tarefas. Fonte: <a href=\"https:\/\/www.salesforce.com\/consumer-goods\/cloud\/\">https:\/\/www.salesforce.com\/consumer-goods\/cloud\/<\/a><\/em><\/figcaption><\/figure>\n\n\n\n<p><strong>LEIA MAIS: <\/strong><a href=\"https:\/\/www.salesforce.com\/br\/blog\/golden-circle\/\"><strong>Golden Circle: como fazer e exemplos<\/strong><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Para que serve o Gr\u00e1fico de Gantt?<\/h2>\n\n\n\n<p>Voc\u00ea j\u00e1 entendeu que<strong> o gr\u00e1fico de Gantt \u00e9 um instrumento poderoso para garantir que os projetos avancem<\/strong> conforme o planejado e entreguem os resultados esperados, n\u00e9? Ent\u00e3o chegou o momento de conferir algumas outras funcionalidades da ferramenta. Confira abaixo:&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Organiza\u00e7\u00e3o clara das atividades do projeto<\/h3>\n\n\n\n<p>A <strong>estrutura visual e intuitiva<\/strong> de um gr\u00e1fico de Gantt torna a organiza\u00e7\u00e3o das tarefas muito mais simples. <strong>Basta inserir as atividades, definir datas de in\u00edcio e t\u00e9rmino, e posicion\u00e1-las na ordem adequada dentro do cronograma.<\/strong><\/p>\n\n\n\n<p>Com todas as tarefas reunidas em um \u00fanico ambiente visual, fica mais f\u00e1cil para as equipes entenderem o escopo do projeto, monitorar o progresso e <strong>manter uma vis\u00e3o geral clara de todas as etapas.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Visualiza\u00e7\u00e3o de depend\u00eancias entre tarefas<\/h3>\n\n\n\n<p>As depend\u00eancias representam a <strong>rela\u00e7\u00e3o entre atividades que precisam seguir uma sequ\u00eancia l\u00f3gica para que o projeto avance sem interrup\u00e7\u00f5es. <\/strong>Quando uma tarefa depende da finaliza\u00e7\u00e3o de outra, qualquer atraso pode afetar o cronograma como um todo.<\/p>\n\n\n\n<p>Por exemplo: <strong>se o projeto inclui as tarefas A, B e C, e a tarefa B s\u00f3 pode come\u00e7ar ap\u00f3s a conclus\u00e3o da A, e C apenas depois de B, ent\u00e3o existe uma cadeia de depend\u00eancias.<\/strong> Nesse sentido, o gr\u00e1fico de Gantt permite que essas rela\u00e7\u00f5es fiquem vis\u00edveis e compreens\u00edveis para todos. <strong>\u00c9 poss\u00edvel, inclusive, utilizar setas entre as tarefas para deixar essa sequ\u00eancia ainda mais clara.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Fortalecimento da colabora\u00e7\u00e3o entre membros da equipe<\/h3>\n\n\n\n<p>Al\u00e9m de ser uma <strong>ferramenta de planejamento<\/strong>, o gr\u00e1fico de Gantt tamb\u00e9m melhora o <strong>trabalho colaborativo.<\/strong> Por ser f\u00e1cil de interpretar, ele permite que todos os envolvidos compreendam suas responsabilidades e saibam como suas tarefas se conectam \u00e0s dos colegas.<\/p>\n\n\n\n<p>Ao criar e compartilhar o gr\u00e1fico por meio de uma plataforma online, as equipes conseguem acompanhar o andamento em tempo real \u2014 o que \u00e9 <strong>especialmente \u00fatil para grupos remotos ou distribu\u00eddos.<\/strong> Isso garante que todos estejam alinhados com os prazos e metas, al\u00e9m de permitir atualiza\u00e7\u00f5es cont\u00ednuas e acess\u00edveis a todos os membros do projeto.<\/p>\n\n\n\n<p><strong>LEIA MAIS: <\/strong><a href=\"https:\/\/www.salesforce.com\/br\/blog\/planejamento-de-marketing\/\"><strong>Planejamento de Marketing: o guia para criar o seu<\/strong><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como fazer um Gr\u00e1fico de Gantt do zero?<\/h2>\n\n\n\n<p>A seguir, voc\u00ea encontrar\u00e1 um <strong>processo simples para montar seu pr\u00f3prio gr\u00e1fico de Gantt.<\/strong> Coloque a metodologia em pr\u00e1tica e veja seus projetos se desenvolverem de forma muito mais natural e fluida (depois, conte para n\u00f3s se deu certo!):&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">1. Entenda o que foi proposto&nbsp;<\/h3>\n\n\n\n<p>Antes de come\u00e7ar a desenhar seu gr\u00e1fico de Gantt, \u00e9 essencial ter<strong> clareza sobre o escopo do projeto <\/strong>&#8211; ou seja, clareza sobre aquilo que foi proposto e o que se deseja alcan\u00e7ar com o desenvolvimento do projeto em quest\u00e3o.&nbsp;<\/p>\n\n\n\n<p>Isso inclui as<strong> metas principais, entregas previstas, requisitos, tarefas envolvidas, or\u00e7amento estimado e prazos. <\/strong>Essa informa\u00e7\u00e3o costuma estar em um documento formal, mas pode assumir diferentes formatos. Isso \u00e9 importante porque ter uma vis\u00e3o completa do que o projeto abrange e por que ele est\u00e1 sendo feito <strong>ajuda a incluir todas as tarefas, marcos e prazos no gr\u00e1fico de forma organizada.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2. Trabalho manual: liste todas as as tarefas no gr\u00e1fico<\/h3>\n\n\n\n<p>Depois de revisar o escopo, comece a<strong> listar as tarefas que fazem parte do projeto.<\/strong> No gr\u00e1fico de Gantt, <strong>cada tarefa \u00e9 representada por uma barra horizontal, que indica sua dura\u00e7\u00e3o.<\/strong><\/p>\n\n\n\n<p>Essas barras tamb\u00e9m podem trazer <strong>informa\u00e7\u00f5es como o respons\u00e1vel pela atividade,<\/strong> a categoria da tarefa ou at\u00e9 o tipo de trabalho (por exemplo, se \u00e9 um marco ou uma etapa cr\u00edtica). Uma boa pr\u00e1tica \u00e9 classificar as tarefas por \u00e1rea, como:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Vendas<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Marketing<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Finan\u00e7as<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Opera\u00e7\u00f5es<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Desenvolvimento<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Tecnologia da Informa\u00e7\u00e3o (TI)<\/li>\n<\/ul>\n\n\n\n<p>Dessa forma, a divis\u00e3o em \u00e1reas facilita o entendimento de <strong>quais equipes est\u00e3o envolvidas<\/strong> e suas respectivas responsabilidades, o que \u00e9 especialmente \u00fatil em projetos mais complexos ou extensos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3. Estabele\u00e7a prazos para cada atividade<\/h3>\n\n\n\n<p>Com as tarefas definidas, atribua datas de in\u00edcio e fim a cada uma. Em plataformas digitais, \u00e9 poss\u00edvel <strong>selecionar essas datas diretamente no modelo de gr\u00e1fico,<\/strong> e a barra correspondente ser\u00e1 automaticamente posicionada na linha do tempo.<\/p>\n\n\n\n<p>Caso n\u00e3o tenha certeza sobre quanto tempo uma tarefa deve durar, voc\u00ea pode seguir algumas estrat\u00e9gias para estimar:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Analise o escopo da tarefa:<\/strong> compreenda o que precisa ser feito, o n\u00edvel de dificuldade, o n\u00famero de pessoas envolvidas e o resultado esperado.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Use dados de projetos anteriores:<\/strong> veja quanto tempo tarefas similares levaram no passado.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Converse com especialistas: <\/strong>pergunte a quem entende do assunto para obter estimativas mais realistas.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">4. Compartilhe com os stakeholders e pe\u00e7a valida\u00e7\u00e3o<\/h3>\n\n\n\n<p>Depois que o cronograma estiver visualmente organizado, compartilhe-o com os principais envolvidos no projeto. Isso garante<strong> transpar\u00eancia e possibilita validar se os prazos e responsabilidades est\u00e3o adequados.<\/strong><\/p>\n\n\n\n<p>Com o cronograma aprovado, voc\u00ea pode registrar essas informa\u00e7\u00f5es no documento oficial do projeto (como o <em>project charter<\/em>), o que ajuda a manter o foco e evitar desvios que comprometam os resultados.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">5. Identifique as depend\u00eancias entre tarefas<\/h3>\n\n\n\n<p>Agora que todas as etapas est\u00e3o no gr\u00e1fico, <strong>avalie quais tarefas dependem da conclus\u00e3o de outras para serem iniciadas.<\/strong> Essas conex\u00f5es, chamadas de <strong>depend\u00eancias<\/strong>, ajudam a identificar pontos cr\u00edticos no andamento do projeto.<\/p>\n\n\n\n<p>Muitas vezes, essas rela\u00e7\u00f5es ficam evidentes ao <strong>mapear todas as atividades,<\/strong> mas, se n\u00e3o for o caso, <strong>analise quais tarefas exigem a finaliza\u00e7\u00e3o de outras.<\/strong> Use setas no gr\u00e1fico para representar essas conex\u00f5es e deixar a sequ\u00eancia l\u00f3gica clara para toda a equipe.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">6. Compartilhe o gr\u00e1fico com sua equipe<\/h3>\n\n\n\n<p>Com tudo estruturado, \u00e9 hora de envolver o time. <strong>Compartilhe o gr\u00e1fico com todos os membros da equipe para que possam revis\u00e1-lo, fazer perguntas e dar sugest\u00f5es.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">7. D\u00ea in\u00edcio ao projeto<\/h3>\n\n\n\n<p><strong>Com o gr\u00e1fico validado e todos os envolvidos alinhados, \u00e9 hora de come\u00e7ar o projeto! <\/strong>Mas o gr\u00e1fico de Gantt n\u00e3o deve ser engavetado: ele ser\u00e1 seu aliado durante toda a execu\u00e7\u00e3o. Afinal, ao longo do projeto, d\u00e1 para usar o gr\u00e1fico para <strong>acompanhar o progresso, identificar atrasos e ajustar o cronograma conforme necess\u00e1rio.<\/strong>&nbsp;<\/p>\n\n\n\n<p><strong>LEIA MAIS: <\/strong><a href=\"https:\/\/www.salesforce.com\/br\/blog\/o-que-e-benchmarking-e-como-aplicar\/\"><strong>Benchmarking: o que \u00e9, tipos e como fazer<\/strong><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">FAQ: saiba mais sobre o Gr\u00e1fico de Gantt<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">O que \u00e9 um gr\u00e1fico de Gantt e para que serve?&nbsp;<\/h3>\n\n\n\n<p>Resumidamente, o gr\u00e1fico de Gantt (tamb\u00e9m conhecido como diagrama ou chart de Gantt) \u00e9 um <strong>gr\u00e1fico de barras horizontais utilizado para representar o cronograma de um projeto e das tarefas e eventos relacionados durante o ciclo de vida do projeto. <\/strong>Ele serve para que gerentes de projetos consigam acompanhar o desenvolvimento das demandas operacionais.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">O que \u00e9 um gr\u00e1fico de Gantt?<\/h3>\n\n\n\n<p><strong>O gr\u00e1fico de Gantt \u00e9 uma ferramenta de visualiza\u00e7\u00e3o em formato de gr\u00e1fico de barras horizontais,<\/strong> feito especialmente para representar o desenvolvimento de um projeto.<strong>&nbsp;<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Qual \u00e9 o objetivo do diagrama de Gantt?<\/h3>\n\n\n\n<p>De forma geral, <strong>o principal objetivo do gr\u00e1fico ou diagrama de Gantt \u00e9 dar uma vis\u00e3o geral do projeto que est\u00e1 sendo desenvolvido por determinada equipe.&nbsp;<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Gostou de saber mais sobre o gr\u00e1fico de Gantt?&nbsp;<\/h2>\n\n\n\n<p>Nosso <a href=\"https:\/\/www.salesforce.com\/br\/blog\/\">blog<\/a> e <a href=\"https:\/\/www.salesforce.com\/br\/resources\/\">Centro de Recursos<\/a> est\u00e3o sempre atualizados, com novidades e conte\u00fados incr\u00edveis sobre <strong>CRM <\/strong>e<strong> lideran\u00e7a. <\/strong>Abaixo, sugerimos outros materiais que podem ser \u00fateis.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.salesforce.com\/br\/blog\/briefing\/\">Briefing: defini\u00e7\u00e3o, import\u00e2ncia e como fazer um<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.salesforce.com\/br\/blog\/mapa-da-empatia\/\">Mapa da Empatia: O que \u00e9 e como criar?<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.salesforce.com\/br\/blog\/icp-perfil-de-cliente-ideal\/\">Perfil de Cliente Ideal (ICP): o que \u00e9 e como definir?<\/a><\/li>\n<\/ul>\n\n\n\n<p>Aproveite para se informar sobre todas as funcionalidades do nosso <a href=\"https:\/\/www.salesforce.com\/br\/crm\/?d=70130000000i80D\"><strong>CRM<\/strong><\/a> e entenda como ele transforma a sua rotina. Bom trabalho e at\u00e9 a pr\u00f3xima!&nbsp;<\/p>\n\n\n\n<div class=\"layout-four wp-block-salesforce-blog-offer\">\n\t<div class=\"wp-block-offer__wrapper\">\n\n\t\t<div class=\"wp-block-offer__content\">\n\t\t\t<h2 class=\"wp-block-offer__title\">Intelig\u00eancia Artificial para CRM<\/h2>\n\t\t\t\t\t\t\t<p class=\"wp-block-offer__description\">Neste e-book, voc\u00ea aprender\u00e1 sobre IA, o que \u00e9 e como ela est\u00e1 transformando os neg\u00f3cios.<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t<a class=\"wp-block-button__link\" target=\"_blank\" href=\"https:\/\/www.salesforce.com\/br\/form\/pdf\/ai-for-crm\/\">Baixe e-book<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"wp-block-offer__media\">\n\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\n\t\t\t<!-- Standard Illustration -->\n\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__illustration\" src=\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-illustration-layout-four.png\" alt=\"\">\n\n\t\t<!-- Small Accent Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__accent\" src=\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-accent-layout-four.png\" alt=\"\">\n\t\t\n\t\t<!-- Left Side Illustration -->\n\t\t\n\t\t<!-- Cloud Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__cloud\" src=\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-cloud-layout-four.png\" alt=\"\">\n\t\t\n\t<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Se voc\u00ea deseja otimizar o seu gerenciamento de projetos, o gr\u00e1fico de Gantt pode ser uma ferramenta \u00fatil. A seguir, descubra mais sobre ele. Boa leitura!<\/p>\n","protected":false},"author":788,"featured_media":22703,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sf_justforyou_enable_alt":true,"optimizely_content_id":"688b730b5207a2f504ccc636","post_meta_title":"","ai_synopsis":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"sf_topic":[836,937],"sf_content_type":[],"blog":[],"coauthors":[1333],"class_list":["post-22702","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","sf_topic-small-business","sf_topic-leadership"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gr\u00e1fico de Gantt: o que \u00e9 e como criar um | Salesforce<\/title>\n<meta name=\"description\" content=\"Se voc\u00ea deseja otimizar o seu gerenciamento de projetos, o gr\u00e1fico de Gantt pode ser uma ferramenta \u00fatil. A seguir, descubra mais sobre ele. Boa leitura!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salesforce.com\/br\/blog\/grafico-de-gantt\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gr\u00e1fico de Gantt: o que \u00e9 e como criar um\" \/>\n<meta property=\"og:description\" content=\"Se voc\u00ea deseja otimizar o seu gerenciamento de projetos, o gr\u00e1fico de Gantt pode ser uma ferramenta \u00fatil. A seguir, descubra mais sobre ele. Boa leitura!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salesforce.com\/br\/blog\/grafico-de-gantt\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-31T13:51:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-08T17:27:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2025\/07\/marquee-crm-project-management.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"573\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Ana Carolina Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ana Carolina Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Ana Carolina Silva\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.salesforce.com\/br\/blog\/grafico-de-gantt\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.salesforce.com\/br\/blog\/grafico-de-gantt\/\"},\"author\":[{\"@id\":\"https:\/\/www.salesforce.com\/br\/blog\/#\/schema\/person\/image\/56b2cdf16e366adeec2e21c03952d831\"}],\"headline\":\"Gr\u00e1fico de Gantt: o que \u00e9 e como criar um\",\"datePublished\":\"2025-07-31T13:51:18+00:00\",\"dateModified\":\"2026-04-08T17:27:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.salesforce.com\/br\/blog\/grafico-de-gantt\/\"},\"wordCount\":2090,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/br\/blog\/grafico-de-gantt\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2025\/07\/marquee-crm-project-management.webp\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.salesforce.com\/br\/blog\/grafico-de-gantt\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.salesforce.com\/br\/blog\/grafico-de-gantt\/\",\"url\":\"https:\/\/www.salesforce.com\/br\/blog\/grafico-de-gantt\/\",\"name\":\"Gr\u00e1fico de Gantt: o que \u00e9 e como criar um | Salesforce\",\"isPartOf\":{\"@id\":\"https:\/\/www.salesforce.com\/br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.salesforce.com\/br\/blog\/grafico-de-gantt\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/br\/blog\/grafico-de-gantt\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2025\/07\/marquee-crm-project-management.webp\",\"datePublished\":\"2025-07-31T13:51:18+00:00\",\"dateModified\":\"2026-04-08T17:27:48+00:00\",\"author\":{\"@id\":\"https:\/\/www.salesforce.com\/br\/blog\/#\/schema\/person\/2cc20e3d4621a176669779183d03eaa7\"},\"description\":\"Se voc\u00ea deseja otimizar o seu gerenciamento de projetos, o gr\u00e1fico de Gantt pode ser uma ferramenta \u00fatil. A seguir, descubra mais sobre ele. Boa leitura!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.salesforce.com\/br\/blog\/grafico-de-gantt\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.salesforce.com\/br\/blog\/grafico-de-gantt\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.salesforce.com\/br\/blog\/grafico-de-gantt\/#primaryimage\",\"url\":\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2025\/07\/marquee-crm-project-management.webp\",\"contentUrl\":\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2025\/07\/marquee-crm-project-management.webp\",\"width\":1024,\"height\":573},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.salesforce.com\/br\/blog\/grafico-de-gantt\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.salesforce.com\/br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gr\u00e1fico de Gantt: o que \u00e9 e como criar um\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.salesforce.com\/br\/blog\/#website\",\"url\":\"https:\/\/www.salesforce.com\/br\/blog\/\",\"name\":\"Salesforce\",\"description\":\"Novidades sobre ia ag\u00eantica, dados e crm\",\"alternateName\":\"Salesforce Brasil\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.salesforce.com\/br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.salesforce.com\/br\/blog\/#\/schema\/person\/image\/56b2cdf16e366adeec2e21c03952d831\",\"name\":\"Ana Carolina Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.salesforce.com\/br\/blog\/#\/schema\/person\/image\/490df6696a75d3d390bb386a60011cdb\",\"url\":\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2025\/10\/profile-pic.jpeg?w=150&h=150&crop=1\",\"contentUrl\":\"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2025\/10\/profile-pic.jpeg?w=150&h=150&crop=1\",\"width\":\"150\",\"height\":\"150\",\"caption\":\"Ana Carolina Silva\"},\"description\":\"Sou especialista em marketing digital, com mais de 11 anos de experi\u00eancia em frentes de conte\u00fado: copywriting, m\u00eddia paga, gest\u00e3o de projetos de web e SEO. Trabalho na Salesforce Brasil com SEO e Blog, al\u00e9m de apoiar em a\u00e7\u00f5es de conte\u00fado para SMM.\",\"url\":\"https:\/\/www.salesforce.com\/br\/blog\/author\/ana-carolina-silva\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gr\u00e1fico de Gantt: o que \u00e9 e como criar um | Salesforce","description":"Se voc\u00ea deseja otimizar o seu gerenciamento de projetos, o gr\u00e1fico de Gantt pode ser uma ferramenta \u00fatil. A seguir, descubra mais sobre ele. Boa leitura!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salesforce.com\/br\/blog\/grafico-de-gantt\/","og_locale":"pt_BR","og_type":"article","og_title":"Gr\u00e1fico de Gantt: o que \u00e9 e como criar um","og_description":"Se voc\u00ea deseja otimizar o seu gerenciamento de projetos, o gr\u00e1fico de Gantt pode ser uma ferramenta \u00fatil. A seguir, descubra mais sobre ele. Boa leitura!","og_url":"https:\/\/www.salesforce.com\/br\/blog\/grafico-de-gantt\/","og_site_name":"Salesforce","article_published_time":"2025-07-31T13:51:18+00:00","article_modified_time":"2026-04-08T17:27:48+00:00","og_image":[{"width":1024,"height":573,"url":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2025\/07\/marquee-crm-project-management.webp","type":"image\/webp"}],"author":"Ana Carolina Silva","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ana Carolina Silva","Est. tempo de leitura":"11 minutos","Written by":"Ana Carolina Silva"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salesforce.com\/br\/blog\/grafico-de-gantt\/#article","isPartOf":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/grafico-de-gantt\/"},"author":[{"@id":"https:\/\/www.salesforce.com\/br\/blog\/#\/schema\/person\/image\/56b2cdf16e366adeec2e21c03952d831"}],"headline":"Gr\u00e1fico de Gantt: o que \u00e9 e como criar um","datePublished":"2025-07-31T13:51:18+00:00","dateModified":"2026-04-08T17:27:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/grafico-de-gantt\/"},"wordCount":2090,"commentCount":0,"image":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/grafico-de-gantt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2025\/07\/marquee-crm-project-management.webp","inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.salesforce.com\/br\/blog\/grafico-de-gantt\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.salesforce.com\/br\/blog\/grafico-de-gantt\/","url":"https:\/\/www.salesforce.com\/br\/blog\/grafico-de-gantt\/","name":"Gr\u00e1fico de Gantt: o que \u00e9 e como criar um | Salesforce","isPartOf":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/grafico-de-gantt\/#primaryimage"},"image":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/grafico-de-gantt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2025\/07\/marquee-crm-project-management.webp","datePublished":"2025-07-31T13:51:18+00:00","dateModified":"2026-04-08T17:27:48+00:00","author":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/#\/schema\/person\/2cc20e3d4621a176669779183d03eaa7"},"description":"Se voc\u00ea deseja otimizar o seu gerenciamento de projetos, o gr\u00e1fico de Gantt pode ser uma ferramenta \u00fatil. A seguir, descubra mais sobre ele. Boa leitura!","breadcrumb":{"@id":"https:\/\/www.salesforce.com\/br\/blog\/grafico-de-gantt\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salesforce.com\/br\/blog\/grafico-de-gantt\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.salesforce.com\/br\/blog\/grafico-de-gantt\/#primaryimage","url":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2025\/07\/marquee-crm-project-management.webp","contentUrl":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2025\/07\/marquee-crm-project-management.webp","width":1024,"height":573},{"@type":"BreadcrumbList","@id":"https:\/\/www.salesforce.com\/br\/blog\/grafico-de-gantt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salesforce.com\/br\/blog\/"},{"@type":"ListItem","position":2,"name":"Gr\u00e1fico de Gantt: o que \u00e9 e como criar um"}]},{"@type":"WebSite","@id":"https:\/\/www.salesforce.com\/br\/blog\/#website","url":"https:\/\/www.salesforce.com\/br\/blog\/","name":"Salesforce","description":"Novidades sobre ia ag\u00eantica, dados e crm","alternateName":"Salesforce Brasil","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salesforce.com\/br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.salesforce.com\/br\/blog\/#\/schema\/person\/image\/56b2cdf16e366adeec2e21c03952d831","name":"Ana Carolina Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.salesforce.com\/br\/blog\/#\/schema\/person\/image\/490df6696a75d3d390bb386a60011cdb","url":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2025\/10\/profile-pic.jpeg?w=150&h=150&crop=1","contentUrl":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2025\/10\/profile-pic.jpeg?w=150&h=150&crop=1","width":"150","height":"150","caption":"Ana Carolina Silva"},"description":"Sou especialista em marketing digital, com mais de 11 anos de experi\u00eancia em frentes de conte\u00fado: copywriting, m\u00eddia paga, gest\u00e3o de projetos de web e SEO. Trabalho na Salesforce Brasil com SEO e Blog, al\u00e9m de apoiar em a\u00e7\u00f5es de conte\u00fado para SMM.","url":"https:\/\/www.salesforce.com\/br\/blog\/author\/ana-carolina-silva\/"}]}},"jetpack_featured_media_url":"https:\/\/www.salesforce.com\/br\/blog\/wp-content\/uploads\/sites\/6\/2025\/07\/marquee-crm-project-management.webp","jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Salesforce","distributor_original_site_url":"https:\/\/www.salesforce.com\/br\/blog","push-errors":false,"_links":{"self":[{"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/posts\/22702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/users\/788"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/comments?post=22702"}],"version-history":[{"count":3,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/posts\/22702\/revisions"}],"predecessor-version":[{"id":22712,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/posts\/22702\/revisions\/22712"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/media\/22703"}],"wp:attachment":[{"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/media?parent=22702"}],"wp:term":[{"taxonomy":"sf_topic","embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/sf_topic?post=22702"},{"taxonomy":"sf_content_type","embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/sf_content_type?post=22702"},{"taxonomy":"blog","embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/blog?post=22702"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.salesforce.com\/br\/blog\/wp-json\/wp\/v2\/coauthors?post=22702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}