{"id":3115,"date":"2017-04-25T16:22:00","date_gmt":"2023-10-18T16:22:16","guid":{"rendered":"https:\/\/www.salesforce.com\/?p=3115"},"modified":"2023-11-14T20:55:00","modified_gmt":"2023-11-14T20:55:00","slug":"aspects-of-first-impression","status":"publish","type":"post","link":"https:\/\/www.salesforce.com\/ca\/blog\/aspects-of-first-impression\/","title":{"rendered":"Aspects of a First Impression Every Salesperson Needs to Know"},"content":{"rendered":"\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04d75307238&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04d75307238\" class=\"wp-block-image wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/www.salesforce.com\/ca\/blog\/wp-content\/uploads\/sites\/12\/2023\/10\/Aspects-of-a-First-Impression-Every-Salesperson-Needs-to-Know-header.png?strip=all&#038;quality=95\" alt=\"\"\/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p>In business, first impressions can be the difference between closing a sale and walking away empty-handed. Within the initial few seconds of meeting a new person, we decide if we like them \u2014 and that first impression stays with us. In an act called thin-slicing, we take a mental snapshot of someone and guess their competence, confidence, and likeability, and that opinion often doesn\u2019t change.<\/p>\n\n\n\n<p>This means you have to decide how you want to be perceived. What\u2019s one word you want people to associate with you? Be introspective: Ask yourself how you come across to others and the kinds of interactions you want to have with people. Work on your soft skills. Improve your ability to communicate effectively, your attitude, and your ability to relax and be yourself. But don\u2019t stop there: Take into account your appearance, and use it to project an appropriate personal image. Stand in a confident position, make eye contact, and ensure your handshake is ready to close deals. With these tips and others found in the infographic below, every salesperson will make the right kind of first impression.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><a href=\"https:\/\/www.salesforce.com\/ca\/form\/blog\/sell-faster-smarter.jsp?d=7010M000002MONe\"><img decoding=\"async\" src=\"https:\/\/www.salesforce.com\/ca\/blog\/wp-content\/uploads\/sites\/12\/2023\/10\/transform-sales-process-cta.png?strip=all&#038;quality=95\" alt=\"4 steps to transforming your sales process.\"\/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-your-first-impression-matters\"><b>Your First Impression Matters <\/b> <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Studies have found that within the first few seconds of meeting someone:\n<ul class=\"wp-block-list\">\n<li>We decide if we like them<\/li>\n\n\n\n<li>That first impression stays with us<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>A good first impression is important\u2014you only get one chance<\/li>\n\n\n\n<li><b>Thin-slicing<\/b>\n<ul class=\"wp-block-list\">\n<li>Thin-slicing is when our opinion of someone doesn\u2019t change<\/li>\n\n\n\n<li>We take a mental snapshot and in a matter of seconds guess someone\u2019s:\n<ul class=\"wp-block-list\">\n<li>Competence<\/li>\n\n\n\n<li>Confidence <\/li>\n\n\n\n<li>Likability <\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Researchers think this may be a survival mechanism we developed to quickly decide if someone is friend or foe<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p><b>Decide How You Want to be Perceived<\/b><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Before a networking or business event, consider the following:\n<ul class=\"wp-block-list\">\n<li>What do people think when they first meet you?\n<ul class=\"wp-block-list\">\n<li>I am _____.\n<ul class=\"wp-block-list\">\n<li>Choose one word from this list or name your own:\n<ul class=\"wp-block-list\">\n<li>Kind<\/li>\n\n\n\n<li>Charismatic<\/li>\n\n\n\n<li>Intelligent<\/li>\n\n\n\n<li>Witty<\/li>\n\n\n\n<li>Fun<\/li>\n\n\n\n<li>Powerful<\/li>\n\n\n\n<li>Engaging<\/li>\n\n\n\n<li>Wise<\/li>\n\n\n\n<li>Professional<\/li>\n\n\n\n<li>_____ <\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Ask yourself\n<ul class=\"wp-block-list\">\n<li>\u201cIs my first impression all positive?\u201d<\/li>\n\n\n\n<li>\u201cDo I come across as negative?\u201d<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Know where you stand in order to move to where you want to be.<\/li>\n\n\n\n<li>The most important thing to do to give a good impression is to set your intention: \u201cI want to be _____.\u201d\n<ul class=\"wp-block-list\">\n<li>This is especially important before events where you will meet a lot of people, such as at\n<ul class=\"wp-block-list\">\n<li>Conferences<\/li>\n\n\n\n<li>Networking events<\/li>\n\n\n\n<li>Social events<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>While you get ready for an event, think about:\n<ul class=\"wp-block-list\">\n<li>The people you want to meet <\/li>\n\n\n\n<li>What kind of interactions you want to have<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p><b>10 Ways to Make a Strong First Impression<\/b><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><b>1. Communication<\/b>\n<ul class=\"wp-block-list\">\n<li>Aristotle broke down the process of communication into three parts\n<ul class=\"wp-block-list\">\n<li><b>Ethos <\/b>\u2013 Credibility\n<ul class=\"wp-block-list\">\n<li>The reason people should <b>believe you<\/b><\/li>\n\n\n\n<li>Revolves around the person you are and the person you are perceived to be<\/li>\n\n\n\n<li>Demonstrate Ethos:\n<ul class=\"wp-block-list\">\n<li>Rank within your organization<\/li>\n\n\n\n<li>Expertise<\/li>\n\n\n\n<li>Displaying strong levels of integrity and character<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><b>Pathos <\/b>\u2013 Emotional connection\n<ul class=\"wp-block-list\">\n<li>Why people should <b>believe what you\u2019re saying will matter to them<\/b><\/li>\n\n\n\n<li>Demonstrate Pathos\n<ul class=\"wp-block-list\">\n<li>Give people your undivided attention<\/li>\n\n\n\n<li>Take an active interest in team members\u2019 career development<\/li>\n\n\n\n<li>Be enthusiastic about your organization\u2019s progress and the individuals who enable it <\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><b>Logos <\/b>\u2014 Logic\n<ul class=\"wp-block-list\">\n<li>Appeal to <b>people\u2019s sense of reason<\/b>\n<ul class=\"wp-block-list\">\n<li>Demonstrate Logos<\/li>\n\n\n\n<li>Employing strategic thinking, problem solving, and analytical skills <\/li>\n\n\n\n<li>Have clear, concise, and logical arguments that provide substance to the your message<\/li>\n\n\n\n<li>Your arguments should be supported by:<\/li>\n\n\n\n<li>Facts<\/li>\n\n\n\n<li>Statistics<\/li>\n\n\n\n<li>Studies<\/li>\n\n\n\n<li>Examples<\/li>\n\n\n\n<li>History<\/li>\n\n\n\n<li>Evidence<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><b>2. Attitude<\/b>\n<ul class=\"wp-block-list\">\n<li>People pick up on attitude instantly<\/li>\n\n\n\n<li>Before greeting someone:\n<ul class=\"wp-block-list\">\n<li>Think about the situation <\/li>\n\n\n\n<li>Make a choice about the attitude you want to personify<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Smile when first meeting someone\n<ul class=\"wp-block-list\">\n<li>A smile says \u2018I\u2019m friendly and approachable\u201d<\/li>\n\n\n\n<li>Data suggests that smiling boosts your mood<\/li>\n\n\n\n<li>When you get a customer in a positive mindset, selling is easier<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Focus on that person and give them your full attention<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><b>3. Appearance<\/b>\n<ul class=\"wp-block-list\">\n<li>Use your appearance to project an appropriate personal image<\/li>\n\n\n\n<li>Look the part when you meet with clients\n<ul class=\"wp-block-list\">\n<li>You want your customers to take you seriously<\/li>\n\n\n\n<li>Your appearance is also a way to show them respect<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>When customers first look at you, they subconsciously make decisions:\n<ul class=\"wp-block-list\">\n<li>Is this someone I can trust?<\/li>\n\n\n\n<li>Does this person seem responsible?<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><b>4. Handshake<\/b>\n<ul class=\"wp-block-list\">\n<li>Occurs at the beginning of business transactions or meetings<\/li>\n\n\n\n<li>A handshake can show that you\u2019re:\n<ul class=\"wp-block-list\">\n<li>Emotionally stable<\/li>\n\n\n\n<li>Agreeable <\/li>\n\n\n\n<li>Respectful of the person you\u2019re meeting <\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Palm direction\n<ul class=\"wp-block-list\">\n<li>Palm extended up conveys submissiveness<\/li>\n\n\n\n<li>Palm extended vertically indicates you\u2019re equal to the person you\u2019re meeting<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Handshake firmness\n<ul class=\"wp-block-list\">\n<li>\u201cDead fish\u201d shake implies weakness<\/li>\n\n\n\n<li>\u201cDeath grip\u201d shake will turn people off<\/li>\n\n\n\n<li>Practice handshake firmness with a coworker to hit a firmness sweet spot<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><b>5. Posture and Stance<\/b>\n<ul class=\"wp-block-list\">\n<li>Stand in launch position:\n<ul class=\"wp-block-list\">\n<li>Arms hanging loosely at side <\/li>\n\n\n\n<li>Opened torso <\/li>\n\n\n\n<li>Shoulders down<\/li>\n\n\n\n<li>Head up <\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Launch stance demonstrates that you\u2019re in confident and in control of your space <\/li>\n\n\n\n<li>Lean in slightly\n<ul class=\"wp-block-list\">\n<li>Leaning forward shows you\u2019re engaged and interested<\/li>\n\n\n\n<li>Stay about two feet away to be respectful of their personal space <\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Straighten your posture<\/li>\n\n\n\n<li>Status and power are nonverbally conveyed by height and space<\/li>\n\n\n\n<li>To convey confidence and competence\n<ul class=\"wp-block-list\">\n<li>Stand tall<\/li>\n\n\n\n<li>Pull back shoulders <\/li>\n\n\n\n<li>Hold head straight <\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><b>6. Eyes<\/b>\n<ul class=\"wp-block-list\">\n<li>Make eye contact\n<ul class=\"wp-block-list\">\n<li>Transmits energy <\/li>\n\n\n\n<li>Indicates interest and openness<\/li>\n\n\n\n<li><b>To improve your eye contact:<\/b> Try to notice the eye color of everyone you meet<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Raise eyebrows\n<ul class=\"wp-block-list\">\n<li>Open your eyes slightly more than normal\n<ul class=\"wp-block-list\">\n<li>This simulates the \u201ceyebrow flash,\u201d the universal signal of recognition and acknowledgement<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><b>7. Relax and be yourself<\/b>\n<ul class=\"wp-block-list\">\n<li>You are good enough<\/li>\n\n\n\n<li>Take a few deep breaths and relax <\/li>\n\n\n\n<li>See what you can do to make the other person comfortable\n<ul class=\"wp-block-list\">\n<li>When they&#8217;re comfortable, you\u2019ll be more comfortable<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p><b>Conclusion<\/b><\/p>\n\n\n\n<p>Working on and improving your first impression can help accelerate your career and broaden your professional network. Try implementing some of these tips at the next business meeting or social event you attend.<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04d7530bede&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04d7530bede\" class=\"wp-block-image wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/www.salesforce.com\/ca\/blog\/wp-content\/uploads\/sites\/12\/2023\/10\/Aspects-of-a-First-Impression-Every-Salesperson-Needs-to-Know-003.png?strip=all&#038;quality=95\" alt=\"\"\/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p><i>Take your sales game to the next level with the tips in our free ebook, \u201c4 Steps to Transforming Your Sales Process.\u201d<\/i><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter is-style-default\"><a href=\"https:\/\/www.salesforce.com\/ca\/form\/blog\/sell-faster-smarter.jsp?d=7010M000002MONe\"><img decoding=\"async\" src=\"https:\/\/www.salesforce.com\/ca\/blog\/wp-content\/uploads\/sites\/12\/2023\/10\/transform-sales-process-cta.png?strip=all&#038;quality=95\" alt=\"4 steps to transforming your sales process.\"\/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-share-aspects-of-a-first-impression-every-salesperson-needs-to-know-on-your-site\">Share &#8220;Aspects of a First Impression Every Salesperson Needs to Know&#8221; On Your Site<span id=\"authorRoot\" path=\"\/content\/blogs\/ca\/en\/authors\/\"><\/span><\/h3>\n\n\n\n<textarea style=\"height:100%;width:100%\" rows=6>\n&lt;p&gt;&lt;strong&gt;Click To Enlarge&lt;\/strong&gt;&lt;br \/&gt;&lt;br \/&gt; &lt;a href=&quot;https:\/\/www.salesforce.com\/ca\/blog\/2017\/04\/aspects-of-first-impression.html&quot; _rte_href=&quot;https:\/\/www.salesforce.com\/ca\/blog\/2017\/04\/aspects-of-first-impression.html&quot; target=&quot;_blank&quot;&gt; &lt;img src=&quot;https:\/\/www.salesforce.com\/content\/dam\/blogs\/ca\/Blog%20Posts\/Aspects-of-a-First-Impression-Every-Salesperson-Needs-to-Know-003.png&quot; _rte_src=&quot;https:\/\/www.salesforce.com\/content\/dam\/blogs\/ca\/Blog%20Posts\/Aspects-of-a-First-Impression-Every-Salesperson-Needs-to-Know-003.png&quot; alt=&quot;Aspects of a First Impression Every Salesperson Needs to Know&quot; width=&quot;600px&quot; border=&quot;0&quot; \/&gt; &lt;\/a&gt; &lt;\/p&gt; &lt;p&gt;Via &lt;a href=&quot;https:\/\/www.salesforce.com\/ca\/&quot; _rte_href=&quot;https:\/\/www.salesforce.com\/ca\/&quot; target=&quot;_blank&quot;&gt;Salesforce&lt;\/a&gt; &lt;\/p&gt; \n<\/textarea>\n","protected":false},"excerpt":{"rendered":"<p>In business, first impressions can be the difference between closing a sale and walking away empty-handed.<\/p>\n","protected":false},"author":1,"featured_media":3117,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sf_justforyou_enable_alt":true,"optimizely_content_id":"","post_meta_title":"","ai_synopsis":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"sf_topic":[4],"sf_content_type":[],"coauthors":[2],"class_list":["post-3115","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","sf_topic-sales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Aspects of a First Impression Every Salesperson Needs to Know - Salesforce<\/title>\n<meta name=\"description\" content=\"In business, first impressions can be the difference between closing a sale and walking away empty-handed.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salesforce.com\/ca\/blog\/aspects-of-first-impression\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aspects of a First Impression Every Salesperson Needs to Know\" \/>\n<meta property=\"og:description\" content=\"In business, first impressions can be the difference between closing a sale and walking away empty-handed.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salesforce.com\/ca\/blog\/aspects-of-first-impression\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-18T16:22:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-14T20:55:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salesforce.com\/ca\/blog\/wp-content\/uploads\/sites\/12\/2023\/10\/Aspects-of-a-First-Impression-Every-Salesperson-Needs-to-Know-opengraph.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Salesforce Canada\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Salesforce Canada\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.salesforce.com\/ca\/blog\/aspects-of-first-impression\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.salesforce.com\/ca\/blog\/aspects-of-first-impression\/\"},\"author\":[{\"@id\":\"https:\/\/www.salesforce.com\/ca\/blog\/#\/schema\/person\/image\/67746feea2d6a73653ce0c10f94077a5\"}],\"headline\":\"Aspects of a First Impression Every Salesperson Needs to Know\",\"datePublished\":\"2023-10-18T16:22:16+00:00\",\"dateModified\":\"2023-11-14T20:55:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.salesforce.com\/ca\/blog\/aspects-of-first-impression\/\"},\"wordCount\":1133,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/ca\/blog\/aspects-of-first-impression\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.salesforce.com\/ca\/blog\/wp-content\/uploads\/sites\/12\/2023\/10\/Aspects-of-a-First-Impression-Every-Salesperson-Needs-to-Know-opengraph.png\",\"inLanguage\":\"en-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.salesforce.com\/ca\/blog\/aspects-of-first-impression\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.salesforce.com\/ca\/blog\/aspects-of-first-impression\/\",\"url\":\"https:\/\/www.salesforce.com\/ca\/blog\/aspects-of-first-impression\/\",\"name\":\"Aspects of a First Impression Every Salesperson Needs to Know - Salesforce\",\"isPartOf\":{\"@id\":\"https:\/\/www.salesforce.com\/ca\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.salesforce.com\/ca\/blog\/aspects-of-first-impression\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/ca\/blog\/aspects-of-first-impression\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.salesforce.com\/ca\/blog\/wp-content\/uploads\/sites\/12\/2023\/10\/Aspects-of-a-First-Impression-Every-Salesperson-Needs-to-Know-opengraph.png\",\"datePublished\":\"2023-10-18T16:22:16+00:00\",\"dateModified\":\"2023-11-14T20:55:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.salesforce.com\/ca\/blog\/#\/schema\/person\/601f410a2801f4ddcf6f00cb182e69d3\"},\"description\":\"In business, first impressions can be the difference between closing a sale and walking away empty-handed.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.salesforce.com\/ca\/blog\/aspects-of-first-impression\/#breadcrumb\"},\"inLanguage\":\"en-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.salesforce.com\/ca\/blog\/aspects-of-first-impression\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\/\/www.salesforce.com\/ca\/blog\/aspects-of-first-impression\/#primaryimage\",\"url\":\"https:\/\/www.salesforce.com\/ca\/blog\/wp-content\/uploads\/sites\/12\/2023\/10\/Aspects-of-a-First-Impression-Every-Salesperson-Needs-to-Know-opengraph.png\",\"contentUrl\":\"https:\/\/www.salesforce.com\/ca\/blog\/wp-content\/uploads\/sites\/12\/2023\/10\/Aspects-of-a-First-Impression-Every-Salesperson-Needs-to-Know-opengraph.png\",\"width\":1200,\"height\":627,\"caption\":\"Aspects of a First Impression Every Salesperson Needs to Know\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.salesforce.com\/ca\/blog\/aspects-of-first-impression\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.salesforce.com\/ca\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aspects of a First Impression Every Salesperson Needs to Know\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.salesforce.com\/ca\/blog\/#website\",\"url\":\"https:\/\/www.salesforce.com\/ca\/blog\/\",\"name\":\"Salesforce\",\"description\":\"News, tips, and insights from the global cloud leader\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.salesforce.com\/ca\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CA\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.salesforce.com\/ca\/blog\/#\/schema\/person\/image\/67746feea2d6a73653ce0c10f94077a5\",\"name\":\"Salesforce Canada\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\/\/www.salesforce.com\/ca\/blog\/#\/schema\/person\/image\/c206078faacfae202082d59bddc16cc4\",\"url\":\"https:\/\/www.salesforce.com\/ca\/blog\/wp-content\/uploads\/sites\/12\/2023\/11\/Salesforce-300x300-1.png?w=150&h=150&crop=1\",\"contentUrl\":\"https:\/\/www.salesforce.com\/ca\/blog\/wp-content\/uploads\/sites\/12\/2023\/11\/Salesforce-300x300-1.png?w=150&h=150&crop=1\",\"width\":\"150\",\"height\":\"150\",\"caption\":\"Salesforce Canada\"},\"url\":\"https:\/\/www.salesforce.com\/ca\/blog\/author\/salesforce-canada\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Aspects of a First Impression Every Salesperson Needs to Know - Salesforce","description":"In business, first impressions can be the difference between closing a sale and walking away empty-handed.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salesforce.com\/ca\/blog\/aspects-of-first-impression\/","og_locale":"en_US","og_type":"article","og_title":"Aspects of a First Impression Every Salesperson Needs to Know","og_description":"In business, first impressions can be the difference between closing a sale and walking away empty-handed.","og_url":"https:\/\/www.salesforce.com\/ca\/blog\/aspects-of-first-impression\/","og_site_name":"Salesforce","article_published_time":"2023-10-18T16:22:16+00:00","article_modified_time":"2023-11-14T20:55:00+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/www.salesforce.com\/ca\/blog\/wp-content\/uploads\/sites\/12\/2023\/10\/Aspects-of-a-First-Impression-Every-Salesperson-Needs-to-Know-opengraph.png","type":"image\/png"}],"author":"Salesforce Canada","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Salesforce Canada","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salesforce.com\/ca\/blog\/aspects-of-first-impression\/#article","isPartOf":{"@id":"https:\/\/www.salesforce.com\/ca\/blog\/aspects-of-first-impression\/"},"author":[{"@id":"https:\/\/www.salesforce.com\/ca\/blog\/#\/schema\/person\/image\/67746feea2d6a73653ce0c10f94077a5"}],"headline":"Aspects of a First Impression Every Salesperson Needs to Know","datePublished":"2023-10-18T16:22:16+00:00","dateModified":"2023-11-14T20:55:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salesforce.com\/ca\/blog\/aspects-of-first-impression\/"},"wordCount":1133,"commentCount":0,"image":{"@id":"https:\/\/www.salesforce.com\/ca\/blog\/aspects-of-first-impression\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/ca\/blog\/wp-content\/uploads\/sites\/12\/2023\/10\/Aspects-of-a-First-Impression-Every-Salesperson-Needs-to-Know-opengraph.png","inLanguage":"en-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.salesforce.com\/ca\/blog\/aspects-of-first-impression\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.salesforce.com\/ca\/blog\/aspects-of-first-impression\/","url":"https:\/\/www.salesforce.com\/ca\/blog\/aspects-of-first-impression\/","name":"Aspects of a First Impression Every Salesperson Needs to Know - Salesforce","isPartOf":{"@id":"https:\/\/www.salesforce.com\/ca\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salesforce.com\/ca\/blog\/aspects-of-first-impression\/#primaryimage"},"image":{"@id":"https:\/\/www.salesforce.com\/ca\/blog\/aspects-of-first-impression\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/ca\/blog\/wp-content\/uploads\/sites\/12\/2023\/10\/Aspects-of-a-First-Impression-Every-Salesperson-Needs-to-Know-opengraph.png","datePublished":"2023-10-18T16:22:16+00:00","dateModified":"2023-11-14T20:55:00+00:00","author":{"@id":"https:\/\/www.salesforce.com\/ca\/blog\/#\/schema\/person\/601f410a2801f4ddcf6f00cb182e69d3"},"description":"In business, first impressions can be the difference between closing a sale and walking away empty-handed.","breadcrumb":{"@id":"https:\/\/www.salesforce.com\/ca\/blog\/aspects-of-first-impression\/#breadcrumb"},"inLanguage":"en-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salesforce.com\/ca\/blog\/aspects-of-first-impression\/"]}]},{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/www.salesforce.com\/ca\/blog\/aspects-of-first-impression\/#primaryimage","url":"https:\/\/www.salesforce.com\/ca\/blog\/wp-content\/uploads\/sites\/12\/2023\/10\/Aspects-of-a-First-Impression-Every-Salesperson-Needs-to-Know-opengraph.png","contentUrl":"https:\/\/www.salesforce.com\/ca\/blog\/wp-content\/uploads\/sites\/12\/2023\/10\/Aspects-of-a-First-Impression-Every-Salesperson-Needs-to-Know-opengraph.png","width":1200,"height":627,"caption":"Aspects of a First Impression Every Salesperson Needs to Know"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salesforce.com\/ca\/blog\/aspects-of-first-impression\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salesforce.com\/ca\/blog\/"},{"@type":"ListItem","position":2,"name":"Aspects of a First Impression Every Salesperson Needs to Know"}]},{"@type":"WebSite","@id":"https:\/\/www.salesforce.com\/ca\/blog\/#website","url":"https:\/\/www.salesforce.com\/ca\/blog\/","name":"Salesforce","description":"News, tips, and insights from the global cloud leader","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salesforce.com\/ca\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"},{"@type":"Person","@id":"https:\/\/www.salesforce.com\/ca\/blog\/#\/schema\/person\/image\/67746feea2d6a73653ce0c10f94077a5","name":"Salesforce Canada","image":{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/www.salesforce.com\/ca\/blog\/#\/schema\/person\/image\/c206078faacfae202082d59bddc16cc4","url":"https:\/\/www.salesforce.com\/ca\/blog\/wp-content\/uploads\/sites\/12\/2023\/11\/Salesforce-300x300-1.png?w=150&h=150&crop=1","contentUrl":"https:\/\/www.salesforce.com\/ca\/blog\/wp-content\/uploads\/sites\/12\/2023\/11\/Salesforce-300x300-1.png?w=150&h=150&crop=1","width":"150","height":"150","caption":"Salesforce Canada"},"url":"https:\/\/www.salesforce.com\/ca\/blog\/author\/salesforce-canada\/"}]}},"jetpack_featured_media_url":"https:\/\/www.salesforce.com\/ca\/blog\/wp-content\/uploads\/sites\/12\/2023\/10\/Aspects-of-a-First-Impression-Every-Salesperson-Needs-to-Know-opengraph.png","jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Salesforce","distributor_original_site_url":"https:\/\/www.salesforce.com\/ca\/blog","push-errors":false,"_links":{"self":[{"href":"https:\/\/www.salesforce.com\/ca\/blog\/wp-json\/wp\/v2\/posts\/3115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salesforce.com\/ca\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salesforce.com\/ca\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/ca\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/ca\/blog\/wp-json\/wp\/v2\/comments?post=3115"}],"version-history":[{"count":7,"href":"https:\/\/www.salesforce.com\/ca\/blog\/wp-json\/wp\/v2\/posts\/3115\/revisions"}],"predecessor-version":[{"id":7053,"href":"https:\/\/www.salesforce.com\/ca\/blog\/wp-json\/wp\/v2\/posts\/3115\/revisions\/7053"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/ca\/blog\/wp-json\/wp\/v2\/media\/3117"}],"wp:attachment":[{"href":"https:\/\/www.salesforce.com\/ca\/blog\/wp-json\/wp\/v2\/media?parent=3115"}],"wp:term":[{"taxonomy":"sf_topic","embeddable":true,"href":"https:\/\/www.salesforce.com\/ca\/blog\/wp-json\/wp\/v2\/sf_topic?post=3115"},{"taxonomy":"sf_content_type","embeddable":true,"href":"https:\/\/www.salesforce.com\/ca\/blog\/wp-json\/wp\/v2\/sf_content_type?post=3115"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.salesforce.com\/ca\/blog\/wp-json\/wp\/v2\/coauthors?post=3115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}