{"id":96,"count":3,"description":"","link":"https:\/\/www.salesforce.com\/ca\/blog\/category\/b2b-marketing\/","name":"B2B Marketing","slug":"b2b-marketing","taxonomy":"sf_topic","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>B2B Marketing Archives - Salesforce<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salesforce.com\/ca\/blog\/category\/b2b-marketing\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"B2B Marketing Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salesforce.com\/ca\/blog\/category\/b2b-marketing\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/ca\\\/blog\\\/category\\\/b2b-marketing\\\/\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/ca\\\/blog\\\/category\\\/b2b-marketing\\\/\",\"name\":\"B2B Marketing Archives - Salesforce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/ca\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/ca\\\/blog\\\/category\\\/b2b-marketing\\\/#breadcrumb\"},\"inLanguage\":\"en-CA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/ca\\\/blog\\\/category\\\/b2b-marketing\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.salesforce.com\\\/ca\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"B2b Marketing\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/ca\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/ca\\\/blog\\\/\",\"name\":\"Salesforce\",\"description\":\"News, tips, and insights from the global cloud leader\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salesforce.com\\\/ca\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CA\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"B2B Marketing Archives - Salesforce","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salesforce.com\/ca\/blog\/category\/b2b-marketing\/","og_locale":"en_US","og_type":"article","og_title":"B2B Marketing Archives","og_url":"https:\/\/www.salesforce.com\/ca\/blog\/category\/b2b-marketing\/","og_site_name":"Salesforce","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.salesforce.com\/ca\/blog\/category\/b2b-marketing\/","url":"https:\/\/www.salesforce.com\/ca\/blog\/category\/b2b-marketing\/","name":"B2B Marketing Archives - Salesforce","isPartOf":{"@id":"https:\/\/www.salesforce.com\/ca\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.salesforce.com\/ca\/blog\/category\/b2b-marketing\/#breadcrumb"},"inLanguage":"en-CA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salesforce.com\/ca\/blog\/category\/b2b-marketing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salesforce.com\/ca\/blog\/"},{"@type":"ListItem","position":2,"name":"B2b Marketing"}]},{"@type":"WebSite","@id":"https:\/\/www.salesforce.com\/ca\/blog\/#website","url":"https:\/\/www.salesforce.com\/ca\/blog\/","name":"Salesforce","description":"News, tips, and insights from the global cloud leader","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salesforce.com\/ca\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"}]}},"_links":{"self":[{"href":"https:\/\/www.salesforce.com\/ca\/blog\/wp-json\/wp\/v2\/sf_topic\/96","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salesforce.com\/ca\/blog\/wp-json\/wp\/v2\/sf_topic"}],"about":[{"href":"https:\/\/www.salesforce.com\/ca\/blog\/wp-json\/wp\/v2\/taxonomies\/sf_topic"}],"wp:post_type":[{"href":"https:\/\/www.salesforce.com\/ca\/blog\/wp-json\/wp\/v2\/media?sf_topic=96"},{"href":"https:\/\/www.salesforce.com\/ca\/blog\/wp-json\/wp\/v2\/posts?sf_topic=96"},{"href":"https:\/\/www.salesforce.com\/ca\/blog\/wp-json\/wp\/v2\/pages?sf_topic=96"},{"href":"https:\/\/www.salesforce.com\/ca\/blog\/wp-json\/wp\/v2\/sf_linked_content?sf_topic=96"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}