{"id":10856,"date":"2024-08-20T15:16:56","date_gmt":"2024-08-20T15:16:56","guid":{"rendered":"https:\/\/www.salesforce.com\/?p=10856"},"modified":"2024-10-30T08:51:09","modified_gmt":"2024-10-30T08:51:09","slug":"business-analyse","status":"publish","type":"post","link":"https:\/\/www.salesforce.com\/de\/blog\/business-analyse\/","title":{"rendered":"Navigieren im Datenmeer: Wie Business Analyse Ihr Unternehmen lenken kann"},"content":{"rendered":"\n<p><strong>Ihr Unternehmen ben\u00f6tigt eine gute Business Analyse. Aber warum eigentlich? Wir werfen einen Blick auf die Vorteile und Schwerpunkte. Erfahren Sie, wie Unternehmen Datenanalysen durchf\u00fchren, um fundierte Entscheidungen zu treffen und ihr Gesch\u00e4ft voranzutreiben. Wir verraten Ihnen au\u00dferdem, wie KI Ihre Business Analyse noch effektiver macht!<\/strong><\/p>\n\n\n\n<p><strong>Inhalt:&nbsp;<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"#topic1\">Was ist Business Analyse? Eine Definition<\/a><\/li>\n\n\n\n<li><a href=\"#topic2\">Vorteile von Business Analyse f\u00fcr Ihr Unternehmen<\/a><\/li>\n\n\n\n<li><a href=\"#topic3\">4 Arten und Schwerpunkte der Unternehmensanalyse<\/a><\/li>\n\n\n\n<li><a href=\"#topic4\">Als Unternehmen mit der Business Analyse starten \u2013 9 Schritte<\/a><\/li>\n\n\n\n<li><a href=\"#topic5\">Welche Herausforderungen begegnen Business Analyst:innen?<\/a><\/li>\n\n\n\n<li><a href=\"#topic6\">H\u00f6her, schneller, weiter \u2013 Die Rolle von KI in der Business Analyse<\/a><\/li>\n\n\n\n<li><a href=\"#topic7\">KI und Business Analyse: Beispiel aus der Praxis<\/a><\/li>\n\n\n\n<li><a href=\"#topic8\">Fazit: So ziehen Sie den gr\u00f6\u00dften Nutzen aus der Business Analyse<\/a><\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-columns has-background is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\" style=\"background-color:#eaf5fe\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\" id=\"topic1\"><strong>Was ist Business Analyse? Eine Definition<\/strong><\/h2>\n\n\n\n<p>Jedes Unternehmen, ob gro\u00df oder klein, generiert Daten. Doch was passiert mit den Informationen zu Gesch\u00e4ftsprozessen, <a href=\"https:\/\/www.salesforce.com\/de\/learning-centre\/customer-service\/measure-customer-satisfaction\/\">Kundenzufriedenheit<\/a> und Co.? Hier setzt die Praxis der Business Analyse an, mit der <a href=\"https:\/\/www.salesforce.com\/de\/data\/was-sind-daten\/\">Daten<\/a> und Prozesse innerhalb eines Unternehmens untersucht werden, um gesch\u00e4ftliche Entscheidungen zu unterst\u00fctzen. Der Hauptzweck der Business Analyse besteht darin, <strong>Probleme zu identifizieren, Anforderungen zu erfassen und L\u00f6sungen zu entwickeln, die zur Wertsteigerung des Unternehmens beitragen.<\/strong><\/p>\n\n\n\n<p>Zu den wichtigsten <strong>Schl\u00fcsselelemente der Business Analyse <\/strong>z\u00e4hlen:<\/p>\n\n\n\n<p><strong>Umsetzungsunterst\u00fctzung:<\/strong> Nach der L\u00f6sungsentwicklung unterst\u00fctzen Business Analyst:innen oft die Implementierung der L\u00f6sung, \u00fcberwachen deren Fortschritte und bewerten die Auswirkungen auf das Gesch\u00e4ft.<\/p>\n\n\n\n<p><strong>Problemidentifikation:<\/strong> Business Analyst:innen beginnen typischerweise mit der Identifizierung und Definition der Probleme oder Herausforderungen, denen ein Unternehmen gegen\u00fcbersteht. Dies kann von interner Prozesseffizienz bis hin zu externen Marktchancen reichen.<\/p>\n\n\n\n<p><strong>Anforderungserfassung<\/strong>: Ein zentraler Teil der Business Analyse ist das Sammeln und Dokumentieren von Gesch\u00e4ftsanforderungen von Stakeholdern. Diese Anforderungen k\u00f6nnen sich auf neue Systeme, Prozessverbesserungen oder strategische Ver\u00e4nderungen beziehen.<\/p>\n\n\n\n<p><strong>L\u00f6sungsentwicklung:<\/strong> Basierend auf den gesammelten Daten und Anforderungen entwickeln Business Analyst:innen L\u00f6sungen oder Empfehlungen. Dies kann die Implementierung neuer Technologien, die \u00c4nderung von Gesch\u00e4ftsprozessen oder strategische Anpassungen beinhalten.<\/p>\n\n\n\n<p><strong>Datenanalyse:<\/strong> Ein wesentlicher Bestandteil der Business Analyse ist die Untersuchung von Daten durch statistische Analysen, Prognosemodellierung und andere quantitative Techniken. Sie werden genutzt, um Muster und Trends zu erkennen, die fundierte Entscheidungen unterst\u00fctzen.<\/p>\n\n\n\n<p><strong>Stakeholder-Kommunikation:<\/strong> Business Analyst:innen m\u00fcssen effektiv mit verschiedenen Stakeholdern kommunizieren, von technischen Teams bis hin zu F\u00fchrungskr\u00e4ften, um sicherzustellen, dass die entwickelten L\u00f6sungen die Gesch\u00e4ftsziele erf\u00fcllen.<\/p>\n<\/div>\n<\/div>\n\n\n\n<p><strong>Die Rolle der Business Analyse ist vielseitig<\/strong> und kann in verschiedenen Branchen und bei unterschiedlichsten Projekttypen zum Einsatz kommen. Erfolg als Business Analyst:in erfordert sowohl technische F\u00e4higkeiten in der Datenanalyse als auch starke zwischenmenschliche F\u00e4higkeiten zur Kommunikation und Probleml\u00f6sung. Die Gesch\u00e4ftsanalytik dient dazu, Unternehmen dabei zu unterst\u00fctzen, <strong>bessere Entscheidungen zu treffen, Chancen und Trends zu erkennen, die Kundenbindung zu verbessern, Kosten zu senken und insgesamt die Leistung zu optimieren<\/strong>.<br><\/p>\n\n\n\n<div class=\"wp-block-columns has-background is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\" style=\"background-color:#f3f3f3\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\" id=\"h-business-analyse-beispiel-sonnen-gruppe-nbsp\"><strong>Business-Analyse-Beispiel: sonnen Gruppe&nbsp;<\/strong><\/h2>\n\n\n\n<p><strong>Wie wird Business Analyse in der Praxis umgesetzt? <\/strong>Die <a href=\"https:\/\/www.tableau.com\/de-de\/solutions\/customer\/sonnen-ermoeglicht-transparenz-im-finanzreporting\">sonnen Gruppe<\/a>, ein f\u00fchrender Hersteller von Stromspeichern und Anbieter von Energiedienstleistungen, nutzt Business Analyse, um <strong>Transparenz im Finanzreporting zu gew\u00e4hrleisten und neue Gesch\u00e4ftspotenziale zu erschlie\u00dfen<\/strong>. Mithilfe des Salesforce-Tools Tableau (eine leistungsstarke Analytics-Plattform, die KI-gest\u00fctzte Analysen und sofort umsetzbare Einblicke direkt in den Workflow integriert) kann sonnen Daten effizient auswerten, was zu einer besseren operativen Steuerung und Identifikation neuer Gesch\u00e4ftschancen f\u00fchrt. Besonders hilfreich: Es k\u00f6nnen <strong>ohne Programmierkenntnisse umfangreiche Analysen<\/strong> durchgef\u00fchrt werden. Das hat die Effizienz im Stromz\u00e4hler-Monitoring und Finanzreporting erheblich verbessert.<\/p>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"topic2\"><strong>Vorteile von Business Analyse f\u00fcr Ihr Unternehmen&nbsp;<\/strong><\/h2>\n\n\n\n<p>Von Kundenzufriedenheit bis Innovationsf\u00f6rderung \u2013 eine gut durchdachte Business Analyse bietet Unternehmen viele Vorteile:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Verbesserte Entscheidungsfindung:<\/strong> Business Analyse liefert detaillierte Einblicke und Daten, die Entscheidungstr\u00e4ger:innen nutzen k\u00f6nnen, um fundierte Entscheidungen zu treffen. Dies kann dazu beitragen, Risiken zu minimieren und die Wahrscheinlichkeit erfolgreicher Ergebnisse zu erh\u00f6hen.<\/li>\n\n\n\n<li><strong>Erh\u00f6hte Effizienz:<\/strong> Durch die Identifizierung ineffizienter Gesch\u00e4ftsprozesse und die Vorschl\u00e4ge zu deren Optimierung kann Business Analyse dazu beitragen, Kosten zu senken und die Produktivit\u00e4t zu steigern.<\/li>\n\n\n\n<li><strong>Zeiteinsparung:<\/strong> Automatisierte Analysen und verbesserte Prozesse f\u00fchren zu schnelleren Entscheidungsabl\u00e4ufen und reduzieren Zeitverluste durch ineffiziente Abl\u00e4ufe.<\/li>\n\n\n\n<li><strong>Bessere Kundenzufriedenheit<\/strong>: Indem sie die Bed\u00fcrfnisse und Erwartungen der Kund:innen genau analysiert, k\u00f6nnen Unternehmen ihre Produkte und Dienstleistungen verbessern.<\/li>\n\n\n\n<li><strong>Strategische Ausrichtung:<\/strong> Business Analyse hilft dabei, die Unternehmensziele klar zu definieren und die Strategien und Taktiken zu entwickeln, die notwendig sind, um diese Ziele zu erreichen. Dies sorgt f\u00fcr eine bessere Ausrichtung der Unternehmensressourcen und Priorit\u00e4ten.<\/li>\n\n\n\n<li><strong>Risikomanagement:<\/strong> Durch fr\u00fchzeitiges Erkennen potenzieller Risiken und Probleme erm\u00f6glicht die Business Analyse proaktive Ma\u00dfnahmen, um diese Risiken zu minimieren oder zu vermeiden.<\/li>\n\n\n\n<li><strong>Innovationsf\u00f6rderung:<\/strong> Durch das st\u00e4ndige Hinterfragen von Prozessen und die Suche nach Verbesserungsm\u00f6glichkeiten f\u00f6rdert die Business Analyse Innovationen innerhalb des Unternehmens. Auch identifizieren Analyst:innen aufkommende Muster und Trends, wodurch Unternehmen proaktiv handeln und sich strategisch positionieren k\u00f6nnen.<\/li>\n\n\n\n<li><strong>Wettbewerbsvorteile:<\/strong> Die durch die Business Analyse gewonnenen Erkenntnisse k\u00f6nnen Unternehmen einen entscheidenden Vorsprung gegen\u00fcber Wettbewerber:innen verschaffen, indem sie schnell auf Marktver\u00e4nderungen reagieren oder neue Marktchancen identifizieren.<\/li>\n\n\n\n<li><strong>Verbesserte Compliance:<\/strong> Business Analyse kann auch dazu beitragen, dass Unternehmen gesetzliche und regulatorische Anforderungen erf\u00fcllen, indem sie sicherstellen, dass die Gesch\u00e4ftspraktiken den Vorschriften entsprechen.<\/li>\n<\/ul>\n\n\n\n<p>Mit der Business Analyse als Schl\u00fcsselwerkzeug k\u00f6nnen Unternehmen nicht nur bestehende Herausforderungen \u00fcberwinden, sondern auch zuk\u00fcnftige Chancen erkennen und nutzen.<\/p>\n\n\n\n<div class=\"wp-block-columns has-background is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\" style=\"background-color:#f3f3f3\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\" id=\"h-business-analyse-beispiel-siemens\"><strong>Business-Analyse-Beispiel: Siemens<\/strong><\/h2>\n\n\n\n<p>Business Analyse ohne passende Tools? Das kostet Zeit und Nerven. Wie es besser geht, zeigt das <a href=\"https:\/\/www.tableau.com\/de-de\/solutions\/customer\/Siemens-gains-deeper-understanding-of-IT-service\">Beispiel von Siemens<\/a>. Das Technologieunternehmen hat mithilfe von Tableau seine IT-Service-Analytik erheblich verbessert. Durch die Integration von Tableau und ServiceNow konnte Siemens <strong>die Analyse von \u00fcber 7 Milliarden Datenzeilen aus mehr als 200 Quellen effizienter gestalten<\/strong>, wodurch tiefere Einblicke in IT-Kosten und Nutzung gewonnen wurden. Die Analyseergebnisse f\u00fchrten zu <strong>verbesserten Managemententscheidungen und einer gesteigerten Benutzerzufriedenheit<\/strong>. Das neue System erm\u00f6glicht eine schnellere und pr\u00e4zisere Datenbearbeitung, was zu signifikanter Zeitersparnis und effizienteren Betriebsabl\u00e4ufen beitr\u00e4gt.<\/p>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"topic3\"><strong>4 Arten und Schwerpunkte der Unternehmensanalyse<\/strong><\/h2>\n\n\n\n<p>Von deskriptiv bis pr\u00e4skriptiv und von strategisch bis operativ \u2013 wenn Ihnen diese Beschreibungen nichts sagen, sollten Sie jetzt weiterlesen. Denn hinter ihnen verbergen sich die Schwerpunkte der Business Analyse. Je nach Fragestellung und Aspekt werden bestimmte Gebiete und Abl\u00e4ufe innerhalb von Unternehmen untersucht.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>4 Arten der Business Analyse<\/strong><\/h3>\n\n\n\n<p>In der Business Analyse gibt es vier grundlegende Arten, die jeweils eine spezifische Fragestellung adressieren:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Deskriptive Analyse (Was ist passiert?):<\/strong><\/li>\n<\/ol>\n\n\n\n<p>Sie beschreibt historische Daten und Trends, um ein Verst\u00e4ndnis f\u00fcr vergangene Ereignisse zu schaffen und aktuelle Situationen zu kl\u00e4ren.<\/p>\n\n\n\n<ol start=\"2\" class=\"wp-block-list\">\n<li><strong>Diagnostische Analyse (Warum ist es passiert?):<\/strong><\/li>\n<\/ol>\n\n\n\n<p>Diese Analyseform konzentriert sich darauf, die Ursachen von Ereignissen oder Zust\u00e4nden zu ergr\u00fcnden, indem sie Datenbeziehungen und -muster untersucht.<\/p>\n\n\n\n<ol start=\"3\" class=\"wp-block-list\">\n<li><strong>Pr\u00e4diktive Analyse (Was wird passieren?):<\/strong><\/li>\n<\/ol>\n\n\n\n<p>Mithilfe statistischer Modelle und Prognosetechniken versucht sie, zuk\u00fcnftige Ereignisse oder Trends auf Basis historischer Daten vorherzusagen.<\/p>\n\n\n\n<ol start=\"4\" class=\"wp-block-list\">\n<li><strong>Pr\u00e4skriptive Analyse (Was sollte getan werden?):<\/strong><\/li>\n<\/ol>\n\n\n\n<p>Diese Art der Analyse bietet Handlungsempfehlungen, indem sie die besten Ma\u00dfnahmen oder Entscheidungen aufzeigt, die auf der Analyse der verf\u00fcgbaren Daten basieren.<\/p>\n\n\n\n<p>Jede dieser Analysearten nutzt spezifische Techniken und Werkzeuge, um Unternehmen zu erm\u00f6glichen, aus ihren Daten maximale Erkenntnisse und Wert zu ziehen. Um das bestm\u00f6gliche Ergebnis zu erhalten, m\u00fcssen alle Fragestellung als Teile einer Analyse-Strategie abgedeckt werden.&nbsp;<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57a613983fb&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57a613983fb\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"563\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2024\/08\/business.analyse-arten.png?w=1000\" alt=\"Eine Grafik zeigt eine Person mit einer Lupe vor einem \u00fcberdimensionalen Bildschirm, der verschiedene Business Analysen zeigt\" class=\"wp-image-10859\" srcset=\"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2024\/08\/business.analyse-arten.png 1000w, https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2024\/08\/business.analyse-arten.png?w=300&amp;h=169 300w, https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2024\/08\/business.analyse-arten.png?w=768&amp;h=432 768w, https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2024\/08\/business.analyse-arten.png?w=150&amp;h=84 150w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>4 Schwerpunkte der Business Analyse<\/strong><\/h3>\n\n\n\n<p>Dar\u00fcber hinaus gibt es in der Business Analyse verschiedene Schwerpunkte, die sich jeweils auf unterschiedliche Aspekte der Unternehmensverbesserung konzentrieren. Vier weit verbreitete Arten der Unternehmensanalyse sind:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Strategische Business Analyse<\/strong><\/li>\n<\/ol>\n\n\n\n<p><strong>Ziel:<\/strong> Identifizierung von gesch\u00e4ftlichen Chancen, Bewertung von Marktpotenzialen und Entwicklung langfristiger Strategien.<\/p>\n\n\n\n<p><strong>T\u00e4tigkeiten:<\/strong> Involviert die Analyse von Markttrends, Wettbewerbsanalysen, und strategische Planung. Strategische Analyst:innen arbeiten oft an der Entwicklung von Visionen und langfristigen Zielen f\u00fcr das Unternehmen, basierend auf umfassenden externen und internen Bewertungen.<\/p>\n\n\n\n<p><strong>Ergebnis:<\/strong> Schaffung einer nachhaltigen Wettbewerbsposition und Ausrichtung der Unternehmensressourcen auf langfristige Ziele.<\/p>\n\n\n\n<ol start=\"2\" class=\"wp-block-list\">\n<li><strong>Taktische Business Analyse<\/strong><\/li>\n<\/ol>\n\n\n\n<p><strong>Ziel:<\/strong> Verbesserung und Optimierung von Gesch\u00e4ftsprozessen und Implementierung von L\u00f6sungen, die sich aus strategischen Zielen ableiten.<\/p>\n\n\n\n<p><strong>T\u00e4tigkeiten<\/strong>: Konzentriert sich auf mittelfristige Initiativen und Projekte, wie die Einf\u00fchrung neuer Systeme oder Prozesse. Sie umfasst ebenfalls die Optimierung bestehender Prozesse und die Sicherstellung, dass die t\u00e4glichen Betriebsabl\u00e4ufe die strategischen Ziele des Unternehmens unterst\u00fctzen.<\/p>\n\n\n\n<p><strong>Ergebnis:<\/strong> Steigerung der betrieblichen Effizienz und Effektivit\u00e4t, wodurch die Unternehmensleistung direkt verbessert wird.<\/p>\n\n\n\n<ol start=\"3\" class=\"wp-block-list\">\n<li><strong>Operative Business Analyse<\/strong><\/li>\n<\/ol>\n\n\n\n<p><strong>Ziel:<\/strong> Unterst\u00fctzung des Tagesgesch\u00e4fts durch direkte Probleml\u00f6sung und Prozessverbesserungen.<\/p>\n\n\n\n<p><strong>T\u00e4tigkeiten:<\/strong> Involviert die Detailanalyse spezifischer Probleme in den Arbeitsabl\u00e4ufen, das Management von kleineren Projekten und die direkte Zusammenarbeit mit den Mitarbeiter:innen, die die Kernprozesse ausf\u00fchren.<\/p>\n\n\n\n<p><strong>Ergebnis:<\/strong> Kurzfristige Verbesserungen, die sofortige Auswirkungen auf die Produktivit\u00e4t und Effektivit\u00e4t haben und oft schnelle L\u00f6sungen f\u00fcr dringende Probleme bieten.<\/p>\n\n\n\n<ol start=\"4\" class=\"wp-block-list\">\n<li><strong>Anforderungsanalyse (Requirements Analysis)<\/strong><\/li>\n<\/ol>\n\n\n\n<p><strong>Ziel:<\/strong> Ermittlung und Definition der Anforderungen, die ein System oder eine Prozessverbesserung erf\u00fcllen muss, um den Bed\u00fcrfnissen der Nutzer:innen oder Stakeholder gerecht zu werden.<\/p>\n\n\n\n<p><strong>T\u00e4tigkeiten:<\/strong> Umfasst das Sammeln von Benutzeranforderungen, die Analyse und Priorisierung dieser Anforderungen und die \u00dcberf\u00fchrung in spezifische, umsetzbare System- oder Prozessspezifikationen.<\/p>\n\n\n\n<p><strong>Ergebnis:<\/strong> Klar definierte und gut dokumentierte Projektanforderungen, die die Grundlage f\u00fcr die Entwicklung und Implementierung von L\u00f6sungen bilden, welche die Benutzerzufriedenheit und die Gesch\u00e4ftseffektivit\u00e4t maximieren.<\/p>\n\n\n\n<div class=\"wp-block-columns has-background is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\" style=\"background-color:#f3f3f3\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\" id=\"h-business-analyse-beispiel-free-now\"><strong>Business-Analyse-Beispiel: Free Now<\/strong><\/h2>\n\n\n\n<p>Daten sind wichtig f\u00fcr eine erfolgreiche Business Analyse, aber nur, wenn sie richtig erhoben und verarbeitet werden. Wie das geht, zeigt das <a href=\"https:\/\/www.tableau.com\/de-de\/solutions\/customer\/Free-Now-unifies-data-from-13-countries\">Beispiel von FREE NOW<\/a>. Das f\u00fchrende Taxi-App-Unternehmen hat mit Tableau eine zentrale, auf AWS basierende Analytics-Plattform entwickelt, die <strong>Daten aus 13 L\u00e4ndern konsolidiert<\/strong>. Dies erm\u00f6glicht Selfservice-Analytics f\u00fcr mehr als die H\u00e4lfte der Mitarbeiter:innen, verbessert das operative Gesch\u00e4ft und unterst\u00fctzt das schnelle Wachstum des Unternehmens. Die Plattform erlaubt eine <strong>flexible Skalierung<\/strong> und erleichtert den Mitarbeiter:innen, unabh\u00e4ngig von ihrem Standort, den Zugang zu konsistenten und pr\u00e4zisen Daten f\u00fcr fundierte Entscheidungen.<\/p>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"topic4\"><strong>9 Schritte, wie Unternehmen mit Business Analyse starten<\/strong><\/h2>\n\n\n\n<p>Nur mit einem strukturierten Ansatz gelingt die Implementierung der Business Analyse in Ihrem Unternehmen. Folgen Sie dazu unseren neun Schritten, um erfolgreich in die Unternehmensanalyse einzusteigen:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>#1 Ziele und Bed\u00fcrfnisse definieren&nbsp;<\/strong><\/h3>\n\n\n\n<p>Kl\u00e4ren Sie, <strong>was das Unternehmen durch Business Analyse erreichen m\u00f6chte<\/strong>. Dies k\u00f6nnte die Verbesserung der Gesch\u00e4ftsprozesse, die Steigerung der Kundenzufriedenheit, die Erh\u00f6hung der Effizienz oder die Unterst\u00fctzung neuer strategischer Initiativen umfassen<strong>. Identifizieren Sie spezifische Probleme oder Herausforderungen<\/strong>, die durch Business Analyse gel\u00f6st werden sollen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>#2 Stakeholder einbinden<\/strong><\/h3>\n\n\n\n<p>Identifizieren Sie alle <strong>relevanten Stakeholder<\/strong> innerhalb und au\u00dferhalb des Unternehmens, die von der Business Analyse betroffen sein k\u00f6nnten. Dies umfasst F\u00fchrungskr\u00e4fte, Abteilungsleiter:innen, Kund:innen und Lieferant:innen. <strong>Kommunizieren Sie den Wert und die Ziele der Business Analyse<\/strong> an alle beteiligten Parteien, um Unterst\u00fctzung und Engagement zu gew\u00e4hrleisten.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>#3 Ressourcen und Team zusammenstellen<\/strong><\/h3>\n\n\n\n<p>Stellen Sie ein <strong>Team aus qualifizierten Business Analyst:innen<\/strong> zusammen. Abh\u00e4ngig von der Gr\u00f6\u00dfe und dem Umfang des Projekts k\u00f6nnen dies interne Mitarbeiter:innen, externe Berater:innen oder eine Kombination aus beiden sein. Stellen Sie sicher, dass das Team \u00fcber die <strong>notwendigen Werkzeuge und Technologien verf\u00fcgt<\/strong>, um Daten zu sammeln, zu analysieren und Berichte zu erstellen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>#4 Analyseframework und Methodologie entwickeln<\/strong><\/h3>\n\n\n\n<p>Entscheiden Sie sich f\u00fcr eine <strong>geeignete Analysemethodologie<\/strong>, die den Zielen des Unternehmens entspricht. Beliebte Methodologien umfassen Agile, Six Sigma, Lean Management und SWOT-Analyse. Entwickeln Sie einen <strong>klaren Prozess f\u00fcr die Durchf\u00fchrung von Analysen<\/strong>, einschlie\u00dflich der Schritte von der Datenerfassung bis zur Implementierung von L\u00f6sungen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>#5 Datenmanagement<\/strong><\/h3>\n\n\n\n<p>Pr\u00fcfen Sie die <strong>verf\u00fcgbaren Datenquellen<\/strong> und stellen Sie sicher, dass die Daten zug\u00e4nglich, genau und relevant sind. Implementieren Sie, wenn n\u00f6tig, <strong>neue Systeme oder Prozesse zur Datenerfassung<\/strong> <strong>und -verarbeitung<\/strong>, um sicherzustellen, dass die Business Analyse auf soliden Informationen basiert.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>#6 Pilotprojekte durchf\u00fchren<\/strong><\/h3>\n\n\n\n<p>Starten Sie mit einem oder mehreren Pilotprojekten, um die Prozesse zu testen und zu verfeinern. W\u00e4hlen Sie Projekte aus, die einen <strong>\u00fcberschaubaren Umfang<\/strong> haben und schnelle Gewinne (Quick Wins) versprechen. Bewerten Sie die <strong>Ergebnisse dieser Pilotprojekte<\/strong> gr\u00fcndlich, um Bereiche f\u00fcr Verbesserungen zu identifizieren und den Erfolg zu messen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>#7 Ergebnisse auswerten und skalieren<\/strong><\/h3>\n\n\n\n<p>Analysieren Sie die Auswirkungen der Business Analyse auf die Unternehmensziele und <strong>messen Sie den <\/strong>Return on Investment (<strong>ROI<\/strong>). Verwenden Sie die Erkenntnisse aus den Pilotprojekten, um die Business-Analyse-Initiativen im gesamten Unternehmen zu erweitern.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>#8 Laufende \u00dcberpr\u00fcfung und Anpassung<\/strong><\/h3>\n\n\n\n<p>Business Analyse sollte ein fortlaufender Prozess sein. <strong>Regelm\u00e4\u00dfige \u00dcberpr\u00fcfungen und Anpassungen<\/strong> der Analysestrategien sind erforderlich, um sicherzustellen, dass sie weiterhin relevant und effektiv sind.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>#9 Aufbau einer datengesteuerten Kultur<\/strong><\/h3>\n\n\n\n<p>Strategie und Pilotprojekt sind ein Erfolg? Das bedeutet nicht, dass die Business Analyse zu Selbstl\u00e4ufer wird. Im letzten und wichtigsten Schritt kommt es darauf an, dass Sie eine Kultur, in der datengest\u00fctzte Entscheidungen zur Norm werden, aufbauen. F\u00f6rdern Sie dazu Datenbef\u00fcrworter:innen in verschiedenen Abteilungen, die helfen k\u00f6nnen, die datengetriebene Kultur voranzutreiben. Bieten Sie ebenfalls Schulungen und kontinuierliche Weiterbildung f\u00fcr Mitarbeiter:innnen an.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"topic5\"><strong>Welche Herausforderungen begegnen Business Analyst:innen?<\/strong><\/h2>\n\n\n\n<p>Business Analyst:innen haben keinen einfachen Job. Sie sto\u00dfen oft auf Herausforderungen, die ihre Arbeit komplex machen. Es gibt jedoch effektive Strategien, mit denen Sie die Probleme der Business Analyse \u00fcberwinden.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Herausforderungen der Business Analyse<\/strong><\/h3>\n\n\n\n<p>Zu den h\u00e4ufigsten Problemen und Hindernisse, denen Business Analyst:innen begegnen, z\u00e4hlen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Unklare Anforderungen:<\/strong> Oft ist es schwierig, pr\u00e4zise Anforderungen von Stakeholdern zu erhalten. Dies kann zu Missverst\u00e4ndnissen oder unvollst\u00e4ndigen L\u00f6sungen f\u00fchren.<\/li>\n\n\n\n<li><strong>Widerstand gegen Ver\u00e4nderungen:<\/strong> Mitarbeiter:innen und manchmal auch das Management k\u00f6nnen skeptisch oder widerwillig gegen\u00fcber neuen Vorschl\u00e4gen und Ver\u00e4nderungen sein. Das trifft besonders dann zu, wenn diese ihren gewohnten Arbeitsablauf st\u00f6ren.<\/li>\n\n\n\n<li><strong>Kommunikationsbarrieren:<\/strong> Effektive Kommunikation zwischen verschiedenen Stakeholdern (Technik, Management, Endnutzer:innen) kann schwierig sein, besonders in gro\u00dfen oder verteilten Organisationen.<\/li>\n\n\n\n<li><strong>Unzureichende Daten:<\/strong> Mangel an qualitativen Daten oder unzureichender Zugang zu Daten kann die F\u00e4higkeit, fundierte Analyseergebnisse zu liefern, erheblich beeintr\u00e4chtigen.<\/li>\n\n\n\n<li><strong>Technologische Einschr\u00e4nkungen<\/strong>: Veraltete Systeme und Technologien k\u00f6nnen die Implementierung von modernen L\u00f6sungen limitieren.<\/li>\n\n\n\n<li><strong>Budget- und Zeitbeschr\u00e4nkungen<\/strong>: Oft stehen nicht gen\u00fcgend Ressourcen zur Verf\u00fcgung, um die besten L\u00f6sungen zu entwickeln und umzusetzen.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Strategien zur \u00dcberwindung dieser Herausforderungen<\/strong><\/h3>\n\n\n\n<p>Mit den folgenden Strategien \u00fcberwinden Sie als Business Analyst:in problematische Hindernisse:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Stakeholder-Management:<\/strong> F\u00f6rdern Sie fr\u00fchzeitiges und regelm\u00e4\u00dfiges Engagement der Stakeholder durch Workshops, Interviews und regelm\u00e4\u00dfige Updates, um deren Bed\u00fcrfnisse zu verstehen und Akzeptanz f\u00fcr das Projekt zu f\u00f6rdern.<\/li>\n\n\n\n<li><strong>Klare Kommunikation:<\/strong> Setzen Sie visuelle Hilfsmittel und klare, jargonfreie Sprache ein, um komplexe Informationen verst\u00e4ndlich zu machen. Regelm\u00e4\u00dfige Meetings und Updates helfen, alle auf dem gleichen Stand zu halten.<\/li>\n\n\n\n<li><strong>Agile Methodologien:<\/strong> Verwenden Sie agile Ans\u00e4tze, wie Scrum oder Kanban, die iterative Entwicklung und kontinuierliches Feedback erm\u00f6glichen, um Flexibilit\u00e4t in der Projektentwicklung zu gew\u00e4hrleisten.<\/li>\n\n\n\n<li><strong>Datenmanagement verbessern:<\/strong> Stellen Sie die Qualit\u00e4t und Zug\u00e4nglichkeit der Daten durch Implementierung robuster Datenmanagementpraktiken und Nutzung moderner Datenanalysetools sicher.<\/li>\n\n\n\n<li><strong>Technologische Aufr\u00fcstung:<\/strong> Argumentieren Sie f\u00fcr die Investition in neue Technologien durch Darstellung des ROI und der langfristigen Vorteile moderner L\u00f6sungen.<\/li>\n\n\n\n<li><strong>Priorisierung und Zeitmanagement:<\/strong> Setzen Sie klare Priorit\u00e4ten f\u00fcr Projektaufgaben und effizientes Zeitmanagement, um Projekte innerhalb des Budgets und Zeitrahmens abzuschlie\u00dfen.<\/li>\n\n\n\n<li><strong>Professionelle Weiterbildung:<\/strong> Investieren Sie in st\u00e4ndige Weiterbildung und Zertifizierungen, um auf dem neuesten Stand der Technik und Best Practices zu bleiben.<\/li>\n<\/ul>\n\n\n\n<p>Durch die Anwendung dieser Strategien k\u00f6nnen Business Analyst:innen effektiver auf die Herausforderungen reagieren, die ihre Arbeit beeintr\u00e4chtigen. Damit werden Sie erfolgreicher bei der Umsetzung von Business-Analyseprojekten sein.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"topic6\"><strong>H\u00f6her, schneller, weiter \u2013 Die Rolle von KI in der Business Analyse<\/strong><\/h2>\n\n\n\n<p><a href=\"https:\/\/www.salesforce.com\/de\/resources\/articles\/ai\/\">K\u00fcnstliche Intelligenz<\/a> (KI) spielt eine zunehmend wichtige Rolle in der Business Analyse. Sie automatisiert Prozesse, vertieft Einblicke und beschleunigt Entscheidungsprozesse in einer Vielzahl von Branchen. Das belegt auch der <a href=\"https:\/\/www.salesforce.com\/de\/resources\/research-reports\/state-of-data-analytics\/\">\u201eState of Data and Analytics\u201c<\/a>. <strong>Technische F\u00fchrungskr\u00e4fte, die KI einsetzen, melden eine deutliche Beschleunigung der Abl\u00e4ufe und Entscheidungsfindung.<\/strong> Geschwindigkeit ist nicht der einzige Vorteil: Analytics- und IT-F\u00fchrungskr\u00e4fte sagen, dass sie dadurch mehr Zeit f\u00fcr strategische Aufgaben haben, statt sich Routinet\u00e4tigkeiten zu verzetteln.<\/p>\n\n\n\n<p>Wir stellen Ihnen einige der Schl\u00fcsselbereiche vor, in denen KI die Business Analyse revolutioniert:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Automatisierung von Routinet\u00e4tigkeiten<\/strong><\/h3>\n\n\n\n<p>KI kann repetitive und zeitaufwendige Aufgaben automatisieren, die traditionell von Business Analyst:innen ausgef\u00fchrt wurden. Dazu geh\u00f6ren Datenbereinigung, -integration und -vorverarbeitung. <strong>Diese Automatisierung erm\u00f6glicht es Analyst:innen, sich auf komplexere und wertsteigernde Aktivit\u00e4ten zu konzentrieren.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Erweiterte Datenanalyse<\/strong><\/h3>\n\n\n\n<p>KI-Technologien wie maschinelles Lernen und tiefe neuronale Netzwerke k\u00f6nnen gro\u00dfe Mengen unstrukturierter Daten analysieren \u2013 von Text in Kundenfeedback bis hin zu Bildern und Videos. <strong>Diese F\u00e4higkeit erlaubt es Unternehmen, Muster und Trends zu erkennen, die f\u00fcr Menschen zu komplex oder subtil sind.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Pr\u00e4diktive Analytik<\/strong><\/h3>\n\n\n\n<p>Mit KI k\u00f6nnen historische Daten genutzt werden, um zuk\u00fcnftige Ereignisse vorherzusagen, was besonders wertvoll f\u00fcr Bereiche wie <strong>Nachfrageprognose, Risikomanagement und Wartungsplanung<\/strong> ist. Pr\u00e4diktive Modelle, die durch KI angetrieben werden, k\u00f6nnen Unternehmen helfen, proaktiver zu handeln und effektiv auf bevorstehende Herausforderungen zu reagieren.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Personalisierte Kundenerlebnisse<\/strong><\/h3>\n\n\n\n<p>K\u00fcnstliche Intelligenz erm\u00f6glicht eine tiefere Personalisierung der Kundeninteraktionen durch das Verst\u00e4ndnis individueller Pr\u00e4ferenzen und Verhaltensweisen. Dies kann die <a href=\"https:\/\/www.salesforce.com\/de\/learning-centre\/customer-service\/customer-retention\/\">Kundenbindung<\/a> verbessern, indem <strong>zielgerichtete Empfehlungen, Inhalte und Angebote bereitgestellt werden<\/strong>, die auf die einzelnen Kund:innen zugeschnitten sind.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Entscheidungsunterst\u00fctzung<\/strong><\/h3>\n\n\n\n<p>KI kann nicht nur Daten analysieren, sondern auch m\u00f6gliche Szenarien simulieren und Empfehlungen aussprechen. Entscheidungsunterst\u00fctzungssysteme, die mit KI verst\u00e4rkt sind<strong>, bieten F\u00fchrungskr\u00e4ften wertvolle Einsichten, die fundierte Entscheidungen erm\u00f6glichen und das Risiko von menschlichen Fehlern verringern.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Echtzeitanalysen und -\u00fcberwachung<\/strong><\/h3>\n\n\n\n<p>Mit KI k\u00f6nnen Unternehmen in Echtzeit auf Daten reagieren, was besonders in schnelllebigen Umgebungen wie dem Finanzmarkt, der Produktion und dem E-Commerce von Vorteil ist. <strong>KI-gest\u00fctzte Systeme k\u00f6nnen kontinuierlich Daten \u00fcberwachen, Anomalien erkennen und sofortige Ma\u00dfnahmen einleiten, wenn n\u00f6tig.<\/strong><\/p>\n\n\n\n<p>Zusammenfassend hat KI das Potenzial, die Art und Weise, wie Unternehmen Daten analysieren und nutzen, grundlegend zu ver\u00e4ndern. Dabei bietet sie sowohl eine Verbesserung der operativen Effizienz als auch der Entscheidungsqualit\u00e4t.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-columns has-background is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\" style=\"background-color:#f3f3f3\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\" id=\"topic7\"><strong>KI und Business Analyse: Beispiel aus der Praxis&nbsp;<\/strong><\/h2>\n\n\n\n<p>KI-Integration in Business-Analyse-Tools ist keine Zukunftsmusik. Jedenfalls, wenn es um Tableau von Salesforce geht. <strong>Mit <\/strong><a href=\"https:\/\/www.tableau.com\/de-de\/products\/tableau-pulse\"><strong>Tableau Pulse<\/strong><\/a><strong>, einer auf KI basierenden Plattform, die in Tableau integriert ist, wird datengesteuerte Entscheidungsfindung im Unternehmen skaliert<\/strong>. Tableau Pulse erm\u00f6glicht Nutzer:innen, personalisierte und kontextbezogene Erkenntnisse direkt im Workflow zu erhalten, ohne neue Tools erlernen oder komplexe Visualisierungen erstellen zu m\u00fcssen. <strong>Tableau Pulse erleichtert auch die Erkennung von Gesch\u00e4ftstrends und -ver\u00e4nderungen<\/strong> durch proaktive, visuell unterst\u00fctzte Analysen in nat\u00fcrlicher Sprache.<\/p>\n\n\n\n<p>So wie sich KI weiterentwickelt, entwickelt sich auch Tableau. Mit dem  <a href=\"https:\/\/www.tableau.com\/einstein-copilot-beta-program\"><strong>Einstein Co-Pilot f\u00fcr Tableau<\/strong><\/a><strong> werden die verschiedenen Aspekte der Datenanalyse automatisiert<\/strong>. Dies f\u00fchrt noch schneller zu besseren Gesch\u00e4ftsentscheidungen.&nbsp;<\/p>\n<\/div>\n<\/div>\n\n\n\n<p>Sie wollen mehr Informationen zu Tableau erhalten? Im folgenden Video wird die Datenanalyseplattform vorgestellt:&nbsp;<br><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"What is Tableau from Salesforce? | How To Increase Your ROI with Tableau | Salesforce Explained\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/oxtYqKkmtd0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"topic8\"><strong>Fazit: So ziehen Sie den gr\u00f6\u00dften Nutzen aus der Business Analyse<\/strong><\/h2>\n\n\n\n<p>Von Definition bis KI \u2013 in unserem Artikel zu Business Analyse haben wir viele unterschiedliche Aspekte einer erfolgreichen Unternehmensanalyse behandelt. Abschlie\u00dfend haben wir Ihnen die sieben wichtigsten Punkte zusammengefasst, mit deren Einsatz Sie den gr\u00f6\u00dftm\u00f6glichen Nutzen aus Business Analytics ziehen:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Zugang zu Erkenntnissen erm\u00f6glichen:<\/strong> Gew\u00e4hrleisten Sie, dass alle Mitarbeiter:innen Zugang zu den f\u00fcr sie relevanten Daten haben. Dies f\u00f6rdert eine informierte Entscheidungsfindung auf allen Ebenen.<\/li>\n\n\n\n<li><strong>Datengesteuerte Kultur schaffen:<\/strong> Integrieren Sie Datenanalyse und Datenstrategie in den Kern der Unternehmensprozesse und f\u00f6rdern Sie eine Kultur, in der Entscheidungen basierend auf Daten getroffen werden.<\/li>\n\n\n\n<li><strong>Die richtigen Talente finden:<\/strong> Stellen Sie sicher, dass Sie qualifizierte Analyst:innen einstellen, die f\u00e4hig sind, Daten sinnvoll zu interpretieren und in handlungsorientierte Erkenntnisse umzusetzen.<\/li>\n\n\n\n<li><strong>Die richtige Infrastruktur bereitstellen:<\/strong> Investieren Sie in die notwendige Technologie und Tools, die robuste Analysen unterst\u00fctzen und skalierbar sind.<\/li>\n\n\n\n<li><strong>Den Nutzen kommunizieren:<\/strong> Verdeutlichen Sie regelm\u00e4\u00dfig den Wert der Business Analyse durch konkrete Beispiele.<\/li>\n\n\n\n<li><strong>Unternehmensziele und Anreize mit Daten abstimmen:<\/strong> Stellen Sie sicher, dass die Ziele und Anreize des Unternehmens klar mit den Datenanalysen abgestimmt sind, um koh\u00e4rente und zielgerichtete Aktionen zu f\u00f6rdern.<\/li>\n\n\n\n<li><strong>Visual Storytelling:<\/strong> Nutzen Sie Datenvisualisierungen, um komplexe Daten und Analysen verst\u00e4ndlich und ansprechend zu kommunizieren, was die Akzeptanz und das Verst\u00e4ndnis \u00fcber verschiedene Stakeholder hinweg erh\u00f6ht.<\/li>\n<\/ol>\n\n\n\n<p>Indem Sie diese Elemente in Ihrer Strategie ber\u00fccksichtigen, k\u00f6nnen Sie die Effektivit\u00e4t Ihrer Business-Analyse-Initiativen maximieren.<\/p>\n\n\n\n<div class=\"wp-block-columns has-background is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\" style=\"background-color:#eaf5fe\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\" id=\"h-jetzt-noch-fitter-in-der-business-analyse-werden-und-alle-vorteile-fur-ihr-unternehmen-nutzen\">Jetzt noch fitter in der Business Analyse werden und alle Vorteile f\u00fcr Ihr Unternehmen nutzen<\/h2>\n\n\n\n<p>Lesen Sie das Whitepaper \u201e<a href=\"https:\/\/www.tableau.com\/learn\/whitepapers\/top-10-principles-of-business-analytics\/?nc=701ed000001QGLZAA4\">Top 10 Principles of Business Analytics<\/a>\u201c und laden Sie sich den <a href=\"https:\/\/www.tableau.com\/de-de\/asset\/unlocking-business-value-ai-powered-data-analytics\/?nc=701ed000001QD2lAAG\">KI-Guide \u201eSchaffung von Mehrwert mit KI-gest\u00fctzter Data Analytics\u201c<\/a> herunter.&nbsp;<em>&nbsp;<\/em><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Bringen Sie Ihr Unternehmen auf Erfolgskurs \u2013 mit unserer Anleitung und hilfreichen Tipps zur Business Analyse.  <\/p>\n","protected":false},"author":13,"featured_media":10858,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sf_justforyou_enable_alt":true,"optimizely_content_id":"d4cbf2b7d8944509b253464f8b1943d6","post_meta_title":"","ai_synopsis":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"sf_topic":[59,165],"sf_content_type":[],"blog":[383,483],"coauthors":[295],"class_list":["post-10856","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","sf_topic-data-culture","sf_topic-data-visualization","blog-data-culture","blog-data-visualization"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Business Analyse: Definition, Vorteile &amp; Anleitung - Salesforce<\/title>\n<meta name=\"description\" content=\"Unternehmensanalyse: \u2713 Definition &amp; Vorteile \u2713 Anleitung in 9 Schritten \u2713 Schwerpunkte \u2713 KI &amp; Tools \u25ba Jetzt zu Business Analyse informieren!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salesforce.com\/de\/blog\/business-analyse\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Navigieren im Datenmeer: Wie Business Analyse Ihr Unternehmen lenken kann\" \/>\n<meta property=\"og:description\" content=\"Unternehmensanalyse: \u2713 Definition &amp; Vorteile \u2713 Anleitung in 9 Schritten \u2713 Schwerpunkte \u2713 KI &amp; Tools \u25ba Jetzt zu Business Analyse informieren!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salesforce.com\/de\/blog\/business-analyse\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-20T15:16:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-30T08:51:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2024\/08\/business-analyse.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Lennart Heuckendorf\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"carolinschmitz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 Minuten\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Lennart Heuckendorf\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/business-analyse\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/business-analyse\/\"},\"author\":[{\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/person\/image\/0ca2ade00f22c8aef928dc994524394b\"}],\"headline\":\"Navigieren im Datenmeer: Wie Business Analyse Ihr Unternehmen lenken kann\",\"datePublished\":\"2024-08-20T15:16:56+00:00\",\"dateModified\":\"2024-10-30T08:51:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/business-analyse\/\"},\"wordCount\":3408,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/business-analyse\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2024\/08\/business-analyse.png\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.salesforce.com\/de\/blog\/business-analyse\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/business-analyse\/\",\"url\":\"https:\/\/www.salesforce.com\/de\/blog\/business-analyse\/\",\"name\":\"Business Analyse: Definition, Vorteile & Anleitung - Salesforce\",\"isPartOf\":{\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/business-analyse\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/business-analyse\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2024\/08\/business-analyse.png\",\"datePublished\":\"2024-08-20T15:16:56+00:00\",\"dateModified\":\"2024-10-30T08:51:09+00:00\",\"description\":\"Unternehmensanalyse: \u2713 Definition & Vorteile \u2713 Anleitung in 9 Schritten \u2713 Schwerpunkte \u2713 KI & Tools \u25ba Jetzt zu Business Analyse informieren!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/business-analyse\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.salesforce.com\/de\/blog\/business-analyse\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/business-analyse\/#primaryimage\",\"url\":\"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2024\/08\/business-analyse.png\",\"contentUrl\":\"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2024\/08\/business-analyse.png\",\"width\":1000,\"height\":563,\"caption\":\"Eine Illustration zeigt einen Mann, der im Meer im Anzug schwimmt und nach einem Rettungsreifen greift.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/business-analyse\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.salesforce.com\/de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Navigieren im Datenmeer: Wie Business Analyse Ihr Unternehmen lenken kann\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/#website\",\"url\":\"https:\/\/www.salesforce.com\/de\/blog\/\",\"name\":\"Salesforce\",\"description\":\"Lesen Sie die neuesten Tipps und Trends f\u00fcr Ihr Business - rund um die Themen Marketing, Vertrieb, Service, IT und Commerce.\",\"publisher\":{\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/#organization\"},\"alternateName\":\"Salesforce\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.salesforce.com\/de\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/#organization\",\"name\":\"Salesforce\",\"url\":\"https:\/\/www.salesforce.com\/de\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Salesforce\"},\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/person\/image\/0ca2ade00f22c8aef928dc994524394b\",\"name\":\"Lennart Heuckendorf\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/person\/image\/d0670c85e16d26cf6dfcfc9a833d6016\",\"url\":\"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2024\/02\/lennart.heuckendorf.png?w=150&h=150&crop=1\",\"contentUrl\":\"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2024\/02\/lennart.heuckendorf.png?w=150&h=150&crop=1\",\"width\":\"150\",\"height\":\"150\",\"caption\":\"Lennart Heuckendorf\"},\"description\":\"Lennart ist Principal Solution Engineer mit mehr als sieben Jahren Erfahrung bei Tableau. Seine Leidenschaft gilt der Nutzung von KI und fortschrittlichen Analysetechnologien, um Unternehmen dabei zu unterst\u00fctzen, den maximalen Wert aus ihren Daten zu generieren. Als treibende Kraft bei Tableau ist sein Ziel, die Transformation von Business Intelligence zu einer datengetriebenen Kultur voranzutreiben und jeder\/m in einer Organisation zu helfen Daten zu sehen, zu verstehen und kommunizieren zu k\u00f6nnen.\",\"url\":\"https:\/\/www.salesforce.com\/de\/blog\/author\/lennart-heuckendorf\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Business Analyse: Definition, Vorteile & Anleitung - Salesforce","description":"Unternehmensanalyse: \u2713 Definition & Vorteile \u2713 Anleitung in 9 Schritten \u2713 Schwerpunkte \u2713 KI & Tools \u25ba Jetzt zu Business Analyse informieren!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salesforce.com\/de\/blog\/business-analyse\/","og_locale":"de_DE","og_type":"article","og_title":"Navigieren im Datenmeer: Wie Business Analyse Ihr Unternehmen lenken kann","og_description":"Unternehmensanalyse: \u2713 Definition & Vorteile \u2713 Anleitung in 9 Schritten \u2713 Schwerpunkte \u2713 KI & Tools \u25ba Jetzt zu Business Analyse informieren!","og_url":"https:\/\/www.salesforce.com\/de\/blog\/business-analyse\/","og_site_name":"Salesforce","article_published_time":"2024-08-20T15:16:56+00:00","article_modified_time":"2024-10-30T08:51:09+00:00","og_image":[{"width":1000,"height":563,"url":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2024\/08\/business-analyse.png","type":"image\/png"}],"author":"Lennart Heuckendorf","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"carolinschmitz","Gesch\u00e4tzte Lesezeit":"18 Minuten","Written by":"Lennart Heuckendorf"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salesforce.com\/de\/blog\/business-analyse\/#article","isPartOf":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/business-analyse\/"},"author":[{"@id":"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/person\/image\/0ca2ade00f22c8aef928dc994524394b"}],"headline":"Navigieren im Datenmeer: Wie Business Analyse Ihr Unternehmen lenken kann","datePublished":"2024-08-20T15:16:56+00:00","dateModified":"2024-10-30T08:51:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/business-analyse\/"},"wordCount":3408,"commentCount":0,"publisher":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/#organization"},"image":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/business-analyse\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2024\/08\/business-analyse.png","inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.salesforce.com\/de\/blog\/business-analyse\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.salesforce.com\/de\/blog\/business-analyse\/","url":"https:\/\/www.salesforce.com\/de\/blog\/business-analyse\/","name":"Business Analyse: Definition, Vorteile & Anleitung - Salesforce","isPartOf":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/business-analyse\/#primaryimage"},"image":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/business-analyse\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2024\/08\/business-analyse.png","datePublished":"2024-08-20T15:16:56+00:00","dateModified":"2024-10-30T08:51:09+00:00","description":"Unternehmensanalyse: \u2713 Definition & Vorteile \u2713 Anleitung in 9 Schritten \u2713 Schwerpunkte \u2713 KI & Tools \u25ba Jetzt zu Business Analyse informieren!","breadcrumb":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/business-analyse\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salesforce.com\/de\/blog\/business-analyse\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.salesforce.com\/de\/blog\/business-analyse\/#primaryimage","url":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2024\/08\/business-analyse.png","contentUrl":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2024\/08\/business-analyse.png","width":1000,"height":563,"caption":"Eine Illustration zeigt einen Mann, der im Meer im Anzug schwimmt und nach einem Rettungsreifen greift."},{"@type":"BreadcrumbList","@id":"https:\/\/www.salesforce.com\/de\/blog\/business-analyse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salesforce.com\/de\/blog\/"},{"@type":"ListItem","position":2,"name":"Navigieren im Datenmeer: Wie Business Analyse Ihr Unternehmen lenken kann"}]},{"@type":"WebSite","@id":"https:\/\/www.salesforce.com\/de\/blog\/#website","url":"https:\/\/www.salesforce.com\/de\/blog\/","name":"Salesforce","description":"Lesen Sie die neuesten Tipps und Trends f\u00fcr Ihr Business - rund um die Themen Marketing, Vertrieb, Service, IT und Commerce.","publisher":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/#organization"},"alternateName":"Salesforce","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salesforce.com\/de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.salesforce.com\/de\/blog\/#organization","name":"Salesforce","url":"https:\/\/www.salesforce.com\/de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Salesforce"},"image":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/person\/image\/0ca2ade00f22c8aef928dc994524394b","name":"Lennart Heuckendorf","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/person\/image\/d0670c85e16d26cf6dfcfc9a833d6016","url":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2024\/02\/lennart.heuckendorf.png?w=150&h=150&crop=1","contentUrl":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2024\/02\/lennart.heuckendorf.png?w=150&h=150&crop=1","width":"150","height":"150","caption":"Lennart Heuckendorf"},"description":"Lennart ist Principal Solution Engineer mit mehr als sieben Jahren Erfahrung bei Tableau. Seine Leidenschaft gilt der Nutzung von KI und fortschrittlichen Analysetechnologien, um Unternehmen dabei zu unterst\u00fctzen, den maximalen Wert aus ihren Daten zu generieren. Als treibende Kraft bei Tableau ist sein Ziel, die Transformation von Business Intelligence zu einer datengetriebenen Kultur voranzutreiben und jeder\/m in einer Organisation zu helfen Daten zu sehen, zu verstehen und kommunizieren zu k\u00f6nnen.","url":"https:\/\/www.salesforce.com\/de\/blog\/author\/lennart-heuckendorf\/"}]}},"jetpack_featured_media_url":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2024\/08\/business-analyse.png","jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Salesforce","distributor_original_site_url":"https:\/\/www.salesforce.com\/de\/blog","push-errors":false,"primary_topic":{"term_id":59,"name":"Datenkultur","slug":"data-culture","term_group":0,"term_taxonomy_id":59,"taxonomy":"sf_topic","description":"","parent":0,"count":21,"filter":"raw"},"featured_image_url":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2024\/08\/business-analyse.png?w=1000","_links":{"self":[{"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/posts\/10856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/comments?post=10856"}],"version-history":[{"count":6,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/posts\/10856\/revisions"}],"predecessor-version":[{"id":11184,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/posts\/10856\/revisions\/11184"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/media\/10858"}],"wp:attachment":[{"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/media?parent=10856"}],"wp:term":[{"taxonomy":"sf_topic","embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/sf_topic?post=10856"},{"taxonomy":"sf_content_type","embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/sf_content_type?post=10856"},{"taxonomy":"blog","embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/blog?post=10856"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/coauthors?post=10856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}