{"id":1125,"date":"2021-07-26T18:48:00","date_gmt":"2023-06-06T18:48:57","guid":{"rendered":"https:\/\/www.salesforce.com\/?p=1125"},"modified":"2023-07-05T15:13:04","modified_gmt":"2023-07-05T15:13:04","slug":"hackathons","status":"publish","type":"post","link":"https:\/\/www.salesforce.com\/de\/blog\/hackathons\/","title":{"rendered":"Hackathons sind nicht nur etwas f\u00fcr Computerfreaks"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><b>Beim Salesforce Ecosystem Academics Dual Study Program Hackathon trafen sich junge Menschen, um an drei Tagen gemeinsam kreative Ideen zu entwickeln.<\/b> Das Wort \u201eHackathon\u201c klingt nach einem abgedunkelten Raum voller Computerfreaks, die fremde Rechner knacken, Kapuzen-Pullover tragen und sich ausschlie\u00dflich von Koffein und Fast Food ern\u00e4hren. \u201eLasst euch nicht von diesem Wort abschrecken! Unser Ziel ist es, euch in ein realistisches Salesforce-Projekt einsteigen zu lassen\u201c, betonte deshalb Christian Kohnle, Projektcoach beim Steinbeis Center of Management and Technology (SCMT) zum Start des Salesforce Ecosystem Academics Dual Study Program Hackathon in diesem Fr\u00fchjahr.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-ohne-ausseren-zwang-besonders-kreativ-sein\">Ohne \u00e4u\u00dferen Zwang besonders kreativ sein<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Es waren 20 ganz normale junge Menschen, die sich als Teil des <a href=\"https:\/\/www.salesforce.com\/de\/company\/talent-ecosystem\">Salesforce Central Europe Talent Ecosystem<\/a> jeweils mit einer Woche Abstand an drei Tagen trafen, um ganz ohne \u00e4u\u00dferen Zwang besonders kreativ zu sein. Alle absolvieren sie derzeit einen 36-monatigen dualen Bachelor-Studiengang im Bereich Digital Management &amp; Transformation, den die Steinbeis School of Management and Innovation an der Steinbeis-Hochschule am Standort M\u00fcnchen in Zusammenarbeit mit Salesforce anbietet. Immer mehr Unternehmen veranstalten f\u00fcr ihren Nachwuchs Hackathons, damit die Teilnehmerinnen und Teilnehmer ein neuartiges Innvotationskonzept kennenlernen, bei dem zusammen L\u00f6sungen erarbeitet oder Produkte entworfen werden. Die Schwerpunkte liegen dabei auf einer lockeren Atmosph\u00e4re und gr\u00f6\u00dftm\u00f6glicher Kreativit\u00e4t. Der Begriff selbst ist eine Zusammensetzung der Worte \u201eHack\u201c und \u201eMarathon\u201c, was treffend die urspr\u00fcngliche Idee hinter einem Hackathons zeigt. Anfangs war es ein Event, dass sich ausschlie\u00dflich auf Soft- und Hardwareentwicklung bezog. Programmierer, Techniker, Computer-Interessierte, Ingenieure und Software-Entwickler waren die Zielgruppe des ersten Hackathons, der bereits 1999 stattfand.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-gemeinsam-mit-unseren-partnern-neue-wege-gehen\">Gemeinsam mit unseren Partnern neue Wege gehen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Seit diesen Anf\u00e4ngen hat sich das Konzept stetig weiterentwickelt und ist l\u00e4ngst nicht mehr nur f\u00fcr Hacker und IT-Spezialisten gedacht. Vielmehr wird der Grundgedanke genutzt, um gemeinsam im Team kreative L\u00f6sungsans\u00e4tze und neue Ideen zu entwickeln. Kein Wunder, dass wir bei Salesforce \u2013 zusammen mit verschiedenen Steinbeis-Einrichtungen und unseren Partnern Covis, Mindtree, entero, Canyon und ec4u, in diesem Jahr erstmals zum \u201eDual Study Program Hackathon\u201c f\u00fcr die Talente von heute und morgen aufgerufen haben. Zur Einf\u00fchrung stellte Christian Kohnle am ersten Tag drei spannende Beispiele aus dem realen Salesforce-Leben vor, um den Teilnehmerinnen und Teilnehmern erste Ideen f\u00fcr ihre eigenen Projekte zu geben. Dabei ging es zum einen um die Online-Plattform CropSafe, die zur Erkennung und Vorhersage von Krankheiten und Verunreinigungen bei Nutzpflanzen mithilfe von Satellitenbildern und maschinellem Lernen eingesetzt werden soll. Projekt 2 drehte sich um \u201e<a href=\"https:\/\/www.easytaxis.com\/\">EasyTaxi<\/a>\u201c \u2013 eine App, die bereits in 30 L\u00e4ndern und in mehr als 420 St\u00e4dten funktioniert. Und das dritte Projekt war \u201eGroupME\u201c. Eine kostenlose Anwendung, mit der auf dem Telefon \u00fcber Push-Benachrichtigungen oder per SMS in Gruppen und auf jedem Ger\u00e4t gechattet werden kann.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-vier-gruppen-wahlten-sich-ehrgeizige-projekte-aus\">Vier Gruppen w\u00e4hlten sich ehrgeizige Projekte aus<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nach dieser Einf\u00fchrung wurden gemeinsam m\u00f6gliche Projekte f\u00fcr die einzelnen Teams diskutiert und vier Gruppen gebildet, die gemeinsam die folgenden Themen bearbeiten wollten: <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>&#8222;Was k\u00f6nnen Sie tun, um Ihre lokale Umwelt sauber zu halten &amp; welche Auswirkungen hat das?&#8220;<\/li>\n\n\n\n<li>&#8222;Bauen Sie eine App mit integrierter Einstein-Analytik zur Vogelbeobachtung.\u201c<\/li>\n\n\n\n<li>&#8222;Wie k\u00f6nnen wir psychologische Hilfe f\u00fcr die breite \u00d6ffentlichkeit in einem On-Demand-Ansatz anbieten? &#8222;*<\/li>\n\n\n\n<li>&#8222;Wie kann man mit Salesforce junge Talente ansprechen und eine motivierte und innovative Studentengemeinschaft schaffen?&#8220;<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Der Coach verabschiedete die gespannten jungen Kreativen am Ende des ersten Tages mit dem Hinweis: \u201eKeine Sorge, Sie k\u00f6nnen am Tag des Hackathons auch einfach improvisieren\u201c. Denn genau dies ist das Grundprinzip eines erfolgreichen Hackathons. Er ist viel weniger f\u00f6rmlich als die t\u00e4gliche Arbeit im B\u00fcro. Das Event soll ungezwungen sein, Spa\u00df machen und kreative Gedanken f\u00f6rdern. Es gibt keinerlei gedankliche Einschr\u00e4nkungen. Stattdessen viel Raum, um sich selbst zu entfalten und sich \u00fcber das normale Ma\u00df hinaus einzubringen. Wichtig dabei ist, dass es au\u00dferhalb des Themas keine weiteren Vorgaben f\u00fcr die Projekte gibt. Jeder kann vollkommen frei, unvoreingenommen, kreativ oder manchmal auch v\u00f6llig abgedreht sein. Nur so kommen die unterschiedlichsten Ergebnisse zustande. Aber nat\u00fcrlich sollten die Dualen Studentinnen und Studenten w\u00e4hrend des Hackathons auch das notwendige Handwerkszeug f\u00fcr das kreative Arbeiten vermittelt bekommen. Deshalb besch\u00e4ftigte sich die erste Session 14 Tage vor dem eigentlichen Hackathon-Tag neben der Einf\u00fchrung und dem Brainstorming auch in einem Workshop mit dem Thema Design Thinking. Die zweite zweist\u00fcndige Session &#8211; einen Tag vor dem gro\u00dfen Ereignis &#8211; war der Teambildung gewidmet.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-ergebnisprasentation-mit-maximal-10-folien-und-in-20-minuten\">Ergebnispr\u00e4sentation mit maximal 10 Folien und in 20 Minuten<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Der Hackathon selbst dauerte dann acht Stunden inklusive der L\u00f6sungserarbeitung, Teamvorstellung und Pr\u00e4sentation vor der Jury. Diese bestand aus Vertretern von Salesforce und den Partnern Covis, Mindtree und Steinbeis. Jedes Team pr\u00e4sentierte seine Ergebnisse und musste dabei klare Vorgaben einhalten: Maximal 10 Folien und h\u00f6chstens 20 Minuten durfte die Vorstellung in Anspruch nehmen. Die Nase vorn hatte am Ende ziemlich knapp die Gruppe 3, die ein On-Demand-Psychologie-Konzept entwickelte. \u201cDas Gewinner-Team konnte am Ende durch eine klare Value-Pr\u00e4position, ein gutes erstes Solution-Design und eine tolle Pr\u00e4sentation \u00fcberzeugen\u201d, so das Urteil der Jurymitglieder. Als Preis erhielten die Sieger eine Career-Development-Session mit dem Salesforce-COO Gurjinder Sembhi. F\u00fcr die Expertenjury war die Entscheidung nicht einfach. Denn sie musste beurteilen, ob die gemeinsam entwickelten Ideen einen Nutzwert f\u00fcr das Unternehmen haben? Sind sie einzigartig oder werden sie als neue Ans\u00e4tze Wirkung zeigen? Lassen sie sich in die Realit\u00e4t umsetzen? Und vor allem: Hat das Team echte Innovationen entwickelt und seine F\u00e4higkeiten erweitert, Probleme zu l\u00f6sen?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-gewonnen-haben-am-ende-alle-teilnehmerinnen-und-teilnehmer\">Gewonnen haben am Ende alle Teilnehmerinnen und Teilnehmer<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Und auch wenn die Jury am Ende nur ein Siegerteam auszeichnen konnte \u2013 gewonnen haben dabei alle Teilnehmerinnen und Teilnehmer. Vor allem an Erfahrung. Und genau das ist das Ziel eines solchen Hackathons \u2013 das ganz praktische F\u00f6rdern junger Talente. Diese und \u00e4hnliche Veranstaltungen sind Teil unseres <a href=\"https:\/\/www.salesforce.com\/de\/company\/talent-ecosystem\">Salesforce Central Europe Talent Ecosystems<\/a>, mit dem wir bis 2024 in unserer Region rund 100.000 neue Arbeitspl\u00e4tze schaffen wollen \u2013 beispielsweise als Berater\/in, Administrator\/in, Systemarchitekten\/in oder Entwickler\/in. Berufe, in denen vor allem Kreativit\u00e4t und Teamgeist gefordert werden. Die Teilnahme am ersten Salesforce Ecosystem Academics Dual Study Program Hackathon hat daf\u00fcr auf jeden Fall schon mal eine gute Basis gelegt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> <span id=\"authorRoot\" path=\"\/content\/blogs\/de\/de\/authors\/\"><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Beim Salesforce Ecosystem Academics Dual Study Program Hackathon trafen sich junge Menschen, um an drei Tagen gemeinsam kreative Ideen zu entwickeln.<\/p>\n","protected":false},"author":1,"featured_media":1124,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sf_justforyou_enable_alt":true,"optimizely_content_id":"","post_meta_title":"","ai_synopsis":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"sf_topic":[99,13],"sf_content_type":[],"blog":[510,449],"coauthors":[20],"class_list":["post-1125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","sf_topic-salesforce-culture","sf_topic-news","blog-news","blog-salesforce-culture"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Hackathons sind nicht nur etwas f\u00fcr Computerfreaks - Salesforce<\/title>\n<meta name=\"description\" content=\"Beim Salesforce Ecosystem Academics Dual Study Program Hackathon trafen sich junge Menschen, um an drei Tagen gemeinsam kreative Ideen zu entwickeln.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salesforce.com\/de\/blog\/hackathons\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hackathons sind nicht nur etwas f\u00fcr Computerfreaks\" \/>\n<meta property=\"og:description\" content=\"Beim Salesforce Ecosystem Academics Dual Study Program Hackathon trafen sich junge Menschen, um an drei Tagen gemeinsam kreative Ideen zu entwickeln.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salesforce.com\/de\/blog\/hackathons\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-06T18:48:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-05T15:13:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/EE_CGC_2019_Amsterdam_3630.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redaktion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Redaktion\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/hackathons\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/hackathons\\\/\"},\"author\":[{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/#\\\/schema\\\/person\\\/image\\\/1d10ab9722894ac201eaf2c479e36f79\"}],\"headline\":\"Hackathons sind nicht nur etwas f\u00fcr Computerfreaks\",\"datePublished\":\"2023-06-06T18:48:57+00:00\",\"dateModified\":\"2023-07-05T15:13:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/hackathons\\\/\"},\"wordCount\":1041,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/hackathons\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2023\\\/06\\\/EE_CGC_2019_Amsterdam_3630.jpg\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/hackathons\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/hackathons\\\/\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/hackathons\\\/\",\"name\":\"Hackathons sind nicht nur etwas f\u00fcr Computerfreaks - Salesforce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/hackathons\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/hackathons\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2023\\\/06\\\/EE_CGC_2019_Amsterdam_3630.jpg\",\"datePublished\":\"2023-06-06T18:48:57+00:00\",\"dateModified\":\"2023-07-05T15:13:04+00:00\",\"description\":\"Beim Salesforce Ecosystem Academics Dual Study Program Hackathon trafen sich junge Menschen, um an drei Tagen gemeinsam kreative Ideen zu entwickeln.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/hackathons\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/hackathons\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/hackathons\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2023\\\/06\\\/EE_CGC_2019_Amsterdam_3630.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2023\\\/06\\\/EE_CGC_2019_Amsterdam_3630.jpg\",\"width\":600,\"height\":400,\"caption\":\"Hackathons sind nicht nur etwas f\u00fcr Computerfreaks\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/hackathons\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hackathons sind nicht nur etwas f\u00fcr Computerfreaks\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/\",\"name\":\"Salesforce\",\"description\":\"Lesen Sie die neuesten Tipps und Trends f\u00fcr Ihr Business - rund um die Themen Marketing, Vertrieb, Service, IT und Commerce.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/#organization\"},\"alternateName\":\"Salesforce\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/#organization\",\"name\":\"Salesforce\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Salesforce\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/#\\\/schema\\\/person\\\/image\\\/1d10ab9722894ac201eaf2c479e36f79\",\"name\":\"Redaktion\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/#\\\/schema\\\/person\\\/image\\\/8e9bcdb7af1799e5d0dfeee36e7f8079\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2023\\\/06\\\/redaktion.png?w=150&h=150&crop=1\",\"contentUrl\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2023\\\/06\\\/redaktion.png?w=150&h=150&crop=1\",\"width\":150,\"height\":150,\"caption\":\"Redaktion\"},\"description\":\"Unser Redaktionsteam versorgt Sie regelm\u00e4\u00dfig mit den neuesten Trends, Tipps &amp; Tricks aus der Salesforce Welt.\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/author\\\/redaktion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Hackathons sind nicht nur etwas f\u00fcr Computerfreaks - Salesforce","description":"Beim Salesforce Ecosystem Academics Dual Study Program Hackathon trafen sich junge Menschen, um an drei Tagen gemeinsam kreative Ideen zu entwickeln.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salesforce.com\/de\/blog\/hackathons\/","og_locale":"de_DE","og_type":"article","og_title":"Hackathons sind nicht nur etwas f\u00fcr Computerfreaks","og_description":"Beim Salesforce Ecosystem Academics Dual Study Program Hackathon trafen sich junge Menschen, um an drei Tagen gemeinsam kreative Ideen zu entwickeln.","og_url":"https:\/\/www.salesforce.com\/de\/blog\/hackathons\/","og_site_name":"Salesforce","article_published_time":"2023-06-06T18:48:57+00:00","article_modified_time":"2023-07-05T15:13:04+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/EE_CGC_2019_Amsterdam_3630.jpg","type":"image\/jpeg"}],"author":"Redaktion","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten","Written by":"Redaktion"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salesforce.com\/de\/blog\/hackathons\/#article","isPartOf":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/hackathons\/"},"author":[{"@id":"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/person\/image\/1d10ab9722894ac201eaf2c479e36f79"}],"headline":"Hackathons sind nicht nur etwas f\u00fcr Computerfreaks","datePublished":"2023-06-06T18:48:57+00:00","dateModified":"2023-07-05T15:13:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/hackathons\/"},"wordCount":1041,"commentCount":0,"publisher":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/#organization"},"image":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/hackathons\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/EE_CGC_2019_Amsterdam_3630.jpg","inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.salesforce.com\/de\/blog\/hackathons\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.salesforce.com\/de\/blog\/hackathons\/","url":"https:\/\/www.salesforce.com\/de\/blog\/hackathons\/","name":"Hackathons sind nicht nur etwas f\u00fcr Computerfreaks - Salesforce","isPartOf":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/hackathons\/#primaryimage"},"image":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/hackathons\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/EE_CGC_2019_Amsterdam_3630.jpg","datePublished":"2023-06-06T18:48:57+00:00","dateModified":"2023-07-05T15:13:04+00:00","description":"Beim Salesforce Ecosystem Academics Dual Study Program Hackathon trafen sich junge Menschen, um an drei Tagen gemeinsam kreative Ideen zu entwickeln.","breadcrumb":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/hackathons\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salesforce.com\/de\/blog\/hackathons\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.salesforce.com\/de\/blog\/hackathons\/#primaryimage","url":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/EE_CGC_2019_Amsterdam_3630.jpg","contentUrl":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/EE_CGC_2019_Amsterdam_3630.jpg","width":600,"height":400,"caption":"Hackathons sind nicht nur etwas f\u00fcr Computerfreaks"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salesforce.com\/de\/blog\/hackathons\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salesforce.com\/de\/blog\/"},{"@type":"ListItem","position":2,"name":"Hackathons sind nicht nur etwas f\u00fcr Computerfreaks"}]},{"@type":"WebSite","@id":"https:\/\/www.salesforce.com\/de\/blog\/#website","url":"https:\/\/www.salesforce.com\/de\/blog\/","name":"Salesforce","description":"Lesen Sie die neuesten Tipps und Trends f\u00fcr Ihr Business - rund um die Themen Marketing, Vertrieb, Service, IT und Commerce.","publisher":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/#organization"},"alternateName":"Salesforce","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salesforce.com\/de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.salesforce.com\/de\/blog\/#organization","name":"Salesforce","url":"https:\/\/www.salesforce.com\/de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Salesforce"},"image":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/person\/image\/1d10ab9722894ac201eaf2c479e36f79","name":"Redaktion","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/person\/image\/8e9bcdb7af1799e5d0dfeee36e7f8079","url":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/redaktion.png?w=150&h=150&crop=1","contentUrl":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/redaktion.png?w=150&h=150&crop=1","width":150,"height":150,"caption":"Redaktion"},"description":"Unser Redaktionsteam versorgt Sie regelm\u00e4\u00dfig mit den neuesten Trends, Tipps &amp; Tricks aus der Salesforce Welt.","url":"https:\/\/www.salesforce.com\/de\/blog\/author\/redaktion\/"}]}},"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Salesforce","distributor_original_site_url":"https:\/\/www.salesforce.com\/de\/blog","push-errors":false,"jetpack_featured_media_url":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/EE_CGC_2019_Amsterdam_3630.jpg","primary_topic":{"term_id":99,"name":"Inside Salesforce","slug":"salesforce-culture","term_group":0,"term_taxonomy_id":99,"taxonomy":"sf_topic","description":"Wir nehmen Sie mit hinter die Kulissen: Hier finden Sie spannende Stories aus der Salesforce Welt.","parent":0,"count":34,"filter":"raw"},"featured_image_url":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/EE_CGC_2019_Amsterdam_3630.jpg?w=600","_links":{"self":[{"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/posts\/1125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/comments?post=1125"}],"version-history":[{"count":4,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/posts\/1125\/revisions"}],"predecessor-version":[{"id":4768,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/posts\/1125\/revisions\/4768"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/media\/1124"}],"wp:attachment":[{"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/media?parent=1125"}],"wp:term":[{"taxonomy":"sf_topic","embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/sf_topic?post=1125"},{"taxonomy":"sf_content_type","embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/sf_content_type?post=1125"},{"taxonomy":"blog","embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/blog?post=1125"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/coauthors?post=1125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}