{"id":1471,"date":"2022-05-24T18:53:00","date_gmt":"2023-06-06T18:53:23","guid":{"rendered":"https:\/\/www.salesforce.com\/?p=1471"},"modified":"2023-07-04T09:06:20","modified_gmt":"2023-07-04T09:06:20","slug":"trailblazer-esl-gaming","status":"publish","type":"post","link":"https:\/\/www.salesforce.com\/de\/blog\/trailblazer-esl-gaming\/","title":{"rendered":"Trailblazer Blog: Wie ESL Gaming sein weltweites Gesch\u00e4ft transformiert und professionalisiert"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Die Gaming-Industrie ist die am schnellsten wachsende Industrie im Entertainment-Bereich. E-Sports hat daran einen entscheidenden Anteil und als weltweit gr\u00f6\u00dftes Unternehmen in der Branche hat ESL Gaming einen ganz entscheidenden Anteil an dieser Entwicklung. \u201cDass Gamer irgendwann einmal Superstars sind und E-Sport zu einem lukrativen Gesch\u00e4ft werden k\u00f6nnte, daran hat noch vor zehn Jahren au\u00dfer uns niemand geglaubt\u201d, erz\u00e4hlt Rodrigo Samwell, Chief Commercial Officer bei ESL Gaming. \u201cMittlerweile fiebern zehntausende Fans vor Ort bei Turnieren und viele Millionen Zuschauer online mit. Um mit dieser Entwicklung Schritt zu halten, m\u00fcssen wir unser Gesch\u00e4ft auf die n\u00e4chste Stufe heben und weiter professionalisieren. Genau dabei unterst\u00fctzt uns die strategische Partnerschaft mit Salesforce.\u201d&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-salesforce-als-zentrale-plattform-nicht-mehr-wegzudenken\">Salesforce als zentrale Plattform nicht mehr wegzudenken<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">David Hiltscher, VP Fan Value Management &amp; Analytics bei ESL Gaming erg\u00e4nzt: \u201cSalesforce ist die zentrale L\u00f6sung, mit der wir einen neuen globalen Sport aufbauen. E-Sport ist ein Sport, der weltweit jedem Menschen offen steht, das macht ihn so einzigartig. Weder gibt es gro\u00dfe Einstiegsh\u00fcrden bei der Ausstattung, noch sprachliche oder r\u00e4umliche Barrieren. Jeder kann gegen jeden spielen, unabh\u00e4ngig von Alter oder Geschlecht. Salesforce ist als globales Kommunikationstool daf\u00fcr pr\u00e4destiniert, den Menschen diesen Sport n\u00e4her zu bringen und zusammenzuwachsen. Diese Mission teilen wir mit unseren Kunden und Fans, denn auch sie wollen, dass E-Sport weltweit noch gr\u00f6\u00dfere Anerkennung findet. Mit Salesforce werden wir E-Sport weltweit unter den popul\u00e4rsten Sportarten etablieren.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDie Salesforce-L\u00f6sungen unterst\u00fctzen uns ebenfalls in allen Commercial-Bereichen und w\u00e4hrend des gesamten Lifecycles &#8211; von der <a adhocenable=\"false\" href=\"https:\/\/www.salesforce.com\/de\/learning-centre\/marketing\/what-is-lead-generation\/\">Lead-Generierung<\/a>, bei der \u00dcberf\u00fchrung unserer Kunden in die n\u00e4chste Phase der <a adhocenable=\"false\" href=\"https:\/\/www.salesforce.com\/de\/learning-centre\/marketing\/what-is-customer-journey-mapping\/\">Customer Journey<\/a> und auch bei den unterschiedlichsten Arten von Kunden Deals\u201d, erkl\u00e4rt Rodrigo Samwell. \u201cUnsere Sales Teams arbeiten seit der Salesforce Implementierung durch die Optimierungen erheblich effizienter.\u201c Zudem k\u00f6nnen wir mit unseren Brand-Partnern viel einfacher und effektiver kommunizieren, was die Beziehungen mit den Kunden erheblich verbessert hat. Dass wir mit Salesforce arbeiten und unsere Organisation transformieren und professionalisieren st\u00e4rkt zudem unsere Position gegen\u00fcber unseren Partnern.\u201d<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-b2b-und-b2c\">B2B und B2C<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wir sind im B2B-Bereich gestartet, hier ist die Plattform l\u00e4ngst das absolute Key-Element. Jetzt rollen wir Salesforce Schritt f\u00fcr Schritt auch im B2C-Bereich aus. Damit legen wir das Fundament, um eine Consumer-zentrierte Organisation zu werden. Die Marketing Cloud und die Partnerschaft mit Salesforce erm\u00f6glichen einen Single-View auf unsere Fans, wodurch wir das Cross- und <a adhocenable=\"false\" href=\"https:\/\/www.salesforce.com\/de\/learning-centre\/sales\/upselling\/\">Upselling<\/a> jetzt tats\u00e4chlich planen k\u00f6nnen. Gleichzeitig sind im B2B-Bereich unsere Brand-Partner auch sehr an den Aktivit\u00e4ten unserer Fans interessiert. Die Consumer-L\u00f6sung bietet uns die M\u00f6glichkeit, unsere Kunden besser zu segmentieren und zu adressieren. Dar\u00fcber hinaus sind wir in der Lage, f\u00fcr unsere Business-Partner authentische Produkte zu kreieren, damit auch sie unsere Fans besser verstehen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">David Hiltscher f\u00fcgt an: \u201cLetztendlich bildet Salesforce das Fundament, um unsere globalen Fan-Beziehungen besser zu monetarisieren, denn hier gibt es noch viel Optimierungspotenzial. In traditionellen Sportarten wie Baseball oder Football liegt die Monetarisierung bei 50 bis 70 US-Dollar pro Fan im Jahr, bei E-Sport liegen wir aktuell zwischen 50 US-Dollar-Cent und 5 US-Dollar. Das Potential ist gro\u00df und wir sind auf einem guten Weg, es auszusch\u00f6pfen.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr weitere Informationen besuchen Sie unsere <a adhocenable=\"false\" href=\"https:\/\/www.salesforce.com\/de\/products\/marketing-cloud\/overview\/\">Marketing Cloud Seite<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.salesforce.com\/de\/customer-success-stories\/esl-gaming\/\"><img decoding=\"async\" src=\"https:\/\/salesforce-news-blog-develop.go-vip.net\/wp-content\/uploads\/sites\/7\/2023\/06\/gesamte_erfolgsgeschichte.jpg\" alt=\"\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Was ist ein <a adhocenable=\"false\" href=\"https:\/\/www.salesforce.com\/de\/blog\/2022\/01\/so-what-is-a-trailblazer.html\">Trailblazer<\/a>? Finden Sie heraus, was einen Trailblazer ausmacht und warum er ein einzigartiger Bestandteil unserer Unternehmenskultur ist.<span id=\"authorRoot\" path=\"\/content\/blogs\/de\/de\/authors\/\"><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lesen Sie in dieser Trailblazer Story, wie ESL Gaming dank Salesforce sein weltweites Gesch\u00e4ft transformiert und professionalisiert.<\/p>\n","protected":false},"author":1,"featured_media":1469,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sf_justforyou_enable_alt":true,"optimizely_content_id":"","post_meta_title":"","ai_synopsis":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"sf_topic":[72],"sf_content_type":[],"blog":[534],"coauthors":[73],"class_list":["post-1471","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","sf_topic-trailblazer-story","blog-trailblazer-story"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Trailblazer Blog: ESL Gaming - Salesforce<\/title>\n<meta name=\"description\" content=\"Lesen Sie in dieser Trailblazer Story, wie ESL Gaming dank Salesforce sein weltweites Gesch\u00e4ft transformiert und professionalisiert.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salesforce.com\/de\/blog\/trailblazer-esl-gaming\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trailblazer Blog: Wie ESL Gaming sein weltweites Gesch\u00e4ft transformiert und professionalisiert\" \/>\n<meta property=\"og:description\" content=\"Lesen Sie in dieser Trailblazer Story, wie ESL Gaming dank Salesforce sein weltweites Gesch\u00e4ft transformiert und professionalisiert.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salesforce.com\/de\/blog\/trailblazer-esl-gaming\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-06T18:53:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-04T09:06:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/trailblazer_story_ESL_gaming.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1152\" \/>\n\t<meta property=\"og:image:height\" content=\"648\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Markus Nigl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Markus Nigl\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/trailblazer-esl-gaming\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/trailblazer-esl-gaming\\\/\"},\"author\":[{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/#\\\/schema\\\/person\\\/image\\\/3b00c55a568031371530d715ec71224f\"}],\"headline\":\"Trailblazer Blog: Wie ESL Gaming sein weltweites Gesch\u00e4ft transformiert und professionalisiert\",\"datePublished\":\"2023-06-06T18:53:23+00:00\",\"dateModified\":\"2023-07-04T09:06:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/trailblazer-esl-gaming\\\/\"},\"wordCount\":580,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/trailblazer-esl-gaming\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2023\\\/06\\\/trailblazer_story_ESL_gaming.jpg\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/trailblazer-esl-gaming\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/trailblazer-esl-gaming\\\/\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/trailblazer-esl-gaming\\\/\",\"name\":\"Trailblazer Blog: ESL Gaming - Salesforce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/trailblazer-esl-gaming\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/trailblazer-esl-gaming\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2023\\\/06\\\/trailblazer_story_ESL_gaming.jpg\",\"datePublished\":\"2023-06-06T18:53:23+00:00\",\"dateModified\":\"2023-07-04T09:06:20+00:00\",\"description\":\"Lesen Sie in dieser Trailblazer Story, wie ESL Gaming dank Salesforce sein weltweites Gesch\u00e4ft transformiert und professionalisiert.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/trailblazer-esl-gaming\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/trailblazer-esl-gaming\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/trailblazer-esl-gaming\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2023\\\/06\\\/trailblazer_story_ESL_gaming.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2023\\\/06\\\/trailblazer_story_ESL_gaming.jpg\",\"width\":1152,\"height\":648,\"caption\":\"Trailblazer Blog ESL Gaming und Salesforce\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/trailblazer-esl-gaming\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trailblazer Blog: Wie ESL Gaming sein weltweites Gesch\u00e4ft transformiert und professionalisiert\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/\",\"name\":\"Salesforce\",\"description\":\"Lesen Sie die neuesten Tipps und Trends f\u00fcr Ihr Business - rund um die Themen Marketing, Vertrieb, Service, IT und Commerce.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/#organization\"},\"alternateName\":\"Salesforce\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/#organization\",\"name\":\"Salesforce\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Salesforce\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/#\\\/schema\\\/person\\\/image\\\/3b00c55a568031371530d715ec71224f\",\"name\":\"Markus Nigl\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/#\\\/schema\\\/person\\\/image\\\/7be1325186c358cd23f209392320a696\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2023\\\/07\\\/Markus-Nigl.png?w=150&h=150&crop=1\",\"contentUrl\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2023\\\/07\\\/Markus-Nigl.png?w=150&h=150&crop=1\",\"width\":150,\"height\":150,\"caption\":\"Markus Nigl\"},\"description\":\"Als Senior Manager Customer Marketing verantwortet Markus bei Salesforce das Trailblazer Marketing. Sein Wirkungsbereich umfasst Kundenprogramme und Konzepte im Bereich Storytelling und Kundenreferenzen. Markus ist seit mehr als 20 Jahren im IT B2B-Bereich t\u00e4tig mit unterschiedlichen T\u00e4tigkeitsschwerpunkten wie Marketing &amp; Kommunikation, Partner-Management, Pre-Sales und Business Development.\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/de\\\/blog\\\/author\\\/markus-nigl\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Trailblazer Blog: ESL Gaming - Salesforce","description":"Lesen Sie in dieser Trailblazer Story, wie ESL Gaming dank Salesforce sein weltweites Gesch\u00e4ft transformiert und professionalisiert.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salesforce.com\/de\/blog\/trailblazer-esl-gaming\/","og_locale":"de_DE","og_type":"article","og_title":"Trailblazer Blog: Wie ESL Gaming sein weltweites Gesch\u00e4ft transformiert und professionalisiert","og_description":"Lesen Sie in dieser Trailblazer Story, wie ESL Gaming dank Salesforce sein weltweites Gesch\u00e4ft transformiert und professionalisiert.","og_url":"https:\/\/www.salesforce.com\/de\/blog\/trailblazer-esl-gaming\/","og_site_name":"Salesforce","article_published_time":"2023-06-06T18:53:23+00:00","article_modified_time":"2023-07-04T09:06:20+00:00","og_image":[{"width":1152,"height":648,"url":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/trailblazer_story_ESL_gaming.jpg","type":"image\/jpeg"}],"author":"Markus Nigl","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten","Written by":"Markus Nigl"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salesforce.com\/de\/blog\/trailblazer-esl-gaming\/#article","isPartOf":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/trailblazer-esl-gaming\/"},"author":[{"@id":"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/person\/image\/3b00c55a568031371530d715ec71224f"}],"headline":"Trailblazer Blog: Wie ESL Gaming sein weltweites Gesch\u00e4ft transformiert und professionalisiert","datePublished":"2023-06-06T18:53:23+00:00","dateModified":"2023-07-04T09:06:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/trailblazer-esl-gaming\/"},"wordCount":580,"commentCount":0,"publisher":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/#organization"},"image":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/trailblazer-esl-gaming\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/trailblazer_story_ESL_gaming.jpg","inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.salesforce.com\/de\/blog\/trailblazer-esl-gaming\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.salesforce.com\/de\/blog\/trailblazer-esl-gaming\/","url":"https:\/\/www.salesforce.com\/de\/blog\/trailblazer-esl-gaming\/","name":"Trailblazer Blog: ESL Gaming - Salesforce","isPartOf":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/trailblazer-esl-gaming\/#primaryimage"},"image":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/trailblazer-esl-gaming\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/trailblazer_story_ESL_gaming.jpg","datePublished":"2023-06-06T18:53:23+00:00","dateModified":"2023-07-04T09:06:20+00:00","description":"Lesen Sie in dieser Trailblazer Story, wie ESL Gaming dank Salesforce sein weltweites Gesch\u00e4ft transformiert und professionalisiert.","breadcrumb":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/trailblazer-esl-gaming\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salesforce.com\/de\/blog\/trailblazer-esl-gaming\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.salesforce.com\/de\/blog\/trailblazer-esl-gaming\/#primaryimage","url":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/trailblazer_story_ESL_gaming.jpg","contentUrl":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/trailblazer_story_ESL_gaming.jpg","width":1152,"height":648,"caption":"Trailblazer Blog ESL Gaming und Salesforce"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salesforce.com\/de\/blog\/trailblazer-esl-gaming\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salesforce.com\/de\/blog\/"},{"@type":"ListItem","position":2,"name":"Trailblazer Blog: Wie ESL Gaming sein weltweites Gesch\u00e4ft transformiert und professionalisiert"}]},{"@type":"WebSite","@id":"https:\/\/www.salesforce.com\/de\/blog\/#website","url":"https:\/\/www.salesforce.com\/de\/blog\/","name":"Salesforce","description":"Lesen Sie die neuesten Tipps und Trends f\u00fcr Ihr Business - rund um die Themen Marketing, Vertrieb, Service, IT und Commerce.","publisher":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/#organization"},"alternateName":"Salesforce","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salesforce.com\/de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.salesforce.com\/de\/blog\/#organization","name":"Salesforce","url":"https:\/\/www.salesforce.com\/de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Salesforce"},"image":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/person\/image\/3b00c55a568031371530d715ec71224f","name":"Markus Nigl","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/person\/image\/7be1325186c358cd23f209392320a696","url":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/07\/Markus-Nigl.png?w=150&h=150&crop=1","contentUrl":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/07\/Markus-Nigl.png?w=150&h=150&crop=1","width":150,"height":150,"caption":"Markus Nigl"},"description":"Als Senior Manager Customer Marketing verantwortet Markus bei Salesforce das Trailblazer Marketing. Sein Wirkungsbereich umfasst Kundenprogramme und Konzepte im Bereich Storytelling und Kundenreferenzen. Markus ist seit mehr als 20 Jahren im IT B2B-Bereich t\u00e4tig mit unterschiedlichen T\u00e4tigkeitsschwerpunkten wie Marketing &amp; Kommunikation, Partner-Management, Pre-Sales und Business Development.","url":"https:\/\/www.salesforce.com\/de\/blog\/author\/markus-nigl\/"}]}},"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Salesforce","distributor_original_site_url":"https:\/\/www.salesforce.com\/de\/blog","push-errors":false,"jetpack_featured_media_url":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/trailblazer_story_ESL_gaming.jpg","primary_topic":{"term_id":72,"name":"Trailblazer Story","slug":"trailblazer-story","term_group":0,"term_taxonomy_id":72,"taxonomy":"sf_topic","description":"Salesforce lebt durch seine Trailblazer! Trailblazer sind Pionier:innen, Innovator:innen und Macher:innen, die mit Salesforce neue Wege gehen und ihre Unternehmen voranbringen. Lassen Sie sich von ihren spannenden Geschichten inspirieren.","parent":0,"count":106,"filter":"raw"},"featured_image_url":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/trailblazer_story_ESL_gaming.jpg?w=1024","_links":{"self":[{"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/posts\/1471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/comments?post=1471"}],"version-history":[{"count":3,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/posts\/1471\/revisions"}],"predecessor-version":[{"id":4433,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/posts\/1471\/revisions\/4433"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/media\/1469"}],"wp:attachment":[{"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/media?parent=1471"}],"wp:term":[{"taxonomy":"sf_topic","embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/sf_topic?post=1471"},{"taxonomy":"sf_content_type","embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/sf_content_type?post=1471"},{"taxonomy":"blog","embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/blog?post=1471"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/coauthors?post=1471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}