{"id":1510,"date":"2022-06-07T18:53:00","date_gmt":"2023-06-06T18:53:53","guid":{"rendered":"https:\/\/www.salesforce.com\/?p=1510"},"modified":"2023-07-03T15:14:49","modified_gmt":"2023-07-03T15:14:49","slug":"grosse-leistung-kleine-teams","status":"publish","type":"post","link":"https:\/\/www.salesforce.com\/de\/blog\/grosse-leistung-kleine-teams\/","title":{"rendered":"5\u00a0Schritte zu gro\u00dfer Leistung mit kleinen Teams"},"content":{"rendered":"\n<p>Gesch\u00e4ftskunden erwarten heute mehr als nur ein gutes Produkt oder guten Service. Sie verlangen\u00a0eine bessere Customer Experience. F\u00fcr KMUs ist das die Chance, gr\u00f6\u00dfere Rivalen auszustechen. Gro\u00dfkonzerne haben scheinbar unbegrenzte Budgets und\u00a0Ressourcen.\u00a0Mit ihnen in Wettbewerb zu treten, kann ganz sch\u00f6n einsch\u00fcchternd sein. Doch mit einer gut durchdachten Technologiestrategie gestalten Kleinunternehmen hervorragende Customer Experiences, mit denen gro\u00dfe Unternehmen nicht mithalten k\u00f6nnen.<\/p>\n\n\n\n<p>Mit einem Kundenmanagement-Tool wie\u00a0CRM\u00a0als Grundlage f\u00fcr erstklassige Einkaufserlebnisse kommt Ihr Kleinunternehmen ganz gro\u00df heraus.\u00a0Die richtige Automatisierung erm\u00f6glicht es Ihnen, auch im kleineren Team hochgradig personalisierte Customer Experiences zu entwickeln.<\/p>\n\n\n\n<p>Mit diesen f\u00fcnf Schritten erzielen Kleinunternehmen durch CRM auch ohne ein gro\u00dfes Team Riesenerfolge:<\/p>\n\n\n\n<p><b>1. Marketingautomatisierung zum Gestalten erstklassiger Einkaufserlebnisse einsetzen<\/b><\/p>\n\n\n\n<p>Marketingautomatisierung f\u00fchrt zu einer besseren Customer Experience: Sie sprechen potenzielle Kunden gezielt mit relevanten Inhalten und Angeboten an, anstatt sie willk\u00fcrlich mit E-Mails und Anrufen zu bombardieren. Indem Sie potenziellen Kunden hochwertige Inhalte pr\u00e4sentieren, f\u00fchren Sie den Vertriebsmitarbeitern qualifizierte und kaufbereite Leads zu. Damit wiederum f\u00f6rdern Sie den Umsatz.<\/p>\n\n\n\n<p>Fassen Sie die\u00a0Marketingautomatisierung,\u00a0das Lead-Nurturing und den\u00a0Vertrieb\u00a0auf einer Plattform zusammen, sodass Ihr gesamtes Team\u00a0\u2013 Marketing und Sales\u00a0\u2013 stets auf dem Laufenden ist.\u00a0Mit gemeinsam genutzten Kundendatens\u00e4tzen, automatischer Lead-Bewertung und Tools f\u00fcr die Datenanalyse sieht jeder Mitarbeiter genau, welche Kundendatens\u00e4tze und Verkaufstechniken funktionieren und welche nicht \u2013 und Ihr gesamtes Unternehmen arbeitet auf dieselben Ziele hin.<\/p>\n\n\n\n<p><b>2. Das richtige Einkaufserlebnis planen<\/b><\/p>\n\n\n\n<p>Der alte Spruch stimmt durchaus: Wer nicht plant, plant sein Scheitern. Sie m\u00fcssen klare Ziele und Erwartungen f\u00fcr Ihr Team abstecken und mit einem Vertriebsplan genau vorgeben, wie sie erreicht werden.&nbsp;<\/p>\n\n\n\n<p>Entwickeln Sie mit\u00a0<a adhocenable=\"false\" href=\"https:\/\/www.salesforce.com\/blog\/2014\/02\/sales-playbooks-crms-gp.html?d=7010M000000uhLmQAI\">\u00fcbersichtlichen Playbooks f\u00fcr den Vertrieb<\/a>\u00a0einen einheitlichen Einkaufsprozess f\u00fcr alle potenziellen Kunden. Strukturieren Sie Vertriebsgebiete so, dass nicht mehrere Vertriebsmitarbeiter dasselbe Unternehmen kontaktieren und schlimmstenfalls sogar denselben potenziellen Kunden unterschiedliche Produkte oder Opportunities anbieten. Legen Sie Ziele fest, um Ihrem Team konkrete Meilensteine zu nennen, auf die es hinarbeiten kann \u2013 f\u00fcr den Monat, das Quartal und das Jahr.\u00a0<\/p>\n\n\n\n<p><b>3. Dem Vertriebsteam die Tools zum Umsetzen des richtigen Einkaufserlebnisses an die Hand geben<\/b><\/p>\n\n\n\n<p>Ihre Vertriebsmitarbeiter ben\u00f6tigen die richtigen Tools, um ihre Aufgaben zu erledigen. Dazu geh\u00f6rt ein m\u00f6glichst einheitlicher und effizienter Kaufprozess f\u00fcr Kunden. Ein CRM-System dient als zentrale Informationsquelle Ihres Unternehmens. So k\u00f6nnen alle Mitarbeiter ihre Aufgaben effizient erledigen und beim Kundenkontakt eine gemeinsame Strategie verfolgen.<\/p>\n\n\n\n<p>Pflegen Sie mehr Daten zu Produkten und Preisb\u00fcchern in Ihr CRM-System ein und automatisieren Sie damit Vertriebsprozesse wie die Angebotserstellung.&nbsp;Eine gute CRM-Plattform kann den gesamten Kaufprozess f\u00fcr Kunden beschleunigen \u2013 und je weniger Zeit diese damit verbringen, auf Angebote zu warten, umso mehr Zeit haben sie, um mit Ihnen Gesch\u00e4fte zu t\u00e4tigen.<\/p>\n\n\n\n<p>Mehr Daten in Ihrem CRM-System erm\u00f6glichen Ihnen auch den verst\u00e4rkten Einsatz\u00a0k\u00fcnstlicher Intelligenz\u00a0(KI) f\u00fcr Ihre Gesch\u00e4fte. KI lebt von Daten; sie durchk\u00e4mmt Kundendaten und verarbeitet Verkaufszahlen, um Erkenntnisse zutage zu f\u00f6rdern, die bessere gesch\u00e4ftliche Entscheidungen erm\u00f6glichen. Sie sorgt daf\u00fcr, dass Ihre Vertriebsmitarbeiter den richtigen Kunden die richtigen Produkte verkaufen. CRM-basierte KI-Tools k\u00f6nnen Kundendaten mit dem Produktinventar und der Produktpipeline abgleichen. Damit erm\u00f6glichen sie es den Vertriebsmitarbeitern, kundenspezifische Cross-Selling-, Upselling- und neue Sales-Opportunities zu erkennen.<\/p>\n\n\n\n<p><b>4. Den Vertrieb durch Partner st\u00e4rken<\/b><\/p>\n\n\n\n<p>Vier Augen sehen mehr als zwei&nbsp;\u2013 also sollten Sie Ihre Verkaufsbem\u00fchungen durch Partnerschaften verst\u00e4rken. Mit dem richtige Partner profitieren Sie von den Vorteilen eines gr\u00f6\u00dferen Vertriebsteams, ohne die Mitarbeiterzahl erh\u00f6hen zu m\u00fcssen. Entscheidend ist, dass alle potenziellen Kunden dieselbe erstklassige Experience genie\u00dfen&nbsp;\u2013 ganz gleich, ob im Kontakt mit Ihrem internen Team oder mit den Vertriebsmitarbeitern Ihres Partners.<\/p>\n\n\n\n<p>Setzen Sie ein CRM-System ein, um Ihre Partner und Ihre Mitarbeiter im Hinblick auf Sales-Playbooks oder kundenorientierte Datenbest\u00e4nde auf einen gemeinsamen Nenner zu bringen. CRM-Plattformen schaffen eine zentrale Informationsquelle im Unternehmen, und diese Funktion l\u00e4sst sich m\u00fchelos auf Partnerteams ausweiten. Sie k\u00f6nnen die Verkaufsbem\u00fchungen Ihres Partners ebenso wie die eigenen \u00fcber eine zentrale Plattform nachverfolgen, im Auge behalten, welche Mitarbeiter welche potenziellen Kunden betreuen, und sicherstellen, dass alle die aktuellsten Marketingmaterialien verwenden.&nbsp;<\/p>\n\n\n\n<p>CRM-Plattformen erfassen nicht nur den Echtzeitfortschritt, sondern k\u00f6nnen auch die Daten so aufbereiten, dass ersichtlich wird, wie erfolgreich sich eine Partnerschaft entwickelt und wie sie im Vergleich zu fr\u00fcheren Partnerschaften abschneidet. Sie k\u00f6nnen Kampagnen und Trends ermitteln, die sich amortisiert haben, aber auch Partner identifizieren, die hinter den Erwartungen zur\u00fcckgeblieben sind. CRM-Plattformen sind also ein ideales Tool f\u00fcr die Verwaltung von Vertriebspartnerschaften.<\/p>\n\n\n\n<p><b>5. Mit Automatisierung eine optimale After-Sales-Experience schaffen<\/b><\/p>\n\n\n\n<p>Technologien wie CRM k\u00f6nnen Mitarbeiter unterst\u00fctzen, doch ihr gr\u00f6\u00dfter Vorteil besteht darin, dass sie einen rund um die Uhr verf\u00fcgbaren und personalisierten\u00a0Kundenservice\u00a0erm\u00f6glichen\u00a0\u2013\u00a0selbst wenn Sie und Ihr Team gerade nicht im Einsatz sind. Die Ausweitung des Service durch die Investition in Technologien anstatt in die Mitarbeiterzahl zahlt sich gerade f\u00fcr Kleinunternehmen aus.\u00a0<\/p>\n\n\n\n<p>Dabei gilt es, vor allem zwei Aspekte zu ber\u00fccksichtigen:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li> <span style=\"color: var(--c-nero); font-family: var(--f-secondary); font-size: 1rem; letter-spacing: 0.0012em;\">Investition in zuverl\u00e4ssige\u00a0<\/span>Self-Service<span style=\"color: var(--c-nero); font-family: var(--f-secondary); font-size: 1rem; letter-spacing: 0.0012em;\">\u00a0-Communities. Moderne Kunden sind st\u00e4ndig online und m\u00f6chten Probleme lieber selbst l\u00f6sen, als sich an den Support zu wenden. Mit Self-Service-Communities stellen Sie Ihren Kunden Anleitungen, Produktwissen und FAQ-Seiten rund um die Uhr bereit. Viele CRM-Plattformen umfassen integrierte Self-Service-Communities, die sich problemlos einrichten lassen und Ihre Servicemitarbeiter informieren, wenn Kunden pers\u00f6nliche Beratung bei der L\u00f6sung ihres Problems ben\u00f6tigen.<\/span> <\/li>\n\n\n\n<li> <span style=\"color: var(--c-nero); font-family: var(--f-secondary); font-size: 1rem; letter-spacing: 0.0012em;\">Entlasten Sie Ihre Servicemitarbeiter mit Service-Bots.\u00a0<\/span>Service-Chatbots<span style=\"color: var(--c-nero); font-family: var(--f-secondary); font-size: 1rem; letter-spacing: 0.0012em;\">\u00a0k\u00f6nnen dabei helfen, die L\u00fccke zwischen Self-Service und dem pers\u00f6nlichen Gespr\u00e4ch mit einem Servicemitarbeiter zu \u00fcberbr\u00fccken. Sie liefern personalisierten Service rund um die Uhr. Chatbots sind seit ihrer Einf\u00fchrung viel besser \u2013\u00a0und kosteng\u00fcnstiger\u00a0\u2013\u00a0geworden und lassen sich an das Wachstum Ihres Unternehmens anpassen. Sie k\u00f6nnen also auch bei umfangreichen Produktkatalogen und komplexen Kundenanliegen eingesetzt werden.<\/span> <\/li>\n<\/ul>\n\n\n\n<p>Suchen Sie das passende Kundenmanagement-Tool f\u00fcr Ihr wachsendes Unternehmen? Nutzen Sie die CRM-Plattform f\u00fcr kleine Unternehmen von <a adhocenable=\"false\" href=\"https:\/\/www.salesforce.com\/eu\/solutions\/small-business-solutions\/overview\/\">Salesforce<\/a>.<\/p>\n\n\n\n<p> <span id=\"authorRoot\" path=\"\/content\/blogs\/de\/de\/authors\/\"><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hier erfahren Sie, wie Ihr Kleinunternehmen ganz gro\u00df herauskommt: mit einem Kundenmanagement-Tool wie CRM als Grundlage f\u00fcr erstklassige Einkaufserlebnisse.<\/p>\n","protected":false},"author":1,"featured_media":1509,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sf_justforyou_enable_alt":true,"optimizely_content_id":"865507882bb54de79e96a2ef2f552099","post_meta_title":"","ai_synopsis":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"sf_topic":[139,33],"sf_content_type":[],"blog":[529,412],"coauthors":[20],"class_list":["post-1510","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","sf_topic-salesforce-platform","sf_topic-startups","blog-startups","blog-salesforce-platform"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>5\u00a0Schritte zu gro\u00dfer Leistung mit kleinen Teams - Salesforce<\/title>\n<meta name=\"description\" content=\"Hier erfahren Sie, wie Ihr Kleinunternehmen ganz gro\u00df herauskommt: mit einem Kundenmanagement-Tool wie CRM als Grundlage f\u00fcr erstklassige Einkaufserlebnisse.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salesforce.com\/de\/blog\/grosse-leistung-kleine-teams\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5\u00a0Schritte zu gro\u00dfer Leistung mit kleinen Teams\" \/>\n<meta property=\"og:description\" content=\"Hier erfahren Sie, wie Ihr Kleinunternehmen ganz gro\u00df herauskommt: mit einem Kundenmanagement-Tool wie CRM als Grundlage f\u00fcr erstklassige Einkaufserlebnisse.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salesforce.com\/de\/blog\/grosse-leistung-kleine-teams\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-06T18:53:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-03T15:14:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/grosse-leistung-kleine-teams.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redaktion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"digital-delivery-operations7076\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 Minuten\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Redaktion\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/grosse-leistung-kleine-teams\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/grosse-leistung-kleine-teams\/\"},\"author\":[{\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/person\/image\/1d10ab9722894ac201eaf2c479e36f79\"}],\"headline\":\"5\u00a0Schritte zu gro\u00dfer Leistung mit kleinen Teams\",\"datePublished\":\"2023-06-06T18:53:53+00:00\",\"dateModified\":\"2023-07-03T15:14:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/grosse-leistung-kleine-teams\/\"},\"wordCount\":1009,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/grosse-leistung-kleine-teams\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/grosse-leistung-kleine-teams.png\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.salesforce.com\/de\/blog\/grosse-leistung-kleine-teams\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/grosse-leistung-kleine-teams\/\",\"url\":\"https:\/\/www.salesforce.com\/de\/blog\/grosse-leistung-kleine-teams\/\",\"name\":\"5\u00a0Schritte zu gro\u00dfer Leistung mit kleinen Teams - Salesforce\",\"isPartOf\":{\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/grosse-leistung-kleine-teams\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/grosse-leistung-kleine-teams\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/grosse-leistung-kleine-teams.png\",\"datePublished\":\"2023-06-06T18:53:53+00:00\",\"dateModified\":\"2023-07-03T15:14:49+00:00\",\"description\":\"Hier erfahren Sie, wie Ihr Kleinunternehmen ganz gro\u00df herauskommt: mit einem Kundenmanagement-Tool wie CRM als Grundlage f\u00fcr erstklassige Einkaufserlebnisse.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/grosse-leistung-kleine-teams\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.salesforce.com\/de\/blog\/grosse-leistung-kleine-teams\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/grosse-leistung-kleine-teams\/#primaryimage\",\"url\":\"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/grosse-leistung-kleine-teams.png\",\"contentUrl\":\"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/grosse-leistung-kleine-teams.png\",\"width\":600,\"height\":400,\"caption\":\"ein Team sitzt zusammen und eine Person schreibt an ein Whiteboard\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/grosse-leistung-kleine-teams\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.salesforce.com\/de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5\u00a0Schritte zu gro\u00dfer Leistung mit kleinen Teams\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/#website\",\"url\":\"https:\/\/www.salesforce.com\/de\/blog\/\",\"name\":\"Salesforce\",\"description\":\"Lesen Sie die neuesten Tipps und Trends f\u00fcr Ihr Business - rund um die Themen Marketing, Vertrieb, Service, IT und Commerce.\",\"publisher\":{\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/#organization\"},\"alternateName\":\"Salesforce\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.salesforce.com\/de\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/#organization\",\"name\":\"Salesforce\",\"url\":\"https:\/\/www.salesforce.com\/de\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Salesforce\"},\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/person\/image\/1d10ab9722894ac201eaf2c479e36f79\",\"name\":\"Redaktion\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/person\/image\/8e9bcdb7af1799e5d0dfeee36e7f8079\",\"url\":\"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/redaktion.png?w=150&h=150&crop=1\",\"contentUrl\":\"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/redaktion.png?w=150&h=150&crop=1\",\"width\":\"150\",\"height\":\"150\",\"caption\":\"Redaktion\"},\"description\":\"Unser Redaktionsteam versorgt Sie regelm\u00e4\u00dfig mit den neuesten Trends, Tipps &amp; Tricks aus der Salesforce Welt.\",\"url\":\"https:\/\/www.salesforce.com\/de\/blog\/author\/redaktion\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"5\u00a0Schritte zu gro\u00dfer Leistung mit kleinen Teams - Salesforce","description":"Hier erfahren Sie, wie Ihr Kleinunternehmen ganz gro\u00df herauskommt: mit einem Kundenmanagement-Tool wie CRM als Grundlage f\u00fcr erstklassige Einkaufserlebnisse.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salesforce.com\/de\/blog\/grosse-leistung-kleine-teams\/","og_locale":"de_DE","og_type":"article","og_title":"5\u00a0Schritte zu gro\u00dfer Leistung mit kleinen Teams","og_description":"Hier erfahren Sie, wie Ihr Kleinunternehmen ganz gro\u00df herauskommt: mit einem Kundenmanagement-Tool wie CRM als Grundlage f\u00fcr erstklassige Einkaufserlebnisse.","og_url":"https:\/\/www.salesforce.com\/de\/blog\/grosse-leistung-kleine-teams\/","og_site_name":"Salesforce","article_published_time":"2023-06-06T18:53:53+00:00","article_modified_time":"2023-07-03T15:14:49+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/grosse-leistung-kleine-teams.png","type":"image\/png"}],"author":"Redaktion","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"digital-delivery-operations7076","Gesch\u00e4tzte Lesezeit":"6 Minuten","Written by":"Redaktion"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salesforce.com\/de\/blog\/grosse-leistung-kleine-teams\/#article","isPartOf":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/grosse-leistung-kleine-teams\/"},"author":[{"@id":"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/person\/image\/1d10ab9722894ac201eaf2c479e36f79"}],"headline":"5\u00a0Schritte zu gro\u00dfer Leistung mit kleinen Teams","datePublished":"2023-06-06T18:53:53+00:00","dateModified":"2023-07-03T15:14:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/grosse-leistung-kleine-teams\/"},"wordCount":1009,"commentCount":0,"publisher":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/#organization"},"image":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/grosse-leistung-kleine-teams\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/grosse-leistung-kleine-teams.png","inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.salesforce.com\/de\/blog\/grosse-leistung-kleine-teams\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.salesforce.com\/de\/blog\/grosse-leistung-kleine-teams\/","url":"https:\/\/www.salesforce.com\/de\/blog\/grosse-leistung-kleine-teams\/","name":"5\u00a0Schritte zu gro\u00dfer Leistung mit kleinen Teams - Salesforce","isPartOf":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/grosse-leistung-kleine-teams\/#primaryimage"},"image":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/grosse-leistung-kleine-teams\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/grosse-leistung-kleine-teams.png","datePublished":"2023-06-06T18:53:53+00:00","dateModified":"2023-07-03T15:14:49+00:00","description":"Hier erfahren Sie, wie Ihr Kleinunternehmen ganz gro\u00df herauskommt: mit einem Kundenmanagement-Tool wie CRM als Grundlage f\u00fcr erstklassige Einkaufserlebnisse.","breadcrumb":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/grosse-leistung-kleine-teams\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salesforce.com\/de\/blog\/grosse-leistung-kleine-teams\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.salesforce.com\/de\/blog\/grosse-leistung-kleine-teams\/#primaryimage","url":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/grosse-leistung-kleine-teams.png","contentUrl":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/grosse-leistung-kleine-teams.png","width":600,"height":400,"caption":"ein Team sitzt zusammen und eine Person schreibt an ein Whiteboard"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salesforce.com\/de\/blog\/grosse-leistung-kleine-teams\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salesforce.com\/de\/blog\/"},{"@type":"ListItem","position":2,"name":"5\u00a0Schritte zu gro\u00dfer Leistung mit kleinen Teams"}]},{"@type":"WebSite","@id":"https:\/\/www.salesforce.com\/de\/blog\/#website","url":"https:\/\/www.salesforce.com\/de\/blog\/","name":"Salesforce","description":"Lesen Sie die neuesten Tipps und Trends f\u00fcr Ihr Business - rund um die Themen Marketing, Vertrieb, Service, IT und Commerce.","publisher":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/#organization"},"alternateName":"Salesforce","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salesforce.com\/de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.salesforce.com\/de\/blog\/#organization","name":"Salesforce","url":"https:\/\/www.salesforce.com\/de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Salesforce"},"image":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/person\/image\/1d10ab9722894ac201eaf2c479e36f79","name":"Redaktion","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/person\/image\/8e9bcdb7af1799e5d0dfeee36e7f8079","url":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/redaktion.png?w=150&h=150&crop=1","contentUrl":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/redaktion.png?w=150&h=150&crop=1","width":"150","height":"150","caption":"Redaktion"},"description":"Unser Redaktionsteam versorgt Sie regelm\u00e4\u00dfig mit den neuesten Trends, Tipps &amp; Tricks aus der Salesforce Welt.","url":"https:\/\/www.salesforce.com\/de\/blog\/author\/redaktion\/"}]}},"jetpack_featured_media_url":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/grosse-leistung-kleine-teams.png","jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Salesforce","distributor_original_site_url":"https:\/\/www.salesforce.com\/de\/blog","push-errors":false,"primary_topic":{"term_id":33,"name":"Start-ups","slug":"startups","term_group":0,"term_taxonomy_id":33,"taxonomy":"sf_topic","description":"","parent":0,"count":55,"filter":"raw"},"featured_image_url":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/grosse-leistung-kleine-teams.png?w=600","_links":{"self":[{"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/posts\/1510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/comments?post=1510"}],"version-history":[{"count":4,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/posts\/1510\/revisions"}],"predecessor-version":[{"id":4390,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/posts\/1510\/revisions\/4390"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/media\/1509"}],"wp:attachment":[{"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/media?parent=1510"}],"wp:term":[{"taxonomy":"sf_topic","embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/sf_topic?post=1510"},{"taxonomy":"sf_content_type","embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/sf_content_type?post=1510"},{"taxonomy":"blog","embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/blog?post=1510"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/coauthors?post=1510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}