{"id":874,"date":"2021-01-28T18:44:00","date_gmt":"2023-06-06T18:44:39","guid":{"rendered":"https:\/\/www.salesforce.com\/?p=874"},"modified":"2023-07-05T16:38:21","modified_gmt":"2023-07-05T16:38:21","slug":"vom-spielplatz-ins-management","status":"publish","type":"post","link":"https:\/\/www.salesforce.com\/de\/blog\/vom-spielplatz-ins-management\/","title":{"rendered":"Vom Spielplatz ins Management \u2013 aus dem Leben berufst\u00e4tiger M\u00fctter"},"content":{"rendered":"\n<p>Als frischgebackene Mutter, die ihre Arbeit bei Salesforce inzwischen wieder aufgenommen hat, war ich neugierig darauf, wie die anderen M\u00fctter das alles unter einen Hut bekommen: Baby, Arbeit, Baby, Arbeit, Baby, Schlaf. Ich fragte mich auch, wie diese Frauen ihre beruflichen F\u00e4higkeiten auf dem neuesten Stand halten? Denn wenn man f\u00fcr sechs und mehr Monate aus dem Berufsleben ausscheidet, ist die Welt anders \u2013 nicht nur in Zeiten wie diesen. Ich schaute mich deshalb in unserer deutschen Ohana um und sah viele starke Frauen, erfolgreiche M\u00fctter \u2013 Menschen, die scheinbar alles unter Kontrolle haben. Und ich fragte mich, wie die das wohl machen? Was ist ihr Erfolgsgeheimnis&#8230; und wie schaffe ich das auch?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-einen-einfachen-weg-zum-erfolg-gibt-es-leider-nicht\"><b>Einen einfachen Weg zum Erfolg gibt es leider nicht<\/b><\/h2>\n\n\n\n<p>Ich wandte mich deshalb an Liesel Klokkers, lange Zeit die einzige weibliche F\u00fchrungskraft in unserem Solution Engineering-Team. Sie leitet eine unglaublich erfolgreiche Gruppe von 29 L\u00f6sungsentwicklern, ist die einzige Frau in diesem Bereich und hat drei wunderbare Kinder. Ich habe ihre Hartn\u00e4ckigkeit und Belastbarkeit immer bewundert. Daher war dieser Blogbeitrag f\u00fcr mich eine Gelegenheit, etwas \u00fcber ihr Erfolgsgeheimnis zu erfahren. Als ich das Gespr\u00e4ch mit Liesel begann, wurde mir klar, dass ihr Weg alles andere als einfach war. Im Gegenteil: Sie musste etliche H\u00fcrden \u00fcberwinden, um so weit zu kommen, wie sie heute ist. Vieles von dem, was sie sagte, hat mir imponiert und die Notwendigkeit unterstrichen, dass wir unsere Stimme erheben und uns gegenseitig als Verb\u00fcndete zur Seite stehen sollten. Wie die meisten von uns wusste auch Liesel nicht, was sie nach der Schule studieren sollte. Ihr Vater schlug Informatik vor, da er wusste, dass dieser Beruf sp\u00e4ter viele T\u00fcren \u00f6ffnen w\u00fcrde. Obwohl Liesel dieses Fach nicht besonders lag und sie das Gef\u00fchl hatte, nicht dazuzugeh\u00f6ren, da es kaum Frauen in ihrem Studiengang gab, blieb sie hartn\u00e4ckig und gab nicht auf. Schon da musste sie sich gegen\u00fcber ihren m\u00e4nnlichen Mitsch\u00fclern immer wieder beweisen. Nach ihrem Studium stie\u00df sie auf eine Anzeige f\u00fcr Trainees bei Oracle, auf die sie sich bewarb und auch tats\u00e4chlich angenommen wurde.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-alte-normalitat-kollegen-und-kunden-sind-alle-mannlich\"><b>Alte Normalit\u00e4t: Kollegen und Kunden sind alle m\u00e4nnlich<\/b><\/h2>\n\n\n\n<p>Dieses Programm erm\u00f6glichte es ihr, alle Abteilungen des Unternehmens zu durchlaufen und sich dabei f\u00fcr neue Wege und Denkweisen zu \u00f6ffnen. Der Weg f\u00fchrte sie in die USA, wo sie eine der wenigen Frauen in IT-Funktionen war. Anschlie\u00dfend zog es sie wieder zur\u00fcck nach Deutschland, um bei einem Startup zu arbeiten. Auch dort war sie erneut die einzige weibliche F\u00fchrungskraft \u2013 und die einzige Frau im Solution Engineering. Es kam Liesel jedoch nie in den Sinn, dar\u00fcber gro\u00df nachzudenken. Ihre Kollegen waren m\u00e4nnlich, ebenso wie ihre Kunden \u2013 das war f\u00fcr sie v\u00f6llig normal. Das alles \u00e4nderte sich, als Liesel mit ihrem ersten Sohn schwanger wurde. Keiner in dem Unternehmen wusste, wie man damit umgehen sollte. Es gab keine Programme oder Richtlinien f\u00fcr den Mutterschaftsurlaub. Sie musste um eine Auszeit k\u00e4mpfen, und hatte Schuldgef\u00fchle als sie einfach ausstieg. Dabei hatte sie schnell das Gef\u00fchl, dass man im Unternehmen deswegen auf sie herabschaute.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-klein-beizugeben-ist-keine-option-im-berufsleben\"><b>Klein beizugeben ist keine Option im Berufsleben<\/b><\/h2>\n\n\n\n<p>Aber anstatt aufzugeben und selbst zu k\u00fcndigen, lernte sie schnell: Wenn man etwas erreichen will, man daf\u00fcr k\u00e4mpfen muss. Sie bekam ihren zweiten Sohn \u2013 und arbeitete weiter, auch um sich im Job zu beweisen. Diese Beharrlichkeit und nat\u00fcrlich ihre fachlichen Qualit\u00e4ten zahlten sich aus: Liesel wurde in eine F\u00fchrungsposition bef\u00f6rdert und stieg die Karriereleiter Schritt f\u00fcr Schritt weiter empor. Auch hier gab es Widerst\u00e4nde. Andere M\u00fctter verurteilten sie daf\u00fcr, dass sie ihre Kinder tags\u00fcber bei einem Kinderm\u00e4dchen lie\u00df. Aber die junge Mutter wusste, dass sie unter den gegebenen Umst\u00e4nden eine Entscheidung treffen musste \u2013 damals war es noch viel schwieriger, Karriere zu machen und gleichzeitig den Nachwuchs zu erziehen. Liesel blickt heute trotzdem mit guten Erinnerungen an diese Zeit zur\u00fcck. Denn sie war sehr stolz auf alles, was sie erreicht hatte. Auf all die H\u00fcrden, die sie \u00fcberwinden konnte. Aber sie denkt auch an ihren Burn-out und die unfairen Entscheidungen auf F\u00fchrungsebene, mit denen sie t\u00e4glich zu k\u00e4mpfen hatte. Sie schaffte es nicht zu den Last-Minute-Reiseterminen nach New York. Sie konnte nicht an allen abendlichen Networking-Sitzungen teilnehmen, die f\u00fcr die Karriere so wichtig sind. An zwei Orten gleichzeitig zu sein, wie \u00f6fters verlang, war nicht m\u00f6glich. Und die Anforderung, als F\u00fchrungskraft st\u00e4ndig unterwegs zu sein, belasteten sie sehr. Nach der Geburt ihres dritten Kindes nahm sie deshalb die volle Elternzeit, um gen\u00fcgend Raum zu haben und dar\u00fcber nachzudenken, wie sie den Spagat zwischen Spielplatz und Managementbesser zu bew\u00e4ltigen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-work-life-balance-ist-teil-der-unternehmensphilosophie\"><b>Work-Life-Balance ist Teil der Unternehmensphilosophie<\/b><\/h2>\n\n\n\n<p>Die Entscheidung fiel ihr zwar schwer, aber Liesel beschloss, in ihrer Karriere einen Schritt zur\u00fcckzutreten, da sie mehr f\u00fcr ihre Kinder da sein wollte. Sie konnte sich damals nicht vorstellen, wie sie einen erfolgreichen Aufstieg im Berufsleben schaffen und gleichzeitig die Mutter sein konnte, die sie sein wollte. Nach all ihren Erfahrungen gab es entweder das eine oder das andere. Die Vereinbarkeit von Familie und Beruf wurde zwar schon damals heftig diskutiert, doch in der Realit\u00e4t war es mit der Work-Live-Balance noch nicht so weit her. <\/p>\n\n\n\n<p><img decoding=\"async\" hspace=\"20\" height=\"600px\" width=\"400px\" src=\"https:\/\/salesforce-news-blog-develop.go-vip.net\/wp-content\/uploads\/sites\/7\/2023\/06\/IMG_2435.jpg\"> <\/p>\n\n\n\n<p>Die Wende f\u00fcr sie pers\u00f6nlich kam, als Salesforce an Liesel herantrat, um sie als Mitglied des Solution Engineering-Teams in Deutschland zu gewinnen. Sie verschwieg dem Recruiting-Manager von Anfang an nicht ihre drei j\u00fcngeren Kinder und erz\u00e4hlte ihm, dass sie gerne nachmittags von zu Hause aus t\u00e4tig sein w\u00fcrde. Zu Liesels \u00dcberraschung gab es keine Bedenken gegen\u00fcber diesem Vorschlag und sie erfuhr, dass man bei Salesforce von \u00fcberall aus arbeiten kann und dass Vertrauen und Gleichberechtigung zentrale Werte der Unternehmensphilosophie sind. Liesels Karriere bei Salesforce ging trotz dieser \u201eEinschr\u00e4nkung\u201c steil bergauf. Sie leitete Teams, entwickelte Programme und ist mittlerweile zur Leiterin der Commercial und Invest Solution Engineers in Deutschland und \u00d6sterreich aufgestiegen. Sie sagte mir, dass man durch die Mutterschaft Lektionen f\u00fcrs Leben lernt, die ein theoretisches Studium niemals vermitteln kann \u2013 etwa die F\u00e4higkeit, Empathie zu zeigen, Organisationstalent zu haben und erfolgreich zu verhandeln. Aber auch die Bef\u00e4higung, sich selbst zu entwickeln und mit anderen Menschen gemeinsam zu wachsen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-sein-authentisches-selbst-mit-in-die-arbeit-einbringen\"><b>Sein authentisches Selbst mit in die Arbeit einbringen<\/b><\/h2>\n\n\n\n<p>Die Managerin ist zielstrebig und sie findet immer wieder Wege, damit ihre Teammitglieder nicht \u00fcberfordert werden und einen Burnout erleben m\u00fcssen, so wie sie damals. Sie ist \u00fcberzeugt: Man kann beides haben&nbsp;\u2013 eine Familie und eine Karriere. Auf dem Weg dorthin werde es zwar auch heute noch H\u00fcrden geben, aber man m\u00fcsse stark sein und an seinen Werten festhalten. <\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a56cf2052964&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a56cf2052964\" class=\"wp-block-image wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/salesforce-news-blog-develop.go-vip.net\/wp-content\/uploads\/sites\/7\/2023\/06\/IMG_4107.jpg\" alt=\"\"\/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p>Die Arbeit f\u00fcr Salesforce hat auch mir gezeigt, wie wichtig es ist, sein volles, authentisches Selbst in die Arbeit einzubringen. Es wird zwar bestimmt Zeiten geben, in denen euer Kind Fieber hat und ihr deshalb nicht ins B\u00fcro kommen k\u00f6nnt. Oder in denen ihr etwas aufgrund unvorhergesehener Umst\u00e4nde absagen m\u00fcsst. Ihr solltet aber in der jetzigen Zeit in der Lage zu sein, das auf ehrliche Weise anzusprechen und gemeinsam eine tragbare L\u00f6sung zu finden. Das Gespr\u00e4ch mit Liesel war f\u00fcr mich unglaublich motivierend und inspirierend. Als frischgebackene Mutter habe ich gelernt, dass ich stolz sein und meine \u201eMutterschaft&#8220; auch offen zeigen kann. Ich muss mich nicht schuldig f\u00fchlen, weil ich f\u00fcr meine kranke Tochter nach Hause gehe.&nbsp;<\/p>\n\n\n\n<p>Es gibt mittlerweile so viele neue M\u00f6glichkeiten, sich st\u00e4ndig weiterzubilden und auf dem Laufenden zu bleiben, sogar wenn man mit seinen Kindern auf dem Spielplatz ist und etwas Zeit hat. Unsere Lernplattform Trailhead und moderne Technologie haben es berufst\u00e4tigen M\u00fcttern sehr viel einfacher gemacht, mit den Kolleginnen und Kollegen in Verbindung zu bleiben, ohne um die Welt reisen oder in einem Schulungsraum fern von den eigenen Kindern sitzen zu m\u00fcssen. Obwohl derzeit die Corona-Zeiten gerade f\u00fcr Familien und alleinerziehende Elternteile unglaublich hart sind, bieten sie doch auch gro\u00dfe Chancen. Die mittlerweile Mainstream gewordene Arbeit von zu Hause aus oder das Home Schooling wird hoffentlich uns Frauen noch mehr M\u00f6glichkeiten geben, sich nicht entweder f\u00fcr die Arbeit ODER aber die Familie entscheiden zu m\u00fcssen.<\/p>\n\n\n\n<p> <span id=\"authorRoot\" path=\"\/content\/blogs\/de\/de\/authors\/\"><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aus dem Leben berufst\u00e4tiger M\u00fctter bei Salesforce.<\/p>\n","protected":false},"author":1,"featured_media":871,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sf_justforyou_enable_alt":true,"optimizely_content_id":"","post_meta_title":"","ai_synopsis":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"sf_topic":[48],"sf_content_type":[],"blog":[385],"coauthors":[129],"class_list":["post-874","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","sf_topic-future-of-work","blog-future-of-work"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Vom Spielplatz ins Management - Salesforce<\/title>\n<meta name=\"description\" content=\"Aus dem Leben berufst\u00e4tiger M\u00fctter bei Salesforce.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salesforce.com\/de\/blog\/vom-spielplatz-ins-management\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vom Spielplatz ins Management \u2013 aus dem Leben berufst\u00e4tiger M\u00fctter\" \/>\n<meta property=\"og:description\" content=\"Aus dem Leben berufst\u00e4tiger M\u00fctter bei Salesforce.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salesforce.com\/de\/blog\/vom-spielplatz-ins-management\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-06T18:44:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-05T16:38:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/IMG_4110.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"4032\" \/>\n\t<meta property=\"og:image:height\" content=\"3024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"digital-delivery-operations7076\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"digital-delivery-operations7076\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 Minuten\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"digital-delivery-operations7076\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/vom-spielplatz-ins-management\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/vom-spielplatz-ins-management\/\"},\"author\":{\"name\":\"digital-delivery-operations7076\",\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/person\/601f410a2801f4ddcf6f00cb182e69d3\"},\"headline\":\"Vom Spielplatz ins Management \u2013 aus dem Leben berufst\u00e4tiger M\u00fctter\",\"datePublished\":\"2023-06-06T18:44:39+00:00\",\"dateModified\":\"2023-07-05T16:38:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/vom-spielplatz-ins-management\/\"},\"wordCount\":1407,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/vom-spielplatz-ins-management\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/IMG_4110.jpg\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.salesforce.com\/de\/blog\/vom-spielplatz-ins-management\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/vom-spielplatz-ins-management\/\",\"url\":\"https:\/\/www.salesforce.com\/de\/blog\/vom-spielplatz-ins-management\/\",\"name\":\"Vom Spielplatz ins Management - Salesforce\",\"isPartOf\":{\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/vom-spielplatz-ins-management\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/vom-spielplatz-ins-management\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/IMG_4110.jpg\",\"datePublished\":\"2023-06-06T18:44:39+00:00\",\"dateModified\":\"2023-07-05T16:38:21+00:00\",\"description\":\"Aus dem Leben berufst\u00e4tiger M\u00fctter bei Salesforce.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/vom-spielplatz-ins-management\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.salesforce.com\/de\/blog\/vom-spielplatz-ins-management\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/vom-spielplatz-ins-management\/#primaryimage\",\"url\":\"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/IMG_4110.jpg\",\"contentUrl\":\"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/IMG_4110.jpg\",\"width\":4032,\"height\":3024,\"caption\":\"Vom Spielplatz ins Management \u2013 aus dem Leben berufst\u00e4tiger M\u00fctter\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/vom-spielplatz-ins-management\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.salesforce.com\/de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vom Spielplatz ins Management \u2013 aus dem Leben berufst\u00e4tiger M\u00fctter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/#website\",\"url\":\"https:\/\/www.salesforce.com\/de\/blog\/\",\"name\":\"Salesforce\",\"description\":\"Lesen Sie die neuesten Tipps und Trends f\u00fcr Ihr Business - rund um die Themen Marketing, Vertrieb, Service, IT und Commerce.\",\"publisher\":{\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/#organization\"},\"alternateName\":\"Salesforce\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.salesforce.com\/de\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/#organization\",\"name\":\"Salesforce\",\"url\":\"https:\/\/www.salesforce.com\/de\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Salesforce\"},\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/person\/601f410a2801f4ddcf6f00cb182e69d3\",\"name\":\"digital-delivery-operations7076\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/39c5d4fc7f8f59985f697ce500d830013b61c45f5398d002b410a83eb6a0c33f?s=96&d=mm&r=g8566f0194350bbd26f1616f3ceb627b8\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/39c5d4fc7f8f59985f697ce500d830013b61c45f5398d002b410a83eb6a0c33f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/39c5d4fc7f8f59985f697ce500d830013b61c45f5398d002b410a83eb6a0c33f?s=96&d=mm&r=g\",\"caption\":\"digital-delivery-operations7076\"},\"sameAs\":[\"http:\/\/www.salesforce.com\"],\"url\":\"https:\/\/www.salesforce.com\/de\/blog\/author\/digital-delivery-operations7076\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Vom Spielplatz ins Management - Salesforce","description":"Aus dem Leben berufst\u00e4tiger M\u00fctter bei Salesforce.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salesforce.com\/de\/blog\/vom-spielplatz-ins-management\/","og_locale":"de_DE","og_type":"article","og_title":"Vom Spielplatz ins Management \u2013 aus dem Leben berufst\u00e4tiger M\u00fctter","og_description":"Aus dem Leben berufst\u00e4tiger M\u00fctter bei Salesforce.","og_url":"https:\/\/www.salesforce.com\/de\/blog\/vom-spielplatz-ins-management\/","og_site_name":"Salesforce","article_published_time":"2023-06-06T18:44:39+00:00","article_modified_time":"2023-07-05T16:38:21+00:00","og_image":[{"width":4032,"height":3024,"url":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/IMG_4110.jpg","type":"image\/jpeg"}],"author":"digital-delivery-operations7076","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"digital-delivery-operations7076","Gesch\u00e4tzte Lesezeit":"8 Minuten","Written by":"digital-delivery-operations7076"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salesforce.com\/de\/blog\/vom-spielplatz-ins-management\/#article","isPartOf":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/vom-spielplatz-ins-management\/"},"author":{"name":"digital-delivery-operations7076","@id":"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/person\/601f410a2801f4ddcf6f00cb182e69d3"},"headline":"Vom Spielplatz ins Management \u2013 aus dem Leben berufst\u00e4tiger M\u00fctter","datePublished":"2023-06-06T18:44:39+00:00","dateModified":"2023-07-05T16:38:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/vom-spielplatz-ins-management\/"},"wordCount":1407,"commentCount":0,"publisher":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/#organization"},"image":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/vom-spielplatz-ins-management\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/IMG_4110.jpg","inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.salesforce.com\/de\/blog\/vom-spielplatz-ins-management\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.salesforce.com\/de\/blog\/vom-spielplatz-ins-management\/","url":"https:\/\/www.salesforce.com\/de\/blog\/vom-spielplatz-ins-management\/","name":"Vom Spielplatz ins Management - Salesforce","isPartOf":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/vom-spielplatz-ins-management\/#primaryimage"},"image":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/vom-spielplatz-ins-management\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/IMG_4110.jpg","datePublished":"2023-06-06T18:44:39+00:00","dateModified":"2023-07-05T16:38:21+00:00","description":"Aus dem Leben berufst\u00e4tiger M\u00fctter bei Salesforce.","breadcrumb":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/vom-spielplatz-ins-management\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salesforce.com\/de\/blog\/vom-spielplatz-ins-management\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.salesforce.com\/de\/blog\/vom-spielplatz-ins-management\/#primaryimage","url":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/IMG_4110.jpg","contentUrl":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/IMG_4110.jpg","width":4032,"height":3024,"caption":"Vom Spielplatz ins Management \u2013 aus dem Leben berufst\u00e4tiger M\u00fctter"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salesforce.com\/de\/blog\/vom-spielplatz-ins-management\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salesforce.com\/de\/blog\/"},{"@type":"ListItem","position":2,"name":"Vom Spielplatz ins Management \u2013 aus dem Leben berufst\u00e4tiger M\u00fctter"}]},{"@type":"WebSite","@id":"https:\/\/www.salesforce.com\/de\/blog\/#website","url":"https:\/\/www.salesforce.com\/de\/blog\/","name":"Salesforce","description":"Lesen Sie die neuesten Tipps und Trends f\u00fcr Ihr Business - rund um die Themen Marketing, Vertrieb, Service, IT und Commerce.","publisher":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/#organization"},"alternateName":"Salesforce","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salesforce.com\/de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.salesforce.com\/de\/blog\/#organization","name":"Salesforce","url":"https:\/\/www.salesforce.com\/de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Salesforce"},"image":{"@id":"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.salesforce.com\/de\/blog\/#\/schema\/person\/601f410a2801f4ddcf6f00cb182e69d3","name":"digital-delivery-operations7076","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/39c5d4fc7f8f59985f697ce500d830013b61c45f5398d002b410a83eb6a0c33f?s=96&d=mm&r=g8566f0194350bbd26f1616f3ceb627b8","url":"https:\/\/secure.gravatar.com\/avatar\/39c5d4fc7f8f59985f697ce500d830013b61c45f5398d002b410a83eb6a0c33f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/39c5d4fc7f8f59985f697ce500d830013b61c45f5398d002b410a83eb6a0c33f?s=96&d=mm&r=g","caption":"digital-delivery-operations7076"},"sameAs":["http:\/\/www.salesforce.com"],"url":"https:\/\/www.salesforce.com\/de\/blog\/author\/digital-delivery-operations7076\/"}]}},"jetpack_featured_media_url":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/IMG_4110.jpg","jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Salesforce","distributor_original_site_url":"https:\/\/www.salesforce.com\/de\/blog","push-errors":false,"primary_topic":{"term_id":48,"name":"Future of Work","slug":"future-of-work","term_group":0,"term_taxonomy_id":48,"taxonomy":"sf_topic","description":"","parent":0,"count":6,"filter":"raw"},"featured_image_url":"https:\/\/www.salesforce.com\/de\/blog\/wp-content\/uploads\/sites\/7\/2023\/06\/IMG_4110.jpg?w=1024","_links":{"self":[{"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/posts\/874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/comments?post=874"}],"version-history":[{"count":4,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/posts\/874\/revisions"}],"predecessor-version":[{"id":4790,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/posts\/874\/revisions\/4790"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/media\/871"}],"wp:attachment":[{"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/media?parent=874"}],"wp:term":[{"taxonomy":"sf_topic","embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/sf_topic?post=874"},{"taxonomy":"sf_content_type","embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/sf_content_type?post=874"},{"taxonomy":"blog","embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/blog?post=874"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.salesforce.com\/de\/blog\/wp-json\/wp\/v2\/coauthors?post=874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}