{"id":1725,"date":"2019-08-08T19:33:00","date_gmt":"2023-10-17T19:33:03","guid":{"rendered":"https:\/\/www.salesforce.com\/?p=1725"},"modified":"2023-10-17T19:49:55","modified_gmt":"2023-10-17T19:49:55","slug":"trailhead-barcelona","status":"publish","type":"post","link":"https:\/\/www.salesforce.com\/es\/blog\/trailhead-barcelona\/","title":{"rendered":"Salesforce Trailhead Bootcamp se celebrar\u00e1 en Barcelona en septiembre"},"content":{"rendered":"\n<p>Uno de los mayores eventos de formaci\u00f3n organizado por Salesforce ser\u00e1 internacional este a\u00f1o, celebr\u00e1ndose por primera vez en Europa y la ciudad elegida para esta edici\u00f3n es\u2026 \u00a1<b>Barcelona<\/b>! Hace unas semanas el Crowne Plaza Surfers Paradise alberg\u00f3 la Academia Trailhead en la Costa de Oro australiana, donde cientos de asistentes pudieron disfrutar con diferentes cursos en profundidad, dos opciones distintas de ex\u00e1menes de certificaci\u00f3n in situ, momentos de networking e incluso consultas personalizadas con los expertos de Salesforce y la comunidad de Trailblazers. Fue un \u00e9xito rotundo con fant\u00e1sticas puntuaciones de CSAT y Net Promoter. La siguiente parada del Bootcamp tour ser\u00e1 Espa\u00f1a del <b>9 al 12 de septiembre<\/b>, y el lugar elegido ha sido el Hotel Arts de la ciudad condal. Nuestros mejores expertos formadores acudir\u00e1n a esta cita para ense\u00f1ar durante tres d\u00edas y medio la mejor manera de dominar las tecnolog\u00edas de Salesforce a todos los <b>administradores<\/b>, <b>arquitectos<\/b>, <b>marketers<\/b>y <b>desarrolladores<\/b>que asistan. Los nuevos clientes de Salesforce estar\u00e1n encantados con el esp\u00edritu de la comunidad mientras aprenden (LEARN), ganan (EARN) y conectan (CONNECT) con nuestros queridos Trailblazers. Los consultores con m\u00e1s experiencia apreciar\u00e1n el valor de los nuevos itinerarios System Architect y Application Architect. Dependiendo de tu nivel, podr\u00e1s elegir entre siete Learining Tracks diferentes. \u00a1No te pierdas el evento del a\u00f1o! <a href=\"https:\/\/developer.salesforce.com\/resources2\/bootcamps\/bootcamp-sp\/index.html\" adhocenable=\"false\">Reg\u00edstrate<\/a> y hazte con tus entradas ya. Si necesitas m\u00e1s razones para convencerte, aqu\u00ed van tres por las que no puedes faltar a esta cita: <\/p>\n<ul>\n<li>\n<ul>\n<li><b>LEARN &#8211; Podr\u00e1s conocer Salesforce a fondo. <\/b>Las lecciones de Bootcamp son impartidas por expertos certificados que manejan nuestra tecnolog\u00eda a la perfecci\u00f3n. De esta forma, los asistentes tendr\u00e1n acceso de primera mano y cara a cara a los conocimientos, experiencia y consejos sobre certificaciones.<\/li>\n<li><b>EARN &#8211; El aprendizaje es una inversi\u00f3n en ti mismo. <\/b>IDC ha pronosticado que el ecosistema de Salesforce crear\u00e1 3,3 millones de nuevos puestos de trabajo que requerir\u00e1n las habilidades de Salesforce para 2022. Por este motivo, tanto si eres nuevo en Salesforce, est\u00e1s buscando un nuevo puesto de trabajo o simplemente deseas actualizar tus habilidades para seguir siendo relevante en tu sector, aprender y conseguir tu certificaci\u00f3n en el Trailhead Bootcamp de Barcelona es la mejor manera de ponerte al d\u00eda. <\/li>\n<li><b>CONNECT &#8211; \u00a1Entra a formar parte de nuestra familia Ohana! <\/b>Conecta con cientos de clientes de Salesforce, nuestros queridos Trailblazers, que ampliar\u00e1n tu red de contactos mientras aprendemos unos de otros.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Si necesitas ayuda para decidir cu\u00e1l es el mejor itinerario para ti, no dudes en ponerte en contacto con el equipo ejecutivo de Trailhead v\u00eda email: <a>educationcoordinator@salesforce.com<\/a>. Estaremos encantados de hablar sobre tus objetivos de aprendizaje para recomendarte cu\u00e1l es el rol (administrador, arquitecto, marketer o desarrollador) que mejor se adapta a ti y a tus metas. Para atenci\u00f3n durante el registro, si tienes alguna incidencia, puedes escribirnos a esta direcci\u00f3n <a>trailheadbc2019BARC@regsvc.com<\/a>. <\/p>\n<p> <span id=\"authorRoot\" path=\"\/content\/blogs\/es\/es\/authors\/\"><\/span> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trailhead Bootcamp es uno de los eventos de formaci\u00f3n en tecnolog\u00edas Salesforce m\u00e1s importantes. Por primera vez se celebra en Europa, en Barcelona. Expertos formadores ense\u00f1ar\u00e1n a administradores, arquitectos, marketers y desarrolladores y tambi\u00e9n otorgar\u00e1n las correspondientes certificaciones.<\/p>\n","protected":false},"author":1,"featured_media":1727,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sf_justforyou_enable_alt":true,"optimizely_content_id":"","post_meta_title":"","ai_synopsis":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"sf_topic":[205],"sf_content_type":[],"blog":[603],"coauthors":[118],"class_list":["post-1725","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","sf_topic-trailblazer","blog-trailblazer"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Salesforce lleva Trailhead Bootcamp a Barcelona - Salesforce<\/title>\n<meta name=\"description\" content=\"Trailhead Bootcamp es uno de los eventos de formaci\u00f3n en tecnolog\u00edas Salesforce m\u00e1s importantes. Por primera vez se celebra en Europa, en Barcelona. Expertos formadores ense\u00f1ar\u00e1n a administradores, arquitectos, marketers y desarrolladores y tambi\u00e9n otorgar\u00e1n las correspondientes certificaciones.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salesforce.com\/es\/blog\/trailhead-barcelona\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salesforce Trailhead Bootcamp se celebrar\u00e1 en Barcelona en septiembre\" \/>\n<meta property=\"og:description\" content=\"Trailhead Bootcamp es uno de los eventos de formaci\u00f3n en tecnolog\u00edas Salesforce m\u00e1s importantes. Por primera vez se celebra en Europa, en Barcelona. Expertos formadores ense\u00f1ar\u00e1n a administradores, arquitectos, marketers y desarrolladores y tambi\u00e9n otorgar\u00e1n las correspondientes certificaciones.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salesforce.com\/es\/blog\/trailhead-barcelona\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-17T19:33:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-17T19:49:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/Trailhead20Bootcamp20BCN.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1115\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Salesforce Espa\u00f1a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Salesforce Espa\u00f1a\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/trailhead-barcelona\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/trailhead-barcelona\\\/\"},\"author\":[{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/#\\\/schema\\\/person\\\/image\\\/e2f6c6d481bffc386e6e8cdaecd17df6\"}],\"headline\":\"Salesforce Trailhead Bootcamp se celebrar\u00e1 en Barcelona en septiembre\",\"datePublished\":\"2023-10-17T19:33:03+00:00\",\"dateModified\":\"2023-10-17T19:49:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/trailhead-barcelona\\\/\"},\"wordCount\":515,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/trailhead-barcelona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2023\\\/10\\\/Trailhead20Bootcamp20BCN.jpg\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/trailhead-barcelona\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/trailhead-barcelona\\\/\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/trailhead-barcelona\\\/\",\"name\":\"Salesforce lleva Trailhead Bootcamp a Barcelona - Salesforce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/trailhead-barcelona\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/trailhead-barcelona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2023\\\/10\\\/Trailhead20Bootcamp20BCN.jpg\",\"datePublished\":\"2023-10-17T19:33:03+00:00\",\"dateModified\":\"2023-10-17T19:49:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/#\\\/schema\\\/person\\\/601f410a2801f4ddcf6f00cb182e69d3\"},\"description\":\"Trailhead Bootcamp es uno de los eventos de formaci\u00f3n en tecnolog\u00edas Salesforce m\u00e1s importantes. Por primera vez se celebra en Europa, en Barcelona. Expertos formadores ense\u00f1ar\u00e1n a administradores, arquitectos, marketers y desarrolladores y tambi\u00e9n otorgar\u00e1n las correspondientes certificaciones.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/trailhead-barcelona\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/trailhead-barcelona\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/trailhead-barcelona\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2023\\\/10\\\/Trailhead20Bootcamp20BCN.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2023\\\/10\\\/Trailhead20Bootcamp20BCN.jpg\",\"width\":1115,\"height\":628,\"caption\":\"Salesforce Trailhead Bootcamp se celebrar\u00e1 en Barcelona en septiembre\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/trailhead-barcelona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salesforce Trailhead Bootcamp se celebrar\u00e1 en Barcelona en septiembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/\",\"name\":\"Salesforce\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/#\\\/schema\\\/person\\\/image\\\/e2f6c6d481bffc386e6e8cdaecd17df6\",\"name\":\"Salesforce Espa\u00f1a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/#\\\/schema\\\/person\\\/image\\\/9671a9a1f236a48b35497e55c367902a\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2023\\\/10\\\/Salesforce-300x300-1.png?w=150&h=150&crop=1\",\"contentUrl\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2023\\\/10\\\/Salesforce-300x300-1.png?w=150&h=150&crop=1\",\"width\":150,\"height\":150,\"caption\":\"Salesforce Espa\u00f1a\"},\"url\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/author\\\/salesforce-espana\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Salesforce lleva Trailhead Bootcamp a Barcelona - Salesforce","description":"Trailhead Bootcamp es uno de los eventos de formaci\u00f3n en tecnolog\u00edas Salesforce m\u00e1s importantes. Por primera vez se celebra en Europa, en Barcelona. Expertos formadores ense\u00f1ar\u00e1n a administradores, arquitectos, marketers y desarrolladores y tambi\u00e9n otorgar\u00e1n las correspondientes certificaciones.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salesforce.com\/es\/blog\/trailhead-barcelona\/","og_locale":"es_ES","og_type":"article","og_title":"Salesforce Trailhead Bootcamp se celebrar\u00e1 en Barcelona en septiembre","og_description":"Trailhead Bootcamp es uno de los eventos de formaci\u00f3n en tecnolog\u00edas Salesforce m\u00e1s importantes. Por primera vez se celebra en Europa, en Barcelona. Expertos formadores ense\u00f1ar\u00e1n a administradores, arquitectos, marketers y desarrolladores y tambi\u00e9n otorgar\u00e1n las correspondientes certificaciones.","og_url":"https:\/\/www.salesforce.com\/es\/blog\/trailhead-barcelona\/","og_site_name":"Salesforce","article_published_time":"2023-10-17T19:33:03+00:00","article_modified_time":"2023-10-17T19:49:55+00:00","og_image":[{"width":1115,"height":628,"url":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/Trailhead20Bootcamp20BCN.jpg","type":"image\/jpeg"}],"author":"Salesforce Espa\u00f1a","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"","Tiempo de lectura":"3 minutos","Written by":"Salesforce Espa\u00f1a"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salesforce.com\/es\/blog\/trailhead-barcelona\/#article","isPartOf":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/trailhead-barcelona\/"},"author":[{"@id":"https:\/\/www.salesforce.com\/es\/blog\/#\/schema\/person\/image\/e2f6c6d481bffc386e6e8cdaecd17df6"}],"headline":"Salesforce Trailhead Bootcamp se celebrar\u00e1 en Barcelona en septiembre","datePublished":"2023-10-17T19:33:03+00:00","dateModified":"2023-10-17T19:49:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/trailhead-barcelona\/"},"wordCount":515,"commentCount":0,"image":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/trailhead-barcelona\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/Trailhead20Bootcamp20BCN.jpg","inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.salesforce.com\/es\/blog\/trailhead-barcelona\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.salesforce.com\/es\/blog\/trailhead-barcelona\/","url":"https:\/\/www.salesforce.com\/es\/blog\/trailhead-barcelona\/","name":"Salesforce lleva Trailhead Bootcamp a Barcelona - Salesforce","isPartOf":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/trailhead-barcelona\/#primaryimage"},"image":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/trailhead-barcelona\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/Trailhead20Bootcamp20BCN.jpg","datePublished":"2023-10-17T19:33:03+00:00","dateModified":"2023-10-17T19:49:55+00:00","author":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/#\/schema\/person\/601f410a2801f4ddcf6f00cb182e69d3"},"description":"Trailhead Bootcamp es uno de los eventos de formaci\u00f3n en tecnolog\u00edas Salesforce m\u00e1s importantes. Por primera vez se celebra en Europa, en Barcelona. Expertos formadores ense\u00f1ar\u00e1n a administradores, arquitectos, marketers y desarrolladores y tambi\u00e9n otorgar\u00e1n las correspondientes certificaciones.","breadcrumb":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/trailhead-barcelona\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salesforce.com\/es\/blog\/trailhead-barcelona\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.salesforce.com\/es\/blog\/trailhead-barcelona\/#primaryimage","url":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/Trailhead20Bootcamp20BCN.jpg","contentUrl":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/Trailhead20Bootcamp20BCN.jpg","width":1115,"height":628,"caption":"Salesforce Trailhead Bootcamp se celebrar\u00e1 en Barcelona en septiembre"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salesforce.com\/es\/blog\/trailhead-barcelona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salesforce.com\/es\/blog\/"},{"@type":"ListItem","position":2,"name":"Salesforce Trailhead Bootcamp se celebrar\u00e1 en Barcelona en septiembre"}]},{"@type":"WebSite","@id":"https:\/\/www.salesforce.com\/es\/blog\/#website","url":"https:\/\/www.salesforce.com\/es\/blog\/","name":"Salesforce","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salesforce.com\/es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.salesforce.com\/es\/blog\/#\/schema\/person\/image\/e2f6c6d481bffc386e6e8cdaecd17df6","name":"Salesforce Espa\u00f1a","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.salesforce.com\/es\/blog\/#\/schema\/person\/image\/9671a9a1f236a48b35497e55c367902a","url":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/Salesforce-300x300-1.png?w=150&h=150&crop=1","contentUrl":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/Salesforce-300x300-1.png?w=150&h=150&crop=1","width":150,"height":150,"caption":"Salesforce Espa\u00f1a"},"url":"https:\/\/www.salesforce.com\/es\/blog\/author\/salesforce-espana\/"}]}},"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Salesforce","distributor_original_site_url":"https:\/\/www.salesforce.com\/es\/blog","push-errors":false,"jetpack_featured_media_url":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/Trailhead20Bootcamp20BCN.jpg","_links":{"self":[{"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/posts\/1725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/comments?post=1725"}],"version-history":[{"count":2,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/posts\/1725\/revisions"}],"predecessor-version":[{"id":2497,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/posts\/1725\/revisions\/2497"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/media\/1727"}],"wp:attachment":[{"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/media?parent=1725"}],"wp:term":[{"taxonomy":"sf_topic","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/sf_topic?post=1725"},{"taxonomy":"sf_content_type","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/sf_content_type?post=1725"},{"taxonomy":"blog","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/blog?post=1725"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/coauthors?post=1725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}