{"id":1863,"date":"2023-07-25T19:35:00","date_gmt":"2023-10-17T19:35:12","guid":{"rendered":"https:\/\/www.salesforce.com\/?p=1863"},"modified":"2024-01-11T14:49:13","modified_gmt":"2024-01-11T14:49:13","slug":"twitch-estrategia-marketing","status":"publish","type":"post","link":"https:\/\/www.salesforce.com\/es\/blog\/twitch-estrategia-marketing\/","title":{"rendered":"Twitch: qu\u00e9 es y c\u00f3mo utilizarlo en una estrategia de marketing"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><b>Twitch<\/b> es una red social que \u00faltimamente est\u00e1 creciendo cada vez m\u00e1s y despertando la curiosidad de muchas marcas. En Italia tambi\u00e9n est\u00e1 aumentando el inter\u00e9s y es importante entender sus caracter\u00edsticas para saber si es oportuno integrarla dentro de nuestra estrategia de marketing en redes sociales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><b>\u00bfQu\u00e9 es Twitch?<\/b> Se trata de una plataforma de live streaming nacida en el \u00e1mbito de los videojuegos en el que<b> jugadores o aficionados opinaban sobre los nuevos lanzamientos de juegos<\/b> online antes de comprarlos. Con el paso del tiempo se ha ido ampliando, abrazando otros \u00e1mbitos que van de los eventos deportivos, a la cocina, pasando por la m\u00fasica, los tutoriales de maquillaje hasta llegar a verdaderos programas.<\/p>\n\n\n\n<div class=\"layout-one wp-block-salesforce-blog-offer\">\n\t<div class=\"wp-block-offer__wrapper\">\n\n\t\t<div class=\"wp-block-offer__content\">\n\t\t\t<h2 class=\"wp-block-offer__title\">Llega m\u00e1s lejos con tus campa\u00f1as de marketing con Marketing Cloud<\/h2>\n\t\t\t\t\t\t\t<p class=\"wp-block-offer__description\">Salesforce Marketing Cloud; la plataforma con IA que le acerca de forma personalizada a tu cliente, en cualquier canal<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t<a class=\"wp-block-button__link\" target=\"_self\" href=\"https:\/\/www.salesforce.com\/es\/form\/demo\/demo-marketing\/?d=inc-blog-banner&#038;nc=7013y000002a33bAAA\">Ver Demo<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"wp-block-offer__media\">\n\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wp-block-offer__graphics wp-block-offer__contour\"><\/div>\n\t\n\t\t\t<!-- Standard Illustration -->\n\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__illustration\" src=\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-illustration-layout-one.png\" alt=\"\">\n\n\t\t<!-- Small Accent Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__accent\" src=\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-accent-layout-one.png\" alt=\"\">\n\t\t\n\t\t<!-- Left Side Illustration -->\n\t\t\n\t\t<!-- Cloud Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__cloud\" src=\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-cloud-layout-one.png\" alt=\"\">\n\t\t\n\t<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-como-funciona-twitch\"><b>\u00bfC\u00f3mo funciona Twitch?<\/b><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los <b>streamers<\/b>, tambi\u00e9n llamados <b>twitchers<\/b>, realizan los v\u00eddeos que publican principalmente en redes sociales, pero tambi\u00e9n en otros canales como <i>YouTube, Vimeo, Facebook,<\/i> gracias a programas de software que conectan con la plataforma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los usuarios ven los v\u00eddeos eligiendo entre diferentes temas, <b>interactuando con el resto de fans<\/b>, aficionados, o con los propios streamers a trav\u00e9s de un sistema de mensajer\u00eda y mostrando agradecimiento o un reconocimiento a quien ha realizado el v\u00eddeo. Este <b>reconocimiento se puede pagar en bits<\/b> (la moneda virtual de la plataforma), donaciones monetarias o suscripciones de pago en moneda real.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los espectadores tambi\u00e9n pueden comprar productos de marca de vendedores o patrocinadores de eventos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quiz\u00e1 el aspecto m\u00e1s interesante de esta red social sean las ventajas para las empresas. De hecho, en Twitch se pueden realizar anuncios disponibles en diferentes formatos para poder promocionar nuestros propios productos o patrocinar eventos online organizados en la plataforma. Pero, como veremos en breve, hay tambi\u00e9n otras formas de obtener beneficios para nuestra empresa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De estos pocos elementos se pueden intuir ya los puntos fuertes de Twitch:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\n<p><b>un entorno todav\u00eda poco explorado<\/b>, en el que interact\u00faan potenciales clientes, en el que es m\u00e1s f\u00e1cil destacar ahora<\/p>\n<\/li>\n\n\n\n<li>\n<p><b>una comunidad espec\u00edfica de personas interesadas en un tema<\/b>, es decir, un target muy espec\u00edfico<\/p>\n<\/li>\n\n\n\n<li>\n<p><b>interacciones directas con los usuarios<\/b> para aumentar el brand awareness en un ambiente m\u00e1s relajado y, por lo tanto, m\u00e1s receptivo<\/p>\n<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-como-saber-si-twitch-se-puede-utilizar-en-una-estrategia-de-marketing\"><b>C\u00f3mo saber si Twitch se puede utilizar en una estrategia de marketing<\/b><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Antes de explorar el mundo violeta de Twitch, hay que tener presente un aspecto peculiar de esta plataforma de live streaming: su p\u00fablico. Como es f\u00e1cil intuir, al ser una plataforma nacida en el entorno de los videojuegos, que ocupan todav\u00eda una parte importante de los contenidos publicados, est\u00e1 formada por j\u00f3venes en su mayor\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><b>Casi el 68 %<\/b> del p\u00fablico tiene <b>menos de 34 a\u00f1os <\/b>y el <b>78,36 % son hombres, mientras que el 19,64 % son mujeres<\/b>. (Fuente 2022: Streamscheme).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed pues, lo primero que hay que entender es si nuestro propio target o una parte del mismo puede enmarcarse esta cuota de mercado. Para una empresa que fabrica ropa deportiva, accesorios o productos tecnol\u00f3gicos, la respuesta es bastante obvia. De la misma forma, tambi\u00e9n puede serlo para los clubes deportivos, pero tambi\u00e9n, para las casas de cosm\u00e9ticos y autom\u00f3viles o para empresas que fabrican snacks o bebidas, como veremos en los ejemplos de empresas que han abrazado esta plataforma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No obstante, tambi\u00e9n para otras empresas como entidades financieras y aseguradoras puede valer la pena considerar este canal:<b> solo hay que pensar en todas las cuentas corrientes, tarjetas de cr\u00e9dito,<\/b> pr\u00e9stamos, seguros y financiaciones concebidas espec\u00edficamente para j\u00f3venes menores de 35 a\u00f1os: \u00a1los usuarios de Twitch!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dichas entidades pueden desembarcar en esta plataforma siempre y cuando adapten toda la comunicaci\u00f3n a los c\u00f3digos del canal y entiendan qu\u00e9 contenidos son aptos para su difusi\u00f3n en live streaming. Implicar a la comunidad de los titulares de cuentas corrientes con medidas espec\u00edficas de social media marketing ser\u00eda, por tanto, un imperativo categ\u00f3rico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si un producto o un servicio lo utiliza aunque solo sea una parte de este tipo de audiencia entonces, con toda probabilidad, valdr\u00e1 la pena empezar a valorar Twitch y pensar en integrarlo, por ejemplo, en las estrategias de social advertising.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-que-se-puede-hacer-con-twitch-en-la-practica\"><b>Qu\u00e9 se puede hacer con Twitch en la pr\u00e1ctica<\/b><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez que hemos visto c\u00f3mo funciona Twitch y que hemos dado<b> algunos consejos para entender si se puede introducir en una estrategia de marketing<\/b>, veamos ahora qu\u00e9 comporta su uso, es decir, las posibilidades para una empresa que decide adoptarlo en sus actividades de marketing:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\n<p><b>aumentar la notoriedad<\/b> de marca (el famoso brand awareness)<\/p>\n<\/li>\n\n\n\n<li> <p><b>hacer <a href=\"https:\/\/www.salesforce.com\/es\/blog\/2023\/06\/lead-generation-porque-es-importante.html\" target=\"_blank\" rel=\"noopener\">lead generation<\/a> <\/b>encontrando los posibles clientes fuera de los canales convencionales<\/p> <\/li>\n\n\n\n<li>\n<p><b>segmentar m\u00e1s el target a trav\u00e9s de Amazon Ads<\/b> que recientemente ha puesto a disposici\u00f3n los anuncios de Twitch<\/p>\n<\/li>\n\n\n\n<li>\n<p><b>crear campa\u00f1as de marketing<\/b> de producto muy espec\u00edficas<\/p>\n<\/li>\n\n\n\n<li>\n<p><b>hacer influencer marketing<\/b> tambi\u00e9n con streamers menos conocidos, pero con seguidores muy apasionados<\/p>\n<\/li>\n\n\n\n<li>\n<p>hacer content marketing con los v\u00eddeos para<b> \u00abmantener calientes\u00bb los propios leads<\/b><\/p>\n<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Naturalmente hay que tener presentes las peculiaridades de la plataforma concebida para dar espacio a un disfrute visual, para crear y mantener una comunidad activa y atenta a la marca, en una atm\u00f3sfera m\u00e1s relajada y, a veces, graciosa.<\/p>\n\n\n\n<div class=\"layout-one wp-block-salesforce-blog-offer\">\n\t<div class=\"wp-block-offer__wrapper\">\n\n\t\t<div class=\"wp-block-offer__content\">\n\t\t\t<h2 class=\"wp-block-offer__title\">Llega m\u00e1s lejos con tus campa\u00f1as de marketing con Marketing Cloud<\/h2>\n\t\t\t\t\t\t\t<p class=\"wp-block-offer__description\">Salesforce Marketing Cloud; la plataforma con IA que le acerca de forma personalizada a tu cliente, en cualquier canal<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t<a class=\"wp-block-button__link\" target=\"_self\" href=\"https:\/\/www.salesforce.com\/es\/form\/demo\/demo-marketing\/?d=inc-blog-banner&#038;nc=7013y000002a33bAAA\">Ver Demo<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"wp-block-offer__media\">\n\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wp-block-offer__graphics wp-block-offer__contour\"><\/div>\n\t\n\t\t\t<!-- Standard Illustration -->\n\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__illustration\" src=\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-illustration-layout-one.png\" alt=\"\">\n\n\t\t<!-- Small Accent Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__accent\" src=\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-accent-layout-one.png\" alt=\"\">\n\t\t\n\t\t<!-- Left Side Illustration -->\n\t\t\n\t\t<!-- Cloud Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__cloud\" src=\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-cloud-layout-one.png\" alt=\"\">\n\t\t\n\t<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><!-- END --> <span id=\"authorRoot\" path=\"\/content\/blogs\/es\/es\/authors\/\"><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Twitch es una red social que \u00faltimamente est\u00e1 creciendo cada vez m\u00e1s y despertando la curiosidad de muchas marcas.<\/p>\n","protected":false},"author":1,"featured_media":1865,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sf_justforyou_enable_alt":true,"optimizely_content_id":"72ec5c4d16194390b9e46e864aa170e8","post_meta_title":"","ai_synopsis":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"sf_topic":[6],"sf_content_type":[],"blog":[490],"coauthors":[118],"class_list":["post-1863","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","sf_topic-marketing-cloud","blog-marketing-cloud"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Twitch: qu\u00e9 es y c\u00f3mo utilizarlo en una estrategia de marketing - Salesforce Blog<\/title>\n<meta name=\"description\" content=\"Twitch es una red social que \u00faltimamente est\u00e1 creciendo cada vez m\u00e1s y despertando la curiosidad de muchas marcas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salesforce.com\/es\/blog\/twitch-estrategia-marketing\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Twitch: qu\u00e9 es y c\u00f3mo utilizarlo en una estrategia de marketing\" \/>\n<meta property=\"og:description\" content=\"Twitch es una red social que \u00faltimamente est\u00e1 creciendo cada vez m\u00e1s y despertando la curiosidad de muchas marcas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salesforce.com\/es\/blog\/twitch-estrategia-marketing\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-17T19:35:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-11T14:49:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/Card_Streaming_Globoplay.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Salesforce Espa\u00f1a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Salesforce Espa\u00f1a\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/twitch-estrategia-marketing\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/twitch-estrategia-marketing\\\/\"},\"author\":[{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/#\\\/schema\\\/person\\\/image\\\/e2f6c6d481bffc386e6e8cdaecd17df6\"}],\"headline\":\"Twitch: qu\u00e9 es y c\u00f3mo utilizarlo en una estrategia de marketing\",\"datePublished\":\"2023-10-17T19:35:12+00:00\",\"dateModified\":\"2024-01-11T14:49:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/twitch-estrategia-marketing\\\/\"},\"wordCount\":897,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/twitch-estrategia-marketing\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2023\\\/10\\\/Card_Streaming_Globoplay.png\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/twitch-estrategia-marketing\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/twitch-estrategia-marketing\\\/\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/twitch-estrategia-marketing\\\/\",\"name\":\"Twitch: qu\u00e9 es y c\u00f3mo utilizarlo en una estrategia de marketing - Salesforce Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/twitch-estrategia-marketing\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/twitch-estrategia-marketing\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2023\\\/10\\\/Card_Streaming_Globoplay.png\",\"datePublished\":\"2023-10-17T19:35:12+00:00\",\"dateModified\":\"2024-01-11T14:49:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/#\\\/schema\\\/person\\\/601f410a2801f4ddcf6f00cb182e69d3\"},\"description\":\"Twitch es una red social que \u00faltimamente est\u00e1 creciendo cada vez m\u00e1s y despertando la curiosidad de muchas marcas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/twitch-estrategia-marketing\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/twitch-estrategia-marketing\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/twitch-estrategia-marketing\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2023\\\/10\\\/Card_Streaming_Globoplay.png\",\"contentUrl\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2023\\\/10\\\/Card_Streaming_Globoplay.png\",\"width\":1600,\"height\":1067,\"caption\":\"Chica viendo contenido en streaming\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/twitch-estrategia-marketing\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Twitch: qu\u00e9 es y c\u00f3mo utilizarlo en una estrategia de marketing\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/\",\"name\":\"Salesforce\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/#\\\/schema\\\/person\\\/image\\\/e2f6c6d481bffc386e6e8cdaecd17df6\",\"name\":\"Salesforce Espa\u00f1a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/#\\\/schema\\\/person\\\/image\\\/9671a9a1f236a48b35497e55c367902a\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2023\\\/10\\\/Salesforce-300x300-1.png?w=150&h=150&crop=1\",\"contentUrl\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2023\\\/10\\\/Salesforce-300x300-1.png?w=150&h=150&crop=1\",\"width\":150,\"height\":150,\"caption\":\"Salesforce Espa\u00f1a\"},\"url\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/author\\\/salesforce-espana\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Twitch: qu\u00e9 es y c\u00f3mo utilizarlo en una estrategia de marketing - Salesforce Blog","description":"Twitch es una red social que \u00faltimamente est\u00e1 creciendo cada vez m\u00e1s y despertando la curiosidad de muchas marcas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salesforce.com\/es\/blog\/twitch-estrategia-marketing\/","og_locale":"es_ES","og_type":"article","og_title":"Twitch: qu\u00e9 es y c\u00f3mo utilizarlo en una estrategia de marketing","og_description":"Twitch es una red social que \u00faltimamente est\u00e1 creciendo cada vez m\u00e1s y despertando la curiosidad de muchas marcas.","og_url":"https:\/\/www.salesforce.com\/es\/blog\/twitch-estrategia-marketing\/","og_site_name":"Salesforce","article_published_time":"2023-10-17T19:35:12+00:00","article_modified_time":"2024-01-11T14:49:13+00:00","og_image":[{"width":1600,"height":1067,"url":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/Card_Streaming_Globoplay.png","type":"image\/png"}],"author":"Salesforce Espa\u00f1a","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"","Tiempo de lectura":"4 minutos","Written by":"Salesforce Espa\u00f1a"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salesforce.com\/es\/blog\/twitch-estrategia-marketing\/#article","isPartOf":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/twitch-estrategia-marketing\/"},"author":[{"@id":"https:\/\/www.salesforce.com\/es\/blog\/#\/schema\/person\/image\/e2f6c6d481bffc386e6e8cdaecd17df6"}],"headline":"Twitch: qu\u00e9 es y c\u00f3mo utilizarlo en una estrategia de marketing","datePublished":"2023-10-17T19:35:12+00:00","dateModified":"2024-01-11T14:49:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/twitch-estrategia-marketing\/"},"wordCount":897,"commentCount":0,"image":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/twitch-estrategia-marketing\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/Card_Streaming_Globoplay.png","inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.salesforce.com\/es\/blog\/twitch-estrategia-marketing\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.salesforce.com\/es\/blog\/twitch-estrategia-marketing\/","url":"https:\/\/www.salesforce.com\/es\/blog\/twitch-estrategia-marketing\/","name":"Twitch: qu\u00e9 es y c\u00f3mo utilizarlo en una estrategia de marketing - Salesforce Blog","isPartOf":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/twitch-estrategia-marketing\/#primaryimage"},"image":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/twitch-estrategia-marketing\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/Card_Streaming_Globoplay.png","datePublished":"2023-10-17T19:35:12+00:00","dateModified":"2024-01-11T14:49:13+00:00","author":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/#\/schema\/person\/601f410a2801f4ddcf6f00cb182e69d3"},"description":"Twitch es una red social que \u00faltimamente est\u00e1 creciendo cada vez m\u00e1s y despertando la curiosidad de muchas marcas.","breadcrumb":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/twitch-estrategia-marketing\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salesforce.com\/es\/blog\/twitch-estrategia-marketing\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.salesforce.com\/es\/blog\/twitch-estrategia-marketing\/#primaryimage","url":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/Card_Streaming_Globoplay.png","contentUrl":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/Card_Streaming_Globoplay.png","width":1600,"height":1067,"caption":"Chica viendo contenido en streaming"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salesforce.com\/es\/blog\/twitch-estrategia-marketing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salesforce.com\/es\/blog\/"},{"@type":"ListItem","position":2,"name":"Twitch: qu\u00e9 es y c\u00f3mo utilizarlo en una estrategia de marketing"}]},{"@type":"WebSite","@id":"https:\/\/www.salesforce.com\/es\/blog\/#website","url":"https:\/\/www.salesforce.com\/es\/blog\/","name":"Salesforce","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salesforce.com\/es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.salesforce.com\/es\/blog\/#\/schema\/person\/image\/e2f6c6d481bffc386e6e8cdaecd17df6","name":"Salesforce Espa\u00f1a","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.salesforce.com\/es\/blog\/#\/schema\/person\/image\/9671a9a1f236a48b35497e55c367902a","url":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/Salesforce-300x300-1.png?w=150&h=150&crop=1","contentUrl":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/Salesforce-300x300-1.png?w=150&h=150&crop=1","width":150,"height":150,"caption":"Salesforce Espa\u00f1a"},"url":"https:\/\/www.salesforce.com\/es\/blog\/author\/salesforce-espana\/"}]}},"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Salesforce","distributor_original_site_url":"https:\/\/www.salesforce.com\/es\/blog","push-errors":false,"jetpack_featured_media_url":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/Card_Streaming_Globoplay.png","_links":{"self":[{"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/posts\/1863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/comments?post=1863"}],"version-history":[{"count":3,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/posts\/1863\/revisions"}],"predecessor-version":[{"id":2885,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/posts\/1863\/revisions\/2885"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/media\/1865"}],"wp:attachment":[{"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/media?parent=1863"}],"wp:term":[{"taxonomy":"sf_topic","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/sf_topic?post=1863"},{"taxonomy":"sf_content_type","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/sf_content_type?post=1863"},{"taxonomy":"blog","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/blog?post=1863"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/coauthors?post=1863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}