{"id":416,"date":"2022-04-19T19:14:00","date_gmt":"2023-10-17T19:14:11","guid":{"rendered":"https:\/\/www.salesforce.com\/?p=416"},"modified":"2023-12-18T20:02:23","modified_gmt":"2023-12-18T20:02:23","slug":"five-trends-shaping-nonprofit-service","status":"publish","type":"post","link":"https:\/\/www.salesforce.com\/es\/blog\/five-trends-shaping-nonprofit-service\/","title":{"rendered":"5 Tendencias clave que dan forma al sector de servicios sin \u00e1nimo de lucro"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Este a\u00f1o hemos publicado nuestro primer informe sobre el <a href=\"https:\/\/www.salesforce.com\/uk\/form\/sfdo\/ngo\/state-of-service-for-nonprofits\/?d=7013y000000vJsUAAU&amp;nc=7013y000000vJsQAAU&amp;utm_source=salesforce.org&amp;utm_medium=blog&amp;utm_campaign=emea_ngoaw&amp;utm_content=uki-fy22-q3-state-of-services-nonprofits_7013y000000vJsUAAUemea_salesforce.org&amp;icid=SFORG:blog-inline:\" target=\"_blank\" rel=\"noopener\">State of Service para Organizaciones Sin \u00c1nimo de Lucro<\/a> , que se centr\u00f3 en las ideas que compartieron diversos representantes de estas organizaciones y los cambios que han experimentado y presenciado desde el inicio de la pandemia en 2020.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Consulta la infograf\u00eda sobre el estado de los servicios para organizaciones sin \u00e1nimo de lucro para obtener una instant\u00e1nea r\u00e1pida de algunos de los principales hallazgos del informe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hacer m\u00e1s con menos no es un concepto nuevo para aquellos que trabajan en organizaciones sin \u00e1nimo de lucro, pero la pandemia ha puesto a\u00fan m\u00e1s de manifiesto esta necesidad. Aun as\u00ed, el ingenio de los integrantes del sector ha salido a la luz a medida que iba creciendo la demanda de servicios. Las organizaciones sin \u00e1nimo de lucro tienen que satisfacer las necesidades de muchas partes interesadas, entre las que se cuentan beneficiarios, miembros, simpatizantes, clientes y voluntarios. A la cabeza de poder satisfacer esta gran variedad de necesidades diferentes se encuentran el reciclaje profesional, la formaci\u00f3n y las soluciones digitales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De los hallazgos del informe surgieron cinco tendencias clave, y en el meollo de estas tendencias siempre se encuentran las experiencias. Las organizaciones sin \u00e1nimo de lucro m\u00e1s resilientes de los \u00faltimos 18 meses han podido recurrir a la madurez digital mientras siguen ofreciendo experiencias a sus usuarios de servicios.<\/p>\n\n\n\n<div class=\"layout-one wp-block-salesforce-blog-offer\">\n\t<div class=\"wp-block-offer__wrapper\">\n\n\t\t<div class=\"wp-block-offer__content\">\n\t\t\t<h2 class=\"wp-block-offer__title\">C\u00f3mo una experiencia de cliente excepcional puede impulsar el \u00e9xito<\/h2>\n\t\t\t\t\t\t\t<p class=\"wp-block-offer__description\">Ya no basta con saber qui\u00e9n es su cliente. Hay que saber c\u00f3mo se comportan, c\u00f3mo reaccionan y qu\u00e9 necesitan.<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t<a class=\"wp-block-button__link\" target=\"_self\" href=\"https:\/\/www.salesforce.com\/es\/form\/pdf\/transform-manufacturing-with-digital-first\/?d=7013y000002ZClWAAW?d=inc-blog-banner\">Descargar informe<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"wp-block-offer__media\">\n\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wp-block-offer__graphics wp-block-offer__contour\"><\/div>\n\t\n\t\t\t<!-- Standard Illustration -->\n\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__illustration\" src=\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-illustration-layout-one.png\" alt=\"\">\n\n\t\t<!-- Small Accent Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__accent\" src=\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-accent-layout-one.png\" alt=\"\">\n\t\t\n\t\t<!-- Left Side Illustration -->\n\t\t\n\t\t<!-- Cloud Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__cloud\" src=\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-cloud-layout-one.png\" alt=\"\">\n\t\t\n\t<\/div>\n\n\n\n<h3 class=\"wp-block-heading\"> <\/h3>\n\n\n\n<h3 class=\"wp-block-heading\"><b>1. Cambiar las expectativas del usuario<\/b><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\"> <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La primera tendencia clave que surgi\u00f3 de los hallazgos se centra en las cambiantes expectativas de servicio de los usuarios y c\u00f3mo las organizaciones sin \u00e1nimo de lucro las est\u00e1n incorporando en sus estrategias para poder responder mejor. As\u00ed pues, \u00bfc\u00f3mo se traduce esto en t\u00e9rminos reales? Los usuarios buscan experiencias m\u00e1s fluidas, m\u00e1s r\u00e1pidas y m\u00e1s conectadas. Sin embargo, a medida que crece la demanda de servicios, equilibrar la velocidad y la calidad que buscan los usuarios de servicios se vuelve un desaf\u00edo para los profesionales que los prestan. En \u00faltima instancia, lo fundamental aqu\u00ed es un mayor uso de la tecnolog\u00eda; ahora bien, es igualmente importante hacer un uso bien pensado de ella, y no verla como una panacea que cura todos los males.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><b>2. Inversiones digitales<\/b><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\"> <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La pr\u00f3xima tendencia est\u00e1 muy en consonancia con la primera y se centra en las inversiones digitales. En Europa, el 65 % de los representantes de organizaciones sin \u00e1nimo de lucro afirman que est\u00e1n ofreciendo m\u00e1s servicios en l\u00ednea que antes de la pandemia. \u00bfQu\u00e9 significa esto para el d\u00eda a d\u00eda de aquellos que trabajan en el sector? Tanto si se trata de aprovechar los canales digitales, automatizar los aspectos b\u00e1sicos del trabajo o incluso utilizar la inteligencia artificial en forma de chatbots, estas herramientas digitales permiten a las organizaciones escalar sus servicios de manera m\u00e1s eficaz e, idealmente, satisfacer las necesidades de los usuarios al mismo tiempo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"> <\/h3>\n\n\n\n<h3 class=\"wp-block-heading\"><b>3. Uniformidad en la experiencia del usuario<\/b><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\"> <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La tercera tendencia se centra en la uniformidad de las experiencias del usuario. M\u00e1s del 75 % de los usuarios de servicio esperan experiencias uniformes cuando interact\u00faan con una organizaci\u00f3n, y el 83 % de los usuarios de servicios esperan poder interactuar con alguien de inmediato cuando se comunican con una organizaci\u00f3n. Esto significa que las organizaciones sin \u00e1nimo de lucro deben contar con la infraestructura digital necesaria para garantizar que sus usuarios tengan una experiencia conectada (y personalizada siempre que sea posible) cuando se comunican con ellas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><b>4. Representaci\u00f3n de la diversidad<\/b><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\"> <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Otra tendencia que se ha puesto a\u00fan m\u00e1s de manifiesto en estos \u00faltimos 18 meses es la forma en que las organizaciones representan a los diversos colectivos y comunidades que muchas de ellas atienden. El tiempo de cantar las excelencias propias en cuanto a diversidad ya ha pasado; si las organizaciones se toman en serio la lucha contra la desigualdad, es necesario que las plantillas sean m\u00e1s diversificadas. Menos del 33 % de los agentes de servicios consideran la diversidad de sus organizaciones como excelente, por lo que queda mucho por avanzar en este sentido.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><b>5. Crecimiento profesional y &amp; oportunidades<\/b><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\"> <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La quinta y \u00faltima tendencia que surgi\u00f3 en el informe del estado del servicio es la trayectoria profesional de los representantes de servicios de primera l\u00ednea en el sector. La pandemia ha subrayado el papel clave que desempe\u00f1an los profesionales de servicios, y muchos ven un mayor aprecio de su trabajo por parte de la direcci\u00f3n. El informe respalda esto, con un 79 % de los responsables de la toma de decisiones que velan por que se realicen importantes inversiones en capacitaci\u00f3n. El acceso continuo a la formaci\u00f3n y la tecnolog\u00eda bajo pedido ser\u00e1 crucial para empoderar a los profesionales de servicios en el futuro, con un 55 % que indica que necesitan m\u00e1s formaci\u00f3n para hacer bien su trabajo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><b>Ejemplos de experiencias de usuario mejoradas<\/b><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\"> <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Por \u00faltimo, \u00bfc\u00f3mo son las experiencias mejoradas para los usuarios de servicios y los profesionales de primera l\u00ednea que los prestan? No hay m\u00e1s que consultar la gu\u00eda para perros lazarillo del Reino Unido (Guide Dogs U.K) y la colecci\u00f3n de libros CustomEyes que crearon para personas con discapacidad visual. El equipo de Guide Dogs U.K. se dio cuenta de que se ocupaba demasiado y valioso tiempo del personal con procesos que se podr\u00edan automatizar. Con <a href=\"https:\/\/www.salesforce.com\/es\/products\/experience-cloud\/overview\/?icid=SFORG:blog-inline:\" target=\"_blank\" rel=\"noopener\">Salesforce Experience Cloud<\/a>, pudieron digitalizar y optimizar las operaciones. Esto liber\u00f3 tiempo para responder a los comentarios de los clientes y mejorar continuamente todo su sistema para garantizar una mejor experiencia del usuario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esperamos que nuestra versi\u00f3n abreviada del informe del Estado de Servicio te haya dado una idea de las tendencias que han surgido y que seguir\u00e1n dando forma al sector en los meses y a\u00f1os venideros, y que te haya despertado el inter\u00e9s por explorar el informe completo.<\/p>\n\n\n\n<div class=\"layout-one wp-block-salesforce-blog-offer\">\n\t<div class=\"wp-block-offer__wrapper\">\n\n\t\t<div class=\"wp-block-offer__content\">\n\t\t\t<h2 class=\"wp-block-offer__title\">C\u00f3mo una experiencia de cliente excepcional puede impulsar el \u00e9xito<\/h2>\n\t\t\t\t\t\t\t<p class=\"wp-block-offer__description\">Ya no basta con saber qui\u00e9n es su cliente. Hay que saber c\u00f3mo se comportan, c\u00f3mo reaccionan y qu\u00e9 necesitan.<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t<a class=\"wp-block-button__link\" target=\"_self\" href=\"https:\/\/www.salesforce.com\/es\/form\/pdf\/transform-manufacturing-with-digital-first\/?d=7013y000002ZClWAAW?d=inc-blog-banner\">DESCARGAR INFORME<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"wp-block-offer__media\">\n\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wp-block-offer__graphics wp-block-offer__contour\"><\/div>\n\t\n\t\t\t<!-- Standard Illustration -->\n\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__illustration\" src=\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-illustration-layout-one.png\" alt=\"\">\n\n\t\t<!-- Small Accent Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__accent\" src=\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-accent-layout-one.png\" alt=\"\">\n\t\t\n\t\t<!-- Left Side Illustration -->\n\t\t\n\t\t<!-- Cloud Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__cloud\" src=\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-cloud-layout-one.png\" alt=\"\">\n\t\t\n\t<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Infograf\u00eda sobre el estado de los servicios para organizaciones sin \u00e1nimo de lucro.<\/p>\n","protected":false},"author":1,"featured_media":418,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sf_justforyou_enable_alt":true,"optimizely_content_id":"","post_meta_title":"","ai_synopsis":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"sf_topic":[17,40],"sf_content_type":[],"blog":[495,576],"coauthors":[118],"class_list":["post-416","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","sf_topic-leading-through-change","sf_topic-service-cloud","blog-service-cloud","blog-leading-through-change"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>5 Tendencias clave que dan forma al sector de servicios sin \u00e1nimo de lucro - Salesforce Blog<\/title>\n<meta name=\"description\" content=\"Infograf\u00eda sobre el estado de los servicios para organizaciones sin \u00e1nimo de lucro.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salesforce.com\/es\/blog\/five-trends-shaping-nonprofit-service\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 Tendencias clave que dan forma al sector de servicios sin \u00e1nimo de lucro\" \/>\n<meta property=\"og:description\" content=\"Infograf\u00eda sobre el estado de los servicios para organizaciones sin \u00e1nimo de lucro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salesforce.com\/es\/blog\/five-trends-shaping-nonprofit-service\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-17T19:14:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-18T20:02:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/non-profit-spring-22-release.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"5335\" \/>\n\t<meta property=\"og:image:height\" content=\"2988\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Salesforce Espa\u00f1a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Salesforce Espa\u00f1a\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/five-trends-shaping-nonprofit-service\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/five-trends-shaping-nonprofit-service\\\/\"},\"author\":[{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/#\\\/schema\\\/person\\\/image\\\/e2f6c6d481bffc386e6e8cdaecd17df6\"}],\"headline\":\"5 Tendencias clave que dan forma al sector de servicios sin \u00e1nimo de lucro\",\"datePublished\":\"2023-10-17T19:14:11+00:00\",\"dateModified\":\"2023-12-18T20:02:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/five-trends-shaping-nonprofit-service\\\/\"},\"wordCount\":1002,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/five-trends-shaping-nonprofit-service\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2023\\\/10\\\/non-profit-spring-22-release.jpg\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/five-trends-shaping-nonprofit-service\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/five-trends-shaping-nonprofit-service\\\/\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/five-trends-shaping-nonprofit-service\\\/\",\"name\":\"5 Tendencias clave que dan forma al sector de servicios sin \u00e1nimo de lucro - Salesforce Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/five-trends-shaping-nonprofit-service\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/five-trends-shaping-nonprofit-service\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2023\\\/10\\\/non-profit-spring-22-release.jpg\",\"datePublished\":\"2023-10-17T19:14:11+00:00\",\"dateModified\":\"2023-12-18T20:02:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/#\\\/schema\\\/person\\\/601f410a2801f4ddcf6f00cb182e69d3\"},\"description\":\"Infograf\u00eda sobre el estado de los servicios para organizaciones sin \u00e1nimo de lucro.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/five-trends-shaping-nonprofit-service\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/five-trends-shaping-nonprofit-service\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/five-trends-shaping-nonprofit-service\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2023\\\/10\\\/non-profit-spring-22-release.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2023\\\/10\\\/non-profit-spring-22-release.jpg\",\"width\":5335,\"height\":2988,\"caption\":\"Un equipo de personas reunidas | Salesforce\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/five-trends-shaping-nonprofit-service\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5 Tendencias clave que dan forma al sector de servicios sin \u00e1nimo de lucro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/\",\"name\":\"Salesforce\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/#\\\/schema\\\/person\\\/image\\\/e2f6c6d481bffc386e6e8cdaecd17df6\",\"name\":\"Salesforce Espa\u00f1a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/#\\\/schema\\\/person\\\/image\\\/9671a9a1f236a48b35497e55c367902a\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2023\\\/10\\\/Salesforce-300x300-1.png?w=150&h=150&crop=1\",\"contentUrl\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2023\\\/10\\\/Salesforce-300x300-1.png?w=150&h=150&crop=1\",\"width\":150,\"height\":150,\"caption\":\"Salesforce Espa\u00f1a\"},\"url\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/blog\\\/author\\\/salesforce-espana\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"5 Tendencias clave que dan forma al sector de servicios sin \u00e1nimo de lucro - Salesforce Blog","description":"Infograf\u00eda sobre el estado de los servicios para organizaciones sin \u00e1nimo de lucro.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salesforce.com\/es\/blog\/five-trends-shaping-nonprofit-service\/","og_locale":"es_ES","og_type":"article","og_title":"5 Tendencias clave que dan forma al sector de servicios sin \u00e1nimo de lucro","og_description":"Infograf\u00eda sobre el estado de los servicios para organizaciones sin \u00e1nimo de lucro.","og_url":"https:\/\/www.salesforce.com\/es\/blog\/five-trends-shaping-nonprofit-service\/","og_site_name":"Salesforce","article_published_time":"2023-10-17T19:14:11+00:00","article_modified_time":"2023-12-18T20:02:23+00:00","og_image":[{"width":5335,"height":2988,"url":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/non-profit-spring-22-release.jpg","type":"image\/jpeg"}],"author":"Salesforce Espa\u00f1a","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"","Tiempo de lectura":"5 minutos","Written by":"Salesforce Espa\u00f1a"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salesforce.com\/es\/blog\/five-trends-shaping-nonprofit-service\/#article","isPartOf":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/five-trends-shaping-nonprofit-service\/"},"author":[{"@id":"https:\/\/www.salesforce.com\/es\/blog\/#\/schema\/person\/image\/e2f6c6d481bffc386e6e8cdaecd17df6"}],"headline":"5 Tendencias clave que dan forma al sector de servicios sin \u00e1nimo de lucro","datePublished":"2023-10-17T19:14:11+00:00","dateModified":"2023-12-18T20:02:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/five-trends-shaping-nonprofit-service\/"},"wordCount":1002,"commentCount":0,"image":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/five-trends-shaping-nonprofit-service\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/non-profit-spring-22-release.jpg","inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.salesforce.com\/es\/blog\/five-trends-shaping-nonprofit-service\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.salesforce.com\/es\/blog\/five-trends-shaping-nonprofit-service\/","url":"https:\/\/www.salesforce.com\/es\/blog\/five-trends-shaping-nonprofit-service\/","name":"5 Tendencias clave que dan forma al sector de servicios sin \u00e1nimo de lucro - Salesforce Blog","isPartOf":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/five-trends-shaping-nonprofit-service\/#primaryimage"},"image":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/five-trends-shaping-nonprofit-service\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/non-profit-spring-22-release.jpg","datePublished":"2023-10-17T19:14:11+00:00","dateModified":"2023-12-18T20:02:23+00:00","author":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/#\/schema\/person\/601f410a2801f4ddcf6f00cb182e69d3"},"description":"Infograf\u00eda sobre el estado de los servicios para organizaciones sin \u00e1nimo de lucro.","breadcrumb":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/five-trends-shaping-nonprofit-service\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salesforce.com\/es\/blog\/five-trends-shaping-nonprofit-service\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.salesforce.com\/es\/blog\/five-trends-shaping-nonprofit-service\/#primaryimage","url":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/non-profit-spring-22-release.jpg","contentUrl":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/non-profit-spring-22-release.jpg","width":5335,"height":2988,"caption":"Un equipo de personas reunidas | Salesforce"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salesforce.com\/es\/blog\/five-trends-shaping-nonprofit-service\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salesforce.com\/es\/blog\/"},{"@type":"ListItem","position":2,"name":"5 Tendencias clave que dan forma al sector de servicios sin \u00e1nimo de lucro"}]},{"@type":"WebSite","@id":"https:\/\/www.salesforce.com\/es\/blog\/#website","url":"https:\/\/www.salesforce.com\/es\/blog\/","name":"Salesforce","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salesforce.com\/es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.salesforce.com\/es\/blog\/#\/schema\/person\/image\/e2f6c6d481bffc386e6e8cdaecd17df6","name":"Salesforce Espa\u00f1a","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.salesforce.com\/es\/blog\/#\/schema\/person\/image\/9671a9a1f236a48b35497e55c367902a","url":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/Salesforce-300x300-1.png?w=150&h=150&crop=1","contentUrl":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/Salesforce-300x300-1.png?w=150&h=150&crop=1","width":150,"height":150,"caption":"Salesforce Espa\u00f1a"},"url":"https:\/\/www.salesforce.com\/es\/blog\/author\/salesforce-espana\/"}]}},"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Salesforce","distributor_original_site_url":"https:\/\/www.salesforce.com\/es\/blog","push-errors":false,"jetpack_featured_media_url":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/non-profit-spring-22-release.jpg","_links":{"self":[{"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/posts\/416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/comments?post=416"}],"version-history":[{"count":4,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/posts\/416\/revisions"}],"predecessor-version":[{"id":2740,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/posts\/416\/revisions\/2740"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/media\/418"}],"wp:attachment":[{"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/media?parent=416"}],"wp:term":[{"taxonomy":"sf_topic","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/sf_topic?post=416"},{"taxonomy":"sf_content_type","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/sf_content_type?post=416"},{"taxonomy":"blog","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/blog?post=416"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/coauthors?post=416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}