{"id":782,"date":"2020-05-11T19:19:00","date_gmt":"2023-10-17T19:19:23","guid":{"rendered":"https:\/\/www.salesforce.com\/?p=782"},"modified":"2023-12-20T16:11:01","modified_gmt":"2023-12-20T16:11:01","slug":"mejorar_servicio_cliente","status":"publish","type":"post","link":"https:\/\/www.salesforce.com\/es\/blog\/mejorar_servicio_cliente\/","title":{"rendered":"C\u00f3mo mejorar la atenci\u00f3n al cliente: 7 maneras de optimizar tu servicio"},"content":{"rendered":"\n<p>Vivimos en un contexto en el que tener el mejor producto o el m\u00e1s econ\u00f3mico, ya no es sin\u00f3nimo de \u00e9xito. Y es que en un mercado tan competitivo, lo que marca la diferencia es un buen servicio de atenci\u00f3n al cliente para poder atraerlos y retenerlos.<\/p>\n\n\n\n<p>Hoy en d\u00eda las opciones de los clientes son infinitas. Es por ello que sus expectativas a la hora de realizar una transacci\u00f3n son m\u00e1s altas y exigentes. Los consumidores est\u00e1n preparados para cambiar cada vez que no est\u00e9n contentos con el trato recibido. <\/p>\n\n\n\n<p>Esta tendencia al cambio est\u00e1 tan integrada en la forma de consumo de las personas que, en el <b>estudio, ya disponible en espa\u00f1ol, \u201c<a href=\"https:\/\/www.salesforce.com\/es\/form\/pdf\/connected-customer-report\/\" adhocenable=\"false\" target=\"_blank\" rel=\"noopener\">State of the Connected Customer<\/a>\u201d, el 66% de los consumidores aseguraron que -probablemente-, cambiar\u00edan de marca si se sent\u00edan tratados como un n\u00famero y no como un individuo.<\/b><\/p>\n\n\n\n<p>Ante este contexto, el resultado es claro: el trato al cliente es imprescindible para diferenciarte del resto. Y en este art\u00edculo de Salesforce te contamos los mejores consejos para mejorar la atenci\u00f3n al cliente de tu negocio. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-que-es-el-servicio-de-atencion-al-cliente\"><b>\u00bfQu\u00e9 es el servicio de atenci\u00f3n al cliente? <\/b> <\/h2>\n\n\n\n<p>Antes de conocer las estrategias para mejorar la atenci\u00f3n al cliente es importante ponerse en situaci\u00f3n y conocer el significado del t\u00e9rmino. <\/p>\n\n\n\n<p>El servicio de atenci\u00f3n al cliente es, por un lado, las ayudas y\/o consejos que se le ofrecen al usuario antes y\/o despu\u00e9s de realizar una transacci\u00f3n en nuestro negocio. Y, por otro lado, es la manera en la que se cuida a un cliente cuando interacciona con la marca. <\/p>\n\n\n\n<p>Un buen servicio de atenci\u00f3n al cliente incluye todo el proceso: desde la manera en la que se escucha y trata a los usuarios, hasta la amabilidad del personal y la eficiencia en la entrega de los pedidos.<\/p>\n\n\n\n<p>Los agentes del servicio de atenci\u00f3n al cliente son, para los responsables en la toma de decisiones de las empresas, la primera l\u00ednea de contacto con los clientes. De hecho, en el estudio previamente mencionado, se estima que el 85% de los responsables consideran a los agentes clave a la hora de transformar el servicio de cara al p\u00fablico.<\/p>\n\n\n\n<p>Sin embargo, cuando se plantean din\u00e1micas para mejorar la atenci\u00f3n al cliente, hay que entender que \u00e9sta no solo es responsabilidad del departamento de atenci\u00f3n al cliente. Todos los departamentos juegan un papel importante, ya que su trabajo repercutir\u00e1 en la satisfacci\u00f3n del consumidor (por ejemplo, que lleguen los pedidos a tiempo). <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-por-que-es-tan-importante-la-atencion-al-cliente\">\u00bfPor qu\u00e9 es tan importante la atenci\u00f3n al cliente? <\/h2>\n\n\n\n<p>Entender c\u00f3mo mejorar la atenci\u00f3n al cliente es necesario, puesto que es el ingrediente m\u00e1gico para mejorar las relaciones con los consumidores y convertirlos en clientes fieles.<\/p>\n\n\n\n<p>Un cliente fiel comprar\u00e1 de forma recurrente, hablar\u00e1 bien de ti y te recomendar\u00e1 entre sus amigos y familiares. <\/p>\n\n\n\n<p>Muchos clientes fieles te permitir\u00e1n reducir el coste de adquisici\u00f3n de nuevos clientes, y as\u00ed destinar esas partidas a otras partes del negocio. Es m\u00e1s, si ofreces una buena atenci\u00f3n al cliente desde el principio, reducir\u00e1s las consultas de los usuarios. <\/p>\n\n\n\n<p>Si quieres definir una estrategia para mejorar la atenci\u00f3n al cliente, primero tienes que entender sus necesidades. Para, posteriormente, implementar una serie de acciones que superen sus expectativas. <\/p>\n\n\n\n<p>\u00bfNo sabes por d\u00f3nde empezar? Desde Salesforce te ofrecemos siete consejos para mejorar la atenci\u00f3n al cliente en toda tu compa\u00f1\u00eda. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-1-unifica-la-informacion-para-conseguir-un-punto-de-vista-real\"><b>1. Unifica la informaci\u00f3n para conseguir un punto de vista real <\/b><\/h3>\n\n\n\n<p>A los consumidores no les importa que los responsables de ventas o de atenci\u00f3n al cliente trabajen en departamentos diferentes. Lo que ellos buscan es una experiencia de usuario en la que los diferentes canales y departamentos est\u00e9n conectados.<\/p>\n\n\n\n<p>Tal y como se recoge en la segunda edici\u00f3n del estudio <a adhocenable=\"false\" href=\"https:\/\/www.salesforce.com\/es\/form\/pdf\/connected-customer-report\/\">\u201cState of the Connected Customer\u201d<\/a>, el 70% de los clientes aseguran que las experiencias conectadas, como que los departamentos actualicen los estados y puedan interconectarse, o que se tengan en cuenta interacciones anteriores sin necesidad de recordarlas, son muy importantes. <\/p>\n\n\n\n<p>Si la informaci\u00f3n de los clientes no est\u00e1 conectada se crean barreras que acaban afectando a la relaci\u00f3n con el cliente. Y, el 56% de los agentes de atenci\u00f3n al cliente tiene que consultar varias fuentes para encontrar la informaci\u00f3n que necesitan, tal y como muestra el estudio.<\/p>\n\n\n\n<p>Reunir todos los datos relativos a un usuario en una misma fuente es una estrategia necesaria para mejorar la atenci\u00f3n al cliente. Al hacerlo, todo el personal puede acceder a toda la informaci\u00f3n de manera inmediata y, ofrecer as\u00ed el mejor servicio.<\/p>\n\n\n\n<p>Tener toda la informaci\u00f3n centralizada tambi\u00e9n te ahorrar\u00e1 mucho tiempo. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-2-crea-experiencias-personalizadas\"><b>2. Crea experiencias personalizadas <\/b><\/h3>\n\n\n\n<p>Esta idea para mejorar la atenci\u00f3n al cliente debes tenerla siempre en mente. No se puede tratar a dos clientes de la misma forma. Cada uno necesita un trato en base a sus necesidades. <\/p>\n\n\n\n<p>Con la ayuda de los datos conectados del cliente en cuesti\u00f3n, crea una experiencia personalizada. Estas pueden ir desde descuentos relacionados con un producto previamente adquirido, hasta ofrecer productos en base a su historial de navegaci\u00f3n. <\/p>\n\n\n\n<p>Del mismo modo, un buena opci\u00f3n para personalizar el trato con los clientes es que expresen qu\u00e9 tipo de informaci\u00f3n les interesa recibir (newsletters, programas de fidelizaci\u00f3n\u2026). As\u00ed solo recibir\u00e1n contenido relevante para ellos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-3-integra-la-inteligencia-artificial-ia\"><b> 3. Integra la inteligencia artificial (IA) <\/b><\/h3>\n\n\n\n<p>Las expectativas de los clientes van cambiando en busca de un trato excelente por parte de las empresas. Muestra de ello es la evoluci\u00f3n de los agentes de atenci\u00f3n al cliente para ofrecer una asistencia m\u00e1s personalizada. <\/p>\n\n\n\n<p>Seg\u00fan el estudio \u201cState of the Connected Customer\u201d, m\u00e1s del 70% de los agentes consideran que sus trabajos son m\u00e1s estrat\u00e9gicos que hace unos a\u00f1os; as\u00ed como que su labor se centra en construir relaciones con el cliente, y no tanto en la transacci\u00f3n.<\/p>\n\n\n\n<p>En este sentido, surge como una idea para mejorar la atenci\u00f3n al cliente la implementaci\u00f3n de la inteligencia artificial. Liberando as\u00ed a los agentes a unas tareas m\u00e1s estrat\u00e9gicas. <\/p>\n\n\n\n<p>El uso de chatbots para cuestiones simples (preguntas b\u00e1sicas, dudas, recopilar informaci\u00f3n\u2026), permite que los especialistas de atenci\u00f3n al cliente dediquen m\u00e1s tiempo a interacciones complejas. <\/p>\n\n\n\n<p>Por otra parte, los sistemas de inteligencia artificial ayudan a mejorar la productividad, lo que se traduce en una resoluci\u00f3n m\u00e1s r\u00e1pida de las dudas, una mayor satisfacci\u00f3n del cliente y, sobre todo, unos mejores est\u00e1ndares de servicio al cliente. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-4-amplia-los-canales-digitales\"><b>4. Ampl\u00eda los canales digitales <\/b><\/h3>\n\n\n\n<p>Tal y como se determina en el estudio \u201cState of the Connected Customer\u201d, los clientes usan, de media, 10 canales diferentes para comunicarse con la empresa (tel\u00e9fono, email, redes sociales, chats en l\u00ednea\u2026). Y en todas y cada una de las acciones esperan tener una experiencia satisfactoria.<\/p>\n\n\n\n<p>Si bien los consumidores cada vez buscan m\u00e1s los medios digitales para comunicarse, no todas las empresas est\u00e1n al d\u00eda en este punto. <\/p>\n\n\n\n<p>Los consumidores cada vez tienen m\u00e1s recursos para la comunicaci\u00f3n gracias a las aplicaciones m\u00f3viles y los asistentes de voz. Y hay que adaptarse a ello para ofrecer la mejor atenci\u00f3n y experiencia posible.<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04044bc3eb5&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04044bc3eb5\" class=\"wp-block-image wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/lh4.googleusercontent.com\/cN_FCzlyYcWZ5r4JuR2XK9re3XgDlYbUMO4J_Jvr6C4obJnMHf7aFwU5aSOPyU7I0OqKE_PksRYtbd7pjHW6W1ayXdiy20YKLpQ8fVxFF9PwQVrB6rEvXJg92rk_F_cmyCMPpTQV\" alt=\"\"\/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p>\u00bfNo est\u00e1s seguro de qu\u00e9 canales de comunicaci\u00f3n debes priorizar? Un buen consejo para mejorar la atenci\u00f3n al cliente en este sentido, es pensar qui\u00e9n es tu buyer persona y cu\u00e1les son sus principales v\u00edas de contacto. Y es que no ser\u00e1n las mismas si tu cliente potencial pertenecen a la Generaci\u00f3n Z o son baby boomers. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-5-ten-un-buen-sistema-de-faqs\"><b>5. Ten un buen sistema de FAQs <\/b><\/h3>\n\n\n\n<p>Cuando un usuario busca respuestas inmediatas a una cuesti\u00f3n, estas opciones son mucho m\u00e1s r\u00e1pidas y convenientes que ponerse en contacto con el servicio de atenci\u00f3n al cliente. <\/p>\n\n\n\n<p>Disponer de FAQs u otros elementos virtuales de consulta a las dudas frecuentes de los usuarios no solo les ahorrar\u00e1 tiempo a ellos, sino que reducir\u00e1 las consultas que el equipo de atenci\u00f3n al cliente reciba. <\/p>\n\n\n\n<p>Para que estas opciones sean efectivas deben ser de f\u00e1cil acceso para los clientes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-6-anima-a-poner-comentarios\"><b> 6. Anima a poner comentarios <\/b><\/h3>\n\n\n\n<p>Ofr\u00e9cele a tus consumidores la oportunidad de poner comentarios sobre la atenci\u00f3n al cliente recibida. <\/p>\n\n\n\n<p>Una idea para mejorar la atenci\u00f3n al cliente en este sentido son las encuestas, tanto online como por tel\u00e9fono. Eso s\u00ed, aseg\u00farate de poder darle la libertad necesaria a tus clientes para sugerir cambios y mejoras. Solo de este modo podr\u00e1s seguir creciendo.<\/p>\n\n\n\n<p>Si animando al feedback recibes una queja de un cliente, man\u00e9jala con cuidado. Las quejas crecen muy r\u00e1pido y podr\u00edan tener un impacto negativo sobre tu marca; sobre todo si se produce por redes sociales. <\/p>\n\n\n\n<p>A la hora de resolver problemas s\u00e9 siempre cort\u00e9s, r\u00e1pido y mant\u00e9n informado al cliente en todo momento. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-7-establece-kpis-sobre-la-satisfaccion-del-cliente\"><b>7. Establece KPIs sobre la satisfacci\u00f3n del cliente <\/b><\/h3>\n\n\n\n<p>Los KPIs clave en cuanto al rendimiento de los servicios de atenci\u00f3n al cliente sol\u00edan basarse en cu\u00e1ntas llamadas pod\u00eda gestionar un cliente, y los tratos que pod\u00eda cerrar. Eso ha cambiado.<\/p>\n\n\n\n<p>Con un enfoque hacia el cliente basado en la construcci\u00f3n de relaciones m\u00e1s all\u00e1 de la venta, los KPIs tambi\u00e9n han cambiado. Seg\u00fan el estudio de \u201cState of the Connected Customer\u201d, los indicadores de \u00e9xito ahora est\u00e1n orientados al consumidor: su satisfacci\u00f3n, la puntuaci\u00f3n a la transacci\u00f3n, el tiempo de entrega de los pedidos, las consultas recibidas, etc.<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04044bc457d&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04044bc457d\" class=\"wp-block-image wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/lh3.googleusercontent.com\/_wZn0e0qKDHH-gXTxHHYKdt4GMC32z22PTB9I2gM6GAFQyeOjFU9aGqV41u9zTDMYyFdSoHastCKpBy3pyVakk08Ej6Dda8r_PgghoA55PDq7Ywn-woek1LR0aVA0ExsjSWR1nmY\" alt=\"\"\/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p>Ante un contexto en el que cada vez hay m\u00e1s competidores por sector y las expectativas de los clientes crecen, ofrecer una atenci\u00f3n al cliente satisfactoria es clave para mantenerse a la vanguardia. <\/p>\n\n\n\n<p>Priorizar el servicio al cliente genera confianza con los consumidores, lo que se traduce en relaciones duraderas; una ventaja competitiva dif\u00edcil de superar.<\/p>\n\n\n\n<p>Si quieres obtener m\u00e1s informaci\u00f3n sobre las mejores estrategias para mejorar la atenci\u00f3n al cliente, <b>consulta la tercera edici\u00f3n del informe de investigaci\u00f3n en espa\u00f1ol \u201c<a adhocenable=\"false\" href=\"https:\/\/www.salesforce.com\/es\/form\/pdf\/connected-customer-report\/\">State of the Connected Customer<\/a>\u201d de Salesforce.<\/b><\/p>\n\n\n\n<p><b>Puedes descargarlo aqu\u00ed: <\/b><\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.salesforce.com\/es\/form\/pdf\/connected-customer-report\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/state-of-the-connected-customer-3rd-edition-uk.jpg?strip=all&#038;quality=95\" alt=\"\"\/><\/a><\/figure>\n\n\n\n<p> <span id=\"authorRoot\" path=\"\/content\/blogs\/es\/es\/authors\/\"><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un buen servicio al cliente es clave para atraer a los consumidores. Descubre las mejores estrategia para mejorar la atenci\u00f3n al cliente de tu empresa.<\/p>\n","protected":false},"author":1,"featured_media":784,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sf_justforyou_enable_alt":true,"optimizely_content_id":"2df9a579bac6459b9282909d6bb697f0","post_meta_title":"","ai_synopsis":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"sf_topic":[8],"sf_content_type":[],"blog":[520],"coauthors":[118],"class_list":["post-782","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","sf_topic-service","blog-service"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Un buen servicio al cliente es clave para atraer a los consumidores. Descubre las mejores estrategia para mejorar la atenci\u00f3n al cliente de tu empresa. - Salesforce<\/title>\n<meta name=\"description\" content=\"Un buen servicio al cliente es clave para atraer a los consumidores. Descubre las mejores estrategia para mejorar la atenci\u00f3n al cliente de tu empresa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salesforce.com\/es\/blog\/mejorar_servicio_cliente\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo mejorar la atenci\u00f3n al cliente: 7 maneras de optimizar tu servicio\" \/>\n<meta property=\"og:description\" content=\"Un buen servicio al cliente es clave para atraer a los consumidores. Descubre las mejores estrategia para mejorar la atenci\u00f3n al cliente de tu empresa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salesforce.com\/es\/blog\/mejorar_servicio_cliente\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-17T19:19:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-20T16:11:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/SetA-Webinar-Card-Service.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Salesforce Espa\u00f1a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"digital-delivery-operations7076\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Salesforce Espa\u00f1a\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.salesforce.com\/es\/blog\/mejorar_servicio_cliente\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.salesforce.com\/es\/blog\/mejorar_servicio_cliente\/\"},\"author\":[{\"@id\":\"https:\/\/www.salesforce.com\/es\/blog\/#\/schema\/person\/image\/e2f6c6d481bffc386e6e8cdaecd17df6\"}],\"headline\":\"C\u00f3mo mejorar la atenci\u00f3n al cliente: 7 maneras de optimizar tu servicio\",\"datePublished\":\"2023-10-17T19:19:23+00:00\",\"dateModified\":\"2023-12-20T16:11:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.salesforce.com\/es\/blog\/mejorar_servicio_cliente\/\"},\"wordCount\":1745,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/es\/blog\/mejorar_servicio_cliente\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/SetA-Webinar-Card-Service.jpg\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.salesforce.com\/es\/blog\/mejorar_servicio_cliente\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.salesforce.com\/es\/blog\/mejorar_servicio_cliente\/\",\"url\":\"https:\/\/www.salesforce.com\/es\/blog\/mejorar_servicio_cliente\/\",\"name\":\"Un buen servicio al cliente es clave para atraer a los consumidores. Descubre las mejores estrategia para mejorar la atenci\u00f3n al cliente de tu empresa. - Salesforce\",\"isPartOf\":{\"@id\":\"https:\/\/www.salesforce.com\/es\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.salesforce.com\/es\/blog\/mejorar_servicio_cliente\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/es\/blog\/mejorar_servicio_cliente\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/SetA-Webinar-Card-Service.jpg\",\"datePublished\":\"2023-10-17T19:19:23+00:00\",\"dateModified\":\"2023-12-20T16:11:01+00:00\",\"author\":{\"@id\":\"https:\/\/www.salesforce.com\/es\/blog\/#\/schema\/person\/601f410a2801f4ddcf6f00cb182e69d3\"},\"description\":\"Un buen servicio al cliente es clave para atraer a los consumidores. Descubre las mejores estrategia para mejorar la atenci\u00f3n al cliente de tu empresa.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.salesforce.com\/es\/blog\/mejorar_servicio_cliente\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.salesforce.com\/es\/blog\/mejorar_servicio_cliente\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.salesforce.com\/es\/blog\/mejorar_servicio_cliente\/#primaryimage\",\"url\":\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/SetA-Webinar-Card-Service.jpg\",\"contentUrl\":\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/SetA-Webinar-Card-Service.jpg\",\"width\":768,\"height\":432,\"caption\":\"C\u00f3mo mejorar la atenci\u00f3n al cliente: 7 maneras de optimizar tu servicio\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.salesforce.com\/es\/blog\/mejorar_servicio_cliente\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.salesforce.com\/es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3mo mejorar la atenci\u00f3n al cliente: 7 maneras de optimizar tu servicio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.salesforce.com\/es\/blog\/#website\",\"url\":\"https:\/\/www.salesforce.com\/es\/blog\/\",\"name\":\"Salesforce\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.salesforce.com\/es\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.salesforce.com\/es\/blog\/#\/schema\/person\/image\/e2f6c6d481bffc386e6e8cdaecd17df6\",\"name\":\"Salesforce Espa\u00f1a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.salesforce.com\/es\/blog\/#\/schema\/person\/image\/9671a9a1f236a48b35497e55c367902a\",\"url\":\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/Salesforce-300x300-1.png?w=150&h=150&crop=1\",\"contentUrl\":\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/Salesforce-300x300-1.png?w=150&h=150&crop=1\",\"width\":\"150\",\"height\":\"150\",\"caption\":\"Salesforce Espa\u00f1a\"},\"url\":\"https:\/\/www.salesforce.com\/es\/blog\/author\/salesforce-espana\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Un buen servicio al cliente es clave para atraer a los consumidores. Descubre las mejores estrategia para mejorar la atenci\u00f3n al cliente de tu empresa. - Salesforce","description":"Un buen servicio al cliente es clave para atraer a los consumidores. Descubre las mejores estrategia para mejorar la atenci\u00f3n al cliente de tu empresa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salesforce.com\/es\/blog\/mejorar_servicio_cliente\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo mejorar la atenci\u00f3n al cliente: 7 maneras de optimizar tu servicio","og_description":"Un buen servicio al cliente es clave para atraer a los consumidores. Descubre las mejores estrategia para mejorar la atenci\u00f3n al cliente de tu empresa.","og_url":"https:\/\/www.salesforce.com\/es\/blog\/mejorar_servicio_cliente\/","og_site_name":"Salesforce","article_published_time":"2023-10-17T19:19:23+00:00","article_modified_time":"2023-12-20T16:11:01+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/SetA-Webinar-Card-Service.jpg","type":"image\/jpeg"}],"author":"Salesforce Espa\u00f1a","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"digital-delivery-operations7076","Tiempo de lectura":"8 minutos","Written by":"Salesforce Espa\u00f1a"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salesforce.com\/es\/blog\/mejorar_servicio_cliente\/#article","isPartOf":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/mejorar_servicio_cliente\/"},"author":[{"@id":"https:\/\/www.salesforce.com\/es\/blog\/#\/schema\/person\/image\/e2f6c6d481bffc386e6e8cdaecd17df6"}],"headline":"C\u00f3mo mejorar la atenci\u00f3n al cliente: 7 maneras de optimizar tu servicio","datePublished":"2023-10-17T19:19:23+00:00","dateModified":"2023-12-20T16:11:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/mejorar_servicio_cliente\/"},"wordCount":1745,"commentCount":0,"image":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/mejorar_servicio_cliente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/SetA-Webinar-Card-Service.jpg","inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.salesforce.com\/es\/blog\/mejorar_servicio_cliente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.salesforce.com\/es\/blog\/mejorar_servicio_cliente\/","url":"https:\/\/www.salesforce.com\/es\/blog\/mejorar_servicio_cliente\/","name":"Un buen servicio al cliente es clave para atraer a los consumidores. Descubre las mejores estrategia para mejorar la atenci\u00f3n al cliente de tu empresa. - Salesforce","isPartOf":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/mejorar_servicio_cliente\/#primaryimage"},"image":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/mejorar_servicio_cliente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/SetA-Webinar-Card-Service.jpg","datePublished":"2023-10-17T19:19:23+00:00","dateModified":"2023-12-20T16:11:01+00:00","author":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/#\/schema\/person\/601f410a2801f4ddcf6f00cb182e69d3"},"description":"Un buen servicio al cliente es clave para atraer a los consumidores. Descubre las mejores estrategia para mejorar la atenci\u00f3n al cliente de tu empresa.","breadcrumb":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/mejorar_servicio_cliente\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salesforce.com\/es\/blog\/mejorar_servicio_cliente\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.salesforce.com\/es\/blog\/mejorar_servicio_cliente\/#primaryimage","url":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/SetA-Webinar-Card-Service.jpg","contentUrl":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/SetA-Webinar-Card-Service.jpg","width":768,"height":432,"caption":"C\u00f3mo mejorar la atenci\u00f3n al cliente: 7 maneras de optimizar tu servicio"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salesforce.com\/es\/blog\/mejorar_servicio_cliente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salesforce.com\/es\/blog\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo mejorar la atenci\u00f3n al cliente: 7 maneras de optimizar tu servicio"}]},{"@type":"WebSite","@id":"https:\/\/www.salesforce.com\/es\/blog\/#website","url":"https:\/\/www.salesforce.com\/es\/blog\/","name":"Salesforce","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salesforce.com\/es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.salesforce.com\/es\/blog\/#\/schema\/person\/image\/e2f6c6d481bffc386e6e8cdaecd17df6","name":"Salesforce Espa\u00f1a","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.salesforce.com\/es\/blog\/#\/schema\/person\/image\/9671a9a1f236a48b35497e55c367902a","url":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/Salesforce-300x300-1.png?w=150&h=150&crop=1","contentUrl":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/Salesforce-300x300-1.png?w=150&h=150&crop=1","width":"150","height":"150","caption":"Salesforce Espa\u00f1a"},"url":"https:\/\/www.salesforce.com\/es\/blog\/author\/salesforce-espana\/"}]}},"jetpack_featured_media_url":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/SetA-Webinar-Card-Service.jpg","jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Salesforce","distributor_original_site_url":"https:\/\/www.salesforce.com\/es\/blog","push-errors":false,"_links":{"self":[{"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/posts\/782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/comments?post=782"}],"version-history":[{"count":3,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/posts\/782\/revisions"}],"predecessor-version":[{"id":2773,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/posts\/782\/revisions\/2773"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/media\/784"}],"wp:attachment":[{"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/media?parent=782"}],"wp:term":[{"taxonomy":"sf_topic","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/sf_topic?post=782"},{"taxonomy":"sf_content_type","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/sf_content_type?post=782"},{"taxonomy":"blog","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/blog?post=782"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/coauthors?post=782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}