{"id":902,"date":"2022-08-11T19:20:00","date_gmt":"2023-10-17T19:20:46","guid":{"rendered":"https:\/\/www.salesforce.com\/?p=902"},"modified":"2023-10-17T19:49:37","modified_gmt":"2023-10-17T19:49:37","slug":"funnel_marketing_messy_middle_nuevo_proceso_compra_consumidor","status":"publish","type":"post","link":"https:\/\/www.salesforce.com\/es\/blog\/funnel_marketing_messy_middle_nuevo_proceso_compra_consumidor\/","title":{"rendered":"Del funnel marketing al \u00abmessy middle\u00bb: el nuevo proceso de compra del consumidor"},"content":{"rendered":" <p>El funnel marketing identifica las fases del proceso de compra online por parte del consumidor. A nivel visual est\u00e1 representado por el cl\u00e1sico embudo (el <a href=\"https:\/\/docs.google.com\/document\/d\/1sYgO4pScI05VkmQyeDaobn4xhsKgBCG6pQPcBVV-Z6k\/edit?usp=sharing\" target=\"_blank\" rel=\"noopener\">significado de la palabra inglesa \u00abfunnel\u00bb es precisamente este<\/a>) dividido en tres partes: conciencia, consideraci\u00f3n y compra.<\/p> <p>La imagen del embudo denota una cierta secuencialidad y tambi\u00e9n una unidireccionalidad impl\u00edcita del proceso de compra. Es como si el comprador, vestido de peregrino, siguiera las diferentes etapas de un camino en un mapa hasta llegar a una meta.<\/p> <p>El valor de esta representaci\u00f3n del embudo de ventas es que ilustra bien la idea de c\u00f3mo la cantidad de posibles compradores disminuye conforme nos vamos acercando a la compra. No obstante, este ya no es el \u00fanico modelo que sirve para interpretar el proceso de aproximaci\u00f3n del usuario al producto\/servicio.<\/p> <!-- BANNER START --> \n<div class=\"layout-one wp-block-salesforce-blog-offer\">\n\t<div class=\"wp-block-offer__wrapper\">\n\n\t\t<div class=\"wp-block-offer__content\">\n\t\t\t<h2 class=\"wp-block-offer__title\">\u00bfC\u00f3mo crear un plan de ventas eficaz?: gu\u00eda \u00fatil para mercados cambiantes<\/h2>\n\t\t\t\t\t\t\t<p class=\"wp-block-offer__description\">Descubra c\u00f3mo Sales Cloud te permite vender con agilidad y conectar con los clientes de la manera que ellos prefieran.<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t<a class=\"wp-block-button__link\" target=\"_self\" href=\"https:\/\/www.salesforce.com\/es\/form\/demo\/demo-sales\/?d=inc-blog-banner&#038;nc=7013y0000022Vx2AAE\">Ver Demo<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"wp-block-offer__media\">\n\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wp-block-offer__graphics wp-block-offer__contour\"><\/div>\n\t\n\t\t\t<!-- Standard Illustration -->\n\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__illustration\" src=\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-illustration-layout-one.png\" alt=\"\">\n\n\t\t<!-- Small Accent Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__accent\" src=\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-accent-layout-one.png\" alt=\"\">\n\t\t\n\t\t<!-- Left Side Illustration -->\n\t\t\n\t\t<!-- Cloud Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__cloud\" src=\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-cloud-layout-one.png\" alt=\"\">\n\t\t\n\t<\/div>\n <!-- END --> <h2><b>Del embudo de ventas secuencial al proceso de compra circular <\/b><\/h2> <p>El proceso de decisi\u00f3n de compra online, con el paso del tiempo, se ha hecho m\u00e1s complejo y ca\u00f3tico, casi fluido.<\/p> <p>Los analistas del equipo de consumer insights de Google, en uno de sus an\u00e1lisis sobre el comportamiento de compra \u00abDecoding decisions: making sense of the messy middle\u00bb, comparan las infinitas posibilidades que existen en cuanto a procesos de aproximaci\u00f3n del usuario al producto o servicio con un plato de espaguetis: una met\u00e1fora divertida y acertada.<\/p> <p>Los mismos investigadores de Google han acu\u00f1ado un neologismo para definir esta fase intermedia, compleja y a menudo confusa: \u00abmessy middle\u00bb, literalmente: \u00abla fase central desordenada\u00bb.<\/p> <p>Situado entre el trigger, es decir, cuando se desencadena el impulso de buscar un producto que se considera necesario, y la compra como tal, con el t\u00e9rmino \u00abmessy middle\u00bb se indica la complejidad y la circularidad del proceso de toma de decisiones que caracteriza hoy en d\u00eda a las diferentes fases del proceso de compra del usuario.<\/p> <p>Por este motivo, de la imagen del embudo hemos pasado a una imagen circular. En el centro, entre el trigger y la compra, se encuentran otras dos \u00e1reas circulares m\u00e1s peque\u00f1as, conectadas entre s\u00ed. Son la fase de exposici\u00f3n, en la que el marketing tiene una funci\u00f3n de acci\u00f3n de continuidad (se habla de marketing \u00abalways on\u00bb que prev\u00e9 estrategias multicanal duraderas en el tiempo en funci\u00f3n de los recursos disponibles) la fase de exploraci\u00f3n en la que el consumidor recaba la informaci\u00f3n sobre todo lo que tiene que ver con un producto o servicio, y una de valoraci\u00f3n en la que empieza a seleccionar la informaci\u00f3n que considera m\u00e1s \u00fatil para tomar la decisi\u00f3n (los dos c\u00edrculos internos).<\/p> <p>Se trata de una fase que puede durar mucho tiempo. Influyen tambi\u00e9n varios factores externos, en los que ya no solo se valora el precio m\u00e1s econ\u00f3mico, sino aspectos cada vez m\u00e1s intangibles vinculados al valor del producto o servicio.<\/p> <h2><b>Sesgos cognitivos y \u00abmessy middle\u00bb<\/b><\/h2> <p>En el \u00abmessy middle\u00bb influyen tambi\u00e9n los llamados sesgos cognitivos, que afectan en gran medida al resultado de la decisi\u00f3n de compra.<\/p> <p>El proceso de toma de decisiones se ve influido por comportamientos del consumidor de los que este no se percata y que responden a motivaciones inconscientes.<\/p> <p>De hecho, los sesgos cognitivos, o distorsiones cognitivas, son interpretaciones subjetivas de la realidad falseadas de tal manera que encajen con nuestras convicciones personales.<\/p> <p>Los analistas e investigadores de Google se centraron en seis sesgos cognitivos que intervienen en el proceso de compra y, en concreto, en el \u00abmessy middle\u00bb:<\/p> <ol> <li><p>Heur\u00edstica de categor\u00eda: las descripciones de los productos son incentivo para la compra.<\/p> <\/li> <li><p>El poder de la inmediatez: si un producto est\u00e1 disponible de inmediato aumentan las posibilidades de que se compre.<\/p> <\/li> <li><p>La aprobaci\u00f3n social: si otras personas han comprado ese producto y hablan sobre \u00e9l o escriben una rese\u00f1a, solemos estar m\u00e1s predispuestos a comprarlo.<\/p> <\/li> <li><p>El principio de escasez: si la disponibilidad de un producto es limitada, resulta m\u00e1s atractivo.<\/p> <\/li> <li><p>El principio de autoridad: la opini\u00f3n de un experto, testimonios u otra fuente fiable influyen positivamente en la fase de toma de decisiones.<\/p> <\/li> <li><p>El poder de lo gratuito: el cl\u00e1sico obsequio de regalo en una compra tambi\u00e9n supone un est\u00edmulo para adquirir el producto o servicio.<\/p> <\/li> <\/ol> <h2><b>\u00bfCu\u00e1les son las principales acciones de marketing en el nuevo \u00abmessy middle\u00bb?<\/b><\/h2> <p>Las<b> fases del proceso de compra<\/b>, por lo tanto, deben sustentarse hoy en d\u00eda en acciones de marketing espec\u00edficas que est\u00e9n en consonancia con el tama\u00f1o y las posibilidades de una empresa.<\/p> <p>Entre otras, destacamos las siguientes:<\/p> <ol> <li><p>Planes de conocimiento de marca que sigan captando la atenci\u00f3n del consumidor hacia una marca, haci\u00e9ndola destacar sobre las opciones que explora y valora y convirti\u00e9ndola en una opci\u00f3n memorable.<\/p> <\/li> <li><p>Aplicar los principios del \u00abbehavioural marketing\u00bb o \u00abmarketing comportamental\u00bb que se basan principalmente en los sesgos cognitivos.<\/p> <\/li> <li><p>Tratar de acercar lo m\u00e1ximo posible el momento del \u00abtrigger\u00bb al de la compra, para reducir el tiempo de exposici\u00f3n de los consumidores a la competencia.<\/p> <\/li> <li><p>Promover la colaboraci\u00f3n entre equipos, para no dejar lagunas en las diferentes fases del proceso de compra.<\/p> <\/li> <\/ol> <p>Cuando el cliente est\u00e1 predispuesto a realizar la compra y realiza la acci\u00f3n deseada, es importante permitir que <b>la experiencia de compra sea lo m\u00e1s fluida y r\u00e1pida posible. <\/b>En este contexto, la \u00abUser Experience\u00bb o \u00abexperiencia del usuario\u00bb juega un papel fundamental.<\/p> <p>Si un consumidor encuentra complicado el proceso de compra, dif\u00edcilmente volver\u00e1 a visitar una tienda online o una tienda f\u00edsica. Estos dos \u00e1mbitos est\u00e1n \u00edntimamente conectados y, si la coordinaci\u00f3n entre ellos no es buena, pueden hacer que se interrumpa el proceso de compra.<\/p> <p>El proceso de decisi\u00f3n es mucho m\u00e1s complejo que en el pasado y resulta impredecible. En ocasiones sorprende incluso a los analistas, que llegan a contar hasta una docena de \u00abtouchpoints\u00bb o \u00abpuntos de contacto\u00bb en los procesos de compra m\u00e1s complejos.<\/p> <p>Por eso es importante mapear el customer journey y, en concreto, el proceso de compra, concentr\u00e1ndose en el seguimiento de los posibles clientes y de aquellos que vuelven.<\/p> <h2><b>Algunos apuntes a modo de conclusi\u00f3n<\/b><\/h2> <p>Este art\u00edculo quiere atraer la atenci\u00f3n de los expertos en marketing sobre ciertos aspectos fundamentales sobre los que debemos reflexionar hoy en d\u00eda:<\/p> <ul> <li>El proceso de compra del consumidor es extremadamente complejo en la actualidad, prev\u00e9 una larga preparaci\u00f3n online, y un v\u00ednculo cada vez m\u00e1s estrecho entre el mundo online y offline.<\/li> <li>El nuevo modelo del proceso de compra del \u00abmessy middle\u00bb es circular. Esto es una se\u00f1al de continuidad, tanto del comportamiento del cliente, como de las acciones de marketing espec\u00edficas.<\/li> <li>El comportamiento de compra y la fase del proceso de decisi\u00f3n depende de decisiones inconscientes en su mayor\u00eda, muy influenciadas por sesgos cognitivos.<\/li> <li>Para las marcas, cada vez es m\u00e1s importante destacar y ser memorables en el imaginario del consumidor.<\/li> <li>Es necesario que los equipos de una empresa colaboren para dise\u00f1ar acciones sin\u00e9rgicas entre marketing y venta online y offline.<\/li> <\/ul> <p>A continuaci\u00f3n, os dejamos otras sugerencias para mejorar la rutina de venta.<\/p> <!-- BANNER START --> \n<div class=\"layout-one wp-block-salesforce-blog-offer\">\n\t<div class=\"wp-block-offer__wrapper\">\n\n\t\t<div class=\"wp-block-offer__content\">\n\t\t\t<h2 class=\"wp-block-offer__title\">\u00bfC\u00f3mo crear un plan de ventas eficaz?: gu\u00eda \u00fatil para mercados cambiantes<\/h2>\n\t\t\t\t\t\t\t<p class=\"wp-block-offer__description\">Descubra c\u00f3mo Sales Cloud te permite vender con agilidad y conectar con los clientes de la manera que ellos prefieran.<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t<a class=\"wp-block-button__link\" target=\"_self\" href=\"https:\/\/www.salesforce.com\/es\/form\/demo\/demo-sales\/?d=inc-blog-banner&#038;nc=7013y0000022Vx2AAE\">Ver Demo<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"wp-block-offer__media\">\n\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wp-block-offer__graphics wp-block-offer__contour\"><\/div>\n\t\n\t\t\t<!-- Standard Illustration -->\n\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__illustration\" src=\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-illustration-layout-one.png\" alt=\"\">\n\n\t\t<!-- Small Accent Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__accent\" src=\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-accent-layout-one.png\" alt=\"\">\n\t\t\n\t\t<!-- Left Side Illustration -->\n\t\t\n\t\t<!-- Cloud Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__cloud\" src=\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-cloud-layout-one.png\" alt=\"\">\n\t\t\n\t<\/div>\n <!-- END --> <span id=\"authorRoot\" path=\"\/content\/blogs\/es\/es\/authors\/\"><\/span> ","protected":false},"excerpt":{"rendered":"<p>Quienes quieran hacer negocios hoy en d\u00eda, en un mercado cada vez m\u00e1s impredecible y cambiante, necesitan elaborar un plan de ventas o sales plan.<\/p>\n","protected":false},"author":1,"featured_media":904,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sf_justforyou_enable_alt":true,"optimizely_content_id":"06bc496943d247769da534d627001a9f","post_meta_title":"","ai_synopsis":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"sf_topic":[7],"sf_content_type":[],"blog":[492],"coauthors":[118],"class_list":["post-902","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","sf_topic-sales-cloud","blog-sales-cloud"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00bfC\u00f3mo crear un plan de ventas eficaz?: gu\u00eda \u00fatil para mercados cambiantes - Salesforce<\/title>\n<meta name=\"description\" content=\"Quienes quieran hacer negocios hoy en d\u00eda, en un mercado cada vez m\u00e1s impredecible y cambiante, necesitan elaborar un plan de ventas o sales plan.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salesforce.com\/es\/blog\/funnel_marketing_messy_middle_nuevo_proceso_compra_consumidor\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Del funnel marketing al \u00abmessy middle\u00bb: el nuevo proceso de compra del consumidor\" \/>\n<meta property=\"og:description\" content=\"Quienes quieran hacer negocios hoy en d\u00eda, en un mercado cada vez m\u00e1s impredecible y cambiante, necesitan elaborar un plan de ventas o sales plan.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salesforce.com\/es\/blog\/funnel_marketing_messy_middle_nuevo_proceso_compra_consumidor\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-17T19:20:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-17T19:49:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/sales-marketing-strategy-from-small-steps-card.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"433\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Salesforce Espa\u00f1a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"digital-delivery-operations7076\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Salesforce Espa\u00f1a\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.salesforce.com\/es\/blog\/funnel_marketing_messy_middle_nuevo_proceso_compra_consumidor\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.salesforce.com\/es\/blog\/funnel_marketing_messy_middle_nuevo_proceso_compra_consumidor\/\"},\"author\":[{\"@id\":\"https:\/\/www.salesforce.com\/es\/blog\/#\/schema\/person\/image\/e2f6c6d481bffc386e6e8cdaecd17df6\"}],\"headline\":\"Del funnel marketing al \u00abmessy middle\u00bb: el nuevo proceso de compra del consumidor\",\"datePublished\":\"2023-10-17T19:20:46+00:00\",\"dateModified\":\"2023-10-17T19:49:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.salesforce.com\/es\/blog\/funnel_marketing_messy_middle_nuevo_proceso_compra_consumidor\/\"},\"wordCount\":1235,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/es\/blog\/funnel_marketing_messy_middle_nuevo_proceso_compra_consumidor\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/sales-marketing-strategy-from-small-steps-card.jpg\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.salesforce.com\/es\/blog\/funnel_marketing_messy_middle_nuevo_proceso_compra_consumidor\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.salesforce.com\/es\/blog\/funnel_marketing_messy_middle_nuevo_proceso_compra_consumidor\/\",\"url\":\"https:\/\/www.salesforce.com\/es\/blog\/funnel_marketing_messy_middle_nuevo_proceso_compra_consumidor\/\",\"name\":\"\u00bfC\u00f3mo crear un plan de ventas eficaz?: gu\u00eda \u00fatil para mercados cambiantes - Salesforce\",\"isPartOf\":{\"@id\":\"https:\/\/www.salesforce.com\/es\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.salesforce.com\/es\/blog\/funnel_marketing_messy_middle_nuevo_proceso_compra_consumidor\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/es\/blog\/funnel_marketing_messy_middle_nuevo_proceso_compra_consumidor\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/sales-marketing-strategy-from-small-steps-card.jpg\",\"datePublished\":\"2023-10-17T19:20:46+00:00\",\"dateModified\":\"2023-10-17T19:49:37+00:00\",\"author\":{\"@id\":\"https:\/\/www.salesforce.com\/es\/blog\/#\/schema\/person\/601f410a2801f4ddcf6f00cb182e69d3\"},\"description\":\"Quienes quieran hacer negocios hoy en d\u00eda, en un mercado cada vez m\u00e1s impredecible y cambiante, necesitan elaborar un plan de ventas o sales plan.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.salesforce.com\/es\/blog\/funnel_marketing_messy_middle_nuevo_proceso_compra_consumidor\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.salesforce.com\/es\/blog\/funnel_marketing_messy_middle_nuevo_proceso_compra_consumidor\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.salesforce.com\/es\/blog\/funnel_marketing_messy_middle_nuevo_proceso_compra_consumidor\/#primaryimage\",\"url\":\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/sales-marketing-strategy-from-small-steps-card.jpg\",\"contentUrl\":\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/sales-marketing-strategy-from-small-steps-card.jpg\",\"width\":768,\"height\":433,\"caption\":\"Del funnel marketing al \u00abmessy middle\u00bb: el nuevo proceso de compra del consumidor\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.salesforce.com\/es\/blog\/funnel_marketing_messy_middle_nuevo_proceso_compra_consumidor\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.salesforce.com\/es\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Del funnel marketing al \u00abmessy middle\u00bb: el nuevo proceso de compra del consumidor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.salesforce.com\/es\/blog\/#website\",\"url\":\"https:\/\/www.salesforce.com\/es\/blog\/\",\"name\":\"Salesforce\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.salesforce.com\/es\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.salesforce.com\/es\/blog\/#\/schema\/person\/image\/e2f6c6d481bffc386e6e8cdaecd17df6\",\"name\":\"Salesforce Espa\u00f1a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.salesforce.com\/es\/blog\/#\/schema\/person\/image\/9671a9a1f236a48b35497e55c367902a\",\"url\":\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/Salesforce-300x300-1.png?w=150&h=150&crop=1\",\"contentUrl\":\"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/Salesforce-300x300-1.png?w=150&h=150&crop=1\",\"width\":\"150\",\"height\":\"150\",\"caption\":\"Salesforce Espa\u00f1a\"},\"url\":\"https:\/\/www.salesforce.com\/es\/blog\/author\/salesforce-espana\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo crear un plan de ventas eficaz?: gu\u00eda \u00fatil para mercados cambiantes - Salesforce","description":"Quienes quieran hacer negocios hoy en d\u00eda, en un mercado cada vez m\u00e1s impredecible y cambiante, necesitan elaborar un plan de ventas o sales plan.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salesforce.com\/es\/blog\/funnel_marketing_messy_middle_nuevo_proceso_compra_consumidor\/","og_locale":"es_ES","og_type":"article","og_title":"Del funnel marketing al \u00abmessy middle\u00bb: el nuevo proceso de compra del consumidor","og_description":"Quienes quieran hacer negocios hoy en d\u00eda, en un mercado cada vez m\u00e1s impredecible y cambiante, necesitan elaborar un plan de ventas o sales plan.","og_url":"https:\/\/www.salesforce.com\/es\/blog\/funnel_marketing_messy_middle_nuevo_proceso_compra_consumidor\/","og_site_name":"Salesforce","article_published_time":"2023-10-17T19:20:46+00:00","article_modified_time":"2023-10-17T19:49:37+00:00","og_image":[{"width":768,"height":433,"url":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/sales-marketing-strategy-from-small-steps-card.jpg","type":"image\/jpeg"}],"author":"Salesforce Espa\u00f1a","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"digital-delivery-operations7076","Tiempo de lectura":"6 minutos","Written by":"Salesforce Espa\u00f1a"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salesforce.com\/es\/blog\/funnel_marketing_messy_middle_nuevo_proceso_compra_consumidor\/#article","isPartOf":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/funnel_marketing_messy_middle_nuevo_proceso_compra_consumidor\/"},"author":[{"@id":"https:\/\/www.salesforce.com\/es\/blog\/#\/schema\/person\/image\/e2f6c6d481bffc386e6e8cdaecd17df6"}],"headline":"Del funnel marketing al \u00abmessy middle\u00bb: el nuevo proceso de compra del consumidor","datePublished":"2023-10-17T19:20:46+00:00","dateModified":"2023-10-17T19:49:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/funnel_marketing_messy_middle_nuevo_proceso_compra_consumidor\/"},"wordCount":1235,"commentCount":0,"image":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/funnel_marketing_messy_middle_nuevo_proceso_compra_consumidor\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/sales-marketing-strategy-from-small-steps-card.jpg","inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.salesforce.com\/es\/blog\/funnel_marketing_messy_middle_nuevo_proceso_compra_consumidor\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.salesforce.com\/es\/blog\/funnel_marketing_messy_middle_nuevo_proceso_compra_consumidor\/","url":"https:\/\/www.salesforce.com\/es\/blog\/funnel_marketing_messy_middle_nuevo_proceso_compra_consumidor\/","name":"\u00bfC\u00f3mo crear un plan de ventas eficaz?: gu\u00eda \u00fatil para mercados cambiantes - Salesforce","isPartOf":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/funnel_marketing_messy_middle_nuevo_proceso_compra_consumidor\/#primaryimage"},"image":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/funnel_marketing_messy_middle_nuevo_proceso_compra_consumidor\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/sales-marketing-strategy-from-small-steps-card.jpg","datePublished":"2023-10-17T19:20:46+00:00","dateModified":"2023-10-17T19:49:37+00:00","author":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/#\/schema\/person\/601f410a2801f4ddcf6f00cb182e69d3"},"description":"Quienes quieran hacer negocios hoy en d\u00eda, en un mercado cada vez m\u00e1s impredecible y cambiante, necesitan elaborar un plan de ventas o sales plan.","breadcrumb":{"@id":"https:\/\/www.salesforce.com\/es\/blog\/funnel_marketing_messy_middle_nuevo_proceso_compra_consumidor\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salesforce.com\/es\/blog\/funnel_marketing_messy_middle_nuevo_proceso_compra_consumidor\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.salesforce.com\/es\/blog\/funnel_marketing_messy_middle_nuevo_proceso_compra_consumidor\/#primaryimage","url":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/sales-marketing-strategy-from-small-steps-card.jpg","contentUrl":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/sales-marketing-strategy-from-small-steps-card.jpg","width":768,"height":433,"caption":"Del funnel marketing al \u00abmessy middle\u00bb: el nuevo proceso de compra del consumidor"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salesforce.com\/es\/blog\/funnel_marketing_messy_middle_nuevo_proceso_compra_consumidor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salesforce.com\/es\/blog\/"},{"@type":"ListItem","position":2,"name":"Del funnel marketing al \u00abmessy middle\u00bb: el nuevo proceso de compra del consumidor"}]},{"@type":"WebSite","@id":"https:\/\/www.salesforce.com\/es\/blog\/#website","url":"https:\/\/www.salesforce.com\/es\/blog\/","name":"Salesforce","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salesforce.com\/es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.salesforce.com\/es\/blog\/#\/schema\/person\/image\/e2f6c6d481bffc386e6e8cdaecd17df6","name":"Salesforce Espa\u00f1a","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.salesforce.com\/es\/blog\/#\/schema\/person\/image\/9671a9a1f236a48b35497e55c367902a","url":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/Salesforce-300x300-1.png?w=150&h=150&crop=1","contentUrl":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/Salesforce-300x300-1.png?w=150&h=150&crop=1","width":"150","height":"150","caption":"Salesforce Espa\u00f1a"},"url":"https:\/\/www.salesforce.com\/es\/blog\/author\/salesforce-espana\/"}]}},"jetpack_featured_media_url":"https:\/\/www.salesforce.com\/es\/blog\/wp-content\/uploads\/sites\/13\/2023\/10\/sales-marketing-strategy-from-small-steps-card.jpg","jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Salesforce","distributor_original_site_url":"https:\/\/www.salesforce.com\/es\/blog","push-errors":false,"_links":{"self":[{"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/posts\/902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/comments?post=902"}],"version-history":[{"count":3,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/posts\/902\/revisions"}],"predecessor-version":[{"id":2800,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/posts\/902\/revisions\/2800"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/media\/904"}],"wp:attachment":[{"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/media?parent=902"}],"wp:term":[{"taxonomy":"sf_topic","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/sf_topic?post=902"},{"taxonomy":"sf_content_type","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/sf_content_type?post=902"},{"taxonomy":"blog","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/blog?post=902"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/blog\/wp-json\/wp\/v2\/coauthors?post=902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}