{"id":1866,"date":"2026-06-24T14:20:13","date_gmt":"2026-06-24T12:20:13","guid":{"rendered":"https:\/\/www.salesforce.com\/?post_type=sf_press_release&#038;p=1866"},"modified":"2026-07-01T14:23:55","modified_gmt":"2026-07-01T12:23:55","slug":"salesforce-y-anthropic-anuncian-la-integracion-de-claude-en-slack","status":"publish","type":"sf_press_release","link":"https:\/\/www.salesforce.com\/es\/news\/press-releases\/2026\/06\/24\/salesforce-y-anthropic-anuncian-la-integracion-de-claude-en-slack\/","title":{"rendered":"Salesforce y Anthropic anuncian la integraci\u00f3n de Claude en Slack"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Madrid, 24 de junio de 2026<\/strong> <strong>\u2013<\/strong> Salesforce, l\u00edder mundial en CRM basado en IA, y Anthropic han anunciado <a href=\"https:\/\/www.anthropic.com\/news\/introducing-claude-tag\" target=\"_blank\" rel=\"noreferrer noopener\">la integraci\u00f3n de Claude en Slack mediante Claude Tag<\/a>, una nueva funcionalidad que incorpora la inteligencia de Anthropic directamente en Slack. Gracias a esta capacidad, los usuarios pueden usar Claude simplemente mencionando @Claude en cualquier canal, incorporando un agente de IA al flujo de trabajo para colaborar en tiempo real en cualquier tipo de tarea sin necesidad de abandonar la conversaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A diferencia de las experiencias tradicionales de IA, que suelen desarrollarse de forma aislada en aplicaciones o ventanas independientes, Claude Tag opera como un miembro m\u00e1s del equipo dentro de Slack. El agente puede acceder al contexto de los canales autorizados, comprender las conversaciones en curso y conectarse con herramientas empresariales y entornos de desarrollo para ejecutar acciones, generar c\u00f3digo o gestionar solicitudes. Todo ello de forma transparente para el equipo, que puede seguir, enriquecer y redirigir el trabajo del agente en tiempo real desde el propio canal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La integraci\u00f3n tambi\u00e9n refuerza el concepto de inteligencia colaborativa al combinar las capacidades de Slackbot y Claude dentro de una misma plataforma. Mientras Slackbot proporciona una experiencia contextual basada en el conocimiento y la memoria organizativa de la compa\u00f1\u00eda, Claude aporta capacidades especializadas para casos de uso t\u00e9cnicos, desarrollo de software y flujos de trabajo avanzados. Esta combinaci\u00f3n permite a las organizaciones incorporar distintos tipos de agentes de IA en un entorno unificado, facilitando una colaboraci\u00f3n m\u00e1s eficiente entre personas y agentes digitales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con esta innovaci\u00f3n, Salesforce y Anthropic avanzan en su visi\u00f3n de una IA verdaderamente integrada en el trabajo diario, donde los agentes no act\u00faan de forma aislada, sino como participantes activos dentro de los equipos. Al aprovechar el contexto compartido de las conversaciones, el conocimiento organizativo y las herramientas empresariales existentes, las compa\u00f1\u00edas pueden acelerar la toma de decisiones, mejorar la productividad y escalar el uso de la inteligencia artificial de manera m\u00e1s efectiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Rob Seaman<\/strong>, EVP &amp; GM de Slack afirma acerca de esta integraci\u00f3n<em> \u00abSlack es el espacio donde los equipos colaboran y toman decisiones cada d\u00eda. Con la incorporaci\u00f3n de Claude Tag, damos un paso m\u00e1s hacia una IA verdaderamente colaborativa, capaz de trabajar junto a las personas dentro del contexto real de la organizaci\u00f3n. Al integrar la inteligencia artificial directamente en las conversaciones y flujos de trabajo compartidos, las empresas pueden aprovechar mejor su conocimiento colectivo, acelerar la ejecuci\u00f3n y generar un impacto tangible a escala\u00bb.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid, 24 de junio de 2026 \u2013 Salesforce, l\u00edder mundial en CRM basado en IA, y Anthropic han anunciado la integraci\u00f3n de Claude en Slack mediante Claude Tag, una nueva funcionalidad que incorpora la inteligencia de Anthropic directamente en Slack. Gracias a esta capacidad, los usuarios pueden usar Claude simplemente mencionando @Claude en cualquier canal, [&hellip;]<\/p>\n","protected":false},"author":649,"featured_media":1867,"template":"","meta":{"sf_subhead":"","sf_i18n_disclaimer":false,"alternateThumbnailId":0,"sf_product_cta_id":0,"footnotes":""},"sf_content_type":[],"sf_theme":[],"sf_topic":[],"sf_product":[88],"sf_industry":[],"sf_role":[],"sf_multimedia_asset":[],"sf_location":[],"sf_collection":[],"sf_visibility":[],"coauthors":[294],"class_list":["post-1866","sf_press_release","type-sf_press_release","status-publish","has-post-thumbnail","hentry","sf_product-slack"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Salesforce y Anthropic anuncian la integraci\u00f3n de Claude en Slack - Salesforce<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salesforce y Anthropic anuncian la integraci\u00f3n de Claude en Slack\" \/>\n<meta property=\"og:description\" content=\"Madrid, 24 de junio de 2026 \u2013 Salesforce, l\u00edder mundial en CRM basado en IA, y Anthropic han anunciado la integraci\u00f3n de Claude en Slack mediante Claude Tag, una nueva funcionalidad que incorpora la inteligencia de Anthropic directamente en Slack. Gracias a esta capacidad, los usuarios pueden usar Claude simplemente mencionando @Claude en cualquier canal, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salesforce.com\/es\/news\/press-releases\/2026\/06\/24\/salesforce-y-anthropic-anuncian-la-integracion-de-claude-en-slack\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-01T12:23:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salesforce.com\/es\/news\/wp-content\/uploads\/sites\/26\/2026\/07\/Claude.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2400\" \/>\n\t<meta property=\"og:image:height\" content=\"1260\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Simona Paperini\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/press-releases\\\/2026\\\/06\\\/24\\\/salesforce-y-anthropic-anuncian-la-integracion-de-claude-en-slack\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/press-releases\\\/2026\\\/06\\\/24\\\/salesforce-y-anthropic-anuncian-la-integracion-de-claude-en-slack\\\/\"},\"author\":[{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/#\\\/schema\\\/person\\\/5e8c79e283acb847e940d3fd5019cf13\"}],\"headline\":\"Salesforce y Anthropic anuncian la integraci\u00f3n de Claude en Slack\",\"datePublished\":\"2026-06-24T12:20:13+00:00\",\"dateModified\":\"2026-07-01T12:23:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/press-releases\\\/2026\\\/06\\\/24\\\/salesforce-y-anthropic-anuncian-la-integracion-de-claude-en-slack\\\/\"},\"wordCount\":442,\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/press-releases\\\/2026\\\/06\\\/24\\\/salesforce-y-anthropic-anuncian-la-integracion-de-claude-en-slack\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2026\\\/07\\\/Claude.png\",\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/press-releases\\\/2026\\\/06\\\/24\\\/salesforce-y-anthropic-anuncian-la-integracion-de-claude-en-slack\\\/\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/press-releases\\\/2026\\\/06\\\/24\\\/salesforce-y-anthropic-anuncian-la-integracion-de-claude-en-slack\\\/\",\"name\":\"Salesforce y Anthropic anuncian la integraci\u00f3n de Claude en Slack - Salesforce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/press-releases\\\/2026\\\/06\\\/24\\\/salesforce-y-anthropic-anuncian-la-integracion-de-claude-en-slack\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/press-releases\\\/2026\\\/06\\\/24\\\/salesforce-y-anthropic-anuncian-la-integracion-de-claude-en-slack\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2026\\\/07\\\/Claude.png\",\"datePublished\":\"2026-06-24T12:20:13+00:00\",\"dateModified\":\"2026-07-01T12:23:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/press-releases\\\/2026\\\/06\\\/24\\\/salesforce-y-anthropic-anuncian-la-integracion-de-claude-en-slack\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/press-releases\\\/2026\\\/06\\\/24\\\/salesforce-y-anthropic-anuncian-la-integracion-de-claude-en-slack\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/press-releases\\\/2026\\\/06\\\/24\\\/salesforce-y-anthropic-anuncian-la-integracion-de-claude-en-slack\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2026\\\/07\\\/Claude.png\",\"contentUrl\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2026\\\/07\\\/Claude.png\",\"width\":2400,\"height\":1260,\"caption\":\"Claude\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/press-releases\\\/2026\\\/06\\\/24\\\/salesforce-y-anthropic-anuncian-la-integracion-de-claude-en-slack\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Press Releases\",\"item\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/sf_press_release\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Salesforce y Anthropic anuncian la integraci\u00f3n de Claude en Slack\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/\",\"name\":\"Salesforce\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/#\\\/schema\\\/person\\\/5e8c79e283acb847e940d3fd5019cf13\",\"name\":\"Simona Paperini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/741ac0a09f4813b96538a894f52df4f87701f9091417de6329cd053c9347d34a?s=96&d=mm&r=g67ac9ad6c0e501381f19ede19ba2267b\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/741ac0a09f4813b96538a894f52df4f87701f9091417de6329cd053c9347d34a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/741ac0a09f4813b96538a894f52df4f87701f9091417de6329cd053c9347d34a?s=96&d=mm&r=g\",\"caption\":\"Simona Paperini\"},\"url\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/author\\\/spaperinisalesforce-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Salesforce y Anthropic anuncian la integraci\u00f3n de Claude en Slack - Salesforce","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Salesforce y Anthropic anuncian la integraci\u00f3n de Claude en Slack","og_description":"Madrid, 24 de junio de 2026 \u2013 Salesforce, l\u00edder mundial en CRM basado en IA, y Anthropic han anunciado la integraci\u00f3n de Claude en Slack mediante Claude Tag, una nueva funcionalidad que incorpora la inteligencia de Anthropic directamente en Slack. Gracias a esta capacidad, los usuarios pueden usar Claude simplemente mencionando @Claude en cualquier canal, [&hellip;]","og_url":"https:\/\/www.salesforce.com\/es\/news\/press-releases\/2026\/06\/24\/salesforce-y-anthropic-anuncian-la-integracion-de-claude-en-slack\/","og_site_name":"Salesforce","article_modified_time":"2026-07-01T12:23:55+00:00","og_image":[{"width":2400,"height":1260,"url":"https:\/\/www.salesforce.com\/es\/news\/wp-content\/uploads\/sites\/26\/2026\/07\/Claude.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos","Written by":"Simona Paperini"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.salesforce.com\/es\/news\/press-releases\/2026\/06\/24\/salesforce-y-anthropic-anuncian-la-integracion-de-claude-en-slack\/#article","isPartOf":{"@id":"https:\/\/www.salesforce.com\/es\/news\/press-releases\/2026\/06\/24\/salesforce-y-anthropic-anuncian-la-integracion-de-claude-en-slack\/"},"author":[{"@id":"https:\/\/www.salesforce.com\/es\/news\/#\/schema\/person\/5e8c79e283acb847e940d3fd5019cf13"}],"headline":"Salesforce y Anthropic anuncian la integraci\u00f3n de Claude en Slack","datePublished":"2026-06-24T12:20:13+00:00","dateModified":"2026-07-01T12:23:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salesforce.com\/es\/news\/press-releases\/2026\/06\/24\/salesforce-y-anthropic-anuncian-la-integracion-de-claude-en-slack\/"},"wordCount":442,"image":{"@id":"https:\/\/www.salesforce.com\/es\/news\/press-releases\/2026\/06\/24\/salesforce-y-anthropic-anuncian-la-integracion-de-claude-en-slack\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/es\/news\/wp-content\/uploads\/sites\/26\/2026\/07\/Claude.png","inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.salesforce.com\/es\/news\/press-releases\/2026\/06\/24\/salesforce-y-anthropic-anuncian-la-integracion-de-claude-en-slack\/","url":"https:\/\/www.salesforce.com\/es\/news\/press-releases\/2026\/06\/24\/salesforce-y-anthropic-anuncian-la-integracion-de-claude-en-slack\/","name":"Salesforce y Anthropic anuncian la integraci\u00f3n de Claude en Slack - Salesforce","isPartOf":{"@id":"https:\/\/www.salesforce.com\/es\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salesforce.com\/es\/news\/press-releases\/2026\/06\/24\/salesforce-y-anthropic-anuncian-la-integracion-de-claude-en-slack\/#primaryimage"},"image":{"@id":"https:\/\/www.salesforce.com\/es\/news\/press-releases\/2026\/06\/24\/salesforce-y-anthropic-anuncian-la-integracion-de-claude-en-slack\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/es\/news\/wp-content\/uploads\/sites\/26\/2026\/07\/Claude.png","datePublished":"2026-06-24T12:20:13+00:00","dateModified":"2026-07-01T12:23:55+00:00","breadcrumb":{"@id":"https:\/\/www.salesforce.com\/es\/news\/press-releases\/2026\/06\/24\/salesforce-y-anthropic-anuncian-la-integracion-de-claude-en-slack\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salesforce.com\/es\/news\/press-releases\/2026\/06\/24\/salesforce-y-anthropic-anuncian-la-integracion-de-claude-en-slack\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.salesforce.com\/es\/news\/press-releases\/2026\/06\/24\/salesforce-y-anthropic-anuncian-la-integracion-de-claude-en-slack\/#primaryimage","url":"https:\/\/www.salesforce.com\/es\/news\/wp-content\/uploads\/sites\/26\/2026\/07\/Claude.png","contentUrl":"https:\/\/www.salesforce.com\/es\/news\/wp-content\/uploads\/sites\/26\/2026\/07\/Claude.png","width":2400,"height":1260,"caption":"Claude"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salesforce.com\/es\/news\/press-releases\/2026\/06\/24\/salesforce-y-anthropic-anuncian-la-integracion-de-claude-en-slack\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salesforce.com\/es\/news\/"},{"@type":"ListItem","position":2,"name":"Press Releases","item":"https:\/\/www.salesforce.com\/es\/news\/sf_press_release\/"},{"@type":"ListItem","position":3,"name":"Salesforce y Anthropic anuncian la integraci\u00f3n de Claude en Slack"}]},{"@type":"WebSite","@id":"https:\/\/www.salesforce.com\/es\/news\/#website","url":"https:\/\/www.salesforce.com\/es\/news\/","name":"Salesforce","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salesforce.com\/es\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.salesforce.com\/es\/news\/#\/schema\/person\/5e8c79e283acb847e940d3fd5019cf13","name":"Simona Paperini","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/741ac0a09f4813b96538a894f52df4f87701f9091417de6329cd053c9347d34a?s=96&d=mm&r=g67ac9ad6c0e501381f19ede19ba2267b","url":"https:\/\/secure.gravatar.com\/avatar\/741ac0a09f4813b96538a894f52df4f87701f9091417de6329cd053c9347d34a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/741ac0a09f4813b96538a894f52df4f87701f9091417de6329cd053c9347d34a?s=96&d=mm&r=g","caption":"Simona Paperini"},"url":"https:\/\/www.salesforce.com\/es\/news\/author\/spaperinisalesforce-com\/"}]}},"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Salesforce","distributor_original_site_url":"https:\/\/www.salesforce.com\/es\/news","push-errors":false,"_links":{"self":[{"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/sf_press_release\/1866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/sf_press_release"}],"about":[{"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/types\/sf_press_release"}],"author":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/users\/649"}],"version-history":[{"count":1,"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/sf_press_release\/1866\/revisions"}],"predecessor-version":[{"id":1868,"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/sf_press_release\/1866\/revisions\/1868"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/media\/1867"}],"wp:attachment":[{"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/media?parent=1866"}],"wp:term":[{"taxonomy":"sf_content_type","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/sf_content_type?post=1866"},{"taxonomy":"sf_theme","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/sf_theme?post=1866"},{"taxonomy":"sf_topic","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/sf_topic?post=1866"},{"taxonomy":"sf_product","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/sf_product?post=1866"},{"taxonomy":"sf_industry","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/sf_industry?post=1866"},{"taxonomy":"sf_role","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/sf_role?post=1866"},{"taxonomy":"sf_multimedia_asset","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/sf_multimedia_asset?post=1866"},{"taxonomy":"sf_location","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/sf_location?post=1866"},{"taxonomy":"sf_collection","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/sf_collection?post=1866"},{"taxonomy":"sf_visibility","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/sf_visibility?post=1866"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/coauthors?post=1866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}