{"id":971,"date":"2025-04-07T12:00:00","date_gmt":"2025-04-07T10:00:00","guid":{"rendered":"https:\/\/www.salesforce.com\/?post_type=sf_press_release&#038;p=971"},"modified":"2025-04-07T16:01:29","modified_gmt":"2025-04-07T14:01:29","slug":"caixabank-y-salesforce-colaboran-para-aplicar-la-ia-en-la-personalizacion-de-la-experiencia-de-cliente-en-los-servicios-bancarios","status":"publish","type":"sf_press_release","link":"https:\/\/www.salesforce.com\/es\/news\/press-releases\/2025\/04\/07\/caixabank-y-salesforce-colaboran-para-aplicar-la-ia-en-la-personalizacion-de-la-experiencia-de-cliente-en-los-servicios-bancarios\/","title":{"rendered":"CaixaBank y Salesforce colaboran para aplicar la IA en la personalizaci\u00f3n de la experiencia de cliente en los servicios bancarios\u00a0"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong><em>La entidad implementar\u00e1 soluciones tecnol\u00f3gicas avanzadas que permitir\u00e1n agilizar los procesos de trabajo y ofrecer a los clientes m\u00e1s calidad y una mejor adaptaci\u00f3n a sus necesidades.\u00a0<\/em><\/strong><br><\/li>\n\n\n\n<li><strong><em>La iniciativa incluye herramientas como los agentes de IA de Agentforce y soluciones de Data Cloud para la generaci\u00f3n y an\u00e1lisis de datos.\u00a0<\/em><\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>7 abril 2025<\/strong> &#8211; CaixaBank y Salesforce, empresa l\u00edder en soluciones tecnol\u00f3gicas en <em>Customer Relationship Management<\/em> (CRM), han firmado un acuerdo para avanzar conjuntamente en proyectos de inteligencia artificial para la transformaci\u00f3n digital de los servicios bancarios. En virtud de este acuerdo estrat\u00e9gico, el segundo que la entidad firma con la compa\u00f1\u00eda, CaixaBank aplicar\u00e1 la tecnolog\u00eda de Salesforce en la redefinici\u00f3n de los diferentes canales de relaci\u00f3n con los clientes para la mejora de la experiencia y de la calidad en la atenci\u00f3n.\u202f\u202f\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El proyecto incluye herramientas basadas en inteligencia artificial, como <em>Agentforce<\/em>, los asistentes integrados en la plataforma de Salesforce, soluciones como <em>Salesforce Data Cloud<\/em>, para la gesti\u00f3n y el an\u00e1lisis de datos, y continuar\u00e1 desplegando otras soluciones dentro de Salesforce.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Agentforce<\/em> es una innovadora soluci\u00f3n que permite el despliegue \u00e1gil de agentes de IA dise\u00f1ados para ofrecer asistencia especializada tanto a empleados como a clientes de CaixaBank. Estos agentes operan de manera proactiva e ininterrumpida, procesando grandes vol\u00famenes de informaci\u00f3n con rapidez para optimizar la toma de decisiones y mejorar la eficiencia en la ejecuci\u00f3n de tareas. Desde las app de la entidad a los <em>chatbots<\/em>, oficinas f\u00edsicas y centros de atenci\u00f3n telef\u00f3nica, <em>Agentforce<\/em> permite responder de forma r\u00e1pida y precisa a las consultas realizadas por los clientes. En paralelo, los empleados de la entidad podr\u00e1n contar con este apoyo para reducir la carga de trabajo de tareas repetitivas y poder dedicarse a tareas m\u00e1s complejas y de mayor valor a\u00f1adido como la asesor\u00eda personalizada, entre otras funciones.\u202f&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, la implementaci\u00f3n de <em>Data Cloud<\/em>, la soluci\u00f3n de Salesforce para la gesti\u00f3n y an\u00e1lisis de datos en la nube, gestionar\u00e1 la transmisi\u00f3n de los datos producidos por la entidad para que est\u00e9n disponibles de forma inmediata a la hora de realizar cualquier consulta. De este modo, los datos se registrar\u00e1n de manera segura y eficiente y permitir\u00e1n su consulta en tiempo real.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de la aplicaci\u00f3n de soluciones IA, en el marco del nuevo acuerdo alcanzado con CaixaBank, Salesforce se posicionar\u00e1 como la plataforma que centralizar\u00e1 de forma conjunta las interacciones relacionadas con venta y servicio de CaixaBank.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Caso de uso: asistente de soporte a la contrataci\u00f3n digital\u202f&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de los casos de uso m\u00e1s recientes implantados por CaixaBank es un asistente de soporte a la contrataci\u00f3n remota, que utiliza la IA generativa para ayudar a gestores y clientes a reducir los tiempos de interacci\u00f3n e impulsar la contrataci\u00f3n de productos desde los canales digitales (app y web). Este asistente, desarrollado por CaixaBank Tech con herramientas de IA nativas de la plataforma Salesforce, se ha creado espec\u00edficamente para un equipo de m\u00e1s de 300 empleados de la entidad que da soporte a clientes en la contrataci\u00f3n de productos por canales digitales.\u202f&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este equipo se activa a trav\u00e9s del bot\u00f3n <em>\u2018\u00bfTe ayudamos?\u2019<\/em> que se encuentra en la app y en la web. Desde que el cliente lo solicita, un gestor tiene el compromiso de contactar con \u00e9l en menos de dos minutos. Tanto durante este tiempo previo de preparaci\u00f3n como durante el transcurso de la llamada, el asistente de ventas proporciona gran cantidad de informaci\u00f3n al gestor para resolver sus dudas y ayudarlo en su gesti\u00f3n. \u202f&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ejemplo, le ofrece algunos datos del cliente y de su relaci\u00f3n con la entidad; informaci\u00f3n del producto por el que se ha interesado; cruce de las condiciones del producto con las caracter\u00edsticas del cliente; comparativa con otros productos de la entidad; o un chat interactivo al que el gestor puede plantear cualquier tipo de consulta. Toda esta informaci\u00f3n viaja de manera encriptada y Salesforce garantiza adem\u00e1s que el modelo de relaci\u00f3n no se entrena con los datos enviados al <em>Large Language Model<\/em> (LLM). Se trata de un uso seguro y responsable de la IA.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El asistente evolucionar\u00e1 hasta convertirse en un agente (<em>Agentforce<\/em>), que act\u00fae de forma proactiva cuando detecte una oportunidad y, por ejemplo, pueda sugerir otros productos de inter\u00e9s para el cliente, programar citas, recordar promociones en curso, etc.\u202f\u202f&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La IA, aliada de los clientes y de los profesionales\u202f&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La aplicaci\u00f3n de la inteligencia artificial tiene un impacto positivo en el d\u00eda a d\u00eda de clientes y empleados, ya que permite agilizar muchas de las tareas rutinarias y centrar la aportaci\u00f3n humana en la generaci\u00f3n de valor.\u202f&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">CaixaBank es pionera en el uso de la inteligencia artificial aplicada a los servicios financieros en Espa\u00f1a, con una larga experiencia de aplicaci\u00f3n de esta tecnolog\u00eda en diferentes aplicaciones y casos de uso, como los primeros asistentes cognitivos desarrollados en el sector financiero espa\u00f1ol para atender a empleados y a clientes\u202f&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La IA generativa supone un paso m\u00e1s, con un alcance muy superior y un potencial inmenso para mejorar aspectos como la productividad, la comunicaci\u00f3n con el cliente o la programaci\u00f3n. CaixaBank cuenta un equipo transversal y de dedicaci\u00f3n exclusiva, conformado por m\u00e1s de 100 personas, para analizar y desplegar Inteligencia Artificial generativa en \u00e1mbitos concretos de procesos, tanto internos como de clientes.\u202f\u202f&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>CaixaBank, referente en innovaci\u00f3n en el sector financiero\u202f&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La tecnolog\u00eda y la innovaci\u00f3n son clave para CaixaBank. Con la mayor base de clientes digitales del sector financiero en Espa\u00f1a, cerca de 12 millones, la entidad se sit\u00faa a la vanguardia en el desarrollo de nuevos modelos y sistemas para dar respuesta a las demandas de sus clientes.\u202f\u202f\u202f\u202f&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gracias a su estrategia de transformaci\u00f3n digital, CaixaBank se ha situado entre los bancos mejor valorados del mundo por la calidad de sus productos y servicios digitales y ha recibido m\u00faltiples reconocimientos internacionales. Entre otros, destacan el de Mejor Banco en Espa\u00f1a 2024, Mejor Banco Digital en Espa\u00f1a 2024 y Mejor Banco en ESG en Espa\u00f1a 2024. Adem\u00e1s, CaixaBank tambi\u00e9n ha sido galardonada con el premio al Mejor Banco en Europa Occidental 2024 y Mejor Banco en Espa\u00f1a 2024 por Global Finance \u2013 The Innovators.\u202f\u202f\u202f&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>7 abril 2025 &#8211; CaixaBank y Salesforce, empresa l\u00edder en soluciones tecnol\u00f3gicas en Customer Relationship Management (CRM), han firmado un acuerdo para avanzar conjuntamente en proyectos de inteligencia artificial para la transformaci\u00f3n digital de los servicios bancarios. En virtud de este acuerdo estrat\u00e9gico, el segundo que la entidad firma con la compa\u00f1\u00eda, CaixaBank aplicar\u00e1 la [&hellip;]<\/p>\n","protected":false},"author":649,"featured_media":972,"template":"","meta":{"sf_subhead":"","sf_i18n_disclaimer":false,"alternateThumbnailId":0,"sf_product_cta_id":0,"footnotes":""},"sf_content_type":[],"sf_theme":[],"sf_topic":[2],"sf_product":[],"sf_industry":[],"sf_role":[],"sf_multimedia_asset":[],"sf_location":[],"sf_collection":[],"sf_visibility":[],"coauthors":[294],"class_list":["post-971","sf_press_release","type-sf_press_release","status-publish","has-post-thumbnail","hentry","sf_topic-artificial-intelligence"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>CaixaBank y Salesforce colaboran para aplicar la IA en la personalizaci\u00f3n de la experiencia de cliente en los servicios bancarios\u00a0 - Salesforce<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CaixaBank y Salesforce colaboran para aplicar la IA en la personalizaci\u00f3n de la experiencia de cliente en los servicios bancarios\u00a0\" \/>\n<meta property=\"og:description\" content=\"7 abril 2025 &#8211; CaixaBank y Salesforce, empresa l\u00edder en soluciones tecnol\u00f3gicas en Customer Relationship Management (CRM), han firmado un acuerdo para avanzar conjuntamente en proyectos de inteligencia artificial para la transformaci\u00f3n digital de los servicios bancarios. En virtud de este acuerdo estrat\u00e9gico, el segundo que la entidad firma con la compa\u00f1\u00eda, CaixaBank aplicar\u00e1 la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salesforce.com\/es\/news\/press-releases\/2025\/04\/07\/caixabank-y-salesforce-colaboran-para-aplicar-la-ia-en-la-personalizacion-de-la-experiencia-de-cliente-en-los-servicios-bancarios\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-07T14:01:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salesforce.com\/es\/news\/wp-content\/uploads\/sites\/26\/2025\/04\/unnamed.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Simona Paperini\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/press-releases\\\/2025\\\/04\\\/07\\\/caixabank-y-salesforce-colaboran-para-aplicar-la-ia-en-la-personalizacion-de-la-experiencia-de-cliente-en-los-servicios-bancarios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/press-releases\\\/2025\\\/04\\\/07\\\/caixabank-y-salesforce-colaboran-para-aplicar-la-ia-en-la-personalizacion-de-la-experiencia-de-cliente-en-los-servicios-bancarios\\\/\"},\"author\":[{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/#\\\/schema\\\/person\\\/5e8c79e283acb847e940d3fd5019cf13\"}],\"headline\":\"CaixaBank y Salesforce colaboran para aplicar la IA en la personalizaci\u00f3n de la experiencia de cliente en los servicios bancarios\u00a0\",\"datePublished\":\"2025-04-07T10:00:00+00:00\",\"dateModified\":\"2025-04-07T14:01:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/press-releases\\\/2025\\\/04\\\/07\\\/caixabank-y-salesforce-colaboran-para-aplicar-la-ia-en-la-personalizacion-de-la-experiencia-de-cliente-en-los-servicios-bancarios\\\/\"},\"wordCount\":1127,\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/press-releases\\\/2025\\\/04\\\/07\\\/caixabank-y-salesforce-colaboran-para-aplicar-la-ia-en-la-personalizacion-de-la-experiencia-de-cliente-en-los-servicios-bancarios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2025\\\/04\\\/unnamed.jpg\",\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/press-releases\\\/2025\\\/04\\\/07\\\/caixabank-y-salesforce-colaboran-para-aplicar-la-ia-en-la-personalizacion-de-la-experiencia-de-cliente-en-los-servicios-bancarios\\\/\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/press-releases\\\/2025\\\/04\\\/07\\\/caixabank-y-salesforce-colaboran-para-aplicar-la-ia-en-la-personalizacion-de-la-experiencia-de-cliente-en-los-servicios-bancarios\\\/\",\"name\":\"CaixaBank y Salesforce colaboran para aplicar la IA en la personalizaci\u00f3n de la experiencia de cliente en los servicios bancarios\u00a0 - Salesforce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/press-releases\\\/2025\\\/04\\\/07\\\/caixabank-y-salesforce-colaboran-para-aplicar-la-ia-en-la-personalizacion-de-la-experiencia-de-cliente-en-los-servicios-bancarios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/press-releases\\\/2025\\\/04\\\/07\\\/caixabank-y-salesforce-colaboran-para-aplicar-la-ia-en-la-personalizacion-de-la-experiencia-de-cliente-en-los-servicios-bancarios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2025\\\/04\\\/unnamed.jpg\",\"datePublished\":\"2025-04-07T10:00:00+00:00\",\"dateModified\":\"2025-04-07T14:01:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/press-releases\\\/2025\\\/04\\\/07\\\/caixabank-y-salesforce-colaboran-para-aplicar-la-ia-en-la-personalizacion-de-la-experiencia-de-cliente-en-los-servicios-bancarios\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/press-releases\\\/2025\\\/04\\\/07\\\/caixabank-y-salesforce-colaboran-para-aplicar-la-ia-en-la-personalizacion-de-la-experiencia-de-cliente-en-los-servicios-bancarios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/press-releases\\\/2025\\\/04\\\/07\\\/caixabank-y-salesforce-colaboran-para-aplicar-la-ia-en-la-personalizacion-de-la-experiencia-de-cliente-en-los-servicios-bancarios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2025\\\/04\\\/unnamed.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2025\\\/04\\\/unnamed.jpg\",\"width\":1000,\"height\":667,\"caption\":\"CaixaBank x Salesforce\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/press-releases\\\/2025\\\/04\\\/07\\\/caixabank-y-salesforce-colaboran-para-aplicar-la-ia-en-la-personalizacion-de-la-experiencia-de-cliente-en-los-servicios-bancarios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Press Releases\",\"item\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/sf_press_release\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CaixaBank y Salesforce colaboran para aplicar la IA en la personalizaci\u00f3n de la experiencia de cliente en los servicios bancarios\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/\",\"name\":\"Salesforce\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/#\\\/schema\\\/person\\\/5e8c79e283acb847e940d3fd5019cf13\",\"name\":\"Simona Paperini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/741ac0a09f4813b96538a894f52df4f87701f9091417de6329cd053c9347d34a?s=96&d=mm&r=g67ac9ad6c0e501381f19ede19ba2267b\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/741ac0a09f4813b96538a894f52df4f87701f9091417de6329cd053c9347d34a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/741ac0a09f4813b96538a894f52df4f87701f9091417de6329cd053c9347d34a?s=96&d=mm&r=g\",\"caption\":\"Simona Paperini\"},\"url\":\"https:\\\/\\\/www.salesforce.com\\\/es\\\/news\\\/author\\\/spaperinisalesforce-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"CaixaBank y Salesforce colaboran para aplicar la IA en la personalizaci\u00f3n de la experiencia de cliente en los servicios bancarios\u00a0 - Salesforce","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"CaixaBank y Salesforce colaboran para aplicar la IA en la personalizaci\u00f3n de la experiencia de cliente en los servicios bancarios\u00a0","og_description":"7 abril 2025 &#8211; CaixaBank y Salesforce, empresa l\u00edder en soluciones tecnol\u00f3gicas en Customer Relationship Management (CRM), han firmado un acuerdo para avanzar conjuntamente en proyectos de inteligencia artificial para la transformaci\u00f3n digital de los servicios bancarios. En virtud de este acuerdo estrat\u00e9gico, el segundo que la entidad firma con la compa\u00f1\u00eda, CaixaBank aplicar\u00e1 la [&hellip;]","og_url":"https:\/\/www.salesforce.com\/es\/news\/press-releases\/2025\/04\/07\/caixabank-y-salesforce-colaboran-para-aplicar-la-ia-en-la-personalizacion-de-la-experiencia-de-cliente-en-los-servicios-bancarios\/","og_site_name":"Salesforce","article_modified_time":"2025-04-07T14:01:29+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/www.salesforce.com\/es\/news\/wp-content\/uploads\/sites\/26\/2025\/04\/unnamed.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos","Written by":"Simona Paperini"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.salesforce.com\/es\/news\/press-releases\/2025\/04\/07\/caixabank-y-salesforce-colaboran-para-aplicar-la-ia-en-la-personalizacion-de-la-experiencia-de-cliente-en-los-servicios-bancarios\/#article","isPartOf":{"@id":"https:\/\/www.salesforce.com\/es\/news\/press-releases\/2025\/04\/07\/caixabank-y-salesforce-colaboran-para-aplicar-la-ia-en-la-personalizacion-de-la-experiencia-de-cliente-en-los-servicios-bancarios\/"},"author":[{"@id":"https:\/\/www.salesforce.com\/es\/news\/#\/schema\/person\/5e8c79e283acb847e940d3fd5019cf13"}],"headline":"CaixaBank y Salesforce colaboran para aplicar la IA en la personalizaci\u00f3n de la experiencia de cliente en los servicios bancarios\u00a0","datePublished":"2025-04-07T10:00:00+00:00","dateModified":"2025-04-07T14:01:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salesforce.com\/es\/news\/press-releases\/2025\/04\/07\/caixabank-y-salesforce-colaboran-para-aplicar-la-ia-en-la-personalizacion-de-la-experiencia-de-cliente-en-los-servicios-bancarios\/"},"wordCount":1127,"image":{"@id":"https:\/\/www.salesforce.com\/es\/news\/press-releases\/2025\/04\/07\/caixabank-y-salesforce-colaboran-para-aplicar-la-ia-en-la-personalizacion-de-la-experiencia-de-cliente-en-los-servicios-bancarios\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/es\/news\/wp-content\/uploads\/sites\/26\/2025\/04\/unnamed.jpg","inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.salesforce.com\/es\/news\/press-releases\/2025\/04\/07\/caixabank-y-salesforce-colaboran-para-aplicar-la-ia-en-la-personalizacion-de-la-experiencia-de-cliente-en-los-servicios-bancarios\/","url":"https:\/\/www.salesforce.com\/es\/news\/press-releases\/2025\/04\/07\/caixabank-y-salesforce-colaboran-para-aplicar-la-ia-en-la-personalizacion-de-la-experiencia-de-cliente-en-los-servicios-bancarios\/","name":"CaixaBank y Salesforce colaboran para aplicar la IA en la personalizaci\u00f3n de la experiencia de cliente en los servicios bancarios\u00a0 - Salesforce","isPartOf":{"@id":"https:\/\/www.salesforce.com\/es\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salesforce.com\/es\/news\/press-releases\/2025\/04\/07\/caixabank-y-salesforce-colaboran-para-aplicar-la-ia-en-la-personalizacion-de-la-experiencia-de-cliente-en-los-servicios-bancarios\/#primaryimage"},"image":{"@id":"https:\/\/www.salesforce.com\/es\/news\/press-releases\/2025\/04\/07\/caixabank-y-salesforce-colaboran-para-aplicar-la-ia-en-la-personalizacion-de-la-experiencia-de-cliente-en-los-servicios-bancarios\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/es\/news\/wp-content\/uploads\/sites\/26\/2025\/04\/unnamed.jpg","datePublished":"2025-04-07T10:00:00+00:00","dateModified":"2025-04-07T14:01:29+00:00","breadcrumb":{"@id":"https:\/\/www.salesforce.com\/es\/news\/press-releases\/2025\/04\/07\/caixabank-y-salesforce-colaboran-para-aplicar-la-ia-en-la-personalizacion-de-la-experiencia-de-cliente-en-los-servicios-bancarios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salesforce.com\/es\/news\/press-releases\/2025\/04\/07\/caixabank-y-salesforce-colaboran-para-aplicar-la-ia-en-la-personalizacion-de-la-experiencia-de-cliente-en-los-servicios-bancarios\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.salesforce.com\/es\/news\/press-releases\/2025\/04\/07\/caixabank-y-salesforce-colaboran-para-aplicar-la-ia-en-la-personalizacion-de-la-experiencia-de-cliente-en-los-servicios-bancarios\/#primaryimage","url":"https:\/\/www.salesforce.com\/es\/news\/wp-content\/uploads\/sites\/26\/2025\/04\/unnamed.jpg","contentUrl":"https:\/\/www.salesforce.com\/es\/news\/wp-content\/uploads\/sites\/26\/2025\/04\/unnamed.jpg","width":1000,"height":667,"caption":"CaixaBank x Salesforce"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salesforce.com\/es\/news\/press-releases\/2025\/04\/07\/caixabank-y-salesforce-colaboran-para-aplicar-la-ia-en-la-personalizacion-de-la-experiencia-de-cliente-en-los-servicios-bancarios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salesforce.com\/es\/news\/"},{"@type":"ListItem","position":2,"name":"Press Releases","item":"https:\/\/www.salesforce.com\/es\/news\/sf_press_release\/"},{"@type":"ListItem","position":3,"name":"CaixaBank y Salesforce colaboran para aplicar la IA en la personalizaci\u00f3n de la experiencia de cliente en los servicios bancarios\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.salesforce.com\/es\/news\/#website","url":"https:\/\/www.salesforce.com\/es\/news\/","name":"Salesforce","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salesforce.com\/es\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.salesforce.com\/es\/news\/#\/schema\/person\/5e8c79e283acb847e940d3fd5019cf13","name":"Simona Paperini","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/741ac0a09f4813b96538a894f52df4f87701f9091417de6329cd053c9347d34a?s=96&d=mm&r=g67ac9ad6c0e501381f19ede19ba2267b","url":"https:\/\/secure.gravatar.com\/avatar\/741ac0a09f4813b96538a894f52df4f87701f9091417de6329cd053c9347d34a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/741ac0a09f4813b96538a894f52df4f87701f9091417de6329cd053c9347d34a?s=96&d=mm&r=g","caption":"Simona Paperini"},"url":"https:\/\/www.salesforce.com\/es\/news\/author\/spaperinisalesforce-com\/"}]}},"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Salesforce","distributor_original_site_url":"https:\/\/www.salesforce.com\/es\/news","push-errors":false,"_links":{"self":[{"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/sf_press_release\/971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/sf_press_release"}],"about":[{"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/types\/sf_press_release"}],"author":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/users\/649"}],"version-history":[{"count":2,"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/sf_press_release\/971\/revisions"}],"predecessor-version":[{"id":974,"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/sf_press_release\/971\/revisions\/974"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/media\/972"}],"wp:attachment":[{"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/media?parent=971"}],"wp:term":[{"taxonomy":"sf_content_type","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/sf_content_type?post=971"},{"taxonomy":"sf_theme","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/sf_theme?post=971"},{"taxonomy":"sf_topic","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/sf_topic?post=971"},{"taxonomy":"sf_product","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/sf_product?post=971"},{"taxonomy":"sf_industry","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/sf_industry?post=971"},{"taxonomy":"sf_role","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/sf_role?post=971"},{"taxonomy":"sf_multimedia_asset","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/sf_multimedia_asset?post=971"},{"taxonomy":"sf_location","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/sf_location?post=971"},{"taxonomy":"sf_collection","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/sf_collection?post=971"},{"taxonomy":"sf_visibility","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/sf_visibility?post=971"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.salesforce.com\/es\/news\/wp-json\/wp\/v2\/coauthors?post=971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}