{"id":229,"date":"2019-04-03T18:03:00","date_gmt":"2023-09-07T18:03:27","guid":{"rendered":"https:\/\/www.salesforce.com\/?p=229"},"modified":"2023-09-07T18:13:47","modified_gmt":"2023-09-07T18:13:47","slug":"un-employe-heureux-fait-un-client-heureux","status":"publish","type":"post","link":"https:\/\/www.salesforce.com\/fr\/blog\/un-employe-heureux-fait-un-client-heureux\/","title":{"rendered":"Un employ\u00e9 heureux, fait un client heureux !"},"content":{"rendered":"\n<p>Pour la seconde ann\u00e9e cons\u00e9cutive, Salesforce se hisse en t\u00eate du palmar\u00e8s Great Place to Work France 2019 qui labellise les entreprises o\u00f9 il fait bon travailler. Une entreprise en tr\u00e8s forte croissance peut donc concilier performances business et bien-\u00eatre des salari\u00e9s. Comment cela est-il possible ? Quelles valeurs transposer pratiquement dans les process ? <b>V\u00e9ronique Marimon, Senior Director Employee Success chez Salesforce France, nous donne son point de vue.<\/b> <\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/Veronique-Marimon.png?strip=all&#038;quality=95\"><\/img><\/p>\n<h2><b> Vous \u00e9tiez auparavant <b><b><b><b>Senior Director<\/b><\/b><\/b><\/b> Customer Success et vous avez r\u00e9cemment pris les fonctions de <b><b><b><b>Senior Director <\/b><\/b><\/b><\/b>Employee Success. Il y a une proximit\u00e9 entre ces deux m\u00e9tiers chez Salesforce ?<\/b><\/h2>\n<p>Chez Salesforce, le succ\u00e8s des clients est primordial ! Nous avons d&rsquo;ailleurs notre propre vision de ce qu&rsquo;est le \u201csucc\u00e8s\u201d. Typiquement, nos <i><a adhocenable=\"false\" href=\"https:\/\/www.salesforce.com\/fr\/blog\/2019\/10\/pourquoi-engager-un-customer-success-manager.html\" target=\"_blank\" rel=\"noopener\">success managers<\/a><\/i> sont avant tout des conseillers dont le but est d&rsquo;aider nos clients \u00e0 grandir, \u00e0 accro\u00eetre leur activit\u00e9 et \u00e0 mieux conna\u00eetre leurs propres clients. Au final, nous mesurons notre efficacit\u00e9 business avant tout par la satisfaction client, qui implique davantage de collaboration par la suite, en un cercle vertueux. Nous concevons les relations avec les collaborateurs de la m\u00eame mani\u00e8re. Il s&rsquo;agit moins de gestion optimale des ressources humaines que de succ\u00e8s des collaborateurs. <a adhocenable=\"false\" href=\"https:\/\/www.salesforce.com\/fr\/blog\/2018\/03\/4-grandes-idees-pour-devenir-une-great-place-to-work.html\" target=\"_blank\" rel=\"noopener\">La satisfaction des employ\u00e9s<\/a> est la motivation principale de ma fonction. <\/p>\n<h2><b>En quoi la r\u00e9ussite et le bien-\u00eatre des collaborateurs sont des cl\u00e9s de performance chez Salesforce ?<\/b><\/h2>\n<p>Ces valeurs sont tr\u00e8s fortes et tr\u00e8s pr\u00e9sentes depuis la cr\u00e9ation de la soci\u00e9t\u00e9\u2026 Concr\u00e8tement, nous nous appuyons sur le concept de <i><a href=\"https:\/\/trailhead.salesforce.com\/fr\/content\/learn\/trails\/camp-pono\" target=\"_blank\" adhocenable=\"false\" rel=\"noopener\">camp pono<\/a><\/i> : dans la culture hawa\u00efenne, vivre en pono signifie atteindre un \u00e9tat d\u2019\u00e9quilibre et d\u2019harmonie dans tous les domaines de votre vie. Chez Salesforce, cette ambition est v\u00e9ritablement incarn\u00e9e : nous nous donnons les moyens de les vivre au quotidien dans un climat de transparence et de confiance. Nous avons un adage \u201c<i>un employ\u00e9 heureux fait un client heureux<\/i>\u201d. Nous ne pouvons prendre soin de nos clients que si nous prenons d&rsquo;abord soin de nous. Nous encourageons donc les salari\u00e9s \u00e0 prendre soin de leur bien-\u00eatre, c&rsquo;est-\u00e0-dire tout ce qui aidera le collaborateur \u00e0 travailler au mieux de sa forme. Nous souhaitons cr\u00e9er, pour nos salari\u00e9s, une exp\u00e9rience collaborateur positive. <img decoding=\"async\" src=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/Camp-Pono.png?strip=all&#038;quality=95\"><\/img> <\/p>\n<h2><b>Peut-on alors parler d\u2019un parcours collaborateur qui serait le reflet du parcours client optimis\u00e9 ?<\/b><\/h2>\n<p>Tout \u00e0 fait. La phase <i>d\u2019onboarding<\/i> d\u2019un nouveau collaborateur peut \u00eatre compar\u00e9e \u00e0 la premi\u00e8re \u00e9tape d\u2019un accueil client : le premier jour est une \u00e9tape important au cours de laquelle plusieurs repr\u00e9sentants du Comit\u00e9 de Direction et des salari\u00e9s pr\u00e9sentent notre culture d&rsquo;entreprise, nos outils et les ressources&#8230; Chaque salari\u00e9 est d&rsquo;ailleurs accompagn\u00e9 \u00e0 ses d\u00e9buts d&rsquo;un \u201c<i>onboarding buddy<\/i>\u201d. Durant les trois premiers mois, chaque nouveau collaborateur b\u00e9n\u00e9ficie ainsi d\u2019un programme \u201cd\u2019inclusion\u201d. Puis, comme dans un parcours client, l\u2019employ\u00e9 se voit proposer les moyens de progresser, d&rsquo;\u00e9voluer, gr\u00e2ce \u00e0 des webinars, des outils et des formations sur notre portail d\u00e9di\u00e9 (myTrailhead). Notre mission est d\u2019accompagner chaque collaborateur vers son propre objectif, sur son propre chemin de d\u00e9veloppement. Nous avons \u00e9galement cr\u00e9\u00e9, cette ann\u00e9e, le Manager Flywheel, un dispositif qui donne, chaque mois, un th\u00e8me de r\u00e9flexion \u00e0 nos managers et \u00e0 nos \u00e9quipes, comme par exemple le feedback, le d\u00e9veloppement de carri\u00e8re, l\u2019alignement\u2026 Tout cela concoure \u00e0 l\u2019installation d\u2019un climat serein au service de la performance.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/manager-flywheel.png?strip=all&#038;quality=95\"><\/img> <\/p>\n<h2><b>Comment est-ce que l&rsquo;\u00e9quipe Employee Success<\/b> <b>\u0153uvre \u00e0 l&rsquo;engagement et le succ\u00e8s des collaborateurs au quotidien ?<\/b><\/h2>\n<p>La gestion du capital humain est un enjeu strat\u00e9gique pour les entreprises. De ce fait l\u2019accompagnement des employ\u00e9s, la motivation des \u00e9quipes, le d\u00e9veloppement des comp\u00e9tences, une politique de recrutement pour trouver les meilleurs talents et enfin le bien-\u00eatre sont des notions fondamentales. Nous cherchons aussi \u00e0 offrir \u00e0 tous un environnement \u00e9panouissant, dans lequel on puisse exprimer ses envies, trouver de l\u2019entraide, tout en donnant du sens au travail. <\/p>\n<h2><b>Donner du sens au travail n&rsquo;est pas qu&rsquo;un luxe ?<\/b><\/h2>\n<p>Non, c&rsquo;est tr\u00e8s important dans notre conception de l&rsquo;<i>employee success<\/i>. Nous croyons fermement au <a href=\"https:\/\/www.salesforce.org\/pledge-1\/\" target=\"_blank\" adhocenable=\"false\" rel=\"noopener\">mod\u00e8le 1-1-1<\/a> dans lequel nous donnons 1 % de notre temps, de nos capitaux et de nos produits \u00e0 la communaut\u00e9. Cette ann\u00e9e, nous avons consacr\u00e9 ainsi plus de 23 000 heures de b\u00e9n\u00e9volat \u00e0 divers organismes de bienfaisance en France. Pour ma part, je me suis par exemple investie dans l\u2019\u00e9ducation en permettant \u00e0 des femmes ou \u00e0 des jeunes en reconversion \u2014 ou qui avaient d\u00e9croch\u00e9 \u2014 de d\u00e9couvrir nos m\u00e9tiers et notre plateforme, de se former, et de trouver un emploi. <\/p>\n<h2><b>Quelles sont vos priorit\u00e9s pour l&rsquo;ann\u00e9e en cours ?<\/b><\/h2>\n<p>Cette ann\u00e9e, nous allons travailler sp\u00e9cifiquement autour de quatre sujets : <\/p>\n<ol>\n<li>la Manager Capability, un accompagnement des managers pour faire grandir leurs \u00e9quipes ;<\/li>\n<li>la notion de transparence dans nos processus de promotion, de d\u00e9veloppement de carri\u00e8re et de reconnaissance ;<\/li>\n<li>l\u2019am\u00e9lioration de la performance en \u00e9quipes, en innovant dans notre fa\u00e7on de travailler ensemble ;<\/li>\n<li>la notion de Psychological safety, pour cr\u00e9er un environnement s\u00fbr : l\u2019id\u00e9e est de prot\u00e9ger les personnes pour qu\u2019elles se sentent dans un environnement de confiance. <\/li>\n<\/ol>\n<h2><b>Comment mesurez-vous la satisfaction des collaborateurs ?<\/b><\/h2>\n<p>Le diagnostic r\u00e9alis\u00e9 par Great Place to Work est une mesure importante, car il provient d&rsquo;un organisme ind\u00e9pendant. Ensuite, deux fois par an, nous menons une enqu\u00eate interne aupr\u00e8s de l\u2019ensemble de nos collaborateurs avec des questions permettant de mesurer le bien-\u00eatre, le niveau de stress, l\u2019engagement, la confiance\u2026 Les r\u00e9sultats sont accessibles par toute l&rsquo;entreprise, en toute transparence. La derni\u00e8re enqu\u00eate a d&rsquo;ailleurs enregistr\u00e9 un taux de r\u00e9ponse de 81 % et le score progresse chaque ann\u00e9e ! Mais nous ne nous contentons pas de cela : le plus important est ensuite de prendre des actions pour am\u00e9liorer les points d&rsquo;attention&#8230; <\/p>\n<h2><b>Finalement, comment r\u00e9sumeriez-vous ce qu\u2019est de \u00ab travailler dans un endroit g\u00e9nial \u00bb ?<\/b><\/h2>\n<p>C\u2019est \u00e9voluer dans une entreprise o\u00f9 chacun a le sentiment de pouvoir grandir, se d\u00e9velopper et contribuer \u00e0 quelque chose qui est plus grand que soi, en b\u00e9n\u00e9ficiant d\u2019un environnement assurant un tr\u00e8s haut niveau de bien-\u00eatre. C\u2019est notre objectif quotidien. Nous souhaitons offrir un environnement de confiance, qui laisse \u00e0 chacun la libert\u00e9 d&rsquo;\u00eatre soi-m\u00eame. Pour cela, tout ce qui est propos\u00e9 par le management doit l&rsquo;\u00eatre avec un niveau de sinc\u00e9rit\u00e9 important.<\/p>\n<p>Customer 360, <a href=\"https:\/\/www.salesforce.com\/fr\/campaign\/experience\/c360-platform\/\">la plateforme unique pour engager vos clients de fa\u00e7on personnalis\u00e9e.<\/a> Dans toute leur diversit\u00e9.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/gptw-france.png?strip=all&#038;quality=95\"><\/img><\/p>\n<p> <span id=\"authorRoot\" path=\"\/content\/blogs\/fr\/fr\/authors\/\"><\/span> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour la seconde ann\u00e9e cons\u00e9cutive, Salesforce se hisse en t\u00eate du palmar\u00e8s Great Place to Work France 2019 qui labellise les entreprises o\u00f9 il fait bon travailler. D\u00e9couvrez comment une entreprise en tr\u00e8s forte croissance peut concilier performances business et bien-\u00eatre des salari\u00e9s.<\/p>\n","protected":false},"author":1,"featured_media":231,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sf_justforyou_enable_alt":true,"optimizely_content_id":"df3ad03b03104334966baed929c70fd9","post_meta_title":"","ai_synopsis":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"sf_topic":[8,10],"sf_content_type":[],"blog":[374,423],"coauthors":[27],"class_list":["post-229","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","sf_topic-best-practices","sf_topic-news","blog-best-practices","blog-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Un employ\u00e9 heureux, fait un client heureux ! \u2022 Salesforce<\/title>\n<meta name=\"description\" content=\"Pour la seconde ann\u00e9e cons\u00e9cutive, Salesforce se hisse en t\u00eate du palmar\u00e8s Great Place to Work France 2019 qui labellise les entreprises o\u00f9 il fait bon travailler. D\u00e9couvrez comment une entreprise en tr\u00e8s forte croissance peut concilier performances business et bien-\u00eatre des salari\u00e9s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salesforce.com\/fr\/blog\/un-employe-heureux-fait-un-client-heureux\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un employ\u00e9 heureux, fait un client heureux !\" \/>\n<meta property=\"og:description\" content=\"Pour la seconde ann\u00e9e cons\u00e9cutive, Salesforce se hisse en t\u00eate du palmar\u00e8s Great Place to Work France 2019 qui labellise les entreprises o\u00f9 il fait bon travailler. D\u00e9couvrez comment une entreprise en tr\u00e8s forte croissance peut concilier performances business et bien-\u00eatre des salari\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salesforce.com\/fr\/blog\/un-employe-heureux-fait-un-client-heureux\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-07T18:03:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-07T18:13:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/great-place-to-work.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Salesforce\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Salesforce\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/un-employe-heureux-fait-un-client-heureux\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/un-employe-heureux-fait-un-client-heureux\\\/\"},\"author\":[{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/#\\\/schema\\\/person\\\/image\\\/c4dae87da9a6134c35582db989c80f90\"}],\"headline\":\"Un employ\u00e9 heureux, fait un client heureux !\",\"datePublished\":\"2023-09-07T18:03:27+00:00\",\"dateModified\":\"2023-09-07T18:13:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/un-employe-heureux-fait-un-client-heureux\\\/\"},\"wordCount\":1145,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/un-employe-heureux-fait-un-client-heureux\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2023\\\/09\\\/great-place-to-work.jpg\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/un-employe-heureux-fait-un-client-heureux\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/un-employe-heureux-fait-un-client-heureux\\\/\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/un-employe-heureux-fait-un-client-heureux\\\/\",\"name\":\"Un employ\u00e9 heureux, fait un client heureux ! \u2022 Salesforce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/un-employe-heureux-fait-un-client-heureux\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/un-employe-heureux-fait-un-client-heureux\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2023\\\/09\\\/great-place-to-work.jpg\",\"datePublished\":\"2023-09-07T18:03:27+00:00\",\"dateModified\":\"2023-09-07T18:13:47+00:00\",\"description\":\"Pour la seconde ann\u00e9e cons\u00e9cutive, Salesforce se hisse en t\u00eate du palmar\u00e8s Great Place to Work France 2019 qui labellise les entreprises o\u00f9 il fait bon travailler. D\u00e9couvrez comment une entreprise en tr\u00e8s forte croissance peut concilier performances business et bien-\u00eatre des salari\u00e9s.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/un-employe-heureux-fait-un-client-heureux\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/un-employe-heureux-fait-un-client-heureux\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/un-employe-heureux-fait-un-client-heureux\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2023\\\/09\\\/great-place-to-work.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2023\\\/09\\\/great-place-to-work.jpg\",\"width\":1200,\"height\":630,\"caption\":\"Un employ\u00e9 heureux, fait un client heureux !\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/un-employe-heureux-fait-un-client-heureux\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un employ\u00e9 heureux, fait un client heureux !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/\",\"name\":\"Salesforce\",\"description\":\"Le Blog du CRM, de l&#039;experience et du Cloud Computing\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/#organization\",\"name\":\"Salesforce\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2023\\\/10\\\/Salesforce.webp\",\"contentUrl\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2023\\\/10\\\/Salesforce.webp\",\"width\":1200,\"height\":630,\"caption\":\"Salesforce\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/#\\\/schema\\\/person\\\/image\\\/c4dae87da9a6134c35582db989c80f90\",\"name\":\"Salesforce\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g60edf16c093aaa190ff084acb1722622\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g\",\"caption\":\"Salesforce\"},\"url\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/author\\\/salesforce\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Un employ\u00e9 heureux, fait un client heureux ! \u2022 Salesforce","description":"Pour la seconde ann\u00e9e cons\u00e9cutive, Salesforce se hisse en t\u00eate du palmar\u00e8s Great Place to Work France 2019 qui labellise les entreprises o\u00f9 il fait bon travailler. D\u00e9couvrez comment une entreprise en tr\u00e8s forte croissance peut concilier performances business et bien-\u00eatre des salari\u00e9s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salesforce.com\/fr\/blog\/un-employe-heureux-fait-un-client-heureux\/","og_locale":"fr_FR","og_type":"article","og_title":"Un employ\u00e9 heureux, fait un client heureux !","og_description":"Pour la seconde ann\u00e9e cons\u00e9cutive, Salesforce se hisse en t\u00eate du palmar\u00e8s Great Place to Work France 2019 qui labellise les entreprises o\u00f9 il fait bon travailler. D\u00e9couvrez comment une entreprise en tr\u00e8s forte croissance peut concilier performances business et bien-\u00eatre des salari\u00e9s.","og_url":"https:\/\/www.salesforce.com\/fr\/blog\/un-employe-heureux-fait-un-client-heureux\/","og_site_name":"Salesforce","article_published_time":"2023-09-07T18:03:27+00:00","article_modified_time":"2023-09-07T18:13:47+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/great-place-to-work.jpg","type":"image\/jpeg"}],"author":"Salesforce","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"","Dur\u00e9e de lecture estim\u00e9e":"6 minutes","Written by":"Salesforce"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salesforce.com\/fr\/blog\/un-employe-heureux-fait-un-client-heureux\/#article","isPartOf":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/un-employe-heureux-fait-un-client-heureux\/"},"author":[{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/person\/image\/c4dae87da9a6134c35582db989c80f90"}],"headline":"Un employ\u00e9 heureux, fait un client heureux !","datePublished":"2023-09-07T18:03:27+00:00","dateModified":"2023-09-07T18:13:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/un-employe-heureux-fait-un-client-heureux\/"},"wordCount":1145,"commentCount":0,"publisher":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/#organization"},"image":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/un-employe-heureux-fait-un-client-heureux\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/great-place-to-work.jpg","inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.salesforce.com\/fr\/blog\/un-employe-heureux-fait-un-client-heureux\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.salesforce.com\/fr\/blog\/un-employe-heureux-fait-un-client-heureux\/","url":"https:\/\/www.salesforce.com\/fr\/blog\/un-employe-heureux-fait-un-client-heureux\/","name":"Un employ\u00e9 heureux, fait un client heureux ! \u2022 Salesforce","isPartOf":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/un-employe-heureux-fait-un-client-heureux\/#primaryimage"},"image":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/un-employe-heureux-fait-un-client-heureux\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/great-place-to-work.jpg","datePublished":"2023-09-07T18:03:27+00:00","dateModified":"2023-09-07T18:13:47+00:00","description":"Pour la seconde ann\u00e9e cons\u00e9cutive, Salesforce se hisse en t\u00eate du palmar\u00e8s Great Place to Work France 2019 qui labellise les entreprises o\u00f9 il fait bon travailler. D\u00e9couvrez comment une entreprise en tr\u00e8s forte croissance peut concilier performances business et bien-\u00eatre des salari\u00e9s.","breadcrumb":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/un-employe-heureux-fait-un-client-heureux\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salesforce.com\/fr\/blog\/un-employe-heureux-fait-un-client-heureux\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.salesforce.com\/fr\/blog\/un-employe-heureux-fait-un-client-heureux\/#primaryimage","url":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/great-place-to-work.jpg","contentUrl":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/great-place-to-work.jpg","width":1200,"height":630,"caption":"Un employ\u00e9 heureux, fait un client heureux !"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salesforce.com\/fr\/blog\/un-employe-heureux-fait-un-client-heureux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salesforce.com\/fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Un employ\u00e9 heureux, fait un client heureux !"}]},{"@type":"WebSite","@id":"https:\/\/www.salesforce.com\/fr\/blog\/#website","url":"https:\/\/www.salesforce.com\/fr\/blog\/","name":"Salesforce","description":"Le Blog du CRM, de l&#039;experience et du Cloud Computing","publisher":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salesforce.com\/fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.salesforce.com\/fr\/blog\/#organization","name":"Salesforce","url":"https:\/\/www.salesforce.com\/fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/10\/Salesforce.webp","contentUrl":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/10\/Salesforce.webp","width":1200,"height":630,"caption":"Salesforce"},"image":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/person\/image\/c4dae87da9a6134c35582db989c80f90","name":"Salesforce","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g60edf16c093aaa190ff084acb1722622","url":"https:\/\/secure.gravatar.com\/avatar\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g","caption":"Salesforce"},"url":"https:\/\/www.salesforce.com\/fr\/blog\/author\/salesforce\/"}]}},"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Salesforce","distributor_original_site_url":"https:\/\/www.salesforce.com\/fr\/blog","push-errors":false,"jetpack_featured_media_url":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/great-place-to-work.jpg","_links":{"self":[{"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/comments?post=229"}],"version-history":[{"count":2,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/229\/revisions"}],"predecessor-version":[{"id":1263,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/229\/revisions\/1263"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/media\/231"}],"wp:attachment":[{"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/media?parent=229"}],"wp:term":[{"taxonomy":"sf_topic","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/sf_topic?post=229"},{"taxonomy":"sf_content_type","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/sf_content_type?post=229"},{"taxonomy":"blog","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/blog?post=229"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/coauthors?post=229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}