{"id":339,"date":"2019-04-26T18:05:00","date_gmt":"2023-09-07T18:05:10","guid":{"rendered":"https:\/\/www.salesforce.com\/?p=339"},"modified":"2023-11-13T16:44:27","modified_gmt":"2023-11-13T16:44:27","slug":"techniques-de-vente-pour-capter-attention-clients-avant-pendant-apres-evenement","status":"publish","type":"post","link":"https:\/\/www.salesforce.com\/fr\/blog\/techniques-de-vente-pour-capter-attention-clients-avant-pendant-apres-evenement\/","title":{"rendered":"Toutes les techniques de vente pour capter l&rsquo;attention des clients avant, pendant et apr\u00e8s un grand \u00e9v\u00e9nement"},"content":{"rendered":"\n<p>Une conf\u00e9rence importante se profile \u00e0 l&rsquo;horizon, vous allez donc interagir avec beaucoup de client potentiels. Avez-vous r\u00e9fl\u00e9chi aux techniques \u00e0 adopter pour capter leur attention?<\/p>\n\n\n\n<p>Il est facile de se laisser distraire par les diff\u00e9rentes sessions et r\u00e9unions planifi\u00e9es. Pourtant, pour tirer le meilleur parti d&rsquo;une conf\u00e9rence, vous avez besoin d&rsquo;une solide strat\u00e9gie de vente afin d&rsquo;\u00eatre parfaitement pr\u00eat, depuis l&rsquo;instant o\u00f9 vous d\u00e9cidez d&rsquo;y participer jusqu&rsquo;aux e-mails de suivi que vous \u00e9crirez par la suite.<\/p>\n\n\n\n<div class=\"layout-six wp-block-salesforce-blog-offer\">\n\t<div class=\"wp-block-offer__wrapper\">\n\n\t\t<div class=\"wp-block-offer__content\">\n\t\t\t<h2 class=\"wp-block-offer__title\">La 6e\u00a0\u00e9dition du rapport \u00ab\u00a0Focus sur les ventes\u00a0\u00bb<\/h2>\n\t\t\t\t\t\t\t<p class=\"wp-block-offer__description\">D\u00e9couvrez des conseils de 5 500 professionnels des ventes sur la mani\u00e8re de stimuler la croissance et de se d\u00e9marquer.<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t<a class=\"wp-block-button__link\" target=\"_self\" href=\"https:\/\/www.salesforce.com\/fr\/form\/sales\/state-of-sales\/?nc=701ed000003AyKZAA0\">Je me d\u00e9marque<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"wp-block-offer__media\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2024\/07\/state-of-sales-2024.png\" class=\"attachment-full size-full\" alt=\"Couverture du guide Focus sur les ventes\" srcset=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2024\/07\/state-of-sales-2024.png 1200w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2024\/07\/state-of-sales-2024.png?w=300&amp;h=169 300w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2024\/07\/state-of-sales-2024.png?w=768&amp;h=432 768w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2024\/07\/state-of-sales-2024.png?w=1024&amp;h=576 1024w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2024\/07\/state-of-sales-2024.png?w=150&amp;h=84 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/div>\n\t<\/div>\n\n\t\n\t<\/div>\n\n\n\n<p><b>Comment am\u00e9liorer les ventes par les interactions en face \u00e0 face<\/b><\/p>\n\n\n\n<p>Selon le rapport <a href=\"https:\/\/www.salesforce.com\/fr\/form\/pdf\/state-of-sales\/\" target=\"_blank\" rel=\"noopener\">Focus sur les ventes<\/a>, 48 % des commerciaux consacrent davantage de temps aux \u00e9changes en personne avec leurs clients qu&rsquo;en 2015. Ce nombre est d&rsquo;autant plus impressionnant si l&rsquo;on tient compte de la popularit\u00e9 croissante des canaux digitaux. Cette \u00e9volution est due \u00e0 divers facteurs, parmi lesquels les renseignements obtenus gr\u00e2ce \u00e0 la communication non verbale ou encore les liens cr\u00e9\u00e9s par les interactions sociales.<\/p>\n\n\n\n<p>Les conf\u00e9rences et les grands \u00e9v\u00e9nements constituent d&rsquo;excellentes opportunit\u00e9s pour accro\u00eetre les ventes de votre entreprise. Il est donc indispensable de les aborder avec une strat\u00e9gie de vente bien rod\u00e9e. Vous trouverez ci-dessous un guide \u00e9tape par \u00e9tape pour vous aider \u00e0 am\u00e9liorer vos techniques de vente avant, pendant et apr\u00e8s un \u00e9v\u00e9nement.<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04b078ead63&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04b078ead63\" class=\"wp-block-image wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/techniques-vente.png?strip=all&#038;quality=95\" alt=\"\"\/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p><b>1. Travail de pr\u00e9paration : assurez-vous que vos prospects seront pr\u00e9sents et attentifs<\/b><\/p>\n\n\n\n<p>Il est essentiel de faire le point sur vos clients potentiels les plus importants avant un \u00e9v\u00e9nement et de s&rsquo;assurer qu&rsquo;ils ont connaissance de votre pr\u00e9sence. Comment y parvenir ?<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><b>Misez sur des communications personnalis\u00e9es<\/b> : Contactez vos clients potentiels de fa\u00e7on personnalis\u00e9e, par exemple avec des invitations manuscrites ou des offres sp\u00e9ciales, pour leur montrer que leur pr\u00e9sence vous importe.<\/li>\n\n\n\n<li><b>Facilitez l&rsquo;acc\u00e8s aux informations : <\/b> Il est \u00e9vident que si vos prospects ne savent rien d&rsquo;un \u00e9v\u00e9nement \u00e0 venir, ils n&rsquo;y assisteront pas. Assurez-vous qu&rsquo;ils connaissent votre programme en leur permettant d&rsquo;acc\u00e9der facilement aux informations. Pourquoi ne pas ajouter un lien dans la signature de votre e-mail par exemple ?<\/li>\n\n\n\n<li><b>Invitez vos prospects \u00e0 interagir avec vous : <\/b>Pour susciter l&rsquo;attention de vos prospects, vous pouvez les inviter \u00e0 participer \u00e0 une activit\u00e9 sp\u00e9cifique avec vous. Si l&rsquo;\u00e9v\u00e9nement apporte une certaine valeur ajout\u00e9e, comme une d\u00e9mo ou une conf\u00e9rence qui r\u00e9pond sp\u00e9cifiquement \u00e0 leurs besoins, ils seront encore plus susceptibles d&rsquo;y participer.<\/li>\n<\/ul>\n\n\n\n<p><b>2. La veille: d\u00e9veloppez votre r\u00e9seau dans un cadre informel<\/b><\/p>\n\n\n\n<p><a href=\"https:\/\/www.virgin.com\/entrepreneur\/infographic-the-importance-of-face-to-face-networking\" target=\"_blank\" rel=\"noopener\">85 % des personnes<\/a> pr\u00e9f\u00e8rent les r\u00e9unions et conf\u00e9rences en petit comit\u00e9, qui leur permettent de tisser des relations commerciales plus fortes et plus pertinentes. En effet, les conf\u00e9rences et les \u00e9v\u00e9nements majeurs peuvent parfois donner aux visiteurs l&rsquo;impression d&rsquo;\u00eatre noy\u00e9s dans la foule, avec peu de chances d&rsquo;approfondir les \u00e9changes avec quiconque.<\/p>\n\n\n\n<p>Comment exploiter une telle situation pour se rapprocher de vos prospects et am\u00e9liorer les ventes ? Comme Sean Zinsmeister l&rsquo;a pr\u00e9cis\u00e9 dans les <i>100 conseils commerciaux<\/i> de Salesforce, \u00ab il est essentiel de se concentrer sur les comptes cibles les plus pertinents, plut\u00f4t que d&rsquo;essayer de ratisser large. \u00bb Entamez des relations ou entretenez les liens existants en rencontrant les principaux responsables des ventes et prospects la veille de la conf\u00e9rence.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><b>Ne perdez pas de vue votre objectif : <\/b> Ce conseil est valable pour tous les aspects de vos activit\u00e9s : vous devriez toujours commencer par vous demander ce que vous voulez accomplir, avant de d\u00e9terminer les strat\u00e9gies et techniques \u00e0 mettre en place pour y parvenir. Ainsi, lors de la planification d&rsquo;une rencontre avant une conf\u00e9rence, il est important d&rsquo;adapter l&rsquo;\u00e9v\u00e9nement \u00e0 vos objectifs sp\u00e9cifiques. Par exemple, vous pouvez convier diff\u00e9rents invit\u00e9s, responsables des ventes et prospects afin de cr\u00e9er un environnement id\u00e9al et un sentiment de communaut\u00e9 qui perdurera tout au long de la conf\u00e9rence et au-del\u00e0.<\/li>\n\n\n\n<li><b>Pr\u00e9f\u00e9rez un cadre restreint et intimiste : <\/b> En planifiant un \u00e9v\u00e9nement de moindre ampleur, ou en prenant le temps d&rsquo;interagir individuellement avec vos principaux prospects, vous laisserez une impression favorable et durable, et votre offre sera davantage prise en consid\u00e9ration. Cela peut m\u00eame constituer une bonne occasion de pr\u00e9senter votre argumentaire de vente.<\/li>\n<\/ul>\n\n\n\n<p><b>3. Le jour de l&rsquo;\u00e9v\u00e9nement : pr\u00e9parez-vous \u00e0 faire des rencontres et soyez attentif<\/b><\/p>\n\n\n\n<p>\u00c0 ce stade, vous avez d\u00e9j\u00e0 rencontr\u00e9 certaines personnes qui assisteront \u00e0 l&rsquo;\u00e9v\u00e9nement et vous avez pr\u00e9vu d&rsquo;en rencontrer d&rsquo;autres. Vous devriez conna\u00eetre clairement vos objectifs et disposer d&rsquo;une strat\u00e9gie de vente bien d\u00e9finie, pour \u00eatre pr\u00eat \u00e0 d\u00e9velopper votre r\u00e9seau le plus efficacement possible.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><b>Adaptez vos plans et respectez-les : <\/b> Le manque de fiabilit\u00e9 risque de vous faire perdre tr\u00e8s rapidement vos clients potentiels. M\u00eame si votre emploi du temps est tr\u00e8s charg\u00e9, il est crucial que vous respectiez tous les engagements que vous avez pris. Planifiez des heures et des lieux de r\u00e9union sp\u00e9cifiques et mettez un point d&rsquo;honneur \u00e0 assister \u00e0 des \u00e9v\u00e9nements qui correspondent aux pr\u00e9f\u00e9rences particuli\u00e8res de votre client.<\/li>\n\n\n\n<li><b>Pr\u00eatez attention \u00e0 vos prospects : <\/b> <a href=\"https:\/\/www.salesforce.com\/fr\/form\/pdf\/state-of-connected-customer\/\" target=\"_blank\" rel=\"noopener\">84 % des clients<\/a> accordent de l&rsquo;importance au fait d&rsquo;\u00eatre trait\u00e9s comme des personnes plut\u00f4t que comme de simples num\u00e9ros dans le cadre d&rsquo;un \u00e9change. Les entreprises doivent donc comprendre leurs clients et leurs priorit\u00e9s sur un plan plus personnel. Pour y parvenir efficacement, vous pouvez notamment pr\u00eater une attention particuli\u00e8re aux r\u00e9actions de vos prospects lors des diff\u00e9rents \u00e9v\u00e9nements et \u00e0 leurs interactions pendant la conf\u00e9rence. Cela ne se limite pas simplement aux mots prononc\u00e9s : le langage corporel, les expressions du visage et les inflexions de la voix peuvent \u00eatre riches de sens.<\/li>\n<\/ul>\n\n\n\n<p><b>4. Apr\u00e8s l&rsquo;\u00e9v\u00e9nement : pensez au suivi et faites preuve de strat\u00e9gie<\/b><\/p>\n\n\n\n<p>Le travail que vous avez effectu\u00e9 pour \u00e9tablir de nouvelles relations avec vos prospects et vos clients existants n&rsquo;est qu&rsquo;un d\u00e9but. Il est maintenant temps d&rsquo;inscrire ces relations dans la dur\u00e9e. Il est important d&rsquo;envoyer un e-mail de suivi apr\u00e8s la r\u00e9union en face \u00e0 face, afin de rappeler aux acheteurs potentiels les exp\u00e9riences et les plans partag\u00e9s au cours de la conf\u00e9rence. Si vous avez fait des promesses, comme d&rsquo;envoyer des informations ou des documents compl\u00e9mentaires, respecter ces engagements est tout aussi important que le fait d&rsquo;honorer vos rendez-vous.<\/p>\n\n\n\n<p><b>La premi\u00e8re \u00e9tape pour cr\u00e9er une relation durable<\/b><\/p>\n\n\n\n<p>Capter l&rsquo;attention des clients lors de grands \u00e9v\u00e9nements est une excellente fa\u00e7on de g\u00e9n\u00e9rer des prospects et d&rsquo;am\u00e9liorer les ventes, mais cela comporte \u00e9galement des enjeux plus importants : cr\u00e9er des relations \u00e0 long terme avec des clients fid\u00e8les.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une conf\u00e9rence importante se profile \u00e0 l&rsquo;horizon, vous allez donc interagir avec beaucoup de client potentiels. Avez-vous r\u00e9fl\u00e9chi aux techniques \u00e0 adopter pour capter leur attention?<\/p>\n","protected":false},"author":1,"featured_media":341,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sf_justforyou_enable_alt":true,"optimizely_content_id":"","post_meta_title":"","ai_synopsis":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"sf_topic":[8,4],"sf_content_type":[],"blog":[374,358],"coauthors":[27],"class_list":["post-339","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","sf_topic-best-practices","sf_topic-sales","blog-best-practices","blog-sales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Toutes les techniques de vente pour capter l&#039;attention des clients avant, pendant et apr\u00e8s un grand \u00e9v\u00e9nement \u2022 Salesforce<\/title>\n<meta name=\"description\" content=\"Une conf\u00e9rence importante se profile \u00e0 l&#039;horizon, vous allez donc interagir avec beaucoup de client potentiels. Avez-vous r\u00e9fl\u00e9chi aux techniques \u00e0 adopter pour capter leur attention?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salesforce.com\/fr\/blog\/techniques-de-vente-pour-capter-attention-clients-avant-pendant-apres-evenement\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Toutes les techniques de vente pour capter l&#039;attention des clients avant, pendant et apr\u00e8s un grand \u00e9v\u00e9nement\" \/>\n<meta property=\"og:description\" content=\"Une conf\u00e9rence importante se profile \u00e0 l&#039;horizon, vous allez donc interagir avec beaucoup de client potentiels. Avez-vous r\u00e9fl\u00e9chi aux techniques \u00e0 adopter pour capter leur attention?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salesforce.com\/fr\/blog\/techniques-de-vente-pour-capter-attention-clients-avant-pendant-apres-evenement\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-07T18:05:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-13T16:44:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/techniques-vente-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2400\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Salesforce\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"digital-delivery-operations7076\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Salesforce\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/techniques-de-vente-pour-capter-attention-clients-avant-pendant-apres-evenement\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/techniques-de-vente-pour-capter-attention-clients-avant-pendant-apres-evenement\/\"},\"author\":[{\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/person\/image\/c4dae87da9a6134c35582db989c80f90\"}],\"headline\":\"Toutes les techniques de vente pour capter l&rsquo;attention des clients avant, pendant et apr\u00e8s un grand \u00e9v\u00e9nement\",\"datePublished\":\"2023-09-07T18:05:10+00:00\",\"dateModified\":\"2023-11-13T16:44:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/techniques-de-vente-pour-capter-attention-clients-avant-pendant-apres-evenement\/\"},\"wordCount\":1186,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/techniques-de-vente-pour-capter-attention-clients-avant-pendant-apres-evenement\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/techniques-vente-2.jpg\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.salesforce.com\/fr\/blog\/techniques-de-vente-pour-capter-attention-clients-avant-pendant-apres-evenement\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/techniques-de-vente-pour-capter-attention-clients-avant-pendant-apres-evenement\/\",\"url\":\"https:\/\/www.salesforce.com\/fr\/blog\/techniques-de-vente-pour-capter-attention-clients-avant-pendant-apres-evenement\/\",\"name\":\"Toutes les techniques de vente pour capter l'attention des clients avant, pendant et apr\u00e8s un grand \u00e9v\u00e9nement \u2022 Salesforce\",\"isPartOf\":{\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/techniques-de-vente-pour-capter-attention-clients-avant-pendant-apres-evenement\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/techniques-de-vente-pour-capter-attention-clients-avant-pendant-apres-evenement\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/techniques-vente-2.jpg\",\"datePublished\":\"2023-09-07T18:05:10+00:00\",\"dateModified\":\"2023-11-13T16:44:27+00:00\",\"description\":\"Une conf\u00e9rence importante se profile \u00e0 l'horizon, vous allez donc interagir avec beaucoup de client potentiels. Avez-vous r\u00e9fl\u00e9chi aux techniques \u00e0 adopter pour capter leur attention?\",\"breadcrumb\":{\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/techniques-de-vente-pour-capter-attention-clients-avant-pendant-apres-evenement\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.salesforce.com\/fr\/blog\/techniques-de-vente-pour-capter-attention-clients-avant-pendant-apres-evenement\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/techniques-de-vente-pour-capter-attention-clients-avant-pendant-apres-evenement\/#primaryimage\",\"url\":\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/techniques-vente-2.jpg\",\"contentUrl\":\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/techniques-vente-2.jpg\",\"width\":2400,\"height\":1600,\"caption\":\"Toutes les techniques de vente pour capter l'attention des clients avant, pendant et apr\u00e8s un grand \u00e9v\u00e9nement\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/techniques-de-vente-pour-capter-attention-clients-avant-pendant-apres-evenement\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.salesforce.com\/fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Toutes les techniques de vente pour capter l&rsquo;attention des clients avant, pendant et apr\u00e8s un grand \u00e9v\u00e9nement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/#website\",\"url\":\"https:\/\/www.salesforce.com\/fr\/blog\/\",\"name\":\"Salesforce\",\"description\":\"Le Blog du CRM, de l&#039;experience et du Cloud Computing\",\"publisher\":{\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.salesforce.com\/fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/#organization\",\"name\":\"Salesforce\",\"url\":\"https:\/\/www.salesforce.com\/fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/10\/Salesforce.webp\",\"contentUrl\":\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/10\/Salesforce.webp\",\"width\":1200,\"height\":630,\"caption\":\"Salesforce\"},\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/person\/image\/c4dae87da9a6134c35582db989c80f90\",\"name\":\"Salesforce\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g60edf16c093aaa190ff084acb1722622\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g\",\"caption\":\"Salesforce\"},\"url\":\"https:\/\/www.salesforce.com\/fr\/blog\/author\/salesforce\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Toutes les techniques de vente pour capter l'attention des clients avant, pendant et apr\u00e8s un grand \u00e9v\u00e9nement \u2022 Salesforce","description":"Une conf\u00e9rence importante se profile \u00e0 l'horizon, vous allez donc interagir avec beaucoup de client potentiels. Avez-vous r\u00e9fl\u00e9chi aux techniques \u00e0 adopter pour capter leur attention?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salesforce.com\/fr\/blog\/techniques-de-vente-pour-capter-attention-clients-avant-pendant-apres-evenement\/","og_locale":"fr_FR","og_type":"article","og_title":"Toutes les techniques de vente pour capter l'attention des clients avant, pendant et apr\u00e8s un grand \u00e9v\u00e9nement","og_description":"Une conf\u00e9rence importante se profile \u00e0 l'horizon, vous allez donc interagir avec beaucoup de client potentiels. Avez-vous r\u00e9fl\u00e9chi aux techniques \u00e0 adopter pour capter leur attention?","og_url":"https:\/\/www.salesforce.com\/fr\/blog\/techniques-de-vente-pour-capter-attention-clients-avant-pendant-apres-evenement\/","og_site_name":"Salesforce","article_published_time":"2023-09-07T18:05:10+00:00","article_modified_time":"2023-11-13T16:44:27+00:00","og_image":[{"width":2400,"height":1600,"url":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/techniques-vente-2.jpg","type":"image\/jpeg"}],"author":"Salesforce","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"digital-delivery-operations7076","Dur\u00e9e de lecture estim\u00e9e":"6 minutes","Written by":"Salesforce"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salesforce.com\/fr\/blog\/techniques-de-vente-pour-capter-attention-clients-avant-pendant-apres-evenement\/#article","isPartOf":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/techniques-de-vente-pour-capter-attention-clients-avant-pendant-apres-evenement\/"},"author":[{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/person\/image\/c4dae87da9a6134c35582db989c80f90"}],"headline":"Toutes les techniques de vente pour capter l&rsquo;attention des clients avant, pendant et apr\u00e8s un grand \u00e9v\u00e9nement","datePublished":"2023-09-07T18:05:10+00:00","dateModified":"2023-11-13T16:44:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/techniques-de-vente-pour-capter-attention-clients-avant-pendant-apres-evenement\/"},"wordCount":1186,"commentCount":0,"publisher":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/#organization"},"image":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/techniques-de-vente-pour-capter-attention-clients-avant-pendant-apres-evenement\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/techniques-vente-2.jpg","inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.salesforce.com\/fr\/blog\/techniques-de-vente-pour-capter-attention-clients-avant-pendant-apres-evenement\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.salesforce.com\/fr\/blog\/techniques-de-vente-pour-capter-attention-clients-avant-pendant-apres-evenement\/","url":"https:\/\/www.salesforce.com\/fr\/blog\/techniques-de-vente-pour-capter-attention-clients-avant-pendant-apres-evenement\/","name":"Toutes les techniques de vente pour capter l'attention des clients avant, pendant et apr\u00e8s un grand \u00e9v\u00e9nement \u2022 Salesforce","isPartOf":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/techniques-de-vente-pour-capter-attention-clients-avant-pendant-apres-evenement\/#primaryimage"},"image":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/techniques-de-vente-pour-capter-attention-clients-avant-pendant-apres-evenement\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/techniques-vente-2.jpg","datePublished":"2023-09-07T18:05:10+00:00","dateModified":"2023-11-13T16:44:27+00:00","description":"Une conf\u00e9rence importante se profile \u00e0 l'horizon, vous allez donc interagir avec beaucoup de client potentiels. Avez-vous r\u00e9fl\u00e9chi aux techniques \u00e0 adopter pour capter leur attention?","breadcrumb":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/techniques-de-vente-pour-capter-attention-clients-avant-pendant-apres-evenement\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salesforce.com\/fr\/blog\/techniques-de-vente-pour-capter-attention-clients-avant-pendant-apres-evenement\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.salesforce.com\/fr\/blog\/techniques-de-vente-pour-capter-attention-clients-avant-pendant-apres-evenement\/#primaryimage","url":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/techniques-vente-2.jpg","contentUrl":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/techniques-vente-2.jpg","width":2400,"height":1600,"caption":"Toutes les techniques de vente pour capter l'attention des clients avant, pendant et apr\u00e8s un grand \u00e9v\u00e9nement"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salesforce.com\/fr\/blog\/techniques-de-vente-pour-capter-attention-clients-avant-pendant-apres-evenement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salesforce.com\/fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Toutes les techniques de vente pour capter l&rsquo;attention des clients avant, pendant et apr\u00e8s un grand \u00e9v\u00e9nement"}]},{"@type":"WebSite","@id":"https:\/\/www.salesforce.com\/fr\/blog\/#website","url":"https:\/\/www.salesforce.com\/fr\/blog\/","name":"Salesforce","description":"Le Blog du CRM, de l&#039;experience et du Cloud Computing","publisher":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salesforce.com\/fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.salesforce.com\/fr\/blog\/#organization","name":"Salesforce","url":"https:\/\/www.salesforce.com\/fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/10\/Salesforce.webp","contentUrl":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/10\/Salesforce.webp","width":1200,"height":630,"caption":"Salesforce"},"image":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/person\/image\/c4dae87da9a6134c35582db989c80f90","name":"Salesforce","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g60edf16c093aaa190ff084acb1722622","url":"https:\/\/secure.gravatar.com\/avatar\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g","caption":"Salesforce"},"url":"https:\/\/www.salesforce.com\/fr\/blog\/author\/salesforce\/"}]}},"jetpack_featured_media_url":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/techniques-vente-2.jpg","jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Salesforce","distributor_original_site_url":"https:\/\/www.salesforce.com\/fr\/blog","push-errors":false,"_links":{"self":[{"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/comments?post=339"}],"version-history":[{"count":8,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/339\/revisions"}],"predecessor-version":[{"id":2567,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/339\/revisions\/2567"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/media\/341"}],"wp:attachment":[{"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/media?parent=339"}],"wp:term":[{"taxonomy":"sf_topic","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/sf_topic?post=339"},{"taxonomy":"sf_content_type","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/sf_content_type?post=339"},{"taxonomy":"blog","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/blog?post=339"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/coauthors?post=339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}