{"id":368,"date":"2019-08-29T18:05:00","date_gmt":"2023-09-07T18:05:36","guid":{"rendered":"https:\/\/www.salesforce.com\/?p=368"},"modified":"2023-11-13T16:55:19","modified_gmt":"2023-11-13T16:55:19","slug":"e-commerce-panier-abandonne-que-faire","status":"publish","type":"post","link":"https:\/\/www.salesforce.com\/fr\/blog\/e-commerce-panier-abandonne-que-faire\/","title":{"rendered":"Panier abandonn\u00e9 : 4 conseils pour que l\u2019affaire soit (enfin) dans le sac"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><b>Un internaute visite votre site. Il consulte vos pages produits, en met un dans son panier, puis deux\u2026 avant de quitter votre site sans finaliser la commande. Rage, d\u00e9sespoir ! H\u00e9las, il faut s\u2019y faire : plus de <\/b><a href=\"https:\/\/www.salesforce.com\/products\/marketing-cloud\/best-practices\/abandoned-cart-emails-guide\/#\" target=\"_blank\" adhocenable=\"false\" rel=\"noopener\"><b><b>69 %<b> <\/b>des paniers e-commerce dans le monde<\/b><\/b><\/a><b> sont abandonn\u00e9s. Comment limiter ce risque et m\u00eame transformer ce faux-pas en d\u00e9tour vers la caisse ? Voici 4 pistes. <\/b> <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-1-attaquez-le-probleme-a-la-racine\"><b>1. Attaquez le probl\u00e8me \u00e0 la racine<\/b><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous avez de nombreux paniers abandonn\u00e9s, c\u2019est que des internautes ont eu le temps de douter ou de s\u2019agacer. Dans un premier temps, attaquez le probl\u00e8me \u00e0 la racine en \u00e9tant irr\u00e9prochable quant au fonctionnement de votre plateforme. Votre objectif est double : <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00e9viter tout probl\u00e8me technique qui perturberait le processus d\u2019achat ;<\/li>\n\n\n\n<li>simplifier au maximum le parcours client, en optant pour une navigation intuitive, au nombre d&rsquo;\u00e9tapes d\u2019achat limit\u00e9, quitte \u00e0 supprimer quelques options.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Un cas classique de complication du parcours client ? La cr\u00e9ation d\u2019un compte utilisateur, <a adhocenable=\"false\" href=\"https:\/\/www.salesforce.com\/products\/marketing-cloud\/best-practices\/abandoned-cart-emails-guide\/#\" target=\"_blank\" rel=\"noopener\"><b>responsable de 31 % des abandons<\/b> <b>de panier aux \u00c9tats-Unis<\/b><\/a><b> <\/b>! Plus vous demandez d&rsquo;informations, plus le risque d&rsquo;abandon augmente. N\u2019h\u00e9sitez donc pas \u00e0 le rendre optionnel, m\u00eame si vous r\u00e9coltez moins de donn\u00e9es client dans un premier temps. <\/p>\n\n\n\n<div class=\"layout-five wp-block-salesforce-blog-offer\">\n\t<div class=\"wp-block-offer__wrapper\">\n\n\t\t<div class=\"wp-block-offer__content\">\n\t\t\t<h2 class=\"wp-block-offer__title\"><br>Focus sur le e-commerce<\/h2>\n\t\t\t\t\t\t\t<p class=\"wp-block-offer__description\">Nous avons interrog\u00e9 plus de 4\u00a0000\u00a0cadres du e-commerce et analys\u00e9 les transactions de plus d&rsquo;un milliard de consommateurs dans le monde, pour comprendre les mutations du e-commerce<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t<a class=\"wp-block-button__link\" target=\"_self\" href=\"https:\/\/www.salesforce.com\/fr\/resources\/research-reports\/state-of-commerce\/\">D\u00e9couvrir les mutations<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"wp-block-offer__media\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2020\/11\/state-of-commerce-2nd-fr-form.png\" class=\"attachment-full size-full\" alt=\"State of ecommerce\" srcset=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2020\/11\/state-of-commerce-2nd-fr-form.png 400w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2020\/11\/state-of-commerce-2nd-fr-form.png?w=150&amp;h=150 150w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2020\/11\/state-of-commerce-2nd-fr-form.png?w=300&amp;h=300 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t<\/div>\n\t<\/div>\n\n\t\n\t\t\t<!-- Standard Illustration -->\n\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__illustration\" src=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-illustration-layout-five.png\" alt=\"\">\n\n\t\t<!-- Small Accent Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__accent\" src=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-accent-layout-five.png\" alt=\"\">\n\t\t\n\t\t<!-- Left Side Illustration -->\n\t\t\n\t\t<!-- Cloud Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__cloud\" src=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-cloud-layout-five.png\" alt=\"\">\n\t\t\n\t<\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-2-rappelez-vous-a-lui\"><b>2. Rappelez-vous \u00e0 lui<\/b><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Il est parti en laissant son panier plein ? Tout n\u2019est pas perdu dans la mesure o\u00f9 vous en savez plus sur les envies d\u2019achat des internautes qui visitent votre site. Si, conform\u00e9ment aux dispositions du <a href=\"https:\/\/www.cnil.fr\/fr\/la-prospection-commerciale-par-courrier-electronique\" target=\"_blank\" adhocenable=\"false\" rel=\"noopener\">RGPD<\/a> (R\u00e9glement g\u00e9n\u00e9ral de la protection des donn\u00e9es), votre client a accept\u00e9 de recevoir des messages commerciaux, vous allez pouvoir lui envoyer un petit e-mail personnalis\u00e9. L\u2019objectif ? Le relancer, tout simplement. Attention cependant, envoyer un mail pour simplement proposer \u00e0 nouveau les produits qu\u2019il vous avait laiss\u00e9s sur les bras risque d\u2019\u00eatre contre-productif (agacement, d\u00e9sinscription, etc.). Contactez-le plut\u00f4t en lui proposant un service qui lui simplifie la vie. Voici quelques pistes : <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>si des promotions sur des produits \u00e9quivalents ou du m\u00eame univers ont lieu peu de temps apr\u00e8s, informez-le en expliquant votre d\u00e9marche ;<\/li>\n\n\n\n<li>proposez un appel d\u2019un conseiller pour lui donner des conseils techniques, ou pour l\u2019aider sur le type de produit dont il aurait besoin ;<\/li>\n\n\n\n<li>proposez de \u00ab r\u00e9server \u00bb le produit pendant quelques jours pour continuer le dialogue ;<\/li>\n\n\n\n<li>dans la majorit\u00e9 des cas, le panier est abandonn\u00e9 du fait des co\u00fbts additionnels (taxe, livraison, options) trop importants. Peut-\u00eatre pouvez-vous offrir des solutions optimales ? <\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-3-montrez-que-vous-vous-souvenez-de-lui\"><b>3. Montrez que vous vous souvenez de lui<\/b><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00eame si vous n\u2019avez pas pu identifier votre visiteur pour lui envoyer des messages, il vous reste une carte \u00e0 jouer : les cookies. L\u00e0 encore, il convient de respecter scrupuleusement les dispositions du RGPD, lequel exige le consentement des internautes. \u00c0 ce sujet, la CNIL (Commission nationale de l\u2019informatique et des libert\u00e9s) a publi\u00e9 en juin 2019 son plan d\u2019action relatif au ciblage publicitaire, donnant aux entreprises un d\u00e9lai d\u2019un an pour modifier leur politique de cookies sur leurs sites internet. Il n\u2019est d\u00e9sormais plus possible de tracer leurs visiteurs sans leur consentemen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une fois ce consentement d\u00fbment recueilli, pas la peine d\u2019envoyer une bo\u00eete pleine de g\u00e2teaux aux p\u00e9pites de chocolats. Utilisez les traces laiss\u00e9es par sa visite pour l\u2019identifier \u00e0 son prochain passage sur le site. Vous pourrez ainsi lui proposer les objets qu\u2019il avait abandonn\u00e9s ou ceux b\u00e9n\u00e9ficiant de remises. Mieux encore, misez sur une campagne de publicit\u00e9 cibl\u00e9e pour l\u2019informer de remises sur des produits qui l\u2019int\u00e9ressent pendant sa navigation sur d\u2019autres sites ! <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans tous les cas, restez sympathique pour limiter l\u2019impression d\u00e9sagr\u00e9able de \u00ab Big Brother \u00bb. Par exemple, votre message pourrait \u00eatre : \u00ab <i>Pr\u00e9c\u00e9demment, vous vous \u00e9tiez int\u00e9ress\u00e9 \u00e0 ces produits&#8230; Nous esp\u00e9rons que vous avez depuis trouv\u00e9 votre bonheur. Si ce n\u2019est pas le cas, sachez qu\u2019il en reste 4 disponibles, dont 2 sont en soldes jusqu\u2019\u00e0 lundi ! Avec livraison en point relais, le total sera de&#8230;<\/i> \u00bb <\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-4-restez-patient-et-anticipez-les-prochaines-visites\"><b>4. Restez patient et anticipez les prochaines visites<\/b><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Une d\u00e9cision d\u2019achat prend du temps : la cr\u00e9ation et l\u2019abandon d\u2019un panier peut t\u00e9moigner d\u2019une intention qui se concr\u00e9tisera plus tard par l\u2019achat en magasin ou par des visites ult\u00e9rieures sur votre site. Ne voyez donc pas ces abandons comme des \u00e9checs, mais comme des opportunit\u00e9s \u00e0 approfondir : apr\u00e8s tout vous avez presque convaincu ! Gardez donc patience et essayez d\u2019entretenir la conversation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> Face \u00e0 la concurrence, voil\u00e0 de quoi rester dans le haut du panier ! <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><i>Poursuivez votre lecture en d\u00e9couvrant les <a adhocenable=\"false\" href=\"https:\/\/www.salesforce.com\/fr\/blog\/2020\/09\/panier-abandonne-meilleures-techniques-et-exemples-de-relance.html\" target=\"_blank\" rel=\"noopener\">meilleures techniques et exemples de mails de relance<\/a> pour limiter les paniers abandonn\u00e9s et augmenter les ventes gr\u00e2ce au marketing automation. <\/i><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> <span id=\"authorRoot\" path=\"\/content\/blogs\/fr\/fr\/authors\/\"><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un internaute visite votre site. Il consulte vos pages produits, en met un dans son panier, puis deux\u2026 avant de quitter votre site sans finaliser la commande. Rage, d\u00e9sespoir ! Comment limiter ce risque et m\u00eame transformer ce faux-pas en d\u00e9tour vers la caisse ? Voici 4 pistes.<\/p>\n","protected":false},"author":1,"featured_media":370,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sf_justforyou_enable_alt":true,"optimizely_content_id":"3ca0a26016f24d97903bbb4b7dad936d","post_meta_title":"","ai_synopsis":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"sf_topic":[15,8],"sf_content_type":[],"blog":[347,374],"coauthors":[27],"class_list":["post-368","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","sf_topic-commerce","sf_topic-best-practices","blog-commerce","blog-best-practices"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Panier abandonn\u00e9 : 4 conseils pour que l\u2019affaire soit (enfin) dans le sac \u2022 Salesforce<\/title>\n<meta name=\"description\" content=\"Un internaute visite votre site. Il consulte vos pages produits, en met un dans son panier, puis deux\u2026 avant de quitter votre site sans finaliser la commande. Rage, d\u00e9sespoir ! Comment limiter ce risque et m\u00eame transformer ce faux-pas en d\u00e9tour vers la caisse ? Voici 4 pistes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salesforce.com\/fr\/blog\/e-commerce-panier-abandonne-que-faire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Panier abandonn\u00e9 : 4 conseils pour que l\u2019affaire soit (enfin) dans le sac\" \/>\n<meta property=\"og:description\" content=\"Un internaute visite votre site. Il consulte vos pages produits, en met un dans son panier, puis deux\u2026 avant de quitter votre site sans finaliser la commande. Rage, d\u00e9sespoir ! Comment limiter ce risque et m\u00eame transformer ce faux-pas en d\u00e9tour vers la caisse ? Voici 4 pistes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salesforce.com\/fr\/blog\/e-commerce-panier-abandonne-que-faire\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-07T18:05:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-13T16:55:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/10\/Salesforce-logo.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"4000\" \/>\n\t<meta property=\"og:image:height\" content=\"2250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Salesforce\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Salesforce\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/e-commerce-panier-abandonne-que-faire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/e-commerce-panier-abandonne-que-faire\\\/\"},\"author\":[{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/#\\\/schema\\\/person\\\/image\\\/c4dae87da9a6134c35582db989c80f90\"}],\"headline\":\"Panier abandonn\u00e9 : 4 conseils pour que l\u2019affaire soit (enfin) dans le sac\",\"datePublished\":\"2023-09-07T18:05:36+00:00\",\"dateModified\":\"2023-11-13T16:55:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/e-commerce-panier-abandonne-que-faire\\\/\"},\"wordCount\":820,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/e-commerce-panier-abandonne-que-faire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2023\\\/09\\\/pannier-abandonne-ecommerce.jpg\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/e-commerce-panier-abandonne-que-faire\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/e-commerce-panier-abandonne-que-faire\\\/\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/e-commerce-panier-abandonne-que-faire\\\/\",\"name\":\"Panier abandonn\u00e9 : 4 conseils pour que l\u2019affaire soit (enfin) dans le sac \u2022 Salesforce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/e-commerce-panier-abandonne-que-faire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/e-commerce-panier-abandonne-que-faire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2023\\\/09\\\/pannier-abandonne-ecommerce.jpg\",\"datePublished\":\"2023-09-07T18:05:36+00:00\",\"dateModified\":\"2023-11-13T16:55:19+00:00\",\"description\":\"Un internaute visite votre site. Il consulte vos pages produits, en met un dans son panier, puis deux\u2026 avant de quitter votre site sans finaliser la commande. Rage, d\u00e9sespoir ! Comment limiter ce risque et m\u00eame transformer ce faux-pas en d\u00e9tour vers la caisse ? Voici 4 pistes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/e-commerce-panier-abandonne-que-faire\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/e-commerce-panier-abandonne-que-faire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/e-commerce-panier-abandonne-que-faire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2023\\\/09\\\/pannier-abandonne-ecommerce.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2023\\\/09\\\/pannier-abandonne-ecommerce.jpg\",\"width\":3000,\"height\":2442,\"caption\":\"Panier abandonn\u00e9 : 4 conseils pour que l\u2019affaire soit (enfin) dans le sac\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/e-commerce-panier-abandonne-que-faire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Panier abandonn\u00e9 : 4 conseils pour que l\u2019affaire soit (enfin) dans le sac\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/\",\"name\":\"Salesforce\",\"description\":\"Le Blog du CRM, de l&#039;experience et du Cloud Computing\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/#organization\",\"name\":\"Salesforce\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2023\\\/10\\\/Salesforce.webp\",\"contentUrl\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2023\\\/10\\\/Salesforce.webp\",\"width\":1200,\"height\":630,\"caption\":\"Salesforce\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/#\\\/schema\\\/person\\\/image\\\/c4dae87da9a6134c35582db989c80f90\",\"name\":\"Salesforce\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g60edf16c093aaa190ff084acb1722622\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g\",\"caption\":\"Salesforce\"},\"url\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/author\\\/salesforce\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Panier abandonn\u00e9 : 4 conseils pour que l\u2019affaire soit (enfin) dans le sac \u2022 Salesforce","description":"Un internaute visite votre site. Il consulte vos pages produits, en met un dans son panier, puis deux\u2026 avant de quitter votre site sans finaliser la commande. Rage, d\u00e9sespoir ! Comment limiter ce risque et m\u00eame transformer ce faux-pas en d\u00e9tour vers la caisse ? Voici 4 pistes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salesforce.com\/fr\/blog\/e-commerce-panier-abandonne-que-faire\/","og_locale":"fr_FR","og_type":"article","og_title":"Panier abandonn\u00e9 : 4 conseils pour que l\u2019affaire soit (enfin) dans le sac","og_description":"Un internaute visite votre site. Il consulte vos pages produits, en met un dans son panier, puis deux\u2026 avant de quitter votre site sans finaliser la commande. Rage, d\u00e9sespoir ! Comment limiter ce risque et m\u00eame transformer ce faux-pas en d\u00e9tour vers la caisse ? Voici 4 pistes.","og_url":"https:\/\/www.salesforce.com\/fr\/blog\/e-commerce-panier-abandonne-que-faire\/","og_site_name":"Salesforce","article_published_time":"2023-09-07T18:05:36+00:00","article_modified_time":"2023-11-13T16:55:19+00:00","og_image":[{"width":4000,"height":2250,"url":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/10\/Salesforce-logo.webp","type":"image\/webp"}],"author":"Salesforce","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"","Dur\u00e9e de lecture estim\u00e9e":"4 minutes","Written by":"Salesforce"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salesforce.com\/fr\/blog\/e-commerce-panier-abandonne-que-faire\/#article","isPartOf":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/e-commerce-panier-abandonne-que-faire\/"},"author":[{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/person\/image\/c4dae87da9a6134c35582db989c80f90"}],"headline":"Panier abandonn\u00e9 : 4 conseils pour que l\u2019affaire soit (enfin) dans le sac","datePublished":"2023-09-07T18:05:36+00:00","dateModified":"2023-11-13T16:55:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/e-commerce-panier-abandonne-que-faire\/"},"wordCount":820,"commentCount":0,"publisher":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/#organization"},"image":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/e-commerce-panier-abandonne-que-faire\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/pannier-abandonne-ecommerce.jpg","inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.salesforce.com\/fr\/blog\/e-commerce-panier-abandonne-que-faire\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.salesforce.com\/fr\/blog\/e-commerce-panier-abandonne-que-faire\/","url":"https:\/\/www.salesforce.com\/fr\/blog\/e-commerce-panier-abandonne-que-faire\/","name":"Panier abandonn\u00e9 : 4 conseils pour que l\u2019affaire soit (enfin) dans le sac \u2022 Salesforce","isPartOf":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/e-commerce-panier-abandonne-que-faire\/#primaryimage"},"image":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/e-commerce-panier-abandonne-que-faire\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/pannier-abandonne-ecommerce.jpg","datePublished":"2023-09-07T18:05:36+00:00","dateModified":"2023-11-13T16:55:19+00:00","description":"Un internaute visite votre site. Il consulte vos pages produits, en met un dans son panier, puis deux\u2026 avant de quitter votre site sans finaliser la commande. Rage, d\u00e9sespoir ! Comment limiter ce risque et m\u00eame transformer ce faux-pas en d\u00e9tour vers la caisse ? Voici 4 pistes.","breadcrumb":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/e-commerce-panier-abandonne-que-faire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salesforce.com\/fr\/blog\/e-commerce-panier-abandonne-que-faire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.salesforce.com\/fr\/blog\/e-commerce-panier-abandonne-que-faire\/#primaryimage","url":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/pannier-abandonne-ecommerce.jpg","contentUrl":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/pannier-abandonne-ecommerce.jpg","width":3000,"height":2442,"caption":"Panier abandonn\u00e9 : 4 conseils pour que l\u2019affaire soit (enfin) dans le sac"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salesforce.com\/fr\/blog\/e-commerce-panier-abandonne-que-faire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salesforce.com\/fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Panier abandonn\u00e9 : 4 conseils pour que l\u2019affaire soit (enfin) dans le sac"}]},{"@type":"WebSite","@id":"https:\/\/www.salesforce.com\/fr\/blog\/#website","url":"https:\/\/www.salesforce.com\/fr\/blog\/","name":"Salesforce","description":"Le Blog du CRM, de l&#039;experience et du Cloud Computing","publisher":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salesforce.com\/fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.salesforce.com\/fr\/blog\/#organization","name":"Salesforce","url":"https:\/\/www.salesforce.com\/fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/10\/Salesforce.webp","contentUrl":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/10\/Salesforce.webp","width":1200,"height":630,"caption":"Salesforce"},"image":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/person\/image\/c4dae87da9a6134c35582db989c80f90","name":"Salesforce","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g60edf16c093aaa190ff084acb1722622","url":"https:\/\/secure.gravatar.com\/avatar\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g","caption":"Salesforce"},"url":"https:\/\/www.salesforce.com\/fr\/blog\/author\/salesforce\/"}]}},"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Salesforce","distributor_original_site_url":"https:\/\/www.salesforce.com\/fr\/blog","push-errors":false,"jetpack_featured_media_url":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/pannier-abandonne-ecommerce.jpg","_links":{"self":[{"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/comments?post=368"}],"version-history":[{"count":4,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/368\/revisions"}],"predecessor-version":[{"id":2574,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/368\/revisions\/2574"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/media\/370"}],"wp:attachment":[{"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/media?parent=368"}],"wp:term":[{"taxonomy":"sf_topic","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/sf_topic?post=368"},{"taxonomy":"sf_content_type","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/sf_content_type?post=368"},{"taxonomy":"blog","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/blog?post=368"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/coauthors?post=368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}