{"id":371,"date":"2023-02-23T18:05:00","date_gmt":"2023-09-07T18:05:49","guid":{"rendered":"https:\/\/www.salesforce.com\/?p=371"},"modified":"2023-10-25T10:56:10","modified_gmt":"2023-10-25T10:56:10","slug":"comprendre-automatisation-workflow","status":"publish","type":"post","link":"https:\/\/www.salesforce.com\/fr\/blog\/comprendre-automatisation-workflow\/","title":{"rendered":"Comprendre l\u2019automatisation des workflows"},"content":{"rendered":"\n<p>Les processus m\u00e9tiers complexes, qui manquent de logique et sont parfois m\u00eame, il faut bien l\u2019avouer, franchement obsol\u00e8tes, font partie du quotidien de milliers d\u2019entreprises. Cela nuit non seulement \u00e0 la productivit\u00e9 et \u00e0 l\u2019efficacit\u00e9, mais aussi au moral des employ\u00e9s. Car rien n\u2019est plus d\u00e9motivant que de devoir ex\u00e9cuter chaque jour des t\u00e2ches r\u00e9barbatives, fastidieuses et chronophages. Mais gr\u00e2ce \u00e0 l\u2019automatisation des workflow, tout cela appartient aujourd\u2019hui au pass\u00e9. Dans cet article, on vous explique tout ce qu\u2019il faut savoir sur l\u2019automatisation des flux de travail et comment ce dispositif permet \u00e0 tous les d\u00e9partements de l\u2019entreprise de gagner du temps et de r\u00e9duire les d\u00e9penses. <\/p>\n\n\n\n<div class=\"layout-five wp-block-salesforce-blog-offer\">\n\t<div class=\"wp-block-offer__wrapper\">\n\n\t\t<div class=\"wp-block-offer__content\">\n\t\t\t<h2 class=\"wp-block-offer__title\">Le guide de la PME connect\u00e9e<\/h2>\n\t\t\t\t\t\t\t<p class=\"wp-block-offer__description\"><span>Ou comment devenir plus rapide, plus agile et plus efficiente gr\u00e2ce \u00e0 la gestion des processus m\u00e9tiers.<\/span><\/p>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t<a class=\"wp-block-button__link\" target=\"_self\" href=\"https:\/\/www.salesforce.com\/fr\/form\/pdf\/connected-small-business-processes\/?d=inc-blog-banner&#038;nc=7013y000002lWUTAA2\">Je connecte mes processus m\u00e9tiers<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"wp-block-offer__media\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" src=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/02\/Le-guide-de-la-PME-connectee.png\" class=\"attachment-full size-full\" alt=\"Le guide de la PME connect\u00e9e\" srcset=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/02\/Le-guide-de-la-PME-connectee.png 1268w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/02\/Le-guide-de-la-PME-connectee.png?w=300&amp;h=169 300w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/02\/Le-guide-de-la-PME-connectee.png?w=768&amp;h=432 768w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/02\/Le-guide-de-la-PME-connectee.png?w=1024&amp;h=577 1024w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/02\/Le-guide-de-la-PME-connectee.png?w=150&amp;h=84 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/div>\n\t<\/div>\n\n\t\n\t\t\t<!-- Standard Illustration -->\n\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__illustration\" src=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-illustration-layout-five.png\" alt=\"\">\n\n\t\t<!-- Small Accent Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__accent\" src=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-accent-layout-five.png\" alt=\"\">\n\t\t\n\t\t<!-- Left Side Illustration -->\n\t\t\n\t\t<!-- Cloud Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__cloud\" src=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-cloud-layout-five.png\" alt=\"\">\n\t\t\n\t<\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><b>Workflow automation, automatisation des workflow, automatisation des processus m\u00e9tiers. De quoi s\u2019agit-il ?<\/b><\/h2>\n\n\n\n<p>Pas de panique, ces trois termes d\u00e9signent la m\u00eame chose : l\u2019utilisation d\u2019outils intelligents pour accomplir des t\u00e2ches sans n\u00e9cessiter d\u2019intervention humaine. Par exemple, plut\u00f4t que les commerciaux transmettent aux clients les devis manuellement, leur envoi peut se faire automatiquement, gr\u00e2ce \u00e0 l\u2019automatisation des processus m\u00e9tiers.<\/p>\n\n\n\n<p>De plus en plus d\u2019entreprises ont recours \u00e0 ces technologies dont l\u2019efficacit\u00e9 a fait ses preuves et dont les fonctionnalit\u00e9s se perfectionnent chaque jour. L\u2019automatisation des flux de travail permet de rationaliser les processus m\u00e9tiers, afin d\u2019\u00e9liminer toutes les r\u00e9p\u00e9titions, les points de friction et les incoh\u00e9rences. Puis de les automatiser, en les attribuant \u00e0 une machine plut\u00f4t qu\u2019\u00e0 un \u00eatre humain. Imaginez un peu un univers de travail o\u00f9 toutes les missions routini\u00e8res et \u00e0 faible valeur, les processus r\u00e9p\u00e9titifs et complexes, disparaissent de la liste des t\u00e2ches \u00e0 ex\u00e9cuter des employ\u00e9s et n\u2019entravent plus leur productivit\u00e9. Ils peuvent enfin se concentrer sur des missions plus strat\u00e9giques qui profiteront davantage \u00e0 l\u2019entreprise.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><b>Les avantages de l\u2019automatisation des processus m\u00e9tiers<\/b><\/h2>\n\n\n\n<p>Depuis quelques ann\u00e9es, l\u2019automatisation des workflow est au centre de toutes les attentions. D\u2019apr\u00e8s <a href=\"https:\/\/www.salesforce.com\/eu\/resources\/research-reports\/trends-in-workflow-automation\/\" target=\"_blank\" rel=\"noopener\">une enqu\u00eate de Salesforce et Pulse<\/a>, 95 % des professionnels de l\u2019IT affirment m\u00eame qu\u2019elle est leur priorit\u00e9. <\/p>\n\n\n\n<p>Et si l\u2019automatisation fait autant parler, c\u2019est parce que beaucoup la voient comme une autoroute vers le succ\u00e8s. Car oui, l\u2019automatisation \u00e7a marche ! <\/p>\n\n\n\n<p>Parmi les avantages de l\u2019automatisation des workflow :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li> <b style=\"color: var(--c-nero); font-family: var(--f-secondary); font-size: 1rem; letter-spacing: 0.0012em;\">L\u2019augmentation de la productivit\u00e9 des \u00e9quipes<\/b> <\/li>\n<\/ul>\n\n\n\n<p>Leur emploi du temps lib\u00e9r\u00e9, les collaborateurs peuvent d\u00e9sormais se concentrer sur les missions propres \u00e0 leur c\u0153ur de m\u00e9tier. 75 % des professionnels informatique interrog\u00e9s rapportent un gain de temps de l\u2019ordre de 4 heures par semaine (dans le cadre d\u2019une semaine de 40 heures).<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li> <b style=\"color: var(--c-nero); font-family: var(--f-secondary); font-size: 1rem; letter-spacing: 0.0012em;\">R\u00e9duction des co\u00fbts<\/b> <\/li>\n<\/ul>\n\n\n\n<p>Le recours aux machines permet d\u2019\u00e9conomiser les d\u00e9penses li\u00e9es \u00e0 l\u2019utilisation de ressources humaines. Ce n\u2019est pas tout. L\u2019automatisation avantage aussi financi\u00e8rement les entreprises en \u00e9liminant les erreurs humaines qui leur co\u00fbtent cher. Parmi les \u00e9quipes soutenues par l\u2019automatisation, 59 % ont constat\u00e9 une r\u00e9duction de leurs d\u00e9penses de 11 \u00e0 30 % minimum. <\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a0477ba170e3&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a0477ba170e3\" class=\"wp-block-image wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/lh6.googleusercontent.com\/Yssrvq4Grb_7RKaclcQSayor6I_57OW0II873ZBivwVNy47Ge-cczI3Z-C6h2lYUvQWilNlUPkAWSu2brEn6O0ydSWT1b4LHXtT1SYj6vjoJz2FHHj_gSVE2ziM9EM9Tgk8gHIhEw_vp_S4Dq9uk0A\" alt=\"\"\/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li> <b style=\"color: var(--c-nero); font-family: var(--f-secondary); font-size: 1rem; letter-spacing: 0.0012em;\">Gain d\u2019efficience<\/b> <\/li>\n<\/ul>\n\n\n\n<p>En outre du temps et de l\u2019argent gagn\u00e9s, l\u2019automatisation est aussi un gage d\u2019efficacit\u00e9. Les employ\u00e9s se concentrent uniquement sur les missions strat\u00e9giques et plus sur les menues besognes. Les ressources humaines et financi\u00e8res de l\u2019entreprise sont ainsi utilis\u00e9es de mani\u00e8re optimale. <\/p>\n\n\n\n<p>R\u00e9sultats : la satisfaction employ\u00e9 augmente. La motivation et le d\u00e9vouement \u00e0 l\u2019entreprise \u00e9galement. Le turnover diminue et par cons\u00e9quent, les co\u00fbts li\u00e9s au recrutement aussi. C\u2019est un v\u00e9ritable cercle vertueux qui se cr\u00e9e et dont les b\u00e9n\u00e9fices rejaillissent en cascade sur l\u2019entreprise. D\u2019ailleurs, l\u2019\u00e9tude r\u00e9v\u00e8le que la majorit\u00e9 des professionnels sond\u00e9s fait \u00e9tat d\u2019un retour sur investissement important, suite \u00e0 l\u2019int\u00e9gration de processus m\u00e9tiers automatis\u00e9s.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><b>Quelques exemples de workflow automation<\/b><\/h2>\n\n\n\n<p>Dans ce contexte \u00e9conomique complexe o\u00f9 les objectifs sont toujours plus \u00e9lev\u00e9s et les budgets restreints, l\u2019automatisation des processus m\u00e9tiers est essentielle pour relever les d\u00e9fis qui se dressent devant les entreprises. Elle peut d\u2019ailleurs \u00eatre mise en \u0153uvre dans quasiment tous les d\u00e9partements de l\u2019entreprise. <\/p>\n\n\n\n<p>Voici quelques exemples de workflow automation par fonctions : <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li> <b style=\"color: var(--c-nero); font-family: var(--f-secondary); font-size: 1rem; letter-spacing: 0.0012em;\">L\u2019automatisation pour le marketing<\/b> <\/li>\n<\/ul>\n\n\n\n<p>Pour maintenir une communication fluide avec les clients et d\u00e9velopper une relation solide, il est impossible aujourd\u2019hui de se passer de l\u2019automatisation. <\/p>\n\n\n\n<p>\u00c9quip\u00e9es de ce dispositif, les entreprises sont capables d\u2019automatiser une suite d\u2019actions, en fonction du comportement de l\u2019utilisateur et selon des sc\u00e9narios pr\u00e9d\u00e9finis. <\/p>\n\n\n\n<p>Exemples : envoi d\u2019emails ou d\u2019offres promotionnelles \u00e0 des moments cl\u00e9s pour le consommateur, envoi de sondages pour mieux conna\u00eetre et segmenter l\u2019audience. <\/p>\n\n\n\n<p>Elle facilite aussi le suivi et l\u2019analyse des campagnes marketing. <\/p>\n\n\n\n<p>Pour r\u00e9sumer, <a href=\"https:\/\/www.salesforce.com\/fr\/resources\/articles\/definition-automation\/\" target=\"_blank\" rel=\"noopener\">l\u2019automatisation marketing (ou marketing automation)<\/a> permet d\u2019automatiser : les interactions clients, l\u2019int\u00e9gration des donn\u00e9es, la personnalisation du parcours client sur les diff\u00e9rents canaux et l\u2019analytique. <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li> <b style=\"color: var(--c-nero); font-family: var(--f-secondary); font-size: 1rem; letter-spacing: 0.0012em;\">L\u2019automatisation pour les ventes<\/b> <\/li>\n<\/ul>\n\n\n\n<p>Le fonctionnement des ventes a beaucoup \u00e9volu\u00e9 en raison de l\u2019automatisation des workflow. <a href=\"https:\/\/www.salesforce.com\/fr\/products\/sales-cloud\/features\/workflow-process-software\/\" target=\"_blank\" rel=\"noopener\">Pour les commerciaux, les flux de travail automatis\u00e9s repr\u00e9sentent un gain de temps majeur.<\/a><\/p>\n\n\n\n<p>Ils permettent de faire progresser les prospects \u00e0 travers le pipeline de vente, \u00e9tape par \u00e9tape, jusqu\u2019\u00e0 ce qu\u2019ils soient suffisamment matures pour \u00eatre abord\u00e9s par un vendeur. Les commerciaux ne perdent plus de temps \u00e0 convaincre des leads qui ne sont tout simplement pas pr\u00eats \u00e0 l\u2019achat.<\/p>\n\n\n\n<p>La mission principale des vendeurs est la vente. Pourtant, de nombreuses \u00e9tudes montrent qu\u2019ils passent plus de temps \u00e0 ex\u00e9cuter des t\u00e2ches administratives qu\u2019\u00e0 construire des relations avec les clients pour vendre. Les flux de travail automatis\u00e9s prennent le relais et g\u00e8rent la saisie des informations clients et des donn\u00e9es li\u00e9es aux ventes. Les vendeurs gagnent ainsi un temps pr\u00e9cieux. <\/p>\n\n\n\n<p>L\u2019automatisation facilite les propositions de ventes crois\u00e9es et incitatives et ainsi, encourage l\u2019augmentation du volume des ventes. <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li> <b style=\"color: var(--c-nero); font-family: var(--f-secondary); font-size: 1rem; letter-spacing: 0.0012em;\">L\u2019automatisation pour le service client<\/b> <\/li>\n<\/ul>\n\n\n\n<p>Sans intervention humaine, les flux de travail automatis\u00e9s peuvent d\u00e9sormais effectuer : la construction du dossier client, sa classification et son attribution au bon agent. Mais aussi, des recommandations d\u2019actions, la transcription des interactions avec les clients et l\u2019envoi d\u2019enqu\u00eates de satisfaction. <\/p>\n\n\n\n<p>L\u2019une des plus belles r\u00e9ussites technologiques au sein du service client (et aussi la plus embl\u00e9matique) est la cr\u00e9ation des chatbots. Ces bots ont r\u00e9volutionn\u00e9 les standards du service client. Ils permettent d\u00e9sormais d\u2019offrir un service plus rapide et \u00e0 toute heure aux consommateurs pour une exp\u00e9rience client plus satisfaisante. <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li> <b style=\"color: var(--c-nero); font-family: var(--f-secondary); font-size: 1rem; letter-spacing: 0.0012em;\">L\u2019automatisation pour la comptabilit\u00e9 et finance<\/b> <\/li>\n<\/ul>\n\n\n\n<p>Saisie de donn\u00e9es, gestion des paiements et des factures, tenue des comptabilit\u00e9s, cr\u00e9ation de rapports comptables\u2026 Les domaines o\u00f9 l\u2019automatisation fait des merveilles sont nombreux. Dans le secteur financier o\u00f9 une erreur infime peut co\u00fbter tr\u00e8s cher, l\u2019automatisation limite fortement le risque d\u2019erreurs humaines. Les factures sont trait\u00e9es dans les d\u00e9lais y compris lors des p\u00e9riodes de travail intenses. Enfin, les directeurs financiers obtiennent sans effort des rapports comptables complexes qui permettent de guider les prises de d\u00e9cisions strat\u00e9giques de l\u2019entreprise. <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li> <b style=\"color: var(--c-nero); font-family: var(--f-secondary); font-size: 1rem; letter-spacing: 0.0012em;\">L\u2019automatisation pour la production<\/b> <\/li>\n<\/ul>\n\n\n\n<p>En usine, la synergie des processus automatis\u00e9s et de l\u2019Internet des Objets (IoT) optimise le contr\u00f4le de la qualit\u00e9. Ils \u00e9liminent les points de friction et permettent de diminuer les co\u00fbts de production. La collecte automatis\u00e9e de donn\u00e9es permet \u00e9galement aux fabricants de d\u00e9velopper leur agilit\u00e9, en acc\u00e9l\u00e9rant leur prise de d\u00e9cision en temps r\u00e9el gr\u00e2ce \u00e0 la fourniture de rapports plus pr\u00e9cis.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><b>Automatisation des processus m\u00e9tiers, les chiffres \u00e0 retenir :<\/b><\/h2>\n\n\n\n<p>Parmi les travailleurs qui utilisent l\u2019automatisation, <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><span style=\"color: var(--c-nero); font-family: var(--f-secondary); font-size: 1rem; letter-spacing: 0.0012em;\">83 % d\u00e9clarent que le temps gagn\u00e9 leur permet de se concentrer sur des missions plus importantes.<\/span> <\/li>\n\n\n\n<li><span style=\"background-color: rgba(24, 24, 24, 0.2); color: var(--c-nero); font-family: var(--f-secondary); font-size: 1rem; letter-spacing: 0.0012em;\">92 % affirment que l\u2019automatisation les rend plus productifs.<\/span> <\/li>\n\n\n\n<li><span style=\"color: var(--c-nero); font-family: var(--f-secondary); font-size: 1rem; letter-spacing: 0.0012em;\">74% revendiquent un regain d\u2019efficacit\u00e9 et affirment travailler plus rapidement.<\/span> <\/li>\n\n\n\n<li><span style=\"color: var(--c-nero); font-family: var(--f-secondary); font-size: 1rem; letter-spacing: 0.0012em;\">88 % font confiance \u00e0 l\u2019automatisation pour effectuer les processus sans erreur.<\/span> <\/li>\n\n\n\n<li><span style=\"color: var(--c-nero); font-family: var(--f-secondary); font-size: 1rem; letter-spacing: 0.0012em;\">84 % d\u00e9clarent qu\u2019ils sont plus satisfaits de leur travail et de leur employeur.<\/span> <\/li>\n\n\n\n<li><span style=\"color: var(--c-nero); font-family: var(--f-secondary); font-size: 1rem; letter-spacing: 0.0012em;\">76 % estiment que l\u2019usage de cette technologie a r\u00e9duit leurs niveaux de stress.<\/span> <\/li>\n<\/ul>\n\n\n\n<p>Source : <a href=\"https:\/\/www.salesforce.com\/news\/stories\/new-salesforce-research-links-lower-stress-levels-and-business-automation\/\" target=\"_blank\" rel=\"noopener\">Enqu\u00eate Automation &amp; Wellbeing<\/a>, Salesforce, 2022<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><span style=\"color: var(--c-nero); font-family: var(--f-secondary); font-size: 1rem; letter-spacing: 0.0012em;\">95 % des entreprises ont d\u00e9j\u00e0 mis en place (ou sont sur le point de le faire) des automatisations dans le but d\u2019am\u00e9liorer leur productivit\u00e9. <\/span> <\/li>\n\n\n\n<li><span style=\"color: var(--c-nero); font-family: var(--f-secondary); font-size: 1rem; letter-spacing: 0.0012em;\">93 % des entreprises per\u00e7oivent l\u2019automatisation comme un levier pour cr\u00e9er des exp\u00e9riences clients de meilleure qualit\u00e9 et comme un moyen d\u2019am\u00e9liorer l\u2019efficacit\u00e9 op\u00e9rationnelle. <\/span> <\/li>\n<\/ul>\n\n\n\n<p>Source : <a href=\"https:\/\/www.mulesoft.com\/lp\/reports\/it-business-alignment-barometer\" target=\"_blank\" rel=\"noopener\">IT and business alignment barometer<\/a>, MuleSoft, 2021<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><b>Vos premiers workflow automatis\u00e9s avec Salesforce<\/b><\/h2>\n\n\n\n<p>Vous aimeriez profiter des avantages de l\u2019automatisation des workflow, mais vous ne savez pas par o\u00f9 commencer ? Identifiez les aspects de votre entreprise que vous aimeriez am\u00e9liorer et laissez Salesforce s\u2019occuper du reste !<\/p>\n\n\n\n<p>Le workflow automation avec Salesforce est un jeu d\u2019enfants. <a href=\"https:\/\/www.salesforce.com\/fr\/products\/platform\/overview\/\" target=\"_blank\" rel=\"noopener\">Notre plateforme<\/a> vous permet de fluidifier vos op\u00e9rations en cr\u00e9ant facilement des workflows automatis\u00e9s, en low-code ou no code, par glisser-d\u00e9poser. Aucune comp\u00e9tence technique particuli\u00e8re n\u2019est n\u00e9cessaire ! <\/p>\n\n\n\n<p>Si vous pr\u00e9f\u00e9rez vous lancer progressivement et d\u00e9buter avec un d\u00e9partement en particulier, nous proposons aussi des solutions par fonction : <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a style=\"font-family: var(--f-secondary); font-size: 1rem; letter-spacing: 0.0012em; background-color: rgb(255, 255, 255);\" href=\"https:\/\/www.salesforce.com\/fr\/products\/sales-cloud\/overview\/\" target=\"_blank\" rel=\"noopener\">Sales Cloud, notre logiciel d&rsquo;automatisation des forces de vente<\/a><span style=\"color: var(--c-nero); font-family: var(--f-secondary); font-size: 1rem; letter-spacing: 0.0012em;\"> (SFA)<\/span> <\/li>\n\n\n\n<li><p><a href=\"https:\/\/www.salesforce.com\/fr\/products\/marketing-cloud\/overview\/\" target=\"_blank\" rel=\"noopener\">Marketing Cloud<\/a> d\u00e9di\u00e9 au marketing automation <\/p><\/li>\n\n\n\n<li><a style=\"font-family: var(--f-secondary); font-size: 1rem; letter-spacing: 0.0012em; background-color: rgb(255, 255, 255);\" href=\"https:\/\/www.salesforce.com\/fr\/products\/service-cloud\/overview\/\" target=\"_blank\" rel=\"noopener\">Service Cloud<\/a><span style=\"color: var(--c-nero); font-family: var(--f-secondary); font-size: 1rem; letter-spacing: 0.0012em;\">, pour les \u00e9quipes de service. <\/span> <\/li>\n<\/ul>\n\n\n\n<p>Elles vous permettront d\u2019optimiser <a href=\"https:\/\/www.salesforce.com\/fr\/blog\/2022\/05\/gestion-processus-metier-pme.html\" target=\"_blank\" rel=\"noopener\">la gestion de vos processus m\u00e9tier<\/a> pour gagner en efficacit\u00e9 et r\u00e9aliser des \u00e9conomies tangibles. <\/p>\n\n\n\n<div class=\"layout-five wp-block-salesforce-blog-offer\">\n\t<div class=\"wp-block-offer__wrapper\">\n\n\t\t<div class=\"wp-block-offer__content\">\n\t\t\t<h2 class=\"wp-block-offer__title\">Le guide de la PME connect\u00e9e<\/h2>\n\t\t\t\t\t\t\t<p class=\"wp-block-offer__description\"><span>Ou comment devenir plus rapide, plus agile et plus efficiente gr\u00e2ce \u00e0 la gestion des processus m\u00e9tiers.<\/span><\/p>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t<a class=\"wp-block-button__link\" target=\"_self\" href=\"https:\/\/www.salesforce.com\/fr\/form\/pdf\/connected-small-business-processes\/?d=inc-blog-banner&#038;nc=7013y000002lWUTAA2\">Je connecte mes processus m\u00e9tiers<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"wp-block-offer__media\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" src=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/02\/Le-guide-de-la-PME-connectee.png\" class=\"attachment-full size-full\" alt=\"Le guide de la PME connect\u00e9e\" srcset=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/02\/Le-guide-de-la-PME-connectee.png 1268w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/02\/Le-guide-de-la-PME-connectee.png?w=300&amp;h=169 300w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/02\/Le-guide-de-la-PME-connectee.png?w=768&amp;h=432 768w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/02\/Le-guide-de-la-PME-connectee.png?w=1024&amp;h=577 1024w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/02\/Le-guide-de-la-PME-connectee.png?w=150&amp;h=84 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/div>\n\t<\/div>\n\n\t\n\t\t\t<!-- Standard Illustration -->\n\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__illustration\" src=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-illustration-layout-five.png\" alt=\"\">\n\n\t\t<!-- Small Accent Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__accent\" src=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-accent-layout-five.png\" alt=\"\">\n\t\t\n\t\t<!-- Left Side Illustration -->\n\t\t\n\t\t<!-- Cloud Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__cloud\" src=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-cloud-layout-five.png\" alt=\"\">\n\t\t\n\t<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tout ce qu\u2019il faut savoir sur l\u2019automatisation des flux de travail. Les diff\u00e9rents usages en entreprise et l&rsquo;impact sur la productivit\u00e9.<\/p>\n","protected":false},"author":1,"featured_media":373,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sf_justforyou_enable_alt":true,"optimizely_content_id":"fba413910e374e59872da69b09a2a1d4","post_meta_title":"","ai_synopsis":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"sf_topic":[8,1,22,24],"sf_content_type":[],"blog":[296,297,365,374],"coauthors":[27],"class_list":["post-371","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","sf_topic-best-practices","sf_topic-small-business","sf_topic-digital-transformation","sf_topic-data-culture","blog-data-culture","blog-digital-transformation","blog-small-business","blog-best-practices"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Comprendre l\u2019automatisation des workflow en 5 minutes \u2022 Salesforce<\/title>\n<meta name=\"description\" content=\"Tout ce qu\u2019il faut savoir sur l\u2019automatisation des flux de travail. Les diff\u00e9rents usages en entreprise et l&#039;impact sur la productivit\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salesforce.com\/fr\/blog\/comprendre-automatisation-workflow\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comprendre l\u2019automatisation des workflows\" \/>\n<meta property=\"og:description\" content=\"Tout ce qu\u2019il faut savoir sur l\u2019automatisation des flux de travail. Les diff\u00e9rents usages en entreprise et l&#039;impact sur la productivit\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salesforce.com\/fr\/blog\/comprendre-automatisation-workflow\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-07T18:05:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-25T10:56:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/guide-to-automatic-workflows.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"288\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Salesforce\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"digital-delivery-operations7076\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Salesforce\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/comprendre-automatisation-workflow\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/comprendre-automatisation-workflow\/\"},\"author\":[{\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/person\/image\/c4dae87da9a6134c35582db989c80f90\"}],\"headline\":\"Comprendre l\u2019automatisation des workflows\",\"datePublished\":\"2023-09-07T18:05:49+00:00\",\"dateModified\":\"2023-10-25T10:56:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/comprendre-automatisation-workflow\/\"},\"wordCount\":1641,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/comprendre-automatisation-workflow\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/guide-to-automatic-workflows.jpg\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.salesforce.com\/fr\/blog\/comprendre-automatisation-workflow\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/comprendre-automatisation-workflow\/\",\"url\":\"https:\/\/www.salesforce.com\/fr\/blog\/comprendre-automatisation-workflow\/\",\"name\":\"Comprendre l\u2019automatisation des workflow en 5 minutes \u2022 Salesforce\",\"isPartOf\":{\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/comprendre-automatisation-workflow\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/comprendre-automatisation-workflow\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/guide-to-automatic-workflows.jpg\",\"datePublished\":\"2023-09-07T18:05:49+00:00\",\"dateModified\":\"2023-10-25T10:56:10+00:00\",\"description\":\"Tout ce qu\u2019il faut savoir sur l\u2019automatisation des flux de travail. Les diff\u00e9rents usages en entreprise et l'impact sur la productivit\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/comprendre-automatisation-workflow\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.salesforce.com\/fr\/blog\/comprendre-automatisation-workflow\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/comprendre-automatisation-workflow\/#primaryimage\",\"url\":\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/guide-to-automatic-workflows.jpg\",\"contentUrl\":\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/guide-to-automatic-workflows.jpg\",\"width\":500,\"height\":288,\"caption\":\"Comprendre l\u2019automatisation des workflows\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/comprendre-automatisation-workflow\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.salesforce.com\/fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comprendre l\u2019automatisation des workflows\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/#website\",\"url\":\"https:\/\/www.salesforce.com\/fr\/blog\/\",\"name\":\"Salesforce\",\"description\":\"Le Blog du CRM, de l&#039;experience et du Cloud Computing\",\"publisher\":{\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.salesforce.com\/fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/#organization\",\"name\":\"Salesforce\",\"url\":\"https:\/\/www.salesforce.com\/fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/10\/Salesforce.webp\",\"contentUrl\":\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/10\/Salesforce.webp\",\"width\":1200,\"height\":630,\"caption\":\"Salesforce\"},\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/person\/image\/c4dae87da9a6134c35582db989c80f90\",\"name\":\"Salesforce\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g60edf16c093aaa190ff084acb1722622\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g\",\"caption\":\"Salesforce\"},\"url\":\"https:\/\/www.salesforce.com\/fr\/blog\/author\/salesforce\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Comprendre l\u2019automatisation des workflow en 5 minutes \u2022 Salesforce","description":"Tout ce qu\u2019il faut savoir sur l\u2019automatisation des flux de travail. Les diff\u00e9rents usages en entreprise et l'impact sur la productivit\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salesforce.com\/fr\/blog\/comprendre-automatisation-workflow\/","og_locale":"fr_FR","og_type":"article","og_title":"Comprendre l\u2019automatisation des workflows","og_description":"Tout ce qu\u2019il faut savoir sur l\u2019automatisation des flux de travail. Les diff\u00e9rents usages en entreprise et l'impact sur la productivit\u00e9.","og_url":"https:\/\/www.salesforce.com\/fr\/blog\/comprendre-automatisation-workflow\/","og_site_name":"Salesforce","article_published_time":"2023-09-07T18:05:49+00:00","article_modified_time":"2023-10-25T10:56:10+00:00","og_image":[{"width":500,"height":288,"url":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/guide-to-automatic-workflows.jpg","type":"image\/jpeg"}],"author":"Salesforce","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"digital-delivery-operations7076","Dur\u00e9e de lecture estim\u00e9e":"8 minutes","Written by":"Salesforce"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salesforce.com\/fr\/blog\/comprendre-automatisation-workflow\/#article","isPartOf":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/comprendre-automatisation-workflow\/"},"author":[{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/person\/image\/c4dae87da9a6134c35582db989c80f90"}],"headline":"Comprendre l\u2019automatisation des workflows","datePublished":"2023-09-07T18:05:49+00:00","dateModified":"2023-10-25T10:56:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/comprendre-automatisation-workflow\/"},"wordCount":1641,"commentCount":0,"publisher":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/#organization"},"image":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/comprendre-automatisation-workflow\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/guide-to-automatic-workflows.jpg","inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.salesforce.com\/fr\/blog\/comprendre-automatisation-workflow\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.salesforce.com\/fr\/blog\/comprendre-automatisation-workflow\/","url":"https:\/\/www.salesforce.com\/fr\/blog\/comprendre-automatisation-workflow\/","name":"Comprendre l\u2019automatisation des workflow en 5 minutes \u2022 Salesforce","isPartOf":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/comprendre-automatisation-workflow\/#primaryimage"},"image":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/comprendre-automatisation-workflow\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/guide-to-automatic-workflows.jpg","datePublished":"2023-09-07T18:05:49+00:00","dateModified":"2023-10-25T10:56:10+00:00","description":"Tout ce qu\u2019il faut savoir sur l\u2019automatisation des flux de travail. Les diff\u00e9rents usages en entreprise et l'impact sur la productivit\u00e9.","breadcrumb":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/comprendre-automatisation-workflow\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salesforce.com\/fr\/blog\/comprendre-automatisation-workflow\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.salesforce.com\/fr\/blog\/comprendre-automatisation-workflow\/#primaryimage","url":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/guide-to-automatic-workflows.jpg","contentUrl":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/guide-to-automatic-workflows.jpg","width":500,"height":288,"caption":"Comprendre l\u2019automatisation des workflows"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salesforce.com\/fr\/blog\/comprendre-automatisation-workflow\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salesforce.com\/fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Comprendre l\u2019automatisation des workflows"}]},{"@type":"WebSite","@id":"https:\/\/www.salesforce.com\/fr\/blog\/#website","url":"https:\/\/www.salesforce.com\/fr\/blog\/","name":"Salesforce","description":"Le Blog du CRM, de l&#039;experience et du Cloud Computing","publisher":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salesforce.com\/fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.salesforce.com\/fr\/blog\/#organization","name":"Salesforce","url":"https:\/\/www.salesforce.com\/fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/10\/Salesforce.webp","contentUrl":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/10\/Salesforce.webp","width":1200,"height":630,"caption":"Salesforce"},"image":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/person\/image\/c4dae87da9a6134c35582db989c80f90","name":"Salesforce","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g60edf16c093aaa190ff084acb1722622","url":"https:\/\/secure.gravatar.com\/avatar\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g","caption":"Salesforce"},"url":"https:\/\/www.salesforce.com\/fr\/blog\/author\/salesforce\/"}]}},"jetpack_featured_media_url":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/guide-to-automatic-workflows.jpg","jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Salesforce","distributor_original_site_url":"https:\/\/www.salesforce.com\/fr\/blog","push-errors":false,"_links":{"self":[{"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/comments?post=371"}],"version-history":[{"count":3,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/371\/revisions"}],"predecessor-version":[{"id":2396,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/371\/revisions\/2396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/media\/373"}],"wp:attachment":[{"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/media?parent=371"}],"wp:term":[{"taxonomy":"sf_topic","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/sf_topic?post=371"},{"taxonomy":"sf_content_type","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/sf_content_type?post=371"},{"taxonomy":"blog","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/blog?post=371"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/coauthors?post=371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}