{"id":4707,"date":"2026-04-23T10:00:05","date_gmt":"2026-04-23T10:00:05","guid":{"rendered":"https:\/\/www.salesforce.com\/?p=4707"},"modified":"2026-04-24T13:22:28","modified_gmt":"2026-04-24T13:22:28","slug":"fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie","status":"publish","type":"post","link":"https:\/\/www.salesforce.com\/fr\/blog\/fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie\/","title":{"rendered":"FillMed injecte les donn\u00e9es et l&rsquo;IA au c\u0153ur de sa strat\u00e9gie"},"content":{"rendered":"\n<p><strong>Chez FillMed, l&rsquo;innovation ne s&rsquo;arr\u00eate pas aux portes du laboratoire. En s&rsquo;appuyant sur Salesforce pour structurer sa strat\u00e9gie CRM, l\u2019entreprise pionni\u00e8re du <em>pro-aging<\/em> place les donn\u00e9es et l\u2019IA au c\u0153ur de son mod\u00e8le op\u00e9rationnel.&nbsp;<\/strong><\/p>\n\n\n\n<p>Fond\u00e9s en 1978, les laboratoires <a href=\"https:\/\/fr.fillmed.com\/\">FillMed<\/a> se sont impos\u00e9s comme un acteur de r\u00e9f\u00e9rence du march\u00e9 de la m\u00e9decine esth\u00e9tique. Au c\u0153ur de leur approche, le <em>pro-aging<\/em>, un positionnement qui vise \u00e0 accompagner les hommes et les femmes de tous \u00e2ges vers le\u00a0\u00ab\u00a0mieux vieillir\u00a0\u00bb\u00a0gr\u00e2ce \u00e0 des dispositifs m\u00e9dicaux innovants.\u00a0<\/p>\n\n\n\n<p>\u00ab Cette philosophie irrigue l\u2019ensemble de nos gammes, en premier lieu le NCTF\u00ae 135 HA, une formule mise au point en 1975 par le docteur Michel Tordjman pour revitaliser la peau en stimulant la production de vitamines et de collag\u00e8ne \u00bb, indique Gauthier M\u00e9nart, Directeur des syst\u00e8mes d\u2019information de FillMed. Des gammes d\u2019injectables, de fillers et de dermo-cosm\u00e9tiques compl\u00e8tent cette offre pour r\u00e9pondre aux signes du vieillissement et r\u00e9g\u00e9n\u00e9rer durablement la peau des patients.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-une-entreprise-en-mouvement-au-coeur-d-un-marche-en-mutation-nbsp\"><strong>Une entreprise en mouvement au c\u0153ur d\u2019un march\u00e9 en mutation&nbsp;<\/strong><\/h1>\n\n\n\n<p>Pr\u00e9sent \u00e0 l\u2019international avec 7 filiales en propre (Angleterre, Chine, Espagne, Portugal, Italie, Pologne, Turquie) et plus de 80 distributeurs, FillMed s\u2019appuie sur une forte capacit\u00e9 d\u2019innovation. Celle-ci repose sur un mod\u00e8le int\u00e9gr\u00e9, qui combine les activit\u00e9s de recherche et d\u00e9veloppement, de production et fabrication, et de conduite d\u2019\u00e9tudes pr\u00e9-cliniques et cliniques, toutes pilot\u00e9es en interne. \u00ab Notre ma\u00eetrise de bout en bout de la cha\u00eene de valeur nous permet d\u2019acc\u00e9l\u00e9rer le d\u00e9veloppement de nouvelles solutions, tout en garantissant un haut niveau d\u2019exigence scientifique et industrielle \u00bb, d\u00e9crit Gauthier M\u00e9nart.<\/p>\n\n\n\n<p>Apr\u00e8s plusieurs ann\u00e9es de croissance soutenue, le march\u00e9 de la m\u00e9decine esth\u00e9tique se stabilise et la concurrence s\u2019intensifie. L\u00e0 o\u00f9 l\u2019innovation produit ne suffit plus, l\u2019excellence dans l\u2019ex\u00e9cution commerciale devient un levier cl\u00e9 de diff\u00e9renciation. Pour FillMed, l&rsquo;enjeu est de conqu\u00e9rir des parts de march\u00e9 tout en gagnant en efficience op\u00e9rationnelle. La ma\u00eetrise et l&rsquo;utilisation des donn\u00e9es sont au c\u0153ur de cette \u00e9quation. Dans un environnement fortement r\u00e9glement\u00e9, o\u00f9 la relation avec les m\u00e9decins est strat\u00e9gique, la capacit\u00e9 \u00e0 centraliser et activer l&rsquo;information est un imp\u00e9ratif pour piloter l&rsquo;activit\u00e9 et garder une longueur d&rsquo;avance.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-unifier-un-ecosysteme-crm-fragmente\"><strong>Unifier un \u00e9cosyst\u00e8me CRM fragment\u00e9<\/strong><\/h1>\n\n\n\n<p>Historiquement, FillMed s\u2019appuyait sur plusieurs CRM et syst\u00e8mes pour couvrir les besoins de ses filiales \u00e0 l\u2019international, de son r\u00e9seau de distributeurs et de ses canaux num\u00e9riques. Un \u00e9cosyst\u00e8me fragment\u00e9, qui limitait la capacit\u00e9 \u00e0 disposer d\u2019une vision client unifi\u00e9e.<\/p>\n\n\n\n<p>Pour soutenir sa croissance et structurer son mod\u00e8le, l&rsquo;entreprise a souhait\u00e9 se doter d&rsquo;un socle unique et centralis\u00e9. \u00ab Nous nous sommes tourn\u00e9s vers Salesforce car la plateforme propose avec <a href=\"https:\/\/www.salesforce.com\/fr\/healthcare-life-sciences\/life-sciences-software\/\">Agentforce Life Sciences<\/a> une solution r\u00e9ellement pens\u00e9e pour nos besoins, et non une adaptation de mod\u00e8les standards r\u00e9pliqu\u00e9s de l&rsquo;industrie pharmaceutique, explique Gauthier M\u00e9nart. Une fois d\u00e9ploy\u00e9e, la plateforme Salesforce va nous permettre de renforcer notre strat\u00e9gie CRM et de mieux piloter le c\u0153ur de notre activit\u00e9, port\u00e9e \u00e0 plus de 70 % par notre r\u00e9seau de distributeurs \u00bb.&nbsp;<\/p>\n\n\n<div class=\"wp-block-quote-article\" style=\"\"><div class=\"wp-block-quote-social-wrapper\"><figure class=\"wp-block-quote-article-quote\">\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Nous nous sommes tourn\u00e9s vers Salesforce car la plateforme propose avec Agentforce Life Sciences une solution r\u00e9ellement pens\u00e9e pour nos besoins. \u00bb<\/p>\n<\/blockquote>\n<span class=\"citation-role\">Gauthier M\u00e9nart, Directeur des syst\u00e8mes d\u2019information, FillMed<\/span>\n<div class=\"post__social post__social--v2 post__social--blockquote\">\n\n\t\n\t<ul class=\"social-nav social-nav-v2\">\n\t\t\t\t\t<li class=\"social-nav__item\">\n\t\t\t\t<a\n\t\t\t\t\taria-label=\"Partager sur LinkedIn (S&#039;ouvre dans un nouvel onglet)\"\n\t\t\t\t\thref=\"http:\/\/www.linkedin.com\/shareArticle?mini=true&#038;url=https%3A%2F%2Fwww.salesforce.com%2Ffr%2Fblog%2Ffillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie%2F%3Futm_source%3DLinkedIn%26utm_medium%3Dorganic_social%26utm_campaign%3Dus_cbaw%26utm_content%3Dblog-ctt&#038;title=FillMed%20injecte%20les%20donn%C3%A9es%20et%20l%E2%80%99IA%20au%20c%C5%93ur%20de%20sa%20strat%C3%A9gie\"\n\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t>\n\t\t\t\t\t\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"21\" height=\"21\" fill=\"none\"><path fill=\"#032D60\" d=\"M16.625 0H4.375A4.375 4.375 0 0 0 0 4.375v12.25A4.375 4.375 0 0 0 4.375 21h12.25A4.375 4.375 0 0 0 21 16.625V4.375A4.375 4.375 0 0 0 16.625 0M7 16.625H4.375V7H7zM5.687 5.89a1.54 1.54 0 0 1-1.53-1.543c0-.852.685-1.544 1.53-1.544.846 0 1.532.692 1.532 1.544S6.534 5.89 5.687 5.89M17.5 16.625h-2.625v-4.903c0-2.947-3.5-2.724-3.5 0v4.903H8.75V7h2.625v1.544c1.222-2.262 6.125-2.43 6.125 2.167z\" \/><\/svg>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t<li class=\"social-nav__item\">\n\t\t\t\t<a\n\t\t\t\t\taria-label=\"Partager sur Twitter (S&#039;ouvre dans un nouvel onglet)\"\n\t\t\t\t\thref=\"https:\/\/x.com\/intent\/tweet?text=FillMed%20injecte%20les%20donn%C3%A9es%20et%20l%E2%80%99IA%20au%20c%C5%93ur%20de%20sa%20strat%C3%A9gie&#038;url=https%3A%2F%2Fwww.salesforce.com%2Ffr%2Fblog%2Ffillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie%2F%3Futm_source%3DTwitter%26utm_medium%3Dorganic_social%26utm_campaign%3Dus_cbaw%26utm_content%3Dblog-ctt&#038;via=salesforce\"\n\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t>\n\t\t\t\t\t\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"32\" fill=\"#032D60\" viewBox=\"0 0 32 32\"><path d=\"M17.4 14.8 23 8.3h-1.3L16.8 14 13 8.3H8.5l5.9 8.5-5.9 6.8h1.3l5.1-6 4.1 6h4.5zm-1.8 2.1-.6-.8-4.7-6.8h2l3.8 5.5.6.8 5 7.1h-2z\" \/><\/svg>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t<li class=\"social-nav__item\">\n\t\t\t\t<a\n\t\t\t\t\taria-label=\"Partager sur Facebook (S&#039;ouvre dans un nouvel onglet)\"\n\t\t\t\t\thref=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.salesforce.com%2Ffr%2Fblog%2Ffillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie%2F%3Futm_source%3DFacebook%26utm_medium%3Dorganic_social%26utm_campaign%3Dus_cbaw%26utm_content%3Dblog-ctt\"\n\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t>\n\t\t\t\t\t\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"19\" height=\"19\" fill=\"none\"><path fill=\"#032D60\" d=\"M19 9.5a9.5 9.5 0 0 0-19 0c0 4.742 3.474 8.672 8.016 9.385v-6.639H5.604V9.5h2.412V7.407c0-2.38 1.418-3.696 3.588-3.696 1.04 0 2.127.185 2.127.185v2.338h-1.198c-1.18 0-1.549.733-1.549 1.484V9.5h2.635l-.421 2.746h-2.214v6.639C15.526 18.172 19 14.242 19 9.5\" \/><\/svg>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\n\t\t<li class=\"social-nav__item\">\n\t\t\t<button\n\t\t\t\tclass=\"copy-share js-copy-link\"\n\t\t\t\taria-label=\"Copy link to clipboard\"\n\t\t\t\thref=\"#\"\n\t\t\t\tdata-clipboard-text='\"FillMed injecte les donn\u00e9es et l&rsquo;IA au c\u0153ur de sa strat\u00e9gie\" https:\/\/www.salesforce.com\/fr\/blog\/fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie\/'\n\t\t\t>\n\t\t\t\t\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"10\" fill=\"none\"><path fill=\"#032D60\" d=\"M14.586.406h-3.667V2.24h3.667a2.76 2.76 0 0 1 2.75 2.75 2.76 2.76 0 0 1-2.75 2.75h-3.667v1.833h3.667a4.585 4.585 0 0 0 4.583-4.583A4.585 4.585 0 0 0 14.586.406m-5.5 7.334H5.419a2.76 2.76 0 0 1-2.75-2.75 2.76 2.76 0 0 1 2.75-2.75h3.667V.406H5.419A4.585 4.585 0 0 0 .836 4.99a4.585 4.585 0 0 0 4.583 4.583h3.667zm-2.75-3.667h7.333v1.833H6.336z\" \/><\/svg>\n\t\t\t<\/button>\n\t\t<\/li>\n\t<\/ul>\n<\/div>\n<\/figure><\/div><\/div>\n\n\n<p>L&rsquo;ambition est de mieux outiller ces partenaires, de fluidifier les \u00e9changes et d&rsquo;am\u00e9liorer le pilotage de la performance commerciale sur l&rsquo;ensemble des march\u00e9s. Avec Agentforce Life Sciences, FillMed souhaite \u00e9galement optimiser l\u2019accompagnement des filiales de distribution en direct dans la gestion et le suivi de leur activit\u00e9. L\u2019objectif est de maximiser la valeur de chaque interaction en alignant l&rsquo;effort commercial sur le potentiel r\u00e9el et les besoins sp\u00e9cifiques des praticiens. Les \u00e9quipes commerciales b\u00e9n\u00e9ficieront ainsi de donn\u00e9es consolid\u00e9es et d\u2019insights pertinents pour prioriser leurs actions et concentrer leurs efforts sur les meilleures opportunit\u00e9s.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-l-e-academy-pivot-de-la-strategie-d-engagement-digital\"><strong>L&rsquo;e-Academy, pivot de la strat\u00e9gie d&rsquo;engagement digital<\/strong><\/h1>\n\n\n\n<p>Au-del\u00e0 des r\u00e9seaux de distribution, FillMed entend \u00e9galement tirer parti d&rsquo;Agentforce Life Sciences pour renforcer l\u2019engagement sur les canaux num\u00e9riques, au premier rang desquels l\u2019e-Academy, plateforme en ligne d\u00e9ploy\u00e9e pour proposer des contenus de formation et des communications cibl\u00e9es aux m\u00e9decins. \u00ab Notre objectif est d&rsquo;enrichir l&rsquo;offre de l&rsquo;e-Academy en y int\u00e9grant un plus fort degr\u00e9 de personnalisation, pr\u00e9cise Gauthier M\u00e9nart. Nous souhaitons notamment d\u00e9ployer un chatbot capable de r\u00e9pondre en direct aux probl\u00e9matiques sp\u00e9cifiques que rencontrent les m\u00e9decins, et de leur sugg\u00e9rer le protocole ou le produit le plus adapt\u00e9 pour chaque situation. Le tout en tenant bien \u00e9videmment compte des r\u00e8gles de conformit\u00e9 en vigueur dans les diff\u00e9rentes r\u00e9gions o\u00f9 nous op\u00e9rons \u00bb. <\/p>\n\n\n<div class=\"wp-block-quote-article\" style=\"\"><div class=\"wp-block-quote-social-wrapper\"><figure class=\"wp-block-quote-article-quote\">\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Nous souhaitons d\u00e9ployer un chatbot capable de r\u00e9pondre en direct aux probl\u00e9matiques sp\u00e9cifiques que rencontrent les m\u00e9decins, et de leur sugg\u00e9rer le protocole ou le produit le plus adapt\u00e9 pour chaque situation. \u00bb <\/p>\n<\/blockquote>\n<span class=\"citation-role\">Gauthier M\u00e9nart, Directeur des syst\u00e8mes d\u2019information, FillMed<\/span>\n<div class=\"post__social post__social--v2 post__social--blockquote\">\n\n\t\n\t<ul class=\"social-nav social-nav-v2\">\n\t\t\t\t\t<li class=\"social-nav__item\">\n\t\t\t\t<a\n\t\t\t\t\taria-label=\"Partager sur LinkedIn (S&#039;ouvre dans un nouvel onglet)\"\n\t\t\t\t\thref=\"http:\/\/www.linkedin.com\/shareArticle?mini=true&#038;url=https%3A%2F%2Fwww.salesforce.com%2Ffr%2Fblog%2Ffillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie%2F%3Futm_source%3DLinkedIn%26utm_medium%3Dorganic_social%26utm_campaign%3Dus_cbaw%26utm_content%3Dblog-ctt&#038;title=FillMed%20injecte%20les%20donn%C3%A9es%20et%20l%E2%80%99IA%20au%20c%C5%93ur%20de%20sa%20strat%C3%A9gie\"\n\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t>\n\t\t\t\t\t\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"21\" height=\"21\" fill=\"none\"><path fill=\"#032D60\" d=\"M16.625 0H4.375A4.375 4.375 0 0 0 0 4.375v12.25A4.375 4.375 0 0 0 4.375 21h12.25A4.375 4.375 0 0 0 21 16.625V4.375A4.375 4.375 0 0 0 16.625 0M7 16.625H4.375V7H7zM5.687 5.89a1.54 1.54 0 0 1-1.53-1.543c0-.852.685-1.544 1.53-1.544.846 0 1.532.692 1.532 1.544S6.534 5.89 5.687 5.89M17.5 16.625h-2.625v-4.903c0-2.947-3.5-2.724-3.5 0v4.903H8.75V7h2.625v1.544c1.222-2.262 6.125-2.43 6.125 2.167z\" \/><\/svg>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t<li class=\"social-nav__item\">\n\t\t\t\t<a\n\t\t\t\t\taria-label=\"Partager sur Twitter (S&#039;ouvre dans un nouvel onglet)\"\n\t\t\t\t\thref=\"https:\/\/x.com\/intent\/tweet?text=FillMed%20injecte%20les%20donn%C3%A9es%20et%20l%E2%80%99IA%20au%20c%C5%93ur%20de%20sa%20strat%C3%A9gie&#038;url=https%3A%2F%2Fwww.salesforce.com%2Ffr%2Fblog%2Ffillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie%2F%3Futm_source%3DTwitter%26utm_medium%3Dorganic_social%26utm_campaign%3Dus_cbaw%26utm_content%3Dblog-ctt&#038;via=salesforce\"\n\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t>\n\t\t\t\t\t\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"32\" fill=\"#032D60\" viewBox=\"0 0 32 32\"><path d=\"M17.4 14.8 23 8.3h-1.3L16.8 14 13 8.3H8.5l5.9 8.5-5.9 6.8h1.3l5.1-6 4.1 6h4.5zm-1.8 2.1-.6-.8-4.7-6.8h2l3.8 5.5.6.8 5 7.1h-2z\" \/><\/svg>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t<li class=\"social-nav__item\">\n\t\t\t\t<a\n\t\t\t\t\taria-label=\"Partager sur Facebook (S&#039;ouvre dans un nouvel onglet)\"\n\t\t\t\t\thref=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.salesforce.com%2Ffr%2Fblog%2Ffillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie%2F%3Futm_source%3DFacebook%26utm_medium%3Dorganic_social%26utm_campaign%3Dus_cbaw%26utm_content%3Dblog-ctt\"\n\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t>\n\t\t\t\t\t\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"19\" height=\"19\" fill=\"none\"><path fill=\"#032D60\" d=\"M19 9.5a9.5 9.5 0 0 0-19 0c0 4.742 3.474 8.672 8.016 9.385v-6.639H5.604V9.5h2.412V7.407c0-2.38 1.418-3.696 3.588-3.696 1.04 0 2.127.185 2.127.185v2.338h-1.198c-1.18 0-1.549.733-1.549 1.484V9.5h2.635l-.421 2.746h-2.214v6.639C15.526 18.172 19 14.242 19 9.5\" \/><\/svg>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\n\t\t<li class=\"social-nav__item\">\n\t\t\t<button\n\t\t\t\tclass=\"copy-share js-copy-link\"\n\t\t\t\taria-label=\"Copy link to clipboard\"\n\t\t\t\thref=\"#\"\n\t\t\t\tdata-clipboard-text='\"FillMed injecte les donn\u00e9es et l&rsquo;IA au c\u0153ur de sa strat\u00e9gie\" https:\/\/www.salesforce.com\/fr\/blog\/fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie\/'\n\t\t\t>\n\t\t\t\t\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"10\" fill=\"none\"><path fill=\"#032D60\" d=\"M14.586.406h-3.667V2.24h3.667a2.76 2.76 0 0 1 2.75 2.75 2.76 2.76 0 0 1-2.75 2.75h-3.667v1.833h3.667a4.585 4.585 0 0 0 4.583-4.583A4.585 4.585 0 0 0 14.586.406m-5.5 7.334H5.419a2.76 2.76 0 0 1-2.75-2.75 2.76 2.76 0 0 1 2.75-2.75h3.667V.406H5.419A4.585 4.585 0 0 0 .836 4.99a4.585 4.585 0 0 0 4.583 4.583h3.667zm-2.75-3.667h7.333v1.833H6.336z\" \/><\/svg>\n\t\t\t<\/button>\n\t\t<\/li>\n\t<\/ul>\n<\/div>\n<\/figure><\/div><\/div>\n\n\n<p>\u00c0 terme, FillMed pourrait \u00e9galement collecter les donn\u00e9es de l\u2019e-Academy (parcours de formation, contenus consult\u00e9s, interactions\u2026) pour les renvoyer vers les forces commerciales, afin d\u2019adresser les bonnes personnes au bon moment, dans le strict respect des cadres r\u00e9glementaires.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-cap-sur-l-efficience-operationnelle\"><strong>Cap sur l\u2019efficience op\u00e9rationnelle<\/strong><\/h1>\n\n\n\n<p>Au-del\u00e0 de ces premiers cas d&rsquo;usage, FillMed explore d\u00e9j\u00e0 de nouveaux leviers pour renforcer son efficacit\u00e9 op\u00e9rationnelle :&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La <strong>planification des visites terrain<\/strong> figure parmi les chantiers prioritaires. Gr\u00e2ce aux agents, un d\u00e9l\u00e9gu\u00e9 commercial pourra demain identifier en quelques instants les m\u00e9decins \u00e0 prioriser sur son secteur, en croisant plusieurs sources d\u2019informations comme l\u2019activit\u00e9 r\u00e9cente, le potentiel commercial ou les interactions sur l&rsquo;e-Academy. Les agents pourront aider le d\u00e9l\u00e9gu\u00e9 \u00e0 pr\u00e9parer efficacement chaque visite avec une synth\u00e8se contextuelle sur le praticien, et des recommandations de contenus et d\u2019argumentaire, dans le respect du cadre r\u00e9glementaire. L&rsquo;automatisation des comptes-rendus de visite est \u00e9galement \u00e0 l&rsquo;\u00e9tude, pour all\u00e9ger le quotidien des \u00e9quipes et am\u00e9liorer la qualit\u00e9 des donn\u00e9es collect\u00e9es en temps r\u00e9el.<\/li>\n\n\n\n<li>Le <strong>pilotage des grands congr\u00e8s professionnels<\/strong> est un autre axe de travail identifi\u00e9.&nbsp;\u00ab&nbsp;Des \u00e9v\u00e9nements comme l&rsquo;IMCAS, congr\u00e8s de r\u00e9f\u00e9rence dans le domaine de la science du vieillissement, repr\u00e9sentent pour nous des investissements significatifs, indique Gauthier M\u00e9nart. L&rsquo;objectif est de mieux capter les leads, de suivre les interactions avec les praticiens et de mesurer pr\u00e9cis\u00e9ment le retour sur investissement de chaque action \u00bb.&nbsp;<\/li>\n\n\n\n<li>Enfin, <strong>l\u2019int\u00e9gration de la gestion des commandes<\/strong> au sein de la plateforme permet de fluidifier l\u2019ensemble du cycle transactionnel via un \u00e9cosyst\u00e8me de donn\u00e9es unifi\u00e9. Cette visibilit\u00e9 en temps r\u00e9el sur les ventes, qu&rsquo;elles soient directes ou via des distributeurs, offre \u00e0 Fillmed un pilotage bien plus fin de sa performance commerciale mondiale. \u00bb<\/li>\n<\/ul>\n\n\n\n<p>Derri\u00e8re chacun de ces projets, un fil conducteur : transformer la donn\u00e9e en avantage comp\u00e9titif. \u00ab Nous souhaitons faire de FillMed une entreprise v\u00e9ritablement <em>data-driven<\/em>, et Salesforce va nous aider \u00e0 y parvenir \u00bb, conclut Gauthier M\u00e9nart.<\/p>\n\n\n<div class=\"wp-block-salesforce-blog-trending-articles\">\n\n\t<header class=\"wp-block-salesforce-blog-trending-articles__header\">\n\t\t<h2 class=\"wp-block-salesforce-blog-trending-articles__title\">Articles tendance<\/h2>\n\t<\/header>\n\n\t\t\t\t\t\t<div class=\"wp-block-salesforce-blog-trending-article\">\n\t\t\n\t\t\t<div class=\"wp-block-salesforce-blog-trending-article__thumbnail\">\n\t\t\t\t<span class=\"img-object-fit\"><img decoding=\"async\" src=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2024\/04\/AI-sales.png?w=300&#038;quality=80\" sizes=\"(min-width: 48em) 500px, 100vw\" srcset=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2024\/04\/AI-sales.png 1186w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2024\/04\/AI-sales.png?w=300&amp;h=166 300w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2024\/04\/AI-sales.png?w=768&amp;h=426 768w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2024\/04\/AI-sales.png?w=1024&amp;h=568 1024w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2024\/04\/AI-sales.png?w=150&amp;h=83 150w\" alt=\"Graphic of a winding path leading to a laptop with people walking and looking at various graphical icons\" loading=\"lazy\" \/><\/span>\t\t\t<\/div>\n\n\t\t\t<div class=\"wp-block-salesforce-blog-trending-article__content\">\n\t\t\t\t<h3 class=\"wp-block-salesforce-blog-trending-article__content--title\">\n\t\t\t\t\tQuels sont les avantages de l&#039;IA pour une entreprise ?\t\t\t\t<\/h3>\n\t\t\t\t<p class=\"wp-block-salesforce-blog-trending-article__content--text trending-article__content--font-size-small\">\n\t\t\t\t\t5 min de lecture\t\t\t\t<\/p>\n\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wp-block-salesforce-blog-trending-article\">\n\t\t\n\t\t\t<div class=\"wp-block-salesforce-blog-trending-article__thumbnail\">\n\t\t\t\t<span class=\"img-object-fit\"><img decoding=\"async\" src=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2024\/04\/data-cloud-whitepaper_visual_asset__1_.png?w=300&#038;quality=80\" sizes=\"(min-width: 48em) 500px, 100vw\" srcset=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2024\/04\/data-cloud-whitepaper_visual_asset__1_.png 1268w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2024\/04\/data-cloud-whitepaper_visual_asset__1_.png?w=300&amp;h=224 300w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2024\/04\/data-cloud-whitepaper_visual_asset__1_.png?w=768&amp;h=572 768w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2024\/04\/data-cloud-whitepaper_visual_asset__1_.png?w=1024&amp;h=763 1024w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2024\/04\/data-cloud-whitepaper_visual_asset__1_.png?w=150&amp;h=112 150w\" alt=\"\" loading=\"lazy\" \/><\/span>\t\t\t<\/div>\n\n\t\t\t<div class=\"wp-block-salesforce-blog-trending-article__content\">\n\t\t\t\t<h3 class=\"wp-block-salesforce-blog-trending-article__content--title\">\n\t\t\t\t\tQu&#039;est-ce que Data\u00a0Cloud\u00a0?\t\t\t\t<\/h3>\n\t\t\t\t<p class=\"wp-block-salesforce-blog-trending-article__content--text trending-article__content--font-size-small\">\n\t\t\t\t\t4 min de lecture\t\t\t\t<\/p>\n\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wp-block-salesforce-blog-trending-article\">\n\t\t\n\t\t\t<div class=\"wp-block-salesforce-blog-trending-article__thumbnail\">\n\t\t\t\t<span class=\"img-object-fit\"><img decoding=\"async\" src=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2024\/10\/retail-marketing-blog-salesforce-fr.jpeg?w=300&#038;quality=80\" sizes=\"(min-width: 48em) 500px, 100vw\" srcset=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2024\/10\/retail-marketing-blog-salesforce-fr.jpeg 1500w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2024\/10\/retail-marketing-blog-salesforce-fr.jpeg?w=300&amp;h=169 300w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2024\/10\/retail-marketing-blog-salesforce-fr.jpeg?w=768&amp;h=432 768w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2024\/10\/retail-marketing-blog-salesforce-fr.jpeg?w=1024&amp;h=576 1024w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2024\/10\/retail-marketing-blog-salesforce-fr.jpeg?w=150&amp;h=84 150w\" alt=\"Une illustration montre une cliente entour\u00e9e de pictogrammes, repr\u00e9sentant les diff\u00e9rents canaux marketing.\" loading=\"lazy\" \/><\/span>\t\t\t<\/div>\n\n\t\t\t<div class=\"wp-block-salesforce-blog-trending-article__content\">\n\t\t\t\t<h3 class=\"wp-block-salesforce-blog-trending-article__content--title\">\n\t\t\t\t\tRetail marketing : data et IA au service de l\u2019engagement client\t\t\t\t<\/h3>\n\t\t\t\t<p class=\"wp-block-salesforce-blog-trending-article__content--text trending-article__content--font-size-small\">\n\t\t\t\t\t4 min de lecture\t\t\t\t<\/p>\n\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Chez FillMed, l&rsquo;innovation ne s&rsquo;arr\u00eate pas aux portes du laboratoire. En s&rsquo;appuyant sur Salesforce pour structurer sa strat\u00e9gie CRM, l\u2019entreprise pionni\u00e8re du pro-aging place les donn\u00e9es et l\u2019IA au c\u0153ur de son mod\u00e8le&hellip;<\/p>\n","protected":false},"author":748,"featured_media":4709,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sf_justforyou_enable_alt":true,"optimizely_content_id":"69e9ddf62f0ca4d39d9263ad","post_meta_title":"","ai_synopsis":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"sf_topic":[539],"sf_content_type":[],"blog":[292],"coauthors":[27],"class_list":["post-4707","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","sf_topic-temoignages-clients","blog-agentforce"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>FillMed injecte les donn\u00e9es et l&#039;IA au c\u0153ur de sa strat\u00e9gie \u2022 Salesforce<\/title>\n<meta name=\"description\" content=\"Chez FillMed, l&#039;innovation ne s&#039;arr\u00eate pas aux portes du laboratoire. En s&#039;appuyant sur Salesforce pour structurer sa strat\u00e9gie CRM, l\u2019entreprise\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salesforce.com\/fr\/blog\/fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FillMed injecte les donn\u00e9es et l&#039;IA au c\u0153ur de sa strat\u00e9gie\" \/>\n<meta property=\"og:description\" content=\"Chez FillMed, l&#039;innovation ne s&#039;arr\u00eate pas aux portes du laboratoire. En s&#039;appuyant sur Salesforce pour structurer sa strat\u00e9gie CRM, l\u2019entreprise\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salesforce.com\/fr\/blog\/fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-23T10:00:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-24T13:22:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2026\/04\/31_SF_HeaderArticleBlog_GauthierMenart-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"844\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Salesforce\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Salesforce\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie\/\"},\"author\":[{\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/person\/image\/c4dae87da9a6134c35582db989c80f90\"}],\"headline\":\"FillMed injecte les donn\u00e9es et l&rsquo;IA au c\u0153ur de sa strat\u00e9gie\",\"datePublished\":\"2026-04-23T10:00:05+00:00\",\"dateModified\":\"2026-04-24T13:22:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie\/\"},\"wordCount\":1270,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2026\/04\/31_SF_HeaderArticleBlog_GauthierMenart-2.png\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.salesforce.com\/fr\/blog\/fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie\/\",\"url\":\"https:\/\/www.salesforce.com\/fr\/blog\/fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie\/\",\"name\":\"FillMed injecte les donn\u00e9es et l'IA au c\u0153ur de sa strat\u00e9gie \u2022 Salesforce\",\"isPartOf\":{\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2026\/04\/31_SF_HeaderArticleBlog_GauthierMenart-2.png\",\"datePublished\":\"2026-04-23T10:00:05+00:00\",\"dateModified\":\"2026-04-24T13:22:28+00:00\",\"description\":\"Chez FillMed, l'innovation ne s'arr\u00eate pas aux portes du laboratoire. En s'appuyant sur Salesforce pour structurer sa strat\u00e9gie CRM, l\u2019entreprise\",\"breadcrumb\":{\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.salesforce.com\/fr\/blog\/fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie\/#primaryimage\",\"url\":\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2026\/04\/31_SF_HeaderArticleBlog_GauthierMenart-2.png\",\"contentUrl\":\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2026\/04\/31_SF_HeaderArticleBlog_GauthierMenart-2.png\",\"width\":1500,\"height\":844},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.salesforce.com\/fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FillMed injecte les donn\u00e9es et l&rsquo;IA au c\u0153ur de sa strat\u00e9gie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/#website\",\"url\":\"https:\/\/www.salesforce.com\/fr\/blog\/\",\"name\":\"Salesforce\",\"description\":\"Le Blog du CRM, de l&#039;experience et du Cloud Computing\",\"publisher\":{\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.salesforce.com\/fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/#organization\",\"name\":\"Salesforce\",\"url\":\"https:\/\/www.salesforce.com\/fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/10\/Salesforce.webp\",\"contentUrl\":\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/10\/Salesforce.webp\",\"width\":1200,\"height\":630,\"caption\":\"Salesforce\"},\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/person\/image\/c4dae87da9a6134c35582db989c80f90\",\"name\":\"Salesforce\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g60edf16c093aaa190ff084acb1722622\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g\",\"caption\":\"Salesforce\"},\"url\":\"https:\/\/www.salesforce.com\/fr\/blog\/author\/salesforce\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"FillMed injecte les donn\u00e9es et l'IA au c\u0153ur de sa strat\u00e9gie \u2022 Salesforce","description":"Chez FillMed, l'innovation ne s'arr\u00eate pas aux portes du laboratoire. En s'appuyant sur Salesforce pour structurer sa strat\u00e9gie CRM, l\u2019entreprise","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salesforce.com\/fr\/blog\/fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie\/","og_locale":"fr_FR","og_type":"article","og_title":"FillMed injecte les donn\u00e9es et l'IA au c\u0153ur de sa strat\u00e9gie","og_description":"Chez FillMed, l'innovation ne s'arr\u00eate pas aux portes du laboratoire. En s'appuyant sur Salesforce pour structurer sa strat\u00e9gie CRM, l\u2019entreprise","og_url":"https:\/\/www.salesforce.com\/fr\/blog\/fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie\/","og_site_name":"Salesforce","article_published_time":"2026-04-23T10:00:05+00:00","article_modified_time":"2026-04-24T13:22:28+00:00","og_image":[{"width":1500,"height":844,"url":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2026\/04\/31_SF_HeaderArticleBlog_GauthierMenart-2.png","type":"image\/png"}],"author":"Salesforce","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"","Dur\u00e9e de lecture estim\u00e9e":"6 minutes","Written by":"Salesforce"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salesforce.com\/fr\/blog\/fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie\/#article","isPartOf":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie\/"},"author":[{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/person\/image\/c4dae87da9a6134c35582db989c80f90"}],"headline":"FillMed injecte les donn\u00e9es et l&rsquo;IA au c\u0153ur de sa strat\u00e9gie","datePublished":"2026-04-23T10:00:05+00:00","dateModified":"2026-04-24T13:22:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie\/"},"wordCount":1270,"commentCount":0,"publisher":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/#organization"},"image":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2026\/04\/31_SF_HeaderArticleBlog_GauthierMenart-2.png","inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.salesforce.com\/fr\/blog\/fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.salesforce.com\/fr\/blog\/fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie\/","url":"https:\/\/www.salesforce.com\/fr\/blog\/fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie\/","name":"FillMed injecte les donn\u00e9es et l'IA au c\u0153ur de sa strat\u00e9gie \u2022 Salesforce","isPartOf":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie\/#primaryimage"},"image":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2026\/04\/31_SF_HeaderArticleBlog_GauthierMenart-2.png","datePublished":"2026-04-23T10:00:05+00:00","dateModified":"2026-04-24T13:22:28+00:00","description":"Chez FillMed, l'innovation ne s'arr\u00eate pas aux portes du laboratoire. En s'appuyant sur Salesforce pour structurer sa strat\u00e9gie CRM, l\u2019entreprise","breadcrumb":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salesforce.com\/fr\/blog\/fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.salesforce.com\/fr\/blog\/fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie\/#primaryimage","url":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2026\/04\/31_SF_HeaderArticleBlog_GauthierMenart-2.png","contentUrl":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2026\/04\/31_SF_HeaderArticleBlog_GauthierMenart-2.png","width":1500,"height":844},{"@type":"BreadcrumbList","@id":"https:\/\/www.salesforce.com\/fr\/blog\/fillmed-injecte-les-donnees-et-lia-au-coeur-de-sa-strategie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salesforce.com\/fr\/blog\/"},{"@type":"ListItem","position":2,"name":"FillMed injecte les donn\u00e9es et l&rsquo;IA au c\u0153ur de sa strat\u00e9gie"}]},{"@type":"WebSite","@id":"https:\/\/www.salesforce.com\/fr\/blog\/#website","url":"https:\/\/www.salesforce.com\/fr\/blog\/","name":"Salesforce","description":"Le Blog du CRM, de l&#039;experience et du Cloud Computing","publisher":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salesforce.com\/fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.salesforce.com\/fr\/blog\/#organization","name":"Salesforce","url":"https:\/\/www.salesforce.com\/fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/10\/Salesforce.webp","contentUrl":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/10\/Salesforce.webp","width":1200,"height":630,"caption":"Salesforce"},"image":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/person\/image\/c4dae87da9a6134c35582db989c80f90","name":"Salesforce","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g60edf16c093aaa190ff084acb1722622","url":"https:\/\/secure.gravatar.com\/avatar\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g","caption":"Salesforce"},"url":"https:\/\/www.salesforce.com\/fr\/blog\/author\/salesforce\/"}]}},"jetpack_featured_media_url":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2026\/04\/31_SF_HeaderArticleBlog_GauthierMenart-2.png","jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Salesforce","distributor_original_site_url":"https:\/\/www.salesforce.com\/fr\/blog","push-errors":false,"_links":{"self":[{"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/4707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/users\/748"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/comments?post=4707"}],"version-history":[{"count":7,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/4707\/revisions"}],"predecessor-version":[{"id":4715,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/4707\/revisions\/4715"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/media\/4709"}],"wp:attachment":[{"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/media?parent=4707"}],"wp:term":[{"taxonomy":"sf_topic","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/sf_topic?post=4707"},{"taxonomy":"sf_content_type","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/sf_content_type?post=4707"},{"taxonomy":"blog","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/blog?post=4707"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/coauthors?post=4707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}