{"id":513,"date":"2017-04-25T18:08:00","date_gmt":"2023-09-07T18:08:14","guid":{"rendered":"https:\/\/www.salesforce.com\/?p=513"},"modified":"2023-11-14T12:27:26","modified_gmt":"2023-11-14T12:27:26","slug":"clients-connectes-ce-qu-ils-attendent-des-marques","status":"publish","type":"post","link":"https:\/\/www.salesforce.com\/fr\/blog\/clients-connectes-ce-qu-ils-attendent-des-marques\/","title":{"rendered":"Clients connect\u00e9s : ce qu&rsquo;ils attendent aujourd&rsquo;hui des marques"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><b>Pas moins de 7 000 clients \u00e0 travers le monde ont particip\u00e9 \u00e0 l\u2019\u00e9tude <i><a href=\"https:\/\/www.salesforce.com\/form\/pdf\/state-of-the-connected-customer.jsp?nc=7010M000002MSqYQAW\" target=\"_blank\" adhocenable=\"false\" rel=\"noopener\">State of the Connected Customer<\/a><\/i>. Une mine d\u2019enseignements aux r\u00e9sultats surprenants \u00e0 plus d\u2019un titre sur leurs attentes en mati\u00e8re d\u2019exp\u00e9rience, de <a adhocenable=\"false\" href=\"https:\/\/www.salesforce.com\/fr\/blog\/2016\/05\/comment-mesurer-la-satisfaction-client.html\" target=\"_blank\" rel=\"noopener\">satisfaction<\/a>, de fid\u00e9lisation et de parcours client.<\/b> <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-un-contact-en-temps-reel-avec-les-marques\"><b>Un contact en temps r\u00e9el avec les marques<\/b><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Aujourd&rsquo;hui, <a adhocenable=\"false\" href=\"https:\/\/www.salesforce.com\/fr\/form\/pdf\/data-au-service-du-client.jsp?nc=7010M000000mUHJ\" target=\"_blank\" rel=\"noopener\">les clients sont devenus rois<\/a>. L\u2019outil de cette conqu\u00eate ? Le mobile. Pour Simon Mulcahy, Chief marketing officer chez Salesforce, \u00ab notre culture est aujourd\u2019hui fa\u00e7onn\u00e9e par cette connexion en continu, avec un acc\u00e8s mobile, \u00e0 tout ce que l\u2019on peut imaginer, au moment o\u00f9 l\u2019on en a besoin. R\u00e9sultat : les clients et les consommateurs [&#8230;] b\u00e9n\u00e9ficient de plus d&rsquo;informations et de choix que jamais, ce qui suppose un plus grand effort pour les marques qui souhaitent conserver leur fid\u00e9lit\u00e9 \u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les chiffres sont sans appel : 60 % des clients comparent les prix sur Internet avant d\u2019acheter et 56 % d\u2019entre eux comparent les produits similaires avant un achat. Si le client est connect\u00e9 avant l\u2019achat, il l\u2019est presque tout autant pendant son shopping et jusque dans la boutique : le mobile est devenu un canal essentiel pour faire son choix. 50 % des consommateurs d\u00e9clarent qu\u2019ils changeraient de marque, si celle-ci n\u2019offrait pas une exp\u00e9rience mobile simple d\u2019usage. <\/p>\n\n\n\n<div class=\"layout-five wp-block-salesforce-blog-offer\">\n\t<div class=\"wp-block-offer__wrapper\">\n\n\t\t<div class=\"wp-block-offer__content\">\n\t\t\t<h2 class=\"wp-block-offer__title\">Focus sur le client connect\u00e9<\/h2>\n\t\t\t\t\t\t\t<p class=\"wp-block-offer__description\">Quelles sont les attentes des clients ? Comment les entreprises peuvent-elles mettre en \u0153uvre l\u2019IA de confiance ?<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t<a class=\"wp-block-button__link\" target=\"_self\" href=\"https:\/\/www.salesforce.com\/fr\/form\/pdf\/client-connecte\/?nc=7013y000000vkjhAAA\">Je d\u00e9couvre les attentes des clients<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"wp-block-offer__media\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"864\" src=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2022\/06\/socc-form.png\" class=\"attachment-full size-full\" alt=\"Focus sur le client connect\u00e9\" srcset=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2022\/06\/socc-form.png 1536w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2022\/06\/socc-form.png?w=300&amp;h=169 300w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2022\/06\/socc-form.png?w=768&amp;h=432 768w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2022\/06\/socc-form.png?w=1024&amp;h=576 1024w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2022\/06\/socc-form.png?w=150&amp;h=84 150w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" \/>\t\t<\/div>\n\t<\/div>\n\n\t\n\t\t\t<!-- Standard Illustration -->\n\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__illustration\" src=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-illustration-layout-five.png\" alt=\"\">\n\n\t\t<!-- Small Accent Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__accent\" src=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-accent-layout-five.png\" alt=\"\">\n\t\t\n\t\t<!-- Left Side Illustration -->\n\t\t\n\t\t<!-- Cloud Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__cloud\" src=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-cloud-layout-five.png\" alt=\"\">\n\t\t\n\t<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Autre ph\u00e9nom\u00e8ne int\u00e9ressant : les consommateurs communiquent non seulement entre eux mais \u00e9galement avec les marques pour demander un conseil, un compl\u00e9ment d\u2019information ou encore faire part de leur niveau de satisfaction. Les marques ont donc tout int\u00e9r\u00eat \u00e0 produire de l\u2019information en acc\u00e8s libre sur <a adhocenable=\"false\" href=\"https:\/\/www.salesforce.com\/fr\/blog\/2015\/10\/qu_est-ce-que-le-service-client-omnicanal---.html\" target=\"_blank\" rel=\"noopener\">tous les canaux<\/a> mis \u00e0 sa disposition : blog, site internet, r\u00e9seaux sociaux, t\u00e9l\u00e9phone, messages instantan\u00e9s\u2026 L\u2019\u00e9tude fait appara\u00eetre que 64 % des clients veulent un contact en temps r\u00e9el avec la marque et 80 % des consommateurs attendent une r\u00e9ponse dans les 6 heures lorsqu&rsquo;ils posent une question sur les r\u00e9seaux sociaux. Dans ces conditions, les d\u00e9sirs des clients deviennent des ordres pour les marques. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><i>L&rsquo;exemple \u00e0 suivre ? <a href=\"https:\/\/www.salesforce.com\/fr\/customer-success-stories\/bouygues-telecom\/\" target=\"_blank\" rel=\"noreferrer noopener\">Bouygues Telecom<\/a>, qui a d\u00e9ploy\u00e9 une strat\u00e9gie omnicanale, permet au client d\u2019acc\u00e9der \u00e0 son dossier, mais aussi \u00e0 une base de connaissance via un portail web\u2026<\/i> <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-une-experience-client-privilegiee\"><b>Une exp\u00e9rience client privil\u00e9gi\u00e9e<\/b><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Selon l\u2019\u00e9tude, \u00ab 73 % des clients annoncent qu\u2019ils changeraient de marque si la qualit\u00e9 de service devenait insatisfaisante \u00bb. Autrement dit : ils attendent un service d\u2019exception ce qui se traduit tr\u00e8s concr\u00e8tement par la personnalisation de l\u2019accueil \u00e0 chaque visite en boutique comme sur internet. Et 66 % des clients sont pr\u00eats \u00e0 changer de marque s\u2019ils se sentent trait\u00e9s comme un num\u00e9ro ! <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les clients connect\u00e9s attendent \u00e9galement des marques une exp\u00e9rience client universelle, d\u2019une qualit\u00e9 aussi soutenue qu\u2019\u00e9gale, \u00e0 tout moment, quel que soit le canal. Pour les marques, il s\u2019agit d\u2019un tour de force possible si et uniquement si l\u2019historique de la relation client est bien partag\u00e9e entre tous le services d\u2019une entreprise. Et ce, en temps r\u00e9el. D\u2019o\u00f9 la n\u00e9cessit\u00e9 de centraliser ces informations dans un <a adhocenable=\"false\" href=\"https:\/\/www.salesforce.com\/fr\/blog\/2016\/02\/une-start-up-a-t-elle-besoin-dun-crm--.html\" target=\"_blank\" rel=\"noopener\">CRM<\/a>, accessible via tous les canaux (par les vendeurs, les t\u00e9l\u00e9conseillers\u2026). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les prises de paroles des marques doivent enfin faire transpara\u00eetre leur connaissance fine de leur client\u00e8le. La conversation doit \u00eatre sinc\u00e8rement et r\u00e9ellement personnalis\u00e9e comme on l\u2019attendrait de n\u2019importe quel interlocuteur de qualit\u00e9.<b> <\/b> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><i>L&rsquo;exemple \u00e0 suivre ? <a href=\"https:\/\/www.salesforce.com\/fr\/customer-success-stories\/alinea\/\" target=\"_blank\" rel=\"noreferrer noopener\">Alin\u00e9a<\/a> qui a r\u00e9concili\u00e9 les canaux de vente en ligne et en boutique, dot\u00e9 ses conseillers en boutique d\u2019outils nouveaux, fait tomber les silos pour un parcours cross-canal en toute fluidit\u00e9.<\/i><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><b><a adhocenable=\"false\" href=\"https:\/\/www.salesforce.com\/fr\/blog\/2017\/04\/9-statistiques-a-retenir-pour-ameliorer-l-experience-client.html\" target=\"_blank\" rel=\"noopener\">Les 9 statistiques \u00e0 retenir pour am\u00e9liorer l&rsquo;exp\u00e9rience client &gt;<\/a><\/b><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-une-forte-capacite-d-anticipation\"><b>Une forte capacit\u00e9 d&rsquo;anticipation<\/b><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Conna\u00eetre les v\u00e9ritables attentes du client est une t\u00e2che de plus en plus complexe : les tendances \u00e9mergent et \u00e9voluent toujours plus rapidement, port\u00e9es par l\u2019essor des nouvelles technologies. Le \u00ab buzz \u00bb peut cr\u00e9er l\u2019engouement autour d\u2019un produit en quelques jours, \u00e0 la suite par exemple de la publication d\u2019une simple vid\u00e9o (que celle-ci \u00e9mane de la marque ou du client). Ainsi, 62 % des consommateurs affirment acheter des produits dont ils ne connaissaient pas m\u00eame l\u2019existence 5 ans plus t\u00f4t !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les marques doivent elles aussi se lancer dans cette course \u00e0 l\u2019innovation en anticipant les r\u00e9volutions \u00e0 venir. Pour d\u00e9tecter au plus t\u00f4t les tendances (et donc la demande), l\u2019entreprise doit d\u00e9ployer des technologies d\u2019analyse pr\u00e9dictive qui lui permettront par exemple d\u2019adapter ses stocks aux ventes, avec des pr\u00e9visions au plus juste\u2026 \u00c0 terme, la marque devra m\u00eame savoir anticiper les tendances gr\u00e2ce \u00e0 l\u2019analyse pr\u00e9dictive et \u00e0 <a adhocenable=\"false\" href=\"https:\/\/www.salesforce.com\/fr\/blog\/2016\/09\/salesforce-einstein-.html\" target=\"_blank\" rel=\"noopener\">l\u2019intelligence artificielle<\/a>. Ce faisant, elle pr\u00e9parera ses outils de production pour \u00e9viter les ruptures d\u2019approvisionnement sous la d\u00e9ferlante des commandes. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Internet a amplifi\u00e9 la \u00ab spontan\u00e9it\u00e9 \u00bb des jeunes consommateurs qui font plus souvent des achats d\u2019impulsion que des achats programm\u00e9s, et ce dans tous les domaines. Par exemple, pour inciter les jeunes \u00e0 red\u00e9couvrir les joies du train aux meilleurs tarifs, Voyages SNCF a imagin\u00e9 un concept totalement innovant : <a adhocenable=\"false\" href=\"https:\/\/www.salesforce.com\/fr\/blog\/2017\/04\/tgvmax.html\" target=\"_blank\" rel=\"noopener\">un abonnement illimit\u00e9 avec TGVMax<\/a>. <b> <\/b> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><i>L\u2019exemple \u00e0 suivre ? <a adhocenable=\"false\" href=\"\/fr\/customer-success-stories\/alinea\/\" target=\"_blank\" rel=\"noopener\">ALDO<\/a>, qui d\u00e9veloppe une connaissance approfondie de ses clients pour mieux comprendre leurs pr\u00e9f\u00e9rences, qui reste \u00e0 l\u2019\u00e9coute des tendances pour partager avec ses clients des informations sur les styles, qui optimise ses stocks entre les diff\u00e9rents points de vente\u2026<\/i> <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-des-produits-services-et-parcours-clients-personnalises\"><b>Des produits, services et parcours clients personnalis\u00e9s<\/b><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">58 % des consommateurs jugent absolument essentiel ou tr\u00e8s important que l\u2019entreprise propose une exp\u00e9rience personnalis\u00e9e. Pire : 52 % d\u2019entre eux affirment qu\u2019ils sont pr\u00eats \u00e0 changer de marque si des efforts ne sont pas faits pour personnaliser leur communication avec eux. Ils souhaitent ainsi une exp\u00e9rience personnalis\u00e9e, avec des services sur mesure, modulables et adapt\u00e9s \u00e0 leurs besoins. Les technologies comme le <i><a adhocenable=\"false\" href=\"https:\/\/www.salesforce.com\/fr\/blog\/2016\/04\/machine-learning-marketing-digital.html\" target=\"_blank\" rel=\"noopener\">machine learning<\/a><\/i> et le <i>natural language processing<\/i> permettent d\u2019automatiser cette personnalisation des \u00e9changes. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette personnalisation concerne enfin les produits eux-m\u00eames ainsi que les services qui lui sont associ\u00e9s. Dans un futur proche, il est probable que les entreprises s\u2019\u00e9quipent sans doute de syst\u00e8mes de production enti\u00e8rement \u00e0 la demande gr\u00e2ce \u00e0 un pilotage automatis\u00e9 de la cha\u00eene de production pour d\u00e9livrer leurs commandes aux clients.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> <b> <\/b> <i>L\u2019exemple \u00e0 suivre ? <a href=\"https:\/\/www.salesforce.com\/fr\/customer-success-stories\/generali-concierge-services\/\" target=\"_blank\" rel=\"noreferrer noopener\">Generali Concierge Services<\/a>, qui a d\u00e9velopp\u00e9 une connaissance 360\u00b0 de ses clients \u2013 sa situation, l\u2019historique de ses demandes, ses habitudes, ses go\u00fbts\u2026 &#8211; pour anticiper leurs demandes, et faire des propositions toujours plus personnalis\u00e9es.<\/i><\/p>\n\n\n\n<div class=\"layout-five wp-block-salesforce-blog-offer\">\n\t<div class=\"wp-block-offer__wrapper\">\n\n\t\t<div class=\"wp-block-offer__content\">\n\t\t\t<h2 class=\"wp-block-offer__title\">Focus sur le client connect\u00e9<\/h2>\n\t\t\t\t\t\t\t<p class=\"wp-block-offer__description\">Quelles sont les attentes des clients ? Comment les entreprises peuvent-elles mettre en \u0153uvre l\u2019IA de confiance ?<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t<a class=\"wp-block-button__link\" target=\"_self\" href=\"https:\/\/www.salesforce.com\/fr\/form\/pdf\/client-connecte\/?nc=7013y000000vkjhAAA\">Je d\u00e9couvre les attentes des clients<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"wp-block-offer__media\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"864\" src=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2022\/06\/socc-form.png\" class=\"attachment-full size-full\" alt=\"Focus sur le client connect\u00e9\" srcset=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2022\/06\/socc-form.png 1536w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2022\/06\/socc-form.png?w=300&amp;h=169 300w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2022\/06\/socc-form.png?w=768&amp;h=432 768w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2022\/06\/socc-form.png?w=1024&amp;h=576 1024w, https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2022\/06\/socc-form.png?w=150&amp;h=84 150w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" \/>\t\t<\/div>\n\t<\/div>\n\n\t\n\t\t\t<!-- Standard Illustration -->\n\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__illustration\" src=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-illustration-layout-five.png\" alt=\"\">\n\n\t\t<!-- Small Accent Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__accent\" src=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-accent-layout-five.png\" alt=\"\">\n\t\t\n\t\t<!-- Left Side Illustration -->\n\t\t\n\t\t<!-- Cloud Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__cloud\" src=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-cloud-layout-five.png\" alt=\"\">\n\t\t\n\t<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"> <span id=\"authorRoot\" path=\"\/content\/blogs\/fr\/fr\/authors\/\"><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pas moins de 7 000 clients \u00e0 travers le monde ont particip\u00e9 \u00e0 l\u2019\u00e9tude State of the Connected Customer. Une mine d\u2019enseignements aux r\u00e9sultats surprenants \u00e0 plus d\u2019un titre sur leurs attentes en mati\u00e8re d\u2019exp\u00e9rience, de satisfaction, de fid\u00e9lisation et de parcours client.<\/p>\n","protected":false},"author":1,"featured_media":515,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sf_justforyou_enable_alt":true,"optimizely_content_id":"5d6737cde17e408e9a11445f2c0e666d","post_meta_title":"","ai_synopsis":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"sf_topic":[12,4,6],"sf_content_type":[],"blog":[363,358,357],"coauthors":[27],"class_list":["post-513","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","sf_topic-service","sf_topic-sales","sf_topic-marketing","blog-service","blog-sales","blog-marketing"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Clients connect\u00e9s : ce qu&#039;ils attendent aujourd&#039;hui des marques \u2022 Salesforce<\/title>\n<meta name=\"description\" content=\"Pas moins de 7 000 clients \u00e0 travers le monde ont particip\u00e9 \u00e0 l\u2019\u00e9tude State of the Connected Customer. Une mine d\u2019enseignements aux r\u00e9sultats surprenants \u00e0 plus d\u2019un titre sur leurs attentes en mati\u00e8re d\u2019exp\u00e9rience, de satisfaction, de fid\u00e9lisation et de parcours client.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salesforce.com\/fr\/blog\/clients-connectes-ce-qu-ils-attendent-des-marques\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Clients connect\u00e9s : ce qu&#039;ils attendent aujourd&#039;hui des marques\" \/>\n<meta property=\"og:description\" content=\"Pas moins de 7 000 clients \u00e0 travers le monde ont particip\u00e9 \u00e0 l\u2019\u00e9tude State of the Connected Customer. Une mine d\u2019enseignements aux r\u00e9sultats surprenants \u00e0 plus d\u2019un titre sur leurs attentes en mati\u00e8re d\u2019exp\u00e9rience, de satisfaction, de fid\u00e9lisation et de parcours client.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salesforce.com\/fr\/blog\/clients-connectes-ce-qu-ils-attendent-des-marques\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-07T18:08:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-14T12:27:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/Clients20connectes20-20ce20qu27ils20attendent20des20marques20aujourd27hui.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1389\" \/>\n\t<meta property=\"og:image:height\" content=\"1039\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Salesforce\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Salesforce\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/clients-connectes-ce-qu-ils-attendent-des-marques\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/clients-connectes-ce-qu-ils-attendent-des-marques\\\/\"},\"author\":[{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/#\\\/schema\\\/person\\\/image\\\/c4dae87da9a6134c35582db989c80f90\"}],\"headline\":\"Clients connect\u00e9s : ce qu&rsquo;ils attendent aujourd&rsquo;hui des marques\",\"datePublished\":\"2023-09-07T18:08:14+00:00\",\"dateModified\":\"2023-11-14T12:27:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/clients-connectes-ce-qu-ils-attendent-des-marques\\\/\"},\"wordCount\":1126,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/clients-connectes-ce-qu-ils-attendent-des-marques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2023\\\/09\\\/Clients20connectes20-20ce20qu27ils20attendent20des20marques20aujourd27hui.png\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/clients-connectes-ce-qu-ils-attendent-des-marques\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/clients-connectes-ce-qu-ils-attendent-des-marques\\\/\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/clients-connectes-ce-qu-ils-attendent-des-marques\\\/\",\"name\":\"Clients connect\u00e9s : ce qu'ils attendent aujourd'hui des marques \u2022 Salesforce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/clients-connectes-ce-qu-ils-attendent-des-marques\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/clients-connectes-ce-qu-ils-attendent-des-marques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2023\\\/09\\\/Clients20connectes20-20ce20qu27ils20attendent20des20marques20aujourd27hui.png\",\"datePublished\":\"2023-09-07T18:08:14+00:00\",\"dateModified\":\"2023-11-14T12:27:26+00:00\",\"description\":\"Pas moins de 7 000 clients \u00e0 travers le monde ont particip\u00e9 \u00e0 l\u2019\u00e9tude State of the Connected Customer. Une mine d\u2019enseignements aux r\u00e9sultats surprenants \u00e0 plus d\u2019un titre sur leurs attentes en mati\u00e8re d\u2019exp\u00e9rience, de satisfaction, de fid\u00e9lisation et de parcours client.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/clients-connectes-ce-qu-ils-attendent-des-marques\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/clients-connectes-ce-qu-ils-attendent-des-marques\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/clients-connectes-ce-qu-ils-attendent-des-marques\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2023\\\/09\\\/Clients20connectes20-20ce20qu27ils20attendent20des20marques20aujourd27hui.png\",\"contentUrl\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2023\\\/09\\\/Clients20connectes20-20ce20qu27ils20attendent20des20marques20aujourd27hui.png\",\"width\":1389,\"height\":1039,\"caption\":\"Clients connect\u00e9s ce qu'ils attendent des marques\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/clients-connectes-ce-qu-ils-attendent-des-marques\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Clients connect\u00e9s : ce qu&rsquo;ils attendent aujourd&rsquo;hui des marques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/\",\"name\":\"Salesforce\",\"description\":\"Le Blog du CRM, de l&#039;experience et du Cloud Computing\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/#organization\",\"name\":\"Salesforce\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2023\\\/10\\\/Salesforce.webp\",\"contentUrl\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2023\\\/10\\\/Salesforce.webp\",\"width\":1200,\"height\":630,\"caption\":\"Salesforce\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/#\\\/schema\\\/person\\\/image\\\/c4dae87da9a6134c35582db989c80f90\",\"name\":\"Salesforce\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g60edf16c093aaa190ff084acb1722622\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g\",\"caption\":\"Salesforce\"},\"url\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/blog\\\/author\\\/salesforce\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Clients connect\u00e9s : ce qu'ils attendent aujourd'hui des marques \u2022 Salesforce","description":"Pas moins de 7 000 clients \u00e0 travers le monde ont particip\u00e9 \u00e0 l\u2019\u00e9tude State of the Connected Customer. Une mine d\u2019enseignements aux r\u00e9sultats surprenants \u00e0 plus d\u2019un titre sur leurs attentes en mati\u00e8re d\u2019exp\u00e9rience, de satisfaction, de fid\u00e9lisation et de parcours client.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salesforce.com\/fr\/blog\/clients-connectes-ce-qu-ils-attendent-des-marques\/","og_locale":"fr_FR","og_type":"article","og_title":"Clients connect\u00e9s : ce qu'ils attendent aujourd'hui des marques","og_description":"Pas moins de 7 000 clients \u00e0 travers le monde ont particip\u00e9 \u00e0 l\u2019\u00e9tude State of the Connected Customer. Une mine d\u2019enseignements aux r\u00e9sultats surprenants \u00e0 plus d\u2019un titre sur leurs attentes en mati\u00e8re d\u2019exp\u00e9rience, de satisfaction, de fid\u00e9lisation et de parcours client.","og_url":"https:\/\/www.salesforce.com\/fr\/blog\/clients-connectes-ce-qu-ils-attendent-des-marques\/","og_site_name":"Salesforce","article_published_time":"2023-09-07T18:08:14+00:00","article_modified_time":"2023-11-14T12:27:26+00:00","og_image":[{"width":1389,"height":1039,"url":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/Clients20connectes20-20ce20qu27ils20attendent20des20marques20aujourd27hui.png","type":"image\/png"}],"author":"Salesforce","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"","Dur\u00e9e de lecture estim\u00e9e":"6 minutes","Written by":"Salesforce"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salesforce.com\/fr\/blog\/clients-connectes-ce-qu-ils-attendent-des-marques\/#article","isPartOf":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/clients-connectes-ce-qu-ils-attendent-des-marques\/"},"author":[{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/person\/image\/c4dae87da9a6134c35582db989c80f90"}],"headline":"Clients connect\u00e9s : ce qu&rsquo;ils attendent aujourd&rsquo;hui des marques","datePublished":"2023-09-07T18:08:14+00:00","dateModified":"2023-11-14T12:27:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/clients-connectes-ce-qu-ils-attendent-des-marques\/"},"wordCount":1126,"commentCount":0,"publisher":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/#organization"},"image":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/clients-connectes-ce-qu-ils-attendent-des-marques\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/Clients20connectes20-20ce20qu27ils20attendent20des20marques20aujourd27hui.png","inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.salesforce.com\/fr\/blog\/clients-connectes-ce-qu-ils-attendent-des-marques\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.salesforce.com\/fr\/blog\/clients-connectes-ce-qu-ils-attendent-des-marques\/","url":"https:\/\/www.salesforce.com\/fr\/blog\/clients-connectes-ce-qu-ils-attendent-des-marques\/","name":"Clients connect\u00e9s : ce qu'ils attendent aujourd'hui des marques \u2022 Salesforce","isPartOf":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/clients-connectes-ce-qu-ils-attendent-des-marques\/#primaryimage"},"image":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/clients-connectes-ce-qu-ils-attendent-des-marques\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/Clients20connectes20-20ce20qu27ils20attendent20des20marques20aujourd27hui.png","datePublished":"2023-09-07T18:08:14+00:00","dateModified":"2023-11-14T12:27:26+00:00","description":"Pas moins de 7 000 clients \u00e0 travers le monde ont particip\u00e9 \u00e0 l\u2019\u00e9tude State of the Connected Customer. Une mine d\u2019enseignements aux r\u00e9sultats surprenants \u00e0 plus d\u2019un titre sur leurs attentes en mati\u00e8re d\u2019exp\u00e9rience, de satisfaction, de fid\u00e9lisation et de parcours client.","breadcrumb":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/clients-connectes-ce-qu-ils-attendent-des-marques\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salesforce.com\/fr\/blog\/clients-connectes-ce-qu-ils-attendent-des-marques\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.salesforce.com\/fr\/blog\/clients-connectes-ce-qu-ils-attendent-des-marques\/#primaryimage","url":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/Clients20connectes20-20ce20qu27ils20attendent20des20marques20aujourd27hui.png","contentUrl":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/Clients20connectes20-20ce20qu27ils20attendent20des20marques20aujourd27hui.png","width":1389,"height":1039,"caption":"Clients connect\u00e9s ce qu'ils attendent des marques"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salesforce.com\/fr\/blog\/clients-connectes-ce-qu-ils-attendent-des-marques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salesforce.com\/fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Clients connect\u00e9s : ce qu&rsquo;ils attendent aujourd&rsquo;hui des marques"}]},{"@type":"WebSite","@id":"https:\/\/www.salesforce.com\/fr\/blog\/#website","url":"https:\/\/www.salesforce.com\/fr\/blog\/","name":"Salesforce","description":"Le Blog du CRM, de l&#039;experience et du Cloud Computing","publisher":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salesforce.com\/fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.salesforce.com\/fr\/blog\/#organization","name":"Salesforce","url":"https:\/\/www.salesforce.com\/fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/10\/Salesforce.webp","contentUrl":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/10\/Salesforce.webp","width":1200,"height":630,"caption":"Salesforce"},"image":{"@id":"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.salesforce.com\/fr\/blog\/#\/schema\/person\/image\/c4dae87da9a6134c35582db989c80f90","name":"Salesforce","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g60edf16c093aaa190ff084acb1722622","url":"https:\/\/secure.gravatar.com\/avatar\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7b22a1347a70a190b5cdd1eadab50e55b6123719ad0c5571e2ab30226dcbe85d?s=96&d=mm&r=g","caption":"Salesforce"},"url":"https:\/\/www.salesforce.com\/fr\/blog\/author\/salesforce\/"}]}},"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Salesforce","distributor_original_site_url":"https:\/\/www.salesforce.com\/fr\/blog","push-errors":false,"jetpack_featured_media_url":"https:\/\/www.salesforce.com\/fr\/blog\/wp-content\/uploads\/sites\/15\/2023\/09\/Clients20connectes20-20ce20qu27ils20attendent20des20marques20aujourd27hui.png","_links":{"self":[{"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/comments?post=513"}],"version-history":[{"count":6,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/513\/revisions"}],"predecessor-version":[{"id":2592,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/posts\/513\/revisions\/2592"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/media\/515"}],"wp:attachment":[{"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/media?parent=513"}],"wp:term":[{"taxonomy":"sf_topic","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/sf_topic?post=513"},{"taxonomy":"sf_content_type","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/sf_content_type?post=513"},{"taxonomy":"blog","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/blog?post=513"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/blog\/wp-json\/wp\/v2\/coauthors?post=513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}