{"id":2170,"date":"2025-07-28T18:23:27","date_gmt":"2025-07-28T16:23:27","guid":{"rendered":"https:\/\/www.salesforce.com\/?post_type=sf_press_release&#038;p=2170"},"modified":"2025-07-28T18:23:28","modified_gmt":"2025-07-28T16:23:28","slug":"agentforce-for-revenue-cloud","status":"publish","type":"sf_press_release","link":"https:\/\/www.salesforce.com\/fr\/news\/press-releases\/2025\/07\/28\/agentforce-for-revenue-cloud\/","title":{"rendered":"Avec Agentforce for Revenue Cloud, Salesforce d\u00e9cline ses agents IA au service de la performance commerciale"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>D\u00e9sormais, les entreprises peuvent transformer leur cycle de vente gr\u00e2ce \u00e0 l&rsquo;intelligence artificielle, de la cr\u00e9ation instantan\u00e9e de devis complexes \u00e0 une facturation simplifi\u00e9e, lib\u00e9rant ainsi un temps pr\u00e9cieux pour leurs \u00e9quipes commerciales.<\/em><\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Paris, le 28 juillet 2025<\/strong> \u2013 Salesforce, leader mondial du CRM, annonce aujourd&rsquo;hui le lancement strat\u00e9gique d\u2019Agentforce for Revenue, une innovation majeure con\u00e7ue pour r\u00e9volutionner la gestion des revenus des entreprises. Cette solution in\u00e9dite int\u00e8gre la puissance des <a href=\"https:\/\/www.salesforce.com\/agentforce\/digital-labor\/\"><strong>agents IA<\/strong><\/a> \u00e0 <a href=\"https:\/\/www.salesforce.com\/sales\/revenue-lifecycle-management\/\"><strong>Revenue Cloud<\/strong><\/a>, la plateforme de gestion du cycle de vente de Salesforce, promettant une automatisation intelligente de bout en bout, de la g\u00e9n\u00e9ration de devis \u00e0 la facturation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans un contexte o\u00f9 la complexit\u00e9 des offres et la multiplication des mod\u00e8les de \u2018pricing\u2019 (abonnement, usage, services) p\u00e8sent sur la productivit\u00e9 des \u00e9quipes commerciales, <a href=\"https:\/\/www.salesforce.com\/agentforce\/\"><strong>Agentforce for Revenue<\/strong><\/a> se positionne comme un v\u00e9ritable catalyseur de croissance. Fini les t\u00e2ches r\u00e9p\u00e9titives et chronophages ! Gr\u00e2ce \u00e0 l&rsquo;IA, les commerciaux peuvent d\u00e9sormais g\u00e9n\u00e9rer des devis complexes en quelques secondes, simplement en d\u00e9crivant leurs besoins. Imaginez une simple phrase comme \u00ab <em>devis pour un g\u00e9n\u00e9rateur avec le pack \u00e9nergie \u00e0 l\u2019usage<\/em> \u00bb. Cela suffit \u00e0 Agentforce pour cr\u00e9er automatiquement le devis parfait, incluant les bons produits, tarifs et conditions.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>L&rsquo;IA au service de la fluidit\u00e9 commerciale : devis instantan\u00e9s et pr\u00e9cision in\u00e9gal\u00e9e<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Salesforce a d\u00e9j\u00e0 constat\u00e9 les b\u00e9n\u00e9fices de cette approche en interne : une <strong>r\u00e9duction spectaculaire de 75 % du temps de g\u00e9n\u00e9ration de devis<\/strong> et une <strong>baisse de 87 % des clics<\/strong> pour ses \u00e9quipes commerciales. Un gain d&rsquo;efficacit\u00e9 qui se traduit directement par plus de temps d\u00e9di\u00e9 \u00e0 la relation client et \u00e0 la conclusion d&rsquo;affaires.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em>Revenue Cloud transforme notre fa\u00e7on de travailler<\/em><strong> .<\/strong> <em>Nous testons actuellement le nouvel agent pour les devis et nous sommes convaincus qu\u2019il va r\u00e9duire les t\u00e2ches manuelles, acc\u00e9l\u00e9rer les cycles de vente et permettre d\u2019envoyer les devis aux clients plus rapidement que jamais. <\/em><\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Bill Francy, pr\u00e9sident des services clients chez AdMed, Inc<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Au-del\u00e0 de la seule g\u00e9n\u00e9ration de devis, Agentforce for Revenue optimise \u00e9galement la configuration des produits. Le nouveau moteur logique de Salesforce, bas\u00e9 sur un <strong>mod\u00e8le de contraintes bi-directionnelles<\/strong>, offre une flexibilit\u00e9 sans pr\u00e9c\u00e9dent pour g\u00e9rer la complexit\u00e9 des offres, m\u00eame celles comportant plus de 1 000 lignes. C&rsquo;est comme un <strong>GPS pour les devis<\/strong>, guidant les commerciaux vers les configurations optimales en temps r\u00e9el, un atout majeur pour r\u00e9duire les erreurs et acc\u00e9l\u00e9rer le processus de vente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pourquoi cette innovation est-elle cruciale pour les entreprises ?<\/strong>Les op\u00e9rations commerciales n&rsquo;ont jamais \u00e9t\u00e9 aussi complexes. Une <a href=\"https:\/\/www.deloittedigital.com\/content\/dam\/digital\/global\/legacy\/documents\/offerings\/offering-20231108-b2b-commerce-trends.pdf\"><strong>\u00e9tude de Deloitte<\/strong><\/a> r\u00e9v\u00e8le que 71 % des dirigeants B2B sont confront\u00e9s \u00e0 des processus de vente fragment\u00e9s et manuels, et que 13 % des ventes sont perdues \u00e0 cause d&rsquo;outils d\u00e9connect\u00e9s. Agentforce for Revenue, int\u00e9gr\u00e9 \u00e0 Revenue Cloud, l\u00e8ve ces freins en unifiant tous les types de transactions sur une plateforme unique et transparente, de la proposition commerciale \u00e0 la facture.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em>Salesforce CPQ a permis l\u2019essor de la deuxi\u00e8me g\u00e9n\u00e9ration de gestion des revenus avec les mod\u00e8les r\u00e9currents \u00e0 grande \u00e9chelle<\/em>. <em>Avec Revenue Cloud, nous lan\u00e7ons la troisi\u00e8me vague : une gestion des revenus pilot\u00e9e par une plateforme modulaire, API-first, pr\u00eate pour les agents IA, qui fluidifie les flux de revenus sur tous les canaux<\/em>.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Meredith Schmidt, EVP et GM de Revenue Cloud chez Salesforce<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Comment \u00e7a marche ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Salesforce a repens\u00e9 son approche en cr\u00e9ant Revenue Cloud, une plateforme modulaire, \u00ab API-first \u00bb (c\u2019est-\u00e0-dire con\u00e7ue pour interagir facilement avec d&rsquo;autres syst\u00e8mes via des interfaces de programmation), optimis\u00e9e pour les agents IA. Cette architecture permet aux agents d&rsquo;interagir nativement avec chaque processus du cycle de revenus.<\/p>\n\n\n<div class=\"wp-block-image__wrapper\">\n<figure class=\"wp-block-image size-full\"><a href=\"#\" class=\"wp-block-image__modal-toggle\" aria-expanded=\"false\" data-modal-id=\"2171-modal\"><span class=\"screen-reader-text\">Ouvrir le modal d&#039;image<\/span><img loading=\"lazy\" decoding=\"async\" width=\"906\" height=\"706\" src=\"https:\/\/www.salesforce.com\/fr\/news\/wp-content\/uploads\/sites\/23\/2025\/07\/Capture-decran-2025-07-28-a-18.13.41.png?strip=all&#038;quality=95\" alt=\"\" class=\"wp-image-2171\" srcset=\"https:\/\/www.salesforce.com\/fr\/news\/wp-content\/uploads\/sites\/23\/2025\/07\/Capture-decran-2025-07-28-a-18.13.41.png 906w, https:\/\/www.salesforce.com\/fr\/news\/wp-content\/uploads\/sites\/23\/2025\/07\/Capture-decran-2025-07-28-a-18.13.41.png?w=300&amp;h=234 300w, https:\/\/www.salesforce.com\/fr\/news\/wp-content\/uploads\/sites\/23\/2025\/07\/Capture-decran-2025-07-28-a-18.13.41.png?w=768&amp;h=598 768w, https:\/\/www.salesforce.com\/fr\/news\/wp-content\/uploads\/sites\/23\/2025\/07\/Capture-decran-2025-07-28-a-18.13.41.png?w=264&amp;h=206 264w, https:\/\/www.salesforce.com\/fr\/news\/wp-content\/uploads\/sites\/23\/2025\/07\/Capture-decran-2025-07-28-a-18.13.41.png?w=468&amp;h=365 468w, https:\/\/www.salesforce.com\/fr\/news\/wp-content\/uploads\/sites\/23\/2025\/07\/Capture-decran-2025-07-28-a-18.13.41.png?w=150&amp;h=117 150w, https:\/\/www.salesforce.com\/fr\/news\/wp-content\/uploads\/sites\/23\/2025\/07\/Capture-decran-2025-07-28-a-18.13.41.png?w=248&amp;h=193 248w\" sizes=\"auto, (max-width: 906px) 100vw, 906px\" \/><\/a><\/figure>\n<div id=\"2171-modal\" class=\"image-modal\" aria-hidden=\"true\" aria-labelledby=\"image-dialog-title\"><div class=\"image-modal__overlay\" tabindex=\"-1\" data-a11y-dialog-hide><\/div><div class=\"image-modal__content\" role=\"dialog\"><button class=\"image-modal__close-button\" type=\"button\" data-a11y-dialog-hide aria-label=\"Fermer cette fen\u00eatre de dialogue\"><svg viewBox=\"0 0 26 25\" height=\"16\" width=\"16\" fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><rect x=\".626\" y=\"22.753\" width=\"32\" height=\"3\" rx=\"1.5\" transform=\"rotate(-45 .626 22.753)\"\/><rect x=\"2.747\" y=\".125\" width=\"32\" height=\"3\" rx=\"1.5\" transform=\"rotate(45 2.747 .125)\"\/><\/svg><\/button><h1 id=\"image-dialog-title\" class=\"screen-reader-text\">Image Modal<\/h1>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"906\" height=\"706\" src=\"https:\/\/www.salesforce.com\/fr\/news\/wp-content\/uploads\/sites\/23\/2025\/07\/Capture-decran-2025-07-28-a-18.13.41.png?strip=all&#038;quality=95\" alt=\"\" class=\"wp-image-2171\" srcset=\"https:\/\/www.salesforce.com\/fr\/news\/wp-content\/uploads\/sites\/23\/2025\/07\/Capture-decran-2025-07-28-a-18.13.41.png 906w, https:\/\/www.salesforce.com\/fr\/news\/wp-content\/uploads\/sites\/23\/2025\/07\/Capture-decran-2025-07-28-a-18.13.41.png?w=300&amp;h=234 300w, https:\/\/www.salesforce.com\/fr\/news\/wp-content\/uploads\/sites\/23\/2025\/07\/Capture-decran-2025-07-28-a-18.13.41.png?w=768&amp;h=598 768w, https:\/\/www.salesforce.com\/fr\/news\/wp-content\/uploads\/sites\/23\/2025\/07\/Capture-decran-2025-07-28-a-18.13.41.png?w=264&amp;h=206 264w, https:\/\/www.salesforce.com\/fr\/news\/wp-content\/uploads\/sites\/23\/2025\/07\/Capture-decran-2025-07-28-a-18.13.41.png?w=468&amp;h=365 468w, https:\/\/www.salesforce.com\/fr\/news\/wp-content\/uploads\/sites\/23\/2025\/07\/Capture-decran-2025-07-28-a-18.13.41.png?w=150&amp;h=117 150w, https:\/\/www.salesforce.com\/fr\/news\/wp-content\/uploads\/sites\/23\/2025\/07\/Capture-decran-2025-07-28-a-18.13.41.png?w=248&amp;h=193 248w\" sizes=\"auto, (max-width: 906px) 100vw, 906px\" \/><\/figure>\n<\/div><\/div><\/div>\n\n\n<p class=\"wp-block-paragraph\">Agentforce et Revenue Cloud harmonisent les donn\u00e9es structur\u00e9es (historiques d&rsquo;achat, catalogues) et non structur\u00e9es (donn\u00e9es d&rsquo;usage) au sein de <a href=\"https:\/\/www.salesforce.com\/data\/\"><strong>Data Cloud<\/strong><\/a>, l&rsquo;orchestrateur de donn\u00e9es intelligent de Salesforce. Ces informations enrichies alimentent l&rsquo;IA agentique d&rsquo;Agentforce, capable de d\u00e9ployer des <strong>agents autonomes et orient\u00e9s objectifs<\/strong>. Contrairement aux assistants IA traditionnels qui se contentent de sugg\u00e9rer des actions, les agents Agentforce <strong>ex\u00e9cutent les t\u00e2ches de bout en bout<\/strong>, lib\u00e9rant ainsi les \u00e9quipes pour des missions \u00e0 plus forte valeur ajout\u00e9e : la strat\u00e9gie, la n\u00e9gociation, et la relation client.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.salesforce.com\/artificial-intelligence\/trusted-ai\/\"><strong>Salesforce Trust Layer<\/strong><\/a> assure une s\u00e9curit\u00e9 des donn\u00e9es in\u00e9gal\u00e9e, garantissant que les agents op\u00e8rent dans le strict respect des autorisations de chaque employ\u00e9. Chaque devis est ainsi conforme aux politiques internes, aux r\u00e8gles de tarification et aux donn\u00e9es clients, \u00e9liminant les risques et les pertes de temps.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Plus qu&rsquo;une solution, une plateforme d&rsquo;avenir<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ces innovations majeures sont disponibles d\u00e8s aujourd&rsquo;hui dans le cadre de la <a href=\"https:\/\/www.salesforce.com\/news\/stories\/summer-2025-product-release-announcement\/\"><strong>mise \u00e0 jour \u201cSummer \u201925<\/strong><\/a>\u201d de Salesforce, la plus importante \u00e0 ce jour pour Revenue Cloud. Cette version offre deux fois plus de fonctionnalit\u00e9s que son pr\u00e9d\u00e9cesseur, Salesforce CPQ, avec une puissance, une flexibilit\u00e9 et une rapidit\u00e9 accrues :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Seamless Workflows avec Slack et le CRM<\/strong> : Agentforce est int\u00e9gr\u00e9 \u00e0 Slack et aux fiches opportunit\u00e9, devis et compte de Salesforce. Les commerciaux peuvent cr\u00e9er, modifier et finaliser des devis depuis n&rsquo;importe quel canal, sans jamais quitter leur environnement de travail.<\/li>\n\n\n\n<li><strong>Revenue Cloud Billing<\/strong> : Revenue Cloud devient une plateforme compl\u00e8te permettant d&rsquo;automatiser l&rsquo;int\u00e9gralit\u00e9 du processus \u00ab <a href=\"https:\/\/www.salesforce.com\/sales\/cpq\/quote-to-cash\/\"><strong>quote-to-cash<\/strong><\/a> \u00bb (du devis \u00e0 la facture), y compris la facturation. La transparence et la pr\u00e9cision des factures sont garanties par l&rsquo;unification des donn\u00e9es sur une seule plateforme.<\/li>\n\n\n\n<li><strong>Revenue Management Intelligence<\/strong> : Gr\u00e2ce \u00e0 <strong>Tableau Next<\/strong>, int\u00e9gr\u00e9 \u00e0 Revenue Cloud, les \u00e9quipes commerciales, financi\u00e8res et op\u00e9rationnelles b\u00e9n\u00e9ficient d&rsquo;une visibilit\u00e9 en temps r\u00e9el sur l&rsquo;ensemble du <a href=\"https:\/\/www.salesforce.com\/sales\/revenue-lifecycle-management\/\"><strong>cycle de revenus<\/strong><\/a>. Des tableaux de bord intuitifs permettent de visualiser les tendances tarifaires, les flux de commandes et la performance des revenus, pour des d\u00e9cisions rapides et \u00e9clair\u00e9es.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Salesforce continue de soutenir ses clients actuels de Salesforce CPQ, tout en proposant un \u00e9cosyst\u00e8me de partenaires pour accompagner la transition vers Revenue Cloud pour ceux qui souhaitent migrer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pour en savoir plus :<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lisez l\u2019article : <a href=\"https:\/\/www.salesforce.com\/blog\/future-of-revenue-management\/\"><em>Le futur du revenu est agentique et agile. Vous avez besoin d\u2019une plateforme unique pour le g\u00e9rer<\/em><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-\"><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9sormais, les entreprises peuvent transformer leur cycle de vente gr\u00e2ce \u00e0 l&rsquo;intelligence artificielle, de la cr\u00e9ation instantan\u00e9e de devis complexes \u00e0 une facturation simplifi\u00e9e, lib\u00e9rant ainsi un temps pr\u00e9cieux pour leurs \u00e9quipes commerciales. Paris, le 28 juillet 2025 \u2013 Salesforce, leader mondial du CRM, annonce aujourd&rsquo;hui le lancement strat\u00e9gique d\u2019Agentforce for Revenue, une innovation majeure [&hellip;]<\/p>\n","protected":false},"author":742,"featured_media":2125,"template":"","meta":{"sf_subhead":"","sf_i18n_disclaimer":false,"alternateThumbnailId":0,"sf_product_cta_id":0,"footnotes":""},"sf_content_type":[41,44,45,48],"sf_theme":[401],"sf_topic":[360,402,18],"sf_product":[62],"sf_industry":[],"sf_role":[110],"sf_multimedia_asset":[],"sf_location":[381],"sf_collection":[],"sf_visibility":[],"coauthors":[405],"class_list":["post-2170","sf_press_release","type-sf_press_release","status-publish","has-post-thumbnail","hentry","sf_content_type-news-announcements","sf_content_type-news-announcements-product","sf_content_type-press-releases","sf_content_type-press-releases-product","sf_theme-agentic-ai","sf_topic-agents","sf_topic-ai","sf_topic-enterprise-ai","sf_product-agentforce","sf_role-sales","sf_location-france"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Salesforce lance Agentforce for Revenue Cloud<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avec Agentforce for Revenue Cloud, Salesforce d\u00e9cline ses agents IA au service de la performance commerciale\" \/>\n<meta property=\"og:description\" content=\"D\u00e9sormais, les entreprises peuvent transformer leur cycle de vente gr\u00e2ce \u00e0 l&rsquo;intelligence artificielle, de la cr\u00e9ation instantan\u00e9e de devis complexes \u00e0 une facturation simplifi\u00e9e, lib\u00e9rant ainsi un temps pr\u00e9cieux pour leurs \u00e9quipes commerciales. Paris, le 28 juillet 2025 \u2013 Salesforce, leader mondial du CRM, annonce aujourd&rsquo;hui le lancement strat\u00e9gique d\u2019Agentforce for Revenue, une innovation majeure [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salesforce.com\/fr\/news\/press-releases\/2025\/07\/28\/agentforce-for-revenue-cloud\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-28T16:23:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salesforce.com\/fr\/news\/wp-content\/uploads\/sites\/23\/2025\/07\/The-Quote-to-Capture-Revolution_-Under-the-Hood-of-Revenue-Clouds-New-Architecture-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Marion Lariviere\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/press-releases\\\/2025\\\/07\\\/28\\\/agentforce-for-revenue-cloud\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/press-releases\\\/2025\\\/07\\\/28\\\/agentforce-for-revenue-cloud\\\/\"},\"author\":[{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/#\\\/schema\\\/person\\\/8a9c51bcdcfacc4c262b6b77e2b3dfef\"}],\"headline\":\"Avec Agentforce for Revenue Cloud, Salesforce d\u00e9cline ses agents IA au service de la performance commerciale\",\"datePublished\":\"2025-07-28T16:23:27+00:00\",\"dateModified\":\"2025-07-28T16:23:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/press-releases\\\/2025\\\/07\\\/28\\\/agentforce-for-revenue-cloud\\\/\"},\"wordCount\":1096,\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/press-releases\\\/2025\\\/07\\\/28\\\/agentforce-for-revenue-cloud\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2025\\\/07\\\/The-Quote-to-Capture-Revolution_-Under-the-Hood-of-Revenue-Clouds-New-Architecture-1.png\",\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/press-releases\\\/2025\\\/07\\\/28\\\/agentforce-for-revenue-cloud\\\/\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/press-releases\\\/2025\\\/07\\\/28\\\/agentforce-for-revenue-cloud\\\/\",\"name\":\"Salesforce lance Agentforce for Revenue Cloud\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/press-releases\\\/2025\\\/07\\\/28\\\/agentforce-for-revenue-cloud\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/press-releases\\\/2025\\\/07\\\/28\\\/agentforce-for-revenue-cloud\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2025\\\/07\\\/The-Quote-to-Capture-Revolution_-Under-the-Hood-of-Revenue-Clouds-New-Architecture-1.png\",\"datePublished\":\"2025-07-28T16:23:27+00:00\",\"dateModified\":\"2025-07-28T16:23:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/press-releases\\\/2025\\\/07\\\/28\\\/agentforce-for-revenue-cloud\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/press-releases\\\/2025\\\/07\\\/28\\\/agentforce-for-revenue-cloud\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/press-releases\\\/2025\\\/07\\\/28\\\/agentforce-for-revenue-cloud\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2025\\\/07\\\/The-Quote-to-Capture-Revolution_-Under-the-Hood-of-Revenue-Clouds-New-Architecture-1.png\",\"contentUrl\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2025\\\/07\\\/The-Quote-to-Capture-Revolution_-Under-the-Hood-of-Revenue-Clouds-New-Architecture-1.png\",\"width\":1200,\"height\":675,\"caption\":\"Salesforce Shares a Deep Dive on the Revenue Cloud\u2019s New Architecture\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/press-releases\\\/2025\\\/07\\\/28\\\/agentforce-for-revenue-cloud\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Communiqu\u00e9s de presse\",\"item\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/sf_press_release\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Avec Agentforce for Revenue Cloud, Salesforce d\u00e9cline ses agents IA au service de la performance commerciale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/\",\"name\":\"Salesforce\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/#\\\/schema\\\/person\\\/8a9c51bcdcfacc4c262b6b77e2b3dfef\",\"name\":\"Marion Lariviere\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e869aed39809b682330a08e1a3d9b9e8ac0a042a0193b6e615459f1c459a9b32?s=96&d=mm&r=g98daad90568a4b32f15e9d316f37677d\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e869aed39809b682330a08e1a3d9b9e8ac0a042a0193b6e615459f1c459a9b32?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e869aed39809b682330a08e1a3d9b9e8ac0a042a0193b6e615459f1c459a9b32?s=96&d=mm&r=g\",\"caption\":\"Marion Lariviere\"},\"url\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/author\\\/mlarivieresalesforce-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Salesforce lance Agentforce for Revenue Cloud","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Avec Agentforce for Revenue Cloud, Salesforce d\u00e9cline ses agents IA au service de la performance commerciale","og_description":"D\u00e9sormais, les entreprises peuvent transformer leur cycle de vente gr\u00e2ce \u00e0 l&rsquo;intelligence artificielle, de la cr\u00e9ation instantan\u00e9e de devis complexes \u00e0 une facturation simplifi\u00e9e, lib\u00e9rant ainsi un temps pr\u00e9cieux pour leurs \u00e9quipes commerciales. Paris, le 28 juillet 2025 \u2013 Salesforce, leader mondial du CRM, annonce aujourd&rsquo;hui le lancement strat\u00e9gique d\u2019Agentforce for Revenue, une innovation majeure [&hellip;]","og_url":"https:\/\/www.salesforce.com\/fr\/news\/press-releases\/2025\/07\/28\/agentforce-for-revenue-cloud\/","og_site_name":"Salesforce","article_modified_time":"2025-07-28T16:23:28+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.salesforce.com\/fr\/news\/wp-content\/uploads\/sites\/23\/2025\/07\/The-Quote-to-Capture-Revolution_-Under-the-Hood-of-Revenue-Clouds-New-Architecture-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes","Written by":"Marion Lariviere"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.salesforce.com\/fr\/news\/press-releases\/2025\/07\/28\/agentforce-for-revenue-cloud\/#article","isPartOf":{"@id":"https:\/\/www.salesforce.com\/fr\/news\/press-releases\/2025\/07\/28\/agentforce-for-revenue-cloud\/"},"author":[{"@id":"https:\/\/www.salesforce.com\/fr\/news\/#\/schema\/person\/8a9c51bcdcfacc4c262b6b77e2b3dfef"}],"headline":"Avec Agentforce for Revenue Cloud, Salesforce d\u00e9cline ses agents IA au service de la performance commerciale","datePublished":"2025-07-28T16:23:27+00:00","dateModified":"2025-07-28T16:23:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salesforce.com\/fr\/news\/press-releases\/2025\/07\/28\/agentforce-for-revenue-cloud\/"},"wordCount":1096,"image":{"@id":"https:\/\/www.salesforce.com\/fr\/news\/press-releases\/2025\/07\/28\/agentforce-for-revenue-cloud\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/fr\/news\/wp-content\/uploads\/sites\/23\/2025\/07\/The-Quote-to-Capture-Revolution_-Under-the-Hood-of-Revenue-Clouds-New-Architecture-1.png","inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.salesforce.com\/fr\/news\/press-releases\/2025\/07\/28\/agentforce-for-revenue-cloud\/","url":"https:\/\/www.salesforce.com\/fr\/news\/press-releases\/2025\/07\/28\/agentforce-for-revenue-cloud\/","name":"Salesforce lance Agentforce for Revenue Cloud","isPartOf":{"@id":"https:\/\/www.salesforce.com\/fr\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salesforce.com\/fr\/news\/press-releases\/2025\/07\/28\/agentforce-for-revenue-cloud\/#primaryimage"},"image":{"@id":"https:\/\/www.salesforce.com\/fr\/news\/press-releases\/2025\/07\/28\/agentforce-for-revenue-cloud\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/fr\/news\/wp-content\/uploads\/sites\/23\/2025\/07\/The-Quote-to-Capture-Revolution_-Under-the-Hood-of-Revenue-Clouds-New-Architecture-1.png","datePublished":"2025-07-28T16:23:27+00:00","dateModified":"2025-07-28T16:23:28+00:00","breadcrumb":{"@id":"https:\/\/www.salesforce.com\/fr\/news\/press-releases\/2025\/07\/28\/agentforce-for-revenue-cloud\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salesforce.com\/fr\/news\/press-releases\/2025\/07\/28\/agentforce-for-revenue-cloud\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.salesforce.com\/fr\/news\/press-releases\/2025\/07\/28\/agentforce-for-revenue-cloud\/#primaryimage","url":"https:\/\/www.salesforce.com\/fr\/news\/wp-content\/uploads\/sites\/23\/2025\/07\/The-Quote-to-Capture-Revolution_-Under-the-Hood-of-Revenue-Clouds-New-Architecture-1.png","contentUrl":"https:\/\/www.salesforce.com\/fr\/news\/wp-content\/uploads\/sites\/23\/2025\/07\/The-Quote-to-Capture-Revolution_-Under-the-Hood-of-Revenue-Clouds-New-Architecture-1.png","width":1200,"height":675,"caption":"Salesforce Shares a Deep Dive on the Revenue Cloud\u2019s New Architecture"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salesforce.com\/fr\/news\/press-releases\/2025\/07\/28\/agentforce-for-revenue-cloud\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salesforce.com\/fr\/news\/"},{"@type":"ListItem","position":2,"name":"Communiqu\u00e9s de presse","item":"https:\/\/www.salesforce.com\/fr\/news\/sf_press_release\/"},{"@type":"ListItem","position":3,"name":"Avec Agentforce for Revenue Cloud, Salesforce d\u00e9cline ses agents IA au service de la performance commerciale"}]},{"@type":"WebSite","@id":"https:\/\/www.salesforce.com\/fr\/news\/#website","url":"https:\/\/www.salesforce.com\/fr\/news\/","name":"Salesforce","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salesforce.com\/fr\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.salesforce.com\/fr\/news\/#\/schema\/person\/8a9c51bcdcfacc4c262b6b77e2b3dfef","name":"Marion Lariviere","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e869aed39809b682330a08e1a3d9b9e8ac0a042a0193b6e615459f1c459a9b32?s=96&d=mm&r=g98daad90568a4b32f15e9d316f37677d","url":"https:\/\/secure.gravatar.com\/avatar\/e869aed39809b682330a08e1a3d9b9e8ac0a042a0193b6e615459f1c459a9b32?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e869aed39809b682330a08e1a3d9b9e8ac0a042a0193b6e615459f1c459a9b32?s=96&d=mm&r=g","caption":"Marion Lariviere"},"url":"https:\/\/www.salesforce.com\/fr\/news\/author\/mlarivieresalesforce-com\/"}]}},"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Salesforce","distributor_original_site_url":"https:\/\/www.salesforce.com\/fr\/news","push-errors":false,"_links":{"self":[{"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/sf_press_release\/2170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/sf_press_release"}],"about":[{"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/types\/sf_press_release"}],"author":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/users\/742"}],"version-history":[{"count":3,"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/sf_press_release\/2170\/revisions"}],"predecessor-version":[{"id":2174,"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/sf_press_release\/2170\/revisions\/2174"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/media\/2125"}],"wp:attachment":[{"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/media?parent=2170"}],"wp:term":[{"taxonomy":"sf_content_type","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/sf_content_type?post=2170"},{"taxonomy":"sf_theme","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/sf_theme?post=2170"},{"taxonomy":"sf_topic","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/sf_topic?post=2170"},{"taxonomy":"sf_product","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/sf_product?post=2170"},{"taxonomy":"sf_industry","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/sf_industry?post=2170"},{"taxonomy":"sf_role","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/sf_role?post=2170"},{"taxonomy":"sf_multimedia_asset","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/sf_multimedia_asset?post=2170"},{"taxonomy":"sf_location","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/sf_location?post=2170"},{"taxonomy":"sf_collection","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/sf_collection?post=2170"},{"taxonomy":"sf_visibility","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/sf_visibility?post=2170"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/coauthors?post=2170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}