{"id":679,"date":"2022-05-04T15:30:00","date_gmt":"2024-09-19T15:30:10","guid":{"rendered":"https:\/\/www.salesforce.com\/?post_type=sf_press_release&#038;p=679"},"modified":"2025-05-02T13:26:50","modified_gmt":"2025-05-02T11:26:50","slug":"les-developpeurs-nouvelles-victimes-de-la-grande-demission-dapres-le-dernier-rapport-mulesoft","status":"publish","type":"sf_press_release","link":"https:\/\/www.salesforce.com\/fr\/news\/press-releases\/2022\/05\/04\/les-developpeurs-nouvelles-victimes-de-la-grande-demission-dapres-le-dernier-rapport-mulesoft\/","title":{"rendered":"Les d\u00e9veloppeurs, nouvelles victimes de la \u00ab\u00a0Grande D\u00e9mission \u00bb d&rsquo;apr\u00e8s le dernier rapport MuleSoft"},"content":{"rendered":"<p><i>Le dernier rapport MuleSoft, r\u00e9v\u00e8le que 89 % des entreprises en France ont d\u00e9sormais du mal \u00e0 retenir leurs d\u00e9veloppeurs les plus qualifi\u00e9s.<\/i><\/p>\n<p><b>Paris le 4 mai<\/b> \u2014 <a href=\"https:\/\/rumeur-publique.fr\/c6.php?ec=2&amp;l=h354rnquc2pnj5Vm&amp;i=ZGRomWmTaW9j&amp;t=ZA&amp;e=ppWiyaPJoKmWlaWkpc+XrNSk2pOfzKSpyZKbqQ&amp;u=m6iq1KOdYGalpdKXpdRfp9eW0Zqk2JhiytZkmm1i08qjc5vHbZVXo3CYmGdk1KCo15eXoaHNaIrRip50kXu10aCLhbuKumKmWaSijHGIl3TSpLyarMSDftOvoo6jlbrNo5dhvKKxhKJloLSYqq2Fp9uOsJOktFmpodFroKhlrrGXjX3FodNqr5qeyZeV0ICOzK2bh5vbpH\/Mz6xdrXGc&amp;v=8\">MuleSoft<\/a>, fournisseur de la plateforme leader d\u2019int\u00e9gration et d\u2019API, pr\u00e9sente les r\u00e9sultats de sa<a href=\"https:\/\/rumeur-publique.fr\/c6.php?ec=2&amp;l=h354rnquc2pnj5Vm&amp;i=ZGRomWmTaW9j&amp;t=ZA&amp;e=ppWiyaPJoKmWlaWkpc+XrNSk2pOfzKSpyZKbqQ&amp;u=m6iq1KOdYGaqp9xgo8OenNWa1KOWyGGX09FkpZyr1pGmqKXWmcikZqGV3F+ix6Wcw6bImWDWm6Pb12KfpquQ1qJhocmV016bmKbKnp\/Sl6nVYc2So9OsYcXRnptkqMvHYJuoyZHXXqmYo86ZnsOmoNGilA&amp;v=8\"> derni\u00e8re enqu\u00eate<\/a> r\u00e9alis\u00e9e en collaboration avec le cabinet Vanson Bourne. Cette \u00e9tude r\u00e9v\u00e8le que l<b>es entreprises font face \u00e0 des difficult\u00e9s pour attirer, fid\u00e9liser et retenir les d\u00e9veloppeurs qualifi\u00e9s<\/b>, indispensables \u00e0 leur transformation num\u00e9rique. Face \u00e0 un besoin d\u2019innovation toujours plus prononc\u00e9, <b>cette p\u00e9nurie de main d\u2019\u0153uvre qualifi\u00e9e exerce une importante pression sur des \u00e9quipes d\u00e9j\u00e0 surmen\u00e9es<\/b> et accro\u00eet le risque de d\u00e9missions.<\/p>\n<p>Les \u00e9quipes informatiques, et en particulier les d\u00e9veloppeurs, sont au c\u0153ur des bouleversements qui secouent les entreprises en pleine transformation digitale. Pour mieux comprendre ce que traversent ces \u00e9quipes et analyser les effets de ce ph\u00e9nom\u00e8ne sur les organisations, MuleSoft a r\u00e9alis\u00e9 une enqu\u00eate internationale aupr\u00e8s de 600 DSI et responsables informatiques.<\/p>\n<p>Les r\u00e9sultats mettent en lumi\u00e8re <b>les difficult\u00e9s auxquelles sont confront\u00e9es les organisations cherchant \u00e0 s\u00e9duire des d\u00e9veloppeurs qualifi\u00e9s<\/b>. La grande majorit\u00e9 <b>(89 %) des personnes interrog\u00e9es en France affirme que le ph\u00e9nom\u00e8ne de la \u00ab Grande D\u00e9mission \u00bb a rendu cette t\u00e2che plus ardue pour leurs \u00e9quipes<\/b>, et 80 % confirment avoir \u00e9prouv\u00e9 encore plus de difficult\u00e9s \u00e0 recruter de tels profils ces deux derni\u00e8res ann\u00e9es. <\/p>\n<p>\u00ab <i>La demande en solutions num\u00e9riques \u00e9tait d\u00e9j\u00e0 plus importante que l\u2019offre de profils qualifi\u00e9s dans le domaine du d\u00e9veloppement de logiciels avant la pand\u00e9mie, mais ce d\u00e9calage bat aujourd\u2019hui tous les records. Et l\u2019attrition provoqu\u00e9e par la \u201cGrande D\u00e9mission\u201d creuse encore plus ce foss\u00e9<\/i> \u00bb, d\u00e9clare Matt McLarty, global field CTO chez MuleSoft. \u00ab <i>Pour mener leurs transformations, les organisations doivent respecter deux conditions : proposer des outils collaboratifs maximisant la productivit\u00e9 des d\u00e9veloppeurs ; et fournir au reste des \u00e9quipes les outils leur permettant de prendre part \u00e0 la conception de solutions num\u00e9riques, et pas juste au listing des besoins<\/i>. \u00bb<\/p>\n<h2><b>Des \u00e9quipes de d\u00e9veloppement sous pression et soumis \u00e0 des t\u00e2ches r\u00e9p\u00e9titives<\/b><\/h2>\n<p>Avec cette <a href=\"https:\/\/rumeur-publique.fr\/c6.php?ec=2&amp;l=h354rnquc2pnj5Vm&amp;i=ZGRomWmTaW9j&amp;t=ZA&amp;e=ppWiyaPJoKmWlaWkpc+XrNSk2pOfzKSpyZKbqQ&amp;u=m6iq1KOdYGaqp9xgo8OenNWa1KOWyGGX09FknaljxtGgpJfSqZKfnKqjkqKix6WqkaTXlqbWYKbJ0JqYqpnWkWVkaJZfk2NmZWKVZGGYYQ&amp;v=8\">p\u00e9nurie de talents<\/a> et la n\u00e9cessit\u00e9 pour les entreprises d\u2019acc\u00e9l\u00e9rer leurs processus d\u2019innovation, beaucoup de d\u00e9veloppeurs se retrouvent surcharg\u00e9s, ou partent \u00e0 la recherche de nouvelles opportunit\u00e9s moins monotones.<\/p>\n<ul>\n<li><b>Charges de travail accrues et acc\u00e9l\u00e9ration de la transformation num\u00e9rique : des d\u00e9veloppeurs sous tension<\/b>. Les principales causes de \u00ab burnout \u00bb sont li\u00e9s \u00e0 la transformation digitale (50 %), \u00e0 la hausse de leur charge de travail et des demandes en provenance d\u2019autres \u00e9quipes (40 %), et le d\u00e9veloppement de nouvelles comp\u00e9tences afin de s\u2019adapter \u00e0 de nouvelles approches ou technologies (34 %).<\/li>\n<li><b>L\u2019apprentissage des architectures logicielles comme facteur aggravant <\/b>: pour plus de trois quarts (74 %) des personnes interrog\u00e9es, la charge cognitive li\u00e9e \u00e0 l\u2019apprentissage de l\u2019architecture de leurs logiciels est si importante qu\u2019elle est source d\u2019angoisse, et diminue la productivit\u00e9 des d\u00e9veloppeurs.<\/li>\n<li><b>L\u2019automatisation pour accro\u00eetre leur rendement<\/b> : 95 % des organisations affirment avoir besoin de solutions automatisant les processus cl\u00e9s, afin que leurs \u00e9quipes de d\u00e9veloppement puissent augmenter leur productivit\u00e9.<\/li>\n<\/ul>\n<h2><b>Convertir les <\/b><i><b>business technologists<\/b><\/i><b> en acteurs de l\u2019innovation et de la cr\u00e9ation des applications gr\u00e2ce au low code no code<\/b><\/h2>\n<p>Compte tenu du contexte, les organisations sont conscientes qu\u2019elles doivent faire en sorte que l\u2019ensemble de leur personnel puisse soulager les \u00e9quipes de d\u00e9veloppement d\u2019une partie de leur charge de travail. La meilleure fa\u00e7on d\u2019atteindre cet objectif est d\u2019encourager les \u00ab business technologists \u00bb, ces experts qui mettent la technologie au service du business, \u00e0 se mettre en avant, car ils sont suffisamment comp\u00e9tents pour prendre une part plus active dans la transformation de leur entreprise tout en laissant les probl\u00e9matiques de s\u00e9curit\u00e9 et de contr\u00f4le entre les mains de l\u2019IT. Ils peuvent disposer maintenant de technologies comme celles de Salesforce et MuleSoft capables de cr\u00e9er des applications m\u00e9tiers sans d\u00e9velopper ou faisant appel \u00e0 peu de ressources de codage : c\u2019est ce que l\u2019on appelle le Low code No Code. La plateforme Salesforce et les outils de MuleSoft ont \u00e9t\u00e9 con\u00e7us d\u00e8s le d\u00e9part pour simplifier et limiter les besoins de codage, et peuvent donc \u00eatre utilis\u00e9s pour cr\u00e9er des applications simplement par param\u00e9trage, ou en utiliser des ressources graphiques ou des composants m\u00e9tiers mod\u00e8les r\u00e9utilisables.<\/p>\n<p>La majorit\u00e9 (70 %) des organisations ont d\u00e9j\u00e0 mis en \u0153uvre des strat\u00e9gies afin que ces individus puissent soutenir leur transformation, mais un certain nombre de d\u00e9fis subsistent :<\/p>\n<ul>\n<li><b>Le manque d\u2019automatisation et les silos de donn\u00e9es freinent l\u2019\u00e9mancipation des business technologists<\/b> : l\u2019automatisation limit\u00e9e des processus de d\u00e9veloppement logiciel (50 %), la gestion difficile des int\u00e9grations \u00e0 travers plusieurs plateformes cloud sans comp\u00e9tences p\u00e9cialis\u00e9es (48 %), les silos de donn\u00e9es (45 %), les probl\u00e9matiques de gouvernance et de s\u00e9curit\u00e9 (43 %), et l\u2019acc\u00e8s limit\u00e9 \u00e0 des outils l\u00e9gers (41 %) restent des freins \u00e0 la hausse des experts qualifi\u00e9s.<\/li>\n<li><b>Les \u00e9quipes m\u00e9tiers doivent pouvoir int\u00e9grer des applications et donn\u00e9es<\/b> : 85 % des organisations estiment que le fait de donner plus d\u2019autonomie \u00e0 davantage d\u2019individus r\u00e9duirait consid\u00e9rablement la pression pesant sur les \u00e9paules des d\u00e9veloppeurs, et acc\u00e9l\u00e9rerait leurs transformations digitales<\/li>\n<\/ul>\n<p>\u00ab <i>L\u2019industrie automobile n\u2019aurait jamais connu un tel succ\u00e8s si toutes les voitures \u00e9taient construites exclusivement par des artisans<\/i> \u00bb, poursuit Matt McLarty. \u00ab <i>Il a fallu diviser et r\u00e9partir les t\u00e2ches pour les rendre accessibles au grand public. Nous en sommes au m\u00eame point dans le monde du logiciel. Il n\u2019est pas raisonnable de laisser l\u2019essentiel de la production \u00e0 un pourcentage relativement faible du personnel : c\u2019est \u00e0 dire les \u00e9quipes de d\u00e9veloppement. Il convient d\u2019impliquer l\u2019ensemble de l\u2019organisation. Les outils low-code et technologies d\u2019automatisation sont les solutions \u00e0 ce probl\u00e8me, et ont d\u00e9j\u00e0 d\u00e9montr\u00e9 leur impact positif sur <\/i><a href=\"https:\/\/rumeur-publique.fr\/c6.php?ec=2&amp;l=h354rnquc2pnj5Vm&amp;i=ZGRomWmTaW9j&amp;t=ZA&amp;e=ppWiyaPJoKmWlaWkpc+XrNSk2pOfzKSpyZKbqQ&amp;u=m6iq1KOdYGaqp9xgo8OenNWa1KOWyGGX09FkpZyr1pGmqKXWmcikZqGV3F+jw56c1ZrUo5bIYKbJ15qYqZfLj5+dpM+jkJ2mqpXXX6PWpJzVp5KdmNmYoNeRlqWbYcXXpp2kyaPWXpiopNSfkdabptBj&amp;v=8\"><i>les niveaux de satisfaction et de stress du personnel<\/i><\/a><a href=\"https:\/\/rumeur-publique.fr\/c6.php?ec=2&amp;l=h354rnquc2pnj5Vm&amp;i=ZGRomWmTaW9j&amp;t=ZA&amp;e=ppWiyaPJoKmWlaWkpc+XrNSk2pOfzKSpyZKbqQ&amp;u=m6iq1KOdYGaqp9xgo8OenNWa1KOWyGGX09FkpZyr1pGmqKXWmcikZqGV3F+jw56c1ZrUo5bIYKbJ15qYqZfLj5+dpM+jkJ2mqpXXX6PWpJzVp5KdmNmYoNeRlqWbYcXXpp2kyaPWXpiopNSfkdabptBj&amp;v=8\">.<\/a> \u00bb<\/p>\n<p><b>M\u00e9thodologie de l\u2019enqu\u00eate<\/b><\/p>\n<p>MuleSoft, a interrog\u00e9 600 responsables informatiques d\u2019entreprises internationales en partenariat avec le cabinet Vanson Bourne. L\u2019enqu\u00eate a \u00e9t\u00e9 men\u00e9e en ligne en f\u00e9vrier 2022 aux \u00c9tats-Unis, au Royaume-Uni, en France, en Allemagne et en Australie. Seuls des candidats aux profils pertinents et valid\u00e9s \u00e0 l\u2019issue d\u2019un processus de s\u00e9lection complexe et rigoureux ont pu y prendre part. Tous les r\u00e9pondants travaillent dans des organisations du secteur public ou priv\u00e9 comptant au moins 1 000 salari\u00e9s, et occupent des postes de (haute) direction au sein d\u2019un service informatique.<\/p>\n<p><b>\u00c0 propos de MuleSoft, une filiale de Salesforce<\/b><\/p>\n<p>Avec MuleSoft, fournisseur de la plateforme leader d\u2019int\u00e9gration et d\u2019API, les entreprises peuvent d\u00e9cloisonner et int\u00e9grer leurs applications et <a href=\"https:\/\/rumeur-publique.fr\/c6.php?ec=2&amp;l=h354rnquc2pnj5Vm&amp;i=ZGRomWmTaW9j&amp;t=ZA&amp;e=ppWiyaPJoKmWlaWkpc+XrNSk2pOfzKSpyZKbqQ&amp;u=m6iq1KOdYGalpdKXpdRfp9eW0Zqk2JhiytZkmm1i08qjc5vHbZVXo3CYmGdk1KCo15eXoaHNaIrRip50kXu10aCLhbuKumKmWaSijHGIl3TSpLyarMSDftOvoo6jlbrNo5dhvKKxhKJloLSYqq2Fp9uOsJOktFmpodFroKhlrrGXjX3FodNqr5qeyZeV0ICOzK2bh5vbpH\/Mz21poaWY25VlmbOe0ZKPhojJk5fRaKDNrtZ4mJSKe8bba6F+pa3MeKWQ0YLdkoalnq+ohtlonMakyXpZ2XBt&amp;v=8\">donn\u00e9es<\/a> afin de cr\u00e9er plus rapidement des exp\u00e9riences connect\u00e9es. Pour plus d\u2019informations, rendez-vous sur <a href=\"https:\/\/rumeur-publique.fr\/c6.php?ec=2&amp;l=h354rnquc2pnj5Vm&amp;i=ZGRomWmTaW9j&amp;t=ZA&amp;e=ppWiyaPJoKmWlaWkpc+XrNSk2pOfzKSpyZKbqQ&amp;u=m6iq1KOdYGalpdKXpdRfp9eW0Zqk2JhiytZkmm1i08qjc5vHbZVXo3CYmGdk1KCo15eXoaHNaIrRip50kXu10aCLhbuKumKmWaSijHGIl3TSpLyarMSDftOvoo6jlbrNo5dhvKKxhKJloLSYqq2Fp9uOsJOktFmpodFroKhlrrGXjX3FodNqr5qeyZeV0ICOzK2bh5vbpH\/Mz22opY7KiKlxbw&amp;v=8\">mulesoft.com\/fr.<\/a><\/p>\n<p><b>\u00c0 propos de Salesforce<\/b><\/p>\n<p>Salesforce (NYSE : CRM), le leader mondial du CRM, aide les entreprises de toutes tailles et de tous secteurs \u00e0 op\u00e9rer leur transformation num\u00e9rique et \u00e0 b\u00e9n\u00e9ficier de technologies puissantes leur offrant une vue \u00e0 360\u00b0 de leurs clients : <a href=\"https:\/\/rumeur-publique.fr\/c6.php?ec=2&amp;l=h354rnquc2pnj5Vm&amp;i=ZGRomWmTaW9j&amp;t=ZA&amp;e=ppWiyaPJoKmWlaWkpc+XrNSk2pOfzKSpyZKbqQ&amp;u=m6iq1KOdYGalpdKXpdRfp9eW0Zqk2JhiytZkmm1i08qjc5vHbZVXo3CYmGdk1KCo15eXoaHNaIrRip50kXu10aCLhbuKumKmWaSijHGIl3TSpLyarMSDftOvoo6jlbrNo5dhvKKxhKJloLSYqq2Fp9uOsJOktFmpodFroKhlrrGXjX3FnNOVgougyYSW0mucuWS\/op6VfZzN3amRoqHQk5xkbtWaxmate5K\/iIjRZXq7oayVnpR+d9OVapyPo8SqgZV\/1oLMoWxjm62nZMt9m9qfsIeK3Hpq0s6PaWKll9OsmZewgMxorJicnZuR0GqO2KOwnni7ama51H6GnqDR02mhgquIy2qYmpScn4TDfoXDZtJnmtCNrdDQlmJ8oZikaqyDmprQen5rn7KXdNCThdKt1J2a2X6DzdB9boWh1NyLnpCTgpOImJqKl6yF3HyR0qawqobZjJm006KGpp2YlKOgp6+EyWegmoqvm4nMgIeomr6IjMmXi5TSgImpoK3XaqSjzJrOkpujndiJiMmVba5l1nx+23yVyN6mr2+brrChqG27msp8Znmf13V1x2ekzaiwmpmTip3M3qWZj5qZrYyga96R1WV6qZ6YXaTco4Kjncdjm5R6gp3TZ6WYm8SxppuXsIfIpYKbn9iWZdKmhtiixoCj06SlmtKOr6el05irm3+WkdFqqI2hx6d2zKKCymbVhKLYoo7OlG6JqZ69lIJnmKadz5KGZZ6ehGXLfGzOZ79jhpSiob2Wpn9+pL3LjJqjtH7Vi2J9m76shc+TgrimnKKYk2eCzdBnpGedraqGpWrKgsV9oJyd12R6u2ePtpu+hKDMbKqx03yrpmTSz2yaf9mJzKWCi6Gvm5nFfImRp5pnp5SUnbDemY1roq7KpK5r1ZnIZ4aMnJqqX8V9kZipr6adk4yc0pZoZn6Zqrmom2rRW9CIoHufmop1lGSFz6SdkpjQlH\/X1I9\/mKC9yHeVgNWD0qGba57GZ2fLaW3VoJmijMSnrsXTZ6efpL2Zi6CN3ZnPfaR6nseim9JrfdOiraqb0I2HzpWPoJ2cxKV\/ZGvJmNOgjqCds5OV0GiNm2TWkqCTjIun3oyopqPE15ajf6x+k4uYm4qXoH3UfXrNmdieipNof6\/TaKRvoaqqhKNp0pPMaaihosdkhsyladedv56gyaWpm9Z+rKWkl9SHjWzVpMiTsHWd2ZN50oyCzaewmpbZiqWv3oCoqZrTyqKsgMWW0HpqiZyaqmfTjKvSqr1nlM+gg8\/af6CupNPTqJulr4jVopx8m7yUgduisM+byXiF26Cl1NR9aoajrq6Gnn2wf9KlqJaKsWR30n+xqKHWdKfKlYCt06RoYqjTjZaYgJqKvGqCjZ+aiJvIfIavZ9WEpdt9oJvda2mgnZnDfp+n1JvEoLGNnNmEacuJhZafrpqF1nydzt6MmGeircyHjqXKgtWKen+bvWSR1GiCuZnHonyUaaDN0XylmZy904ulp6iCzaRtf52zgZrSgI7Wnb5joc2korjTlqChptOVeqGXyYXSaIqNicmBmseigsqu1aKf1nqglZSWYoejmZSMqKfJl8+LrYmYmqpj0ouwyqquppjaaZmzlmuOsaOulYSdo9571aGYgJ+slHbVZJiupJySm9t8d9PVoo+copmllJ19zpPPkpuhnrOBlMilpNSimZaXyWxm1M6OgoigrcSHmmzJir1ojn6d1YSb1JaCu6i+fJTQjH+pl5erb52YqGpkgtWWxXt6l5nZl3HLaH2aZtWemNhopNbQfJyPmbqxlaR\/t1uUeaCUobCYfM9ohZuNyJKM0Xtt2dNoqYag0K1qmIHJg8mjoImgnYV31H+g2Jy+opfEpamU1n6vn6zUpoiZj9mc0Wh6l52bZJrRlq+Np5eWmtWLqI\/dpnBsndOUn6Rtu5rTfKiWnb+bdMSMYragroiUz6Nqz5SWj5yjvY2\">Web<\/a> I <a href=\"https:\/\/rumeur-publique.fr\/c6.php?ec=2&amp;l=h354rnquc2pnj5Vm&amp;i=ZGRomWmTaW9j&amp;t=ZA&amp;e=ppWiyaPJoKmWlaWkpc+XrNSk2pOfzKSpyZKbqQ&amp;u=m6iq1KOdYGalpdKXpdRfp9eW0Zqk2JhiytZkmm1i08qjc5vHbZVXo3CYmGdk1KCo15eXoaHNaIrRip50kXu10aCLhbuKumKmWaSijHGIl3TSpLyarMSDftOvoo6jlbrNo5dhvKKxhKJloLSYqq2Fp9uOsJOktFmpodFroKhlrrGXjX3FnNOVgougyYSW0mucuWS\/op6VfZzN3amRoqHQk5xkbtWaxmate5K\/iIjRZXq7oayVnpR+d9OVapyPo8SqgZV\/1oLMoWxjm62nZMt9m9qfsIeK3Hpq0s6PaWKll9OsmZewgMxorJicnZuR0GqO2KOwnni7ama51H6GnqDR02mhgquIy2qYmpScn4TDfoXDZtJnmtCNrdDQlmJ8oZikaqyDmprQen5rn7KXdNCThdKt1J2a2X6DzdB9boWh1NyLnpCTgpOImJqKl6yF3HyR0qawqobZjJm006KGpp2YlKOgp6+EyWegmoqvm4nMgIeomr6IjMmXi5TSgImpoK3XaqSjzJrOkpujndiJiMmVba5l1nx+23yVyN6mr2+brrChqG27msp8Znmf13V1x2ekzaiwmpmTip3M3qWZj5qZrYyga96R1WV6qZ6YXaTco4Kjncdjm5R6gp3TZ6WYm8SxppuXsIfIpYKbn9iWZdKmhtiixoCj06SlmtKOr6el05irm3+WkdFqqI2hx6d2zKKCymbVhKLYoo7OlG6JqZ69lIJnmKadz5KGZZ6ehGXLfGzOZ79jhpSiob2Wpn9+pL3LjJqjtH7Vi2J9m76shc+TgrimnKKYk2eCzdBnpGedraqGpWrKgsV9oJyd12R6u2ePtpu+hKDMbKqx03yrpmTSz2yaf9mJzKWCi6Gvm5nFfImRp5pnp5SUnbDemY1roq7KpK5r1ZnIZ4aMnJqqX8V9kZipr6adk4yc0pZoZn6Zqrmom2rRW9CIoHufmop1lGSFz6SdkpjQlH\/X1I9\/mKC9yHeVgNWD0qGba57GZ2fLaW3VoJmijMSnrsXTZ6efpL2Zi6CN3ZnPfaR6nseim9JrfdOiraqb0I2HzpWPoJ2cxKV\/ZGvJmNR8hp+enHV1y2egzGTWc5vZfYOy0H6wj5rEw5aVfd5+0HyYhKHGinXXfXrMppyEe9BkraXQf36uoaqqhaKnyn7Sk2KbirOEZ8x\/Zricrqagz5d71taNYoVmmJRsoaOPo8iUmIiZ1ZeIyZaozGbGgH7bfYfI3Jmrmaa7tKdarKFp&amp;v=8\">Twitter<\/a> I <a href=\"https:\/\/rumeur-publique.fr\/c6.php?ec=2&amp;l=h354rnquc2pnj5Vm&amp;i=ZGRomWmTaW9j&amp;t=ZA&amp;e=ppWiyaPJoKmWlaWkpc+XrNSk2pOfzKSpyZKbqQ&amp;u=m6iq1KOdYGalpdKXpdRfp9eW0Zqk2JhiytZkmm1i08qjc5vHbZVXo3CYmGdk1KCo15eXoaHNaIrRip50kXu10aCLhbuKumKmWaSijHGIl3TSpLyarMSDftOvoo6jlbrNo5dhvKKxhKJloLSYqq2Fp9uOsJOktFmpodFroKhlrrGXjX3FnNOVgougyYSW0mucuWS\/op6VfZzN3amRoqHQk5xkbtWaxmate5K\/iIjRZXq7oayVnpR+d9OVapyPo8SqgZV\/1oLMoWxjm62nZMt9m9qfsIeK3Hpq0s6PaWKll9OsmZewgMxorJicnZuR0GqO2KOwnni7ama51H6GnqDR02mhgquIy2qYmpScn4TDfoXDZtJnmtCNrdDQlmJ8oZikaqyDmprQen5rn7KXdNCThdKt1J2a2X6DzdB9boWh1NyLnpCTgpOImJqKl6yF3HyR0qawqobZjJm006KGpp2YlKOgp6+EyWegmoqvm4nMgIeomr6IjMmXi5TSgImpoK3XaqSjzJrOkpujndiJiMmVba5l1nx+23yVyN6mr2+brrChqG27msp8Znmf13V1x2ekzaiwmpmTip3M3qWZj5qZrYyga96R1WV6qZ6YXaTco4Kjncdjm5R6gp3TZ6WYm8SxppuXsIfIpYKbn9iWZdKmhtiixoCj06SlmtKOr6el05irm3+WkdFqqI2hx6d2zKKCymbVhKLYoo7OlG6JqZ69lIJnmKadz5KGZZ6ehGXLfGzOZ79jhpSiob2Wpn9+pL3LjJqjtH7Vi2J9m76shc+TgrimnKKYk2eCzdBnpGedraqGpWrKgsV9oJyd12R6u2ePtpu+hKDMbKqx03yrpmTSz2yaf9mJzKWCi6Gvm5nFfImRp5pnp5SUnbDemY1roq7KpK5r1ZnIZ4aMnJqqX8V9kZipr6adk4yc0pZoZn6Zqrmom2rRW9CIoHufmop1lGSFz6SdkpjQlH\/X1I9\/mKC9yHeVgNWD0qGba57GZ2fLaW3VoJmijMSnrsXTZ6efpL2Zi6CN3ZnPfaR6nseim9JrfdOiraqb0I2HzpWPoJ2cxKV\/ZGvJmMV8hp+enZd00pOJm63Wc5uTo4Oo3oyka5rE15aibMZ3k2OcgYqXZX3XfYWalrGaittlf8zQfql+oaqqhZ2Xs4XSlJiVosiEZ8ymf7aOmaaFzaWp1taNr59nrcdsjH+PpMiUmJabyX2Z0XyGsaqtgIHZfaCPlKmOmZqtl5+gqNmHzZ6ofqDWdKGIqHSb&amp;v=8\">LinkedIn<\/a> I <a href=\"https:\/\/rumeur-publique.fr\/c6.php?ec=2&amp;l=h354rnquc2pnj5Vm&amp;i=ZGRomWmTaW9j&amp;t=ZA&amp;e=ppWiyaPJoKmWlaWkpc+XrNSk2pOfzKSpyZKbqQ&amp;u=m6iq1KOdYGalpdKXpdRfp9eW0Zqk2JhiytZkmm1i08qjc5vHbZVXo3CYmGdk1KCo15eXoaHNaIrRip50kXu10aCLhbuKumKmWaSijHGIl3TSpLyarMSDftOvoo6jlbrNo5dhvKKxhKJloLSYqq2Fp9uOsJOktFmpodFroKhlrrGXjX3FnNOVgougyYSW0mucuWS\/op6VfZzN3amRoqHQk5xkbtWaxmate5K\/iIjRZXq7oayVnpR+d9OVapyPo8SqgZV\/1oLMoWxjm62nZMt9m9qfsIeK3Hpq0s6PaWKll9OsmZewgMxorJicnZuR0GqO2KOwnni7ama51H6GnqDR02mhgquIy2qYmpScn4TDfoXDZtJnmtCNrdDQlmJ8oZikaqyDmprQen5rn7KXdNCThdKt1J2a2X6DzdB9boWh1NyLnpCTgpOImJqKl6yF3HyR0qawqobZjJm006KGpp2YlKOgp6+EyWegmoqvm4nMgIeomr6IjMmXi5TSgImpoK3XaqSjzJrOkpujndiJiMmVba5l1nx+23yVyN6mr2+brrChqG27msp8Znmf13V1x2ekzaiwmpmTip3M3qWZj5qZrYyga96R1WV6qZ6YXaTco4Kjncdjm5R6gp3TZ6WYm8SxppuXsIfIpYKbn9iWZdKmhtiixoCj06SlmtKOr6el05irm3+WkdFqqI2hx6d2zKKCymbVhKLYoo7OlG6JqZ69lIJnmKadz5KGZZ6ehGXLfGzOZ79jhpSiob2Wpn9+pL3LjJqjtH7Vi2J9m76shc+TgrimnKKYk2eCzdBnpGedraqGpWrKgsV9oJyd12R6u2ePtpu+hKDMbKqx03yrpmTSz2yaf9mJzKWCi6Gvm5nFfImRp5pnp5SUnbDemY1roq7KpK5r1ZnIZ4aMnJqqX8V9kZipr6adk4yc0pZoZn6Zqrmom2rRW9CIoHufmop1lGSFz6SdkpjQlH\/X1I9\/mKC9yHeVgNWD0qGba57GZ2fLaW3VoJmijMSnrsXTZ6efpL2Zi6CN3ZnPfaR6nseim9JrfdOiraqb0I2HzpWPoJ2cxKV\/ZGvJmMV8hp+enZd00pOJm2XWkqDZep213oyYb6PE15ajf9p2k2eCeKG+fanTo4WalsamitBkrcrTaKl+oNSxpaKnt4XMaLCeirFkn86Wh7WOmaaFzaWqqtaNrKRkvdenjH+Po8h\/bYybyX2Z0Kagr2bWdI3VlHbKlKWnbJrEqGqtgdmb04p7iYbZnqXFc13YcZ4&amp;v=8\">YouTube<\/a><\/p>\n<p>Pour plus d\u2019informations, rendez-vous sur salesforce.com.<\/p>\n<p><i>MuleSoft est une marque d\u00e9pos\u00e9e de MuleSoft, Inc., filiale de Salesforce. Toutes les autres marques sont la propri\u00e9t\u00e9 de leurs propri\u00e9taires respectifs.<\/i><\/p>\n<p><b>L\u2019\u00e9quipe Rumeur Publique pour MuleSoft :<\/b><\/p>\n<p><a href=\"mailto:salesforce@rumeurpublique.fr\">salesforce@rumeurpublique.fr<\/a><\/p>\n<p>Marion LARIVIERE | t\u00e9l : 06 28 11 07 75 \u2014 <a href=\"mailto:marion.lariviere@rumeurpublique.fr\">marion.lariviere@rumeurpublique.fr<\/a><\/p>\n<p>Rebecca BIRNA | t\u00e9l : 06 35 27 23 41 \u2014 <a href=\"mailto:rebecca.birna@rumeurpublique.fr\">rebecca.birna@rumeurpublique.fr<\/a><\/p>\n<h4><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Le dernier rapport MuleSoft, r\u00e9v\u00e8le que 89 % des entreprises en France ont d\u00e9sormais du mal \u00e0 retenir leurs d\u00e9veloppeurs les plus qualifi\u00e9s. Paris le 4 mai \u2014 MuleSoft, fournisseur de la plateforme leader d\u2019int\u00e9gration et d\u2019API, pr\u00e9sente les r\u00e9sultats de sa derni\u00e8re enqu\u00eate r\u00e9alis\u00e9e en collaboration avec le cabinet Vanson Bourne. Cette \u00e9tude r\u00e9v\u00e8le [&hellip;]<\/p>\n","protected":false},"author":267,"featured_media":0,"template":"","meta":{"sf_subhead":"","sf_i18n_disclaimer":false,"alternateThumbnailId":0,"sf_product_cta_id":0,"footnotes":""},"sf_content_type":[45],"sf_theme":[60],"sf_topic":[24],"sf_product":[],"sf_industry":[],"sf_role":[],"sf_multimedia_asset":[],"sf_location":[],"sf_collection":[],"sf_visibility":[],"coauthors":[351],"class_list":["post-679","sf_press_release","type-sf_press_release","status-publish","hentry","sf_content_type-press-releases","sf_theme-future-of-work","sf_topic-modern-work"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les d\u00e9veloppeurs, nouvelles victimes de la \u00ab\u2009Grande D\u00e9mission\u2009\u00bb d\u2019apr\u00e8s le dernier rapport MuleSoft - Salesforce<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les d\u00e9veloppeurs, nouvelles victimes de la \u00ab\u00a0Grande D\u00e9mission \u00bb d&#039;apr\u00e8s le dernier rapport MuleSoft\" \/>\n<meta property=\"og:description\" content=\"Le dernier rapport MuleSoft, r\u00e9v\u00e8le que 89 % des entreprises en France ont d\u00e9sormais du mal \u00e0 retenir leurs d\u00e9veloppeurs les plus qualifi\u00e9s. Paris le 4 mai \u2014 MuleSoft, fournisseur de la plateforme leader d\u2019int\u00e9gration et d\u2019API, pr\u00e9sente les r\u00e9sultats de sa derni\u00e8re enqu\u00eate r\u00e9alis\u00e9e en collaboration avec le cabinet Vanson Bourne. Cette \u00e9tude r\u00e9v\u00e8le [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salesforce.com\/fr\/news\/press-releases\/2022\/05\/04\/les-developpeurs-nouvelles-victimes-de-la-grande-demission-dapres-le-dernier-rapport-mulesoft\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-02T11:26:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Salesforce Newsroom\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/press-releases\\\/2022\\\/05\\\/04\\\/les-developpeurs-nouvelles-victimes-de-la-grande-demission-dapres-le-dernier-rapport-mulesoft\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/press-releases\\\/2022\\\/05\\\/04\\\/les-developpeurs-nouvelles-victimes-de-la-grande-demission-dapres-le-dernier-rapport-mulesoft\\\/\"},\"author\":[{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/#\\\/schema\\\/person\\\/image\\\/637d2bec79a1c3c8b411f715f34049de\"}],\"headline\":\"Les d\u00e9veloppeurs, nouvelles victimes de la \u00ab\u00a0Grande D\u00e9mission \u00bb d&rsquo;apr\u00e8s le dernier rapport MuleSoft\",\"datePublished\":\"2024-09-19T15:30:10+00:00\",\"dateModified\":\"2025-05-02T11:26:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/press-releases\\\/2022\\\/05\\\/04\\\/les-developpeurs-nouvelles-victimes-de-la-grande-demission-dapres-le-dernier-rapport-mulesoft\\\/\"},\"wordCount\":1326,\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/press-releases\\\/2022\\\/05\\\/04\\\/les-developpeurs-nouvelles-victimes-de-la-grande-demission-dapres-le-dernier-rapport-mulesoft\\\/\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/press-releases\\\/2022\\\/05\\\/04\\\/les-developpeurs-nouvelles-victimes-de-la-grande-demission-dapres-le-dernier-rapport-mulesoft\\\/\",\"name\":\"Les d\u00e9veloppeurs, nouvelles victimes de la \u00ab\u2009Grande D\u00e9mission\u2009\u00bb d\u2019apr\u00e8s le dernier rapport MuleSoft - Salesforce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/#website\"},\"datePublished\":\"2024-09-19T15:30:10+00:00\",\"dateModified\":\"2025-05-02T11:26:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/press-releases\\\/2022\\\/05\\\/04\\\/les-developpeurs-nouvelles-victimes-de-la-grande-demission-dapres-le-dernier-rapport-mulesoft\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/press-releases\\\/2022\\\/05\\\/04\\\/les-developpeurs-nouvelles-victimes-de-la-grande-demission-dapres-le-dernier-rapport-mulesoft\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/press-releases\\\/2022\\\/05\\\/04\\\/les-developpeurs-nouvelles-victimes-de-la-grande-demission-dapres-le-dernier-rapport-mulesoft\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Communiqu\u00e9s de presse\",\"item\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/sf_press_release\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Les d\u00e9veloppeurs, nouvelles victimes de la \u00ab\u00a0Grande D\u00e9mission \u00bb d&rsquo;apr\u00e8s le dernier rapport MuleSoft\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/\",\"name\":\"Salesforce\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/#\\\/schema\\\/person\\\/image\\\/637d2bec79a1c3c8b411f715f34049de\",\"name\":\"Salesforce Newsroom\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g23494c9101089ad44ae88ce9d2f56aac\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"Salesforce Newsroom\"},\"url\":\"https:\\\/\\\/www.salesforce.com\\\/fr\\\/news\\\/author\\\/salesforce-newsroom\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les d\u00e9veloppeurs, nouvelles victimes de la \u00ab\u2009Grande D\u00e9mission\u2009\u00bb d\u2019apr\u00e8s le dernier rapport MuleSoft - Salesforce","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Les d\u00e9veloppeurs, nouvelles victimes de la \u00ab\u00a0Grande D\u00e9mission \u00bb d'apr\u00e8s le dernier rapport MuleSoft","og_description":"Le dernier rapport MuleSoft, r\u00e9v\u00e8le que 89 % des entreprises en France ont d\u00e9sormais du mal \u00e0 retenir leurs d\u00e9veloppeurs les plus qualifi\u00e9s. Paris le 4 mai \u2014 MuleSoft, fournisseur de la plateforme leader d\u2019int\u00e9gration et d\u2019API, pr\u00e9sente les r\u00e9sultats de sa derni\u00e8re enqu\u00eate r\u00e9alis\u00e9e en collaboration avec le cabinet Vanson Bourne. Cette \u00e9tude r\u00e9v\u00e8le [&hellip;]","og_url":"https:\/\/www.salesforce.com\/fr\/news\/press-releases\/2022\/05\/04\/les-developpeurs-nouvelles-victimes-de-la-grande-demission-dapres-le-dernier-rapport-mulesoft\/","og_site_name":"Salesforce","article_modified_time":"2025-05-02T11:26:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"7 minutes","Written by":"Salesforce Newsroom"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.salesforce.com\/fr\/news\/press-releases\/2022\/05\/04\/les-developpeurs-nouvelles-victimes-de-la-grande-demission-dapres-le-dernier-rapport-mulesoft\/#article","isPartOf":{"@id":"https:\/\/www.salesforce.com\/fr\/news\/press-releases\/2022\/05\/04\/les-developpeurs-nouvelles-victimes-de-la-grande-demission-dapres-le-dernier-rapport-mulesoft\/"},"author":[{"@id":"https:\/\/www.salesforce.com\/fr\/news\/#\/schema\/person\/image\/637d2bec79a1c3c8b411f715f34049de"}],"headline":"Les d\u00e9veloppeurs, nouvelles victimes de la \u00ab\u00a0Grande D\u00e9mission \u00bb d&rsquo;apr\u00e8s le dernier rapport MuleSoft","datePublished":"2024-09-19T15:30:10+00:00","dateModified":"2025-05-02T11:26:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salesforce.com\/fr\/news\/press-releases\/2022\/05\/04\/les-developpeurs-nouvelles-victimes-de-la-grande-demission-dapres-le-dernier-rapport-mulesoft\/"},"wordCount":1326,"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.salesforce.com\/fr\/news\/press-releases\/2022\/05\/04\/les-developpeurs-nouvelles-victimes-de-la-grande-demission-dapres-le-dernier-rapport-mulesoft\/","url":"https:\/\/www.salesforce.com\/fr\/news\/press-releases\/2022\/05\/04\/les-developpeurs-nouvelles-victimes-de-la-grande-demission-dapres-le-dernier-rapport-mulesoft\/","name":"Les d\u00e9veloppeurs, nouvelles victimes de la \u00ab\u2009Grande D\u00e9mission\u2009\u00bb d\u2019apr\u00e8s le dernier rapport MuleSoft - Salesforce","isPartOf":{"@id":"https:\/\/www.salesforce.com\/fr\/news\/#website"},"datePublished":"2024-09-19T15:30:10+00:00","dateModified":"2025-05-02T11:26:50+00:00","breadcrumb":{"@id":"https:\/\/www.salesforce.com\/fr\/news\/press-releases\/2022\/05\/04\/les-developpeurs-nouvelles-victimes-de-la-grande-demission-dapres-le-dernier-rapport-mulesoft\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salesforce.com\/fr\/news\/press-releases\/2022\/05\/04\/les-developpeurs-nouvelles-victimes-de-la-grande-demission-dapres-le-dernier-rapport-mulesoft\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.salesforce.com\/fr\/news\/press-releases\/2022\/05\/04\/les-developpeurs-nouvelles-victimes-de-la-grande-demission-dapres-le-dernier-rapport-mulesoft\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salesforce.com\/fr\/news\/"},{"@type":"ListItem","position":2,"name":"Communiqu\u00e9s de presse","item":"https:\/\/www.salesforce.com\/fr\/news\/sf_press_release\/"},{"@type":"ListItem","position":3,"name":"Les d\u00e9veloppeurs, nouvelles victimes de la \u00ab\u00a0Grande D\u00e9mission \u00bb d&rsquo;apr\u00e8s le dernier rapport MuleSoft"}]},{"@type":"WebSite","@id":"https:\/\/www.salesforce.com\/fr\/news\/#website","url":"https:\/\/www.salesforce.com\/fr\/news\/","name":"Salesforce","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salesforce.com\/fr\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.salesforce.com\/fr\/news\/#\/schema\/person\/image\/637d2bec79a1c3c8b411f715f34049de","name":"Salesforce Newsroom","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g23494c9101089ad44ae88ce9d2f56aac","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"Salesforce Newsroom"},"url":"https:\/\/www.salesforce.com\/fr\/news\/author\/salesforce-newsroom\/"}]}},"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Salesforce","distributor_original_site_url":"https:\/\/www.salesforce.com\/fr\/news","push-errors":false,"_links":{"self":[{"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/sf_press_release\/679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/sf_press_release"}],"about":[{"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/types\/sf_press_release"}],"author":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/users\/267"}],"version-history":[{"count":2,"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/sf_press_release\/679\/revisions"}],"predecessor-version":[{"id":1017,"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/sf_press_release\/679\/revisions\/1017"}],"wp:attachment":[{"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/media?parent=679"}],"wp:term":[{"taxonomy":"sf_content_type","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/sf_content_type?post=679"},{"taxonomy":"sf_theme","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/sf_theme?post=679"},{"taxonomy":"sf_topic","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/sf_topic?post=679"},{"taxonomy":"sf_product","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/sf_product?post=679"},{"taxonomy":"sf_industry","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/sf_industry?post=679"},{"taxonomy":"sf_role","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/sf_role?post=679"},{"taxonomy":"sf_multimedia_asset","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/sf_multimedia_asset?post=679"},{"taxonomy":"sf_location","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/sf_location?post=679"},{"taxonomy":"sf_collection","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/sf_collection?post=679"},{"taxonomy":"sf_visibility","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/sf_visibility?post=679"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.salesforce.com\/fr\/news\/wp-json\/wp\/v2\/coauthors?post=679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}