{"id":191,"count":3,"description":"","link":"https:\/\/www.salesforce.com\/il\/blog\/category\/mulesoft\/","name":"Mulesoft","slug":"mulesoft","taxonomy":"sf_topic","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mulesoft Archives &#8212; Salesforce<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salesforce.com\/il\/blog\/category\/mulesoft\/\" \/>\n<meta property=\"og:locale\" content=\"he_IL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mulesoft Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salesforce.com\/il\/blog\/category\/mulesoft\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salesforce.com\/il\/blog\/wp-content\/uploads\/sites\/16\/2023\/12\/Salesforce-logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"4000\" \/>\n\t<meta property=\"og:image:height\" content=\"2250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/il\\\/blog\\\/category\\\/mulesoft\\\/\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/il\\\/blog\\\/category\\\/mulesoft\\\/\",\"name\":\"Mulesoft Archives &#8212; Salesforce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/il\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/il\\\/blog\\\/category\\\/mulesoft\\\/#breadcrumb\"},\"inLanguage\":\"he-IL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/il\\\/blog\\\/category\\\/mulesoft\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.salesforce.com\\\/il\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mulesoft\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/il\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/il\\\/blog\\\/\",\"name\":\"Salesforce\",\"description\":\"\u05d7\u05d3\u05e9\u05d5\u05ea, \u05d8\u05d9\u05e4\u05d9\u05dd \u05d5\u05ea\u05d5\u05d1\u05e0\u05d5\u05ea \u05e9\u05dc \u05de\u05e0\u05d4\u05d9\u05d2\u05d9 \u05d4\u05e2\u05e0\u05df \u05d4\u05e2\u05d5\u05dc\u05de\u05d9\u05d9\u05dd\",\"alternateName\":\"Salesforce\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salesforce.com\\\/il\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"he-IL\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mulesoft Archives &#8212; Salesforce","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salesforce.com\/il\/blog\/category\/mulesoft\/","og_locale":"he_IL","og_type":"article","og_title":"Mulesoft Archives","og_url":"https:\/\/www.salesforce.com\/il\/blog\/category\/mulesoft\/","og_site_name":"Salesforce","og_image":[{"width":4000,"height":2250,"url":"https:\/\/www.salesforce.com\/il\/blog\/wp-content\/uploads\/sites\/16\/2023\/12\/Salesforce-logo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.salesforce.com\/il\/blog\/category\/mulesoft\/","url":"https:\/\/www.salesforce.com\/il\/blog\/category\/mulesoft\/","name":"Mulesoft Archives &#8212; Salesforce","isPartOf":{"@id":"https:\/\/www.salesforce.com\/il\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.salesforce.com\/il\/blog\/category\/mulesoft\/#breadcrumb"},"inLanguage":"he-IL"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salesforce.com\/il\/blog\/category\/mulesoft\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salesforce.com\/il\/blog\/"},{"@type":"ListItem","position":2,"name":"Mulesoft"}]},{"@type":"WebSite","@id":"https:\/\/www.salesforce.com\/il\/blog\/#website","url":"https:\/\/www.salesforce.com\/il\/blog\/","name":"Salesforce","description":"\u05d7\u05d3\u05e9\u05d5\u05ea, \u05d8\u05d9\u05e4\u05d9\u05dd \u05d5\u05ea\u05d5\u05d1\u05e0\u05d5\u05ea \u05e9\u05dc \u05de\u05e0\u05d4\u05d9\u05d2\u05d9 \u05d4\u05e2\u05e0\u05df \u05d4\u05e2\u05d5\u05dc\u05de\u05d9\u05d9\u05dd","alternateName":"Salesforce","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salesforce.com\/il\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"he-IL"}]}},"_links":{"self":[{"href":"https:\/\/www.salesforce.com\/il\/blog\/wp-json\/wp\/v2\/sf_topic\/191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salesforce.com\/il\/blog\/wp-json\/wp\/v2\/sf_topic"}],"about":[{"href":"https:\/\/www.salesforce.com\/il\/blog\/wp-json\/wp\/v2\/taxonomies\/sf_topic"}],"wp:post_type":[{"href":"https:\/\/www.salesforce.com\/il\/blog\/wp-json\/wp\/v2\/media?sf_topic=191"},{"href":"https:\/\/www.salesforce.com\/il\/blog\/wp-json\/wp\/v2\/posts?sf_topic=191"},{"href":"https:\/\/www.salesforce.com\/il\/blog\/wp-json\/wp\/v2\/pages?sf_topic=191"},{"href":"https:\/\/www.salesforce.com\/il\/blog\/wp-json\/wp\/v2\/sf_linked_content?sf_topic=191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}