{"id":3753,"date":"2024-11-06T09:30:00","date_gmt":"2024-11-06T07:30:00","guid":{"rendered":"https:\/\/www.salesforce.com\/?p=3753"},"modified":"2024-11-05T13:03:37","modified_gmt":"2024-11-05T11:03:37","slug":"sales-pipeline-review","status":"publish","type":"post","link":"https:\/\/www.salesforce.com\/it\/blog\/sales-pipeline-review\/","title":{"rendered":"I riesami della pipeline sono un incubo: ecco 10 facili modi per migliorarli"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Il leader di vendita Richard Harris, che si autodefinisce &#8220;da vecchia a nuova scuola&#8221;, ricorda la prima volta in cui qualcuno si \u00e8 licenziato. &#8220;Nessuna lettera di dimissioni, se n&#8217;\u00e8 andata e basta.&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il motivo? Una serie di faticose riunioni per il riesame della pipeline.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Durante i riesami, io chiedevo X e lei mi dava Y. Aveva un percorso tutto suo per concludere le trattative, ma non mi sono mai preso il tempo per capire il suo procedimento,&#8221; ci ha raccontato <a href=\"https:\/\/www.linkedin.com\/in\/rharris415\" target=\"_blank\" rel=\"noreferrer noopener\">Harris<\/a>, che ora \u00e8 a capo di Harris Consulting Group, un&#8217;azienda di formazione post vendita molto richiesta. &#8220;Un giorno se n&#8217;\u00e8 andata dalla frustrazione.&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Se un efficace riesame della pipeline identifica i modi in cui i rappresentanti possono far progredire le trattative, spesso capita che queste revisioni falliscano miseramente.<\/strong> I motivi sono infiniti \u2014 scarsa qualit\u00e0 dei dati di vendita, obiettivi disallineati, mancanza di preparazione, incomprensioni a livello di comunicazione, capacit\u00e0 di gestione mediocri \u2014 ma con un riesame produttivo della pipeline come base di un&#8217;accurata previsione aziendale, \u00e8 fondamentale che i team di vendita svolgano questi riesami nel modo giusto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Qui di seguito condividiamo <strong>nove tecniche dimostrate per correggere le riunioni sulla pipeline e preparare i tuoi rappresentanti al successo. <\/strong>Scoprirai come usare l&#8217;AI per vedere il futuro, concentrarsi sulle principali priorit\u00e0 e costruire una conversazione continua che sia un win-win per te e per i tuoi venditori.<\/p>\n\n\n\n<div class=\"layout-seven wp-block-salesforce-blog-offer\">\n\t<div class=\"wp-block-offer__wrapper\">\n\n\t\t<div class=\"wp-block-offer__content\">\n\t\t\t<h2 class=\"wp-block-offer__title\">Scopri 7 modi in cui i rappresentanti possono usare l&#8217;AI per migliorare le vendite<\/h2>\n\t\t\t\t\t\t\t<p class=\"wp-block-offer__description\">Vedi esempi concreti di come usare l&#8217;AI per vendere, dall&#8217;automazione della ricerca di potenziali clienti alla scrittura di e-mail, insieme a indicazioni in tempo reale.<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t<a class=\"wp-block-button__link\" target=\"_blank\" href=\"https:\/\/www.salesforce.com\/it\/form\/sales\/sales-ai-playbook\/\">Scarica l&#039;e-book gratuito<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"wp-block-offer__media\">\n\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wp-block-offer__graphics wp-block-offer__contour\"><\/div>\n\t\n\t\t\t<!-- Standard Illustration -->\n\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__illustration\" src=\"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-illustration-layout-seven.png\" alt=\"\">\n\n\t\t<!-- Small Accent Illustration -->\n\t\t\n\t\t<!-- Left Side Illustration -->\n\t\t\n\t\t<!-- Cloud Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__cloud\" src=\"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-cloud-layout-seven.png\" alt=\"\">\n\t\t\n\t<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-che-cos-e-un-riesame-della-pipeline\">Che cos&#8217;\u00e8 un riesame della pipeline?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Un riesame della pipeline \u00e8 <strong>una riunione che si svolge una volta alla settimana o due volte al mese tra un rappresentante di vendita e un manager per discutere lo stato delle trattative in sospeso. <\/strong>Queste riunioni si concentrano unicamente su ci\u00f2 che ostacola la conclusione delle trattative e sulle misure che il rappresentante o il manager possono adottare per rimuovere questi ostacoli.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-come-effettuare-un-miglior-riesame-della-pipeline-in-10-passi\">Come effettuare un miglior riesame della pipeline in 10 passi<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">I leader di vendita e i CRO possono effettuare migliori riesami della pipeline assumendosi la responsabilit\u00e0 di migliorare la struttura e la cadenza di queste riunioni fondamentali e assicurandosi che i rappresentanti abbiano ci\u00f2 di cui hanno bisogno per far progredire le trattative e raggiungere i propri obiettivi. Di seguito condividiamo <strong>le nove azioni pi\u00f9 importanti da adottare per rendere pi\u00f9 utili ed efficienti i riesami della pipeline.\u00a0<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-1-annulla-i-riesami-della-pipeline-che-coinvolgono-tutto-il-team\">1. Annulla i riesami della pipeline che coinvolgono tutto il team<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">I riesami della pipeline in gruppo sono quasi sempre una perdita di tempo. Alcuni manager pensano che sia il modo migliore per offrire coaching agli altri, esaminando la trattativa bloccata di un rappresentante e usandola come punto di riferimento o come lezione per tutto il team. Ma <strong>la verit\u00e0 \u00e8 che i rappresentanti non prestano attenzione.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I riesami delle pipeline devono coinvolgere i singoli rappresentanti e il manager. Questo fa s\u00ec che entrambi rimangano concentrati sulle trattative realmente importanti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C&#8217;\u00e8 un&#8217;eccezione: <strong>quando pi\u00f9 rappresentanti sono coinvolti in una vendita, i manager devono riunirli per collaborare alla strategia e alla risoluzione dei problemi.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-2-semplifica-la-manutenzione-della-pipeline-con-l-automazione\">2. Semplifica la manutenzione della pipeline con l&#8217;automazione<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">I riesami della pipeline sono pi\u00f9 efficaci quando i manager e i rappresentanti possono fare riferimento agli stessi <a href=\"https:\/\/www.salesforce.com\/it\/blog\/ai-basata-sui-dati\/\" target=\"_blank\" rel=\"noreferrer noopener\">dati di vendita affidabili<\/a> (dati di alta qualit\u00e0, accurati e tempestivi). La sfida \u00e8 proprio arrivare a questi dati: <strong>i rappresentanti spesso sono troppo impegnati per aggiornare il loro strumento di gestione delle relazioni con i clienti<\/strong> (<a href=\"https:\/\/www.salesforce.com\/it\/learning-centre\/crm\/what-is-crm\/\" target=\"_blank\" rel=\"noreferrer noopener\">CRM<\/a>) perch\u00e9 alcuni ancora richiedono l&#8217;inserimento manuale dei dati. Le lacune che ne conseguono rendono difficile\u00a0valutare lo stato dei lead nella pipeline. La soluzione \u00e8 una combinazione di automazione dei processi e formazione aggiornata per il team.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per aiutare i rappresentanti, p<strong>uoi implementare CRM potenziati dall&#8217;intelligenza artificiale con workflow automatizzati che riducono al minimo l&#8217;inserimento manuale dei dati<\/strong>. <a href=\"https:\/\/www.salesforce.com\/it\/products\/sales-cloud\/overview\/\" target=\"_blank\" rel=\"noreferrer noopener\">Sales Cloud<\/a>, per esempio, registra automaticamente tutte le tue telefonate, le tue e-mail e i tuoi appunti cos\u00ec non dovrai farlo tu e sincronizza questi dati a ogni nuova interazione con il cliente, per darti la certezza che i dati siano sempre aggiornati.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I rappresentanti, per\u00f2, devono comunque inserire alcuni dati. Assicurati di istruirli ad aggiornare le informazioni critiche sulle trattative appena le ricevono. Avranno anche bisogno di frequenti promemoria, quindi <strong>invita i manager a controllare regolarmente che l&#8217;inserimento dei dati venga svolto.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-3-usa-l-ai-per-vedere-il-futuro-della-tua-pipeline\">3. Usa l&#8217;AI per vedere il futuro della tua pipeline<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Uno dei superpoteri dell&#8217;AI \u00e8 fare previsioni accurate, e uno degli obiettivi fondamentali di un riesame della pipeline \u00e8 prevedere in modo accurato i risultati di ogni trattativa. Per questo l&#8217;AI e il riesame della pipeline sono una coppia perfetta.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>L&#8217;AI, integrata nel tuo CRM, pu\u00f2 studiare l&#8217;enorme volume di dati sulle trattative nella tua pipeline<\/strong> e inviarti un elenco di classificazione dei lead basato sulla probabilit\u00e0 di conclusione. Per esempio, <a href=\"https:\/\/www.salesforce.com\/it\/sales\/artificial-intelligence\/\" target=\"_blank\" rel=\"noreferrer noopener\">Einstein di Sales Cloud<\/a> fornisce una classificazione predittiva dei lead nella tua pipeline, che ti aiuta ad avere conversazioni mirate durante il riesame della pipeline. Puoi rivedere i lead col punteggio pi\u00f9 alto e assegnare loro priorit\u00e0, ed esaminare le motivazioni negative dei punteggi pi\u00f9 bassi per rimuovere gli ostacoli che bloccano le trattative.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-4-elimina-le-chiacchiere\">4. Elimina le chiacchiere<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Responsabili e manager spesso cedono alla tentazione di partire per la tangente durante il riesame della pipeline, ma questo non \u00e8 un momento adatto a chiacchiere inutili o discussioni approfondite sulla strategia. Non \u00e8 nemmeno il momento adatto a moduli di formazione, sessioni estese di coaching o aggiornamenti sull&#8217;azienda. <strong>Concentrati sui lead e non far durare il riesame pi\u00f9 di 30 minuti.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se i manager devono condividere informazioni con i rappresentanti, possono farlo tramite e-mail o Slack. Questo non solo lascia una traccia consultabile, ma i rappresentanti possono leggere i messaggi quando hanno tempo, al di fuori di discussioni mirate sui lead.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-5-suddividi-il-tempo-delle-riunioni-tra-le-tre-maggiori-opportunita\">5. Suddividi il tempo delle riunioni tra le tre maggiori opportunit\u00e0<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Concentrarsi su un solo lead problematico per l&#8217;intera riunione \u00e8 allettante, ma cos\u00ec altri lead non verranno discussi. Per evitare che questo accada, <strong>i veterani delle vendite come Harris consigliano di creare un programma chiaro<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>4 minuti: Panoramica\/stato generale<\/li>\n\n\n\n<li>7 minuti: Riesame del lead problematico #1<\/li>\n\n\n\n<li>7 minuti: Riesame del lead problematico #2<\/li>\n\n\n\n<li>7 minuti: Riesame del lead problematico #3<\/li>\n\n\n\n<li>5 minuti: Conclusione e identificazione delle azioni da intraprendere<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Per non sprecare tempo, assicurati che i rappresentanti e i manager esaminino le stesse metriche sui lead, idealmente dalla stessa dashboard CRM.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-6-definisci-criteri-di-uscita-per-ogni-fase-della-pipeline\">6. Definisci criteri di uscita per ogni fase della pipeline<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A causare una pipeline confusa non sono solo i dati sporchi. <strong>In troppi casi i rappresentanti non sanno quando un lead dovrebbe passare da una fase alla successiva nella pipeline.<\/strong> Questo, naturalmente, rende nebulosi i riesami della pipeline; manager e rappresentanti finiscono per avere idee molto diverse sullo stato dei lead in un dato momento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tronca questo problema sul nascere definendo con chiarezza in che modo il rappresentante pu\u00f2 concludere ciascuna fase della pipeline. Come ho imparato da esperti del settore vendite, <strong>il miglior approccio \u00e8 stilare due o tre domande per ciascuna fase.<\/strong> Le risposte dovrebbero indicare chiaramente se un lead \u00e8 pronto a progredire nella pipeline o meno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per esempio, per muovere un lead dalla fase di qualificazione a quella di demo, i rappresentanti dovrebbero fare domande come:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Il lead ha articolato un caso d&#8217;uso chiaro per il prodotto nella sua azienda?<\/li>\n\n\n\n<li>L&#8217;azienda soddisfa i requisiti tecnici necessari per l&#8217;uso di questo prodotto?<\/li>\n\n\n\n<li>Il prodotto rientra nel budget aziendale?<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Se la risposta a tutte e tre le domande \u00e8 &#8220;s\u00ec&#8221;, il lead \u00e8 probabilmente pronto per una demo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-7-identifica-con-chiarezza-azioni-da-intraprendere-e-priorita\">7. Identifica con chiarezza azioni da intraprendere e priorit\u00e0<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Come abbiamo detto prima, <strong>ogni riesame della pipeline dovrebbe concentrarsi su azioni da intraprendere per la settimana a venire<\/strong>, non su cosa \u00e8 successo la settimana prima. Per esempio: quali sono gli ostacoli specifici che impediscono a una trattativa di progredire? Chi affronter\u00e0 ciascun ostacolo: il rappresentante, il manager o la dirigenza? Qual \u00e8 il pi\u00f9 importante? Sono aspetti che devono essere definiti con chiarezza e allineati alle metriche, cos\u00ec che manager e rappresentanti possano misurare il progresso.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-8-crea-un-meccanismo-di-responsabilita-per-rappresentanti-e-manager\">8. Crea un meccanismo di responsabilit\u00e0 per rappresentanti e manager<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Una delle principali trappole dei riesami della pipeline \u00e8 la mancanza di responsabilit\u00e0, tanto per i rappresentanti quanto per i manager. Per garantire un follow-up sulle azioni da intraprendere, assicurati che i manager contattino i rappresentanti tramite telefono o e-mail alla fine della settimana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Un&#8217;altra opzione \u00e8 usare un CRM per tenere traccia dei progressi. <\/strong>Questa unica fonte di informazioni offre ai manager la visibilit\u00e0 sulle attivit\u00e0 dei rappresentanti, semplificando il follow-up con domande critiche sui lead che non stanno progredendo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"576\" width=\"1024\" src=\"https:\/\/www.salesforce.com\/blog\/wp-content\/uploads\/sites\/2\/2021\/06\/sales-pipeline-review-PipelineInspection.jpg?w=1600\" alt=\"Schermata di Ispezione opportunit\u00e0 in corso di realizzazione di Sales Cloud\" class=\"wp-image-3755\" srcset=\"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2021\/06\/sales-pipeline-review-PipelineInspection.jpg 1600w, https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2021\/06\/sales-pipeline-review-PipelineInspection.jpg?w=300&amp;h=169 300w, https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2021\/06\/sales-pipeline-review-PipelineInspection.jpg?w=768&amp;h=432 768w, https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2021\/06\/sales-pipeline-review-PipelineInspection.jpg?w=1024&amp;h=576 1024w, https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2021\/06\/sales-pipeline-review-PipelineInspection.jpg?w=1536&amp;h=864 1536w, https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2021\/06\/sales-pipeline-review-PipelineInspection.jpg?w=150&amp;h=84 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Un CRM permette ai responsabili e ai manager di tenere facilmente traccia dello stato dei lead nella pipeline<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-9-evita-lo-scaricabarile\">9. Evita lo scaricabarile<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A causa della forte pressione a concludere le trattative e incrementare il fatturato, durante i riesami della pipeline molti manager pongono domande tendenziose per ottenere le risposte che vogliono. Quando i rappresentanti farfugliano, insicuri di come spingere i lead verso una vendita, i manager sono pronti all&#8217;attacco. Viene affibbiata la colpa e i rappresentanti sono frustrati.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Questa ricerca di un colpevole \u00e8 una perdita di tempo. <strong>I manager dovrebbero dare ai riesami della pipeline un taglio diverso per evitare che questo accada: i problemi sono nelle opportunit\u00e0<\/strong>, non da imputare ai rappresentanti. Invece di strigliare i venditori per non aver raggiunto le quote o dato ai manager le risposte che volevano, pensa a soluzioni orientate al team. I manager dovrebbero evitare domande del tipo: &#8220;Come hai fatto a sbagliare?&#8221; e chiedere piuttosto: &#8220;Cosa possiamo fare per far funzionare la cosa?&#8221;.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-10-scagliona-gli-incontri-individuali-e-i-riesami-della-pipeline\">10. Scagliona gli incontri individuali e i riesami della pipeline<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Questo consiglio deriva da un fraintendimento comune, ovvero che gli <a href=\"https:\/\/www.salesforce.com\/resources\/articles\/sales-manager-checklist-successful-rep-one-on-ones\/\" target=\"_blank\" rel=\"noopener nofollow\">incontri individuali con il manager<\/a> siano anche riesami della pipeline. Sbagliato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gli incontri e i riesami della pipeline devono essere programmati separatamente e scaglionati per evitare una sovrabbondanza di riunioni. <strong>Consiglio di svolgere due incontri individuali con il manager al mese e due riesami della pipeline al mese.<\/strong> Se necessario, puoi aggiungere pi\u00f9 riesami verso la fine del trimestre per assicurarti che le trattative progrediscano secondo i piani. Se la priorit\u00e0 \u00e8 questa, non programmare incontri individuali che vadano in conflitto con questo obiettivo. Dai ai rappresentanti il tempo di concentrarsi su quello che sanno fare meglio: vendere.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-fasi-successive\">Fasi successive<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">I riesami della pipeline sono al centro di un team di vendita coinvolto e orientato ai risultati. Danno ai rappresentanti gli strumenti e gli insight di cui hanno bisogno per concludere le trattative e permettono ai manager di creare previsioni accurate. Per assicurarti che abbiano successo, i riesami devono essere fruibili e mirati. Il consiglio di Brian Bachofner, il nostro VP di Product Marketing, \u00e8: &#8220;Identifica le attivit\u00e0 chiave che faranno progredire le trattative. Questo aumenter\u00e0 la salute della pipeline, la precisione delle previsioni e la probabilit\u00e0 di raggiungere \u2014 o superare \u2014 le quote.&#8221;<\/p>\n\n\n\n<div class=\"layout-four wp-block-salesforce-blog-offer\">\n\t<div class=\"wp-block-offer__wrapper\">\n\n\t\t<div class=\"wp-block-offer__content\">\n\t\t\t<h2 class=\"wp-block-offer__title\">Vuoi fare una prova con il numero uno dei CRM?<\/h2>\n\t\t\t\t\t\t\t<p class=\"wp-block-offer__description\">Fai il nostro Tour guidato per vedere come Sales Cloud aumenta la produttivit\u00e0 in ogni fase del ciclo di vendita con l&#8217;aiuto dell&#8217;AI.\u00a0<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t<a class=\"wp-block-button__link\" target=\"_blank\" href=\"https:\/\/www.salesforce.com\/it\/form\/conf\/testdrive\/\">Fai il tour gratuito<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"wp-block-offer__media\">\n\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\n\t\t\t<!-- Standard Illustration -->\n\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__illustration\" src=\"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-illustration-layout-four.png\" alt=\"\">\n\n\t\t<!-- Small Accent Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__accent\" src=\"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-accent-layout-four.png\" alt=\"\">\n\t\t\n\t\t<!-- Left Side Illustration -->\n\t\t\n\t\t<!-- Cloud Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__cloud\" src=\"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-cloud-layout-four.png\" alt=\"\">\n\t\t\n\t<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le riunioni sulla pipeline possono spesso essere estenuanti per rappresentanti e manager. Ma non devono esserlo per forza. Ecco come risolvere gli errori pi\u00f9 comuni nelle riunioni sulla pipeline.<\/p>\n","protected":false},"author":179,"featured_media":3754,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sf_justforyou_enable_alt":true,"optimizely_content_id":"73920b5c57dd4462b16360f6863d80ab","post_meta_title":"","ai_synopsis":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"sf_topic":[972,12,971,11,1220],"sf_content_type":[],"blog":[],"coauthors":[2],"class_list":["post-3753","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","sf_topic-salesblazer","sf_topic-sales-cloud","sf_topic-sales-strategy-2","sf_topic-sales","sf_topic-employee-experience"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Riunioni di riesame della pipeline pi\u00f9 produttivi | Salesforce<\/title>\n<meta name=\"description\" content=\"Le riunioni sulla pipeline sono spesso estenuanti. Ma non devono esserlo per forza. Ecco come risolvere gli errori pi\u00f9 comuni.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salesforce.com\/it\/blog\/sales-pipeline-review\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I riesami della pipeline sono un incubo: ecco 10 facili modi per migliorarli\" \/>\n<meta property=\"og:description\" content=\"Le riunioni sulla pipeline sono spesso estenuanti. Ma non devono esserlo per forza. Ecco come risolvere gli errori pi\u00f9 comuni.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salesforce.com\/it\/blog\/sales-pipeline-review\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-06T07:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2023\/03\/Sales-Pipeline-Review.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"844\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Salesforce Italia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Salesforce Italia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minuti\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Salesforce Italia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/sales-pipeline-review\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/sales-pipeline-review\\\/\"},\"author\":[{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/#\\\/schema\\\/person\\\/image\\\/d74bba174b633a02c1daa27bf350774f\"}],\"headline\":\"I riesami della pipeline sono un incubo: ecco 10 facili modi per migliorarli\",\"datePublished\":\"2024-11-06T07:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/sales-pipeline-review\\\/\"},\"wordCount\":1771,\"publisher\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/sales-pipeline-review\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2023\\\/03\\\/Sales-Pipeline-Review.jpg\",\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/sales-pipeline-review\\\/\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/sales-pipeline-review\\\/\",\"name\":\"Riunioni di riesame della pipeline pi\u00f9 produttivi | Salesforce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/sales-pipeline-review\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/sales-pipeline-review\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2023\\\/03\\\/Sales-Pipeline-Review.jpg\",\"datePublished\":\"2024-11-06T07:30:00+00:00\",\"description\":\"Le riunioni sulla pipeline sono spesso estenuanti. Ma non devono esserlo per forza. Ecco come risolvere gli errori pi\u00f9 comuni.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/sales-pipeline-review\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/sales-pipeline-review\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/sales-pipeline-review\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2023\\\/03\\\/Sales-Pipeline-Review.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2023\\\/03\\\/Sales-Pipeline-Review.jpg\",\"width\":1500,\"height\":844,\"caption\":\"Magnifying glass over a pipeline with prospects pouring in: pipeline review\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/sales-pipeline-review\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I riesami della pipeline sono un incubo: ecco 10 facili modi per migliorarli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/\",\"name\":\"Salesforce\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/#organization\",\"name\":\"Salesforce\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2023\\\/09\\\/Salesforce.webp\",\"contentUrl\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2023\\\/09\\\/Salesforce.webp\",\"width\":1200,\"height\":630,\"caption\":\"Salesforce\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/#\\\/schema\\\/person\\\/image\\\/d74bba174b633a02c1daa27bf350774f\",\"name\":\"Salesforce Italia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g23494c9101089ad44ae88ce9d2f56aac\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"Salesforce Italia\"},\"url\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/author\\\/salesforceitalia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Riunioni di riesame della pipeline pi\u00f9 produttivi | Salesforce","description":"Le riunioni sulla pipeline sono spesso estenuanti. Ma non devono esserlo per forza. Ecco come risolvere gli errori pi\u00f9 comuni.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salesforce.com\/it\/blog\/sales-pipeline-review\/","og_locale":"it_IT","og_type":"article","og_title":"I riesami della pipeline sono un incubo: ecco 10 facili modi per migliorarli","og_description":"Le riunioni sulla pipeline sono spesso estenuanti. Ma non devono esserlo per forza. Ecco come risolvere gli errori pi\u00f9 comuni.","og_url":"https:\/\/www.salesforce.com\/it\/blog\/sales-pipeline-review\/","og_site_name":"Salesforce","article_published_time":"2024-11-06T07:30:00+00:00","og_image":[{"width":1500,"height":844,"url":"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2023\/03\/Sales-Pipeline-Review.jpg","type":"image\/jpeg"}],"author":"Salesforce Italia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Salesforce Italia","Tempo di lettura stimato":"10 minuti","Written by":"Salesforce Italia"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salesforce.com\/it\/blog\/sales-pipeline-review\/#article","isPartOf":{"@id":"https:\/\/www.salesforce.com\/it\/blog\/sales-pipeline-review\/"},"author":[{"@id":"https:\/\/www.salesforce.com\/it\/blog\/#\/schema\/person\/image\/d74bba174b633a02c1daa27bf350774f"}],"headline":"I riesami della pipeline sono un incubo: ecco 10 facili modi per migliorarli","datePublished":"2024-11-06T07:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salesforce.com\/it\/blog\/sales-pipeline-review\/"},"wordCount":1771,"publisher":{"@id":"https:\/\/www.salesforce.com\/it\/blog\/#organization"},"image":{"@id":"https:\/\/www.salesforce.com\/it\/blog\/sales-pipeline-review\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2023\/03\/Sales-Pipeline-Review.jpg","inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.salesforce.com\/it\/blog\/sales-pipeline-review\/","url":"https:\/\/www.salesforce.com\/it\/blog\/sales-pipeline-review\/","name":"Riunioni di riesame della pipeline pi\u00f9 produttivi | Salesforce","isPartOf":{"@id":"https:\/\/www.salesforce.com\/it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salesforce.com\/it\/blog\/sales-pipeline-review\/#primaryimage"},"image":{"@id":"https:\/\/www.salesforce.com\/it\/blog\/sales-pipeline-review\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2023\/03\/Sales-Pipeline-Review.jpg","datePublished":"2024-11-06T07:30:00+00:00","description":"Le riunioni sulla pipeline sono spesso estenuanti. Ma non devono esserlo per forza. Ecco come risolvere gli errori pi\u00f9 comuni.","breadcrumb":{"@id":"https:\/\/www.salesforce.com\/it\/blog\/sales-pipeline-review\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salesforce.com\/it\/blog\/sales-pipeline-review\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.salesforce.com\/it\/blog\/sales-pipeline-review\/#primaryimage","url":"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2023\/03\/Sales-Pipeline-Review.jpg","contentUrl":"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2023\/03\/Sales-Pipeline-Review.jpg","width":1500,"height":844,"caption":"Magnifying glass over a pipeline with prospects pouring in: pipeline review"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salesforce.com\/it\/blog\/sales-pipeline-review\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salesforce.com\/it\/blog\/"},{"@type":"ListItem","position":2,"name":"I riesami della pipeline sono un incubo: ecco 10 facili modi per migliorarli"}]},{"@type":"WebSite","@id":"https:\/\/www.salesforce.com\/it\/blog\/#website","url":"https:\/\/www.salesforce.com\/it\/blog\/","name":"Salesforce","description":"","publisher":{"@id":"https:\/\/www.salesforce.com\/it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salesforce.com\/it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.salesforce.com\/it\/blog\/#organization","name":"Salesforce","url":"https:\/\/www.salesforce.com\/it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.salesforce.com\/it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2023\/09\/Salesforce.webp","contentUrl":"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2023\/09\/Salesforce.webp","width":1200,"height":630,"caption":"Salesforce"},"image":{"@id":"https:\/\/www.salesforce.com\/it\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.salesforce.com\/it\/blog\/#\/schema\/person\/image\/d74bba174b633a02c1daa27bf350774f","name":"Salesforce Italia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g23494c9101089ad44ae88ce9d2f56aac","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"Salesforce Italia"},"url":"https:\/\/www.salesforce.com\/it\/blog\/author\/salesforceitalia\/"}]}},"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Salesforce","distributor_original_site_url":"https:\/\/www.salesforce.com\/it\/blog","push-errors":false,"jetpack_featured_media_url":"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2023\/03\/Sales-Pipeline-Review.jpg","_links":{"self":[{"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/posts\/3753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/users\/179"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/comments?post=3753"}],"version-history":[{"count":4,"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/posts\/3753\/revisions"}],"predecessor-version":[{"id":3853,"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/posts\/3753\/revisions\/3853"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/media\/3754"}],"wp:attachment":[{"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/media?parent=3753"}],"wp:term":[{"taxonomy":"sf_topic","embeddable":true,"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/sf_topic?post=3753"},{"taxonomy":"sf_content_type","embeddable":true,"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/sf_content_type?post=3753"},{"taxonomy":"blog","embeddable":true,"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/blog?post=3753"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/coauthors?post=3753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}