{"id":4645,"date":"2020-06-05T21:56:00","date_gmt":"2020-06-05T19:56:00","guid":{"rendered":"https:\/\/www.salesforce.com\/?p=4645"},"modified":"2026-01-26T12:45:49","modified_gmt":"2026-01-26T10:45:49","slug":"foundations-of-effective-online-selling","status":"publish","type":"post","link":"https:\/\/www.salesforce.com\/it\/blog\/foundations-of-effective-online-selling\/","title":{"rendered":"E-commerce: 5 consigli per vendere online con successo"},"content":{"rendered":"\n<p>Nel 2018, ci sono state approssimativamente&nbsp;<a href=\"https:\/\/www.statista.com\/statistics\/379046\/worldwide-retail-e-commerce-sales\/\" target=\"_blank\" rel=\"noreferrer noopener\">2,84 bilioni di dollari di vendite da distribuzione e-commerce in tutto il mondo<\/a>.&nbsp;Entro la fine del 2021, questo numero dovrebbe toccare i 5 bilioni. Ancora non basta? Di pari passo alle vendite online cresce la concorrenza. Con una tale posta in gioco, non potete permettervi di rimanere nascosti tra la folla e dovete connettervi con i clienti in maniera efficace.<\/p>\n\n\n\n<p>Ma come fare? Per navigare nella marea della concorrenza e conquistare clienti che sono sempre online e connessi, la vostra strategia di vendita online deve comprendere cinque requisiti basilari.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-di-che-cosa-ci-occuperemo\">Di che cosa ci occuperemo:<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Non fallite la vostra prima prova di vendita online: un sito web&nbsp;ottimizzato<\/li>\n\n\n\n<li>Raggiungete nuovi clienti con una strategia efficace di marketing online<\/li>\n\n\n\n<li>Personalizzate&nbsp;la vostra offerta e-commerce con l&#8217;aiuto dell&#8217;intelligenza artificiale (IA)<\/li>\n\n\n\n<li>Completate il quadro con contenuti integrati<\/li>\n\n\n\n<li>Trovate gli strumenti adatti per le vostre strategie di vendita online<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-1-non-fallite-la-vostra-prima-prova-di-vendita-online-un-sito-web-nbsp-ottimizzato\">1. Non fallite la vostra prima prova di vendita online: un sito web&nbsp;ottimizzato<\/h2>\n\n\n\n<p><br>Sapevate che un visitatore pu\u00f2 impiegare meno di&nbsp;<a href=\"http:\/\/cdn2.business2community.com\/wp-content\/uploads\/2015\/05\/Shrinking-attention-spans-of-consumers.png\" target=\"_blank\" rel=\"noreferrer noopener\">10 secondi a decidere se rimanere sulla vostra pagina o no<\/a>? Pi\u00f9 importante ancora, se riuscite a far rimanere gli utenti nella vostra pagina per pi\u00f9 di 30 secondi, questi saranno pi\u00f9 propensi a tornare.<\/p>\n\n\n\n<p>Il punto \u00e8 che dovete garantire che le esperienze basilari di\u00a0utilizzo\u00a0del sito web siano di qualit\u00e0. Se i vostri tassi di conversione sono pi\u00f9 bassi della norma o quelli di abbandono sono pi\u00f9 alti di quanto vorreste, date un&#8217;occhiata attenta al design del vostro sito. Ogni clic fa parte di un percorso che conduce i vostri clienti all&#8217;obiettivo finale: l&#8217;acquisto. Pi\u00f9 sono le attese, le ricerche e i passi obbligatori, meno gli acquirenti taglieranno il traguardo o vorranno tornare un&#8217;altra volta. Per incrementare le vendite online, badate a\u00a0ottimizzare\u00a0la vostra esperienza web con le best practice di oggi: l&#8217;assenza pi\u00f9 che benvenuta di problemi di caricamento pagina e link non funzionanti, un\u00a0design mobile-friendly\u00a0che funzioni su ogni dispositivo, &#8220;call to action&#8221; chiare e significative, un processo di checkout facile e veloce e un aspetto ordinato e user-friendly.<\/p>\n\n\n\n<div class=\"layout-six wp-block-salesforce-blog-offer\">\n\t<div class=\"wp-block-offer__wrapper\">\n\n\t\t<div class=\"wp-block-offer__content\">\n\t\t\t<h2 class=\"wp-block-offer__title\"><sub>STATE OF COMMERCE<\/sub><br><br>Scopri tendenze e opportunit\u00e0 per le piattaforme e-commerce<\/h2>\n\t\t\t\t\t\t\t<p class=\"wp-block-offer__description\">Abbiamo\u00a0analizzato\u00a0un bilione di transazioni online: scopri quali opportunit\u00e0 puoi cogliere con il tuo e-commerce.<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t<a class=\"wp-block-button__link\" target=\"_blank\" href=\"\/it\/form\/pdf\/state-of-commerce\/?d=pb\">Scarica il report<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"wp-block-offer__media\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2026\/01\/soc-form-image.png\" class=\"attachment-full size-full\" alt=\"State of commerce\" srcset=\"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2026\/01\/soc-form-image.png 1536w, https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2026\/01\/soc-form-image.png?w=300&amp;h=169 300w, https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2026\/01\/soc-form-image.png?w=768&amp;h=432 768w, https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2026\/01\/soc-form-image.png?w=1024&amp;h=576 1024w, https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2026\/01\/soc-form-image.png?w=150&amp;h=84 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/div>\n\t<\/div>\n\n\t\n\t<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-2-raggiungete-nuovi-clienti-con-una-strategia-efficace-di-marketing-online\">2. Raggiungete nuovi clienti con una strategia efficace di marketing online<\/h2>\n\n\n\n<p>Sono ormai passati i giorni in cui semplicemente offrire un e-commerce poteva garantire un vantaggio competitivo impareggiabile. Oggigiorno per competere nel mercato delle vendite, dove ognuno ha un sito web, dovete raggiungere e incontrare il vostro pubblico nei luoghi in cui vive, naviga e acquista.<\/p>\n\n\n\n<p>Dovreste iniziare pianificare regolari campagne pubblicitarie e promozioni digitali online, sia su mobile che su web e social network. Popolare questi canali con costanza aiuter\u00e0 a identificare la vostra utenza chiave, ad aumentare il riconoscimento del vostro marchio e a incrementare le vendite online attirando nuovi clienti sul vostro sito.<\/p>\n\n\n\n<p>Nell&#8217;era dei social network, raccomandiamo anche di sfruttare contenuti generati dagli utenti. Questi vi possono aiutare a costruire il riconoscimento del marchio grazie a testimonial in real-life, tutorial amatoriali e influencer che sui social promuovono i vostri prodotti e servizi. Mostrare persone reali alle prese (con successo!) con i prodotti vale pi\u00f9 di mille foto professionali.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-3-nbsp-personalizzate-nbsp-la-vostra-offerta-e-commerce-con-l-aiuto-dell-intelligenza-artificiale-ia\">3.&nbsp;Personalizzate&nbsp;la vostra offerta e-commerce con l&#8217;aiuto dell&#8217;intelligenza artificiale (IA)<\/h2>\n\n\n\n<p>Le persone vivono esperienze guidate dall&#8217;intelligenza artificiale ogni giorno: app preferite, raccomandazioni prodotto, riconoscimento facciale e vocale e tanto altro ancora. Oggi il cliente connesso si aspetta queste esperienze smart altamente&nbsp;personalizzate&nbsp;per ogni marchio con cui interagisce, compreso il vostro. Pi\u00f9 della met\u00e0 (52%) dei consumatori di oggi, infatti, ha dichiarato di essere propensa a&nbsp;<a href=\"\/it\/form\/pdf\/state-of-marketing\/?d=pb\" target=\"_blank\" rel=\"noreferrer noopener\">cambiare marchio nel caso in cui un&#8217;azienda non&nbsp;personalizzi&nbsp;le proprie comunicazioni<\/a>.<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a577a653633a&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a577a653633a\" class=\"wp-block-image size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"765\" height=\"350\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2026\/01\/IT_Foundations_1.jpg?strip=all&#038;quality=95\" alt=\"Pi\u00f9 della met\u00e0 (52%) dei consumatori di oggi ha dichiarato di essere propensa a\u00a0cambiare marchio nel caso in cui un'azienda non\u00a0personalizzi\u00a0le proprie comunicazioni. \" class=\"wp-image-4648\" srcset=\"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2026\/01\/IT_Foundations_1.jpg 765w, https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2026\/01\/IT_Foundations_1.jpg?w=300&amp;h=137 300w, https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2026\/01\/IT_Foundations_1.jpg?w=150&amp;h=69 150w\" sizes=\"auto, (max-width: 765px) 100vw, 765px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p>Puntando sull&#8217;<a href=\"https:\/\/www.salesforce.com\/it\/blog\/2019\/12\/cosa-e-intelligenza-artificiale.html\">intelligenza artificiale (IA)<\/a>, potete velocemente trasformare grandi quantit\u00e0 di informazioni generate dal cliente in intuizioni chiare e&nbsp;utilizzabili, oltre che in esperienze&nbsp;personalizzate. L&#8217;IA pu\u00f2 aiutarvi a generare momenti significativi su misura per ogni acquirente, quali le raccomandazioni prodotto e i risultati di ricerca&nbsp;personalizzati, cosa in grado di aumentare drasticamente le vostre vendite online. Dietro le quinte, l&#8217;IA pu\u00f2 potenziare i vostri venditori con intuizioni sui clienti guidate dai dati, evitando che decisioni importanti vengano guidate esclusivamente da congetture.<\/p>\n\n\n\n<div class=\"layout-six wp-block-salesforce-blog-offer\">\n\t<div class=\"wp-block-offer__wrapper\">\n\n\t\t<div class=\"wp-block-offer__content\">\n\t\t\t<h2 class=\"wp-block-offer__title\"><sub>CONNECTED CUSTOMER<\/sub><br><br>Offri ai clienti l&#8217;esperienza che chiedono<\/h2>\n\t\t\t\t\t\t\t<p class=\"wp-block-offer__description\">Abbiamo indagato i comportamenti d&#8217;acquisto di oltre 15000 consumatori, Italia compresa: scopri che cosa hanno risposto alle nostre domande.<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t<a class=\"wp-block-button__link\" target=\"_blank\" href=\"\/it\/form\/pdf\/state-of-connected-customer\/?d=pb\">Scarica il report<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"wp-block-offer__media\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"528\" height=\"353\" src=\"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2026\/01\/state-of-connected-customer-banner.png\" class=\"attachment-full size-full\" alt=\"Focus sul cliente connesso\" srcset=\"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2026\/01\/state-of-connected-customer-banner.png 528w, https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2026\/01\/state-of-connected-customer-banner.png?w=300&amp;h=201 300w, https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2026\/01\/state-of-connected-customer-banner.png?w=150&amp;h=100 150w\" sizes=\"auto, (max-width: 528px) 100vw, 528px\" \/>\t\t<\/div>\n\t<\/div>\n\n\t\n\t<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-4-completate-il-quadro-con-contenuti-integrati\">4. Completate il quadro con contenuti integrati<\/h2>\n\n\n\n<p>Nonostante il marketing dei contenuti sia estremamente efficace, il suo impatto dipende da quanto sia ben integrato al vostro percorso di conversione. Sapevate che&nbsp;<a href=\"https:\/\/www.salesforce.com\/it\/commerce\/\">il 72% dei contenuti per gli utenti su homepage negli Stati Uniti<\/a>&nbsp;non fornisce un percorso chiaro verso l&#8217;acquisto, e che il 44% dei blog aziendali non \u00e8 integrato con l&#8217;e-commerce dell&#8217;azienda? Sono un sacco di opportunit\u00e0 mancate per generare vendite online!<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a577a6537c94&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a577a6537c94\" class=\"wp-block-image size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"765\" height=\"350\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2026\/01\/IT_Foundations_2.jpg?strip=all&#038;quality=95\" alt=\"Sapevate che\u00a0il 72% dei contenuti per gli utenti su homepage negli Stati Uniti\u00a0non fornisce un percorso chiaro verso l'acquisto, e che il 44% dei blog aziendali non \u00e8 integrato con l'e-commerce dell'azienda?\" class=\"wp-image-4651\" srcset=\"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2026\/01\/IT_Foundations_2.jpg 765w, https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2026\/01\/IT_Foundations_2.jpg?w=300&amp;h=137 300w, https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2026\/01\/IT_Foundations_2.jpg?w=150&amp;h=69 150w\" sizes=\"auto, (max-width: 765px) 100vw, 765px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Enlarge\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p>I brand con un contenuto profondamente integrato durante tutto il percorso di vendita hanno tassi di conversione pi\u00f9 alti rispetto alla concorrenza, e per ottime ragioni: combinare strategicamente i contenuti e l&#8217;e-commerce vi permette di mettere in evidenza i messaggi pi\u00f9 invitanti di cui siete in possesso al massimo del loro potenziale. Per ogni porzione di contenuto che pubblicate, assicuratevi che questa si amalgami al percorso di vendita con soluzione di continuit\u00e0 e che includa una via chiara e facile all&#8217;acquisto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-5-trovate-gli-strumenti-adatti-per-le-vostre-strategie-di-vendita-online\">5. Trovate gli strumenti adatti per le vostre strategie di vendita online<\/h2>\n\n\n\n<p>Per&nbsp;realizzare&nbsp;a pieno quanto detto sopra, avete bisogno di una soluzione che vi aiuti a gestire tutti gli aspetti della vendita online da un singolo luogo e verso tutti i canali. Oltre che al sito web in s\u00e9, l&#8217;ideale sarebbe includere campagne marketing e mezzi di promozione, intelligenza artificiale integrata, strumenti di gestione dei contenuti, tracciamento, dati analitici e molto altro.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.salesforce.com\/it\/products\/commerce-cloud\/overview\/\">Salesforce Commerce Cloud<\/a>&nbsp;vi permette un controllo sui vostri sforzi di marketing ed e-commerce, supportato dalla capacit\u00e0 di prendere le decisioni pi\u00f9 intelligenti e strategiche senza alcuna ulteriore fatica o competenze aggiuntive. Ancora pi\u00f9 importante, potete integrare Commerce Cloud con altre soluzioni Salesforce, quali Service Cloud, Sales Cloud e Marketing Cloud, per raggiungere una piena collaborazione tra tutti i dipartimenti, generando una singola visione a 360 gradi su ogni cliente, sui suoi comportamenti e sulle sue necessit\u00e0.<\/p>\n\n\n\n<p>La vendita online richiede una voce del brand riconoscibile e l&#8217;abilit\u00e0 di raggiungere e ispirare i clienti con esperienze intelligenti e fluide. Salesforce vi pu\u00f2 aiutare a farlo con gli strumenti, la tecnologia e il supporto di cui avete bisogno per ritrovarvi un passo avanti agli altri.<\/p>\n\n\n\n<div class=\"layout-six wp-block-salesforce-blog-offer\">\n\t<div class=\"wp-block-offer__wrapper\">\n\n\t\t<div class=\"wp-block-offer__content\">\n\t\t\t<h2 class=\"wp-block-offer__title\">Guarda Commerce Cloud in azione<\/h2>\n\t\t\t\t\t\t\t<p class=\"wp-block-offer__description\">Impara a fornire ai clienti un&#8217;esperienza di integrazione perfetta con Commerce Cloud.<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t<a class=\"wp-block-button__link\" target=\"_blank\" href=\"\/it\/form\/commerce\/commerce-cloud-overview-demo\/?d=pb\">Guarda la demo<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"wp-block-offer__media\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"713\" height=\"426\" src=\"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2026\/01\/natparks-contact-us-astro-office.png\" class=\"attachment-full size-full\" alt=\"Guarda Commerce Cloud in azione\" srcset=\"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2026\/01\/natparks-contact-us-astro-office.png 713w, https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2026\/01\/natparks-contact-us-astro-office.png?w=300&amp;h=179 300w, https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2026\/01\/natparks-contact-us-astro-office.png?w=150&amp;h=90 150w\" sizes=\"auto, (max-width: 713px) 100vw, 713px\" \/>\t\t<\/div>\n\t<\/div>\n\n\t\n\t<\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nel 2018, ci sono state approssimativamente&nbsp;2,84 bilioni di dollari di vendite da distribuzione e-commerce in tutto il mondo.&nbsp;Entro la fine del 2021, questo numero dovrebbe toccare i 5 bilioni. Ancora non basta? Di&hellip;<\/p>\n","protected":false},"author":820,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sf_justforyou_enable_alt":true,"optimizely_content_id":"948d8cef1c0c4c4186391194IT","post_meta_title":"","ai_synopsis":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"sf_topic":[],"sf_content_type":[1280],"blog":[],"coauthors":[2],"class_list":["post-4645","post","type-post","status-publish","format-standard","hentry","sf_content_type-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>E-commerce: 5 consigli per vendere online con successo - Salesforce<\/title>\n<meta name=\"description\" content=\"Nel 2018, ci sono state approssimativamente&nbsp;2,84 bilioni di dollari di vendite da distribuzione e-commerce in tutto il mondo.&nbsp;Entro la fine del\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salesforce.com\/it\/blog\/foundations-of-effective-online-selling\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"E-commerce: 5 consigli per vendere online con successo\" \/>\n<meta property=\"og:description\" content=\"Nel 2018, ci sono state approssimativamente&nbsp;2,84 bilioni di dollari di vendite da distribuzione e-commerce in tutto il mondo.&nbsp;Entro la fine del\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salesforce.com\/it\/blog\/foundations-of-effective-online-selling\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-05T19:56:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-26T10:45:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2026\/01\/IT_Foundations_1.jpg\" \/>\n<meta name=\"author\" content=\"Salesforce Italia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Salesforce Italia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Salesforce Italia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.salesforce.com\/it\/blog\/foundations-of-effective-online-selling\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.salesforce.com\/it\/blog\/foundations-of-effective-online-selling\/\"},\"author\":[{\"@id\":\"https:\/\/www.salesforce.com\/it\/blog\/#\/schema\/person\/image\/d74bba174b633a02c1daa27bf350774f\"}],\"headline\":\"E-commerce: 5 consigli per vendere online con successo\",\"datePublished\":\"2020-06-05T19:56:00+00:00\",\"dateModified\":\"2026-01-26T10:45:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.salesforce.com\/it\/blog\/foundations-of-effective-online-selling\/\"},\"wordCount\":1056,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.salesforce.com\/it\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/it\/blog\/foundations-of-effective-online-selling\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2026\/01\/IT_Foundations_1.jpg\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.salesforce.com\/it\/blog\/foundations-of-effective-online-selling\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.salesforce.com\/it\/blog\/foundations-of-effective-online-selling\/\",\"url\":\"https:\/\/www.salesforce.com\/it\/blog\/foundations-of-effective-online-selling\/\",\"name\":\"E-commerce: 5 consigli per vendere online con successo - Salesforce\",\"isPartOf\":{\"@id\":\"https:\/\/www.salesforce.com\/it\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.salesforce.com\/it\/blog\/foundations-of-effective-online-selling\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/it\/blog\/foundations-of-effective-online-selling\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2026\/01\/IT_Foundations_1.jpg\",\"datePublished\":\"2020-06-05T19:56:00+00:00\",\"dateModified\":\"2026-01-26T10:45:49+00:00\",\"description\":\"Nel 2018, ci sono state approssimativamente&nbsp;2,84 bilioni di dollari di vendite da distribuzione e-commerce in tutto il mondo.&nbsp;Entro la fine del\",\"breadcrumb\":{\"@id\":\"https:\/\/www.salesforce.com\/it\/blog\/foundations-of-effective-online-selling\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.salesforce.com\/it\/blog\/foundations-of-effective-online-selling\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.salesforce.com\/it\/blog\/foundations-of-effective-online-selling\/#primaryimage\",\"url\":\"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2026\/01\/IT_Foundations_1.jpg\",\"contentUrl\":\"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2026\/01\/IT_Foundations_1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.salesforce.com\/it\/blog\/foundations-of-effective-online-selling\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.salesforce.com\/it\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"E-commerce: 5 consigli per vendere online con successo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.salesforce.com\/it\/blog\/#website\",\"url\":\"https:\/\/www.salesforce.com\/it\/blog\/\",\"name\":\"Salesforce\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.salesforce.com\/it\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.salesforce.com\/it\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.salesforce.com\/it\/blog\/#organization\",\"name\":\"Salesforce\",\"url\":\"https:\/\/www.salesforce.com\/it\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.salesforce.com\/it\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2023\/09\/Salesforce.webp\",\"contentUrl\":\"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2023\/09\/Salesforce.webp\",\"width\":1200,\"height\":630,\"caption\":\"Salesforce\"},\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/it\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.salesforce.com\/it\/blog\/#\/schema\/person\/image\/d74bba174b633a02c1daa27bf350774f\",\"name\":\"Salesforce Italia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g23494c9101089ad44ae88ce9d2f56aac\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g\",\"caption\":\"Salesforce Italia\"},\"url\":\"https:\/\/www.salesforce.com\/it\/blog\/author\/salesforceitalia\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"E-commerce: 5 consigli per vendere online con successo - Salesforce","description":"Nel 2018, ci sono state approssimativamente&nbsp;2,84 bilioni di dollari di vendite da distribuzione e-commerce in tutto il mondo.&nbsp;Entro la fine del","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salesforce.com\/it\/blog\/foundations-of-effective-online-selling\/","og_locale":"it_IT","og_type":"article","og_title":"E-commerce: 5 consigli per vendere online con successo","og_description":"Nel 2018, ci sono state approssimativamente&nbsp;2,84 bilioni di dollari di vendite da distribuzione e-commerce in tutto il mondo.&nbsp;Entro la fine del","og_url":"https:\/\/www.salesforce.com\/it\/blog\/foundations-of-effective-online-selling\/","og_site_name":"Salesforce","article_published_time":"2020-06-05T19:56:00+00:00","article_modified_time":"2026-01-26T10:45:49+00:00","og_image":[{"url":"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2026\/01\/IT_Foundations_1.jpg","type":"","width":"","height":""}],"author":"Salesforce Italia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Salesforce Italia","Tempo di lettura stimato":"6 minuti","Written by":"Salesforce Italia"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salesforce.com\/it\/blog\/foundations-of-effective-online-selling\/#article","isPartOf":{"@id":"https:\/\/www.salesforce.com\/it\/blog\/foundations-of-effective-online-selling\/"},"author":[{"@id":"https:\/\/www.salesforce.com\/it\/blog\/#\/schema\/person\/image\/d74bba174b633a02c1daa27bf350774f"}],"headline":"E-commerce: 5 consigli per vendere online con successo","datePublished":"2020-06-05T19:56:00+00:00","dateModified":"2026-01-26T10:45:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salesforce.com\/it\/blog\/foundations-of-effective-online-selling\/"},"wordCount":1056,"commentCount":0,"publisher":{"@id":"https:\/\/www.salesforce.com\/it\/blog\/#organization"},"image":{"@id":"https:\/\/www.salesforce.com\/it\/blog\/foundations-of-effective-online-selling\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2026\/01\/IT_Foundations_1.jpg","inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.salesforce.com\/it\/blog\/foundations-of-effective-online-selling\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.salesforce.com\/it\/blog\/foundations-of-effective-online-selling\/","url":"https:\/\/www.salesforce.com\/it\/blog\/foundations-of-effective-online-selling\/","name":"E-commerce: 5 consigli per vendere online con successo - Salesforce","isPartOf":{"@id":"https:\/\/www.salesforce.com\/it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salesforce.com\/it\/blog\/foundations-of-effective-online-selling\/#primaryimage"},"image":{"@id":"https:\/\/www.salesforce.com\/it\/blog\/foundations-of-effective-online-selling\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2026\/01\/IT_Foundations_1.jpg","datePublished":"2020-06-05T19:56:00+00:00","dateModified":"2026-01-26T10:45:49+00:00","description":"Nel 2018, ci sono state approssimativamente&nbsp;2,84 bilioni di dollari di vendite da distribuzione e-commerce in tutto il mondo.&nbsp;Entro la fine del","breadcrumb":{"@id":"https:\/\/www.salesforce.com\/it\/blog\/foundations-of-effective-online-selling\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salesforce.com\/it\/blog\/foundations-of-effective-online-selling\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.salesforce.com\/it\/blog\/foundations-of-effective-online-selling\/#primaryimage","url":"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2026\/01\/IT_Foundations_1.jpg","contentUrl":"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2026\/01\/IT_Foundations_1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salesforce.com\/it\/blog\/foundations-of-effective-online-selling\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salesforce.com\/it\/blog\/"},{"@type":"ListItem","position":2,"name":"E-commerce: 5 consigli per vendere online con successo"}]},{"@type":"WebSite","@id":"https:\/\/www.salesforce.com\/it\/blog\/#website","url":"https:\/\/www.salesforce.com\/it\/blog\/","name":"Salesforce","description":"","publisher":{"@id":"https:\/\/www.salesforce.com\/it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salesforce.com\/it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.salesforce.com\/it\/blog\/#organization","name":"Salesforce","url":"https:\/\/www.salesforce.com\/it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.salesforce.com\/it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2023\/09\/Salesforce.webp","contentUrl":"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2023\/09\/Salesforce.webp","width":1200,"height":630,"caption":"Salesforce"},"image":{"@id":"https:\/\/www.salesforce.com\/it\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.salesforce.com\/it\/blog\/#\/schema\/person\/image\/d74bba174b633a02c1daa27bf350774f","name":"Salesforce Italia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g23494c9101089ad44ae88ce9d2f56aac","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"Salesforce Italia"},"url":"https:\/\/www.salesforce.com\/it\/blog\/author\/salesforceitalia\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Salesforce","distributor_original_site_url":"https:\/\/www.salesforce.com\/it\/blog","push-errors":false,"_links":{"self":[{"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/posts\/4645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/users\/820"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/comments?post=4645"}],"version-history":[{"count":8,"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/posts\/4645\/revisions"}],"predecessor-version":[{"id":4688,"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/posts\/4645\/revisions\/4688"}],"wp:attachment":[{"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/media?parent=4645"}],"wp:term":[{"taxonomy":"sf_topic","embeddable":true,"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/sf_topic?post=4645"},{"taxonomy":"sf_content_type","embeddable":true,"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/sf_content_type?post=4645"},{"taxonomy":"blog","embeddable":true,"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/blog?post=4645"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/coauthors?post=4645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}