{"id":770,"date":"2023-02-13T21:02:00","date_gmt":"2023-07-20T21:02:55","guid":{"rendered":"https:\/\/www.salesforce.com\/?p=770"},"modified":"2023-09-08T10:31:45","modified_gmt":"2023-09-08T10:31:45","slug":"risultati-state-of-sales-quinta-edizione","status":"publish","type":"post","link":"https:\/\/www.salesforce.com\/it\/blog\/risultati-state-of-sales-quinta-edizione\/","title":{"rendered":"10 highlight rivelano in che modo i team di vendita stanno raggiungendo il successo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Nel campo delle vendite, una cosa \u00e8 certa: non esistono certezze. Questa realt\u00e0 trova conferma nell&#8217;<i><a href=\"https:\/\/www.salesforce.com\/it\/resources\/research-reports\/state-of-sales\/\" target=\"_blank\" rel=\"noopener\">ultima edizione del nostro report &#8220;State of Sales&#8221;<\/a><\/i>, da cui emerge che<b> il 72% dei professionisti delle vendite non prevede di raggiungere il proprio obiettivo annuale<\/b>. Perch\u00e9? Le difficolt\u00e0 legate all&#8217;inflazione, ai persistenti problemi sanitari e alle interruzioni della supply chain non accennano a diminuire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La buona notizia \u00e8 che i venditori stanno trovando il modo di superarle massimizzando l&#8217;efficienza, tagliando i costi e incrementando la produttivit\u00e0 dei responsabili commerciali. I 10 highlight qui sotto, tratti dal report, illustrano <b>il modo in cui i venditori si stanno adeguando alle necessit\u00e0 del momento. <\/b><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-1-il-70-dei-leader-di-vendita-afferma-che-la-propria-azienda-si-assume-meno-rischi-di-quanto-non-facesse-prima-della-pandemia\"><b>1. Il 70% dei leader di vendita afferma che la propria azienda si assume meno rischi di quanto non facesse prima della pandemia<\/b><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nonostante l&#8217;incertezza economica, le aziende devono comunque raggiungere i propri obiettivi. Anzich\u00e9 scommettere su strategie e tattiche pi\u00f9 rischiose, i leader di vendita stanno adottando un approccio pi\u00f9 prudente, puntando su ci\u00f2 che ha dimostrato di funzionare. Infatti,<b> il 55% dei leader di vendita dichiara di dare priorit\u00e0 alle iniziative a basso rischio<\/b>, che assicurano una crescita modesta ma garantita. La principale conclusione \u00e8 che le scommesse sicure sono preferibili a guadagni maggiori ma pi\u00f9 incerti, soprattutto nei momenti difficili. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-2-i-responsabili-commerciali-dedicano-alle-vendite-solo-il-28-del-loro-impegno-lavorativo-settimanale-rispetto-al-34-del-2018\"><b>2. I responsabili commerciali dedicano alle vendite solo il 28% del loro impegno lavorativo settimanale rispetto al 34% del 2018 <\/b><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;attivit\u00e0 dei responsabili commerciali \u00e8 rallentata da una quantit\u00e0 eccessiva di lavoro manuale. I venditori vogliono vendere, ma <b>pi\u00f9 di due terzi del loro tempo viene assorbito da attivit\u00e0 di registrazione dei record, processi incompleti, gestione degli strumenti, inserimento di dati e gestione dei lead.<\/b> Tutto ci\u00f2 porta a processi di vendita affrettati e riduce il tempo a disposizione per raggiungere l&#8217;obiettivo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-\"> <\/h3>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-3-il-66-dei-responsabili-commerciali-afferma-di-stare-annegando-in-un-mare-di-strumenti\"><b>3. Il 66% dei responsabili commerciali afferma di stare annegando in un mare di strumenti<\/b><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Come accennato in precedenza, la necessit\u00e0 di destreggiarsi tra tanti strumenti diversi \u00e8 uno dei motivi che riduce il tempo da dedicare alle vendite. In media, <b>i team di vendita utilizzano 10 strumenti per chiudere una trattativa.<\/b> Molti di questi hanno un ruolo importante nel processo di vendita, ma possono essere costosi, richiedere procedure lunghe e complesse e impedire ai responsabili di dedicare pi\u00f9 tempo a coltivare relazioni con i clienti acquisiti e potenziali per concludere nuove trattative. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-4-il-94-delle-organizzazioni-di-vendita-ha-intenzione-di-consolidare-il-proprio-stack-tecnologico-entro-i-prossimi-12-mesi\"><b>4. Il 94% delle organizzazioni di vendita ha intenzione di consolidare il proprio stack tecnologico entro i prossimi 12 mesi<\/b><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Per risolvere il sovraccarico tecnologico, le organizzazioni di vendita stanno cercando di snellire il proprio stack. Ma la strada da percorrere non \u00e8 quella di abbandonare la tecnologia. Si tratta piuttosto di ottimizzare gli strumenti fondamentali e di eliminare quelli non essenziali o ridondanti. I venditori sostengono che, sotto questo profilo, vi \u00e8 un ampio margine di miglioramento: <b>solo il 37% \u00e8 fermamente convinto che la propria azienda sfrutti appieno le potenzialit\u00e0 del sistema <a href=\"https:\/\/www.salesforce.com\/it\/learning-centre\/crm\/what-is-crm\/\" target=\"_blank\" rel=\"noopener\">CRM<\/a>. <\/b><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><b>George Carrera III, Senior Manager di Systems Technology presso Mitsubishi Elevators<\/b>, sottolinea l&#8217;importanza del consolidamento e dell&#8217;ottimizzazione: <i>&#8220;Dal momento che i team di vendita cercano nuovi percorsi verso l&#8217;efficienza, le soluzioni tecniche infinite sono spesso considerate una ricetta magica. In realt\u00e0, bisogna analizzare i processi per capire ci\u00f2 che serve realmente, utilizzare al meglio gli strumenti che devono essere conservati ed eliminare gli strumenti preesistenti che non sono di alcun aiuto&#8221;.<\/i><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-5-il-97-dei-leader-e-dei-professionisti-del-settore-delle-vendite-sostiene-che-l-ia-possa-offrire-ai-responsabili-commerciali-piu-tempo-da-dedicare-alle-vendite\"><b>5. Il 97% dei leader e dei professionisti del settore delle vendite sostiene che l&#8217;IA possa offrire ai responsabili commerciali pi\u00f9 tempo da dedicare alle vendite<\/b><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Non soltanto le organizzazioni di vendita stanno cercando di consolidare gli stack tecnologici per aumentare l&#8217;efficienza, ma sono anche intenzionate a eliminare il lavoro manuale che affligge le giornate lavorative dei responsabili commerciali. <b>L&#8217;<a target=\"_blank\" rel=\"noopener\">intelligenza artificiale (IA)<\/a>, abbinata all&#8217;automazione, elimina una serie di attivit\u00e0 improduttive<\/b>, come l&#8217;aggiornamento dei dati sulle trattative e la valutazione dei lead, affinch\u00e9 i venditori possano concentrarsi sulle conversazioni con gli acquirenti. E non si tratta affatto di un incremento di produttivit\u00e0 puramente teorico. Come rivela il nostro report, \u00e8 1,9 volte pi\u00f9 probabile che i venditori migliori utilizzino l&#8217;intelligenza artificiale.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-6-il-90-dei-responsabili-commerciali-dei-team-con-performance-piu-elevate-afferma-che-la-loro-leadership-li-incoraggia-a-dare-priorita-alle-relazioni-a-lungo-termine-con-i-clienti-rispetto-ai-successi-a-breve-termine\"><b>6. Il 90% dei responsabili commerciali dei team con performance pi\u00f9 elevate afferma che la loro leadership li incoraggia a dare priorit\u00e0 alle relazioni a lungo termine con i clienti rispetto ai successi a breve termine<\/b><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">In questo momento di incertezza, i leader di vendita cercano opportunit\u00e0 di ricavi su cui poter contare. Ecco perch\u00e9 sottolineano <b>l&#8217;importanza delle relazioni con i clienti rispetto alle trattative rapide<\/b>, dando ai responsabili commerciali la possibilit\u00e0 di costruire solidi legami che promuovono la fidelizzazione e favoriscono opportunit\u00e0 di <a href=\"https:\/\/www.salesforce.com\/it\/learning-centre\/sales\/cross-selling\/\" target=\"_blank\" rel=\"noopener\">cross-selling<\/a>, <a href=\"https:\/\/www.salesforce.com\/it\/learning-centre\/sales\/upselling\/\" target=\"_blank\" rel=\"noopener\">up-selling<\/a> e rinnovi (ovvero, ricavi prevedibili). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per rafforzare queste relazioni, i responsabili commerciali non agiscono pi\u00f9 da semplici addetti alle vendite che si occupano soltanto di concludere transazioni. Infatti, l&#8217;82% dei responsabili commerciali afferma che la loro azienda li incoraggia a diventare i consulenti di fiducia degli acquirenti, aiutandoli a risolvere problemi complessi e a soddisfare esigenze diversificate.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><i>\u201cI potenziali clienti hanno bisogno di poter dimostrare il valore di un acquisto e ora collaborano con i venditori per concentrarsi su risultati tangibili\u201d,<\/i> ha dichiarato <b>Alexine Mudawar, Strategic account Executive della societ\u00e0 software Alyce. <\/b><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-7-l-81-dei-responsabili-commerciali-afferma-che-la-vendita-in-team-aiuta-a-concludere-le-trattative\"><b>7. L&#8217;81% dei responsabili commerciali afferma che la vendita in team aiuta a concludere le trattative<\/b><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">I buyer sono sempre pi\u00f9 esperti e questo \u00e8 un altro cambiamento a cui devono adattarsi i venditori. <b>Oltre l&#8217;80% dei responsabili commerciali afferma che i buyer svolgono sempre pi\u00f9 spesso delle ricerche prima di rivolgersi a loro<\/b>, il che significa che i venditori devono disporre delle risorse e conoscenze necessarie per rispondere a quesiti che vanno al di l\u00e0 delle funzionalit\u00e0 di base del prodotto. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La cattiva notizia \u00e8 che l&#8217;allineamento interfunzionale richiede un certo impegno. Sebbene gran parte dei rappresentanti sia concorde nell&#8217;affermare che la vendita in team aiuti a concludere le trattative, non \u00e8 semplice essere tutti sulla stessa lunghezza d\u2019onda. Riuscire a gestire questo problema sar\u00e0 una delle priorit\u00e0 principali dei leader di vendita, i quali sostengono che l&#8217;allineamento interfunzionale \u00e8 la tattica vincente per promuovere la crescita.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-8-l-85-dei-leader-di-vendita-afferma-di-avere-difficolta-a-reperire-il-budget-per-l-organico-necessario\"><b>8. L&#8217;85% dei leader di vendita afferma di avere difficolt\u00e0 a reperire il budget per l&#8217;organico necessario <\/b><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">I budget ridotti rappresentano sempre di pi\u00f9 un problema per i leader di vendita. Ai team viene chiesto di raggiungere gli obiettivi di fatturato senza aumentare l&#8217;organico o le risorse a disposizione, il che genera frustrazione e spesso comporta un incremento del tasso di turnover. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ecco perch\u00e9 <b>\u00e8 importante assicurarsi che ogni rappresentante disponga delle risorse e del supporto necessari per poter svolgere al meglio il proprio ruolo<\/b>. L&#8217;esperienza e il coinvolgimento dei dipendenti sono in cima alle priorit\u00e0 dei leader, che cercano quindi di offrire percorsi di coaching individuale, promuovere la formazione sugli strumenti, favorire un migliore equilibrio tra attivit\u00e0 professionale e vita privata e aumentare i benefit. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-9-l-81-dei-responsabili-commerciali-dichiara-di-ricevere-un-coaching-prezioso-dal-proprio-manager\"><b>9. L&#8217;81% dei responsabili commerciali dichiara di ricevere un coaching prezioso dal proprio manager <\/b><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c8 sicuramente una buona notizia, ma resta il fatto che il coaching individuale \u00e8 relativamente poco frequente: <b>solo il 26% dei professionisti delle vendite afferma che le sessioni avvengono con cadenza settimanale<\/b>. Quando i manager si incontrano con i responsabili commerciali, sono molti i temi e gli argomenti da trattare. Forse persino troppi. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una possibile soluzione \u00e8 offerta dalla tecnologia di abilitazione che identifica automaticamente gli aspetti principali su cui dovrebbe focalizzarsi il coaching dei responsabili commerciali. \u00c8 un&#8217;area che offre grandi opportunit\u00e0, in quanto s<b>olo il 53% dei leader di vendita afferma di utilizzare questo tipo di soluzioni per il coaching.<\/b><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-10-solo-il-28-dei-professionisti-delle-vendite-prevede-di-raggiungere-o-superare-il-proprio-obiettivo-il-prossimo-anno-ma-le-organizzazioni-di-vendita-stanno-offrendo-il-loro-supporto\"><b>10. Solo il 28% dei professionisti delle vendite prevede di raggiungere o superare il proprio obiettivo il prossimo anno, ma le organizzazioni di vendita stanno offrendo il loro supporto <\/b><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">In un contesto di forte incertezza economica a livello globale, i professionisti delle vendite sono preoccupati di non riuscire a raggiungere i loro obiettivi di fatturato. Ma il quadro non \u00e8 tutto nero. Anche di fronte a difficolt\u00e0 finanziarie molto concrete, i<b>l 75% dei professionisti delle vendite ha fiducia nella capacit\u00e0 della propria organizzazione di formare i responsabili commerciali<\/b> affinch\u00e9 siano in grado di gestire il nuovo panorama di vendita. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-highlight-sulle-vendite-per-promuovere-il-successo-in-una-nuova-era-di-efficienza\"><b>Highlight sulle vendite per promuovere il successo in una nuova era di efficienza <\/b><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">I leader di vendita di successo sanno che per eccellere in periodi di difficolt\u00e0 \u00e8 necessario puntare sull&#8217;efficienza e sulla produttivit\u00e0. Il <a href=\"https:\/\/www.salesforce.com\/it\/resources\/research-reports\/state-of-sales\/\" target=\"_blank\" rel=\"noopener\">nostro report <i>&#8220;State of Sales&#8221;<\/i><\/a> sottolinea questo aspetto: <b>nei prossimi 12 mesi, i leader di vendita intendono adottare modalit\u00e0 di vendita ibride e virtuali <\/b>che assicurano una maggiore flessibilit\u00e0, migliorare l&#8217;allineamento interfunzionale e massimizzare l&#8217;uso di strumenti e tecnologie. Queste iniziative saranno essenziali per promuovere il successo nel 2023 e sono altrettanto fondamentali per garantire risultati positivi nell&#8217;immediato.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><i>Scopri i dati e le analisi pi\u00f9 recenti alla base della produttivit\u00e0 e dell&#8217;efficienza di oltre 7.700 professionisti delle vendite. <a href=\"https:\/\/www.salesforce.com\/it\/resources\/research-reports\/state-of-sales\/\" target=\"_blank\" rel=\"noopener\">Scarica l&#8217;ultima edizione del report &#8220;State of Sales&#8221;!<\/a><\/i><\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.salesforce.com\/it\/resources\/research-reports\/state-of-sales\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2023\/07\/State20of20Sale-A20Version-Italian-Banner-970x250px.png?strip=all&#038;quality=95\" alt=\"\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"> <span id=\"authorRoot\" path=\"\/content\/blogs\/it\/it\/authors\/\"><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;ultima edizione del nostro report &#8220;State of Sales&#8221;, che raccoglie le opinioni di oltre 7.700 professionisti del settore, mostra come i team stiano massimizzando il valore in un contesto economico difficile.<\/p>\n","protected":false},"author":1,"featured_media":772,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sf_justforyou_enable_alt":true,"optimizely_content_id":"","post_meta_title":"","ai_synopsis":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"sf_topic":[11],"sf_content_type":[],"blog":[1114],"coauthors":[2],"class_list":["post-770","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","sf_topic-sales","blog-sales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>I risultati della quinta edizione del report &quot;State of Sales&quot; - Salesforce<\/title>\n<meta name=\"description\" content=\"L&#039;ultima edizione del nostro report &quot;State of Sales&quot;, che raccoglie le opinioni di oltre 7.700 professionisti del settore, mostra come i team stiano massimizzando il valore in un contesto economico difficile.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salesforce.com\/it\/blog\/risultati-state-of-sales-quinta-edizione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 highlight rivelano in che modo i team di vendita stanno raggiungendo il successo\" \/>\n<meta property=\"og:description\" content=\"L&#039;ultima edizione del nostro report &quot;State of Sales&quot;, che raccoglie le opinioni di oltre 7.700 professionisti del settore, mostra come i team stiano massimizzando il valore in un contesto economico difficile.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salesforce.com\/it\/blog\/risultati-state-of-sales-quinta-edizione\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-20T21:02:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-08T10:31:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2023\/07\/26-stats-prove-sales-changing-blog-img-12-2022.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Salesforce Italia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Salesforce Italia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Salesforce Italia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/risultati-state-of-sales-quinta-edizione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/risultati-state-of-sales-quinta-edizione\\\/\"},\"author\":[{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/#\\\/schema\\\/person\\\/image\\\/d74bba174b633a02c1daa27bf350774f\"}],\"headline\":\"10 highlight rivelano in che modo i team di vendita stanno raggiungendo il successo\",\"datePublished\":\"2023-07-20T21:02:55+00:00\",\"dateModified\":\"2023-09-08T10:31:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/risultati-state-of-sales-quinta-edizione\\\/\"},\"wordCount\":1450,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/risultati-state-of-sales-quinta-edizione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2023\\\/07\\\/26-stats-prove-sales-changing-blog-img-12-2022.webp\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/risultati-state-of-sales-quinta-edizione\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/risultati-state-of-sales-quinta-edizione\\\/\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/risultati-state-of-sales-quinta-edizione\\\/\",\"name\":\"I risultati della quinta edizione del report \\\"State of Sales\\\" - Salesforce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/risultati-state-of-sales-quinta-edizione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/risultati-state-of-sales-quinta-edizione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2023\\\/07\\\/26-stats-prove-sales-changing-blog-img-12-2022.webp\",\"datePublished\":\"2023-07-20T21:02:55+00:00\",\"dateModified\":\"2023-09-08T10:31:45+00:00\",\"description\":\"L'ultima edizione del nostro report \\\"State of Sales\\\", che raccoglie le opinioni di oltre 7.700 professionisti del settore, mostra come i team stiano massimizzando il valore in un contesto economico difficile.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/risultati-state-of-sales-quinta-edizione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/risultati-state-of-sales-quinta-edizione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/risultati-state-of-sales-quinta-edizione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2023\\\/07\\\/26-stats-prove-sales-changing-blog-img-12-2022.webp\",\"contentUrl\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2023\\\/07\\\/26-stats-prove-sales-changing-blog-img-12-2022.webp\",\"width\":768,\"height\":432,\"caption\":\"10 nuovi risultati rivelano in che modo i team di vendita stanno ora raggiungendo il successo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/risultati-state-of-sales-quinta-edizione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"10 highlight rivelano in che modo i team di vendita stanno raggiungendo il successo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/\",\"name\":\"Salesforce\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/#organization\",\"name\":\"Salesforce\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2023\\\/09\\\/Salesforce.webp\",\"contentUrl\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2023\\\/09\\\/Salesforce.webp\",\"width\":1200,\"height\":630,\"caption\":\"Salesforce\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/#\\\/schema\\\/person\\\/image\\\/d74bba174b633a02c1daa27bf350774f\",\"name\":\"Salesforce Italia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g23494c9101089ad44ae88ce9d2f56aac\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"Salesforce Italia\"},\"url\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/blog\\\/author\\\/salesforceitalia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"I risultati della quinta edizione del report \"State of Sales\" - Salesforce","description":"L'ultima edizione del nostro report \"State of Sales\", che raccoglie le opinioni di oltre 7.700 professionisti del settore, mostra come i team stiano massimizzando il valore in un contesto economico difficile.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salesforce.com\/it\/blog\/risultati-state-of-sales-quinta-edizione\/","og_locale":"it_IT","og_type":"article","og_title":"10 highlight rivelano in che modo i team di vendita stanno raggiungendo il successo","og_description":"L'ultima edizione del nostro report \"State of Sales\", che raccoglie le opinioni di oltre 7.700 professionisti del settore, mostra come i team stiano massimizzando il valore in un contesto economico difficile.","og_url":"https:\/\/www.salesforce.com\/it\/blog\/risultati-state-of-sales-quinta-edizione\/","og_site_name":"Salesforce","article_published_time":"2023-07-20T21:02:55+00:00","article_modified_time":"2023-09-08T10:31:45+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2023\/07\/26-stats-prove-sales-changing-blog-img-12-2022.webp","type":"image\/webp"}],"author":"Salesforce Italia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Salesforce Italia","Tempo di lettura stimato":"8 minuti","Written by":"Salesforce Italia"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salesforce.com\/it\/blog\/risultati-state-of-sales-quinta-edizione\/#article","isPartOf":{"@id":"https:\/\/www.salesforce.com\/it\/blog\/risultati-state-of-sales-quinta-edizione\/"},"author":[{"@id":"https:\/\/www.salesforce.com\/it\/blog\/#\/schema\/person\/image\/d74bba174b633a02c1daa27bf350774f"}],"headline":"10 highlight rivelano in che modo i team di vendita stanno raggiungendo il successo","datePublished":"2023-07-20T21:02:55+00:00","dateModified":"2023-09-08T10:31:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salesforce.com\/it\/blog\/risultati-state-of-sales-quinta-edizione\/"},"wordCount":1450,"commentCount":0,"publisher":{"@id":"https:\/\/www.salesforce.com\/it\/blog\/#organization"},"image":{"@id":"https:\/\/www.salesforce.com\/it\/blog\/risultati-state-of-sales-quinta-edizione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2023\/07\/26-stats-prove-sales-changing-blog-img-12-2022.webp","inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.salesforce.com\/it\/blog\/risultati-state-of-sales-quinta-edizione\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.salesforce.com\/it\/blog\/risultati-state-of-sales-quinta-edizione\/","url":"https:\/\/www.salesforce.com\/it\/blog\/risultati-state-of-sales-quinta-edizione\/","name":"I risultati della quinta edizione del report \"State of Sales\" - Salesforce","isPartOf":{"@id":"https:\/\/www.salesforce.com\/it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salesforce.com\/it\/blog\/risultati-state-of-sales-quinta-edizione\/#primaryimage"},"image":{"@id":"https:\/\/www.salesforce.com\/it\/blog\/risultati-state-of-sales-quinta-edizione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2023\/07\/26-stats-prove-sales-changing-blog-img-12-2022.webp","datePublished":"2023-07-20T21:02:55+00:00","dateModified":"2023-09-08T10:31:45+00:00","description":"L'ultima edizione del nostro report \"State of Sales\", che raccoglie le opinioni di oltre 7.700 professionisti del settore, mostra come i team stiano massimizzando il valore in un contesto economico difficile.","breadcrumb":{"@id":"https:\/\/www.salesforce.com\/it\/blog\/risultati-state-of-sales-quinta-edizione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salesforce.com\/it\/blog\/risultati-state-of-sales-quinta-edizione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.salesforce.com\/it\/blog\/risultati-state-of-sales-quinta-edizione\/#primaryimage","url":"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2023\/07\/26-stats-prove-sales-changing-blog-img-12-2022.webp","contentUrl":"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2023\/07\/26-stats-prove-sales-changing-blog-img-12-2022.webp","width":768,"height":432,"caption":"10 nuovi risultati rivelano in che modo i team di vendita stanno ora raggiungendo il successo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salesforce.com\/it\/blog\/risultati-state-of-sales-quinta-edizione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salesforce.com\/it\/blog\/"},{"@type":"ListItem","position":2,"name":"10 highlight rivelano in che modo i team di vendita stanno raggiungendo il successo"}]},{"@type":"WebSite","@id":"https:\/\/www.salesforce.com\/it\/blog\/#website","url":"https:\/\/www.salesforce.com\/it\/blog\/","name":"Salesforce","description":"","publisher":{"@id":"https:\/\/www.salesforce.com\/it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salesforce.com\/it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.salesforce.com\/it\/blog\/#organization","name":"Salesforce","url":"https:\/\/www.salesforce.com\/it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.salesforce.com\/it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2023\/09\/Salesforce.webp","contentUrl":"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2023\/09\/Salesforce.webp","width":1200,"height":630,"caption":"Salesforce"},"image":{"@id":"https:\/\/www.salesforce.com\/it\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.salesforce.com\/it\/blog\/#\/schema\/person\/image\/d74bba174b633a02c1daa27bf350774f","name":"Salesforce Italia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g23494c9101089ad44ae88ce9d2f56aac","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"Salesforce Italia"},"url":"https:\/\/www.salesforce.com\/it\/blog\/author\/salesforceitalia\/"}]}},"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Salesforce","distributor_original_site_url":"https:\/\/www.salesforce.com\/it\/blog","push-errors":false,"jetpack_featured_media_url":"https:\/\/www.salesforce.com\/it\/blog\/wp-content\/uploads\/sites\/17\/2023\/07\/26-stats-prove-sales-changing-blog-img-12-2022.webp","_links":{"self":[{"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/posts\/770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/comments?post=770"}],"version-history":[{"count":3,"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/posts\/770\/revisions"}],"predecessor-version":[{"id":1747,"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/posts\/770\/revisions\/1747"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/media\/772"}],"wp:attachment":[{"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/media?parent=770"}],"wp:term":[{"taxonomy":"sf_topic","embeddable":true,"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/sf_topic?post=770"},{"taxonomy":"sf_content_type","embeddable":true,"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/sf_content_type?post=770"},{"taxonomy":"blog","embeddable":true,"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/blog?post=770"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.salesforce.com\/it\/blog\/wp-json\/wp\/v2\/coauthors?post=770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}