{"id":1001,"date":"2025-10-14T15:48:02","date_gmt":"2025-10-14T13:48:02","guid":{"rendered":"https:\/\/www.salesforce.com\/?post_type=sf_press_release&#038;p=1001"},"modified":"2025-10-14T15:48:03","modified_gmt":"2025-10-14T13:48:03","slug":"anthropic-e-salesforce-rafforzano-la-loro-collaborazione-per-offrire-soluzioni-di-intelligenza-artificiale-pensate-per-le-esigenze-dei-settori-regolamentati","status":"publish","type":"sf_press_release","link":"https:\/\/www.salesforce.com\/it\/news\/press-releases\/2025\/10\/14\/anthropic-e-salesforce-rafforzano-la-loro-collaborazione-per-offrire-soluzioni-di-intelligenza-artificiale-pensate-per-le-esigenze-dei-settori-regolamentati\/","title":{"rendered":"Anthropic e Salesforce rafforzano la loro collaborazione per offrire soluzioni di intelligenza artificiale pensate per le esigenze dei settori regolamentati"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>Ora anche i settori regolamentati e a elevata sensibilit\u00e0 dei dati possono utilizzare i modelli Claude di Anthropic all\u2019interno di Agentforce<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>L\u2019integrazione tra Claude e Slack porta l\u2019intelligenza artificiale conversazionale nei flussi di lavoro aziendali, consentendo ai dipendenti di analizzare documenti, accedere alla conoscenza organizzativa e prendere decisioni pi\u00f9 rapidamente, senza cambiare applicazione<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>SAN FRANCISCO, 14 ottobre 2025 <\/em>\u2014<strong> Salesforce <\/strong>(NYSE: CRM) e <strong>Anthropic<\/strong> annunciano un importante ampliamento della loro partnership strategica volta a fornire un&#8217;intelligenza artificiale sicura e di livello aziendale per i settori regolamentati e ad alta sensibilit\u00e0 dei dati.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;ampliamento della partnership prevede tre nuove importanti soluzioni:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Claude di Anthropic, uno dei modelli di intelligenza artificiale pi\u00f9 potenti al mondo, \u00e8 un elemento fondamentale per la piattaforma Agentforce 360 di Salesforce. Partendo da questa base, Claude pu\u00f2 ora essere utilizzato come modello di intelligenza artificiale preferito per i settori regolamentati, tra cui servizi finanziari, sanit\u00e0, sicurezza informatica e life science, garantendo al contempo la sicurezza dei dati sensibili e dei carichi di lavoro all&#8217;interno dell&#8217; infrastruttura di Salesforce.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Anthropic e Salesforce collaboreranno alla realizzazione di soluzioni di intelligenza artificiale specifiche per i settori regolamentati tramite la piattaforma Agentforce 360, a cominciare dai servizi finanziari.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Salesforce e Anthropic stanno procedendo a una profonda integrazione tra Claude e Slack per offrire agli utenti il vantaggio di esperienze AI all&#8217;avanguardia all&#8217;interno delle loro app di lavoro preferite, con il progetto di integrare Agentforce 360 in Claude.<\/li>\n<\/ul>\n\n\n<?xml version=\"1.0\" standalone=\"yes\"?>\n<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><figure class=\"wp-block-gallery has-nested-images columns-default is-cropped is-style-rectangular wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><div class=\"wp-block-image__wrapper\">\n<figure class=\"wp-block-image size-large prevent-download\"><a href=\"#\" class=\"prevent-download\" aria-expanded=\"false\" data-modal-id=\"1003-modal\"><span class=\"screen-reader-text\">Open Image Modal<\/span><img loading=\"lazy\" decoding=\"async\" height=\"1024\" width=\"1024\" data-id=\"1003\" src=\"https:\/\/www.salesforce.com\/it\/news\/wp-content\/uploads\/sites\/24\/2025\/10\/video-platform01-1x1-5_0a0283.gif?w=1024\" alt=\"Claude\/Slack\" class=\"wp-image-1003\"\/><\/a><\/figure>\n<div id=\"1003-modal\" class=\"image-modal\" aria-hidden=\"true\" aria-labelledby=\"image-dialog-title\"><div class=\"image-modal__overlay\" tabindex=\"-1\" data-a11y-dialog-hide=\"\"\/><div class=\"image-modal__content\" role=\"dialog\"><button class=\"image-modal__close-button\" type=\"button\" data-a11y-dialog-hide=\"\" aria-label=\"Close this image dialog window\"><svg viewbox=\"0 0 26 25\" height=\"16\" width=\"16\" fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><rect x=\".626\" y=\"22.753\" width=\"32\" height=\"3\" rx=\"1.5\" transform=\"rotate(-45 .626 22.753)\"\/><rect x=\"2.747\" y=\".125\" width=\"32\" height=\"3\" rx=\"1.5\" transform=\"rotate(45 2.747 .125)\"\/><\/svg><\/button><h1 id=\"image-dialog-title\" class=\"screen-reader-text\">Image Modal<\/h1>\n<figure class=\"wp-block-image size-large prevent-download\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.salesforce.com\/it\/news\/wp-content\/uploads\/sites\/24\/2025\/10\/video-platform01-1x1-5_0a0283.gif?w=1024\" alt=\"Claude\/Slack\" class=\"wp-image-1003\"\/><\/figure>\n<\/div><\/div><\/div><\/figure>\n<\/body><\/html>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<em>Salesforce e Anthropic condividono la visione di un ecosistema AI affidabile che pone i clienti al centro<\/em>\u201d, ha dichiarato <strong>Marc Benioff, Presidente e CEO di Salesforce<\/strong>. \u201c <em>Con l\u2019integrazione diretta di Salesforce in Claude e dell\u2019intelligenza di Claude in Salesforce e Slack, offriamo a ogni azienda la possibilit\u00e0 di lavorare in modi del tutto nuovi. Insieme, stiamo rendendo l\u2019intelligenza artificiale basata su agenti affidabile e reale per ogni settore, combinando i modelli di Anthropic all&#8217;avanguardia con la fiducia, l&#8217;affidabilit\u00e0, l&#8217;accuratezza e la scalabilit\u00e0 di Agentforce 360, consentendo ai clienti di raggiungere nuovi livelli di produttivit\u00e0, innovazione e crescita<\/em>\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<em>I settori regolamentati hanno bisogno di funzionalit\u00e0 di AI all&#8217;avanguardia, ma necessitano anche di adeguate misure di sicurezza prima di poterle implementare all&#8217;interno di sistemi sensibili. Abbiamo creato Claude per offrire entrambe le cose: performance e misure di sicurezza\u201d<\/em>, ha affermato <strong>Dario Amodei, CEO e co-founder di Anthropic<\/strong>.<em> \u201c Con questa partnership, Claude sar\u00e0 disponibile per un numero maggiore di clienti Salesforce tramite Agentforce, raggiungendo aziende di settori quali sanit\u00e0, servizi finanziari, sicurezza informatica e altri<\/em>\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per la versione integrale del comunicato stampa in lingua inglese si rimanda alla <a href=\"https:\/\/www.salesforce.com\/news\/press-releases\/2025\/10\/14\/anthropic-regulated-industries-partnership-expansion-announcement\/\" target=\"_blank\" rel=\"noreferrer noopener\">newsroom globale di Salesforce<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>I nuovi servizi o le nuove funzionalit\u00e0 citati nel presente documento non sono attualmente disponibili e potrebbero non essere forniti nei tempi previsti o del tutto. Si consiglia ai clienti di basare le proprie decisioni di acquisto sulle funzionalit\u00e0 attualmente disponibili.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ora anche i settori regolamentati e a elevata sensibilit\u00e0 dei dati possono utilizzare i modelli Claude di Anthropic all\u2019interno di Agentforce L\u2019integrazione tra Claude e Slack porta l\u2019intelligenza artificiale conversazionale nei flussi di lavoro aziendali, consentendo ai dipendenti di analizzare documenti, accedere alla conoscenza organizzativa e prendere decisioni pi\u00f9 rapidamente, senza cambiare applicazione SAN FRANCISCO, [&hellip;]<\/p>\n","protected":false},"author":649,"featured_media":980,"template":"","meta":{"sf_subhead":"","sf_i18n_disclaimer":false,"alternateThumbnailId":0,"sf_product_cta_id":0,"footnotes":""},"sf_content_type":[],"sf_theme":[],"sf_topic":[30],"sf_product":[],"sf_industry":[],"sf_role":[],"sf_multimedia_asset":[],"sf_location":[],"sf_collection":[],"sf_visibility":[],"coauthors":[292],"class_list":["post-1001","sf_press_release","type-sf_press_release","status-publish","has-post-thumbnail","hentry","sf_topic-salesforce-partners"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Anthropic e Salesforce rafforzano la loro collaborazione per offrire soluzioni di intelligenza artificiale pensate per le esigenze dei settori regolamentati - Salesforce<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anthropic e Salesforce rafforzano la loro collaborazione per offrire soluzioni di intelligenza artificiale pensate per le esigenze dei settori regolamentati\" \/>\n<meta property=\"og:description\" content=\"Ora anche i settori regolamentati e a elevata sensibilit\u00e0 dei dati possono utilizzare i modelli Claude di Anthropic all\u2019interno di Agentforce L\u2019integrazione tra Claude e Slack porta l\u2019intelligenza artificiale conversazionale nei flussi di lavoro aziendali, consentendo ai dipendenti di analizzare documenti, accedere alla conoscenza organizzativa e prendere decisioni pi\u00f9 rapidamente, senza cambiare applicazione SAN FRANCISCO, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salesforce.com\/it\/news\/press-releases\/2025\/10\/14\/anthropic-e-salesforce-rafforzano-la-loro-collaborazione-per-offrire-soluzioni-di-intelligenza-artificiale-pensate-per-le-esigenze-dei-settori-regolamentati\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-14T13:48:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salesforce.com\/it\/news\/wp-content\/uploads\/sites\/24\/2025\/10\/Anthropic-Brings-Full-Salesforce-Apps-Into-Claude-and-Drives-Trusted-Industry-Tailored-AI-Agents-Experiences-in-Agentforce.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data2\" content=\"Simona Paperini\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Simona Paperini\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/news\\\/press-releases\\\/2025\\\/10\\\/14\\\/anthropic-e-salesforce-rafforzano-la-loro-collaborazione-per-offrire-soluzioni-di-intelligenza-artificiale-pensate-per-le-esigenze-dei-settori-regolamentati\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/news\\\/press-releases\\\/2025\\\/10\\\/14\\\/anthropic-e-salesforce-rafforzano-la-loro-collaborazione-per-offrire-soluzioni-di-intelligenza-artificiale-pensate-per-le-esigenze-dei-settori-regolamentati\\\/\"},\"author\":[{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/news\\\/#\\\/schema\\\/person\\\/5e8c79e283acb847e940d3fd5019cf13\"}],\"headline\":\"Anthropic e Salesforce rafforzano la loro collaborazione per offrire soluzioni di intelligenza artificiale pensate per le esigenze dei settori regolamentati\",\"datePublished\":\"2025-10-14T13:48:02+00:00\",\"dateModified\":\"2025-10-14T13:48:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/news\\\/press-releases\\\/2025\\\/10\\\/14\\\/anthropic-e-salesforce-rafforzano-la-loro-collaborazione-per-offrire-soluzioni-di-intelligenza-artificiale-pensate-per-le-esigenze-dei-settori-regolamentati\\\/\"},\"wordCount\":494,\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/news\\\/press-releases\\\/2025\\\/10\\\/14\\\/anthropic-e-salesforce-rafforzano-la-loro-collaborazione-per-offrire-soluzioni-di-intelligenza-artificiale-pensate-per-le-esigenze-dei-settori-regolamentati\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2025\\\/10\\\/Anthropic-Brings-Full-Salesforce-Apps-Into-Claude-and-Drives-Trusted-Industry-Tailored-AI-Agents-Experiences-in-Agentforce.png\",\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/news\\\/press-releases\\\/2025\\\/10\\\/14\\\/anthropic-e-salesforce-rafforzano-la-loro-collaborazione-per-offrire-soluzioni-di-intelligenza-artificiale-pensate-per-le-esigenze-dei-settori-regolamentati\\\/\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/news\\\/press-releases\\\/2025\\\/10\\\/14\\\/anthropic-e-salesforce-rafforzano-la-loro-collaborazione-per-offrire-soluzioni-di-intelligenza-artificiale-pensate-per-le-esigenze-dei-settori-regolamentati\\\/\",\"name\":\"Anthropic e Salesforce rafforzano la loro collaborazione per offrire soluzioni di intelligenza artificiale pensate per le esigenze dei settori regolamentati - Salesforce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/news\\\/press-releases\\\/2025\\\/10\\\/14\\\/anthropic-e-salesforce-rafforzano-la-loro-collaborazione-per-offrire-soluzioni-di-intelligenza-artificiale-pensate-per-le-esigenze-dei-settori-regolamentati\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/news\\\/press-releases\\\/2025\\\/10\\\/14\\\/anthropic-e-salesforce-rafforzano-la-loro-collaborazione-per-offrire-soluzioni-di-intelligenza-artificiale-pensate-per-le-esigenze-dei-settori-regolamentati\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2025\\\/10\\\/Anthropic-Brings-Full-Salesforce-Apps-Into-Claude-and-Drives-Trusted-Industry-Tailored-AI-Agents-Experiences-in-Agentforce.png\",\"datePublished\":\"2025-10-14T13:48:02+00:00\",\"dateModified\":\"2025-10-14T13:48:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/news\\\/press-releases\\\/2025\\\/10\\\/14\\\/anthropic-e-salesforce-rafforzano-la-loro-collaborazione-per-offrire-soluzioni-di-intelligenza-artificiale-pensate-per-le-esigenze-dei-settori-regolamentati\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salesforce.com\\\/it\\\/news\\\/press-releases\\\/2025\\\/10\\\/14\\\/anthropic-e-salesforce-rafforzano-la-loro-collaborazione-per-offrire-soluzioni-di-intelligenza-artificiale-pensate-per-le-esigenze-dei-settori-regolamentati\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/news\\\/press-releases\\\/2025\\\/10\\\/14\\\/anthropic-e-salesforce-rafforzano-la-loro-collaborazione-per-offrire-soluzioni-di-intelligenza-artificiale-pensate-per-le-esigenze-dei-settori-regolamentati\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2025\\\/10\\\/Anthropic-Brings-Full-Salesforce-Apps-Into-Claude-and-Drives-Trusted-Industry-Tailored-AI-Agents-Experiences-in-Agentforce.png\",\"contentUrl\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2025\\\/10\\\/Anthropic-Brings-Full-Salesforce-Apps-Into-Claude-and-Drives-Trusted-Industry-Tailored-AI-Agents-Experiences-in-Agentforce.png\",\"width\":1200,\"height\":675,\"caption\":\"View of user interacting with Claude in Slack\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/news\\\/press-releases\\\/2025\\\/10\\\/14\\\/anthropic-e-salesforce-rafforzano-la-loro-collaborazione-per-offrire-soluzioni-di-intelligenza-artificiale-pensate-per-le-esigenze-dei-settori-regolamentati\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Press Releases\",\"item\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/news\\\/sf_press_release\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Anthropic e Salesforce rafforzano la loro collaborazione per offrire soluzioni di intelligenza artificiale pensate per le esigenze dei settori regolamentati\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/news\\\/\",\"name\":\"Salesforce\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/news\\\/#\\\/schema\\\/person\\\/5e8c79e283acb847e940d3fd5019cf13\",\"name\":\"Simona Paperini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/741ac0a09f4813b96538a894f52df4f87701f9091417de6329cd053c9347d34a?s=96&d=mm&r=g67ac9ad6c0e501381f19ede19ba2267b\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/741ac0a09f4813b96538a894f52df4f87701f9091417de6329cd053c9347d34a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/741ac0a09f4813b96538a894f52df4f87701f9091417de6329cd053c9347d34a?s=96&d=mm&r=g\",\"caption\":\"Simona Paperini\"},\"url\":\"https:\\\/\\\/www.salesforce.com\\\/it\\\/news\\\/author\\\/spaperinisalesforce-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Anthropic e Salesforce rafforzano la loro collaborazione per offrire soluzioni di intelligenza artificiale pensate per le esigenze dei settori regolamentati - Salesforce","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Anthropic e Salesforce rafforzano la loro collaborazione per offrire soluzioni di intelligenza artificiale pensate per le esigenze dei settori regolamentati","og_description":"Ora anche i settori regolamentati e a elevata sensibilit\u00e0 dei dati possono utilizzare i modelli Claude di Anthropic all\u2019interno di Agentforce L\u2019integrazione tra Claude e Slack porta l\u2019intelligenza artificiale conversazionale nei flussi di lavoro aziendali, consentendo ai dipendenti di analizzare documenti, accedere alla conoscenza organizzativa e prendere decisioni pi\u00f9 rapidamente, senza cambiare applicazione SAN FRANCISCO, [&hellip;]","og_url":"https:\/\/www.salesforce.com\/it\/news\/press-releases\/2025\/10\/14\/anthropic-e-salesforce-rafforzano-la-loro-collaborazione-per-offrire-soluzioni-di-intelligenza-artificiale-pensate-per-le-esigenze-dei-settori-regolamentati\/","og_site_name":"Salesforce","article_modified_time":"2025-10-14T13:48:03+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.salesforce.com\/it\/news\/wp-content\/uploads\/sites\/24\/2025\/10\/Anthropic-Brings-Full-Salesforce-Apps-Into-Claude-and-Drives-Trusted-Industry-Tailored-AI-Agents-Experiences-in-Agentforce.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuti","Scritto da":"Simona Paperini","Written by":"Simona Paperini"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.salesforce.com\/it\/news\/press-releases\/2025\/10\/14\/anthropic-e-salesforce-rafforzano-la-loro-collaborazione-per-offrire-soluzioni-di-intelligenza-artificiale-pensate-per-le-esigenze-dei-settori-regolamentati\/#article","isPartOf":{"@id":"https:\/\/www.salesforce.com\/it\/news\/press-releases\/2025\/10\/14\/anthropic-e-salesforce-rafforzano-la-loro-collaborazione-per-offrire-soluzioni-di-intelligenza-artificiale-pensate-per-le-esigenze-dei-settori-regolamentati\/"},"author":[{"@id":"https:\/\/www.salesforce.com\/it\/news\/#\/schema\/person\/5e8c79e283acb847e940d3fd5019cf13"}],"headline":"Anthropic e Salesforce rafforzano la loro collaborazione per offrire soluzioni di intelligenza artificiale pensate per le esigenze dei settori regolamentati","datePublished":"2025-10-14T13:48:02+00:00","dateModified":"2025-10-14T13:48:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salesforce.com\/it\/news\/press-releases\/2025\/10\/14\/anthropic-e-salesforce-rafforzano-la-loro-collaborazione-per-offrire-soluzioni-di-intelligenza-artificiale-pensate-per-le-esigenze-dei-settori-regolamentati\/"},"wordCount":494,"image":{"@id":"https:\/\/www.salesforce.com\/it\/news\/press-releases\/2025\/10\/14\/anthropic-e-salesforce-rafforzano-la-loro-collaborazione-per-offrire-soluzioni-di-intelligenza-artificiale-pensate-per-le-esigenze-dei-settori-regolamentati\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/it\/news\/wp-content\/uploads\/sites\/24\/2025\/10\/Anthropic-Brings-Full-Salesforce-Apps-Into-Claude-and-Drives-Trusted-Industry-Tailored-AI-Agents-Experiences-in-Agentforce.png","inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.salesforce.com\/it\/news\/press-releases\/2025\/10\/14\/anthropic-e-salesforce-rafforzano-la-loro-collaborazione-per-offrire-soluzioni-di-intelligenza-artificiale-pensate-per-le-esigenze-dei-settori-regolamentati\/","url":"https:\/\/www.salesforce.com\/it\/news\/press-releases\/2025\/10\/14\/anthropic-e-salesforce-rafforzano-la-loro-collaborazione-per-offrire-soluzioni-di-intelligenza-artificiale-pensate-per-le-esigenze-dei-settori-regolamentati\/","name":"Anthropic e Salesforce rafforzano la loro collaborazione per offrire soluzioni di intelligenza artificiale pensate per le esigenze dei settori regolamentati - Salesforce","isPartOf":{"@id":"https:\/\/www.salesforce.com\/it\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salesforce.com\/it\/news\/press-releases\/2025\/10\/14\/anthropic-e-salesforce-rafforzano-la-loro-collaborazione-per-offrire-soluzioni-di-intelligenza-artificiale-pensate-per-le-esigenze-dei-settori-regolamentati\/#primaryimage"},"image":{"@id":"https:\/\/www.salesforce.com\/it\/news\/press-releases\/2025\/10\/14\/anthropic-e-salesforce-rafforzano-la-loro-collaborazione-per-offrire-soluzioni-di-intelligenza-artificiale-pensate-per-le-esigenze-dei-settori-regolamentati\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/it\/news\/wp-content\/uploads\/sites\/24\/2025\/10\/Anthropic-Brings-Full-Salesforce-Apps-Into-Claude-and-Drives-Trusted-Industry-Tailored-AI-Agents-Experiences-in-Agentforce.png","datePublished":"2025-10-14T13:48:02+00:00","dateModified":"2025-10-14T13:48:03+00:00","breadcrumb":{"@id":"https:\/\/www.salesforce.com\/it\/news\/press-releases\/2025\/10\/14\/anthropic-e-salesforce-rafforzano-la-loro-collaborazione-per-offrire-soluzioni-di-intelligenza-artificiale-pensate-per-le-esigenze-dei-settori-regolamentati\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salesforce.com\/it\/news\/press-releases\/2025\/10\/14\/anthropic-e-salesforce-rafforzano-la-loro-collaborazione-per-offrire-soluzioni-di-intelligenza-artificiale-pensate-per-le-esigenze-dei-settori-regolamentati\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.salesforce.com\/it\/news\/press-releases\/2025\/10\/14\/anthropic-e-salesforce-rafforzano-la-loro-collaborazione-per-offrire-soluzioni-di-intelligenza-artificiale-pensate-per-le-esigenze-dei-settori-regolamentati\/#primaryimage","url":"https:\/\/www.salesforce.com\/it\/news\/wp-content\/uploads\/sites\/24\/2025\/10\/Anthropic-Brings-Full-Salesforce-Apps-Into-Claude-and-Drives-Trusted-Industry-Tailored-AI-Agents-Experiences-in-Agentforce.png","contentUrl":"https:\/\/www.salesforce.com\/it\/news\/wp-content\/uploads\/sites\/24\/2025\/10\/Anthropic-Brings-Full-Salesforce-Apps-Into-Claude-and-Drives-Trusted-Industry-Tailored-AI-Agents-Experiences-in-Agentforce.png","width":1200,"height":675,"caption":"View of user interacting with Claude in Slack"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salesforce.com\/it\/news\/press-releases\/2025\/10\/14\/anthropic-e-salesforce-rafforzano-la-loro-collaborazione-per-offrire-soluzioni-di-intelligenza-artificiale-pensate-per-le-esigenze-dei-settori-regolamentati\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salesforce.com\/it\/news\/"},{"@type":"ListItem","position":2,"name":"Press Releases","item":"https:\/\/www.salesforce.com\/it\/news\/sf_press_release\/"},{"@type":"ListItem","position":3,"name":"Anthropic e Salesforce rafforzano la loro collaborazione per offrire soluzioni di intelligenza artificiale pensate per le esigenze dei settori regolamentati"}]},{"@type":"WebSite","@id":"https:\/\/www.salesforce.com\/it\/news\/#website","url":"https:\/\/www.salesforce.com\/it\/news\/","name":"Salesforce","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salesforce.com\/it\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.salesforce.com\/it\/news\/#\/schema\/person\/5e8c79e283acb847e940d3fd5019cf13","name":"Simona Paperini","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/741ac0a09f4813b96538a894f52df4f87701f9091417de6329cd053c9347d34a?s=96&d=mm&r=g67ac9ad6c0e501381f19ede19ba2267b","url":"https:\/\/secure.gravatar.com\/avatar\/741ac0a09f4813b96538a894f52df4f87701f9091417de6329cd053c9347d34a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/741ac0a09f4813b96538a894f52df4f87701f9091417de6329cd053c9347d34a?s=96&d=mm&r=g","caption":"Simona Paperini"},"url":"https:\/\/www.salesforce.com\/it\/news\/author\/spaperinisalesforce-com\/"}]}},"jetpack_sharing_enabled":true,"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Salesforce","distributor_original_site_url":"https:\/\/www.salesforce.com\/it\/news","push-errors":false,"_links":{"self":[{"href":"https:\/\/www.salesforce.com\/it\/news\/wp-json\/wp\/v2\/sf_press_release\/1001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salesforce.com\/it\/news\/wp-json\/wp\/v2\/sf_press_release"}],"about":[{"href":"https:\/\/www.salesforce.com\/it\/news\/wp-json\/wp\/v2\/types\/sf_press_release"}],"author":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/it\/news\/wp-json\/wp\/v2\/users\/649"}],"version-history":[{"count":3,"href":"https:\/\/www.salesforce.com\/it\/news\/wp-json\/wp\/v2\/sf_press_release\/1001\/revisions"}],"predecessor-version":[{"id":1006,"href":"https:\/\/www.salesforce.com\/it\/news\/wp-json\/wp\/v2\/sf_press_release\/1001\/revisions\/1006"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/it\/news\/wp-json\/wp\/v2\/media\/980"}],"wp:attachment":[{"href":"https:\/\/www.salesforce.com\/it\/news\/wp-json\/wp\/v2\/media?parent=1001"}],"wp:term":[{"taxonomy":"sf_content_type","embeddable":true,"href":"https:\/\/www.salesforce.com\/it\/news\/wp-json\/wp\/v2\/sf_content_type?post=1001"},{"taxonomy":"sf_theme","embeddable":true,"href":"https:\/\/www.salesforce.com\/it\/news\/wp-json\/wp\/v2\/sf_theme?post=1001"},{"taxonomy":"sf_topic","embeddable":true,"href":"https:\/\/www.salesforce.com\/it\/news\/wp-json\/wp\/v2\/sf_topic?post=1001"},{"taxonomy":"sf_product","embeddable":true,"href":"https:\/\/www.salesforce.com\/it\/news\/wp-json\/wp\/v2\/sf_product?post=1001"},{"taxonomy":"sf_industry","embeddable":true,"href":"https:\/\/www.salesforce.com\/it\/news\/wp-json\/wp\/v2\/sf_industry?post=1001"},{"taxonomy":"sf_role","embeddable":true,"href":"https:\/\/www.salesforce.com\/it\/news\/wp-json\/wp\/v2\/sf_role?post=1001"},{"taxonomy":"sf_multimedia_asset","embeddable":true,"href":"https:\/\/www.salesforce.com\/it\/news\/wp-json\/wp\/v2\/sf_multimedia_asset?post=1001"},{"taxonomy":"sf_location","embeddable":true,"href":"https:\/\/www.salesforce.com\/it\/news\/wp-json\/wp\/v2\/sf_location?post=1001"},{"taxonomy":"sf_collection","embeddable":true,"href":"https:\/\/www.salesforce.com\/it\/news\/wp-json\/wp\/v2\/sf_collection?post=1001"},{"taxonomy":"sf_visibility","embeddable":true,"href":"https:\/\/www.salesforce.com\/it\/news\/wp-json\/wp\/v2\/sf_visibility?post=1001"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.salesforce.com\/it\/news\/wp-json\/wp\/v2\/coauthors?post=1001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}