{"id":5068,"date":"2025-01-22T17:21:44","date_gmt":"2025-01-22T17:21:44","guid":{"rendered":"https:\/\/www.salesforce.com\/?p=5068"},"modified":"2025-04-15T14:03:44","modified_gmt":"2025-04-15T14:03:44","slug":"data-centric-ai","status":"publish","type":"post","link":"https:\/\/www.salesforce.com\/mx\/blog\/data-centric-ai\/","title":{"rendered":"El \u00e9xito de los agentes de IA depende de un solo factor\u00a0"},"content":{"rendered":"\n<p>Los agentes de IA est\u00e1n a punto de cambiarlo todo, pero los datos de mala calidad son como comida chatarra para ellos. Ali\u00e9ntalos con datos limpios, completos y conectados. Aqu\u00ed te explicamos c\u00f3mo.&nbsp;<\/p>\n\n\n\n<p>\u00bfCu\u00e1l es una de las acciones m\u00e1s importantes que puedes realizar para implementar exitosamente agentes de IA? Si respondiste &#8220;gestionar los datos&#8221;, date una palmada en la espalda.&nbsp;<\/p>\n\n\n\n<p>\u00bfNecesitas pruebas? Considera el caso de la aerol\u00ednea que <a href=\"https:\/\/www.cbsnews.com\/news\/aircanada-chatbot-discount-customer\/\" target=\"_blank\" rel=\"noreferrer noopener\">tuvo que reembolsar a un viajero<\/a> despu\u00e9s de que un bot le diera informaci\u00f3n incorrecta sobre su pol\u00edtica de duelo. O el bot que inform\u00f3 a empresarios de Nueva York que <a href=\"https:\/\/themarkup.org\/news\/2024\/03\/29\/nycs-ai-chatbot-tells-businesses-to-break-the-law\" target=\"_blank\" rel=\"noreferrer noopener\">estaba bien infringir ciertas leyes<\/a>. O <a href=\"https:\/\/www.sportingnews.com\/us\/nba\/news\/warriors-klay-thompson-brick-trend-nba-play\/5e46e0908b657516f1e90156\" target=\"_blank\" rel=\"noreferrer noopener\">la IA que insisti\u00f3<\/a> en que una estrella de la NBA vandaliz\u00f3 varias casas.&nbsp;<\/p>\n\n\n\n<p>\u00bfQu\u00e9 sali\u00f3 mal en esos ejemplos? Podr\u00eda ser supervisi\u00f3n inadecuada o falta de medidas de control apropiadas. Pero, lo m\u00e1s probable, es que algo sali\u00f3 mal con los datos. Datos err\u00f3neos o mal etiquetados, datos de fuentes desconocidas o datos atrapados o dispersos en m\u00faltiples sistemas son escenarios comunes que pueden condenar a la IA agente.&nbsp;<\/p>\n\n\n\n<p><a href=\"https:\/\/www.salesforce.com\/news\/stories\/data-for-ai\/\" target=\"_blank\" rel=\"noreferrer noopener\">Investigaciones<\/a> recientes destacan esta realidad. Casi 6 de cada 10 usuarios de IA afirman que es dif\u00edcil obtener lo que quieren de la IA en este momento, y m\u00e1s de la mitad asegura que no conf\u00eda en los datos utilizados para entrenar los sistemas de IA actuales. Esta falta de confianza en los datos podr\u00eda frenar significativamente la adopci\u00f3n de la IA y dificultar la capacidad de tu empresa para competir.&nbsp;<\/p>\n\n\n\n<p><a href=\"https:\/\/www.salesforce.com\/mx\/agentforce\/what-are-ai-agents\/\" target=\"_blank\" rel=\"noreferrer noopener\">Los agentes de IA<\/a> prometen transformar por completo c\u00f3mo se realiza el trabajo y c\u00f3mo se gestionan las relaciones con los clientes, pero requieren datos que sean precisos, actualizados, accesibles y completos. Esto se llama IA centrada en los datos y se basa en la idea de que los sistemas de IA se desarrollan \u00fanicamente con datos de calidad.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-yoast-seo-table-of-contents yoast-table-of-contents\"><h6>Lo que aprender\u00e1:<\/h6><ul><li><a href=\"#h-que-puede-hacer-tu-empresa-ahora\" data-level=\"2\">Qu\u00e9 puede hacer tu empresa ahora<\/a><\/li><li><a href=\"#h-conecta-todos-tus-datos-empresariales-nbsp-nbsp\" data-level=\"2\">Conecta todos tus datos empresariales\u00a0\u00a0<\/a><\/li><li><a href=\"#h-establece-las-bases-para-agentes-de-ia-centrados-en-datos-nbsp-nbsp\" data-level=\"2\">Establece las bases para agentes de IA centrados en datos\u00a0\u00a0<\/a><\/li><li><a href=\"#h-en-la-era-de-la-ia-los-datos-son-valiosos-nbsp\" data-level=\"2\">En la era de la IA, los datos son valiosos \u00a0<\/a><\/li><\/ul><\/div>\n\n\n\n<div class=\"layout-six wp-block-salesforce-blog-offer\">\n\t<div class=\"wp-block-offer__wrapper\">\n\n\t\t<div class=\"wp-block-offer__content\">\n\t\t\t<h2 class=\"wp-block-offer__title\">Descubre c\u00f3mo generar valor con agentes de ventas con IA<\/h2>\n\t\t\t\t\t\t\t<p class=\"wp-block-offer__description\">Activa leads, entrena representantes y genera cotizaciones al instante<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t<a class=\"wp-block-button__link\" target=\"_blank\" href=\"https:\/\/www.salesforce.com\/mx\/form\/sales\/agentforce-for-sales-demos\/\">Ver demonstraci\u00f3n<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"wp-block-offer__media\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"596\" height=\"432\" src=\"https:\/\/www.salesforce.com\/mx\/blog\/wp-content\/uploads\/sites\/11\/2025\/01\/agentforce-for-sales-form-e1744725752940.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.salesforce.com\/mx\/blog\/wp-content\/uploads\/sites\/11\/2025\/01\/agentforce-for-sales-form-e1744725752940.png 596w, https:\/\/www.salesforce.com\/mx\/blog\/wp-content\/uploads\/sites\/11\/2025\/01\/agentforce-for-sales-form-e1744725752940.png?w=300&amp;h=217 300w, https:\/\/www.salesforce.com\/mx\/blog\/wp-content\/uploads\/sites\/11\/2025\/01\/agentforce-for-sales-form-e1744725752940.png?w=150&amp;h=109 150w\" sizes=\"auto, (max-width: 596px) 100vw, 596px\" \/>\t\t<\/div>\n\t<\/div>\n\n\t\n\t<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-que-puede-hacer-tu-empresa-ahora\">Qu\u00e9 puede hacer tu empresa ahora <\/h2>\n\n\n\n<p>Aqu\u00ed tienes dos pasos clave que tu empresa puede tomar ahora mismo para poner en orden sus datos:&nbsp;<\/p>\n\n\n\n<ol start=\"1\" class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.salesforce.com\/mx\/data\/\" target=\"_blank\" rel=\"noreferrer noopener\">Conecta tus fuentes de datos<\/a> \u2014 marketing, ventas, servicio, comercio \u2014 en un \u00fanico registro, actualizado en tiempo real, para que un agente de IA pueda ejecutar tareas de manera precisa y con toda la informaci\u00f3n disponible.&nbsp;<\/li>\n<\/ol>\n\n\n\n<ol start=\"2\" class=\"wp-block-list\">\n<li>Garantiza la calidad de tus datos. Elimina duplicados, valores at\u00edpicos, errores y otros elementos que puedan afectar negativamente los resultados de la IA.&nbsp;<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-conecta-todos-tus-datos-empresariales-nbsp-nbsp\">Conecta todos tus <a href=\"https:\/\/www.salesforce.com\/mx\/data\/\" target=\"_blank\" rel=\"noreferrer noopener\">datos<\/a> empresariales&nbsp;&nbsp;<\/h2>\n\n\n\n<p>El acceso en tiempo real a datos de calidad en toda la organizaci\u00f3n es la base del \u00e9xito de la IA. Sin embargo, muchas empresas luchan con esto. Los datos est\u00e1n aislados, en diferentes formatos y repartidos por todas partes. De hecho, las empresas afirman que la falta de armonizaci\u00f3n de datos es la segunda mayor barrera para extraer valor de ellos.&nbsp;<\/p>\n\n\n\n<p>Plataformas como Salesforce Data Cloud conectan todas las fuentes de datos, tanto estructuradas como no estructuradas, independientemente del tipo de datos, en una plataforma unificada e integrada. <a href=\"https:\/\/www.salesforce.com\/news\/press-releases\/2024\/09\/17\/data-cloud-unstructured-data-announcement\/\" target=\"_blank\" rel=\"noreferrer noopener\">Las incorporaciones recientes<\/a> a la plataforma incluyen soporte para el procesamiento nativo de audio y video, como seminarios web y llamadas, y un modelo sem\u00e1ntico de datos que ayuda a los agentes de IA y a los humanos a interpretar y utilizar los datos de manera coherente.&nbsp;<\/p>\n\n\n\n<p>Todos estos datos respaldan <a href=\"https:\/\/www.salesforce.com\/mx\/agentforce\/\" target=\"_blank\" rel=\"noreferrer noopener\">Agentforce<\/a>, el conjunto de herramientas de agentes de IA de Salesforce, y hacen que los agentes sean contextualmente conscientes y conocedores. Por ejemplo, un Agente de Servicio de Agentforce tiene acceso a correos electr\u00f3nicos previos, tickets de soporte, mensajes de voz y cualquier otra fuente definida por la organizaci\u00f3n, para comprender mejor las necesidades del cliente. Estos datos gu\u00edan al agente de IA con los pr\u00f3ximos pasos \u00f3ptimos, como automatizar un correo de seguimiento o compartir un resumen de chat con un representante humano.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-establece-las-bases-para-agentes-de-ia-centrados-en-datos-nbsp-nbsp\">Establece las bases para agentes de IA centrados en datos&nbsp;&nbsp;<\/h2>\n\n\n\n<p>Tus datos no necesitan ser perfectos para construir un programa efectivo de agentes de IA, pero s\u00ed deben estar limpios. Esto significa libres de errores, formatos incorrectos, duplicados o etiquetas err\u00f3neas.&nbsp;<\/p>\n\n\n\n<p>Los expertos en datos de Tableau <a href=\"https:\/\/www.tableau.com\/learn\/articles\/what-is-data-cleaning?_gl=1*udqq56*_gcl_au*MTc0NTM2NTkzNi4xNzMwOTk4NzE3*_ga*NjYxMjMyNzY4LjE3MzA5OTg3MTg.*_ga_3VHBZ2DJWP*MTczNDE4MjY0Ni4yMi4xLjE3MzQxODU5MjIuMTguMC4w&amp;_ga=2.149871222.1136795245.1734182647-661232768.1730998718\" target=\"_blank\" rel=\"noreferrer noopener\">ofrecen una plantilla completa<\/a> para limpiar sistem\u00e1ticamente tus datos, un primer paso crucial para unificar conjuntos de datos en proyectos de IA.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-elimina-observaciones-duplicadas-o-irrelevantes-nbsp\"><strong>Elimina observaciones duplicadas o irrelevantes<\/strong>&nbsp;<\/h3>\n\n\n\n<p>La duplicaci\u00f3n ocurre cuando combinas conjuntos de datos de m\u00faltiples fuentes y se crean copias. Las observaciones irrelevantes aparecen cuando datos (por ejemplo, sobre consumidores mayores) no encajan en el problema que intentas analizar (como los h\u00e1bitos de compra de los millennials). Eliminar estas observaciones hace que el an\u00e1lisis sea m\u00e1s eficiente, \u00fatil y preciso para un sistema de IA.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-corrige-errores-estructurales-nbsp\"><strong>Corrige errores estructurales<\/strong>&nbsp;<\/h3>\n\n\n\n<p>Los errores estructurales ocurren cuando los datos incluyen errores tipogr\u00e1ficos, capitalizaci\u00f3n incorrecta o etiquetas err\u00f3neas. Por ejemplo, \u201cN\/A\u201d y \u201cno aplicable\u201d significan lo mismo, pero no se analizan de la misma forma debido a sus diferencias de formato. Las entradas deben ser consistentes para garantizar un an\u00e1lisis preciso y completo por parte del sistema de IA.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-filtra-valores-atipicos-no-deseados-nbsp\"><strong>Filtra valores at\u00edpicos no deseados<\/strong>&nbsp;<\/h3>\n\n\n\n<p>A menudo hay observaciones \u00fanicas que no se alinean con los datos que est\u00e1s analizando. Esto podr\u00eda deberse a errores en la entrada de datos (y deber\u00edan eliminarse), pero a veces un valor at\u00edpico ayuda a probar una teor\u00eda. En cualquier caso, es necesario un an\u00e1lisis para determinar su validez.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-maneja-los-datos-faltantes-nbsp\"><strong>Maneja los datos faltantes<\/strong>&nbsp;<\/h3>\n\n\n\n<p>Los datos incompletos son un problema muy com\u00fan en los conjuntos de datos y pueden reducir la precisi\u00f3n de los modelos de IA. Existen varias formas de abordar esto:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Eliminar observaciones con valores faltantes<\/strong>, aunque esto puede llevar a la p\u00e9rdida de informaci\u00f3n.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Imputar valores faltantes bas\u00e1ndote en otras observaciones<\/strong>, aunque esto puede comprometer la integridad de los datos, ya que se basa en suposiciones y no en observaciones reales.&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Modificar la forma en que se usan los datos<\/strong> para navegar efectivamente los valores faltantes.&nbsp;<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-valida-nbsp\"><strong>Valida<\/strong>&nbsp;<\/h3>\n\n\n\n<p>Despu\u00e9s de limpiar los datos, deber\u00edas poder responder a estas preguntas:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00bfLos datos tienen sentido?&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00bfLos datos siguen las reglas apropiadas para su campo?&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00bfConfirman o refutan tu teor\u00eda, o revelan alg\u00fan insight?&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00bfPuedes identificar tendencias que ayuden a informar la pr\u00f3xima teor\u00eda? Si no, \u00bfes debido a problemas continuos de calidad de datos?&nbsp;<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-en-la-era-de-la-ia-los-datos-son-valiosos-nbsp\"><strong>En la era de la IA, los datos son valiosos<\/strong>&nbsp;<\/h2>\n\n\n\n<p>Pronto, los datos no solo respaldar\u00e1n las operaciones, sino que ser\u00e1n la columna vertebral de los sistemas, flujos de trabajo, interacciones con clientes y procesos automatizados. Estar\u00e1n entretejidos en todo, impulsando decisiones y desencadenando acciones en tiempo real, con supervisi\u00f3n humana que garantice la responsabilidad. Las empresas que prosperen no solo recopilar\u00e1n datos, sino que los integrar\u00e1n con tecnolog\u00edas para aprovechar nuevas capacidades y oportunidades.&nbsp;<\/p>\n\n\n\n<p>Esto representa una diferenciaci\u00f3n a gran escala.&nbsp;<\/p>\n\n\n\n<p>Como dijo recientemente Rahul Auradkar, vicepresidente ejecutivo y gerente general de Data Cloud en Salesforce: \u201cEn esta nueva era de IA y agentes, los datos de clientes y metadatos son el nuevo oro para las empresas\u201d.&nbsp;<\/p>\n\n\n\n<p>Los datos son tan cruciales para el \u00e9xito de la IA y los agentes de IA que pueden ser incluso m\u00e1s valiosos que el oro.&nbsp;<\/p>\n\n\n\n<div class=\"layout-three wp-block-salesforce-blog-offer\">\n\t<div class=\"wp-block-offer__wrapper\">\n\n\t\t<div class=\"wp-block-offer__content\">\n\t\t\t<h2 class=\"wp-block-offer__title\">Conoce el Agentforce<\/h2>\n\t\t\t\t\t\t\t<p class=\"wp-block-offer__description\">Humanos y Agentes se unen por el \u00e9xito del cliente. Cree y personalice agentes de IA aut\u00f3nomos para ayudar continuamente a sus colaboradores y clientes.<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"wp-block-button\">\n\t\t\t\t\t<a class=\"wp-block-button__link\" target=\"_self\" href=\"https:\/\/www.salesforce.com\/mx\/form\/agentforce\/demo\/\">Ver demo<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"wp-block-offer__media\">\n\t\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t\t<div class=\"wp-block-offer__graphics wp-block-offer__contour\"><\/div>\n\t\n\t\t\t<!-- Standard Illustration -->\n\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__illustration\" src=\"https:\/\/www.salesforce.com\/mx\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-illustration-layout-three.png\" alt=\"\">\n\n\t\t<!-- Small Accent Illustration -->\n\t\t\t\t\t<img decoding=\"async\" class=\"wp-block-offer__graphics wp-block-offer__accent\" src=\"https:\/\/www.salesforce.com\/mx\/blog\/wp-content\/themes\/salesforce-blog\/dist\/images\/offer-block\/offer-accent-layout-three.png\" alt=\"\">\n\t\t\n\t\t<!-- Left Side Illustration -->\n\t\t\n\t\t<!-- Cloud Illustration -->\n\t\t\n\t<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Descubre c\u00f3mo plataformas como Salesforce Data Cloud transforman la gesti\u00f3n de datos para agentes de IA, conectando fuentes estructuradas y no estructuradas, optimizando la calidad de los datos y potenciando decisiones en tiempo real para un \u00e9xito empresarial sin precedentes. <\/p>\n","protected":false},"author":522,"featured_media":5070,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sf_justforyou_enable_alt":true,"optimizely_content_id":"b8de66d7997247278211fc464de31e8b","post_meta_title":"","ai_synopsis":"","footnotes":""},"sf_topic":[446],"sf_content_type":[],"blog":[],"coauthors":[4],"class_list":["post-5068","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","sf_topic-ai"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El \u00e9xito de los agentes de IA depende de un solo factor\u00a0 | Salesforce<\/title>\n<meta name=\"description\" content=\"Descubre c\u00f3mo plataformas como Salesforce Data Cloud transforman la gesti\u00f3n de datos para agentes de IA, conectando fuentes estructuradas y no estructuradas, optimizando la calidad de los datos y potenciando decisiones en tiempo real para un \u00e9xito empresarial sin precedentes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salesforce.com\/mx\/blog\/data-centric-ai\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El \u00e9xito de los agentes de IA depende de un solo factor\u00a0 | Salesforce\" \/>\n<meta property=\"og:description\" content=\"Descubre c\u00f3mo plataformas como Salesforce Data Cloud transforman la gesti\u00f3n de datos para agentes de IA, conectando fuentes estructuradas y no estructuradas, optimizando la calidad de los datos y potenciando decisiones en tiempo real para un \u00e9xito empresarial sin precedentes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salesforce.com\/mx\/blog\/data-centric-ai\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-22T17:21:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-15T14:03:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salesforce.com\/mx\/blog\/wp-content\/uploads\/sites\/11\/2025\/01\/GettyImages-1463568611.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"889\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Salesforce LATAM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Salesforce LATAM\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.salesforce.com\/mx\/blog\/data-centric-ai\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.salesforce.com\/mx\/blog\/data-centric-ai\/\"},\"author\":[{\"@id\":\"https:\/\/www.salesforce.com\/mx\/blog\/#\/schema\/person\/image\/db53ece7ac036aafdb1246e656d3421d\"}],\"headline\":\"El \u00e9xito de los agentes de IA depende de un solo factor\u00a0\",\"datePublished\":\"2025-01-22T17:21:44+00:00\",\"dateModified\":\"2025-04-15T14:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.salesforce.com\/mx\/blog\/data-centric-ai\/\"},\"wordCount\":1307,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.salesforce.com\/mx\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/mx\/blog\/data-centric-ai\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.salesforce.com\/mx\/blog\/wp-content\/uploads\/sites\/11\/2025\/01\/GettyImages-1463568611.webp\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.salesforce.com\/mx\/blog\/data-centric-ai\/#respond\"]}],\"accessibilityFeature\":[\"tableOfContents\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.salesforce.com\/mx\/blog\/data-centric-ai\/\",\"url\":\"https:\/\/www.salesforce.com\/mx\/blog\/data-centric-ai\/\",\"name\":\"El \u00e9xito de los agentes de IA depende de un solo factor\u00a0 | Salesforce\",\"isPartOf\":{\"@id\":\"https:\/\/www.salesforce.com\/mx\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.salesforce.com\/mx\/blog\/data-centric-ai\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/mx\/blog\/data-centric-ai\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.salesforce.com\/mx\/blog\/wp-content\/uploads\/sites\/11\/2025\/01\/GettyImages-1463568611.webp\",\"datePublished\":\"2025-01-22T17:21:44+00:00\",\"dateModified\":\"2025-04-15T14:03:44+00:00\",\"description\":\"Descubre c\u00f3mo plataformas como Salesforce Data Cloud transforman la gesti\u00f3n de datos para agentes de IA, conectando fuentes estructuradas y no estructuradas, optimizando la calidad de los datos y potenciando decisiones en tiempo real para un \u00e9xito empresarial sin precedentes.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.salesforce.com\/mx\/blog\/data-centric-ai\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.salesforce.com\/mx\/blog\/data-centric-ai\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.salesforce.com\/mx\/blog\/data-centric-ai\/#primaryimage\",\"url\":\"https:\/\/www.salesforce.com\/mx\/blog\/wp-content\/uploads\/sites\/11\/2025\/01\/GettyImages-1463568611.webp\",\"contentUrl\":\"https:\/\/www.salesforce.com\/mx\/blog\/wp-content\/uploads\/sites\/11\/2025\/01\/GettyImages-1463568611.webp\",\"width\":889,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.salesforce.com\/mx\/blog\/data-centric-ai\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.salesforce.com\/mx\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El \u00e9xito de los agentes de IA depende de un solo factor\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.salesforce.com\/mx\/blog\/#website\",\"url\":\"https:\/\/www.salesforce.com\/mx\/blog\/\",\"name\":\"Salesforce\",\"description\":\"Novedades sobre IA ag\u00e9ntica, datos y CRM\",\"publisher\":{\"@id\":\"https:\/\/www.salesforce.com\/mx\/blog\/#organization\"},\"alternateName\":\"Salesforce LATAM Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.salesforce.com\/mx\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.salesforce.com\/mx\/blog\/#organization\",\"name\":\"Salesforce\",\"url\":\"https:\/\/www.salesforce.com\/mx\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.salesforce.com\/mx\/blog\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Salesforce\"},\"image\":{\"@id\":\"https:\/\/www.salesforce.com\/mx\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.salesforce.com\/mx\/blog\/#\/schema\/person\/image\/db53ece7ac036aafdb1246e656d3421d\",\"name\":\"Salesforce LATAM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.salesforce.com\/mx\/blog\/#\/schema\/person\/image\/6743583b146bf9f6d57d73590f53bef2\",\"url\":\"https:\/\/www.salesforce.com\/mx\/blog\/wp-content\/uploads\/sites\/11\/2023\/09\/salesforce-icon.webp?w=150&h=150&crop=1\",\"contentUrl\":\"https:\/\/www.salesforce.com\/mx\/blog\/wp-content\/uploads\/sites\/11\/2023\/09\/salesforce-icon.webp?w=150&h=150&crop=1\",\"width\":\"150\",\"height\":\"150\",\"caption\":\"Salesforce LATAM\"},\"description\":\"Somos una plataforma de gesti\u00f3n de relaciones con clientes (CRM) basada en la nube, que ayuda a las empresas a administrar sus operaciones de ventas, marketing, atenci\u00f3n al cliente y otras operaciones comerciales en un solo lugar.\",\"url\":\"https:\/\/www.salesforce.com\/mx\/blog\/author\/mexico\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El \u00e9xito de los agentes de IA depende de un solo factor\u00a0 | Salesforce","description":"Descubre c\u00f3mo plataformas como Salesforce Data Cloud transforman la gesti\u00f3n de datos para agentes de IA, conectando fuentes estructuradas y no estructuradas, optimizando la calidad de los datos y potenciando decisiones en tiempo real para un \u00e9xito empresarial sin precedentes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salesforce.com\/mx\/blog\/data-centric-ai\/","og_locale":"es_MX","og_type":"article","og_title":"El \u00e9xito de los agentes de IA depende de un solo factor\u00a0 | Salesforce","og_description":"Descubre c\u00f3mo plataformas como Salesforce Data Cloud transforman la gesti\u00f3n de datos para agentes de IA, conectando fuentes estructuradas y no estructuradas, optimizando la calidad de los datos y potenciando decisiones en tiempo real para un \u00e9xito empresarial sin precedentes.","og_url":"https:\/\/www.salesforce.com\/mx\/blog\/data-centric-ai\/","og_site_name":"Salesforce","article_published_time":"2025-01-22T17:21:44+00:00","article_modified_time":"2025-04-15T14:03:44+00:00","og_image":[{"width":889,"height":500,"url":"https:\/\/www.salesforce.com\/mx\/blog\/wp-content\/uploads\/sites\/11\/2025\/01\/GettyImages-1463568611.webp","type":"image\/webp"}],"author":"Salesforce LATAM","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"","Tiempo de lectura":"6 minutos","Written by":"Salesforce LATAM"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salesforce.com\/mx\/blog\/data-centric-ai\/#article","isPartOf":{"@id":"https:\/\/www.salesforce.com\/mx\/blog\/data-centric-ai\/"},"author":[{"@id":"https:\/\/www.salesforce.com\/mx\/blog\/#\/schema\/person\/image\/db53ece7ac036aafdb1246e656d3421d"}],"headline":"El \u00e9xito de los agentes de IA depende de un solo factor\u00a0","datePublished":"2025-01-22T17:21:44+00:00","dateModified":"2025-04-15T14:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salesforce.com\/mx\/blog\/data-centric-ai\/"},"wordCount":1307,"commentCount":0,"publisher":{"@id":"https:\/\/www.salesforce.com\/mx\/blog\/#organization"},"image":{"@id":"https:\/\/www.salesforce.com\/mx\/blog\/data-centric-ai\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/mx\/blog\/wp-content\/uploads\/sites\/11\/2025\/01\/GettyImages-1463568611.webp","inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.salesforce.com\/mx\/blog\/data-centric-ai\/#respond"]}],"accessibilityFeature":["tableOfContents"]},{"@type":"WebPage","@id":"https:\/\/www.salesforce.com\/mx\/blog\/data-centric-ai\/","url":"https:\/\/www.salesforce.com\/mx\/blog\/data-centric-ai\/","name":"El \u00e9xito de los agentes de IA depende de un solo factor\u00a0 | Salesforce","isPartOf":{"@id":"https:\/\/www.salesforce.com\/mx\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salesforce.com\/mx\/blog\/data-centric-ai\/#primaryimage"},"image":{"@id":"https:\/\/www.salesforce.com\/mx\/blog\/data-centric-ai\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salesforce.com\/mx\/blog\/wp-content\/uploads\/sites\/11\/2025\/01\/GettyImages-1463568611.webp","datePublished":"2025-01-22T17:21:44+00:00","dateModified":"2025-04-15T14:03:44+00:00","description":"Descubre c\u00f3mo plataformas como Salesforce Data Cloud transforman la gesti\u00f3n de datos para agentes de IA, conectando fuentes estructuradas y no estructuradas, optimizando la calidad de los datos y potenciando decisiones en tiempo real para un \u00e9xito empresarial sin precedentes.","breadcrumb":{"@id":"https:\/\/www.salesforce.com\/mx\/blog\/data-centric-ai\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salesforce.com\/mx\/blog\/data-centric-ai\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.salesforce.com\/mx\/blog\/data-centric-ai\/#primaryimage","url":"https:\/\/www.salesforce.com\/mx\/blog\/wp-content\/uploads\/sites\/11\/2025\/01\/GettyImages-1463568611.webp","contentUrl":"https:\/\/www.salesforce.com\/mx\/blog\/wp-content\/uploads\/sites\/11\/2025\/01\/GettyImages-1463568611.webp","width":889,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.salesforce.com\/mx\/blog\/data-centric-ai\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salesforce.com\/mx\/blog\/"},{"@type":"ListItem","position":2,"name":"El \u00e9xito de los agentes de IA depende de un solo factor\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.salesforce.com\/mx\/blog\/#website","url":"https:\/\/www.salesforce.com\/mx\/blog\/","name":"Salesforce","description":"Novedades sobre IA ag\u00e9ntica, datos y CRM","publisher":{"@id":"https:\/\/www.salesforce.com\/mx\/blog\/#organization"},"alternateName":"Salesforce LATAM Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salesforce.com\/mx\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.salesforce.com\/mx\/blog\/#organization","name":"Salesforce","url":"https:\/\/www.salesforce.com\/mx\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.salesforce.com\/mx\/blog\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Salesforce"},"image":{"@id":"https:\/\/www.salesforce.com\/mx\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.salesforce.com\/mx\/blog\/#\/schema\/person\/image\/db53ece7ac036aafdb1246e656d3421d","name":"Salesforce LATAM","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.salesforce.com\/mx\/blog\/#\/schema\/person\/image\/6743583b146bf9f6d57d73590f53bef2","url":"https:\/\/www.salesforce.com\/mx\/blog\/wp-content\/uploads\/sites\/11\/2023\/09\/salesforce-icon.webp?w=150&h=150&crop=1","contentUrl":"https:\/\/www.salesforce.com\/mx\/blog\/wp-content\/uploads\/sites\/11\/2023\/09\/salesforce-icon.webp?w=150&h=150&crop=1","width":"150","height":"150","caption":"Salesforce LATAM"},"description":"Somos una plataforma de gesti\u00f3n de relaciones con clientes (CRM) basada en la nube, que ayuda a las empresas a administrar sus operaciones de ventas, marketing, atenci\u00f3n al cliente y otras operaciones comerciales en un solo lugar.","url":"https:\/\/www.salesforce.com\/mx\/blog\/author\/mexico\/"}]}},"jetpack_featured_media_url":"https:\/\/www.salesforce.com\/mx\/blog\/wp-content\/uploads\/sites\/11\/2025\/01\/GettyImages-1463568611.webp","distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Salesforce","distributor_original_site_url":"https:\/\/www.salesforce.com\/mx\/blog","push-errors":false,"_links":{"self":[{"href":"https:\/\/www.salesforce.com\/mx\/blog\/wp-json\/wp\/v2\/posts\/5068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salesforce.com\/mx\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salesforce.com\/mx\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/mx\/blog\/wp-json\/wp\/v2\/users\/522"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/mx\/blog\/wp-json\/wp\/v2\/comments?post=5068"}],"version-history":[{"count":2,"href":"https:\/\/www.salesforce.com\/mx\/blog\/wp-json\/wp\/v2\/posts\/5068\/revisions"}],"predecessor-version":[{"id":5218,"href":"https:\/\/www.salesforce.com\/mx\/blog\/wp-json\/wp\/v2\/posts\/5068\/revisions\/5218"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salesforce.com\/mx\/blog\/wp-json\/wp\/v2\/media\/5070"}],"wp:attachment":[{"href":"https:\/\/www.salesforce.com\/mx\/blog\/wp-json\/wp\/v2\/media?parent=5068"}],"wp:term":[{"taxonomy":"sf_topic","embeddable":true,"href":"https:\/\/www.salesforce.com\/mx\/blog\/wp-json\/wp\/v2\/sf_topic?post=5068"},{"taxonomy":"sf_content_type","embeddable":true,"href":"https:\/\/www.salesforce.com\/mx\/blog\/wp-json\/wp\/v2\/sf_content_type?post=5068"},{"taxonomy":"blog","embeddable":true,"href":"https:\/\/www.salesforce.com\/mx\/blog\/wp-json\/wp\/v2\/blog?post=5068"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.salesforce.com\/mx\/blog\/wp-json\/wp\/v2\/coauthors?post=5068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}